{"id":75350,"date":"2014-06-14T06:30:17","date_gmt":"2014-06-14T06:30:17","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/06\/14\/le-desordre-des-forces-de-lordre-postmodernes\/"},"modified":"2014-06-14T06:30:17","modified_gmt":"2014-06-14T06:30:17","slug":"le-desordre-des-forces-de-lordre-postmodernes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/06\/14\/le-desordre-des-forces-de-lordre-postmodernes\/","title":{"rendered":"Le d\u00e9sordre des \u201cforces de l&rsquo;ordre\u201d postmodernes"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Le d\u00e9sordre des forces de l&rsquo;ordre postmodernes<\/h3>\n<\/p>\n<p><p>\tNous ferons un rapprochement entre deux \u00e9pisodes concernant les forces arm\u00e9es de deux pays dans cette situation postmoderne interm\u00e9diaire m\u00ealant la conqu\u00eate ou l&rsquo;influence du Syst\u00e8me venues de l&rsquo;ext\u00e9rieur et la d\u00e9structuration de tous les cadres principiels qui en d\u00e9coule, et ces forces confront\u00e9es \u00e0 des conflits de contestation de cette situation. Il n&rsquo;est pas question de juger selon les orientations id\u00e9ologiques, politiques, militaires et autres de ces pays mais bien de les rapprocher selon leur \u00e9tat de d\u00e9structuration, sinon de dissolution suivant l&rsquo;intervention du Syst\u00e8me. Les deux pays sont l&rsquo;Ukraine-Kiev \u00e0 l&rsquo;assaut des r\u00e9volt\u00e9s du Donbass d&rsquo;une part, l&rsquo;Irak confront\u00e9 \u00e0 une attaque des islamo-terroristes de l&rsquo;ISIS d&rsquo;autre part. Comme on le verra bien entendu, il s&rsquo;agit d&rsquo;\u00e9tablir une analogie de situation, concernant sp\u00e9cifiquement autant le traitement par leurs autorit\u00e9s politiques que le comportement de ces forces arm\u00e9es dans les situations conflictuelles \u00e9voqu\u00e9es, aboutissant \u00e0 leur intense fragilisation, sinon \u00e0 leur impuissance.<\/p>\n<\/p>\n<p><p>\t(Il doit \u00eatre bien entendu que nous ne traitons pas les deux \u00e9v\u00e9nements comme deux \u00e9v\u00e9nements militaires,  qu&rsquo;ils ne sont d&rsquo;ailleurs pas, \u00e0 notre sens. Par exemple, l&rsquo;effondrement, ou la dissolution de l&rsquo;arm\u00e9e irakienne ne doit pas \u00eatre appr\u00e9ci\u00e9, et ne peut l&rsquo;\u00eatre d&rsquo;ailleurs, par rapport \u00e0 un autre \u00e9v\u00e9nement de m\u00eame apparence, dans l&rsquo;histoire militaire. Si l&rsquo;on prend le cas de l&rsquo;effondrement et de la dissolution de l&rsquo;arm\u00e9e russe \u00e0 l&rsquo;\u00e9t\u00e9-automne 1917, cet \u00e9v\u00e9nement, qu&rsquo;on peut  qualifier notamment et effectivement de militaire, est <strong>la conclusion d&rsquo;une longue s\u00e9quence<\/strong> marqu\u00e9e par trois ann\u00e9es de guerre cruelle et de pertes immenses, dans un climat national extr\u00eamement pesant de dissolution. La dissolution de l&rsquo;arm\u00e9e irakienne, qui ne conclut rien et qui n&rsquo;est en rien la cons\u00e9quence d&rsquo;un conflit, est <strong>un \u00e9pisode d&rsquo;une s\u00e9quence historique bien entendu toujours en cours<\/strong>, qui concerne l&rsquo;affrontement g\u00e9n\u00e9ral g\u00e9n\u00e9r\u00e9 par les tensions issues du Syst\u00e8me et de sa crise g\u00e9n\u00e9rale.)<\/p>\n<\/p>\n<p><p>\t Du c\u00f4t\u00e9 ukrainien, il s&rsquo;agit de l&rsquo;odyss\u00e9e d&rsquo;une unit\u00e9 de la garde Nationale dans la r\u00e9gion Est, le troisi\u00e8me escadron du premier bataillon de r\u00e9serve de la Garde, contre les diverses forces anti-Kiev. Normalement, ces unit\u00e9s de la Garde Nationale, constitu\u00e9es depuis la prise du pouvoir par la nouvelle \u00e9quipe dans le but sp\u00e9cifique d&rsquo;intervenir dans l&rsquo;Est du pays, sont constitu\u00e9es pour l&rsquo;essentiel de membres du groupe <em>Pravy Sektor<\/em> (Secteur Droite), ultranationaliste et de tendance n\u00e9o-nazie. Le troisi\u00e8me escadron s&rsquo;est mutin\u00e9 \u00e0 cause des conditions o\u00f9 il \u00e9volue, sans paie, sans \u00e9quipements de subsistance, notamment pour sa nourriture et ses installations de campagne, sans soutien logistique, etc., \u00e9galement dans une situation administrative extraordinaire,  comme s&rsquo;il n&rsquo;existait pas&#8230; C&rsquo;est <em>Russia Today<\/em> du <a href=\"http:\/\/rt.com\/news\/165472-ukraine-national-guard-mutiny\/\" class=\"gen\">12 juin 2014<\/a>, qui nous rapporte l&rsquo;odyss\u00e9e du troisi\u00e8me escadron.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Now an entire unit of the National Guard has revolted and is heading back to Kiev, claiming they have been abandoned by the government and left unpaid. According to official papers, we don&rsquo;t exist! We&rsquo;re an illusion. It&rsquo;s like we haven&rsquo;t been deployed here, we haven&rsquo;t got any ammunition &#8211; nothing! claimed the commander of the Third squadron of the First reserve battalion of the National Guard, Lieutenant Taras Zherebetsky. He said that all documents of his detachment have disappeared as if they had never been created. We were sleeping on the ground, because we didn&rsquo;t even have tents! They just sent us there &#8211; and forgot about us! And while all the generals and commanders were sitting pretty in their warm tents, guarded by the newest APCs, we were sent to fight like cannon fodder, Zherebetsky said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Other members of the National Guard said that sometimes they had to buy their uniform themselves and the body armor was given by sponsors, not the government. Another peculiar detail about the unit reveled by the fighters, is that its military personnel have been attributed to other units which actually never existed. That means that technically, they actually saw action, were carrying arms and probably killed adversaries in Donetsk Region of their own accord.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But that is not the whole story either. The National Guards found out that while actually being deployed to a war zone near the city of Slavyansk for weeks, according to papers they remained in the peaceful city of Pavlograd in the neighboring Dnepropetrovsk Region, so they may forget about the combat pay they were promised. We haven&rsquo;t been paid. We got around $600 on arrival here two months ago, and that&rsquo;s it. We didn&rsquo;t have any food. Instead, they&rsquo;ve been feeding us with promises that it&rsquo;s going to happen tomorrow. But we&rsquo;re tired of waiting! said another National Guard soldier, Evgeny Ivanenko.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Several dozen unarmed members of the National Guard are now rallying in front of Ukrainian government&rsquo;s headquarters in protest, demanding to be recognized as combatants. That would give them exceptional treatment and rights to benefits such as discounts on housing services and utilities payments, and privileged healthcare.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, nous prenons ce cas particulier comme assez exemplaire de ce que doit \u00eatre l&rsquo;\u00e9tat g\u00e9n\u00e9ral des forces anti-Kiev. Il y a d\u00e9j\u00e0 eu de nombreux cas et des remous suffisamment significatifs dans les forces arm\u00e9es, avec des cas de refus de combattre, de d\u00e9sertion, etc., ainsi qu&rsquo;une attitude g\u00e9n\u00e9rale marqu\u00e9e par une r\u00e9ticence \u00e9vidente \u00e0 s&rsquo;aventurer \u00e0 d\u00e9couvert dans des phases offensives qui permettraient des gains significatifs, malgr\u00e9 une consid\u00e9rable sup\u00e9riorit\u00e9 en nombre et en armements. D&rsquo;autre part, l&rsquo;aspect composite, avec des statuts diff\u00e9rents, voire des autorit\u00e9s supr\u00eames diff\u00e9rentes, des forces engag\u00e9es, y compris avec des apports \u00e9trangers (non-ukrainiens,  comme des mercenaires US), tout cela implique un manque complet d&rsquo;unit\u00e9 et de coordination.<\/p>\n<\/p>\n<p><p>\t Le cas des forces arm\u00e9es irakiennes pourraient sembler \u00e0 premi\u00e8re vue compl\u00e8tement diff\u00e9rent, du point de vue des combats engag\u00e9s, du volume et du comportement de ces forces, etc. Des analyses ont d\u00e9j\u00e0 \u00e9t\u00e9 publi\u00e9es sur ce comportement o\u00f9 l&rsquo;on voit des cas surprenants, comme celui d&rsquo;une division de 15 000 hommes se d\u00e9bandant devant une force de 800 hommes de ISIS. Par contraste avec les forces pro-Kiev dans le cas cit\u00e9 ci-dessus, les soldats irakiens sont grassement pay\u00e9s, mieux que certaines professions lib\u00e9rales ($1 300 mensuels pour un soldat, contre $1<NB>000 pour un professeur d&rsquo;universit\u00e9). La corruption semble une sorte d&rsquo;activit\u00e9 courante, \u00e0 tous les niveaux, tandis que les motivations sont tr\u00e8s fortement marqu\u00e9es par les provenances et les loyaut\u00e9s ethniques, tribales, partisanes, religieuses, etc. Ces provenances et ces loyaut\u00e9s peuvent \u00eatre honorables en soi mais elles actent et renforcent massivement une situation de d\u00e9structuration et de dissolution lorsqu&rsquo;elles prennent la place des principes de l\u00e9gitimit\u00e9 et de souverainet\u00e9 qui n&rsquo;existent plus dans le cas qui tend \u00e0 devenir universel de ces \u00c9tats r\u00e9duits \u00e0 une existence fantomatique, souvent elle-m\u00eame partisane, d\u00e9structur\u00e9e et dissolue. Le journal en anglais <em>Al-Akhbar<\/em> donne, le <a href=\"http:\/\/english.al-akhbar.com\/node\/20164\" class=\"gen\">13 juin 2014<\/a> un rapport sur le sujet&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Military affairs expert Dr. Hisham al-Hashemi says that the Iraqi army comprises 15 divisions, each made up of 12,000 to 15,000 troops, in addition to the Air Force, the Navy, the Security Forces, Intelligence, and Military Police. The total number of troops is 600,000, which should be sufficient to thwart any plot or attack against Iraq, he says, were it not for the weak military spirit, corruption among officers, and the desertion of the officers in charge of the Ninawa Operations Command.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Explaining the causes of the security forces&rsquo; retreat, Dr. Hashemi said, The defeat is the result of military commanders relying on political parties to justify their actions and protect them, while neglecting their military responsibilities, and being preoccupied with side activities for profiteering, as well as their lack of moral integrity.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Ali al-Nour, another military affairs expert, believes that the army&rsquo;s collapse is not the result of a single mistake, but rather of the accumulation of many political and military errors, in addition to what he described as the state&rsquo;s failure to contain corruption, and provide basic security and services for the citizens. Nour told Al-Akhbar that what happened in Mosul was not just the result of corruption, but the culmination of all of the corruption Iraq has seen since 2003, pointing out that what happened was a result of the lack of proper security consultation, sectarian quotas in security posts, and the lack of seriousness among politicians when it comes to state-building after 2003.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>He added, Corruption is institutionalized in Iraq. It is therefore natural for the military to be part of the corruption, with many officials profiteering from it, without performing their duty. They sell fuel, vehicles, and weapons, smuggle prisoners, and extort people. Nour also pointed out that the army has no doctrine, save for sectarianism.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>For instance, he said, a Shia soldier might not be interested in defending a Sunni city, and vice versa, pointing out that an army&rsquo;s doctrine should be a combination of emotional and intellectual bonds that the army has failed to develop, even though soldiers are paid more than university professors. Nour said, The ordinary soldier is paid a [monthly] salary of $1,300 and above, while professors earn only $1000. In addition, officers with the rank of Major General and above are paid more than $6,000 a month, which is more than what a deputy minister earns.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Nour continued, The problem of armament and empty slogans, which led to the U.S. withdrawal without preparing an alternative, was also a big mistake. The military expert then drew attention to the growing phenomenon of ghost soldiers, or soldiers enrolled in the army without being assigned duties or even attending, for which officers are paid half of the ghost soldiers&rsquo; salaries, all with the knowledge of senior officials at the Army Command and some MPs.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In the opinion of the military expert, what happened in Iraq is a reflection of the troubling situation in the region, but also the result of the huge wealth that has been squandered by sectarian quota-based clientelism. Nour said it was unlikely that assistance from the U.S. army or any international assistance to the Iraqi army would solve the security crisis, unless all crises in the region were addressed together&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDans toutes ces consid\u00e9rations, nulle notion telles que d\u00e9fense de la patrie, h\u00e9ro\u00efsme, esprit de sacrifice, etc. Ces r\u00e9f\u00e9rences semblent aujourd&rsquo;hui des anachronismes absolument stup\u00e9fiants pour l&rsquo;esprit du temps, comme \u00e0 mille si\u00e8cles de nous et d&rsquo;une autre civilisation. Philosophe et chercheur au CNRS qui a publi\u00e9 <em>Le Soldat impossible<\/em> sur la question de l&rsquo;\u00e9volution du soldat (ou soldat selon l&rsquo;id\u00e9e d&rsquo;une seule mission sacrificielle, devenu militaire aux multiples missions possibles selon l&rsquo;\u00e9volution des murs culturels et id\u00e9ologiques dans un temps extr\u00eamement \u00e9lastique \u00e0 cet \u00e9gard), Robert Redeker observe : \u00ab<em>Un soldat se bat, c&rsquo;est-\u00e0-dire tue et meurt, pour la nation, la France par exemple, articul\u00e9 \u00e0 la profondeur du temps, la longue dur\u00e9e, tandis que le militaire contemporain, gendarme contemporain d\u00e9guis\u00e9 en soldat, est commis \u00e0 se battre pour imposer des id\u00e9es, des valeurs, dans un horizon p\u00e9dagogique (convertir, en punissant les r\u00e9calcitrants, tous les \u00c9tats aux droits de l&rsquo;homme et \u00e0 la d\u00e9mocratie).<\/em>\u00bb (Dans <em>El\u00e9ments<\/em>, avril-juin 2014.)<\/p>\n<\/p>\n<p><p>\tDans les cas qui nous occupent, les combattants pro-Kiev et l&rsquo;arm\u00e9e irakienne, il s&rsquo;agit de sous-gendarmes contemporains aux capacit\u00e9s p\u00e9dagogiques caricaturales, des suppl\u00e9tifs des gendarmes contemporains n\u00e9s des n\u00e9cessit\u00e9s des actes d\u00e9structurants du Syst\u00e8me, sur lesquels on a greff\u00e9 quelques slogans vides import\u00e9s du bloc BAO, qui r\u00e9pondent \u00e0 des consignes-Syst\u00e8me que r\u00e9percutent ceux qui les ont form\u00e9s. Ils \u00e9voluent dans des milieux interlopes de directions politiques absolument corrompues avant m\u00eame d&rsquo;exister, donc des sous-directions-Syst\u00e8me (impos\u00e9es par le Syst\u00e8me), non pas corrompues par le Syst\u00e8me, mais corrompues avant que d&rsquo;exister en tant que telles, c&rsquo;est-\u00e0-dire accouch\u00e9es du Syst\u00e8me lui-m\u00eame et ayant comme condition d&rsquo;existence la corruption d&rsquo;abord psychologique ; par cons\u00e9quent, ayant pour condition <em>sine qua non<\/em> d&rsquo;existence le rejet de tous les principes (l\u00e9gitimit\u00e9, autorit\u00e9, identit\u00e9) qui permettent d&rsquo;esp\u00e9rer fonder une force coh\u00e9rente, solidaire et disposant d&rsquo;une unit\u00e9 collective de dessein. C&rsquo;est bien le cas, aussi bien des forces pro-Kiev, d\u00e9pendant d&rsquo;un pouvoir install\u00e9 par le bloc BAO pour servir les int\u00e9r\u00eats d\u00e9structurants du bloc, que des forces irakiennes qui d\u00e9pendent d&rsquo;un gouvernement form\u00e9 selon une d\u00e9marche de sens similaire, m\u00eame si cela s&rsquo;est fait dans des conditions compl\u00e8tement diff\u00e9rentes et selon des r\u00e9f\u00e9rences correspondantes aux situations r\u00e9gionales, aux murs et aux nuances religieuses des populations et de l&rsquo;histoire. Cela signifie que, pour nous, les dynamiques postmodernes du Syst\u00e8me plaqu\u00e9es sur les situations existantes avec leurs conflits larv\u00e9s ou actifs, se servent de ces situations existantes pour nourrir leur propre production de d\u00e9sordre.<\/p>\n<\/p>\n<p><p>\tIl en r\u00e9sulte que ces soldats sont par d\u00e9finition de pi\u00e8tres combattants, simplement parce qu&rsquo;ils ne peuvent \u00eatre autre chose, parce qu&rsquo;ils sont ontologiquement impuissants \u00e0 \u00eatre autre chose en raison des conditions impos\u00e9es par le Syst\u00e8me. <em>Pravy Sektor<\/em> n&rsquo;a emprunt\u00e9 aux nazis que leurs tendances \u00e0 appliquer des comportements massacreurs sans la moindre capacit\u00e9 combattante de leurs troupes. Les soldats irakiens, d\u00e9pendant d&rsquo;un pouvoir qui s&rsquo;affiche partisan \u00e0 cause des conditions cr\u00e9\u00e9es par le Syst\u00e8me (les USA et leur invasion de 2003 suivant plus d&rsquo;une d\u00e9cennie de pressions de tous ordres) et qui corrompt tout ce qui bouge au nom de sa partisanerie, sont eux-m\u00eames partisans au niveau de leurs ethnies, de leurs tribus, de leur appartenance religieuse, etc., c&rsquo;est-\u00e0-dire que leurs r\u00e9flexes les poussent \u00e0 aller au-devant des buts recherch\u00e9s par leurs adversaires, qui sont des buts de nettoyage ethnique, de division, de partition, etc., au d\u00e9savantage de ce qu&rsquo;ils sont cens\u00e9s promouvoir. Par leur comportement, ils se font les complices, plus ou moins volontaires c&rsquo;est selon, de ceux qu&rsquo;ils affrontent, qui sont en g\u00e9n\u00e9ral des irr\u00e9guliers par rapport aux arrangements du Syst\u00e8me, qui suivent en g\u00e9n\u00e9ral des buts pr\u00e9cis et structurants pour eux-m\u00eames, au service d&rsquo;entit\u00e9s unitaires ou d&rsquo;id\u00e9ologies bien identifi\u00e9es (que certaines soient d\u00e9testables ou critiquables n&rsquo;importe pas pour cette observation qui n&rsquo;appr\u00e9cie que la seule probl\u00e9matique de l&rsquo;\u00e9volution de la structuration des situations). Il s&rsquo;agit alors de conflits appartenant \u00e0 la guerre dite de 4\u00e8me g\u00e9n\u00e9ration (G4G), o\u00f9 les diff\u00e9rences se marquent selon des r\u00e9f\u00e9rences aux capacit\u00e9s unificatrices, structurantes et identitaires tr\u00e8s in\u00e9gales selon qu&rsquo;elles r\u00e9pondent ou non \u00e0 des principes,  et l&#8217;emportent ceux qui r\u00e9pondent le mieux \u00e0 ces r\u00e9f\u00e9rences lorsqu&rsquo;elles repr\u00e9sentent elles-m\u00eames des principes unificateurs.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 14 juin 2014 \u00e0 06H26<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9sordre des forces de l&rsquo;ordre postmodernes Nous ferons un rapprochement entre deux \u00e9pisodes concernant les forces arm\u00e9es de deux pays dans cette situation postmoderne interm\u00e9diaire m\u00ealant la conqu\u00eate ou l&rsquo;influence du Syst\u00e8me venues de l&rsquo;ext\u00e9rieur et la d\u00e9structuration de tous les cadres principiels qui en d\u00e9coule, et ces forces confront\u00e9es \u00e0 des conflits de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3858,2936,857,13758,2937,15634,6704,15874,15635,1296],"class_list":["post-75350","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-corruption","tag-garde","tag-irak","tag-isis","tag-nationale","tag-pravy","tag-principes","tag-redeker","tag-sektor","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75350"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75350\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}