{"id":75380,"date":"2014-06-30T08:05:13","date_gmt":"2014-06-30T08:05:13","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/06\/30\/le-systeme-et-leurs-escapades-incontrolables\/"},"modified":"2014-06-30T08:05:13","modified_gmt":"2014-06-30T08:05:13","slug":"le-systeme-et-leurs-escapades-incontrolables","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/06\/30\/le-systeme-et-leurs-escapades-incontrolables\/","title":{"rendered":"Le Syst\u00e8me et leurs \u201cescapades incontr\u00f4lables\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">Le Syst\u00e8me et leurs \u00ab\u00a0escapades incontr\u00f4lables\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>30 juin 2014 &ndash; En un sens, cette tournure que nous voudrions imprimer \u00e0 ce <em>F&#038;C<\/em> rejoint, ou plut\u00f4t prolonge et compl\u00e8te, celle des <em>Notes d&rsquo;analyse<\/em> du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_m_tamorphose_furieuse_des_cloportes_24_06_2014.html\">24 juin 2014<\/a>, \u00e0 propos de la furieuse \u00ab\u00a0m\u00e9tamorphose des cloportes\u00a0\u00bb&#8230; Cette fois, il s&rsquo;agit d&rsquo;\u00e9v\u00e9nements, que nous connaissons et suivons d&rsquo;une fa\u00e7on continue, au travers de diverses sources, mais qui soudain, par le biais d&rsquo;un texte ou l&rsquo;autre, acqui\u00e8rent toute leur signification.<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit d&rsquo;un processus qui m\u00e9rite d&rsquo;\u00eatre d\u00e9taill\u00e9, et cela d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, c&rsquo;est-\u00e0-dire sans prise en compte directe de tel ou tel texte que nous allons utiliser. Nous voulons dire par l\u00e0 que ce n&rsquo;est pas le texte lui-m\u00eame qui est le porteur, sinon le cr\u00e9ateur de cette \u00ab\u00a0prise de conscience\u00a0\u00bb ; les textes de ce caract\u00e8re auquel nous nous r\u00e9f\u00e9rons ont leurs qualit\u00e9s diverses qui leur sont propres, et qui les justifient par eux-m\u00eames ; certains sont brillants, d&rsquo;autres tr\u00e8s bien structur\u00e9s et inform\u00e9s, mais ils ne sont pas les acteurs centraux du processus dont nous parlons. En effet, nous parlons d&rsquo;abord, ici, d&rsquo;un processus mental qui, <strong>gr\u00e2ce \u00e0 un texte<\/strong> que vous lisez et qui illustre \u00e0 sa mani\u00e8re et de fa\u00e7on convaincante ou brillante une situation, conduit votre esprit \u00e0 appr\u00e9hender brusquement cette situation dans son essence m\u00eame. La lecture a jou\u00e9 son r\u00f4le de d\u00e9tonateur de la d\u00e9marche intellectuelle, en ceci qu&rsquo;elle conduit l&rsquo;esprit \u00e0 solliciter sa propre exp\u00e9rience, \u00e0 s&rsquo;ouvrir \u00e0 l&rsquo;intuition, \u00e0 travailler sous la conduite de sa raison comme outil de rationalisation et de communication du constat bient\u00f4t r\u00e9alis\u00e9.<\/p>\n<\/p>\n<p><p>Ce rapide aper\u00e7u d&rsquo;une m\u00e9thodologie complexe et intellectuellement tr\u00e8s diverse et tr\u00e8s ouverte introduit notre d\u00e9marche centrale : \u00e0 partir de ces trois situations brusquement saisies dans leur essence, il s&rsquo;agit de tirer une analyse g\u00e9n\u00e9rale d&rsquo;un ph\u00e9nom\u00e8ne qui ne l&rsquo;est pas moins. La particularit\u00e9 de ces trois situations se trouve dans leur exceptionnalit\u00e9 par rapport aux normes rationnelles des relations internationales autant que des normes historiques habituellement observ\u00e9es \u00e0 l&rsquo;int\u00e9rieur du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_syst_me_08_07_2013.html\">Syst\u00e8me<\/a>, &ndash; disons, pour substantiver et symboliser \u00e0 la fois notre propos en nous r\u00e9f\u00e9rant au <em>Glossaire.dde<\/em> sur la m\u00e9tahistoire (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_dimension_m_tahistorique_25_06_2014.html\">25 juin 2014<\/a>) : l&rsquo;exceptionnalit\u00e9 de ces situations par rapport \u00e0 l'\u00a0\u00bbhistoire-tout-court\u00a0\u00bb qui repr\u00e9sente pour nous, dans notre constat de la situation g\u00e9n\u00e9rale, l&rsquo;historiographie pseudo-scientifique restituant une <em>narrative<\/em> rassurante et apaisante, capable de camoufler et d&rsquo;habiller de v\u00eatements d\u00e9cents l&rsquo;avancement de la surpuissance du Syst\u00e8me issu du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_cha_nement_de_la_mati_re__05_11_2012.html\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>. En quelque sorte, le Syst\u00e8me lui-m\u00eame serait conduit de plus en plus \u00e0 laisser se faire, dans le chef des psychologies \u00e9puis\u00e9es de nombre de ses acteurs-Syst\u00e8me ou figurants-Syst\u00e8me, des extractions de la fiction narrative qu&rsquo;il soutient, &ndash; l&rsquo;histoire-tout-court, &ndash; tant cette fiction ne suffit plus \u00e0 arr\u00eater la mar\u00e9e des \u00e9v\u00e9nements conduits par la m\u00e9tahistoire&#8230;<\/p>\n<\/p>\n<p><p>Mais nous anticipons sur notre analyse. Passons imm\u00e9diatement \u00e0 la description que nous jugeons d\u00e9monstrative de trois \u00e9v\u00e9nements en cours, au sein des deux centres de crise majeurs (l&rsquo;Ukraine et l&rsquo;Irak) qui constituent aujourd&rsquo;hui le moteur de la crise g\u00e9n\u00e9rale du Syst\u00e8me. Encore une fois et d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, nous citons des textes nullement pour prendre position par rapport \u00e0 eux, mais parce qu&rsquo;ils d\u00e9crivent d&rsquo;une fa\u00e7on pr\u00e9cise et claire, ou d&rsquo;une fa\u00e7on \u00e9clairante par sa profondeur pour l&rsquo;un d&rsquo;entre eux, trois \u00e9v\u00e9nements ressortant de l&rsquo;exceptionnalit\u00e9 dont nous parlons.<\/p>\n<\/p>\n<p><p>&bull; D&rsquo;abord un texte de <em>WSWS.org<\/em> portant sur la situation int\u00e9rieure de l&rsquo;Ukraine, du point de vue d&rsquo;une part de l&rsquo;organisation et de l&rsquo;action des groupes extr\u00e9mistes, ultra-nationalistes et clairement \u00e0 tendance nazie, du point de vue d&rsquo;autre part de l&rsquo;action des oligarques en tant que forces autonomes \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;ensemble ukrainien (Kiev), et pr\u00e9cis\u00e9ment d&rsquo;un de ces oligarques, Igor Kolomo\u00efski, nomm\u00e9 gouverneur de la province de Dnepopetrovsk et qui a fait de cette ville le centre op\u00e9rationnel de la r\u00e9pression dans l&rsquo;Est du pays. Les extraits ci-dessous sont du texte de <em>WSWS.org<\/em>, de Clara Weiss, le <a class=\"gen\" href=\"http:\/\/www.wsws.org\/en\/articles\/2014\/06\/28\/fasc-j28.html\">28 juin 2014<\/a>.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>&#8230;The<\/em> [<em>Azov<\/em>] <em>battalion clearly enjoys the support of Washington and the regime. A YouTube video from Radio Free Europe, which is financed by the US Congress, shows Azov militiamen at a shooting practice. The pro-government Ukrainian media reports positively about the paramilitary groups and celebrates them as \u00ab\u00a0Heroes of Ukraine.\u00a0\u00bb Members of the battalion take every opportunity to declare that they do not view their opponents as people and seek to \u00ab\u00a0destroy\u00a0\u00bb them.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>According to accounts in the press, the battalion is financed by the oligarch Ihor Kolomoyskyi. With a total worth of $3 billion, Kolomoyskyi was the third richest man in Ukraine in 2012, according to Forbes. The Russian newspaper Correspondent estimates his worth at $6.2 billion. He is a co-owner of Private Bank, the largest bank in Ukraine. He is also one of the biggest operators in the Ukrainian oil, mining and air transport industries. At the beginning of March, Kolomoyskyi was named governor of the eastern Ukrainian state of Dnepopetrovsk.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Kolomoyskyi has politically and financially supported the pro-Western opposition for many years. He was one of the main financiers of the UDAR Party of boxer Vitali Klitschko. Previously, Kolomoyskyi was one of the most important oligarchs behind the opposition politician Yulia Tymoshenko. He also purportedly financed the head of Svoboda, Oleh Tyahnybok, who has, however, denied this in the Ukrainian press. According to accounts in the Frankfurter Rundschau and the Kiev Post, Kolomoyskyi is behind the \u00ab\u00a0Dnepr\u00a0\u00bb and \u00ab\u00a0Donbass\u00a0\u00bb battalions, which spread terror in eastern Ukraine. These units recruit mainly from fascist organizations and former soldiers.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Dnepopetrovsk has been transformed under Kolomoyskyi into an organizational center of paramilitary forces used by the Kiev regime to combat opposition in the eastern part of the country. The news agency Reuters reports that at the end of May, Kolomoyskyi used several dozen millions of US dollars to prevent the region from falling into the hands of separatists. With this money, a \u00ab\u00a0National Defense Unit\u00a0\u00bb was built comprising 15,000 men. These included 2,000 battle-ready soldiers divided into four battalions.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Igor Beresa, commander of the National Defense Unit, told Reuters that the battalions are accepting formal orders from the Ukrainian army and security forces, although the battalions receive an income twice as high and are better equipped. Kolomoyskyi&rsquo;s second-in-command, Boris Filatov, explained to Reuters: \u00ab\u00a0We are doing all this in agreement with the central government. We coordinate and cooperate with Kiev. They accept that we are influential as a consolidating factor in the east.\u00a0\u00bb The Right Sector, which is also active as an independent formation in armed confrontations, shifted its headquarters to Dniepopetrovsk at the end of April. At the time, its leader, Dmitro Yarosh, boasted in an interview with Spiegel Online, \u00ab\u00a0Our battalions are part of the new territorial defense. We have good relations with everybody, apart from the police.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ce texte, \u00e9crit sans fioritures, sans laisser percer les sentiments, \u00e0 partir de sources honorables et \u00e9quilibr\u00e9es, restitue une image saisissante de la v\u00e9rit\u00e9 d&rsquo;une situation en plein c&oelig;ur de l&rsquo;Europe, consid\u00e9r\u00e9e <em>de facto<\/em> comme l\u00e9gale et souveraine par l&rsquo;UE (encore plus depuis qu&rsquo;un accord de coop\u00e9ration a \u00e9t\u00e9 sign\u00e9 avec l&rsquo;Ukraine), et bien entendu par les USA. On pr\u00e9cisera ce que tout le monde devrait savoir, que ces milices et groupes arm\u00e9s sont, pour nombre d&rsquo;entre eux, de tendance nazie (et nullement n\u00e9o-nazie, la r\u00e9f\u00e9rence directe \u00e0 l&rsquo;Allemagne hitl\u00e9rienne \u00e9tant faite), que Igor Kolomo\u00efski qui les finance et les influence \u00e0 sa guise est juif, avec la double nationalit\u00e9 ukrainienne et isra\u00e9lienne (<em>Wikip\u00e9dia<\/em> signale \u00e0 propos de Kolomo\u00efski qu&rsquo;il est &laquo;[r]<em>ussophobe et antis\u00e9mite convaincu en d\u00e9pit de sa filiation<\/em>&raquo;). Isra\u00ebl Shamir, commentateur russo-isra\u00e9lien d&rsquo;une redoutable ambigu\u00eft\u00e9, \u00e9crit dans son article (traduction fran\u00e7aise de Maria Poumier) &laquo;<em> Le triangle fatidique: la Russie, l&rsquo;Ukraine et les juifs<\/em>&raquo;, le <a class=\"gen\" href=\"http:\/\/www.israelshamir.net\/French\/Le_triangle.htm\">20 juin 2014<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Ils savent quand il faut feindre l&rsquo;indignation et quand il convient de se taire.<\/em>[&#8230;] <em>Les US veulent d\u00e9cider seuls qui est antis\u00e9mite et qui ne l&rsquo;est pas, comme Hermann Goering voulait d\u00e9cider qui \u00e9tait juif et qui ne l&rsquo;\u00e9tait pas, dans la Luftwaffe.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; L&rsquo;article cit\u00e9 nous offre une description convenable d&rsquo;une extraordinaire escapade hors des exigences de la r\u00e9alit\u00e9-Syst\u00e8me, des <em>narrative<\/em> imp\u00e9ratives, voire de la m\u00e9taphysique-simulacre du Syst\u00e8me (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_psychanalytiques_et_m_taphysiques_sur_9_11_11_10_2011.html\">10 octobre 2011<\/a>). Il faut un instant se d\u00e9faire de nos habitudes de tout lire et de tout voir, d&rsquo;identifier leurs distorsions sans nombre des r\u00e9alit\u00e9s, de se d\u00e9placer dans la facticit\u00e9 de l&rsquo;univers du Syst\u00e8me, pour retrouver une appr\u00e9ciation g\u00e9n\u00e9rale qui permet de juger combien cette situation ukrainienne repr\u00e9sente de d\u00e9sordre extraordinaire et de libert\u00e9s insultantes prises par rapport aux normes du Syst\u00e8me. Il s&rsquo;agit d&rsquo;une formidable d\u00e9viation hors de l&rsquo;histoire-tout-court \u00e0 laquelle le Syst\u00e8me pr\u00e9tend r\u00e9duire notre destin. C&rsquo;est cette occurrence qui nous para&icirc;t fondamentale, parce qu&rsquo;il nous semble qu&rsquo;il devrait \u00eatre, et qu&rsquo;il \u00e9tait effectivement <strong>impensable et indicible<\/strong> que l&rsquo;on puisse, de l&rsquo;int\u00e9rieur du Syst\u00e8me, s&rsquo;aventurer dans de tels chemins de traverse qui rel\u00e8vent de l&rsquo;h\u00e9r\u00e9sie, de l&rsquo;apostasie pure et simple. Mais non, la chose se fait sans vraiment inqui\u00e9ter ceux qui devraient l&rsquo;\u00eatre avant tous les autres, &ndash; les directions politiques du Syst\u00e8me elles-m\u00eames&#8230;<\/p>\n<\/p>\n<p><p>&bull; Encore n&rsquo;a-t-on rien vu de ce qui nous cr\u00e8ve les yeux. Cet exemple ukrainien de Kolomo\u00efski, de ses nazis &#038; Cie, ressuscitant dans un cadre digne des pires <em>blockbuster<\/em> hollywoodiens une circonstance effectivement <strong>impensable et indicible<\/strong> au sein m\u00eame d&rsquo;une entreprise (la nouvelle Ukraine) pr\u00e9sent\u00e9e comme exemplaire de l&rsquo;avancement de l&rsquo;id\u00e9al hyperlib\u00e9ral et d\u00e9mocratique du Syst\u00e8me, cet exemple est spectaculaire. Il n&rsquo;est pourtant pas celui qui va le plus au fond des choses, largement surpass\u00e9 dans le champ du risque et de la menace impos\u00e9s \u00e0 soi-m\u00eame, par le comportement de la direction US vis-\u00e0-vis de la Russie. L\u00e0-dessus, il n&rsquo;est gu\u00e8re besoin de documentation, tant abondent les documents publics et officiels \u00e0 cet \u00e9gard. Pour simplement rappeler de quoi est fait notre sujet, on citera simplement les premi\u00e8res lignes d&rsquo;un autre article, non moins s\u00e9rieux et parfaitement document\u00e9, de <em>WSWS.org<\/em>, sur la visite r\u00e9cente de John Kerry \u00e0 Paris, de sa courte d\u00e9claration publique, qui laisse sur place m\u00eame le bellicisme fran\u00e7ais que nous nous sommes habitu\u00e9s \u00e0 voir r\u00e9solument en premi\u00e8re ligne&#8230; (Article de Bill Van Auken, <em>WSWS.org<\/em>, le <a class=\"gen\" href=\"http:\/\/www.wsws.org\/en\/articles\/2014\/06\/27\/nato-j27.html\">27 juin 2014<\/a>.)<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Speaking in Paris Thursday, US Secretary of State John Kerry issued a fresh ultimatum to the government of Russia, warning that it had to demonstrate \u00ab\u00a0within hours\u00a0\u00bb that it is acting to end the revolt in eastern Ukraine against the Western-installed government in Kiev or face the consequences. \u00ab\u00a0We are in full agreement that it is critical for Russia to show in the next hours, literally, that they are moving to help disarm the separatists,\u00a0\u00bb Kerry said. He added that \u00ab\u00a0the European Community will be meeting on their component of the sanctions. We all agree that they need to be ready.\u00a0\u00bb Kerry&rsquo;s warning came in the context of a NATO foreign minister&rsquo;s meeting that wrapped up in Brussels Thursday and a European Union summit scheduled for today in the Belgian city and World War I battle site of Ypres.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>The US Secretary of State delivered his remarks alongside French Foreign Minister Laurent Fabius, who was clearly acting on a somewhat different agenda, not to mention timetable. Fabius spoke of a \u00ab\u00a0de-escalation\u00a0\u00bb in Ukraine and of commitments that Russian President Vladimir Putin had made the day before in a four-way telephone conference that included German Chancellor Angela Merkel, French President Francois Hollande and Ukraine&rsquo;s President Petro Poroshenko. France, he said, hoped that Russia&rsquo;s promises would be fulfilled \u00ab\u00a0in the coming days.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>While Washington is manifestly seeking to ratchet up the confrontation with Russia, the Western European powers are showing somewhat less enthusiasm for such an escalation. Meanwhile, it is far from clear that there has been any \u00ab\u00a0de-escalation\u00a0\u00bb of the situation on the ground in Ukraine, which is turning into a major humanitarian crisis, largely ignored by Western governments and media.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ce que nous voulons mettre en \u00e9vidence, dans ce qui para&icirc;t \u00eatre une sorte de routine \u00ab\u00a0au-jour-le-jour\u00a0\u00bb, de la part du secr\u00e9taire d&rsquo;&Eacute;tat, c&rsquo;est qu&rsquo;il y a un acte diplomatique extraordinaire et insens\u00e9 dans le fait de parler de la sorte \u00e0 la Russie, dans les circonstances qu&rsquo;on sait, pour une crise qui se d\u00e9roule sur la fronti\u00e8re russe. Nous croyons que le caract\u00e8re extraordinaire de cette d\u00e9marche consid\u00e9r\u00e9e comme du <em>business as usual<\/em>, devrait conduire \u00e0 un jugement particuli\u00e8rement stup\u00e9fait sur la situation ainsi \u00e9tablie par l&rsquo;une des deux superpuissances nucl\u00e9aires (c&rsquo;est-\u00e0-dire ayant une capacit\u00e9 strat\u00e9gique globale de frappe d&rsquo;an\u00e9antissement) parlant de la sorte \u00e0 son vis-\u00e0-vis. Kerry \u00e9gr\u00e8ne les ultimatums, en jours, voire en heures comme dans le cas mis en \u00e9vidence ici, \u00e0 partir d&rsquo;une situation rocambolesque de d\u00e9ni de toute d\u00e9viation de la <em>narrative<\/em> d\u00e9velopp\u00e9e par Washington. (On peut voir, par exemple, comme un des \u00e9l\u00e9ments de cette extraordinaire op\u00e9ration de d\u00e9ni la porte-parole adjointe du d\u00e9partement d&rsquo;&Eacute;tat, Marie Harff, rejeter avec une extraordinaire l\u00e9g\u00e8ret\u00e9, le 28 juin 2014, l&rsquo;\u00e9valuation de 110 000 r\u00e9fugi\u00e9s ukrainiens en Russie \u00e9tablie par l&rsquo;Agence des Nations-Unies charg\u00e9e de cette question, &ndash; d&rsquo;une seule affirmation, r\u00e9p\u00e9t\u00e9e plusieurs fois \u00e0 l&rsquo;insistance du correspondant d&rsquo;AP accr\u00e9dit\u00e9 au d\u00e9partement d&rsquo;&Eacute;tat : &laquo;<em>Nous n&rsquo;avons aucune preuve, aucun \u00e9l\u00e9ment cr\u00e9dible de ce qui est avanc\u00e9&#8230;<\/em>&raquo;, &ndash; donc, \u00ab\u00a0nous passons outre&#8230; Une autre question ?\u00a0\u00bb)<\/p>\n<\/p>\n<p><p>L&rsquo;exceptionnalit\u00e9 se trouve ici, justement, dans le d\u00e9veloppement d&rsquo;une <em>narrative<\/em> qui, au pr\u00e9texte d&rsquo;appuyer la politique-Syst\u00e8me, conduit \u00e0 une situation extraordinairement dangereuse de potentialit\u00e9 d&rsquo;affrontement dont la logique terminale peut \u00eatre une guerre nucl\u00e9aire. Une telle occurrence \u00e9tait simplement impensable durant la p\u00e9riode qui a \u00e9tabli les relations les plus prudentes et les plus efficaces entre puissances nucl\u00e9aires, durant la Guerre froide. Aucune circonstance, durant la Guerre froide, n&rsquo;a vu de tels risques pris au niveau de la communication, m\u00eame dans des circonstances bien plus pressantes (crise de Berlin en 1961, crise de Cuba en 1962). Ce qui repr\u00e9sente une escapade extraordinaire par rapport aux correspondants diplomatiques et strat\u00e9giques, c&rsquo;est bien le risque pris au niveau de la communication, alors que l&rsquo;enjeu pourrait \u00eatre r\u00e9duit ais\u00e9ment au niveau op\u00e9rationnel, par simple arrangement de compromis.<\/p>\n<\/p>\n<p><p>&bull; Le troisi\u00e8me exemple repr\u00e9sent\u00e9 ici d&rsquo;une escapade extraordinaire des r\u00e9alit\u00e9s courantes qui devraient \u00eatre ma&icirc;tris\u00e9es par la politique-Syst\u00e8me pour \u00e9viter tout risque inconsid\u00e9r\u00e9, c&rsquo;est la crise irakienne. Cette fois, il s&rsquo;agit d&rsquo;un exemple par inversion, par rapport \u00e0 ce qui a pr\u00e9c\u00e9d\u00e9. Il ne s&rsquo;agit plus d&rsquo;une situation extraordinaire et rocambolesque, et tr\u00e8s risqu\u00e9e, d\u00e9velopp\u00e9e en bonne partie en connaissance de cause par des agents du Syst\u00e8me, mais, tel que nous le prenons explicitement et dans ces limites, d&rsquo;un \u00e9v\u00e9nement issu du d\u00e9sordre du Syst\u00e8me qui s&rsquo;institue brusquement comme la possibilit\u00e9 d&rsquo;une aventure extraordinaire hors-du-Syst\u00e8me, sans que l&rsquo;on sache l&rsquo;orientation que prendra cette aventure et les effets qu&rsquo;elle donnera. L&rsquo;extraordinaire se trouve dans ce cas, dans le fait que le Syst\u00e8me ait permis ce d\u00e9veloppement, puisque l&rsquo;appr\u00e9ciation la plus pure et la plus puissante de l&rsquo;aventure strat\u00e9gique d&rsquo;ISIS se trouve au niveau th\u00e9ologique. (Cet \u00e9v\u00e9nement, comme on le voit [<em>Russia Today<\/em>, ce <a class=\"gen\" href=\"http:\/\/rt.com\/news\/169256-isis-create-islamic-state\/\">29 juin 2014<\/a>], est en pleine maturation.) Bien s&ucirc;r, on trouve les habituels amas de complots divers, de repr\u00e9sentation d&rsquo;ISIS comme &laquo;<em>a CIA asset<\/em>\u00ab\u00a0, etc., mais cela n&rsquo;a gu\u00e8re de cr\u00e9dit ni de puissance, par comparaison avec l&rsquo;\u00e9valuation qu&rsquo;en donne l&rsquo;institut <em>Conflict Forum<\/em>, dans les commentaires hebdomadaires que donne son directeur Alastair Crooke. (Nous avons d\u00e9j\u00e0 repris certains de ces <em>Weekly Comment<\/em> d&rsquo;Alastair Crooke, par exemple le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_situation_gyptienne_la_lumi_re_de_l_histoire_19_08_2013.html\">19 ao&ucirc;t 2013<\/a>.)<\/p>\n<\/p>\n<p><p>Cette \u00e9valuation commence avec le <em>Weekly Comment<\/em> du <a class=\"gen\" href=\"http:\/\/www.conflictsforum.org\/2014\/conflict-forums-weekly-comment-14-21-june\/\">21 juin 2014<\/a> et se poursuit surtout dans le <em>Weekly Comment<\/em> du 29 juin (mis en ligne sur le <a class=\"gen\" href=\"http:\/\/rt.com\/news\/169256-isis-create-islamic-state\/\">site<\/a>, \u00e9galement repris sur <em>Huffington Post<\/em>, le <a class=\"gen\" href=\"http:\/\/www.huffingtonpost.com\/alastair-crooke\/iraq-isis-alqaeda_b_5542575.html?utm_hp_ref=world\">30 juin 2014<\/a>). L&rsquo;on y observe que la crise actuelle est v\u00e9ritablement explicable par une analyse th\u00e9ologique concernant les tourments de la religion musulmane, et c&rsquo;est bien dans cette opportunit\u00e9 donn\u00e9e \u00e0 une analyse qui \u00e9chappe \u00e9videmment au Syst\u00e8me, qui se r\u00e9f\u00e8re \u00e0 des notions et des analogies confrontant un aspect de la Tradition et l&rsquo;\u00e9poque-Syst\u00e8me que nous vivons, que se trouvent l&rsquo;exceptionnalit\u00e9 dont nous faisons \u00e9tat, et l&rsquo;incontr\u00f4labilit\u00e9 qui va avec. L&rsquo;analyse grandit l&rsquo;\u00e9v\u00e9nement en lui restituant sa perspective historique qui n&rsquo;est \u00e9videmment pas exempte d&rsquo;\u00e9l\u00e9ments m\u00e9tahistoriques.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Extraordinary times: Extraordinary events in Iraq (and in the Muslim World). The lightening seizure of \u00ab\u00a0Sunni territory\u00a0\u00bb spanning Syria and Iraq (but imagined as the realisation of a Sunni &lsquo;belt&rsquo; extending across the region); with all its potent symbolism in the context of the early history of Islam; with its forging of a completely new &lsquo;Sunni geography&rsquo;; and with the cold ruthlessness of its military strategy, has dazzled and stimulated the ardour of young Sunni Muslims everywhere.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>It has forced the admiration of many in Iraq and the Gulf States; yet it frightens too, the flesh creeps with the \u00ab\u00a0march of the beheaders\u00a0\u00bb. It is this heady, adrenalin-laden mix of fear, mingling with the euphoric sense that events somehow are mirroring the very laying down of the Islamic Empire, which is seeding fertile ground. Across the Middle East and Africa, agrarian distress and the Salafist firing-up of a Sunni self-perception of victimhood, usurpation and grievance are making for a wide vulnerability to this new collective fervour for Da&rsquo;ish (ISIS).<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo;<em>In Iraq today, it is clear that ISIS sees the path toward consolidating the Islamic State to have already passed through the first stage (vexation operations, dispersing the enemy&rsquo;s strength and over-extending its resources). Here again, the question arises, to which &lsquo;enemy&rsquo; does ISIS refer? Well, ISIS does not say; but Gulf leaders make this abundantly clear when they tell westerners that if only Bashar Assad and Nouri al-Maliki were to be removed, all would be resolved, and peace would return to the Middle East (both of course bring perceived as obstacles to regional Sunni hegemony).<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>So today, ISIS regards Iraq (and eastern Syria) to be in the second stage (the \u00ab\u00a0Management of Savagery\u00a0\u00bb) in the progress toward the consolidation of the Caliphate (the third stage). What does this mean; and what does it imply for the conduct of next period?<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>The term &lsquo;administration of savagery&rsquo; in fact refers to that hiatus which occurs between the waning of one power and the consolidation of power of another. What is being assumed here is that a certain chaos will pertain, and that the disputed territory will be ravaged by violence as power oscillates back and forth between the &lsquo;old&rsquo; power and its incoming successor (the Islamic State).<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>In this period, ISIS according to its literature, will have limited aims: achieving internal security and preserving it; fixing its frontiers; feeding the population; establishing Shariah and Islamic justice &ndash; and most importantly fixing the establishment of a &lsquo;fighting society&rsquo;, at all levels within the community. In this stage, security will require the elimination of spies and \u00ab\u00a0deterring the hypocrites with proof and other means and forcing them to repress and conceal their hypocrisy, to hide their discouraged opinions, and to comply with those in authority, until their evil is put in check\u00a0\u00bb. In short, we might expect that this will comprise ISIS&rsquo; aims for the coming period. In other words, that any move on Baghdad, which Da&rsquo;ish insists will come, is unlikely to be imminent, but will have to await until the area already seized is &lsquo;secured&rsquo;, and its frontiers controlled&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Escapade, &ndash; ou comment \u00ab\u00a0s&rsquo;\u00e9chapper\u00a0\u00bb ?<\/h3>\n<\/p>\n<p><p>&#8230; En introduction \u00e0 notre commentaire ci-dessous, nous proposons d&rsquo;abord de baptiser cette sorte d&rsquo;\u00e9v\u00e9nements, que nous jugeons extraordinaires pour les raisons diverses que nous exposons, de l&rsquo;expression d'\u00a0\u00bbescapade incontr\u00f4l\u00e9e\u00a0\u00bb. (On aurait pu ajouter le qualificatif d'\u00a0\u00bbexceptionnel\u00a0\u00bb mais nous ne voulons pas trop charger l&rsquo;expression et il nous semble que le caract\u00e8re d&rsquo;incontr\u00f4labilit\u00e9 peut absorber celui d&rsquo;exceptionnalit\u00e9.) Le mot \u00ab\u00a0escapade\u00a0\u00bb signifie \u00e9tymologiquement \u00ab\u00a0s&rsquo;\u00e9chapper\u00a0\u00bb : &laquo;<em>Du vieil espagnol escapada, d\u00e9riv\u00e9 de escapar [\u00ab\u00a0\u00e9chapper\u00a0\u00bb], du latin vulgaire excappre [\u00ab\u00a0\u00e9chapper\u00a0\u00bb].<\/em>&raquo; Ce sens profond nous convient parfaitement, pour la signification profonde de la chose, par rapport \u00e0 l&rsquo;\u00e9tat des psychologies. D\u00e8s lors, les \u00ab\u00a0escapades incontr\u00f4l\u00e9es\u00a0\u00bb dans leur origine deviennent g\u00e9n\u00e9riquement des \u00ab\u00a0escapades incontr\u00f4lables\u00a0\u00bb, acqu\u00e9rant une sorte d&rsquo;autonomie, et l&rsquo;on peut envisager qu&rsquo;elle s&rsquo;imposent au Syst\u00e8me de cette fa\u00e7on ; nous les identifions effectivement comme des \u00ab\u00a0escapades incontr\u00f4lables\u00a0\u00bb, \u00ab\u00a0n\u00e9es du Syst\u00e8me mais non d\u00e9sir\u00e9es par lui dans cette intensit\u00e9 d\u00e9stabilisatrice\u00a0\u00bb, comme nous l&rsquo;\u00e9crivons par ailleurs (dans le r\u00e9sum\u00e9 de pr\u00e9sentation, l&rsquo;<em>abstract<\/em> de cet article).<\/p>\n<\/p>\n<p><p>Ce qu&rsquo;il nous importe de montrer \u00e0 ce point, apr\u00e8s avoir d\u00e9velopp\u00e9 et pr\u00e9sent\u00e9 ces trois exemples d&rsquo;\u00e9v\u00e9nements extraordinaires issus d&rsquo;une fa\u00e7on ou d&rsquo;une autre de l&rsquo;activit\u00e9 du Syst\u00e8me dans le chef de la politique-Syst\u00e8me, c&rsquo;est combien ces \u00ab\u00a0\u00e9v\u00e9nements extraordinaires\u00a0\u00bb d\u00e9veloppent n\u00e9cessairement une instabilit\u00e9 qui peut \u00e9videmment \u00e9branler le Syst\u00e8me, ou bien, encore plus, l&rsquo;affoler absolument. Or, ces \u00e9v\u00e9nements sont \u00e9galement machin\u00e9s, comme l&rsquo;on dirait d&rsquo;un encha&icirc;nement m\u00e9canique, d&rsquo;une fa\u00e7on compl\u00e8tement anarchique et incontr\u00f4lable par des acteurs du Syst\u00e8me, directement ou indirectement. Ces \u00e9v\u00e9nements constituent en quelque sorte des \u00ab\u00a0escapades incontr\u00f4lables\u00a0\u00bb de la ligne que devrait suivre la politique-Syst\u00e8me alors qu&rsquo;ils sont issus effectivement de l&rsquo;activisme du Syst\u00e8me. On voit combien, dans ces m\u00e9andres et dans ces m\u00e9langes extraordinairement contradictoires, o&ugrave; seul pr\u00e9vaut le d\u00e9sordre, on retrouve la correspondance entre la dynamique de surpuissance et la dynamique de l&rsquo;autodestruction. Les \u00e9v\u00e9nements s&rsquo;\u00e9gr\u00e8nent, \u00e0 une vitesse extraordinaire qui marque l&rsquo;acc\u00e9l\u00e9ration de l&rsquo;histoire et la contraction du temps, selon une course qui ressemble \u00e0 un parcours en h\u00e9lice, o&ugrave; se croisent et s&rsquo;entrecroisent la logique de la surpuissance et celle de l&rsquo;autodestruction.<\/p>\n<\/p>\n<p><p>C&rsquo;est en cela que nous substantivons la contradiction interne fondamentale du Syst\u00e8me, d\u00e9j\u00e0 expos\u00e9e plus haut, dans la pr\u00e9sentation des exemples choisis. D&rsquo;une part, le Syst\u00e8me a besoin de ce que nous nommons l&rsquo;histoire-tout-court, c&rsquo;est-\u00e0-dire l&rsquo;histoire r\u00e9duite \u00e0 sa normalit\u00e9, l&rsquo;histoire en un sens sans pass\u00e9 ni futur, l&rsquo;histoire r\u00e9duite au <em>big Now<\/em>, ou \u00ab\u00a0pr\u00e9sent \u00e9ternel\u00a0\u00bb (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-du_big_now_l_l_ternel_pr_sent__29_01_2014.html\">29 janvier 2014<\/a>), l&rsquo;histoire rassurante et apaisante, qui r\u00e9duit (\u00ab\u00a0qui grandit\u00a0\u00bb pensent certains) nos pr\u00e9occupation \u00e0 l&rsquo;imm\u00e9diatet\u00e9 con\u00e7ue comme une mise en sc\u00e8ne, &ndash; du \u00ab\u00a0mariage pour tous\u00a0\u00bb \u00e0 la Coupe du Monde de football, au sacr\u00e9 de la religion r\u00e9duite aux repr\u00e9sentations postmodernes de l'\u00a0\u00bbArt Contemporain\u00a0\u00bb (AC) (1). D&rsquo;autre part, le Syst\u00e8me sugg\u00e8re, par l&rsquo;activit\u00e9 de sa surpuissance qui est sa raison d&rsquo;\u00eatre, l&rsquo;activation de forces qui conduisent \u00e0 mettre en question la banalit\u00e9 de l&rsquo;histoire-tout-court, \u00e0 la faire exploser, \u00e0 s&rsquo;autoriser des \u00ab\u00a0escapades incontr\u00f4lables\u00a0\u00bb qui font tout basculer&#8230;<\/p>\n<\/p>\n<p><p>C&rsquo;est dans cette contradiction entre une normalit\u00e9 forc\u00e9e et une surpuissance conduisant aux \u00ab\u00a0escapades incontr\u00f4lables\u00a0\u00bb que s&rsquo;immisce la m\u00e9tahistoire, comme un puissant levier s&rsquo;inc\u00e8re dans une fissure pour l&rsquo;agrandir en une b\u00e9ance catastrophique (pour le Syst\u00e8me). Une autre image pourrait \u00eatre celle de \u00ab\u00a0trous\u00a0\u00bb que les \u00ab\u00a0escapades incontr\u00f4lables\u00a0\u00bb percent dans le Syst\u00e8me, par lesquelles s&rsquo;engouffre effectivement la m\u00e9tahistoire gr\u00e2ce \u00e0 la signification qu&rsquo;elle donne au ph\u00e9nom\u00e8ne. Effectivement, les \u00e9v\u00e9nements extraordinaires qui s&rsquo;\u00e9chappent ainsi du cadre convenu (l&rsquo;histoire-tout-court) pour satisfaire aux effets des ambitions de la politique-Syst\u00e8me, deviennent des instruments involontaires de l&rsquo;activation de la m\u00e9tahistoire, et de sa p\u00e9n\u00e9tration directe dans l&rsquo;histoire-tout-cour, pour la dynamiter, pour la dissoudre et la transmuter d&rsquo;un m\u00eame \u00e9lan.<\/p>\n<\/p>\n<p><p>On voit bien que le secr\u00e9taire d&rsquo;&Eacute;tat Kerry balance un ultimatum \u00e0 la Russie comme on prend son petit d\u00e9jeuner, d&rsquo;une fa\u00e7on qu&rsquo;on dirait naturelle tant elle est robotis\u00e9e, ou robotis\u00e9e tant elle est naturelle. En fait et pour d\u00e9tendre l&rsquo;atmosph\u00e8re, cela vous \u00e9tonnerait-il que l&rsquo;on vous fasse l&rsquo;hypoth\u00e8se que Kerry \u00e9gr\u00e8ne tout cela comme une corv\u00e9e sans grand int\u00e9r\u00eat ? &#8230; Puisque, grand amateur de football qu&rsquo;il d\u00e9signe de ce nom, &ndash; alors qu&rsquo;il devrait dire <em>soccer<\/em> pour \u00eatre bon am\u00e9ricaniste (voir le site Washington <em>Free Bacon<\/em>, le <a class=\"gen\" href=\"http:\/\/freebeacon.com\/blog\/john-kerrys-soccer-obsession-is-undermining-america\/\">20 juin 2014<\/a>), &ndash; il semblerait manifeste qu&rsquo;il aurait pr\u00e9f\u00e9r\u00e9 suivre la Coupe du Monde plut\u00f4t que de \u00ab\u00a0balancer [des] ultimatum[s] \u00e0 la Russie\u00a0\u00bb : ainsi Kerry met-il l'\u00a0\u00bbescapade incontr\u00f4l\u00e9e\u00a0\u00bb dans une perspective qui en fait une \u00ab\u00a0escapade incontr\u00f4lable\u00a0\u00bb. Ce qu&rsquo;il r\u00e9duit \u00e0 un acte presque compulsif et presque inconscient, comme il sied \u00e0 la r\u00e9f\u00e9rence de l&rsquo;histoire-tout-court, est en v\u00e9rit\u00e9, nous voulons dire pour la v\u00e9rit\u00e9 de la situation, un acte extraordinaire d&rsquo;impudence et d&rsquo;imprudence, qui dissimule \u00e0 peine le risque de l&rsquo;affrontement nucl\u00e9aire.<\/p>\n<\/p>\n<p><p>Ceci, \u00e9galement : m\u00eame si ISIS &laquo;<em>is a CIA asset<\/em>&raquo;, &ndash; qui n&rsquo;est pas &laquo;<em>a CIA asset<\/em>&raquo; \u00e0 ce compte o&ugrave; la CIA est partout, y compris <em>dedefensa.org<\/em> ? &ndash; ISIS est \u00e9galement une folle \u00ab\u00a0escapade incontr\u00f4lable\u00a0\u00bb qui ressuscite furieusement une th\u00e9ologie venue d&rsquo;autres si\u00e8cles, et ainsi l&rsquo;histoire-tout-court est \u00e0 nouveau rompue. Quant \u00e0 la normalit\u00e9 des \u00ab\u00a0hordes nazies\u00a0\u00bb (comme on ne dit pas, pour une fois, dans les salons), sous le contr\u00f4le de l&rsquo;\u00e9tonnant oligarque Kolomo\u00efski, ukraino-isra\u00e9lien, juif et semble-t-il antis\u00e9mite, il est difficile d&rsquo;y ajouter foi (nous parlons de la \u00ab\u00a0normalit\u00e9\u00a0\u00bb de la chose). L\u00e0 aussi, l&rsquo;histoire-tout-court est rompu dans une \u00ab\u00a0escapade incontr\u00f4lable\u00a0\u00bb ; l&rsquo;UE tenant dans son berceau un nouveau futur-&Eacute;tat-membre qui ressuscite dans un d\u00e9sordre affolant pour sa propre id\u00e9ologie (celle de l&rsquo;UE) les pratiques des <em>condottiere<\/em> d&rsquo;un niveau assez bas, ou bien encore des \u00ab\u00a0seigneurs de la guerre\u00a0\u00bb type-afghans&#8230;<\/p>\n<\/p>\n<p><p>Bien entendu, nous ne pouvons en rester \u00e0 ce constat des ruptures de l&rsquo;histoire-tout-court enregistr\u00e9es comme on compostait un ticket de m\u00e9tro aux temps b\u00e9nis du \u00ab\u00a0poin\u00e7onneur des Lilas\u00a0\u00bb. Il nous semble aller de soit que ces \u00e9pisodes de contraction soudaine, ces \u00e9v\u00e9nements \u00e9normes qui t\u00e9moignent de la p\u00e9n\u00e9tration soudaine de la m\u00e9tahistoire dans l&rsquo;histoire-tout-court alors qu&rsquo;ils nous sont livr\u00e9s sous une \u00e9trange enveloppe de banalisation, comme si un ultimatum \u00e0 la Russie \u00e9quivalait \u00e0 un croissant dans son caf\u00e9 et avait beaucoup moins d&rsquo;importance qu&rsquo;un tir au but de Benz\u00e9ma, il nous semble \u00e9vident que tout cela <strong>doit n\u00e9cessairement faire peser<\/strong> un poids \u00e9norme sur les psychologies ; et nous parlons, prioritairement, des psychologies des employ\u00e9s-Syst\u00e8me, d&rsquo;une Marie Harff refusant avec une arrogance un peu hyst\u00e9rique les d\u00e9comptes de l&rsquo;ONU concernant les r\u00e9fugi\u00e9s fuyant en Russie leur Ukraine devenue massacreuse des siens, qu&rsquo;elle accepterait d&rsquo;une voix protectrice si ces m\u00eames d\u00e9comptes concernaient le nombre de r\u00e9fugi\u00e9s syriens ayant fui la Syrie-d&rsquo;Assad&#8230; D&rsquo;ailleurs, on peut \u00e9videmment renverser le flux qu&rsquo;on d\u00e9crit ici, de la tension que les ruptures de l&rsquo;histoire-tout-court p\u00e9n\u00e9tr\u00e9e par la m\u00e9tahistoire font peser sur les psychologies : n&rsquo;est-ce pas ce processus qui trouble si fortement les psychologies, \u00e0 ce point que ces psychologies nous pr\u00e9parent d\u00e9j\u00e0 d&rsquo;autres \u00ab\u00a0escapades incontr\u00f4lables\u00a0\u00bb \u00e0 l&rsquo;occasion desquelles la m\u00e9tahistoire p\u00e9n\u00e9trera \u00e0 nouveau l&rsquo;histoire-tout-court ? Et les psychologies actuelles, celles des employ\u00e9s-Syst\u00e8me soumises au Syst\u00e8me, ne sont-elles pas conduites par une pulsion lib\u00e9ratrice, parce qu&rsquo;elles \u00e9touffent dans le Syst\u00e8me dans sa phase actuelle d\u00e9cisive o&ugrave; la surpuissance est \u00e0 son paroxysme, et d\u00e9j\u00e0 autodestruction, ces psychologies ne r\u00eavent-elles pas secr\u00e8tement de \u00ab\u00a0s&rsquo;\u00e9chapper\u00a0\u00bb de cette prison, cela conduisant \u00e0 ces \u00ab\u00a0escapades\u00a0\u00bb, d&rsquo;un mot dont le sens profond est effectivement \u00ab\u00a0s&rsquo;\u00e9chapper\u00a0\u00bb ?<\/p>\n<\/p>\n<p><p>Profitant du centenaire qu&rsquo;on sait (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-de_2013_2014_en_passant_par_1914_02_01_2014.html\">2 janvier 2014<\/a>), 2014 semble se dessiner comme une ann\u00e9e rupturielle dans la course du Syst\u00e8me. La situation actuelle ressemble donc \u00e0 une roue devenue folle, qui tourne sur elle-m\u00eame de plus en plus vite, en avan\u00e7ant de plus en plus vite, m\u00e9langeant effectivement effets de puissance et effets d&rsquo;autodestruction selon ce mouvement de rotation qui emp\u00eache de regarder le pass\u00e9 imm\u00e9diat et d&rsquo;appr\u00e9hender le futur imm\u00e9diat pour s\u00e9parer surpuissance d&rsquo;autodestruction, multipliant ainsi les occasions de perc\u00e9es de la m\u00e9tahistoire dans l&rsquo;histoire-tout-court &#8230; Qui ne reconna&icirc;trait en effet, dans ce sch\u00e9ma, une all\u00e9gorie de l&rsquo;\u00e9quation surpuissance-autodestruction ? La surpuissance maintient l&rsquo;apparence de l&rsquo;histoire-tout-court qui permet \u00e0 la politique-Syst\u00e8me de poursuivre sa course, les perc\u00e9es de la m\u00e9tahistoire criblent cette course de pesanteurs de plus en plus insupportables, illustrations du processus d&rsquo;autodestruction, et la structure m\u00eame du Syst\u00e8me de trous par o&ugrave; elle-m\u00eame (la m\u00e9tahistoire) s&rsquo;engouffrerait&#8230; Alors se pose la question d&rsquo;une autre rupture qui pourrait se constituer comme \u00ab\u00a0finale\u00a0\u00bb, de savoir dans quelle mesure l&rsquo;une ou l&rsquo;autre de ces \u00ab\u00a0escapades incontr\u00f4l\u00e9es\u00a0\u00bb suppose un retour \u00e0 la normalit\u00e9, &ndash; c&rsquo;est souvent le fait d&rsquo;une \u00ab\u00a0escapade\u00a0\u00bb qu&rsquo;on en puisse revenir, &ndash; ou si, devenant effectivement \u00ab\u00a0escapades incontr\u00f4lables\u00a0\u00bb, elle implique au contraire une telle puissance qu&rsquo;elle cr\u00e9e une situation compl\u00e8tement nouvelle d&rsquo;o&ugrave; elle ne reviendra plus, posant ainsi un probl\u00e8me d\u00e9cisif, une interrogation ontologique, au Syst\u00e8me.<\/p>\n<\/p>\n<p><h4>Note<\/h4>\n<\/p>\n<p><p>(1) Lire \u00e0 ce propos le tr\u00e8s-\u00e9difiant <em>Sacr\u00e9 Art Contemporain<\/em>, de Maude de Kerros, 2012, \u00e9ditions Jean-Cyrille Godefroy.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Syst\u00e8me et leurs \u00ab\u00a0escapades incontr\u00f4lables\u00a0\u00bb 30 juin 2014 &ndash; En un sens, cette tournure que nous voudrions imprimer \u00e0 ce F&#038;C rejoint, ou plut\u00f4t prolonge et compl\u00e8te, celle des Notes d&rsquo;analyse du 24 juin 2014, \u00e0 propos de la furieuse \u00ab\u00a0m\u00e9tamorphose des cloportes\u00a0\u00bb&#8230; Cette fois, il s&rsquo;agit d&rsquo;\u00e9v\u00e9nements, que nous connaissons et suivons d&rsquo;une&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3761,2664,4270,2665,15895,3106,2645,15896,857,855,15861,3809,3004,15858,2730,1296],"class_list":["post-75380","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-3761","tag-alastair","tag-autodestruction","tag-crooke","tag-escapade","tag-froide","tag-guerre","tag-incontrolee","tag-irak","tag-kerry","tag-kolomoiski","tag-nazi","tag-nucleaire","tag-oligarque","tag-russie","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75380"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75380\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}