{"id":75386,"date":"2014-07-03T13:50:01","date_gmt":"2014-07-03T13:50:01","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/07\/03\/des-brics-a-lalliance-anti-dollar\/"},"modified":"2014-07-03T13:50:01","modified_gmt":"2014-07-03T13:50:01","slug":"des-brics-a-lalliance-anti-dollar","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/07\/03\/des-brics-a-lalliance-anti-dollar\/","title":{"rendered":"Des BRICS \u00e0 l&rsquo;alliance anti-dollar"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Des BRICS \u00e0 l&rsquo;alliance anti-dollar<\/h3>\n<\/p>\n<p><p>\tUne fois boucl\u00e9e la Coupe du Monde, le Br\u00e9sil re\u00e7oit les BRICS, les 14-16 juillet, pour un sommet qui est pr\u00e9sent\u00e9 en g\u00e9n\u00e9ral comme tr\u00e8s important. La Russie, depuis l&rsquo;arriv\u00e9e \u00e0 maturit\u00e9 de la crise ukrainienne, en a fait (des BRICS comme de ce sommet) un de ses chevaux de bataille dans son offensive g\u00e9n\u00e9rale pour tenter de r\u00e9organiser les relations internationales en dehors du <em>diktat<\/em> permanent (depuis 1945) des USA. C&rsquo;est dire si l&rsquo;on parlera \u00e9videmment du dollar, et de son remplacement comme monnaie d&rsquo;\u00e9change et de r\u00e9serve. On a pu lire \u00e0 de nombreuses reprises, sur ce site, que la Russie s&rsquo;active tr\u00e8s pr\u00e9cis\u00e9ment sur ce th\u00e8me.<\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_folie-syst_me_marche_forc_e_28_06_2014.html\" class=\"gen\">28 juin 2014<\/a>, nous r\u00e9sumions cette perspective Russie-BRICS-d\u00e9-dollarisation, en la pla\u00e7ant dans un cadre absolument politique, et dans un cadre crisique qui conduit, sinon force \u00e0 des orientations et \u00e0 des d\u00e9cisions absolument politiques, avec de tr\u00e8s fortes cons\u00e9quences&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>En \u00e9change de l&rsquo;avis qu&rsquo;ils ont re\u00e7u de l&rsquo;UE concernant les accords d&rsquo;association, les Russes ont parl\u00e9 \u00e0 leurs interlocuteurs de la prochaine r\u00e9union des BRICS en juillet. Cette r\u00e9union appara\u00eet d&rsquo;une extr\u00eame importance, selon les Russes, et un travail intense est en cours \u00e0 cet \u00e9gard. Les BRICS travaillent sur deux accords fondamentaux, celui, d\u00e9j\u00e0 connu, d&rsquo;une banque d&rsquo;investissement, et celui, nouveau d&rsquo;un pool de monnaies de r\u00e9serve pour leurs \u00e9changes. Ce dernier point est une \u00e9tape fondamentale dans la concr\u00e9tisation de la dynamique de d\u00e9-dollarisation dont nous avons d\u00e9j\u00e0 beaucoup parl\u00e9&#8230;<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>La chose a \u00e9t\u00e9 pr\u00e9sent\u00e9e avec modestie aux d\u00e9l\u00e9gu\u00e9s de l&rsquo;UE,  lesquels ont l&rsquo;habitude de traiter avec le plus parfait m\u00e9pris les initiatives russes, et en g\u00e9n\u00e9ral non-bloc BAO, de cette sorte. Les Russes ont pr\u00e9sent\u00e9 ce projet comme \u00e9tant le produit d&rsquo;une situation qui les a forc\u00e9s \u00e0 y venir. Ce n&rsquo;est pas \u00e0 notre sens une pr\u00e9caution oratoire tactique mais bien une r\u00e9alit\u00e9 &#8230; Cette attitude correspond \u00e0 ce que nous \u00e9crivions le 21 juin 2014, avec pour la compr\u00e9hension du texte l&rsquo;extension du syst\u00e8me de l&rsquo;am\u00e9ricanisme \u00e0 l&rsquo;ensemble du bloc BAO :<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Nous \u00e9crivons pour conduire sinon<\/em><strong><em> forcer<\/em><\/strong><em>&#8230;&rsquo;, parce que nous pensons qu&rsquo;en l&rsquo;absence d&rsquo;une crise d&rsquo;une telle intensit\u00e9 que l&rsquo;ukrainienne, la Russie n&rsquo;aurait pas choisi la voie qu&rsquo;elle a choisie, de crainte de para\u00eetre trop dans une posture de confrontation avec ses partenaires&rsquo; du bloc BAO, des USA. Le syst\u00e8me de l&rsquo;am\u00e9ricanisme, dans son aveuglement habituel, ne mesurera jamais la position de s\u00fbret\u00e9 qu&rsquo;il a perdue en poussant la Russie \u00e0 la confrontation, notamment depuis la r\u00e9\u00e9lection de Poutine et, ouvertement, depuis le d\u00e9but de la crise ukrainienne. Le syst\u00e8me de l&rsquo;am\u00e9ricanisme n&rsquo;a jamais compris durant toutes ces ann\u00e9es, qu&rsquo;il avait, avec Poutine, un centriste ouvert \u00e0 une coop\u00e9ration \u00e9quilibr\u00e9e, dont l&rsquo;ambition n&rsquo;\u00e9tait nullement de d\u00e9fier le Syst\u00e8me, voire de chercher \u00e0 le frapper. Mais on ne peut attendre le moindre \u00e9clair de finesse dans le jugement d&rsquo;un syst\u00e8me, celui de l&rsquo;am\u00e9ricanisme, dont on peut dire sans crainte d&rsquo;\u00eatre d\u00e9menti que la seule chose qu&rsquo;il attend de la Russie, c&rsquo;est que la Russie n&rsquo;existe plus&rsquo; (phrase fameuse de Leonid Chebarchine, ancien chef des SR russes).<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes diff\u00e9rentes orientations sont confirm\u00e9es dans un texte de Valentin Mandrasescu, pour <em>The Voice of Russia<\/em>, ce <a href=\"http:\/\/voiceofrussia.com\/2014_07_03\/BRICS-is-morphing-into-an-anti-dollar-alliance-6229\/\" class=\"gen\">3 juillet 2014<\/a>, fait \u00e0 l&rsquo;occasion de d\u00e9clarations de la directrice de la banque centrale russe, Elvira Nabiullina, qui se rend \u00e0 P\u00e9kin la semaine prochaine pour travailler \u00e0 l&rsquo;\u00e9tablissement de l&rsquo;accord rouble-yuan r\u00e9glant la m\u00e9thodologie des transactions hors-dollar entre Russie et Chine. Nabiullina a rencontr\u00e9 Poutine et l&rsquo;on voit que la discussion s&rsquo;est \u00e9largie au sch\u00e9ma de constitution d&rsquo;une alliance anti-dollar,  on emploie d\u00e9sormais plus volontiers ce terme que celui de d\u00e9-dollarisation, et cela a un sens&#8230; Voici l&rsquo;essentiel du texte de Mandrasescu (soulign\u00e9 de gras dans le texte original) :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>&#8230; On June 10th, Sergey Glaziev, Putin&rsquo;s economy advisor published an article outlining the need to establish an international alliance of countries willing to get rid of the dollar in international trade and refrain from using dollars in their currency reserves. The ultimate goal would be to break the Washington&rsquo;s money printing machine that is feeding its military-industrial complex and giving the US ample possibilities to spread chaos across the globe, fueling the civil wars in Libya, Iraq, Syria and Ukraine. Glaziev&rsquo;s critics believe that such an alliance would be difficult to establish and that creating a non-dollar-based global financial system would be extremely challenging from a technical point of view. However, in her discussion with Vladimir Putin, the head of the Russian central bank unveiled an elegant technical solution for this problem and left a clear hint regarding the members of the anti-dollar alliance that is being created by the efforts of Moscow and Beijing:<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>We&rsquo;ve done a lot of work on the ruble-yuan swap deal in order to facilitate trade financing. I have a meeting next week in Beijing, she said casually and then dropped the bomb: <\/em><strong><em>We are discussing with China and our BRICS parters the establishment of a system of multilateral swaps that will allow to transfer resources to one or another country, if needed. A part of the currency reserves can be directed to<\/em><\/strong> [<strong><em>the new system<\/em><\/strong>]<em>. (source of the quote: Prime news agency)<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It seems that Kremlin chose the all-in-one approach for establishing its anti-dollar alliance. Currency swaps between the BRICS central banks will facilitate trade financing while completely bypassing the dollar. At the same time, the new system will also act as a de facto replacement of the IMF, because it will allow the members of the alliance to direct resources to finance the weaker countries. As an important bonus, derived from this quasi-IMF system, the BRICS will use a part (most likely the dollar part) of their currency reserves to support it, thus drastically reducing the amount of dollar-based instruments bought by some of the biggest foreign creditors of the US.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Skeptics will surely claim that a BRICS-based anti-dollar alliance will not manage to deprive the dollar of its global reserve currency status. Instead of arguing against this line of thought, it is easier to point out that Washington is doing its best to enlarge the ranks of the enemies of the dollar. Asked by the Russia 24 channel to comment on Nabiullina statements, Andrei Kostin, the president of the state-owned VTB bank and one of the staunchest supporters of anti-dollar policies, offered an interesting perspective on the situation in Europe:<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<MI><strong><em>I think the work on ruble-yuan swap line will finalized in the nearest future and the way for ruble-yuan settlement will be open. Moreover, we are not the only ones with such initiatives. We know about the statements made by Mr. Noyer, chairman of the Bank of France. As a retaliation for what Americans have done to BNP Paribas, he opined that the trade with China must be done in yuan or euro.<\/em><\/strong><em><\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>If the current trend continues, soon the dollar will be abandoned by most of the significant global economies and it will be kicked out of the global trade finance. Washington&rsquo;s bullying will make even former American allies chose the anti-dollar alliance instead of the existing dollar-based monetary system. The point of no return for the dollar may be much closer than it is generally thought. In fact, the greenback may have already past its point of no return on its way to irrelevance.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl est absolument essentiel d&rsquo;observer encore une fois,  dans ce cas, la r\u00e9p\u00e9tition est une vertu,  combien cette op\u00e9ration s&rsquo;effectue <strong>dans un cadre fondamentalement politique<\/strong>. Il y a bien s\u00fbr les observations de Glaziev, selon qui il s&rsquo;agit de casser la machine d\u00e9structurante de la <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\" class=\"gen\">politique-Syst\u00e8me<\/a> des USA (c&rsquo;est-\u00e0-dire, il faut bien le comprendre, une attaque contre le Syst\u00e8me). Mais il y a aussi les circonstances tr\u00e8s concr\u00e8tes et imm\u00e9diates, \u00e9voqu\u00e9es d&rsquo;une fa\u00e7on ouverte&#8230; Les Russes ne s&rsquo;avanceraient pas \u00e0 \u00e9voquer le cas fran\u00e7ais si les relations de la Russie avec la France n&rsquo;\u00e9taient pas en cours d&rsquo;am\u00e9lioration depuis la valse diplomatique de la comm\u00e9moration du <em>D-Day<\/em> (voir le <a href=\"http:\/\/www.dedefensa.org\/article-de_l_ukraine_la_normandie_et_vice-versa_07_06_2014.html\" class=\"gen\">7 juin 2014<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-l_nigme_fran_aise_interpr_t_e_par_les_autres_26_06_2014.html\" class=\"gen\">26 juin 2014<\/a>), cela dans un cadre de plus en plus structur\u00e9 d&rsquo;entente Russie-Allemagne-France pour faire \u00e9voluer diplomatiquement l&rsquo;aspect int\u00e9rieur de la crise ukrainienne (accord pour un nouveau cessez-le-feu hier \u00e0 Berlin, entre les trois pays et l&rsquo;Ukraine,  voir <em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/news\/170012-lavrov-ukraine-talks-peace\/\" class=\"gen\">2 juillet 2014<\/a>). L&rsquo;on doit \u00e9videmment remarquer que ce travail de r\u00e9solution de la crise interne ukrainienne se fait sans les USA, et avec, du c\u00f4t\u00e9 fran\u00e7ais, l&rsquo;ombre tr\u00e8s pesante de l&rsquo;amende impos\u00e9e par l&rsquo;administration Obama \u00e0 Paribas,  et cette amende d\u00e9crite par Poutine comme pur chantage li\u00e9 \u00e0 la vente \u00e0 la Russie des porte-h\u00e9licopt\u00e8res classe <em>Mistral<\/em>&#8230; (Discours de Poutine devant le corps diplomatique russe, le 1er juillet  : \u00ab<em>We know about the pressure that our American partners put on the French so that they would not deliver the Mistral ships to Russia. And we know that Washington hinted that if the French don&rsquo;t deliver Mistral, sanctions on the French bank will be minimized or removed. What is this, if not blackmail?<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tAinsi pr\u00eatons-nous une grande attention \u00e0 parler ici, tr\u00e8s pr\u00e9cis\u00e9ment, de la r\u00e9solution de la crise interne  ukrainienne, pour mieux mettre en \u00e9vidence que cette crise ukrainienne, dans sa dimension ext\u00e9rieure, internationale, sinon globale, se poursuit et ne cesse de grandir en importance. Si elle n&rsquo;avait pas eu lieu, nous n&rsquo;aurions pas cette op\u00e9ration d&rsquo;alliance anti-dollar (d\u00e9cid\u00e9ment, l&rsquo;expression convient mieux que celle de d\u00e9-dollarisation). Si l&rsquo;op\u00e9ration s&rsquo;\u00e9tend au BRICS, ce qui est en cours effectivement, si elle int\u00e9resse des pays europ\u00e9ens,  comme la France, cit\u00e9e ici, et probablement l&rsquo;Allemagne, qui y verrait en plus d&rsquo;un assez bon il une fa\u00e7on \u00e9galement \u00e9l\u00e9gante de riposter aux entreprises de la NSA,  alors il s&rsquo;agit bien d&rsquo;un alliance dont le contenu politique est \u00e9vident,  et explosif, d&rsquo;ailleurs. Comme disait fameusement L\u00e9nine, pas d&rsquo;omelette sans casser des ufs : une d\u00e9-dollarisation sera n\u00e9cessairement vue par les USA, quand ils s&rsquo;en apercevront, comme une alliance anti-dollar, c&rsquo;est-\u00e0-dire une alliance contre les USA&#8230; Et alors, puisque c&rsquo;est exactement le cas ? On appelle cela une v\u00e9rit\u00e9 de situation.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 3 juillet 2014 \u00e0 13H49<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des BRICS \u00e0 l&rsquo;alliance anti-dollar Une fois boucl\u00e9e la Coupe du Monde, le Br\u00e9sil re\u00e7oit les BRICS, les 14-16 juillet, pour un sommet qui est pr\u00e9sent\u00e9 en g\u00e9n\u00e9ral comme tr\u00e8s important. La Russie, depuis l&rsquo;arriv\u00e9e \u00e0 maturit\u00e9 de la crise ukrainienne, en a fait (des BRICS comme de ce sommet) un de ses chevaux de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2996,11035,3977,15804,2687,15880,8635,15904,916,5420,1296,4660],"class_list":["post-75386","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-alliance","tag-brics","tag-chine","tag-de-dollarisation","tag-france","tag-glaziev","tag-mistral","tag-nabiullina","tag-poutine","tag-rouble","tag-ukraine","tag-yuan"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75386"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75386\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}