{"id":75391,"date":"2014-07-06T14:44:25","date_gmt":"2014-07-06T14:44:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/07\/06\/le-saker-in-french\/"},"modified":"2014-07-06T14:44:25","modified_gmt":"2014-07-06T14:44:25","slug":"le-saker-in-french","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/07\/06\/le-saker-in-french\/","title":{"rendered":"Le Saker <em>in French<\/em>"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Le Saker <em>in French<\/em><\/h3>\n<\/p>\n<p><p>\tNous voulons et nous nous devons de signaler et de saluer \u00e0 la fois le lancement (\u00e0 la mi-juin) du site <em>The Vineyard of the Saker<\/em> en <a href=\"http:\/\/www.vineyardsaker.fr\/\" class=\"gen\">version fran\u00e7aise<\/a>, ou Point de vue d&rsquo;un oiseau sur le vignoble. D\u00e9sormais nous pourrons \u00e9crire Le Saker en plus d&rsquo;\u00e9crire <em>The Saker<\/em> (voir le <a href=\"http:\/\/www.dedefensa.org\/article-a_propos_de_saker_30_05_2014.html\" class=\"gen\">30 mai 2014<\/a>), comme nous nous limitions \u00e0 faire jusqu&rsquo;ici. Il s&rsquo;agit \u00e0 premi\u00e8re vue d&rsquo;une traduction en fran\u00e7ais des articles du <a href=\"http:\/\/vineyardsaker.blogspot.be\/\" class=\"gen\">site<\/a> <em>The Vineyard of The Saker<\/em>, meilleure source aujourd&rsquo;hui sur les \u00e9v\u00e9nements d&rsquo;Ukraine ; mais ce n&rsquo;est qu&rsquo;une premi\u00e8re vue qui s&rsquo;av\u00e8re toujours, \u00e0 l&rsquo;examen, une bien courte vue. Le Saker, c&rsquo;est donc <em>The Saker<\/em> en fran\u00e7ais, mais c&rsquo;est bien plus que cela.<\/p>\n<\/p>\n<p><p>\tQuelques observations g\u00e9n\u00e9rale : comme <em>The Saker<\/em>, Le Saker est ce qu&rsquo;on nomme un <em>blog<\/em>, \u00e0 la diff\u00e9rence d&rsquo;un site, mais selon une d\u00e9finition technique qui nous para\u00eet un peu courte, elle aussi. Pour nous, un site, comme un <em>blog<\/em> qui-n&rsquo;est-pas-vraiment-un-<em>blog<\/em>, est une v\u00e9ritable entit\u00e9 d&rsquo;information, de chronique et de commentaire ; il se d\u00e9finit par sa diversit\u00e9, une certaine rigueur du travail dans la s\u00e9lection au cur de cette diversit\u00e9, une volont\u00e9 de monter un v\u00e9ritable instrument d&rsquo;information et de le structurer en artefact de communication. Il se diff\u00e9rencie du <em>blog<\/em> comme on entend la chose par sa structure, son extension, une volont\u00e9 objective de r\u00e9pondre aux \u00e9v\u00e9nements du monde pour les d\u00e9crire et tenter de les expliquer, et ainsi de ne pas s&rsquo;en tenir \u00e0 la seule humeur de celui qui le fait,  m\u00eame si cette d\u00e9finition n&rsquo;exclut pas l&rsquo;humeur, et m\u00eame si les \u00e9crits d&rsquo;humeur ont toute leur valeur et leur noblesse. Pour cela et selon ce point de vue qui est le n\u00f4tre, m\u00eame s&rsquo;il a la forme d&rsquo;un <em>blog<\/em> Le Saker est un site.<\/p>\n<\/p>\n<p><p>\tLe Saker pr\u00e9sente aussi la particularit\u00e9, bienvenue, de d\u00e9passer largement sa source originale. Certes, il donne de tr\u00e8s nombreuses traductions du <em>Saker<\/em> original, mais il y ajoute des traductions r\u00e9guli\u00e8res d&rsquo;au moins deux autres sources tr\u00e8s int\u00e9ressantes : les chroniques dites de L&rsquo;il itin\u00e9rant de P\u00e9p\u00e9 Escobar, sur <em>ATimes.com<\/em>, et certains articles de <em>ZeroHedge.com<\/em>, de Tyler Durden. Il y ajoute des traductions ponctuelles d&rsquo;articles, notamment en provenance de Russie (par exemple l&rsquo;article de Valentin Mandrasescu, pour <em>La Voix de la Russie<\/em> du <a href=\"http:\/\/voiceofrussia.com\/2014_07_03\/BRICS-is-morphing-into-an-anti-dollar-alliance-6229\/\" class=\"gen\">3 juillet 2014<\/a>, que nous avions cit\u00e9 le m\u00eame <a href=\"http:\/\/www.dedefensa.org\/article-des_brics_l_alliance_anti-dollar_03_07_2014.html\" class=\"gen\">3 juillet 2014<\/a>, qui para\u00eet sur Le Saker-fran\u00e7ais le <a href=\"http:\/\/www.vineyardsaker.fr\/2014\/07\/04\/les-pays-brics-vers-une-alliance-anti-dollar\/\" class=\"gen\">4 juillet 2014<\/a>). Enfin, il y a des articles ou des reprises d&rsquo;articles d&rsquo;autres sources, notamment fran\u00e7aises (voir un article de Jean-Paul Baquiast, du <a href=\"http:\/\/www.vineyardsaker.fr\/2014\/06\/24\/ttip-negociations-bruxelles-washington\/\" class=\"gen\">24 juin 2014<\/a>).  <\/p>\n<\/p>\n<p><p>\tLe Saker est une initiative d&rsquo;une \u00e9quipe qui semble productrice d&rsquo;une tr\u00e8s grande activit\u00e9, avec d\u00e9j\u00e0 de tr\u00e8s nombreux articles, en g\u00e9n\u00e9ral d&rsquo;excellentes traductions. Tout cela invite le lectorat fran\u00e7ais, toujours caract\u00e9ris\u00e9 par son individualisme de caract\u00e8re (si diff\u00e9rent jusqu&rsquo;\u00e0 en \u00eatre l&rsquo;oppos\u00e9 de l&rsquo;individualisme \u00e9conomique de la robotisation hyperlib\u00e9rale) \u00e0 r\u00e9aliser combien l&rsquo;internet est un formidable instrument <strong>transnational de r\u00e9sistance<\/strong>, un outil de <strong>subversion du d\u00e9sordre subversif<\/strong> qui nous est impos\u00e9 (fameuse tactique du contre-feu), c&rsquo;est-\u00e0-dire une force qui utilise en les unissant les individualismes de caract\u00e8re pour attaquer frontalement l&rsquo;individualisme \u00e9conomique robotis\u00e9 ; avec cela, une mise en page simple et claire, un appareil de communication important (notamment des vid\u00e9os d&rsquo;illustration), etc.<\/p>\n<\/p>\n<p><p>\tLa ma\u00eetresse d&rsquo;uvre de l&rsquo;entreprise est l&rsquo;astronome Claude Roddier, \u00e9pouse de l&rsquo;astronome Fran\u00e7ois Roddier, dont nous avons cit\u00e9 et utilis\u00e9 le livre <em>Thermodynamique de l&rsquo;\u00e9volution<\/em>, notamment dans un <em>Faits &#038; Commentaires<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-l_entropisation_de_l_crevisse_11_10_2012.html\" class=\"gen\">11 octobre 2012<\/a>, \u00ab<em>L&rsquo;entropisation de l&rsquo;\u00e9crevisse<\/em>\u00bb. Nous citons ci-dessous un passage substantiel de pr\u00e9sentation du site (<em>blog<\/em>) Le Saker,  dont nous trouverons certainement une d\u00e9nomination-maison dans nos futures r\u00e9f\u00e9rences \u00e0 lui,  par exemple Le Saker-fran\u00e7ais d\u00e9j\u00e0 venu sous la plume un peu plus haut, peut-\u00eatre en attendant mieux&#8230; Il s&rsquo;agit donc d&rsquo;un texte de Claude Roddier, du <a href=\"http:\/\/www.vineyardsaker.fr\/2014\/06\/22\/des-nouvelles-de-notre-blog\/\" class=\"gen\">22 juin 2014<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Je souhaiterais maintenant faire une petite analyse. Ce qui me frappe est l&rsquo;efficacit\u00e9 de la coop\u00e9ration lorsqu&rsquo;elle survient spontan\u00e9ment dans un monde domin\u00e9 par la comp\u00e9tition. Le Saker a employ\u00e9 le mot de spontaneous self-organization un mot dont j&rsquo;entends r\u00e9guli\u00e8rement parler par mon mari, Fran\u00e7ois Roddier, dans son blog et dans son livre Thermodynamique de l&rsquo;\u00e9volution. Nous sommes tous deux des astronomes \u00e0 la retraite et je ressentais ces belles th\u00e9ories de structures dissipatives et de thermodynamique appliqu\u00e9e aux soci\u00e9t\u00e9s humaines comme la suite des th\u00e9ories que nous connaissions et appliquions dans notre travail, mais je n&rsquo;arrivais pas \u00e0 penser qu&rsquo;elles \u00e9taient toutes pr\u00eates \u00e0 s&rsquo;appliquer \u00e0 notre vie de tous les jours. En fait notre environnement est tel qu&rsquo;elles s&rsquo;appliquent parfaitement. Nous sommes en train de vivre une transition semblable \u00e0 celle des petits mammif\u00e8res du temps des dinosaures. Pour \u00e9chapper aux dinosaures, qui leur rendaient la vie difficile, ils sortaient la nuit. Lorsque les dinosaures se sont \u00e9teints, ils se sont multipli\u00e9s, puis ont \u00e9volu\u00e9 pour donner naissance \u00e0 notre propre esp\u00e8ce.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Les journalistes de la presse officielle, dinosaures modernes de la communication, ne cessent de se montrer dans le plus grand nombre d&rsquo;endroits possibles. Les membres de notre \u00e9quipe, et le Saker par la m\u00eame occasion, refusent de donner leur identit\u00e9. Je crois que je connais une seule v\u00e9ritable identit\u00e9 parmi les personnes avec qui j&rsquo;ai \u00e9chang\u00e9 plusieurs messages chaque jour depuis une semaine. Les nouveaux sites sont de plus en plus  anonymes. Ceux que je connais depuis longtemps sont li\u00e9s \u00e0 des personnes ayant rendu publique leur identit\u00e9, Olivier Berruyer, Paul Jorion, Philippe Grasset par exemple, alors que Bertrand Gaideclin et combien d&rsquo;autres pr\u00e9f\u00e8rent rester en retrait. Est ce que la guerre ti\u00e8de commence \u00e0 se faire sentir chez nous et que, sans m\u00eame en \u00eatre tout \u00e0 fait conscients, nous adoptons des comportements qui sont ceux de r\u00e9sistants de pays o\u00f9 la guerre ne fait plus semblant d&rsquo;\u00eatre ti\u00e8de ?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Avant l&rsquo;effondrement la comp\u00e9tition est ma\u00eetresse mais quand l&rsquo;effondrement approche la coop\u00e9ration se met en place. C&rsquo;est bien ce que nous constatons entre nous. C&rsquo;est la coop\u00e9ration des membres de notre petite \u00e9quipe, mais aussi de tous ceux et celles qui donnent beaucoup de leur temps \u00e0 maintenir sites et blogs, celle de leurs lecteurs et commentateurs.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Nous sommes les premi\u00e8res pousses de l&rsquo;humanit\u00e9 de demain.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNotre commentaire \u00e0 nous s&rsquo;exprime dans le constat fondamental du regroupement dans notre \u00e9poque de crise d&rsquo;effondrement du Syst\u00e8me : qu&rsquo;il importe que s&rsquo;effectuent des regroupements de type antiSyst\u00e8me, que ces regroupements se font effectivement, qu&rsquo;ils se font naturellement, librement, par la simple attraction d&rsquo;une r\u00e9sistance commune. Ce constat fondamental se poursuit par l&rsquo;observation, illustr\u00e9e par le sujet de ce texte, que ces regroupements se font de plus en plus rapidement et efficacement \u00e0 mesure que l&rsquo;\u00e9quation surpuissance-effondrement du Syst\u00e8me produit un formidable d\u00e9sordre plan\u00e9taire dont l&rsquo;expansion est exponentielle, intenable \u00e0 terme de plus en plus court, suscitant des r\u00e9sistances de plus en plus fermes. Ces regroupements \u00e9videmment antiSyst\u00e8me se font effectivement de mani\u00e8re naturelle, parce que des forces puissantes sont d\u00e9sormais en action dans ce sens, avec l&rsquo;enjeu de la destruction du Syst\u00e8me, et de la contre-civilisation dont le Syst\u00e8me est l&rsquo;instrument op\u00e9rationnel.<\/p>\n<\/p>\n<p><p>\tLe Saker-fran\u00e7ais est une excellente entreprise de diffusion de l&rsquo;information pour un public fran\u00e7ais extraordinairement frustr\u00e9 \u00e0 cet \u00e9gard, notamment pour ce qui concerne la crise ukrainienne elle-m\u00eame, mais aussi pour la crise ukrainienne dans ses dimensions exceptionnelles qui d\u00e9passent tr\u00e8s largement le cadre de l&rsquo;Ukraine. (Voir notre texte du <a href=\"http:\/\/www.dedefensa.org\/article-la_crise_haute_ultime__24_03_2014.html\" class=\"gen\">24 mars 2014<\/a>.) D&rsquo;autres sujets sont \u00e9galement abord\u00e9, ce qui est l&rsquo;\u00e9vidence m\u00eame tant est n\u00e9cessaire la globalisation de la r\u00e9sistance contre la globalisation de l&rsquo;attaque d\u00e9structurante du Syst\u00e8me. D&rsquo;une fa\u00e7on sp\u00e9cifique, Le Saker-fran\u00e7ais ouvre une perspective capitale, pour le public fran\u00e7ais, sur la r\u00e9alit\u00e9 de la Russie actuelle, sur son r\u00f4le naturel, op\u00e9rationnel et surtout spirituel dans la lutte antiSyst\u00e8me.<\/p>\n<\/p>\n<p><p>\tQue nous le voulions ou non, que nous la sachions clairement ou pas, nous sommes dans la m\u00eame gal\u00e8re, heureusement de mieux en mieux gr\u00e9\u00e9e. Nous gardons nos propres sp\u00e9cificit\u00e9s mais nous affrontons la m\u00eame temp\u00eate. Le vent souffle comme jamais ; diable, nous ne sommes plus tr\u00e8s loin du <a href=\"http:\/\/fr.wikipedia.org\/wiki\/\u00c9chelle_de_Beaufort\" class=\"gen\">Force 12<\/a>. On se met \u00e0 la cape, certes ; c&rsquo;est non seulement pour tenir, c&rsquo;est aussi pour r\u00e9sister et pour contre-attaquer.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 5 juillet 2014 \u00e0 14H45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Saker in French Nous voulons et nous nous devons de signaler et de saluer \u00e0 la fois le lancement (\u00e0 la mi-juin) du site The Vineyard of the Saker en version fran\u00e7aise, ou Point de vue d&rsquo;un oiseau sur le vignoble. D\u00e9sormais nous pourrons \u00e9crire Le Saker en plus d&rsquo;\u00e9crire The Saker (voir le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3396,12608,12664,15911,1296],"class_list":["post-75391","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-dollar","tag-roddier","tag-saker","tag-saker-francais","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75391"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75391\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}