{"id":75404,"date":"2014-07-15T11:45:13","date_gmt":"2014-07-15T11:45:13","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/07\/15\/saison-nouvelle\/"},"modified":"2014-07-15T11:45:13","modified_gmt":"2014-07-15T11:45:13","slug":"saison-nouvelle","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/07\/15\/saison-nouvelle\/","title":{"rendered":"Saison nouvelle"},"content":{"rendered":"<p><h2 class=\"common-article2\">Saison nouvelle<\/h2>\n<\/p>\n<p><p>\tEn deux ans, ils n&rsquo;ont pas eu le temps de s&rsquo;assoupir.<\/p>\n<\/p>\n<p><p>\t\u00c0 peine reposaient-ils leurs mains meurtries par la chaux et les gravats d\u00e9gag\u00e9s. Le ciment ne venait plus. Tout un apprentissage s&rsquo;\u00e9laborait pour recycler \u00e9boulis et d\u00e9bris de maison tr\u00e8s abondants.<\/p>\n<\/p>\n<p><p>\tIls songent peut-\u00eatre d\u00e9j\u00e0 \u00e0 adapter leur habitat aux nouvelles saisons d\u00e9cid\u00e9es par l&rsquo;occupant.<\/p>\n<\/p>\n<p><p>\tEn plus du long hiver dense du silence de leurs voisins arabes, de faux printemps allum\u00e9s par des vraies torches vivantes, le rituel de punition collective&rsquo; biennal s&rsquo;installe.<\/p>\n<\/p>\n<p><p>\tLe syst\u00e8me a r\u00e9alis\u00e9 la fermeture d&rsquo;une bande de 360 Km2 tr\u00e8s dens\u00e9ment peupl\u00e9e au sein d&rsquo;un ouvert o\u00f9 il abolit les fronti\u00e8res.<\/p>\n<\/p>\n<p><p>\tCe petit espace est uniform\u00e9ment et contin\u00fbment cl\u00f4tur\u00e9 par des bornes multiples affectant l&rsquo;air, la mer, la terre et le souterrain. Il est l&rsquo;un des champs favoris d&rsquo;exp\u00e9rimentation o\u00f9 l&rsquo;avis \u00e9clair\u00e9 des cobayes n&rsquo;est pas requis.<\/p>\n<\/p>\n<p><p>\tLe phosphore blanc sur fond de nuit gazaouie velout\u00e9e dessine des volutes qui \u00e0 leur retomb\u00e9e calcine les chairs en profondeur. Les <a href=\"http:\/\/www.brecorder.com\/top-news\/1-front-top-news\/183743-israel-uses-dime-explosives-in-gaza-official.html\" class=\"gen\">DIME<\/a> (Dense Inert Metal Explosive) y inscrivent des chemins en vrille. Les bombes sonores terrifient et assourdissent sans discriminer le peu de faune qui a r\u00e9sist\u00e9 \u00e0 la salinisation de la terre.<\/p>\n<\/p>\n<p><p>\tCe ne sont que des prisonniers. Le monde civilis\u00e9 approuve que leurs ge\u00f4liers sanctionnent pr\u00e9ventivement leur insoumission.<\/p>\n<\/p>\n<p><p>\tMais au-del\u00e0 de l&rsquo;aspect trivial qui consiste \u00e0 produire des tests in vivo avant la commercialisation de machines et de ferblanteries, le proc\u00e9d\u00e9 \u00e9prouve la r\u00e9activit\u00e9 du voisinage.<\/p>\n<\/p>\n<p><p>\tLe plus proche d&rsquo;abord.<\/p>\n<\/p>\n<p><p>\tL&rsquo;av\u00e8nement du nouveau pharaon arriv\u00e9 au pouvoir au terme d&rsquo;une contre-r\u00e9volution revancharde sur le peuple \u00e9gyptien  co\u00efncide avec un alignement sur la position de Tel Aviv.<\/p>\n<\/p>\n<p><p>\tLe mouvement Hamas nagu\u00e8re favoris\u00e9 pour affaiblir la r\u00e9sistance la\u00efque \u00e0 l&rsquo;occupation est \u00e0 \u00e9liminer.<\/p>\n<\/p>\n<p><p>\tLa fermeture totale des tunnels de ravitaillement du camp de Gaza aggrave dramatiquement le blocus subi depuis 7 ans.<\/p>\n<\/p>\n<p><p>\tLe Caire a renonc\u00e9 \u00e0 \u00eatre la puissance r\u00e9gionale faisant office d&rsquo;interm\u00e9diaire entre l&rsquo;occupant et le peuple palestinien assi\u00e9g\u00e9 dans son archipel en Cisjordanie comme \u00e0 Gaza.<\/p>\n<\/p>\n<p><p>\tLa visite fin juin \u00e0 Alger du Ra\u00efs a \u00e9t\u00e9 presque tenue secr\u00e8te. Un \u00e9lu par forfait forc\u00e9 est all\u00e9 rendre compte \u00e0 une vague ombre sortie de ses convalescences des Invalides de Paris de la limitation de ses degr\u00e9s de libert\u00e9 en politique \u00e9trang\u00e8re sous \u00e9troite d\u00e9pendance du num\u00e9raire p\u00e9tro-monarchique saoudien. Le Chef de l&rsquo;\u00c9tat le plus vaste d&rsquo;Afrique ne fait plus d&rsquo;apparition publique et a remis la s\u00e9curit\u00e9 de ses fronti\u00e8res Sud aux entreprises p\u00e9troli\u00e8res particuli\u00e8rement \u00e9tasunienne et britannique. L&rsquo;or noir doit continuer de couler sous protection de milices priv\u00e9es ou non, \u00e9trang\u00e8res.<\/p>\n<\/p>\n<p><p>\tLes manifestations populaires de soutien \u00e0 la Palestine ont \u00e9t\u00e9 interdites en Alg\u00e9rie.<\/p>\n<\/p>\n<p><p>\tLes attitudes n\u00e9o-ottomanes d&rsquo;Erdogan vis-\u00e0-vis des anciens sandjaks prises depuis les mouvements de protestations des peuples arabes ont \u00e9t\u00e9 troqu\u00e9es pour du r\u00e9alisme&rsquo; otanesque.<\/p>\n<\/p>\n<p><p>\tLes armes et les hommes en charge de d\u00e9truire la Syrie passent par les fronti\u00e8res turques et la partition de l&rsquo;Irak avec le d\u00e9tachement d&rsquo;un petit \u00e9tat kurde promu et promis depuis longtemps par les sionistes ne g\u00eane pas Ankara.<\/p>\n<\/p>\n<p><p>\tUn cercle plus loin, la vassalisation de l&rsquo;Europe est telle que l&rsquo;encouragement du personnage qui sert de Pr\u00e9sident de la R\u00e9publique fran\u00e7aise \u00e0 Netanyahu \u00e0 poursuivre ses frappes ne semble plus obsc\u00e8ne mais pitoyable de veulerie et digne de lui.<\/p>\n<\/p>\n<p><p>\tLa tuerie organis\u00e9e des Palestiniens, une attaque a\u00e9rienne toutes les 4 mn 30 depuis plusieurs jours, est aussi une  vulgaire op\u00e9ration de politique int\u00e9rieure pr\u00e9m\u00e9dit\u00e9e pour affermir la clique au pouvoir qui voit la coalition droite extr\u00eame et droite la plus extr\u00eame se d\u00e9liter en faveur de cette derni\u00e8re. L&rsquo;entit\u00e9 sioniste figure le prototype de l&rsquo;\u00c9tat mafieux o\u00f9 tr\u00e8s rares sont les ministres qui ne sont pas \u00e9clabouss\u00e9s par des scandales de pr\u00e9varications, de trafic d&rsquo;influence et d&rsquo;abus de biens sociaux.<\/p>\n<\/p>\n<p><p>\tElle met surtout \u00e0 l&rsquo;\u00e9preuve la part de l&rsquo;humain non pervertie en chacun par la propagande dominante, encore accessible \u00e0 un r\u00e9cit que ne truffe aucun mythe vermoulu.<\/p>\n<\/p>\n<p><p>\tUn peuple a \u00e9t\u00e9 d\u00e9poss\u00e9d\u00e9, en grande partie chass\u00e9 de sa terre, d\u00e9plac\u00e9 puis pour ce qu&rsquo;il en reste, confin\u00e9 dans des minuscules territoires sans lien g\u00e9ographique entre eux sous contr\u00f4le constant d&rsquo;une arm\u00e9e tr\u00e8s puissamment dot\u00e9e d&rsquo;armes et des outils de communication les plus performants.<\/p>\n<\/p>\n<p><p>\tIl r\u00e9siste.<\/p>\n<\/p>\n<p><p>\tL&rsquo;aum\u00f4ne m\u00eame abondante fournie par le Qatar aux gardiens de la prison de Gaza n&rsquo;a pas rompu les liens avec l&rsquo;axe du refus Hezbollah-Syrie-Iran.<\/p>\n<\/p>\n<p><p>\tLes roquettes longue port\u00e9e parviennent jusqu&rsquo;\u00e0 Tel Aviv et J\u00e9rusalem, elles sont de fabrication iranienne. M\u00eame impr\u00e9cises, le fameux D\u00f4me qui re\u00e7oit des dotations tr\u00e8s importantes du Tr\u00e9sor \u00e9tasunien, cens\u00e9 t\u00e9moigner de l&rsquo;efficacit\u00e9 technologique sans faille de l&rsquo;artefact sioniste, n&rsquo;en arr\u00eate qu&rsquo;une sur sept.<\/p>\n<\/p>\n<p><p>\t.<\/p>\n<\/p>\n<p><p>\tCe peuple, comme tout autre, a le droit le plus incontestable de se d\u00e9fendre contre la d\u00e9possession, contre l&rsquo;oppression militaire et contre le grignotage continu de sa terre (la colonisation a progress\u00e9 de 130% sous Obama versus Bush).<\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/www.lemondejuif.info\/etats-unis-boycott-israel-netanyahu-jette-lanatheme-leglise-presbyterienne\/\" class=\"gen\">vote r\u00e9cent<\/a> de l&rsquo;\u00c9glise presbyt\u00e9rienne \u00e9tasunienne, forte de plus de deux millions d&rsquo;adh\u00e9rents, en faveur du Boycott, d\u00e9sinvestissement et sanctions contre Isra\u00ebl, est une des r\u00e9ponses morales ad\u00e9quates face au d\u00e9cha\u00eenement impuni de la force.<\/p>\n<\/p>\n<p><p>\tEn poursuivant ses assassinats, la \u00ab seule d\u00e9mocratie au MO \u00bb est en train de progresser dans le classement des pays <a href=\"http:\/\/jssnews.com\/2013\/05\/24\/israel-lun-des-5-pays-les-plus-detestes-au-monde-selon-la-bbc\/\" class=\"gen\">les plus ha\u00efs<\/a> au monde.<\/p>\n<\/p>\n<p><p>\tDans deux ans, de nouvelles \u00e9lections au Us(a), d&rsquo;autres Jeux Olympiques, autant d&rsquo;occasions pour d\u00e9tourner l&rsquo;attention et pr\u00e9parer la prochaine saison, pluie de bombes et fauchage de nouvelles vies.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Badia Benjelloun<\/p>\n<\/p>\n<p><\/p>\n<h4>Avertissement<\/h4>\n<p>Cet avertissement figure d\u00e9sormais en queue de chaque article d&rsquo;<em>Ouverture libre<\/em>. Il est l\u00e0 pour rappeler un passage du statut des articles publi\u00e9s, figurant en t\u00eate des archives de cette <a href=\"http:\/\/www.dedefensa.org\/section-ouverture_libre.html\" class=\"gen\">rubrique<\/a>. Cet avertissement ne vise aucun article en particulier mais les concerne tous, rappelant simplement une condition de principe&#8230; \u00ab<em>Les articles et contributions sont sign\u00e9s du nom des auteurs et engagent<\/em> <strong><em>leur seule responsabilit\u00e9<\/em><\/strong>, <em>sans aucune n\u00e9cessit\u00e9 de conformit\u00e9 avec l&rsquo;orientation de dedefensa.org, et sans que dedefensa.org ne prenne en rien \u00e0 son compte leur orientation.<\/em>\u00bb On rappelle \u00e9galement les articles de pr\u00e9sentation de cette rubrique <em>Ouverture libre<\/em>, le <a href=\"http:\/\/www.dedefensa.org\/article-le_nouvel_an_de_dedefensaorg_ouverture_libre_03_01_2010.html?admin=1\" class=\"gen\">3 janvier 2010<\/a>, le <a href=\"http:\/\/www.dedefensa.org\/article-dedefensaorg_et_le_premier_jour_d_ouverture_libre_10_01_2010.html\" class=\"gen\">10 janvier 2010<\/a>, et surtout le <a href=\"http:\/\/www.dedefensa.org\/article-precisions_sur_ouverture_libre_28_09_2011.html\" class=\"gen\">28 septembre 2011<\/a>, qui constitue une mise \u00e0 jour d\u00e9taill\u00e9e des conditions d&rsquo;acc\u00e8s, de collaboration, etc., \u00e0 <em>Ouverture libre<\/em>.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saison nouvelle En deux ans, ils n&rsquo;ont pas eu le temps de s&rsquo;assoupir. \u00c0 peine reposaient-ils leurs mains meurtries par la chaux et les gravats d\u00e9gag\u00e9s. Le ciment ne venait plus. Tout un apprentissage s&rsquo;\u00e9laborait pour recycler \u00e9boulis et d\u00e9bris de maison tr\u00e8s abondants. Ils songent peut-\u00eatre d\u00e9j\u00e0 \u00e0 adapter leur habitat aux nouvelles saisons&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[7353,2774,3291],"class_list":["post-75404","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-boycott","tag-israel","tag-palestinien"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75404"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75404\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}