{"id":75430,"date":"2014-07-29T18:19:08","date_gmt":"2014-07-29T18:19:08","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/07\/29\/quimporte-puisquune-guerre-se-prepare-en-europe\/"},"modified":"2014-07-29T18:19:08","modified_gmt":"2014-07-29T18:19:08","slug":"quimporte-puisquune-guerre-se-prepare-en-europe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/07\/29\/quimporte-puisquune-guerre-se-prepare-en-europe\/","title":{"rendered":"\u201cQu&rsquo;importe&#8230; Puisqu&rsquo;une guerre se pr\u00e9pare en Europe\u201d"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Qu&rsquo;importe&#8230; Puisqu&rsquo;une guerre se pr\u00e9pare en Europe<\/h3>\n<\/p>\n<p><p>\t<em>ZeroHedge.com<\/em> signalait \u00e0 notre attention, le <a href=\"http:\/\/www.zerohedge.com\/news\/2014-07-28\/shocking-reason-putin-isnt-worried-about-50-billion-yukos-ruling\" class=\"gen\">29 juillet 2014<\/a>, la raison pour laquelle Poutine serait totalement indiff\u00e9rent au jugement condamnant la Russie \u00e0 une amende d&rsquo;autour de $50 milliards dans l&rsquo;affaire Yukos (voir ce <a href=\"http:\/\/www.dedefensa.org\/article-le_verdict_yukos_ou_l_inversion_de_la_loi_l_esprit_de_tafta__29_07_2014.html\" class=\"gen\">29 juillet 2014<\/a>). Il s&rsquo;agit d&rsquo;un commentaire recueilli par le <em>Financial Times<\/em> du <a href=\"http:\/\/www.ft.com\/cms\/s\/0\/b01cfb72-1669-11e4-8210-00144feabdc0.html#ixzz38qriQU00\" class=\"gen\">28 juillet 2014<\/a>, en fin d&rsquo;un article qui distille, la plume ourl\u00e9e d&rsquo;un m\u00e9pris typiquement <em>british<\/em>, son gallon de poison anglosaxon garanti tueur-de-Poutine ; justement, il s&rsquo;agit d&rsquo;un commentaire d&rsquo;un proche de Poutine qui dit qu&rsquo;au Kremlin, on se fout royalement du jugement de La Haye, et ainsi faisant tout aussi royalement le rapprochement que nous recommandons entre cet \u00e9v\u00e9nement et la crise ukrainienne&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>One person close to Mr Putin said the Yukos ruling was insignificant in light of the bigger geopolitical stand-off over Ukraine. There is a war coming in Europe, he said. Do you really think this matters?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDiantre, la guerre ? Il semble que la loi 2277 du S\u00e9nat des Etats-Unis (loi S.2277) en soit, disons d&rsquo;un point de vue l\u00e9gal, sinon le plus court du moins le plus s\u00fbr chemin pour y parvenir. C&rsquo;est Patrick Buchanan, l&rsquo;\u00e9trange r\u00e9publicain de type pal\u00e9o-conservateur qui ne cache pas son <a href=\"http:\/\/www.dedefensa.org\/article-question_de_fond_is_putin_one_of_us__18_12_2013.html\" class=\"gen\">admiration<\/a> pour Poutine, qui la d\u00e9cortique en la pr\u00e9sentant pour ce qu&rsquo;elle est,  une loi concoct\u00e9e par les r\u00e9publicains du S\u00e9nat, par le s\u00e9nateur Bob Corker qui dirige les r\u00e9publicains \u00e0 la commission des relations ext\u00e9rieures, pour menacer directement la Russie : \u00ab<em>A GOP Ultimatum to Vlad<\/em>\u00bb, tel est le titre de l&rsquo;article du <a href=\"http:\/\/original.antiwar.com\/buchanan\/2014\/07\/28\/a-gop-ultimatum-to-vlad\/\" class=\"gen\">29 juillet 2014<\/a> de Patrick Buchanan. C&rsquo;est en effet Crocker qui a concoct\u00e9 2277, laquelle a d\u00e9j\u00e0 le soutien de la moiti\u00e9 des s\u00e9nateurs r\u00e9publicains, et qui, de toutes les fa\u00e7ons, passera si les r\u00e9publicains l&#8217;emportent en novembre prochain et retrouvent la majorit\u00e9 au S\u00e9nat. Voici la description de 2277 par Buchanan&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Corker&rsquo;s bill would declare Moldova, Georgia, and Ukraine major non-NATO allies of the United States, move NATO forces into Poland, Lithuania, Latvia and Estonia, accelerate the building of an ABM system in Eastern Europe, and authorize U.S. intelligence and military aid for Ukraine&rsquo;s army in the Donbass war with Russian-backed separatists. U.S. aid would include antitank and antiaircraft weapons.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>S. 2277 would direct the secretary of state to intensify efforts to strengthen democratic institutions inside the Russian Federation, e.g., subvert Vladimir Putin&rsquo;s government, looking toward regime change. If Putin has not vacated Crimea and terminated support for Ukraine&rsquo;s separatist rebels within seven days of passage of the Corker Ultimatum, sweeping sanctions would be imposed on Russian officials, banks and energy companies, including Gazprom. Economic relations between us would be virtually severed.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In short, this is an ultimatum to Russia that she faces a new Cold War if she does not get out of Ukraine and Crimea, and it is a U.S. declaration that we will now regard three more former Soviet republics  Moldova, Ukraine and Georgia  as allies&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tUn petit pays c\u00e9derait, observe Buchanan, mais pas la Russie, o\u00f9 l&rsquo;on est de plus en plus antiam\u00e9ricaniste, o\u00f9 Poutine est soutenu \u00e0 plus de 80% par sa population (\u00ab<em>The Russian people, today backing Putin by 80 percent, seem happier with their government than we Americans do with ours<\/em>\u00bb),  o\u00f9, ajouterait-on, r\u00e8gne un patriotisme ardent (\u00ab<em>un chauvinisme mystique<\/em>\u00bb, dit Zbigniew Brzezinski, d&rsquo;une voix s\u00e9pulcrale et roulant des yeux terribles). (D&rsquo;ailleurs, la Russie n&rsquo;a jamais dout\u00e9 du risque que la situation pr\u00e9sente entretient. Medvedev lui-m\u00eame, qui n&rsquo;est certainement pas un fauteur de guerre, avertissait ses amis du G8, lorsque la Russie s&rsquo;y trouvait encore, des risques de guerre nucl\u00e9aire r\u00e9gionale [voir le <a href=\"http:\/\/www.dedefensa.org\/article-avertissement_nucl_aire_de_la_russie_au_g8_18_05_2012.html\" class=\"gen\">18 mai 2012<\/a>]. Tout cela vient de loin.)<\/p>\n<\/p>\n<p><p>\tBref, poursuit Buchanan, non seulement les Russes ne c\u00e9deront pas mais ils se seraient d\u00e9j\u00e0 accoutum\u00e9s \u00e0 l&rsquo;id\u00e9e de la chose, semble-t-il (si l&rsquo;on en croit la source du <em>Financial Times<\/em>), et se tiendraient pr\u00eats \u00e0 riposter \u00e0 la loi 2277 du S\u00e9nat. \u00ab<em>And how Russia would respond is not difficult to predict.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Our demand that she get out of Crimea and leave her two-century-old naval base at Sevastopol in the custody of President Petro Poroshenko in Kiev and his U.S. allies, would be laughed off.<\/em> [&#8230;] <em>To make good on our latest red line, we would have to start shipping weapons to Kiev, in which case Russia, with superior forces closer, would likely move preemptively into East Ukraine. What would our NATO allies do then?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The U.S. directive to the State Department to work with NGOs in Russia, blatant intervention in the internal affairs of a sovereign nation, would be answered with a general expulsion of these agencies from Moscow. We would not sit still for this kind of open subversion in the United States. What makes us think they would? And where do we come off telling the Russians what kind of government they may have?&#8230;<\/em> [&#8230;] <\/p>\n<\/p>\n<p><p>\t\u00bb<em>But it may be this idea of installing a ballistic missile defense, an ABM system, in Poland and the Czech Republic, that is most dangerous of all. Putin has already signaled that this would cross his red line, that if we start implanting antimissile missiles in Eastern Europe, he will reply by installing offensive missiles. The Reagan-Gorbachev INF treaty to eliminate all intermediate-range nuclear missiles from Europe  the USSR&rsquo;s triple-warhead SS-20s, and our Pershing II and cruise missiles  could wind up in the dumpster. We could have a mini-Cuban missile crisis in Eastern Europe. And how would our German allies react to Russian missiles rising in Kaliningrad, the former Prussian capital of Konigsberg, wedged between Lithuania and Poland?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDans sa phrase de conclusion, Buchanan constate bien plus qu&rsquo;il ne menace que si un tel programme qu&rsquo;implique la loi 2277 (dite <em>Russian Aggression Prevention Act of 2014<\/em>) est adopt\u00e9 d&rsquo;une fa\u00e7on ou d&rsquo;une autre, il y aura une rupture dans le parti r\u00e9publicain, et cela impliquerait essentiellement le d\u00e9part de l&rsquo;aile pal\u00e9o-conservatrice\/libertarienne (\u00ab<em>If the Republican counteroffer to Obama&rsquo;s is a return to the compulsive interventionism of Bush II, this is where some of us will be getting off<\/em>\u00bb). Ce constat illustre un climat en train de se d\u00e9velopper aux USA, autour de l&rsquo;\u00e9volution de la politique russe de Washington, et, bien entendu, des perspectives de conflit. Le vieux Ron Paul, qui n&rsquo;a pas perdu son \u00e9nergie ni mis sa langue dans sa poche, est de plus en plus souvent accus\u00e9 de trahison par la presse-Syst\u00e8me, \u00e0 cause de ses prises de position hostiles \u00e0 cette politique, et par cons\u00e9quent proches de la position de Poutine. Cela signifie-t-il que la crise ukrainienne, avec sa dimension transformatrice vers un conflit impliquant la Russie et les USA, commence \u00e0 entrer dans la perception politique aux USA, et cela pouvant alors figurer dans la campagne \u00e9lectorale des \u00e9lections <em>mid-term<\/em> (novembre prochain), et peser sur les r\u00e9sultats ? Cela signifie-t-il que la psychologie am\u00e9ricaniste, comme la psychologie russe, chacune \u00e0 sa fa\u00e7on et chacune avec ses motivations et ses responsabilit\u00e9s, finissent par percevoir la perspective d&rsquo;un affrontement comme quelque chose d&rsquo;in\u00e9vitable ? La loi 2277 est un de ces m\u00e9canismes dont le Congr\u00e8s US a le secret, qui favorisent effectivement l&rsquo;\u00e9volution m\u00e9canique vers une aggravation des tensions comme s&rsquo;installe un processus normal, et cela interdisant par cons\u00e9quent toute tentative de r\u00e9solution du diff\u00e9rend \u00e0 propos duquel grandissent ces tensions.<\/p>\n<\/p>\n<p><p>\tPeu \u00e0 peu, au milieu des pol\u00e9miques, des coups fourr\u00e9s et des coups mont\u00e9s, au milieu des affrontements o\u00f9 les incendiaires agissent \u00e0 visage d\u00e9couvert et sans que personne ne songe \u00e0 les arr\u00eater, s&rsquo;installe effectivement le sentiment de la possibilit\u00e9 de l&rsquo;in\u00e9luctabilit\u00e9, sinon du conflit, dans tous les cas de la tension rupturielle. Nous ne sommes plus ici sur le terrain des responsabilit\u00e9s historiques, voire des responsabilit\u00e9s de machination, mais sur le terrain plus \u00e9lev\u00e9 o\u00f9 l&rsquo;Histoire c\u00f4toie la m\u00e9tahistoire. Cette possibilit\u00e9 de l&rsquo;in\u00e9luctabilit\u00e9&#8230; de la tension rupturielle correspond surtout, essentiellement, \u00e0 la perception de la perte totale du contr\u00f4le des \u00e9v\u00e9nements dans leur plus grande tendance. Certes, les uns et les autres agissent \u00e0 leur niveau, la machine de provocation et de montage du bloc BAO marche \u00e0 fond, mais nous parlons bien d&rsquo;un sentiment puissant qui domine le reste. Plus personne ne contr\u00f4le cette crise, qui est d\u00e9sormais plus qu&rsquo;une crise, qui est en train de devenir un destin, et qui est le destin de cette civilisation devenue contre-civilisation. Sera-ce la guerre ou bien sera-ce un autre \u00e9v\u00e9nement d&rsquo;une grande rupture ? Dans tous les cas, la crise ukrainienne a d\u00e9finitivement quitt\u00e9 l&rsquo;aire g\u00e9ographique et politique o\u00f9 elle se trouvait primitivement enferm\u00e9e, et d&rsquo;o\u00f9 elle a surgi. Elle est compl\u00e8tement install\u00e9e au cur de la politique de s\u00e9curit\u00e9 nationale des deux grandes puissances nucl\u00e9aires strat\u00e9giques, et d&rsquo;autre part chacune repr\u00e9sentant le mieux le Syst\u00e8me et l&rsquo;antiSyst\u00e8me. Les \u00e9v\u00e9nements \u00e9voluent comme si l&rsquo;on trouvait au bout du chemin d&rsquo;une \u00e9poque, d&rsquo;une \u00e8re historique, au moment o\u00f9 l&rsquo;influence de la m\u00e9tahistoire prend le dessus.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 29 juillet 2014 \u00e0 18H17<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu&rsquo;importe&#8230; Puisqu&rsquo;une guerre se pr\u00e9pare en Europe ZeroHedge.com signalait \u00e0 notre attention, le 29 juillet 2014, la raison pour laquelle Poutine serait totalement indiff\u00e9rent au jugement condamnant la Russie \u00e0 une amende d&rsquo;autour de $50 milliards dans l&rsquo;affaire Yukos (voir ce 29 juillet 2014). Il s&rsquo;agit d&rsquo;un commentaire recueilli par le Financial Times du 28&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[15953,4056,3335,15955,3107,2645,4174,2707,916,3531,1296,15954],"class_list":["post-75430","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-15953","tag-antimissiles","tag-buchanan","tag-crocker","tag-euromissiles","tag-guerre","tag-loi","tag-moscou","tag-poutine","tag-senat","tag-ukraine","tag-yukos"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75430"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75430\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}