{"id":75432,"date":"2014-07-30T09:10:54","date_gmt":"2014-07-30T09:10:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/07\/30\/pour-une-alliance-franco-russe\/"},"modified":"2014-07-30T09:10:54","modified_gmt":"2014-07-30T09:10:54","slug":"pour-une-alliance-franco-russe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/07\/30\/pour-une-alliance-franco-russe\/","title":{"rendered":"Pour une alliance franco-russe"},"content":{"rendered":"<p><h2 class=\"common-article2\">Pour une alliance franco-russe<\/h2>\n<\/p>\n<p><p>\tCe texte, encore en discussion, a \u00e9t\u00e9 r\u00e9dig\u00e9 pour le compte du comit\u00e9 de r\u00e9daction de Europe solidaire. Il est sign\u00e9 par Jean-Paul Baquiast et Jean-Claude Empereur (ordre alphab\u00e9tique) <\/p>\n<h3>Introduction <\/h3>\n<\/p>\n<p><p>\tNous avons pr\u00e9c\u00e9demment montr\u00e9 (voir \u00ab <a href=\"http:\/\/www.europesolidaire.eu\/article.php?article_id=1433&#038;r_id=\" class=\"gen\">L&rsquo;Europe, \u00e9picentre de conflits destructeurs<\/a> \u00bb) que si l&rsquo;Europe ne se d\u00e9gage pas d&rsquo;une domination de plus de soixante ans impos\u00e9e par les Etats-Unis, elle restera ind\u00e9finiment un simple instrument par lesquels ceux-ci voudront poursuivre leur principal projet dans cette partie du monde, d\u00e9truire la Russie. Mais, pour \u00e9chapper \u00e0 cette domination, l&rsquo;Europe devrait se rapprocher d&rsquo;un ensemble g\u00e9opolitique encore en constitution, les BRICS. L&rsquo;Europe et les BRICS repr\u00e9senteraient alors une force susceptible de faire contrepoids \u00e0 la puissance am\u00e9ricaine, laquelle demeurera longtemps sup\u00e9rieure aux moyens mobilisables par l&rsquo;Europe ou par les BRICS agissant individuellement. <\/p>\n<\/p>\n<p><p>\tCeci admis, force est de faire deux constatations:<\/p>\n<\/p>\n<p><p>\t* L&rsquo;Europe est trop disparate et trop p\u00e9n\u00e9tr\u00e9e de l&rsquo;influence am\u00e9ricaines pour qu&rsquo;il soit raisonnable de penser qu&rsquo;elle puisse s&rsquo;engager rapidement, et avec l&rsquo;intensit\u00e9 n\u00e9cessaire, dans une alliance, ni m\u00eame dans de simples coop\u00e9rations strat\u00e9giques, avec les BRICS. Il faudrait que des Etats europ\u00e9ens agissant \u00e0 titre individuel, autrement dit s&rsquo;affranchissant des contraintes impos\u00e9es par la diplomatie de l&rsquo;Union europ\u00e9enne, prennent l&rsquo;initiative de n\u00e9gocier pour leur compte les rapprochements n\u00e9cessaires.<\/p>\n<\/p>\n<p><p>\t* Les BRICS sont encore trop diff\u00e9rents, et pour certains trop \u00e9loign\u00e9s de l&rsquo;Europe, pour que des n\u00e9gociations globales avec eux soient envisageables \u00e0 court terme, sauf dans des cas particuliers. L\u00e0 encore, les Europ\u00e9ens doivent se donner des partenaires privil\u00e9gi\u00e9s, qui partagent avec eux le plus grand nombre d&rsquo;objectifs  communs. <\/p>\n<\/p>\n<p><p>\tPour r\u00e9pondre \u00e0 cette double exigence, nous proposons ici de consid\u00e9rer une alliance strat\u00e9gique entre la France et la Russie comme le premier pas indispensable dans la constitution \u00e0 terme d&rsquo;une alliance plus large entre l&rsquo;Europe et les BRICS. La France et la Russie, bien que ne disposant pas de fronti\u00e8res terrestres communes, ont partag\u00e9 depuis l&rsquo;\u00e9poque de la Grande Catherine jusqu&rsquo;\u00e0 la seconde guerre mondiale des points communs et des int\u00e9r\u00eats tr\u00e8s proches. M\u00eame du temps de la dictature stalinienne, les deux nations ne se sont pas v\u00e9ritablement oppos\u00e9es. De Gaulle fut le premier des chefs d&rsquo;Etat europ\u00e9ens \u00e0 encourager le rapprochement avec la Russie. <\/p>\n<\/p>\n<p><p>\tPr\u00e9cisons d&#8217;embl\u00e9e qu&rsquo;un tel projet d&rsquo;alliance avec la Russie pourrait d\u00e8s maintenant \u00eatre \u00e9tendu \u00e0 d&rsquo;autres pays europ\u00e9ens, notamment en premier lieu l&rsquo;Allemagne, l&rsquo;Espagne et l&rsquo;Italie. Mais dans chacun de ces cas, il faudrait d\u00e9velopper les raisons pour lesquelles renforcer des liens avec la Russie les int\u00e9resse aujourd&rsquo;hui et pourrait les int\u00e9resser davantage encore demain. Ceci d\u00e9passerait le cadre de cet article.<\/p>\n<\/p>\n<p><p>\tPour en revenir \u00e0 la France, rappelons pour la petite histoire que lorsque les troupes du czar Alexandre ont momentan\u00e9ment occup\u00e9 Paris \u00e0 la suite de la chute de Napol\u00e9on premier, elles se sont presque parfaitement comport\u00e9es. Rappelons \u00e9galement que l&rsquo;Alliance Franco-Russe n\u00e9goci\u00e9e dans la perspective de la 1e guerre mondiale a \u00e9t\u00e9 tr\u00e8s populaire dans les deux pays. Le succ\u00e8s persistant en France de l&rsquo;entremets du m\u00eame nom, n&rsquo;est pas simplement anecdotique. Il manifeste les connivences profondes entre les deux soci\u00e9t\u00e9s, connivences qui se sont manifest\u00e9es depuis cette date dans des domaines plus spectaculaires, la litt\u00e9rature et les arts, la technologie, la science&#8230;<\/p>\n<\/p>\n<p><p>\tMais sur quelles bases concevoir aujourd&rsquo;hui une alliance franco-russe pouvant \u00eatre un prototype pour une alliance euroBRICS? <\/p>\n<h3>Un projet g\u00e9opolitique<\/h3>\n<\/p>\n<p><p>\tIl devrait d&rsquo;abord s&rsquo;agir d&rsquo;un projet g\u00e9opolitique. Ce terme d\u00e9signe un projet d&rsquo;alliance ou de rapprochement politique entre Etats partageant un m\u00eame espace g\u00e9ographique et les m\u00eames objectifs strat\u00e9giques. Ce partage, m\u00eame \u00e0 l&rsquo;\u00e2ge de la mondialisation des \u00e9changes, entraine n\u00e9cessairement des int\u00e9r\u00eats communs. Concernant la France et la Russie, le partage de l&rsquo;espace g\u00e9ographique n&rsquo;est pas \u00e9vident, au vue d&rsquo;une carte. Mais en approfondissant ce concept, il s&rsquo;impose de lui-m\u00eame: les liaisons ferroviaires, maritimes et a\u00e9riennes sont d\u00e9j\u00e0 nombreuses et pourraient \u00eatre accrues \u00e0 moindre frais. Les similitudes r\u00e9gnant d&rsquo;un bout \u00e0 l&rsquo;autre de ce que de Gaulle avait appel\u00e9 l&rsquo;Europe de l&rsquo;Atlantique \u00e0 l&rsquo;Oural, et au del\u00e0, sont certaines. Aujourd&rsquo;hui, des Etats s&rsquo;interposent g\u00e9ographiquement entre la France et la Russie, mais il n&rsquo;y a pas de raisons obligeant \u00e0 penser que ces Etats, ou du moins leurs populations, s&rsquo;opposeraient aux rapprochements entre les deux ailes de cet ensemble, dont ils pourraient tous b\u00e9n\u00e9ficier. Ce ne serait d&rsquo;ailleurs que la r\u00e9activation de ce qui fut l&rsquo;Europe des Lumi\u00e8res avant la r\u00e9volution fran\u00e7aise. <\/p>\n<h3>Un projet reposant sur la mutualisation des compl\u00e9mentarit\u00e9s<\/h3>\n<\/p>\n<p><p>\tLa compl\u00e9mentarit\u00e9 est d&rsquo;abord celle des ressources et de l&rsquo;int\u00e9r\u00eat qu&rsquo;il y aurait \u00e0 les d\u00e9velopper en commun. Au plan g\u00e9ographique la Russie pourrait acc\u00e9der par l&rsquo;interm\u00e9diaire de la France \u00e0 des espaces maritimes qui lui sont encore tr\u00e8s difficiles \u00e0 atteindre: arc atlantique, m\u00e9diterran\u00e9e occidentale, mers entourant l&rsquo;\u00e9tendue consid\u00e9rable (en fait unique au monde) composant de ce l&rsquo;on appelle l&rsquo;outremer fran\u00e7ais . A l&rsquo;inverse la France pourrait acc\u00e9der aux r\u00e9gions polaires et sib\u00e9riennes qui, convenablement g\u00e9r\u00e9es, prendront de plus en plus d&rsquo;importance dans la perspective du changement climatique.<\/p>\n<\/p>\n<p><p>\tAu plan \u00e9conomique, la France relativement bien industrialis\u00e9e, pourrait aider la Russie \u00e0 se d\u00e9velopper dans les domaines correspondants, tout en b\u00e9n\u00e9ficiant en retour des savoir-faire et des ressources russes, notamment technologiques, \u00e9nerg\u00e9tiques et mini\u00e8res (terres rares). Dans le domaine essentiel de la recherche-d\u00e9veloppement, on mentionnera la possibilit\u00e9 de lancer en commun de grands programmes concernant notamment les \u00e9nergies vertes, toutes les technologies NBIC (nano, bio, info et cognotechnologies), mais aussi l&rsquo;espace et la d\u00e9fense. <\/p>\n<\/p>\n<p><p>\tEnfin, au plan politico-diplomatique, la compl\u00e9mentarit\u00e9 sera de plus en plus \u00e9vidente.  C&rsquo;est d\u00e9j\u00e0 largement le cas en ce qui concerne la lutte contre les mouvements islamiques radicaux, aussi dangereux en Russie qu&rsquo;en Europe et au Moyen Orient. Leur extension s&rsquo;op\u00e8re actuellement en Afrique sub-saharienne. M\u00eame si la France traite ce probl\u00e8me diff\u00e9remment de ce que fait la Russie, des coop\u00e9rations s&rsquo;imposeront. D&rsquo;une fa\u00e7on plus constructive, si la France cessait de se consid\u00e9rer comme ayant le devoir de suivre docilement les m\u00e9andres de la politique am\u00e9ricaine, France et Russie unies pourraient peser d&rsquo;une fa\u00e7on d\u00e9terminante dans les grands n\u00e9gociations ou conflits se d\u00e9roulant \u00e0 leurs fronti\u00e8res; Iran, Irak, Syrie, question isra\u00e9lo-palestinienne, question kurde, etc. <\/p>\n<\/p>\n<p><p>\tLa question des diff\u00e9rences d&rsquo;approche en mati\u00e8re de d\u00e9mocratie politique, de libert\u00e9s publiques et de murs ne devrait pas \u00eatre un obstacle aux coop\u00e9rations envisag\u00e9es. D&rsquo;une part avec le temps ces diff\u00e9rences s&rsquo;att\u00e9nueront. D&rsquo;autre part, chacun des partenaires doit afficher sa volont\u00e9 de laisser \u00e0 l&rsquo;autre la responsabilit\u00e9 de ses choix soci\u00e9taux, sans pr\u00e9tendre les changer.<\/p>\n<h3>Un processus progressif<\/h3>\n<\/p>\n<p><p>\tIl ne faut pas dissimuler le fait que les divergences et proc\u00e8s d&rsquo;intention sont encore tr\u00e8s vifs, notamment en France, relativement \u00e0 ce que pourrait \u00eatre une alliance franco-russe. Aussi les mouvements et hommes politiques convaincus de son int\u00e9r\u00eat devront proposer une d\u00e9marche progressive, s&rsquo;inscrivant dans une dur\u00e9e longue. Mais qui dit progressivit\u00e9 ne signifie pas ne pas prendre de d\u00e9cisions imm\u00e9diates, sur des points embl\u00e9matiques.<\/p>\n<\/p>\n<p><p>\tIl a \u00e9t\u00e9 fait valoir ainsi que si la France, c\u00e9dant aux injonctions am\u00e9ricaines, avait d\u00e9cid\u00e9 de ne pas livrer \u00e0 la Russie ce qui lui appartient, en l&rsquo;esp\u00e8ce les deux b\u00e2timents de projection et de combat de type Mistral con\u00e7us \u00e0 Saint Nazaire, il en aurait \u00e9t\u00e9 fait pour longtemps des espoirs de coop\u00e9ration entre les deux pays. A l&rsquo;inverse, si la France et la Russie approfondissaient encore leurs coop\u00e9rations, d\u00e9j\u00e0 tr\u00e8s fertiles, dans le domaine de l&rsquo;espace, elles pourraient mettre au point plus rapidement que seules les lanceurs, modules habit\u00e9s et stations terrestres n\u00e9cessaires \u00e0 des coop\u00e9rations accrues en mati\u00e8re d&rsquo;\u00e9tudes cosmologiques, mais aussi en ce qui concerne l&rsquo;exploration de la Lune, des satellites de Mars et de Mars elle-m\u00eame. Dans des domaines d&rsquo;applications plus imm\u00e9diates, les besoins et possibilit\u00e9s de coop\u00e9ration sont nombreux. Citons la m\u00e9decine, la robotique, la traduction automatique des langues, les sciences sociales et politiques&#8230;<\/p>\n<h3>Conclusion<\/h3>\n<\/p>\n<p><p>\tPour ce qui nous concerne, en tant qu&rsquo;association(s) convaincue(s) de la n\u00e9cessit\u00e9 d&rsquo;une alliance franco-russe, nous d\u00e9velopperons nos interventions en ce domaine et nous efforcerons d&rsquo;\u00e9tablir avec les autres organismes jouant un r\u00f4le de m\u00eame nature, tant en France et dans les pays europ\u00e9ens qu&rsquo;en Russie, un r\u00e9seau virtuel utilisant les outils num\u00e9riques susceptible de provoquer des changements en profondeur dans les opinions publiques.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Jean-Paul Baquiast et Jean-Claude Empereur<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour une alliance franco-russe Ce texte, encore en discussion, a \u00e9t\u00e9 r\u00e9dig\u00e9 pour le compte du comit\u00e9 de r\u00e9daction de Europe solidaire. Il est sign\u00e9 par Jean-Paul Baquiast et Jean-Claude Empereur (ordre alphab\u00e9tique) Introduction Nous avons pr\u00e9c\u00e9demment montr\u00e9 (voir \u00ab L&rsquo;Europe, \u00e9picentre de conflits destructeurs \u00bb) que si l&rsquo;Europe ne se d\u00e9gage pas d&rsquo;une domination&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[7895,11035,398,15957,15956,1296,2804,6190],"class_list":["post-75432","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-baquiast","tag-brics","tag-europe","tag-lempereur","tag-transatklantique","tag-ukraine","tag-usa","tag-vassalite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75432"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75432\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}