{"id":75487,"date":"2014-09-01T11:48:47","date_gmt":"2014-09-01T11:48:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/09\/01\/lue-en-ordre-de-bataille-mais-quelle-bataille\/"},"modified":"2014-09-01T11:48:47","modified_gmt":"2014-09-01T11:48:47","slug":"lue-en-ordre-de-bataille-mais-quelle-bataille","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/09\/01\/lue-en-ordre-de-bataille-mais-quelle-bataille\/","title":{"rendered":"L&rsquo;UE en ordre de bataille, \u2013 mais quelle bataille ?"},"content":{"rendered":"<p><h3 class=\"titrebloc\">L&rsquo;UE en ordre de bataille,  mais quelle bataille ?<\/h3>\n<\/p>\n<p><p>\tIl y a une tr\u00e8s grande diff\u00e9rence entre les nominations pr\u00e9c\u00e9dentes des dirigeants institutionnels de l&rsquo;UE dans sa formule d\u00e9finitive, et celle qui intervient cinq ans apr\u00e8s. Au trio Von Rompuy-Ashton-Barroso succ\u00e8de un trio original et haut en couleurs diverses, le Polonais Tusk \u00e0 la place de Van Rompuy, l&rsquo;Italienne Mogherini \u00e0 celle d&rsquo;Ashton, apr\u00e8s le Luxembourgeois Juncker \u00e0 la place de Barroso. D\u00e9j\u00e0, avec la nomination de Juncker, nous avancions notre sentiment, qui se trouve compl\u00e8tement confirm\u00e9e, moins sur le fond de l&rsquo;argument que sur la forme de la nouvelle configuration, par les deux nominations du week-end&#8230; Le <a href=\"http:\/\/www.dedefensa.org\/article-l_europe_au_rythme_de_juncker_28_06_2014.html\" class=\"gen\">28 juin 2014<\/a>, nous \u00e9crivions \u00e0 propos de Juncker&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>&#8230; Il n&rsquo;y aura donc pas de lutte politique \u00e0 proprement parler entre Juncker et les Britanniques, ce qui n&rsquo;est d&rsquo;ailleurs pas une chose mauvaise parce qu&rsquo;une lutte politique ne serait qu&rsquo;une occurrence trompeuse par rapport \u00e0 ce qu&rsquo;elle nous ferait croire faussement d&rsquo;une v\u00e9ritable \u00e9volution de la situation. Mais il y aura sans aucun doute une lutte bureaucratique, pour deux raisons : 1) parce que Juncker, sp\u00e9cialiste des arcanes europ\u00e9ennes et effectivement f\u00e9d\u00e9raliste acharn\u00e9, n&rsquo;a pas l&rsquo;habitude de l\u00e2cher prise. Il voudra faire passer ses options f\u00e9d\u00e9ralistes dans la monstrueuse bureaucratie de la Commission, c&rsquo;est-\u00e0-dire aller dans le sens de dessaisir les pays-membres de ce qu&rsquo;il leur reste de miettes de souverainet\u00e9. 2) Contre cela, les Britanniques (pas les Fran\u00e7ais, certes, dans l&rsquo;\u00e9tat o\u00f9 ils sont) se battront jusqu&rsquo;au bout. Or, s&rsquo;ils sont bien peu europ\u00e9ens, ils ont par contre une grande maestria bureaucratique et ont r\u00e9ussi \u00e0 placer leurs hommes (tout fonctionnaire UE de nationalit\u00e9 britannique reste par-dessus tout un homme de l&rsquo;Angleterre) dans nombre de postes strat\u00e9giques de la bureaucratie de l&rsquo;UE. C&rsquo;est dire si Juncker trouvera \u00e0 qui parler et que, compte-tenu de son caract\u00e8re, cela se traduira par des batailles internes et des tensions extr\u00eames \u00e0 l&rsquo;int\u00e9rieur des bureaucraties europ\u00e9ennes,  les deux adversaires, Juncker et l&rsquo;activisme bureaucratique britannique d\u00e9ployant une \u00e9gale vacherie dans la bataille \u00e0 venir.<\/em> [&#8230;] <em>La d\u00e9signation \u00e9lective de Juncker ouvre donc bien des perspectives, dans la mesure o\u00f9 elle pourrait \u00eatre le pas de clerc de la pouss\u00e9e globalisante, s&rsquo;exprimant en Europe sous le visage du f\u00e9d\u00e9ralisme \u00e0 outrance. Comme Juncker est un dur, on peut compter sur lui pour contribuer \u00e0 pousser l&rsquo;exp\u00e9rience jusqu&rsquo;\u00e0 son terme, c&rsquo;est-\u00e0-dire contribuer \u00e9ventuellement \u00e0 conduire directement l&rsquo;Europe \u00e0 sa Guerre de S\u00e9cession avant m\u00eame que leur ambition des \u00c9tats-Unis d&rsquo;Europe soit rencontr\u00e9e.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEntretemps, Juncker a ajout\u00e9 des d\u00e9clarations \u00e0 son dossier&#8230; Il a d\u00e9clar\u00e9 qu&rsquo;il fallait chercher \u00e0 r\u00e9duire l&rsquo;influence US dans les institutions europ\u00e9ennes, qu&rsquo;il juge trop importante. En temps normal, il n&rsquo;y aurait pas de quoi secouer la cendre de sa cigarette dans un cendrier, mais dans les circonstances pr\u00e9sentes par contre&#8230; Cela peut signifier que l&rsquo;animosit\u00e9 furieuse de Juncker contre les Britanniques, s&rsquo;exprimant par toutes les voies possibles, pourrait \u00e9galement prendre celle d&rsquo;une d\u00e9nonciation de l&rsquo;influence US trop importante que relaient les Britanniques. La posture <em>softly<\/em> antiam\u00e9ricaniste de Juncker, qu&rsquo;on jugerait de pure communication sans cons\u00e9quence, se colorerait alors de la possibilit\u00e9s d&rsquo;actions r\u00e9elles puisqu&rsquo;elle permettrait de contrer les Britanniques. (Nous irons jusqu&rsquo;\u00e0 penser que si Juncker a fait cette d\u00e9claration, c&rsquo;est plus contre les Britanniques, porteurs d&rsquo;eau des USA, que contre les USA,  mais qu&rsquo;importe puisqu&rsquo;en cette circonstance seul le r\u00e9sultat compte, et qu&rsquo;en l&rsquo;occurrence l&rsquo;hostilit\u00e9 contre les Britanniques est, chez Juncker, un moteur plus puissant qu&rsquo;aucun autre.)<\/p>\n<\/p>\n<p><p>\tObserver tout cela, c&rsquo;est d\u00e9finir la r\u00e9f\u00e9rence et le cadre o\u00f9 nous allons appr\u00e9cier les deux autres nominations. C&rsquo;est-\u00e0-dire, une r\u00e9f\u00e9rence et un cadre qui ont essentiellement \u00e0 voir avec la politique ext\u00e9rieure, c&rsquo;est-\u00e0-dire aussi bien la crise ukrainienne que les relations avec les USA par cons\u00e9quent, et le trouble que ces questions introduisent au sein de l&rsquo;UE. Que nous dit la presse-Syst\u00e8me \u00e0 cet \u00e9gard ? Des banalit\u00e9s en s&rsquo;attachant aux conditions et aux effets \u00e0 l&rsquo;int\u00e9rieur des institutions europ\u00e9ennes et entre pays-membres, pour ne surtout pas aborder l&rsquo;essentiel. Voici un extrait de l&rsquo;\u00e9dito du <em>Guardian<\/em>, du <a href=\"http:\/\/www.theguardian.com\/commentisfree\/2014\/aug\/31\/guardian-view-europes-next-five-years-long-road-ahead\" class=\"gen\">1er septembre 2014<\/a> ; il nous int\u00e9resse, cet \u00e9dito, parce qu&rsquo;il illustre les deux tendances (les banalit\u00e9s pour ne pas aborder l&rsquo;essentiel, et l&rsquo;essentiel abord\u00e9 par inadvertance). <\/p>\n<\/p>\n<p><p>\t\u00ab<em>&#8230;The Polish centre-right prime minister Donald Tusk, the first eastern European to get a top EU post of this kind, quickly emerged as the new European council president to succeed Herman Van Rompuy, while the Italian centre-left foreign minister Federica Mogherini becomes the new EU foreign policy chief to succeed Catherine Ashton. These choices now open the way for Mr Juncker to pick the rest of his commission team, all of whom will face confirmation hearings at the newly empowered European parliament before the new commission takes over the reins in two months&rsquo; time. This was, inevitably, a trade-off session  a necessary price worth paying for a Europe in which the member states retain much power. Yet no one should pretend that the appointments, though important, will galvanise many people outside the corridors of Brussels.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It is ridiculous to see the appointments too excitedly or through an exclusively parochial prism. Mr Juncker has been consistently and absurdly vilified in the UK as a threat to Britain, even though he has made clear that he wishes to strike a compromise with the UK, while Mr Tusk, after an earlier spat with Downing Street over EU benefit rights, is now being portrayed as the man whom David Cameron can do EU business with. For her part, Ms Mogherini is patronisingly cast as inexperienced and soft on Russia. Meanwhile, the possibility that Mr Juncker might now offer the financial services job to the new British commission nominee, Jonathan Hill, is variously seen as an olive branch, which it manifestly would be, or a dastardly Brussels power grab, which it isn&rsquo;t.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>None of this is to say that parochial considerations don&rsquo;t matter in relations with the EU. But the big tasks facing our continent are all shared business  to get the European economies growing again and to prevent war in Ukraine. That was the most important discussion at the weekend summit. And that is where real British interests are at stake too.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe ton est caract\u00e9ristique : sans enthousiasme, prenant soin de mettre en \u00e9vidence les aspects bureaucratiques, mettant naturellement l&rsquo;accent sur la position anglaise, faisant de Juncker presque un amoureux secret du Royaume-Unis,  ce qui est une mise au point bien dans la nature des Europ\u00e9ens id\u00e9ologiques qui se veulent r\u00e9alistes et soutenus par la grande solidarit\u00e9 lib\u00e9ral-d\u00e9mocratique de notre civilisation\/contre-civilisation&#8230;  \u00ab<em>Mr Juncker has been consistently and absurdly vilified in the UK as a threat to Britain<\/em>\u00bb, \u00e9crit le tr\u00e8s lib\u00e9ral et europ\u00e9en <em>Guardian<\/em>, ce qui est justement absurde tant le sentiment de Mr. Juncker, effectivement anti-britannique, va peser de tout son poids dans une bureaucratie que les Britanniques ont l&rsquo;habitude de noyauter \u00e0 leur botte. \u00ab<em>For her part, Ms Mogherini is patronisingly cast as inexperienced and soft on Russia<\/em>\u00bb, nous dit encore le m\u00eame, ce qui revient \u00e0 dire, <em>in fine<\/em>,  inexp\u00e9riment\u00e9e parce que <em>soft on Russia<\/em>, ou bien <em>soft on Russia<\/em> parce qu&rsquo;inexp\u00e9riment\u00e9e, c&rsquo;est selon et c&rsquo;est au choix&#8230; Bref, il va falloir la mettre au pas, l&rsquo;Italienne, l&rsquo;exp\u00e9rimenter, au contraire de celle qu&rsquo;elle remplace, la nullissime Lady Ashton, qui \u00e9tait, comme chacun sait, parfaitement exp\u00e9riment\u00e9e puisqu&rsquo;elle n&rsquo;avait jamais entendu parler des questions de politique ext\u00e9rieure et qu&rsquo;elle avait pour seule mission de r\u00e9citer par cur les fiches du Foreign Office. Le <em>Guardian<\/em> est capable vraiment en m\u00eame temps d&rsquo;\u00eatre lib\u00e9ral-Syst\u00e8me \u00e0 50% et britannique \u00e0 50% dans ses commentaires, c&rsquo;est-\u00e0-dire sordide \u00e0 120-130%, nous d\u00e9montrant que m\u00eame dans les officines les plus chics le nihilisme britannique, ou plut\u00f4t anglo-saxon, est en mode-<em>turbo<\/em>. <\/p>\n<\/p>\n<p><p>\tVoyons maintenant ce que nous en pensons, nous, en nous concentrant bien entendu sur les nouvelles nominations. En effet, elles ne sont nullement indiff\u00e9rentes et refl\u00e8tent, non pas les habituels jugements pseudo-bureaucratiques des connaisseurs de type britannique mais bien certains aspects int\u00e9ressants de la situation europ\u00e9enne,  la vraie, s&rsquo;entend, pas celle des \u00e9ditos de la presse-Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\t On a parl\u00e9 souvent, avec insistance et l&rsquo;air entendu, du Polonais Sikorski pour le remplacement de Lady Ashton. Sikorski \u00e9tant <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_m_tamorphose_furieuse_des_cloportes_24_06_2014.html\" class=\"gen\">ce qu&rsquo;il est<\/a>,  un <em>neocon<\/em> de circonstance qui d\u00e9teste ses ma\u00eetres mais leur est compl\u00e8tement soumis,  on imagine l&rsquo;intentionnalit\u00e9 de la suggestion, particuli\u00e8rement insistante en juillet, au moment de la destruction du vol MH17 imm\u00e9diatement attribu\u00e9 \u00e0 Poutine. On n&rsquo;a pas Sikorski, on a Tusk, et en remplacement de Van Rompuy. C&rsquo;est compl\u00e8tement diff\u00e9rent. D&rsquo;abord, Tusk ce n&rsquo;est pas Sikorski ; s&rsquo;il a dirig\u00e9 et dirige encore pour quelques semaines un gouvernement polonais ultra-dur, antirusse, ce n&rsquo;est pas lui qui a donn\u00e9 cette orientation, n&rsquo;\u00e9tant pas particuli\u00e8rement int\u00e9ress\u00e9 par les affaires de s\u00e9curit\u00e9, mais plut\u00f4t par les questions \u00e9conomiques. D&rsquo;autre part, le poste de pr\u00e9sident de l&rsquo;UE est plus une fonction organisatrice qu&rsquo;une fonction ex\u00e9cutive : la t\u00e2che du pr\u00e9sident est plut\u00f4t de chercher des accords consensuels entre les \u00c9tats-membres plut\u00f4t que concevoir et d&rsquo;applique une politique. La nomination de Tusk donne satisfaction aux pays de l&rsquo;Europe de l&rsquo;Est pour leur statut \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;UE, mais nullement \u00e0 la politique antirusse et hyst\u00e9rique de ces pays d&rsquo;Europe de l&rsquo;Est. Les Allemands, qui sont derri\u00e8re cette nomination, sont tr\u00e8s contents \u00e0 cause de ces deux arguments justement. On peut \u00eatre s\u00fbr que la position de Tusk ne sera pas ais\u00e9e parce qu&rsquo;il devra faire ce pour quoi il est nomm\u00e9, tandis que de nombreuses pressions, venues des USA, de son propre pays et des pays d&rsquo;Europe de l&rsquo;Est, s&rsquo;exerceront sur lui pour qu&rsquo;il en fasse plus, au-del\u00e0 de ses pr\u00e9rogatives, c&rsquo;est-\u00e0-dire dans le sens d&rsquo;une politique ext\u00e9rieure antirusse ; et r\u00e9ciproquement, d&rsquo;autres forces s&rsquo;exerceront sur lui pour qu&rsquo;il reste au contraire dans le strict cadre de ses fonctions. Le r\u00e9sultat peut \u00eatre un d\u00e9sordre sympathique.<\/p>\n<\/p>\n<p><p>\t Mogherini, elle, arrive aur\u00e9ol\u00e9e d&rsquo;une position vis-\u00e0-vis de la Russie qui avait mobilis\u00e9 contre elle, ces derni\u00e8res semaines, toutes les forces antirusses. Sa premi\u00e8re d\u00e9claration apr\u00e8s sa nomination a \u00e9t\u00e9 du type certes il y a les sanctions, mais il ne faut pas pour autant et surtout pas n\u00e9gliger la voie diplomatique (du dialogue avec la Russie). Elle est peut-\u00eatre inexp\u00e9riment\u00e9e mais elle sait infiniment plus ce qu&rsquo;elle veut que ce qu&rsquo;en savait pour elle-m\u00eame Ashton lorsqu&rsquo;elle fut nomm\u00e9e,  c&rsquo;est-\u00e0-dire rien, hormis les fiches du Foreign Office. Mogherini sera donc la cible privil\u00e9gi\u00e9e de tout ce qu&rsquo;il y a d&rsquo;antirusse dans le domaine et, avec un peu de chance et un peu de caract\u00e8re, elle sera tent\u00e9e de construire sa position et sa carri\u00e8re politique europ\u00e9enne, justement sur cet aspect de ses conceptions qui lui permettront d&rsquo;affirmer sa diff\u00e9rence dans le concert de b\u00ealements du troupeau-Syst\u00e8me. Dans ce cas, son inexp\u00e9rience signifierait qu&rsquo;elle n&rsquo;est pas compl\u00e8tement sous le joug du Syst\u00e8me, et l&rsquo;on comprend alors le persiflage transatlantique du <em>Guardian<\/em>.<\/p>\n<\/p>\n<p><p>\tEncore une fois, et avec un plaisir \u00e0 peine dissimul\u00e9, nous mettrons la plus grande attention \u00e0 contredire le <em>Guardian<\/em>. \u00ab<em>It is ridiculous to see the appointments too excitedly&#8230;<\/em>\u00bb, \u00e9crit-il ; eh bien non, il n&rsquo;est du tout <em>ridiculous<\/em>, etc., parce que, justement, ces nominations, au contraire de la charrette pr\u00e9c\u00e9dente qui puait l&rsquo;arrangement bureaucratique, sortent du cadre bureaucratique pour \u00eatre notablement connect\u00e9es aux conditions politiques cr\u00e9\u00e9es par la crise ukrainienne, et \u00e0 l&rsquo;affrontement interne, politique lui aussi avec un zeste atlantiste involontaire, entre les Britanniques et le reste. Cela ne signifie pas que l&rsquo;on s&rsquo;excite dans un sens europ\u00e9en,  du type L&rsquo;Europe ! L&rsquo;Europe ! en sautant sur sa chaise, selon l&rsquo;image affectionn\u00e9e par le G\u00e9n\u00e9ral. L&rsquo;Europe institutionnelle reste ce qu&rsquo;elle n&rsquo;est et ne pourra pas produire plus que son inf\u00e9condit\u00e9 par absence de souverainet\u00e9 et de l\u00e9gitimit\u00e9 ne le lui permet. Par contre, son agitation \u00e9ventuelle, son d\u00e9sordre en un mot au milieu de conditions politiques extraordinaires, \u00e0 cause de nominations politiques qui sont en rapport avec ces conditions, peut apporter d&rsquo;int\u00e9ressants d\u00e9veloppements, inattendus, cr\u00e9ateurs de nouveaux d\u00e9sordres au-del\u00e0 du sien, mena\u00e7ant par inadvertance la ligne-Syst\u00e8me et ainsi de suite. Bref et somme toute, on finirait bien par comprendre l&rsquo;esp\u00e8ce de scepticisme un peu forc\u00e9 et m\u00e9prisant de l&rsquo;\u00e9dito du <em>Guardian<\/em> ; c&rsquo;est le scepticisme et le m\u00e9pris dissimulant somme toute assez mal une certaine crainte et un r\u00e9el d\u00e9sappointement.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 1er septembre 2014 \u00e0 11H48<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;UE en ordre de bataille, mais quelle bataille ? Il y a une tr\u00e8s grande diff\u00e9rence entre les nominations pr\u00e9c\u00e9dentes des dirigeants institutionnels de l&rsquo;UE dans sa formule d\u00e9finitive, et celle qui intervient cinq ans apr\u00e8s. Au trio Von Rompuy-Ashton-Barroso succ\u00e8de un trio original et haut en couleurs diverses, le Polonais Tusk \u00e0 la place&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8150,12783,3216,8948,2730,4862,2828,1296,4164],"class_list":["post-75487","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-ashton","tag-mogherini","tag-neocon","tag-rompuy","tag-russie","tag-sikorski","tag-tusk","tag-ukraine","tag-van"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75487"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75487\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}