{"id":75526,"date":"2014-09-25T14:33:16","date_gmt":"2014-09-25T14:33:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/09\/25\/letrange-hit-parade-de-bho\/"},"modified":"2014-09-25T14:33:16","modified_gmt":"2014-09-25T14:33:16","slug":"letrange-hit-parade-de-bho","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/09\/25\/letrange-hit-parade-de-bho\/","title":{"rendered":"L&rsquo;\u00e9trange <em>Hit Parade<\/em> de BHO"},"content":{"rendered":"<p><h4 class=\"breve-de-crise\">L&rsquo;\u00e9trange <em>Hit Parade<\/em> de BHO<\/h4>\n<p>Le ministre russe des affaires \u00e9trang\u00e8res Lavrov reste imperturbable,  c&rsquo;est sa qualit\u00e9 principale,   malgr\u00e9 les stup\u00e9factions int\u00e9rieures que lui procurent les audaces dialectiques et conceptuelles de ses partenaires. Il n&rsquo;en exprime pas moins des mots extr\u00eamement durs et des jugements particuli\u00e8rement tranchants sur le discours que vient de faire Obama \u00e0 l&rsquo;ONU, et le calme du ministre russe fait d&rsquo;autant plus ressortir la rudesse de son propos. Il semble, \u00e0 chaque sortie dialectique am\u00e9ricaniste suivie de la riposte russe, qu&rsquo;on atteint des domaines jusqu&rsquo;ici inexplor\u00e9s de la pol\u00e9mique non-diplomatique dans le cadre de la diplomatie ; non pas des invectives, non, simplement des signes exprimant la consid\u00e9ration la plus \u00e9bahie, \u00e9chang\u00e9s d&rsquo;une plan\u00e8te \u00e0 l&rsquo;autre, qui s&rsquo;\u00e9loignent de plus en plus l&rsquo;une de l&rsquo;autre&#8230; Devinez laquelle est la plan\u00e8te des fous ?<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit du discours o\u00f9 Obama donne son classement,  son <em>Hit Parade<\/em>, si l&rsquo;on veut,  des trois principales menaces qui p\u00e8sent sur le monde. Dans l&rsquo;ordre : le virus Ebola, la politique agressive et expansionniste de la Russie-qui-a-envahi-l&rsquo;Ukraine, la n\u00e9buleuse terroriste ISIS. Il est difficile de prendre une approche critique rationnelle de ces choix et de ce classement, tant chacun des sujets choisis a de multiples facettes faussaires et inverties, et dites par un homme qui dirige une administration elle-m\u00eame compl\u00e8tement faussaire, et suivant les consignes faussaires d&rsquo;un Syst\u00e8me qui domine tout \u00e0 Washington. Aussi Lavrov s&rsquo;en donne-t-il \u00e0 cur joie, avec des jugements qui mettent en doute le s\u00e9rieux du pr\u00e9sident de type-orwellien, sinon peut-\u00eatre son \u00e9quilibre mental. Le pr\u00e9sident, lui, s&rsquo;en fout ; il lit un discours pr\u00e9par\u00e9 par son service de la communication sous inspiration <em>neocon<\/em>, et seuls comptent l&rsquo;effet, l&#8217;emphase qu&rsquo;il y met, la posture exceptionnaliste qu&rsquo;il prend, etc. A d\u00e9faut de se mettre en col\u00e8re, Lavrov, finalement, c&rsquo;est-\u00e0-dire aux derni\u00e8res nouvelles, se marre en-dedans lui. Mais il en dira un mot \u00e0 John Kerry, qui \u00e9coutera avec gravit\u00e9&#8230; Le monde s&rsquo;en portera mieux, <em>freer and safer<\/em>, comme dit Obama. (Dans <em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/news\/190392-russia-lavrov-obama-threat-speech\/\" class=\"gen\">25 septembre 2014<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Following the US President&rsquo;s speech at the UN, Russian FM Sergey Lavrov was puzzled with Barack Obama&rsquo;s ranking of international threats: deadly Ebola virus top, followed by so-called Russian aggression and ISIS in Syria and Iraq only third?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Gathered at the UN headquarters in New York, the world leaders attending the 69th General Assembly heard Barack Obama highlighting the three most significant global threats today. As we gather here, an outbreak of Ebola overwhelms public health systems in West Africa, and threatens to move rapidly across borders. Russian aggression in Europe recalls the days when large nations trampled small ones in pursuit of territorial ambition. The brutality of terrorists in Syria and Iraq forces us to look into the heart of darkness, the US leader said at the beginning of his statement.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Reacting to the speech, Russia&rsquo;s Foreign Minister Sergey Lavrov spoke with astonishment. We earned the second place among the threats to international peace and stability, Lavrov told journalists on the sidelines of the UN assembly. Not only the ranking of international threats seemed bizarre to Lavrov, especially in the light of the current strikes in Iraq and Syria that bypassed the UN mandate, but also Obama&rsquo;s certainty that the world has become freer and safer.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>I didn&rsquo;t understand whether he was serious or not and whether there was an Orwellian element in it. Because George Orwell invented the Ministry of Truth and it looks like this philosophy is lingering. The Russian foreign minister assessed Obama&rsquo;s words at the session as a speech of a peacemaker  the way it was conceived which he failed to deliver if one compares it to real facts.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The US President presented a US worldview stressing the exceptionality of himself and of his country, the Russian FM said: That&rsquo;s the worldview of a country that has spelt out its right to use force arbitrarily regardless of UN Security Council&rsquo;s resolutions or other international legal acts in its national defense doctrine.<\/em>\u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 25 septembre 2014 \u00e0 14H32<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9trange Hit Parade de BHO Le ministre russe des affaires \u00e9trang\u00e8res Lavrov reste imperturbable, c&rsquo;est sa qualit\u00e9 principale, malgr\u00e9 les stup\u00e9factions int\u00e9rieures que lui procurent les audaces dialectiques et conceptuelles de ses partenaires. Il n&rsquo;en exprime pas moins des mots extr\u00eamement durs et des jugements particuli\u00e8rement tranchants sur le discours que vient de faire Obama&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[16069,13758,2830,3679,3478,5676,1296,11562],"class_list":["post-75526","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-ebola","tag-isis","tag-lavrov","tag-menace","tag-onu","tag-orwellien","tag-ukraine","tag-virus"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75526"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75526\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}