{"id":75625,"date":"2014-11-28T05:34:09","date_gmt":"2014-11-28T05:34:09","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/11\/28\/glossairedde-glossairedde-crisis\/"},"modified":"2014-11-28T05:34:09","modified_gmt":"2014-11-28T05:34:09","slug":"glossairedde-glossairedde-crisis","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/11\/28\/glossairedde-glossairedde-crisis\/","title":{"rendered":"<em>Glossaire.dde<\/em> + <em>Glossaire.dde-crisis<\/em>"},"content":{"rendered":"<p><h2><em>Glossaire.dde<\/em> + <em>Glossaire.dde-crisis<\/em><\/h2>\n<\/p>\n<p><p>28 novembre 2014 &ndash; Nous introduisons une nouvelle \u00ab\u00a0dimension\u00a0\u00bb dans cette rubrique <em>Glossaire.dde<\/em>. Nous pourrions la nommer \u00ab\u00a0nouvelle rubrique\u00a0\u00bb, qui serait alors une sorte de \u00ab\u00a0sous-rubrique\u00a0\u00bb. Nous pr\u00e9f\u00e9rons \u00ab\u00a0dimension\u00a0\u00bb pour ne pas s\u00e9parer cette s\u00e9rie de sujets du reste, pour montrer qu&rsquo;il faut la consid\u00e9rer comme partie int\u00e9grante de notre glossaire.<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit de l&rsquo;exploitation par la mise en ligne ouverte de toute une s\u00e9rie de <em>dde.crisis<\/em> des ann\u00e9es 2010-2013 (s&rsquo;entend, la rubrique essentielle dite <em>dedefensa<\/em> de chaque num\u00e9ro). On dispose d\u00e9j\u00e0, dans nos archives, d&rsquo;un r\u00e9sum\u00e9, d&rsquo;un aper\u00e7u du contenu, des th\u00e8mes, etc., de ces num\u00e9ros \u00e0 mesure de la parution dans la \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/section-analyse_ddecrisis.html\">sous-rubrique<\/a>\u00a0\u00bb (ici, c&rsquo;est le cas de le dire) <em>Analyse-dde.crisis<\/em> int\u00e9gr\u00e9e dans la rubrique <em>Analyse<\/em>. Tous ces textes constituaient des r\u00e9sum\u00e9s analytiques du contenu des num\u00e9ros de <em>dde.crisis<\/em> correspondants, &ndash; cela \u00e0 partir du num\u00e9ro du 25 mai 2010 (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_des_special_relationships_en_embuscade_ddecrisis_27_05_2010.html\">27 mai 2010<\/a>). Bien entendu, le contenu complet du num\u00e9ro est infiniment plus riche que ces r\u00e9sum\u00e9s-aper\u00e7us, et il ne fut accessible, jusqu&rsquo;aux tout derniers num\u00e9ros de la s\u00e9rie (fin 2013), qu&rsquo;aux abonn\u00e9s puis par paiement, num\u00e9ro par num\u00e9ro. Nous pensons que le d\u00e9lai de prescription du au paiement est largement \u00e9chu et que nous pouvons, sans crainte de l\u00e9ser personne, exploiter le contenu de ces <em>dde.crisis<\/em>.<\/p>\n<\/p>\n<p><p>L&rsquo;introduction de cette nouvelle \u00ab\u00a0dimension\u00a0\u00bb du <em>Glossaire.dde<\/em> sera signal\u00e9e par une d\u00e9nomination diff\u00e9rente lorsqu&rsquo;un <em>dde.crisis<\/em> sera exploit\u00e9 : le titre de la rubrique passera de <em>Glossaire.dde<\/em> \u00e0 <em>Glossaire.dde-crisis<\/em>. Cet exercice se fera selon plusieurs r\u00e8gles que nous allons d\u00e9tailler ci-dessous. D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, la premi\u00e8re de ces r\u00e8gles, qui est g\u00e9n\u00e9rale et concerne la rubrique, et qui est faite pour permettre une int\u00e9gration compl\u00e8te de <em>Glossaire.dde-crisis<\/em> dans la rubrique, est qu&rsquo;il n&rsquo;y aura aucune chronologie oblig\u00e9e dans la production et le rangement des nouveaux articles. On peut tr\u00e8s bien trouver trois <em>Glossaire.dde-crisis<\/em> avant de revenir \u00e0 un <em>Glossaire.dde<\/em> normal, ou un seul <em>Glossaire.dde-crisis<\/em> suivi de un, deux ou trois <em>Glossaire.dde<\/em> normaux.<\/p>\n<\/p>\n<p><p>D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, nous attendons que l&rsquo;introduction de ces <em>Glossaire.dde-crisis<\/em> apporte l&rsquo;exploration de sujets plus diversifi\u00e9s et plus composites que les sujets normalement trait\u00e9s dans le <em>Glossaire.dde<\/em>. Il ne s&rsquo;agit <strong>en aucun cas<\/strong> d&rsquo;une critique pour l&rsquo;une ou l&rsquo;autre formule, mais du constat qu&rsquo;ainsi la rubrique <em>Glossaire.dde<\/em> va s&rsquo;\u00e9largir et s&rsquo;enrichir, tout en conservant bien entendu l&rsquo;orientation g\u00e9n\u00e9rale d\u00e9velopp\u00e9e jusqu&rsquo;ici. En un sens, cet apport permet de mieux r\u00e9pondre \u00e0 la d\u00e9finition de la rubrique : &laquo;<em>Cette nouvelle rubrique n&rsquo;a pas simplement une forme d&rsquo;explication statique, elle a aussi une forme d&rsquo;analyse dynamique.<\/em>&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Les r\u00e8gles du jeu<\/h3>\n<\/p>\n<p><p>Voici donc les principales r\u00e8gles du \u00ab\u00a0jeu\u00a0\u00bb consistant \u00e0 int\u00e9grer <em>Glossaire.dde-crisis<\/em> dans <em>Glossaire.dde<\/em>. On verra qu&rsquo;elles sont faites, pour la plupart, pour disposer d&rsquo;un maximum de libert\u00e9 \u00e0 l&rsquo;int\u00e9rieur du rangement que nous voudrions organiser pour l&rsquo;int\u00e9gration dans la rubrique.<\/p>\n<\/p>\n<p><p>&bull; Nous ne serons nullement tenus par l&rsquo;ordre chronologique de parution des num\u00e9ros de <em>dde.crisis<\/em>. Nous les choisissons selon la pertinence du sujet par rapport \u00e0 nos r\u00e9flexions, par rapport aux diverses \u00ab\u00a0v\u00e9rit\u00e9s de situation\u00a0\u00bb, par rapport enfin aux exigences de l&rsquo;\u00e9volution des fondements de la situation catastrophique pr\u00e9sente du monde. Bien entendu, chaque texte sera accompagn\u00e9, pr\u00e9c\u00e9d\u00e9 en fait, d&rsquo;une sorte d&rsquo;introduction donnant toutes les indications chronologiques n\u00e9cessaires et des explications du choix de l&rsquo;inscrire dans ce <em>Glossaire.dde-crisis<\/em>.<\/p>\n<\/p>\n<p><p>&bull; Le texte sera retranscrit d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale tel qu&rsquo;il fut \u00e9crit et publi\u00e9 \u00e0 son \u00e9poque (sauf pour une coquille tra&icirc;nant ici ou l\u00e0, voire une maladresse formelle d&rsquo;\u00e9criture qui demande r\u00e9paration). Par contre, il y aura une sorte de \u00ab\u00a0commentaire\u00a0\u00bb venu du \u00ab\u00a0temps pr\u00e9sent\u00a0\u00bb, &ndash; car la pens\u00e9e \u00e9volue et la contraction du temps nourrit d&rsquo;autant plus cette \u00e9volution, &ndash; sous la forme de notes sur tel ou tel point de d\u00e9tail, sur tel ou tel sens d&rsquo;un jugement, montrant effectivement cette \u00e9volution et observant la fa\u00e7on dont cette \u00e9volution s&rsquo;est faite. Il s&rsquo;agit d&rsquo;une \u00ab\u00a0actualisation\u00a0\u00bb dans le sens le plus large possible, puisqu&rsquo;il s&rsquo;agit <strong>aussi et surtout<\/strong> d&rsquo;une volont\u00e9 de poursuivre, d&rsquo;\u00e9largir, d&rsquo;enrichir, de transmuter \u00e9ventuellement les diff\u00e9rents concepts expos\u00e9s, comment\u00e9s et document\u00e9s. On ne se trouve donc nullement dans le cas syst\u00e9matique d&rsquo;une reprise d&rsquo;archives telles quelles, mais d&rsquo;une reprise d&rsquo;archives en relation directe avec les \u00e9v\u00e9nements courants (de notre temps pr\u00e9sent), et surtout en relation serr\u00e9e avec l&rsquo;\u00e9volution de la pens\u00e9e depuis la publication de ces textes.<\/p>\n<\/p>\n<p><p>&bull; Il n&rsquo;est nullement assur\u00e9 que nous incluions dans le <em>Glossaire.dde-crisis<\/em> tous les num\u00e9ros parus. Certains th\u00e8mes trait\u00e9s sont directement li\u00e9s \u00e0 une actualit\u00e9 de l&rsquo;\u00e9poque et peuvent \u00eatre, &ndash; encore est-ce \u00e0 voir et nous verrons, &ndash; jug\u00e9s d\u00e9pass\u00e9s et sans peu d&rsquo;int\u00e9r\u00eat pour le d\u00e9bat pr\u00e9sent de la pens\u00e9e, l\u00e0 o&ugrave; nous en sommes. Ou bien, certains de ces textes peuvent \u00eatre tout de m\u00eame repris, mais alors avec un appareil critique actuel particuli\u00e8rement ac\u00e9r\u00e9, mettant en \u00e9vidence ce que l&rsquo;actualit\u00e9 \u00e9v\u00e9nementielle peut, dans certains cas, constituer d&rsquo;appauvrissement d&rsquo;une pens\u00e9e qui doit continuellement chercher \u00e0 utiliser les \u00e9v\u00e9nements courants pour se nourrir au niveau le plus haut, c&rsquo;est-\u00e0-dire au niveau le plus \u00ab\u00a0intemporel\u00a0\u00bb possible. Dans cet exercice pourra \u00eatre mieux cern\u00e9e, ici d&rsquo;une fa\u00e7on plus critique que l\u00e0, notre m\u00e9thodologie d&rsquo;utiliser les \u00e9v\u00e9nements pour entretenir et nourrir une pens\u00e9e qui, par d\u00e9finition, ne peut \u00eatre prisonni\u00e8re des \u00e9v\u00e9nements. Dans certains cas limites de r\u00e9f\u00e9rence trop marqu\u00e9e aux \u00e9v\u00e9nements, on pourra mettre en \u00e9vidence l&rsquo;utilisation trop timide de notre concept d'\u00a0\u00bbinconnaissance\u00a0\u00bb dont l&rsquo;op\u00e9rationnalisation dans ce cas est d&rsquo;utiliser certains \u00e9v\u00e9nements \u00e0 notre guise, et d&rsquo;\u00e9carter la n\u00e9cessit\u00e9 de les comprendre compl\u00e8tement selon la situation \u00e9v\u00e9nementielle qui les d\u00e9termine. Cette r\u00e8gle est ici \u00e9mise sans aucune id\u00e9e pr\u00e9con\u00e7ue, c&rsquo;est-\u00e0-dire sans savoir si effectivement nous \u00e9carterons tel ou tel texte de <em>dde.crisis<\/em>, ou si nous les reprendrons tous.<\/p>\n<\/p>\n<p><p>&bull; Il est tout \u00e0 fait possible qu&rsquo;un <em>Glossaire.dde-crisis<\/em> qui nous para&icirc;t particuli\u00e8rement \u00ab\u00a0intemporel\u00a0\u00bb et toujours tr\u00e8s pertinent par rapport \u00e0 notre pens\u00e9e \u00e0 son stade pr\u00e9sent, engendre un autre texte, qui serait alors un <em>Glossaire.dde<\/em> normal. Au contraire, un tel processus serait la meilleure justification possible \u00e0 une vision enrichie de cette d\u00e9marche d&rsquo;exhumer les <em>dde.crisis<\/em>. Le lien entre la pens\u00e9e actuelle et la pens\u00e9e d&rsquo;il y a trois ou quatre ans, m\u00eame s&rsquo;il s&rsquo;agit de l&rsquo;extr\u00eame d&rsquo;un lien critique pour souligner une erreur ou une fausse orientation, doit \u00eatre soulign\u00e9 constamment et exploit\u00e9 autant que faire se peut. L&rsquo;initiative <em>Glossaire.dde-crisis<\/em>, si elle est certes un moyen \u00e0 la fois de p\u00e9renniser <em>dde.crisis<\/em> et d&rsquo;enrichir le <em>Glossaire.dde<\/em> en acc\u00e9l\u00e9rant d&rsquo;une fa\u00e7on assez ais\u00e9e son rythme de parution, est aussi un moyen d&rsquo;enrichissement de la pens\u00e9e pr\u00e9sente. Il se pourrait m\u00eame qu&rsquo;il soit un moyen de modification, de r\u00e9orientation, etc., de la pens\u00e9e pr\u00e9sente. Nous n&rsquo;en savons rien parce que nous n&rsquo;avons pas relu ces textes depuis leur parution et ce sera pour nous une \u00ab\u00a0(re)-d\u00e9couverte\u00a0\u00bb de relire chaque texte, comme si nous ne les avions pas \u00e9crit nous-m\u00eames, comme si nous les lisions pour la premi\u00e8re fois et qu&rsquo;ils fussent d&rsquo;une autre plume que la n\u00f4tre.<\/p>\n<\/p>\n<p><p>&bull; Il est entendu que ces r\u00e8gles ne sont pas restrictives. D&rsquo;autres peuvent s&rsquo;imposer \u00e0 mesure que nous \u00ab\u00a0(re)-d\u00e9couvrons\u00a0\u00bb nos textes. A ce moment, la chose sera indiqu\u00e9e dans l&rsquo;introduction du texte qui nous sugg\u00e8re cette initiative.<\/p>\n<\/p>\n<p><p>&bull; Le premier texte <em>Glossaire.dde-crisis<\/em> est \u00e0 venir tr\u00e8s vite, l&rsquo;affaire de quelques jours. Notre choix est d\u00e9j\u00e0 fait, travail commenc\u00e9 ; le th\u00e8me est celui de \u00ab\u00a0la crise de la raison humaine\u00a0\u00bb, ou \u00ab\u00a0la raison humaine subvertie\u00a0\u00bb (concept, &ndash; la-raison-subvertie, &ndash; que nous utilisons beaucoup dans nos textes courants), avec le contenu du num\u00e9ro du 10 juillet 2010.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Glossaire.dde + Glossaire.dde-crisis 28 novembre 2014 &ndash; Nous introduisons une nouvelle \u00ab\u00a0dimension\u00a0\u00bb dans cette rubrique Glossaire.dde. Nous pourrions la nommer \u00ab\u00a0nouvelle rubrique\u00a0\u00bb, qui serait alors une sorte de \u00ab\u00a0sous-rubrique\u00a0\u00bb. Nous pr\u00e9f\u00e9rons \u00ab\u00a0dimension\u00a0\u00bb pour ne pas s\u00e9parer cette s\u00e9rie de sujets du reste, pour montrer qu&rsquo;il faut la consid\u00e9rer comme partie int\u00e9grante de notre glossaire. Il&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[19],"tags":[8254,8617,12038,9827,2642,5535],"class_list":["post-75625","post","type-post","status-publish","format-standard","hentry","category-glossairedde","tag-dde-crisis","tag-formule","tag-glossaire-dde","tag-humaine","tag-nouvelle","tag-raison"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75625"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75625\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}