{"id":75639,"date":"2014-12-02T17:48:17","date_gmt":"2014-12-02T17:48:17","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/12\/02\/qui-veut-du-pentagone-silence-de-mort\/"},"modified":"2014-12-02T17:48:17","modified_gmt":"2014-12-02T17:48:17","slug":"qui-veut-du-pentagone-silence-de-mort","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/12\/02\/qui-veut-du-pentagone-silence-de-mort\/","title":{"rendered":"Qui veut du Pentagone ? Silence de mort &#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Qui veut du Pentagone ? Silence de mort &#8230;<\/h2>\n<\/p>\n<p><p>La prestigieuse et tr\u00e8s-puissante fonction de secr\u00e9taire \u00e0 la d\u00e9fense est ainsi d\u00e9crit par Colin Clark, de <em>BreakingDefense.com<\/em> : &laquo;<em>&#8230;what is rapidly beginning to look like the rottenest job in town &mdash; leading the world&rsquo;s greatest military<\/em>&raquo; (\u00ab\u00a0&#8230; ce qui est en train de devenir le job le plus pourri en ville, &ndash; commander la plus grande puissance militaire du monde\u00a0\u00bb). Le temps passant et les rempla\u00e7ants d\u00e9sign\u00e9s d\u00e9clinant l&rsquo;offre les uns apr\u00e8s les autres donnent de plus en plus la mesure de ce que fut la destitution de Chuck Hagel ; une mesure injuste et arbitraire, li\u00e9e \u00e0 la politique totalement incoh\u00e9rente de la Maison-Blanche que l&rsquo;ancien secr\u00e9taire \u00e0 la d\u00e9fense est implicitement accus\u00e9 de n&rsquo;avoir pas suivie, ou de l&rsquo;avoir critiqu\u00e9e, ou les deux en m\u00eame temps&#8230; Trois \u00ab\u00a0candidats d\u00e9sign\u00e9s\u00a0\u00bb, comme on parle de \u00ab\u00a0volontaires d\u00e9sign\u00e9s\u00a0\u00bb, ont d\u00e9clin\u00e9 l&rsquo;offre, &ndash; Michelle Flournoy, le s\u00e9nateur d\u00e9mocrate Jack Reed et, plus r\u00e9cemment, le secr\u00e9taire \u00e0 la s\u00e9curit\u00e9 int\u00e9rieure (<em>Department of Homeland Security<\/em>) et ancien premier juriste du Pentagone, Jeh Johnson.<\/p>\n<\/p>\n<p><p>Colin Clark, d&rsquo;habitude s\u00e9rieux et respectueux des pouvoirs et des consignes, se fait extr\u00eamement sarcastique et irrespectueux dans son commentaire du <a class=\"gen\" href=\"http:\/\/breakingdefense.com\/2014\/12\/defense-secretary-does-anyone-want-this-job\/?utm_source=Breaking+Defense&#038;utm_campaign=e923e9b20c-RSS_EMAIL_CAMPAIGN&#038;utm_medium=email&#038;utm_term=0_4368933672-e923e9b20c-407346369\">1er d\u00e9cembre 2014<\/a>. Il se demande pourquoi on a <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_syst_me_a_vir_hagel_25_11_2014.html\">vir\u00e9 Hagel<\/a> alors que ceux qui devraient l&rsquo;avoir \u00e9t\u00e9, ce sont les conseillers de s\u00e9curit\u00e9 nationale de la Maison-Blanche, qui se sont appropri\u00e9s \u00e0 peu pr\u00e8s tous les pouvoirs de Hagel (du secr\u00e9taire \u00e0 la d\u00e9fense) pour pouvoir mieux conduire les militaires dans le bordel indescriptible qu&rsquo;est devenue la politique de s\u00e9curit\u00e9 national de Sa Majest\u00e9 Obama-Saint, plong\u00e9e dans les contradictions, les changements d&rsquo;orientation et d&rsquo;humeur, les renversements d&rsquo;options, etc., qui mettent m\u00eame ces braves Fran\u00e7ais si polic\u00e9s et ob\u00e9issants dans des \u00e9tats de grande fureur &#8230;<\/p>\n<\/p>\n<p><p>&laquo;<em>The idea that Hagel needed replacing &mdash; and not the White House aides who have made such a hash of military and national security policy over the last 18 months &mdash; is one that seems hard to grasp. Bomb Syria and work with the French to destroy the Assad regime? Check. After a walk between White House chief of staff and President Obama, uncheck! I remember speaking with a senior French official soon after that decision. Details on how the public announcement about air strikes etc and had all been worked out between the two countries and then, poof! Policy changed. The French, to put it gently, were bemused&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Dans ce grand foutoir qu&rsquo;est Washington D.C. du temps d&rsquo;Obama, dans cet imbroglio qu&rsquo;est le d\u00e9part de Chuck Hagel, on en est \u00e0 envisager de nommer un sous-fifre, ou peut-\u00eatre le portier \u00e0 ce poste prestigieux, ou peut-\u00eatre, &ndash; pourquoi pas, maintenir Hagel \u00ab\u00a0d\u00e9missionnaire\u00a0\u00bb jusqu&rsquo;\u00e0 la fin de l&rsquo;administration Obama, histoire d&rsquo;exp\u00e9dier les affaires courantes.<\/p>\n<\/p>\n<p><p>&laquo;<em>The only good news I can see in all this for the Obama administration is that they don&rsquo;t need to worry about replacing a second senior Cabinet position now that Johnson&rsquo;s pulled out. We appear left with Deputy Defense Secretary Bob Work, former deputy secretary Ash Carter and, perhaps, Air Force Secretary Deborah Lee James as the only people who haven&rsquo;t yet turned the administration down as it hunts for a new Cabinet-level appointee to lead the U.S. military. Or are White House officials already effectively doing that job?<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Perhaps Hagel and Obama will discuss this when they meet tomorrow morning at the White House.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Le jour pr\u00e9c\u00e9dent, le <a class=\"gen\" href=\"http:\/\/www.ronpaulinstitute.org\/archives\/featured-articles\/2014\/november\/30\/who-wants-to-be-defense-secretary\/\">30 novembre 2014<\/a>, sur le site de son institut, Ron Paul posait une question correspondant assez bien \u00e0 l&rsquo;\u00e9tat d&rsquo;esprit qu&rsquo;on voit chez Colin Clark : &laquo;<em>Who Wants To Be Defense Secretary?<\/em>&raquo; Paul rel\u00e8ve que les pr\u00e9d\u00e9cesseurs de Hagel (Gates et Panetta), sans doute comme Hagel lui-m\u00eame, se sont eux aussi am\u00e8rement plaint de ce qu&rsquo;on nomme le \u00ab\u00a0<em>micromanagment<\/em>\u00a0\u00bb de la d\u00e9fense par la clique de la Maison-Blanche &#8230;<\/p>\n<\/p>\n<p><p>&laquo;<em>The president&rsquo;s first two Defense Secretaries, Robert Gates and Leon Panetta, both complained bitterly this month about their time in the administration. The president&rsquo;s National Security Council staff micro-managed the Pentagon, they said at a forum last week. Former Secretary Gates revealed that while he was running the Defense Department, the White House established a line of communication to the Joint Special Operations Command to discuss matters of strategy and tactics, cutting the Defense Secretary out of the loop. His successor at the Pentagon, Leon Panetta, made similar complaints.<\/em>&raquo;<\/p>\n<\/p>\n<p><p><em>A contrario<\/em>, Ron Paul tend \u00e0 d\u00e9mentir indirectement la premi\u00e8re version du d\u00e9part de Hagel (\u00ab\u00a0les <em>neocons<\/em> ont eu la peau de Hagel\u00a0\u00bb), d&rsquo;abord parce que, comme nous l&rsquo;avons observ\u00e9, Hagel n&rsquo;avait justement aucune influence ni capacit\u00e9 de diriger la politique et la strat\u00e9gie de s\u00e9curit\u00e9 nationale puisque c&rsquo;est justement le constat que tous font, &ndash; y compris les <em>neocons<\/em> eux-m\u00eames ! Car c&rsquo;est l\u00e0 que le d\u00e9sordre devenant hyper-d\u00e9sordre de Washington D.C. est mis en \u00e9vidence, par le seul fait du refus de Michelle Flournoy de succ\u00e9der \u00e0 Gates. <em>Neocon<\/em> pur jus elle-m\u00eame, &ndash; pourquoi ce refus puisqu&rsquo;ainsi s&rsquo;offrait \u00e0 elle ce poste que les <em>neocons<\/em> auraient jug\u00e9 usurp\u00e9 par cette redoutable colombe de Hagel ? Flournoy, justement, selon Ron Paul, qui attend Hillary Clinton, &ndash; Godot attendu(e) comme salvatrice de la Grande R\u00e9publique avec quelques guerres de plus fourr\u00e9es dans son sac-\u00e0-dos Herm\u00e8s (hypoth\u00e8se, pour la marque)&#8230;<\/p>\n<\/p>\n<p><p>&laquo;<em>Shortly after Chuck Hagel&rsquo;s ouster, the media reported that the president favored Michelle Flournoy to replace him. She would have been the first female defense secretary, but more tellingly she would come to the position from a think tank almost entirely funded by the military industrial complex. The Center for a New American Security, which she founded in 2007, is the flagship of the neocon wing of the Democratic Party. The Center has argued against US troops ever leaving Iraq and has endorsed the Bush administration&rsquo;s doctrine of preventative warfare. The Center is perhaps best known for pushing the failed counterinsurgency (COIN) doctrine in Iraq and Afghanistan. The COIN doctrine was said at the time to have been the key to the US victory in Iraq and Afghanistan. Now that the US is back in Iraq and will continue combat operations in Afghanistan next year, you don&rsquo;t hear too much about COIN and victories.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Flournoy turned down Obama before she was even asked, however. She is said to be waiting for a Hillary Clinton presidency, where her militarism may be even more appreciated. With the next Senate to be led by neocons like John McCain, a Hillary Clinton presidency would find little resistance to a more militaristic foreign policy.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>D\u00e9cid\u00e9ment, la conclusion est in\u00e9vitable : l&rsquo;hyper-d\u00e9sordre r\u00e8gne d\u00e9sormais en ma&icirc;tre absolu dans la direction am\u00e9ricaniste, avec un ma&icirc;tre du domaine \u00e0 la baguette, le pr\u00e9sident Barack Obama lui-m\u00eame. Cela nous vaut une situation in\u00e9dite car jamais dans l&rsquo;histoire de la Grande R\u00e9publique modernis\u00e9e en <em>National Security State<\/em> (NSS), m\u00eame au temps du Watergate o&ugrave; les ministres valsaient d&rsquo;un poste \u00e0 l&rsquo;autre (en sept mois, de janvier \u00e0 juillet 1973, trois secr\u00e9taires \u00e0 la d\u00e9fense successivement, Richardson, Clements et Schlesinger), une de ces \u00ab\u00a0grosses pointures\u00a0\u00bb sollicit\u00e9es ne refusa cette fonction prestigieuse qui est un des piliers du susdit NSS, qui n\u00e9cessite une personnalit\u00e9 d&rsquo;envergure \u00e0 sa t\u00eate, qui ne peut souffrir de vacance infamante ou de nomination par raccroc. On peut se fixer sur ce fait historique pour mieux mesurer l&rsquo;\u00e9tat de d\u00e9labrement du pouvoir \u00e0 Washington.<\/p>\n<\/p>\n<p><p>La responsabilit\u00e9 de cette hyper-d\u00e9sordre de Washington ainsi si symboliquement mis en \u00e9vidence, revient \u00e9videmment \u00e0 l'\u00a0\u00bbhomme le plus puissant du monde\u00a0\u00bb, cet \u00e9trange Iago qui, un jour, semble \u00eatre \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-iago_l_impromptu_de_brisbane_18_11_2014.html\">le Mal incarn\u00e9<\/a>\u00a0\u00bb pour un Poutine, comme Bhadrakumar en faisait la remarque concernant le G20 de Brisbane, qui semble l&rsquo;\u00eatre, deux semaines plus tard, comme dans une \u00e9trange et radicale inversion, pour Washington et le centre m\u00eame du pouvoir le plus puissant \u00e0 l&rsquo;int\u00e9rieur du Syst\u00e8me. Que penser de tout cela si ce n&rsquo;est songer \u00e0 l&rsquo;hyper-d\u00e9sordre, ou d\u00e9sordre extr\u00eame devenant, \u00e0 force d&rsquo;inversion et de simulacre, un hyper-d\u00e9sordre se retournant contre le Syst\u00e8me lui-m\u00eame ?<\/p>\n<\/p>\n<p><p>Nous en viendrions \u00e0 plaindre le pauvre Pentagone, apr\u00e8s tout, le fameux et terrible <em>Moby Dick<\/em> qui a besoin d&rsquo;un capitaine Achab d&rsquo;une certaine hauteur pour pouvoir donner toute sa surpuissance. (L&rsquo;image de <em>Moby Dick<\/em> \u00e9tait du secr\u00e9taire \u00e0 la d\u00e9fense Cohen, homme politique et po\u00e8te \u00e0 ses heures, qui confiait en 1998 \u00e0 <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-regarder_le_monstre_dans_les_yeux_james_carroll_et_le_pentagone_20_07_2006.html\">James Carroll<\/a> ce que c&rsquo;\u00e9tait qu&rsquo;\u00eatre secr\u00e9taire \u00e0 la d\u00e9fense au milieu de ce monstre tentaculaire dont on verrait bien vite qu&rsquo;il est capable d&rsquo;encaisser un Boeing 757 sur une de ses fa\u00e7ades sans broncher, comme \u00e0 la parade, par un beau jour au ciel bleu \u00e9clatant d&rsquo;un mois de septembre, &ndash; et ensuite, continuer sa <em>narrative<\/em> sur son innocence et sur ses vertus sans prendre la peine de reprendre son souffle&#8230;)<\/p>\n<\/p>\n<p><p>Mais attention au symbole &#8230; La terrible inculture symbolique de Barack Obama lui fait ignorer la n\u00e9cessit\u00e9 de la pr\u00e9sence imp\u00e9rieuse de <em>Moby Dick<\/em> dans la <em>narrative<\/em> imp\u00e9riale de la Grande R\u00e9publique. Ce sont ses pratiques arrogantes et pleines d&rsquo;un \u00e9trange <em>hybris<\/em>, invers\u00e9 lui aussi, &ndash; l&rsquo;<em>hybris<\/em> de la non-d\u00e9cision par d\u00e9cisions autodestructrices les unes des autres, du genre \u00ab\u00a0ne faisons rien, nous ne ferons pas de conneries\u00a0\u00bb, &ndash; qui le conduisent \u00e0 une centralisation mortelle par paralysie, au d\u00e9dain des coutumes et des puissances du Syst\u00e8me qui nourrit l&rsquo;impuissance, \u00e0 l&rsquo;ignorance des privil\u00e8ges des p\u00f4les de puissance du Syst\u00e8me qui ouvre la voie de l&rsquo;autodestruction \u00e0 la surpuissance. Les P\u00e8res Fondateurs et m\u00eame Eisenhower et son <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-un_g_n_ral-pr_sident_nous_parle_du_complexe_militaro-industriel_10_08_2005.html\">discours<\/a> sur le complexe militaro-industriel se retournent dans leurs tombes, d&rsquo;indignation de voir cette fonction prestigieuse devenue sous la plume sans grandeur d&rsquo;un Colin Clark \u00ab\u00a0le job le plus pourri <em>in town<\/em>\u00ab\u00a0. Dans la course qu&rsquo;il a prise, Obama est en train de liquider le statut et le fondement d&rsquo;une des fonctions-clef du Syst\u00e8me. <em>Moby Dick<\/em> laiss\u00e9 \u00e0 lui-m\u00eame (ou confi\u00e9 \u00e0 un sous-fifre, cela revient au m\u00eame), cela risque de faire des vagues&#8230;<\/p>\n<\/p>\n<p><p>Et Ron Paul, plein d&rsquo;espoir malgr\u00e9 son \u00e2ge canonique qui ne lui \u00f4te rien de sa verdeur d&rsquo;esprit, termine son pensum par un avertissement qu&rsquo;il voudrait sans doute solennel et qu&rsquo;il juge fort justement plein de bon sens, que personne n&rsquo;entendra parce que plus personne n&rsquo;\u00e9coute plus personne \u00e0 Washington D.C. : &laquo;<em>So President Obama cannot keep defense secretaries on the job and his top Pentagon pick is not interested in serving the last stretch of a lame duck administration. There is bickering and fighting within the administration about who should be running the latest US wars in the Middle East and elsewhere. Here is one thing none of them are fighting about: the US policy of global intervention&#8230;<\/em> [&#8230;] <em>There is no real foreign policy debate in Washington. But the real national security crisis<\/em> <strong><em>will come when their militarism finally cripples our economy and places us at the mercy of the rest of the world.<\/em><\/strong>&raquo;<\/p>\n<\/p>\n<p><p>Bref, il faudra bien que l&rsquo;Empire grim\u00e9 en artefact simili-historique comme on dit simili-cuir craque et s&rsquo;effondre d&rsquo;une fa\u00e7on ou l&rsquo;autre. <em>Moby Dick<\/em> sans capitaine Achab digne de ce nom est candidat pour la chose, parmi d&rsquo;autres. Qui vivra verra&#8230;<\/p>\n<\/p>\n<p><p>Mis en ligne le 2 d\u00e9cembre 2014 \u00e0 17H48<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui veut du Pentagone ? Silence de mort &#8230; La prestigieuse et tr\u00e8s-puissante fonction de secr\u00e9taire \u00e0 la d\u00e9fense est ainsi d\u00e9crit par Colin Clark, de BreakingDefense.com : &laquo;&#8230;what is rapidly beginning to look like the rottenest job in town &mdash; leading the world&rsquo;s greatest military&raquo; (\u00ab\u00a0&#8230; ce qui est en train de devenir le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[831,3369,3168,8608,3019,7921,15312,4841,16208,16207,2622,6521,3140,3310,6907,7900,2626],"class_list":["post-75639","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-a","tag-carroll","tag-clark","tag-colin","tag-defense","tag-dick","tag-flournoy","tag-hagel","tag-hyper-centralisation","tag-hyper-decordre","tag-la","tag-moby","tag-paul","tag-ron","tag-secretaire","tag-symbole","tag-watergate"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75639"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75639\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}