{"id":75649,"date":"2014-12-09T16:41:15","date_gmt":"2014-12-09T16:41:15","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/12\/09\/des-drones-ukrainiens-abattus-en-crimee\/"},"modified":"2014-12-09T16:41:15","modified_gmt":"2014-12-09T16:41:15","slug":"des-drones-ukrainiens-abattus-en-crimee","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/12\/09\/des-drones-ukrainiens-abattus-en-crimee\/","title":{"rendered":"Des drones ukrainiens abattus en Crim\u00e9e"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Des drones ukrainiens abattus en Crim\u00e9e<\/h3>\n<\/p>\n<p><p>\tDiscr\u00e8tement et sans gu\u00e8re de d\u00e9tails inutiles, des sources militaires russes ont inform\u00e9 l&rsquo;agence Novosti (voir <em>Sputnik.News<\/em> le <a href=\"http:\/\/sputniknews.com\/russia\/20141209\/1015647016.html\" class=\"gen\">9 d\u00e9cembre 2014<\/a>) que plusieurs drones ukrainiens avaient \u00e9t\u00e9 abattus au-dessus de la Crim\u00e9e, qui a \u00e9t\u00e9 rattach\u00e9e \u00e0 la Russie en mars dernier et dont Kiev annonce r\u00e9guli\u00e8rement et pompeusement le reconqu\u00eate prochaine. Les sources ne pr\u00e9cisent ni le nombre de drones, ni la chronologie pr\u00e9cise o\u00f9 ces diverses interventions ont eu lieu sinon que ces interceptions et ces destructions ont \u00e9t\u00e9 r\u00e9alis\u00e9es le mois dernier, ni les circonstances sinon les observations classiques sur les proc\u00e9dures utilis\u00e9es \u00e0 cet \u00e9gard (interception au franchissement de la fronti\u00e8re, communication pour recommander un changement de vol, destruction en cas de poursuite de la mission). Une pr\u00e9cision technique est donn\u00e9e : ce sont des aff\u00fbts mobiles <em>Pantsir<\/em>, avec \u00e9quipement mixte canons (2) de 30mm\/missiles \u00e0 courte port\u00e9e, qui ont \u00e9t\u00e9 utilis\u00e9s.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Russia has shot down several Ukrainian unmanned surveillance aircrafts flying over the Crimean Peninsula from the North over the last month using Pantsir (Greyhound) surface-to-air missile systems, a Crimean military source told RIA Novosti on Tuesday. Pantsirs have been used against the targets by the division based close to the Chongar Isthmus, the military source said. After recognizing the unmanned surveillance aircraft, it is intercepted on the border with the command of capturing and escort. If the unmanned surveillance aircraft flies deep into our territory or approaches a military facility, then it is shot down, the source added. The number of surveillance aircrafts destroyed by Russian missiles was not specified.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa discr\u00e9tion des Russes, leur stricte observation du secret dans des cas sensibles et des mati\u00e8res militaires (op\u00e9rationnelles et autres) rendent d&rsquo;autant plus significatives ces r\u00e9v\u00e9lations. Les sources \u00e9tant officielles, il est tout \u00e0 fait probable qu&rsquo;elles ont donn\u00e9 leurs informations avec l&rsquo;accord des autorit\u00e9s politiques, et dans un but politique autant qu&rsquo;op\u00e9rationnel. Plusieurs conclusions de type politique\/op\u00e9rationnel peuvent \u00eatre tir\u00e9es dans le cadre d&rsquo;une hypoth\u00e8se interpr\u00e9tative.<\/p>\n<\/p>\n<p><p>\t D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, ces interventions signifient aux observzteurs et aux directions politiques que la Crim\u00e9e est bien un territoire russe, que ce territoire est \u00e9quip\u00e9 pour sa d\u00e9fense comme tout territoire russe et qu&rsquo;aucune violation de souverainet\u00e9 ne sera tol\u00e9r\u00e9e. La Crim\u00e9e n&rsquo;est pas une sorte de Pakistan ou de Yemen o\u00f9 les drones \u00e9trangers se baladent en toute impunit\u00e9.<\/p>\n<\/p>\n<p><p>\t Ces interventions, donn\u00e9es au compte-goutte mais avec pr\u00e9cision, tendent \u00e0 mettre en \u00e9vidence l&rsquo;efficacit\u00e9 de la d\u00e9fense a\u00e9rienne russe install\u00e9e e Crim\u00e9e. Si l&rsquo;autre c\u00f4t\u00e9 voulait \u00eatre inform\u00e9 \u00e0 cet \u00e9gard par ses incursions, il l&rsquo;est d\u00e9sormais,  et nous aussi, preuve que nous sommes aussi bien dans la guerre de communication que dans l&rsquo;op\u00e9rationnel <em>covert<\/em>.<\/p>\n<\/p>\n<p><p>\t La pr\u00e9cision concernant le syst\u00e8me qui et intervenu pour ces destructions peut \u00e9galement \u00eatre interpr\u00e9t\u00e9es comme une indication selon laquelle la d\u00e9fense a\u00e9rienne install\u00e9e en Crim\u00e9e est s\u00e9rieuse, dans le sens o\u00f9 elle dispose d&rsquo;une panoplie pour toutes les sortes d&rsquo;intervention n\u00e9cessaire. (On sait par ailleurs qu&rsquo;un escadron de Soukhoi Su-30 d&rsquo;interception a \u00e9t\u00e9 d\u00e9tach\u00e9 de son escadre-m\u00e8re d&rsquo;une base russe plus au Nord pour \u00eatre d\u00e9ploy\u00e9 en Crim\u00e9e, pour les t\u00e2ches plus classiques de police de l&rsquo;espace a\u00e9rien.)<\/p>\n<\/p>\n<p><p>\t Enfin la pr\u00e9cision selon laquelle ces destructions ont eu lieu le mois dernier, sans pr\u00e9ciser ce qui s&rsquo;est pass\u00e9 avant, laisse \u00e0 penser que les Russes voudraient qu&rsquo;on en conclut qu&rsquo;eux-m\u00eames ont conclu, sinon qu&rsquo;ils ont la certitude que ces drones sont d&rsquo;origine \u00e9trang\u00e8re \u00e0 l&rsquo;Ukraine. Les drones ne sont nullement un \u00e9quipement courant des forces ukrainiennes, et les tentatives ukrainiennes officielles de s&rsquo;en \u00e9quiper faites aupr\u00e8s des Isra\u00e9liens n&rsquo;ont jusqu&rsquo;ici pas donn\u00e9 grand&rsquo;chose (voir notamment le <a href=\"http:\/\/www.dedefensa.org\/article-isra_l_refuse_une_commande_d_armes_de_kiev_17_09_2014.html\" class=\"gen\">17 septembre 2014<\/a>.). Ces r\u00e9v\u00e9lations nous inviteraient donc \u00e0 conclure que les Russes estiment ou savent que les drones ont \u00e9t\u00e9 d\u00e9ploy\u00e9s et sont utilis\u00e9s par des non-Ukrainiens,  c&rsquo;est-\u00e0-dire, poursuivons l&rsquo;hypoth\u00e8se, par exemple par la CIA qui en est si coutumi\u00e8re,  <em>Who else<\/em>?<\/p>\n<\/p>\n<p><p>\t\u00c9largissons maintenant le propos. Cette impression de professionnalisme, de discr\u00e9tion et d&rsquo;efficacit\u00e9 qui \u00e9mane de ces informations rencontre les appr\u00e9hensions du bloc BAO, surtout des USA, concernant les capacit\u00e9s russes, notamment, \u00e0 partir de l&rsquo;information sur la destruction des drones ukrainiens, dans le domaine de la missilerie sol-air. A cet \u00e9gard, des informations nouvelles plus g\u00e9n\u00e9rales ont filtr\u00e9  du c\u00f4t\u00e9 du bloc BAO.<\/p>\n<\/p>\n<p><p>\tDes sources militaires et du renseignement US ont comment\u00e9 ces derni\u00e8res jours que la livraison pr\u00e9vue de S-400 \u00e0 la Chine, apr\u00e8s signature d&rsquo;un contrat de vente (voir le <a href=\"http:\/\/www.dedefensa.org\/article-des_s-400_russes_pour_la_chine_01_12_2014.html\" class=\"gen\">1er d\u00e9cembre 2014<\/a>), constituait un acte militaire tr\u00e8s pr\u00e9occupant pour les forces US. Ces sources confirment que les USA et le bloc BAO n&rsquo;ont rien d&rsquo;\u00e9quivalent au S-400 et aucun moyen de contre-mesures s\u00e9rieux contre ces engins, ce qui constitue une \u00e9norme hypoth\u00e8que pour l&#8217;emploi de l&rsquo;aviation offensive en cas de conflit. La seule incertitude qui plane, selon ces sources, est de savoir si les Russes livreront aux Chinois les S-400 au standard maximal qui \u00e9quipent leurs propres forces. L&rsquo;hypoth\u00e8ses classique serait qu&rsquo;ils ne le feraient pas, les Russes \u00e9tant extraordinairement prudents pour ce qui est des livraisons d&rsquo;armement sophistiqu\u00e9s et de transfert de technologies. Mais les nouveaux liens strat\u00e9giques entre la Russie et la Chine brouillent toutes les donn\u00e9es disponibles jusqu&rsquo;ici, selon ces sources, et les hypoth\u00e8ses classiques pourraient s&rsquo;av\u00e9rer d&rsquo;ores et d\u00e9j\u00e0 obsol\u00e8tes,  et les S-400 \u00e0 livrer au standard russe lui-m\u00eame&#8230;<\/p>\n<\/p>\n<p><p>\tDans le m\u00eame domaine de la missilerie russe (mais aussi chinoise, voire iranienne), ces m\u00eames sources pr\u00e9cisent que la  principale menace, \u00e0 c\u00f4t\u00e9 de la puissance des capacit\u00e9s sol-air de la Russie, concerne le domaine des missiles antinavires (sol-mer, mer-mer, air-mer). Les sources militaires du bloc BAO (US) sont extr\u00eamement impressionn\u00e9s par le d\u00e9veloppement de missiles antinavires, surtout russes et chinois, extr\u00eamement rapides (dans l&rsquo;hypersonique vars Mach 4\/Mach 5), \u00e9lectroniquement tr\u00e8s prot\u00e9g\u00e9s,  rendant l&rsquo;interception incroyablement complexe, pour ne pas dire impossible,  \u00e0 grande port\u00e9e et \u00e0 charge explosive tr\u00e8s lourde. Ces missiles sont destin\u00e9s \u00e0 frapper les porte-avions US, et \u00e0 les frapper tr\u00e8s durement, \u00e0 la mani\u00e8re dont les Japonais frapp\u00e8rent les cuirass\u00e9s de la Flotte du Pacifique \u00e0 Pearl Harbor&#8230; C&rsquo;est dire le peu d&rsquo;enthousiasme de l&rsquo;US Navy pour les politiques bellicistes antirusse et antichinoise pratiqu\u00e9es par la direction politique \u00e0 Washington .<\/p>\n<\/p>\n<p><p>\tCe type d&rsquo;arme a presque un caract\u00e8re d&rsquo;arme navale absolue, en fonction des capacit\u00e9s et des structures op\u00e9rationnelles de la puissance de l&rsquo;US Navy. S&rsquo;il s&rsquo;av\u00e8re qu&rsquo;un missile ou des missiles anti-porte-avions existent, c&rsquo;est un risque de paralysie de l&rsquo;US Navy \u00e0 cause de la psychose qui na\u00eetrait : le nombre tr\u00e8s r\u00e9duit de grands porte-avions d&rsquo;attaque qui rassemblent l&rsquo;essentiel de la puissance navale US ,  10 actuellement, dont 5-6 en d\u00e9ploiement offensif par rotation, avec les n\u00e9cessit\u00e9s d&rsquo;entretien, de car\u00e9nages, etc.,  inciterait \u00e0 des mesures de prudence telles que cette flotte, offensive par essence, en deviendrait presque d\u00e9fensive par repli strat\u00e9gique et priverait la Navy de ses capacit\u00e9s de contr\u00f4le global des mers. Cela, sans parler de la catastrophe que constituerait la perte d&rsquo;un  ou de plusieurs porte-avions, qui serait per\u00e7u comme une sorte de 9\/11 (\u00e0 nouveau l&rsquo;image de Pearl Harbor) pour la puissance militaire US,  mais un 9\/11 sans puissance militaire derri\u00e8re pour organiser une riposte, puisque c&rsquo;est cette puissance militaire elle-m\u00eame qui serait atteinte et affreusement handicap\u00e9e.<\/p>\n<\/p>\n<p><p>\tDans le m\u00eame ordre d&rsquo;id\u00e9e, et alors que les n\u00e9gociations avec l&rsquo;Iran sur le nucl\u00e9aire tournent \u00e0 l&rsquo;\u00e9chec, ces sources pr\u00e9cisent encore que l&rsquo;US Navy consid\u00e8re le Golfe Persique comme un pi\u00e8ge mortel, d&rsquo;o\u00f9 elle retirerait le plus vite possible l&rsquo;un ou l&rsquo;autre porte-avions s&rsquo;il s&rsquo;y trouvait, en cas de risque de conflit. La c\u00f4te iranienne est absolument h\u00e9riss\u00e9e et truff\u00e9e de postes de tir de missiles dont au moins la moiti\u00e9 sont dissimul\u00e9s et non identifi\u00e9s, et donc ne pouvant \u00eatre d\u00e9truits par des attaques pr\u00e9ventives&#8230; <\/p>\n<\/p>\n<p><p>\tAinsi la situation de tension g\u00e9n\u00e9rale et les <strong>v\u00e9ritables conditions de la possibilit\u00e9 de conflit<\/strong> existant depuis le d\u00e9but de la crise ukrainienne poussent les strat\u00e8ges militaires US (les s\u00e9rieux, pas les strat\u00e8ges <em>neocons<\/em> des <em>think tanks<\/em>) \u00e0 consid\u00e9rer les r\u00e9alit\u00e9s de la situation strat\u00e9gique g\u00e9n\u00e9rale. Le r\u00e9sultat n&rsquo;est pas si exaltant qu&rsquo;on croit. La puissance US est consid\u00e9rable, certes, mais elle est sur-projet\u00e9es et elle est en plus sur-concentr\u00e9es dans des points de force (comme les porte-avions) qui doivent \u00eatre n\u00e9cessairement invuln\u00e9rables. Une soudaine modification de circonstances ou de capacit\u00e9s techniques, ou les deux, pourrait brusquement faire basculer l&rsquo;h\u00e9g\u00e9monie de cette puissance en la rendant brusquement vuln\u00e9rable et en la for\u00e7ant \u00e0 se replier sur une d\u00e9fensive qui serait <strong>en totale contradiction<\/strong> avec la politique expansionniste des USA (du bloc BAO). Dans ces circonstances o\u00f9 la Russie (et la Chine, et quelques autres) tendent \u00e0 progresser vers une mise sur pied de guerre de leurs capacit\u00e9s, les USA se d\u00e9couvrent des faiblesses potentiellement fond\u00e9es sur des d\u00e9s\u00e9quilibres, des ad\u00e9quations ou des contradictions structurelles qui impliquent des possibilit\u00e9s d&rsquo;effondrement menant \u00e0 des changements dramatiques de fortune politique.<\/p>\n<\/p>\n<p><p>\tAinsi se d\u00e9finit toute la puissance (la militaire et les autres) du bloc BAO (des USA) et de notre contre-civilisation : consid\u00e9rable, \u00e9norme, \u00e9crasante dirait-on, mais aussi de plus en plus en d\u00e9s\u00e9quilibre constant et de plus en plus instable, avec des possibilit\u00e9s d&rsquo;effondrement grandissantes, sans \u00e9tapes interm\u00e9diaires permettant un repli, un redressement, une contre-attaque. La situation est toujours plus celle du tout ou rien tandis que le tout ne cesse de vaciller de plus en plus.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 9 d\u00e9cembre 2014 \u00e0 16H42<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des drones ukrainiens abattus en Crim\u00e9e Discr\u00e8tement et sans gu\u00e8re de d\u00e9tails inutiles, des sources militaires russes ont inform\u00e9 l&rsquo;agence Novosti (voir Sputnik.News le 9 d\u00e9cembre 2014) que plusieurs drones ukrainiens avaient \u00e9t\u00e9 abattus au-dessus de la Crim\u00e9e, qui a \u00e9t\u00e9 rattach\u00e9e \u00e0 la Russie en mars dernier et dont Kiev annonce r\u00e9guli\u00e8rement et pompeusement&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[16230,3977,2932,3723,3176,2773,2774,16229,3319,3175,16228,5220,3704,8289,3959,1296,2671],"class_list":["post-75649","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antinavires","tag-chine","tag-drone","tag-golfe","tag-harbor","tag-iran","tag-israel","tag-missilerie","tag-navy","tag-pearl","tag-pentsir","tag-persique","tag-porte-avions","tag-s-400","tag-sol-air","tag-ukraine","tag-us"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75649"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75649\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}