{"id":75668,"date":"2014-12-22T05:31:04","date_gmt":"2014-12-22T05:31:04","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/12\/22\/loption-nucleaire-i-do-not-object\/"},"modified":"2014-12-22T05:31:04","modified_gmt":"2014-12-22T05:31:04","slug":"loption-nucleaire-i-do-not-object","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/12\/22\/loption-nucleaire-i-do-not-object\/","title":{"rendered":"L&rsquo;\u201coption nucl\u00e9aire\u201d? \u00ab<em>I do not object&#8230;<\/em>\u00bb"},"content":{"rendered":"<p><h3 class=\"titrebloc\">L&rsquo;option nucl\u00e9aire? \u00ab<em>I do not object&#8230;<\/em>\u00bb<\/h3>\n<\/p>\n<p><p>\tDaniel McAdams est directeur d\u00e9l\u00e9gu\u00e9 du Ron Paul Peace Institute. Parlementaire \u00e0 la Chambre des Repr\u00e9sentants pendant 12 ans, au c\u00f4t\u00e9 de Ron Paul, McAdams conna\u00eet parfaitement l&rsquo;ontologie de la machine washingtonienne.,  le Syst\u00e8me r\u00e9gnant \u00e0 Washington, la fa\u00e7on dont fonctionne le Congr\u00e8s, le niveau d&rsquo;information incroyablement bas de ces parlementaires qui tiennent une partie du pouvoir de la plus d\u00e9structurante et destructrice puissance du monde, etc. Interview\u00e9 par <em>Russia Today<\/em> le <a href=\"http:\/\/rt.com\/op-edge\/215879-obama-bill-congress-military-russia\/\" class=\"gen\">19 d\u00e9cembre 2014<\/a>, McAdams explique le sens de cette loi vot\u00e9e dans les conditions surr\u00e9alistes de 3 voix exprim\u00e9es contre 0 (<em>unanimous consent<\/em>), telles que nous les avons pr\u00e9sent\u00e9es le <a href=\"http:\/\/www.dedefensa.org\/article-et_ainsi_se_d_cide_le_sort_du_monde_i_do_not_object_18_12_2014.html\" class=\"gen\">18 d\u00e9cembre 2014<\/a>.<\/p>\n<\/p>\n<p><p>\t(En passant, et d&rsquo;une fa\u00e7on tr\u00e8s int\u00e9ressante et instructive, McAdams approfondit les conditions de ce vote surr\u00e9aliste. Il est remarquable de noter que les instigateurs de cette manuvre sont des parlementaires de base, tr\u00e8s peu connus m\u00eame s&rsquo;ils occupent des postes dans des commissions puissantes, agissant \u00e9videmment et sans surprise au nom des lobbies concern\u00e9s, notamment celui des Ukrainiens \u00e0 Washington. On franchit ainsi un pas suppl\u00e9mentaire dans la dissolution du facteur humain au profit du Syst\u00e8me agissant \u00e0 visage d\u00e9couvert, sans la moindre vergogne, comme s&rsquo;il \u00e9tait chez lui, dans ce cas au Congr\u00e8s,  ce qui est le cas, \u00e9videmment : le Syst\u00e8me est <strong>chez lui<\/strong> au Congr\u00e8s, <strong>il est<\/strong> le Congr\u00e8s. On n&rsquo;a m\u00eame plus besoin de vedettes type-McCain ou Lindsey Graham, avec leur notori\u00e9t\u00e9 m\u00e9diatique, leur vernis id\u00e9ologique qui maquille le forfait dans le genre hollywoodien. Quelques porte-flingue d&rsquo;occasion mais bien plac\u00e9s, qui ont \u00e9t\u00e9 arros\u00e9s juste ce qu&rsquo;il faut et qui ont leur conviction \u00e0 partir de l&rsquo;\u00e9dito du Washington <em>Post<\/em>, font l&rsquo;affaire,  et la loi est vot\u00e9e&#8230;)<\/p>\n<\/p>\n<p><p>\tObama n&rsquo;a pas ratifi\u00e9 cette loi mais il la tient en r\u00e9serve, sous le coude. Il s&rsquo;agit d&rsquo;une loi qui, dans le code des usages du Congr\u00e8s, repr\u00e9sente une autorisation implicite d&#8217;employer tous les moyens que le pr\u00e9sident jugera n\u00e9cessaire dans son action contre la Russie &#8230; Cette action du pr\u00e9sident qui, selon McAdams, repr\u00e9sente une guerre totale, pour l&rsquo;instant \u00e9conomique,  l&rsquo;option nucl\u00e9aire du domaine de la guerre \u00e9conomique. Nous citons abondamment cette interview, qui d\u00e9voile les r\u00e9elles conditions de l&rsquo;action US actuelle contre la Russie, et les risques de guerre totale qu&rsquo;elles impliquent,  pour l&rsquo;instant dans le domaine \u00e9conomique, mais avec aucun obstacle infranchissable pour aller au-del\u00e0. (C&rsquo;est ce que nous nommions, le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_tout_pour_le_pire_1998_2008_17_12_2014.html\" class=\"gen\">17 d\u00e9cembre 2014<\/a>, le tout pour le pire, estimant implicitement et m\u00eame explicitement que, pour les USA, tenter le tout pour le tout c&rsquo;est se diriger inexorablement vers le pire&#8230;)<\/p>\n<\/p>\n<p><p>\t<strong><em>Russia Today<\/em><\/strong> : \u00ab<em>President Obama recently cautioned that the policy of sanctions might not be as effective as first projected. And yet we see him signing a bill that authorizes more restrictions against Moscow. How do you interpret the move?<\/em><\/p>\n<\/p>\n<p><p>\t<strong><em>Daniel McAdams<\/em><\/strong> : \u00ab<em>I think it&rsquo;s interesting. Just yesterday when the President announced a major change in policy towards Cuba he said that 50 years of sanctions hasn&rsquo;t worked, it doesn&rsquo;t work. Doing the same over and over again and expecting a different result is counter-productive. So he recognizes that it doesn&rsquo;t work. The most important thing about this bill, I think, there are two things First of all, what is essentially is a placeholder authorization for an enormous amount of money not just for military aid, but money to increase US propaganda broadcasts into the region. What it is similar to is the 2002 authorization for war against Iraq when Congress said, Here is the authorization, use it if you need to, whenever you need to. No need to contact us, here you go. And that is essentially what Congress is doing  it is giving the President this authorization. The second part that is most important is the way this bill was passed. It was brought up at night after all the other members went home; it was three members of Congress who colluded to bring this effort after everyone was gone. That was Ed Royce, the Chairman of the House Foreign Affairs Committee, Eliot Engel who was also on the Committee and Marcy Kaptur, a democrat from Ohio, who was a co-Chair of the House Ukrainian Caucus. The bill was brought up and passed within a minute; there was nobody there to object. The first and only statement that Marcy Kaptur made was that Russia had invaded Ukraine and this is a response. Well, the bills like this are generally written by special interests. So my guess is there was some Ukrainian special interest group that passed it through the Ukraine Caucus to Marcy Kaptur and it went up the flag to Ed Royce, the Chairman of the Committee. So this is all very underhanded in a nefarious way of passing a very significant escalation bill.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Russia Today<\/em><\/strong> : \u00ab<em>The Russian ruble has been making small gains in recent days. Do you think this bill could turn the tide again?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Daniel McAdams<\/em><\/strong> : \u00ab<em>I think that&rsquo;s a pincer movement that the US and its allies are using against Russia. The US, it is well-known from many news reports, has been colluding with Saudi Arabia to reduce the price of oil significantly, which certainly has hurt the Russian bottom line. When you combine that with sanctions that restrict the ability of Russia to raise currency on international markets, you have a pincer move. I would call it a nuclear first strike option against the Russian economy. The US is turning a blind eye to the repercussions, a retaliatory strike, will you call it unintended consequences against its own economy. It seems that they are going to try to take down the Russian economy. Who knows what kind of resources they will apply to this, I believe, a full-hearted attempt.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Russia Today<\/em><\/strong> : \u00ab<em>The bill also authorizes lethal aid for Ukraine. If supplied, what effect could US arms have on the ongoing crisis in the east of the country?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Daniel McAdams<\/em><\/strong> : \u00ab<em>This bill doesn&rsquo;t only authorize US$350 million for arms, which is by the way a huge Christmas gift to the US defense contractors. But it also sets forth the US policy, which is that Kiev should attempt to get back the territories in eastern Ukraine, essentially giving them a green light for an attack. That is an enormously significant development on that front.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Russia Today<\/em><\/strong> : \u00ab<em>Washington made it clear on several occasions that it&rsquo;s open for dialogue. How does that correspond with its actions?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Daniel McAdams<\/em><\/strong> : \u00ab<em>This is called coercive diplomacy. Dialogue presupposes that you accept the dictate of the other partner. This is what the US has been doing with Iran for the past year or so. It has the appearance of diplomatic talks but in reality the other partner has to concede major points, has to give up its position before the US will engage in a dialogue. Coercive diplomacy doesn&rsquo;t have a very good track record.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Russia Today<\/em><\/strong> : \u00ab<em>How do you see events unfolding from here? Do you think that the US will pursue its policy of sanctions even further?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Daniel McAdams<\/em><\/strong> : \u00ab<em>People should understand how limited the information inputs are to members of Congress. I served as a member of Congress for 12 years and I know other members of the Foreign Affairs Committee, and I know what the information inputs they have. That&rsquo;s exclusively newspapers like The Washington Post, The Wall Street Journal who are absolutely one-sided in their propaganda. These papers are more lock stepped than Pravda would have been in a height of the Soviet Union. So their inputs are only one sort, and these people absolutely dominate the discussion in Washington right now. The handful of members of Congress who are somewhat uneasy can easily be ignored, and that&rsquo;s what is happening. So it&rsquo;s very dangerous and it reminds us of what happened a hundred years ago when there was arrogance and ignorance combining to lead to a horrible conflagration. And I fear something radical doesn&rsquo;t change quickly, that&rsquo;s exactly where we are heading.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t&#8230; Bien s\u00fbr, tout le monde,  c&rsquo;est-\u00e0-dire tout le monde chez ceux qui en ont la volont\u00e9 et la possibilit\u00e9 par leur position antiSyst\u00e8me,  tout le monde se sent transport\u00e9 d&rsquo;ironie et secou\u00e9 d&rsquo;un rire un peu nerveux (un peu inquiet pour la sant\u00e9 mentale de ceux qui font marcher la pseudo-politique US), lorsqu&rsquo;un jour Obama annonce que <strong>le demi-si\u00e8cle de sanctions<\/strong> contre Cuba n&rsquo;a servi \u00e0 <strong>rien<\/strong>, et que le lendemain il annonce de nouvelles sanctions contre la Russie. C&rsquo;est un aspect remarquable par la proximit\u00e9 des choses de ce qu&rsquo;Alexander Mercouris (voir le <a href=\"http:\/\/www.dedefensa.org\/article-une_victoire_de_cuba_gr_ce_au_syst_me_21_12_2014.html\" class=\"gen\">21 d\u00e9cembre 2014<\/a>) nomme \u00ab<em>the profoundly dysfunctional nature of the US decision-making process, where changing even the most obviously unsuccessful policy is extraordinarily difficult<\/em>\u00bb. Dans ce cas, il s&rsquo;agit de l&rsquo;impuissance totale de faire \u00e9voluer mentalement l&rsquo;id\u00e9e que puisque Cuba d\u00e9montre que la politique des sanctions ne donnent g\u00e8re de r\u00e9sultat, la politique des sanctions appliqu\u00e9e \u00e0 la Russie n&rsquo;a gu\u00e8re de chance d&rsquo;en donner plus. M\u00eame cloisonnement mental pour la diplomatie coercitive, en \u00e9chec av\u00e9r\u00e9 d\u00e9sormais avec l&rsquo;Iran, et qui est appliqu\u00e9e avec z\u00e8le avec la Russie.<\/p>\n<\/p>\n<p><p>\t&#8230; De tout cela sort une seule certitude op\u00e9rationnelle : aujourd&rsquo;hui, tout est concentr\u00e9 sur la Russie, ou plut\u00f4t <strong>contre la Russie<\/strong>. Aucun enseignement, aucune d\u00e9monstration concernant la validit\u00e9 des politiques appliqu\u00e9es, aucun souci des cons\u00e9quences ne parvient \u00e0 interf\u00e9rer sur cette nouvelle politique obsessionnelle qui constitue l&rsquo;ultime obsession en mati\u00e8re de politique des USA (l&rsquo;importance de la Russie fait l&rsquo;affaire), c&rsquo;est-\u00e0-dire sa pathologie destructrice au service du Syst\u00e8me conduite \u00e0 son terme d&rsquo;activit\u00e9s d\u00e9structurantes et dissolvantes. Le danger est \u00e0 mesure, extr\u00eamement grand, puisque toute la puissance US, pour l&rsquo;instant sur le plan \u00e9conomique, est et va continuer \u00e0 \u00eatre d\u00e9velopp\u00e9e contre la Russie, quelles qu&rsquo;en soient les cons\u00e9quences. (\u00ab<em>The US is turning a blind eye to the repercussions, a retaliatory strike, will you call it unintended consequences against its own economy.<\/em>\u00bb) Son exp\u00e9rience du Congr\u00e8s permet \u00e0 McAdams de pr\u00e9ciser la signification des mesures que le Congr\u00e8s est en train de voter, comme ce vote surr\u00e9aliste de la Chambre des Repr\u00e9sentants : moins des mesures sp\u00e9cifiques contre la Russie (l&rsquo;administration s&rsquo;en charge, qui suit \u00e0 cet \u00e9gard les tendances les plus extr\u00eames) qu&rsquo;une carte blanche donn\u00e9e \u00e0 l&rsquo;administration pour agir contre la Russie, comme le Congr\u00e8s le fit pour le cas irakien en 2002. C&rsquo;est \u00e0 ce point qu&rsquo;on r\u00e9alise qu&rsquo;au dysfonctionnement total du pouvoir impuissant et paralys\u00e9 \u00e0 Washington s&rsquo;ajoutent tous les aspects si sp\u00e9cifiques de la psychologie am\u00e9ricaniste, pour contribuer \u00e0 cette pouss\u00e9e offensive ; et la politique ainsi produite, confirmant par l&rsquo;absurde  l&rsquo;impuissance et la paralysie du pouvoir washingtonien, devient compl\u00e8tement la <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\" class=\"gen\">politique-Syst\u00e8me<\/a>, exactement comme si le Syst\u00e8me \u00e9tait \u00e0 la fois l&rsquo;inspirateur et le moteur de ce que nous prenons encore pour une politique US sp\u00e9cifique, comme s&rsquo;il \u00e9tait ontologiquement cette politique. (Mais certainement, le si est inutile,  il ne s&rsquo;agit pas de savoir si le Syst\u00e8me dirige en tout, il s&rsquo;agit de constater que c&rsquo;est bien le cas.) Les r\u00e9f\u00e9rences que donne McAdams renvoient effectivement \u00e0 une politique de cette sorte, mais lorsqu&rsquo;il s&rsquo;agit de l&rsquo;affrontement avec la Russie et qu&rsquo;aucune mesure, aucune prudence ne nuance cette politique,  alors il s&rsquo;agit bien absolument de la politique-Syst\u00e8me qui est par d\u00e9finition une politique que n&rsquo;influence aucun \u00e9l\u00e9ment \u00e9tranger \u00e0 elle-m\u00eame, et c&rsquo;est le Syst\u00e8me, et ce n&rsquo;est <strong>que le Syst\u00e8me<\/strong> qui est en action.<\/p>\n<\/p>\n<p><p>\tAinsi consid\u00e9rerions-nous que ces analyses d&rsquo;un McAdams qui conna\u00eet si bien le fonctionnement de Washington constituent l&rsquo;un des signes les plus convaincants de l&rsquo;extr\u00eame dangerosit\u00e9 de l&rsquo;actuelle situation. Nous dirions que l&rsquo;enjeu ne se situe pas du tout du c\u00f4t\u00e9 des concessions que pourrait faire Poutine, de sa faiblesse suppos\u00e9e de reculer devant les pressions US ou de son habilet\u00e9 envisag\u00e9e \u00e0 contenir les effets de ces pressions, voire \u00e0 sa capacit\u00e9 de manuvre (<a href=\"http:\/\/www.dedefensa.org\/article-r_sistance_et_autodestruction_02_07_2012.html\" class=\"gen\">faire<\/a> <em>a\u00efkido<\/em>) pour reprendre l&rsquo;offensive \u00e0 son avantage, mais bien \u00e0 l&rsquo;aveuglement complet des USA \u00e0 cet \u00e9gard, dans l&rsquo;\u00e9tat d&rsquo;esprit-Syst\u00e8me o\u00f9 ils se trouvent, sous le complet empire du Syst\u00e8me. Rien de ce que fera Poutine, rien de ce que fera la Russie, m\u00eame en imaginant les pires capitulations, ne satisferont les USA qui recherchent finalement une sorte d&rsquo;objectif mythique, un qu\u00eate pathologique : une sorte de  situation schizophr\u00e9nique qui devrait d\u00e9montrer la justesse de leur obsession,  savoir, que la Russie n&rsquo;existe pas, dans tous les cas qu&rsquo;elle disparaisse, en un sens que tout se passe comme si elle n&rsquo;avait jamais exist\u00e9, et ainsi n&rsquo;existerait-elle plus. Leonid Chebarchine, l&rsquo;ancien chef des services de renseignement ext\u00e9rieur du FBS, l&rsquo;ex-KGB, r\u00e9sumait au printemps dernier la situation sur un plan concret, r\u00e9aliste, en disant : \u00ab<em>L&rsquo;Ouest<\/em> [les USA] <em>ne veut qu&rsquo;une chose de la Russie : que la Russie n&rsquo;existe plus.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAinsi, la partie ne se joue pas vraiment entre les USA et la Russie, entre le soi-disant Empire et ses conqu\u00eates-d\u00e9j\u00e0-faites tant il (l&rsquo;Empire) serait irr\u00e9sistible ; elle se joue, sur les questions fondamentales habituelles, entre les USA et les USA, \u00e0 l&rsquo;int\u00e9rieur d&rsquo;eux-m\u00eames, dans une psychologie collective dont la pathologie est sans doute d&rsquo;une puissance sans peu de pr\u00e9c\u00e9dents dans l&rsquo;histoire des psychologies collectives&#8230; Elle se joue fondamentalement sur le fait de savoir si la politique-Syst\u00e8me, lorsqu&rsquo;elle confrontera les USA avec la possibilit\u00e9 devenant probabilit\u00e9 que sa guerre \u00e9conomique totale doive \u00eatre parachev\u00e9e par des pressions dans d&rsquo;autres domaines (essentiellement le domaine militaire), avec la possibilit\u00e9 effective d&rsquo;action, ne va pas finir par provoquer une sorte de r\u00e9volte dans certains compartiments \u00e0 la fois tr\u00e8s puissants et tr\u00e8s sp\u00e9cialis\u00e9s de la r\u00e9partition des centres de pouvoir \u00e0 Washington. (En effet, nous pensons plus que jamais que la politique de guerre \u00e9conomique totale contre la Russie ne donnera aucun r\u00e9sultat d\u00e9cisif pour les USA,  \u00e0 l&rsquo;extr\u00eame tr\u00e8s improbable, le d\u00e9sordre apocalyptique en Russie, mais fort probablement sinon immanquablement une r\u00e9action de d\u00e9fense furieuse de la Russie, Poutine ou pas Poutine ; car ce qui menace si Poutine devait abandonner le pouvoir, c&rsquo;est moins un r\u00e9gime-marionnette de la clique atlantiste-lib\u00e9rale qu&rsquo;un r\u00e9gime russe nationaliste et patriotique dur, \u00e9ventuellement militaire, avec la r\u00e9action qu&rsquo;on imagine.)<\/p>\n<\/p>\n<p><p>\tC&rsquo;est dire si, \u00e9non\u00e7ant cette hypoth\u00e8se (guerre \u00e9conomique totale&rsquo; parachev\u00e9e par des pressions dans d&rsquo;autres domaines), impliquant en fait le passage au domaine de la confrontation militaire, l&rsquo;on pense \u00e0 la possibilit\u00e9 de passer aux pressions militaires avec la possibilit\u00e9, au-del\u00e0, d&rsquo;un engagement militaire, et \u00e0 l&rsquo;hypoth\u00e8se chronologiquement secondaire mais politiquement essentielle d&rsquo;envisager qu&rsquo;une discorde int\u00e9rieure aux USA pousse \u00e0 une r\u00e9action de r\u00e9volte le centre de pouvoir qui devient le premier concern\u00e9 (les militaires) r\u00e9alisant les cons\u00e9quences catastrophiques <strong>pour toutes les parties<\/strong> (c&rsquo;est-\u00e0-dire pour toute la plan\u00e8te) de cette ouverture vers le suicide. (On garde \u00e0 l&rsquo;esprit la parole de Lincoln, encore r\u00e9cemment cit\u00e9e [voir le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_tout_pour_le_pire_1998_2008_17_12_2014.html\" class=\"gen\">17 d\u00e9cembre 2014<\/a>].) C&rsquo;est toujours selon cette m\u00eame logique que nous en revenons \u00e0 l&rsquo;affirmation que le v\u00e9ritable enjeu se situe bien dans la coh\u00e9sion de l&rsquo;architecture du pouvoir am\u00e9ricaniste, dans cette situation de tension extr\u00eame, et de logique autodestructrice pour lui-m\u00eame (m\u00eame s&rsquo;il entra\u00eene les autres dans sa chute). Nous en revenons \u00e0 cette m\u00eame alternative que nous avons \u00e9voqu\u00e9e d\u00e8s le d\u00e9but de la crise ukrainienne (voir par exemple le <a href=\"http:\/\/www.dedefensa.org\/article-la_guerre_est_en_r_paration_d_urgence_03_03_2014.html\" class=\"gen\">3 mars 2014<\/a>) :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>On comprend que ce qui nous rapproche de 1914, ce n&rsquo;est pas n\u00e9cessairement l&rsquo;\u00e9v\u00e9nement (la guerre) mais l&rsquo;esprit d&rsquo;un temps perdu dans une ivresse aveuglante et qui se trouve soudain confront\u00e9 aux r\u00e9alit\u00e9s catastrophiques de lui-m\u00eame. La crise ukrainienne, et la r\u00e9alisation que les pressions du Syst\u00e8me (du bloc BAO, son factotum) peuvent conduire \u00e0 l&rsquo;extr\u00eame catastrophique des affaires du monde, peuvent aussi bien, gr\u00e2ce au formidable choc psychologique dont nous parlons et \u00e0 l&rsquo;immense crainte qu&rsquo;il rec\u00e8le, d\u00e9clencher une autre dynamique d&rsquo;une puissance inou\u00efe. Notre hypoth\u00e8se \u00e0 cet \u00e9gard<\/em> [&#8230;] <em>est que cette dynamique est celle de l&rsquo;effondrement du Syst\u00e8me dont<\/em> <strong><em> rien, absolument rien<\/em><\/strong> <em>ne r\u00e9clame qu&rsquo;il se fasse dans l&rsquo;apocalypse nucl\u00e9aire, parce qu&rsquo;alors elle pourrait bien \u00eatre, cette dynamique, le fruit de la panique psychologique totale naissant de la perspective soudain apparue que le risque de la guerre nucl\u00e9aire existe plus que jamais&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa logique du pire r\u00e8gne donc, ce n&rsquo;est paradoxalement pas le pire de tout&#8230; Si l&rsquo;on peut juger catastrophique l&rsquo;aggravation de la situation actuelle du fait des USA, elle repr\u00e9sente en fait <strong>la seule chance<\/strong> que le r\u00e9gime US, c&rsquo;est-\u00e0-dire le Syst\u00e8me d\u00e9sormais \u00e0 visage d\u00e9couvert, se mette dans une position de confrontation interne qui pourrait susciter les conditions de la phase finale de l&rsquo;effondrement. Il faut se d\u00e9gager des raisonnements faussaires de la raison-subvertie (par le Syst\u00e8me), qui conduisent \u00e0 c\u00e9der devant le Syst\u00e8me de crainte d&rsquo;une situation s&rsquo;aggravant d&rsquo;une fa\u00e7on catastrophique. La vraie raison, d\u00e9barrass\u00e9e de sa subversion interne, dit que c&rsquo;est justement cette situation catastrophiquement aggrav\u00e9e qui peut conduire \u00e0 l&rsquo;\u00e9v\u00e9nement ultime (l&rsquo;effondrement). <strong>De toutes les fa\u00e7ons, nous n&rsquo;avons pas le choix<\/strong>, nous ne pouvons que tenter d&rsquo;analyser les \u00e9v\u00e9nements pour tenter de les comprendre. Ce sont des forces ext\u00e9rieures \u00e0 nous, les brillants <em>sapiens<\/em>, qui m\u00e8nent la danse, et celles qui animent le Syst\u00e8me emp\u00eacheront \u00e9videmment toute r\u00e9orientation raisonnable de la pseudo-politique US ; et nous n&rsquo;avons plus qu&rsquo;\u00e0 esp\u00e9rer que ce processus conduisent effectivement, avec la pression de forces ext\u00e9rieures oppos\u00e9es au Syst\u00e8me, \u00e0 la discorde int\u00e9rieure et \u00e0 l&rsquo;effondrement. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 22 d\u00e9cembre 2014 \u00e0 06H00<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;option nucl\u00e9aire? \u00abI do not object&#8230;\u00bb Daniel McAdams est directeur d\u00e9l\u00e9gu\u00e9 du Ron Paul Peace Institute. Parlementaire \u00e0 la Chambre des Repr\u00e9sentants pendant 12 ans, au c\u00f4t\u00e9 de Ron Paul, McAdams conna\u00eet parfaitement l&rsquo;ontologie de la machine washingtonienne., le Syst\u00e8me r\u00e9gnant \u00e0 Washington, la fa\u00e7on dont fonctionne le Congr\u00e8s, le niveau d&rsquo;information incroyablement bas de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6654,3359,2651,4751,2645,5616,5270,6653,16270,3004,6767,6934,4608,3140,15903,16271,4102,916,3099,3310,2861,3248],"class_list":["post-75668","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bout","tag-chambre","tag-du","tag-economique","tag-guerre","tag-impuissance","tag-interview","tag-jusquau","tag-macadam","tag-nucleaire","tag-obsession","tag-option","tag-paralysie","tag-paul","tag-pire","tag-politique-system","tag-politique-systeme","tag-poutine","tag-psychologie","tag-ron","tag-totale","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75668"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75668\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}