{"id":75691,"date":"2015-01-07T16:26:46","date_gmt":"2015-01-07T16:26:46","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/01\/07\/notes-sur-leur-confiance\/"},"modified":"2015-01-07T16:26:46","modified_gmt":"2015-01-07T16:26:46","slug":"notes-sur-leur-confiance","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/01\/07\/notes-sur-leur-confiance\/","title":{"rendered":"Notes sur LEUR confiance&#8230;"},"content":{"rendered":"<p><h2>Notes sur LEUR confiance&#8230; <\/h2>\n<\/p>\n<p><p>7 janvier 2014 &ndash; Nous allons prendre l&rsquo;occasion de remarques d&rsquo;un lecteur qui a r\u00e9agi en deux temps \u00e0 notre <em>Br\u00e8ve de crise<\/em> du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-au_commencement_tait_leur_confiance_05_01_2015.html\">5 janvier 2015<\/a>, qui n&rsquo;en demandait pas tant. Mais cette occasion est int\u00e9ressante et elle fait le larron. Ce lecteur soul\u00e8ve un probl\u00e8me lui-m\u00eame des plus int\u00e9ressants, qui <strong>ne peut pas<\/strong> se r\u00e9sumer \u00e0 quelques mots-bateaux et bien connus, &ndash; \u00ab\u00a0id\u00e9alisme\u00a0\u00bb, \u00ab\u00a0na\u00efvet\u00e9\u00a0\u00bb, \u00ab\u00a0r\u00e9alisme en politique\u00a0\u00bb, etc., et l&rsquo;on en passe tant , &ndash; un probl\u00e8me qui m\u00e9rite bien plus que cela.<\/p>\n<\/p>\n<p><p>&#8230; Bien avant de nous laisser filer dans nos habituels emportements, fureurs, ironies grin\u00e7antes et d&rsquo;autres, voici les attendus du d\u00e9lit. Elles sont donc d&rsquo;un lecteur, Mr. Alain Vit\u00e9, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/forum-au_commencement_tait_leur_confiance_05_01_2015.html\">5 janvier 2015<\/a>, dans le <em>Forum<\/em> de notre texte &laquo;<em>Au commencement \u00e9tait LEUR confiance<\/em>&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Erreur et honneur<\/h3>\n<\/p>\n<p><p>Voici donc, ramen\u00e9es \u00e0 l&rsquo;essentiel (on peut lire les textes entiers dans les r\u00e9f\u00e9rences\/liens donn\u00e9es ci-dessus), les remarques de ce lecteur :<\/p>\n<\/p>\n<p><p>&laquo;<em>Ne pas r\u00e9diger d&rsquo;accord \u00e9crit, c&rsquo;\u00e9tait offrir un blanc seing aux USA pour d\u00e9cha&icirc;ner leur soif de puissance d\u00e9vorante et maladive (cause pr\u00e9cise et racine de la Guerre Froide, justement) avec un air ing\u00e9nu et frais, sans que personne ne puisse rien leur reprocher puisque rien n&rsquo;\u00e9tait officiel.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Les Sovi\u00e9tiques ont commis une tr\u00e8s, tr\u00e8s grande faute : oublier la r\u00e9alit\u00e9 de la situation, dont on parle ici d&rsquo;habitude. Puisque c&rsquo;est important, revenons-y. Les USA n&rsquo;ont pas d&rsquo;honneur, ils n&rsquo;en ont jamais eu et ils ont \u00e9t\u00e9 d&rsquo;une parfaite constance en la mati\u00e8re depuis leur origine il y a plus de 250 ans, m\u00eame avec leurs alli\u00e9s. Alors face \u00e0 un ennemi mortel, surtout un ennemi mortel terrass\u00e9&#8230; <\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo;<em>O&ugrave; sont pass\u00e9s la lucidit\u00e9 et le courage d&rsquo;oser dire ce qui est vrai, qui sont la marque de fabrique de Dedefensa.org ? Vous n&rsquo;h\u00e9sitez en g\u00e9n\u00e9ral pas \u00e0 ramener sur terre et \u00e0 corriger bien des experts que vous estimez dans l&rsquo;erreur, surtout ceux que vous estimez tout court (les autres que vous n&rsquo;estimez pas, vous les hachez menus). Comment se fait-il que vous ne reprochiez pas \u00e0 ces gamins de tous \u00e2ges leur aveuglement devant la r\u00e9alit\u00e9 de la situation ? A savoir : ici le monde r\u00e9el, les USA y sont toujours les USA et ne sont toujours pas des gentlemen&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Deuxi\u00e8me message, qui compl\u00e8te le pr\u00e9c\u00e9dent : &laquo;<em>Il ne s&rsquo;agit pas de diaboliser les Etats-Unis \u00e0 bon compte, \u00ab\u00a0vade retro satanas\u00a0\u00bb, etc. Les rapports de force int\u00e9rieurs au pays et les luttes d&rsquo;int\u00e9r\u00eats y pr\u00e9sident \u00e0 tout, et bien des d\u00e9cisions ext\u00e9rieures servent \u00e0 soulager des tensions int\u00e9rieures. C&rsquo;est constitutif des USA et c&rsquo;est sa m\u00e9canique de fonctionnement. Ses strat\u00e9gies belles ou laides et fructueuses ou foireuses, ne sont que la cons\u00e9quence de cette m\u00e9canique, comme c&rsquo;est largement et finement document\u00e9 ici ann\u00e9e apr\u00e8s ann\u00e9e.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>La fin de la Guerre Froide a re\u00e7u le m\u00eame traitement US que toute autre situation, c&rsquo;est la d\u00e9mesure des enjeux et des possibilit\u00e9s qui en a rendu d\u00e9lirants les effets (et c&rsquo;est, du reste, le prolongement du fonctionnement colonial britannique depuis Elizabeth I, mais c&rsquo;est un autres sujet). C&rsquo;est de ces USA l\u00e0 qu&rsquo;il \u00e9tait question dans mon intervention pr\u00e9c\u00e9dente.<\/em>&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">L&rsquo;ivresse du \u00ab\u00a0tout est possible\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>Pour aborder l&rsquo;analyse qui servira \u00e0 la fois de r\u00e9ponse \u00e0 ces remarques et (surtout) de commentaires aux probl\u00e8mes soulev\u00e9s, nous allons faire d&rsquo;abord appel ici ou l\u00e0 au t\u00e9moignage direct de notre anc\u00eatre \u00e0 bord, Philippe Grasset. En effet, dans les remarques d\u00e9velopp\u00e9es se trouvent nombre de sentiments, d&rsquo;impressions, voire d&rsquo;anecdotes demandant l&#8217;emploi direct du propos, o&ugrave; Grasset parlera dans ce qui appara&icirc;tra comme une citation, souvent \u00e0 la premi\u00e8re personne. On s&rsquo;y reconna&icirc;tra, ces citations \u00e9tant entre guillemets et \u00e0 la premi\u00e8re personne, mais pas en italique comme le sont en g\u00e9n\u00e9ral les citations (comme on le voit plus loin avec de v\u00e9ritables citations) &#8230; Commen\u00e7ons par cela, par l&rsquo;essentiel de sa citation, &ndash; souvenirs de PhG d&rsquo;une d\u00e9cennie sans pareille.<\/p>\n<\/p>\n<p><p>&laquo; Je crois que cette impression g\u00e9n\u00e9rale a d\u00e9j\u00e0 \u00e9t\u00e9 \u00e9voqu\u00e9e ici et l\u00e0 sur ce site, mais il faut \u00e0 ce propos la r\u00e9p\u00e9ter. Les ann\u00e9es 1980 \u00e0 Bruxelles, o&ugrave; se trouvent l&rsquo;OTAN, l&rsquo;UE, etc., avec le tournant du 9 mars 1985 (nomination de Gorbatchev comme Premier Secr\u00e9taire du PC de l&rsquo;URSS), ont \u00e9t\u00e9 d&rsquo;une intensit\u00e9, d&rsquo;un rythme, d&rsquo;une vigueur, et d&rsquo;un caract\u00e8re compl\u00e8tement et constamment inattendus, qui n&rsquo;ont sans doute pas de pr\u00e9c\u00e9dent historique sur une p\u00e9riode d&rsquo;une telle longueur. Ce fut une p\u00e9riode presque magique, o&ugrave; tout semblait possible, une sorte de \u00ab\u00a0fen\u00eatre d&rsquo;opportunit\u00e9\u00a0\u00bb sur une v\u00e9ritable r\u00e9volution des conditions m\u00eames de l&rsquo;organisation du monde. Je passe ici sur les espoirs, arrangements, projets g\u00e9opolitiques boulevers\u00e9s qu&rsquo;entretenaient les uns et les autres&#8230; Je parle ici d&rsquo;un sentiment, d&rsquo;une atmosph\u00e8re,<strong> c&rsquo;est-\u00e0-dire d&rsquo;une perception<\/strong> relevant de la communication et de la psychologie, sans pr\u00e9cision n\u00e9cessaire d&rsquo;\u00e9v\u00e9nements ou de projets politiques, voire de complots tortueux, sans d\u00e9termination oblig\u00e9e d&rsquo;un vainqueur et d&rsquo;un vaincu, cette perception qui est presque de l&rsquo;ivresse du \u00ab\u00a0tout est possible\u00a0\u00bb&#8230; Et je parle \u00e9galement, pour ce qui concerne l&rsquo;Occident, non pas de vastes mouvements de foule face \u00e0 des appareils politiques retranch\u00e9s et terroris\u00e9s, mais bien au contraire d&rsquo;appareils politiques constitu\u00e9s et exer\u00e7ant le pouvoir, lanc\u00e9s activement dans ce mouvement, y participant, y contribuant, et surtout attach\u00e9s \u00e0 combattre les forces bureaucratiques qui constituaient, dans leurs camps, les seuls v\u00e9ritables freins au changement<\/p>\n<\/p>\n<p><p>&raquo; Je ne crois pas qu&rsquo;ailleurs qu&rsquo;\u00e0 Bruxelles et au jour le jour, dans cette ville qui connut son \u00e9poque de gloire en se transcendant hors de ses caract\u00e8res pesants, en \u00ab\u00a0oubliant\u00a0\u00bb presque compl\u00e8tement la Belgique pour devenir le carrefour de toutes les forces r\u00e9gissant le monde, on ait pu parfaitement saisir et se p\u00e9n\u00e9trer de cette p\u00e9riode d&rsquo;exception. Si j&rsquo;avais employ\u00e9 le mot de m\u00e9tahistoire, &ndash; que je d\u00e9daignais \u00e0 cette \u00e9poque si seulement je le connaissais, &ndash; il e&ucirc;t \u00e9t\u00e9 appropri\u00e9. Qui plus est pour renforcer la suggestion, la p\u00e9riode ainsi d\u00e9crite se divise exactement en deux (9 mars 1985), entre la nuit et le jour, la descente aux abysses sombres et la mont\u00e9e \u00e0 la lumi\u00e8re folle&#8230; Il y eut d&rsquo;abord l&rsquo;enfermement cr\u00e9pusculaire du bord de la guerre nucl\u00e9aire jusqu&rsquo;au paroxysme de 1983-1984, puis il y eut apr\u00e8s mars 1985 l&rsquo;explosion extraordinaire de nouvelles et de d\u00e9cisions, de suggestions, d&rsquo;hypoth\u00e8ses emport\u00e9es, de rencontres pleines de surprises, de mouvements lib\u00e9rateurs et lib\u00e9ratoires des esprits. Pendant cette p\u00e9riode, <strong>la politique ne ressembla plus \u00e0 ce qu&rsquo;elle est d&rsquo;habitude<\/strong>, &ndash; et cela embrasse notre fameux sujet des conf\u00e9rences et promesses de 1989-1990 qui nous r\u00e9unit ici.<\/p>\n<\/p>\n<p><p>&raquo; Je rapporte ici une anecdote qui r\u00e9sume tout, qui r\u00e9sume comment s&rsquo;improvisait au jour le jour, heure apr\u00e8s heure, ce qu&rsquo;on ne pouvait plus nommer \u00ab\u00a0politique\u00a0\u00bb. Cela se passait \u00e0 Bruxelles, au cours d&rsquo;un important colloque des 8-9 d\u00e9cembre 1988 \u00e0 Evere, au quartier-g\u00e9n\u00e9ral des forces arm\u00e9es belges qui est contigu \u00e0 l&rsquo;OTAN (un \u00ab\u00a0hasard\u00a0\u00bb, jurerait le na\u00eff, et \u00e0 cette \u00e9poque particuli\u00e8rement). Le th\u00e8me ne pouvait \u00eatre que la situation en Europe, la situation des forces, etc., c&rsquo;est-\u00e0-dire l&rsquo;ouragan Gorbatchev. Un intervenant US, un sp\u00e9cialiste incontest\u00e9 de l&rsquo;arme blind\u00e9e, consultant de l&rsquo;US Army, auteurs de nombreux articles d\u00e9finitifs et inspirateurs d&rsquo;une doctrine d&#8217;emploi des blind\u00e9s en coop\u00e9ration rapproch\u00e9e avec une nouvelle g\u00e9n\u00e9ration d&rsquo;engins a\u00e9riens comme l&rsquo;avion antichar type-A-10A, cet expert dont je ne parviens pas \u00e0 retrouver le nom devait donner une intervention sur la situation strat\u00e9gique des forces terrestres Est-Ouest en Europe, qui restaient encore fix\u00e9es \u00e0 leur niveau de la Guerre froide, dans ces moments d&rsquo;une fluidit\u00e9 politique extr\u00eame. En m\u00eame temps (8-9 d\u00e9cembre \u00e9galement) se tenait \u00e0 New York une r\u00e9union sp\u00e9ciale \u00e0 l&rsquo;ONU o&ugrave; parlait Gorbatchev. Il parla le premier jour et quitta brusquement New York le lendemain pour l&rsquo;Arm\u00e9nie, alors en URSS, o&ugrave; venait d&rsquo;avoir lieu un tremblement de terre. Il avait eu tout de m\u00eame le temps de dire des choses int\u00e9ressantes.<\/p>\n<\/p>\n<p><p>&raquo; &#8230; Notre orateur arriva au colloque le 9 au matin. Il vint directement \u00e0 la tribune, venu tout aussi directement de Zaventem o&ugrave; venait d&rsquo;atterrir l&rsquo;avion qui l&rsquo;amenait de Washington. Il avait en main le texte de la d\u00e9claration de Gorbatchev, qui \u00e9tait en train d&rsquo;\u00eatre faite ou venait d&rsquo;\u00eatre faite, et pas encore publique ou \u00e0 peine. On fit une rapide pr\u00e9sentation de l&rsquo;expert, il y eut des applaudissements, etc., puis la parole lui fut donn\u00e9e. Excellent ma&icirc;tre de l&rsquo;effet, il observa quelques secondes de silence, contemplant l&rsquo;assistance la main pos\u00e9e sur une vingtaine de feuillets qu&rsquo;il avait devant lui, le texte de son intervention. Puis il s&rsquo;en saisit avec brusquerie, se leva, avan\u00e7a sur le devant de l&rsquo;estrade et d\u00e9clara d&rsquo;une voix forte, &ndash; quelques mots en fran\u00e7ais, le reste <em>Made In USA<\/em>, &ndash; \u00ab\u00a0Voici mon intervention ! Trois semaines de travail, des documents secrets consult\u00e9s, des chiffres in\u00e9dits, eh bien voil\u00e0 ce que j&rsquo;en fais !\u00a0\u00bb Et il envoya valser sa vingtaine de feuillets dans les airs&#8230; Puis de s&rsquo;expliquer, sur un ton mi-sardonique, mi-ironique, mi-fataliste (comme dans le <em>Cesar<\/em> de Pagnol, le cocktail contient trois moiti\u00e9s) : \u00ab\u00a0Gorbatchev est en train de nous dire \u00e0 l&rsquo;ONU qu&rsquo;il a d\u00e9cid\u00e9 de retirer unilat\u00e9ralement 13 divisions d&rsquo;Europe de l&rsquo;Est ! Personne, vous entendez, personne n&rsquo;\u00e9tait au courant &#8230; Qu&rsquo;est-ce vous voulez que je vous dise ? Il a trois m\u00e9tros d&rsquo;avance, on n&rsquo;en peut plus \u00e0 essayer de le suivre, et moi avec mes vingt feuillets d&rsquo;un autre temps&#8230;\u00a0\u00bb (Mais il fit une intervention improvis\u00e9e sur le cauchemar d&rsquo;\u00eatre un expert par les temps qui couraient, qui fut tr\u00e8s dr\u00f4le.) Pendant de temps, dans une interview, William H. Webster, directeur de la CIA, geignait parce que, disait-il, \u00ab\u00a0l&rsquo;Agence affronte de tr\u00e8s s\u00e9rieux probl\u00e8mes en devant conseiller le pr\u00e9sident sur la fa\u00e7on d&rsquo;anticiper et de r\u00e9pondre \u00e0 des initiatives d&rsquo;un dirigeant sovi\u00e9tique innovateur et impr\u00e9visible\u00a0\u00bb&#8230;&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Coup d&rsquo;&Eacute;tat \u00ab\u00a0\u00e0-la-Gorbatchev\u00a0\u00bb de Bush-p\u00e8re<\/h3>\n<\/p>\n<p><p>Concernant cet \u00e9pisode, &ndash; il y en eut de multiples de cette sorte pendant la p\u00e9riode, &ndash; il y eut une \u00ab\u00a0r\u00e9plique sismique\u00a0\u00bb six mois plus tard. On voit \u00e0 quel point l&rsquo;action de Gorbatchev bousculait absolument tout, &ndash; non seulement la position sovi\u00e9tique, mais aussi la position occidentale et, bien entendu, la situation des relations Est-Ouest et par cons\u00e9quent la situation du reste du monde.<\/p>\n<\/p>\n<p><p>A la fin mai 1989, le pr\u00e9sident Bush (Bush-p\u00e8re) proposa lors d&rsquo;un sommet de l&rsquo;OTAN un d\u00e9sarmement des armes nucl\u00e9aires de courte port\u00e9e et des avions de combat affect\u00e9s \u00e0 cette t\u00e2che. Cette d\u00e9cision \u00e9tait annonc\u00e9e unilat\u00e9ralement, sans consultation d&rsquo;aucune sorte, y compris de tous les alli\u00e9s. La chose \u00e9clata comme une bombe et fut aussit\u00f4t interpr\u00e9t\u00e9e comme une \u00ab\u00a0r\u00e9ponse\u00a0\u00bb aux initiatives-Gorbatchev de d\u00e9cembre 1988, pour tenter de tenir le rythme. Un mois plus t\u00f4t, en avril, une r\u00e9union des ministres de la d\u00e9fense de l&rsquo;OTAN avait montr\u00e9 que la bureaucratie travaillait \u00e0 pleine vitesse, et semblait devoir triompher, pour d\u00e9cider de <strong>la modernisation<\/strong> de ce type d&rsquo;armements qui resteraient \u00e9videmment d\u00e9ploy\u00e9es, &ndash; le contraire de la proposition-Bush le mois suivant.<\/p>\n<\/p>\n<p><p>Que s&rsquo;\u00e9tait-il pass\u00e9 ? Bush-p\u00e8re avait simplement fait un coup d&rsquo;&Eacute;tat bureaucratique. Il avait saisi le dossier de ces armes des griffes de la bureaucratie, balanc\u00e9 aux orties le discours l\u00e9nifiant qu&rsquo;on lui proposait, rassembl\u00e9 autour de lui un petit groupe d&rsquo;experts (son conseiller de s\u00e9curit\u00e9 nationale Scowcroft, le secr\u00e9taire d&rsquo;&Eacute;tat Baker, l&rsquo;amiral Crowe, pr\u00e9sident du comit\u00e9 des chefs d&rsquo;\u00e9tat-major, etc.) pour travailler sur une d\u00e9cision <strong>exactement inverse<\/strong> et entrer dans le jeu de Gorbatchev. Ensemble, ils firent le discours-bombe du sommet de l&rsquo;OTAN. La bureaucratie US\/OTAN \u00e9tait furieuse mais tant pis pour elle.<\/p>\n<\/p>\n<p><p>Un commentateur fit cette observation absolument fondamentale que &laquo;<em>Bush menait d\u00e9sormais contre sa bureaucratie la m\u00eame bataille que Gorbatchev contre la sienne<\/em>&raquo;. (Une chose semblable, quoique moins \u00e9labor\u00e9e, s&rsquo;\u00e9tait produite en 1987. Reagan avait forc\u00e9 \u00e0 la signature d&rsquo;un trait\u00e9 FNI [Force Nucl\u00e9aires Interm\u00e9diaires\/de Th\u00e9\u00e2tre] avec l&rsquo;URSS \u00e0 un niveau z\u00e9ro-z\u00e9ro, &ndash; suppression compl\u00e8te de ces forces, &ndash; contre l&rsquo;avis forcen\u00e9 de sa bureaucratie qui voulait conserver un seuil minimal de telles forces en Europe et voulait un accord \u00e0 un chiffre r\u00e9duit par rapport au nombre de syst\u00e8mes d\u00e9ploy\u00e9s. Sorte de coup d&rsquo;&Eacute;tat bureaucratique, l\u00e0 aussi.) Il s&rsquo;av\u00e9rait alors que la \u00ab\u00a0r\u00e9volution-Gorbatchev\u00a0\u00bb touchait l&rsquo;Ouest \u00e9galement, o&ugrave; les directions politiques commen\u00e7aient \u00e0 se r\u00e9volter contre leurs bureaucraties du temps de la Guerre froide, comme Gorbatchev avait pulv\u00e9ris\u00e9 la sienne. La <strong>lecture vraie<\/strong> de la situation politique d&rsquo;alors balayait tous les antagonismes courants, les int\u00e9r\u00eats nationaux apparents imm\u00e9diats, etc. C&rsquo;\u00e9tait une v\u00e9rit\u00e9 de situation sans pr\u00e9c\u00e9dent.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">La sinc\u00e9rit\u00e9 de Gorbatchev<\/h3>\n<\/p>\n<p><p>&laquo; Voil\u00e0 l&rsquo;atmosph\u00e8re qui r\u00e9gnait depuis 1985 et qui perdura jusqu&rsquo;en 1991. Je me rappelle un article de l&rsquo;International Herald Tribune, ce devait \u00eatre en 1990 ou en 1991, o&ugrave; l&rsquo;auteur rapportait le d\u00e9sarroi des \u00e9lites US devant le fait que Washington \u00e9tait rel\u00e9gu\u00e9 \u00e0 un r\u00f4le provincial, que c&rsquo;\u00e9tait d\u00e9sormais Bruxelles qui jouait le r\u00f4le central de la rencontre Est-Ouest o&ugrave; se r\u00e9glaient toutes les affaires du monde, avec des liens nouveaux \u00e9tablis en toute h\u00e2te entre l&rsquo;Est et l&rsquo;Ouest, les visites constantes des chefs d&rsquo;\u00e9tat-major sovi\u00e9tiques \u00e0 l&rsquo;OTAN, quelques navires de l&rsquo;US Navy en visite d&rsquo;amiti\u00e9 \u00e0 Saint-Petersbourg, une vir\u00e9e du secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN Woerner \u00e0 Moscou, etc. Au niveau diplomatique, c&rsquo;\u00e9tait la m\u00eame atmosph\u00e8re d&rsquo;ivresse qui touchait absolument tous les c\u00f4t\u00e9s, Est et Ouest, et chacun ne songeait plus qu&rsquo;\u00e0 l&rsquo;opportunit\u00e9 de mettre en place une organisation g\u00e9n\u00e9rale du monde, hors des int\u00e9r\u00eats particuliers qui existaient toujours mais \u00e9taient rel\u00e9gu\u00e9s au second plan, compl\u00e8tement sur la d\u00e9fensive&#8230; &raquo;<\/p>\n<\/p>\n<p><p>Nous allons maintenant aborder le sujet central du texte qui concerne cet accord oral de non-extension de l&rsquo;OTAN. On gardera \u00e0 l&rsquo;esprit la puissance formidable du contraste r\u00e9gnant alors. &laquo; Ma conviction (dit Philippe Grasset) est que la suspicion, la m\u00e9fiance dominaient absolument les bureaucraties occidentales et les experts de seconde zone quant \u00e0 l&rsquo;action de Gorbatchev, mais qu&rsquo;au contraire les directions politiques \u00e9taient de plus en plus convaincues de la sinc\u00e9rit\u00e9 du Sovi\u00e9tique et faisait de plus en plus tout ce qu&rsquo;il fallait pour l&rsquo;aider dans sa lutte int\u00e9rieure, <strong>sans arri\u00e8re-pens\u00e9e ni plan machiav\u00e9lique<\/strong>. Tous ceux-l\u00e0 avaient la sensation de quelque chose d&rsquo;historique qui les d\u00e9passait. Il y avait une v\u00e9ritable confiance, la sensation de ces dirigeants de jouer ensemble contre des forces bureaucratiques et autres qui freinaient des quatre fers&#8230;&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Talleyrand, homme de caract\u00e8re<\/h3>\n<\/p>\n<p><p>Ici, nous \u00e9largissons le sujet pour mieux \u00e9tablir un pont entre la p\u00e9riode que nous \u00e9voquons et la n\u00f4tre, et aussi pour mieux nous concentrer sur le sujet trait\u00e9 (\u00ab\u00a0la confiance\u00a0\u00bb ou \u00ab\u00a0la na\u00efvet\u00e9\u00a0\u00bb ?). Cette r\u00e9flexion se fait sous le magist\u00e8re, l&rsquo;inspiration, la r\u00e9f\u00e9rence de deux hommes, &ndash; Talleyrand et de Gaulle.<\/p>\n<\/p>\n<p><p>Le premier est un homme de caract\u00e8re ; de Gaulle pas moins certes mais Talleyrand pla\u00e7ait le caract\u00e8re au-dessus de tout et il le disait. Dans la <em>Chronique du 19 courant..<\/em> du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-chronique_du_19_courant_l_horreur-fascination_19_08_2014.html\">19 mars 2014<\/a>, notre chroniqueur \u00e9crit \u00e0 propos du \u00ab\u00a0caract\u00e8re\u00a0\u00bb, dont il juge qu&rsquo;il englobe notamment l&rsquo;intelligence, avec d&rsquo;autres traits, et qui n\u00e9cessairement la d\u00e9passe (l&rsquo;intelligence)  : &laquo;<em>C&rsquo;est bien dans cette dimension du caract\u00e8re que se trouve le secret des \u00e9poques exceptionnelles, comme le fut avant la n\u00f4tre celle de la R\u00e9volution, comme celle de la Grande Guerre il y a un si\u00e8cle. Finalement, qu&rsquo;importent les id\u00e9es une fois que vous avez trouv\u00e9 le sens de la grande bataille qui anime l&rsquo;histoire que vous vivez ; l\u00e0-dessus, \u00e9galement me s\u00e9parant de Cioran, tant les personnages qu&rsquo;il nous d\u00e9signe sont trop exclusivement d\u00e9finis par des id\u00e9es lorsqu&rsquo;on les qualifie de \u00ab\u00a0r\u00e9actionnaires\u00a0\u00bb, il est vrai que ce qui me pousse vers eux c&rsquo;est le caract\u00e8re. C&rsquo;est une conception g\u00e9n\u00e9rale sur laquelle je reviendrai, tant le caract\u00e8re me semble ce qui est le plus apte, chez le sapiens, \u00e0 recevoir par le canal de sa psychologie l&rsquo;onction de l&rsquo;intuition haute, pour alimenter l&rsquo;\u00e9nergie de l&rsquo;esprit vers des hauteurs qui justifient de vivre &#8230; Je suis absolument p\u00e9n\u00e9tr\u00e9, baign\u00e9, par cette appr\u00e9ciation instinctive et spirituelle \u00e0 la fois, selon laquelle le caract\u00e8re occupe la place essentielle, lui seul qui vous permet d&rsquo;assurer \u00e0 la fois un sentiment d&rsquo;horreur et un sentiment de fascination, pour le m\u00eame objet, sans succomber \u00e0 cette contradiction, et m\u00eame en se sentant plus libre que jamais en l&rsquo;\u00e9prouvant. Notre \u00e9poque trempe les caract\u00e8res ou les pulv\u00e9rise c&rsquo;est selon, et mesure ainsi la force qu&rsquo;on en retire en distinguant ceux qui ont l&rsquo;audace tranquille d&rsquo;affronter le monstre. Notre \u00e9poque est le temps de la d\u00e9b\u00e2cle des id\u00e9es et de l&rsquo;offrande supr\u00eame de leur caract\u00e8re pour ceux qui veulent faire de leur vie un juste combat&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Et, pour terminer de main de ma&icirc;tre en laissant parler un autre, notre chroniqueur citait donc Talleyrand : &laquo;[&hellip;Talleyrand] <em>dit alors une de ces choses qui ne sortent jamais de la m\u00e9moire quand on les a entendues ; \u00ab\u00a0Je suis bien aise de vous communiquer une pens\u00e9e qui est venue dans beaucoup de t\u00eates mais que je n&rsquo;ai vu bien nettement d\u00e9velopp\u00e9e nulle part. Il y a trois choses n\u00e9cessaires pour former un grand homme, d&rsquo;abord la position sociale, une haute position ; ensuite la capacit\u00e9 et les qualit\u00e9s ; mais surtout et avant tout le caract\u00e8re. C&rsquo;est le caract\u00e8re qui fait l&rsquo;homme.\u00a0\u00bb Et il citait, poursuit-elle, \u00e0 l&rsquo;appui de son dire, tous les demi-dieux de l&rsquo;histoire : Alexandre, C\u00e9sar, Fr\u00e9d\u00e9ric, et ajoutait : \u00ab\u00a0Si un des pieds de ce tr\u00e9pied qui doit se maintenir par l&rsquo;\u00e9quilibre doit \u00eatre plus faible que les deux autres, que ce ne soit pas le caract\u00e8re&hellip; que ce ne soit pas le caract\u00e8re !\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Le caract\u00e8re, c&rsquo;est-\u00e0-dire cette puissante entit\u00e9 int\u00e9gr\u00e9e qui permet de trouver une entente entre des choses contradictoires, qui conduit, dans une circonstance donn\u00e9e, un \u00eatre habitu\u00e9 aux man&oelig;uvres, aux chausse-trappes, aux marchandages m\u00e9diocres, \u00e0 distinguer soudain une \u00e9chapp\u00e9e de lumi\u00e8re et \u00e0 se dire \u00ab\u00a0ici, dans cette trouv\u00e9e inattendue de clart\u00e9, se dessine une circonstance exceptionnelle o&ugrave; des hommes hargneux, m\u00e9fiants, soup\u00e7onneux, soudain se d\u00e9barrassent de tout cela se disent en un commun accord &lsquo;l\u00e0, oui, dans cet instant magique, quelque chose nous \u00e9l\u00e8ve tous et nous permet de tenter d&rsquo;envisager une &oelig;uvre in\u00e9dite'\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Guglielmo Ferrero, dans son <em>Talleyrand au Congr\u00e8s de Vienne<\/em>, rend compte de cet instant de magie dans la rencontre du 31 mars 1814 entre Talleyrand et le jeune tsar Alexandre, qui devait d\u00e9boucher sur une d\u00e9claration d&rsquo;intention sur une organisation de l&rsquo;Europe et du monde qui, si elle avait \u00e9t\u00e9 suivie, aurait install\u00e9 une exceptionnelle concorde et qui, dans tous les cas, insuffla un \u00e9lan qui fit de cette immense jacasserie de presque une ann\u00e9e du Congr\u00e8s de Vienne un \u00e9v\u00e9nement diplomatique respectable d&rsquo;arrangement apr\u00e8s 25 ans de terreur r\u00e9volutionnaire et de d\u00e9vastation napol\u00e9onienne. C&rsquo;est ce caract\u00e8re-l\u00e0 qui inspira le Talleyrand de 1814, repr\u00e9sentant le grand vaincu du Congr\u00e8s et arrivant pour annoncer que la France, ce grand vaincu qui \u00e9tait un grand pays, faisait le geste magnanime de renoncer aux conqu\u00eates de l&rsquo;Empire, &ndash; &laquo;<em>La maison de Bourbon seule, pouvait noblement faire reprendre \u00e0 la France les heureuses proportions indiqu\u00e9es par la politique et par la nature. Avec la maison de Bourbon,<\/em> <strong><em>la France cessait d&rsquo;\u00eatre gigantesque pour devenir grande<\/em><\/strong><em>. Soulag\u00e9e du poids de ses conqu\u00eates, la maison de Bourbon seule, pouvait la replacer au rang \u00e9lev\u00e9 qu&rsquo;elle doit occuper dans le syst\u00e8me social ; seule, elle pouvait d\u00e9tourner les vengeances que vingt ans d&rsquo;exc\u00e8s avaient amoncel\u00e9es contre elle.<\/em>&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">&laquo;<em>L&rsquo;avenir dure longtemps.<\/em>&raquo;<\/h3>\n<\/p>\n<p><p>&#8230; Poursuivons les citations : &laquo;<em>Tout peut, un jour arriver, m\u00eame ceci qu&rsquo;un acte conforme \u00e0 l&rsquo;honneur et \u00e0 l&rsquo;honn\u00eatet\u00e9 apparaisse, en fin de compte, comme un bon placement politique.<\/em>&raquo; (<em>M\u00e9moires de guerre, Le Salut<\/em>, p.659, La Pl\u00e9iade)<\/p>\n<\/p>\n<p><p>Le g\u00e9n\u00e9ral de Gaulle est notre seconde r\u00e9f\u00e9rence, et cette phrase dit l&rsquo;essentiel de ce que nous jugeons qu&rsquo;il nous apporte en l&rsquo;occurrence, dans ce d\u00e9bat que nous voulons d\u00e9velopper. La remarque salue une position fran\u00e7aise affirm\u00e9e fin 1944 contre les intentions sovi\u00e9tiques d&rsquo;installer en Pologne le gouvernement-fantoche, communiste certes, de Lublin, alors que les Anglo-Am\u00e9ricains, malgr\u00e9 leurs r\u00e9ticences exprim\u00e9es en secret aux Fran\u00e7ais, se pr\u00e9parent \u00e0 soutenir la proposition de Staline. Qu&rsquo;importe, de Gaulle s&rsquo;y oppose de fa\u00e7on officielle et publique, sans espoir de changer quoi que ce soit, et fait pr\u00e9c\u00e9der la citation ci-dessus de cette phrase courte et \u00e9nigmatique : &laquo;<em>L&rsquo;avenir dure longtemps.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>On ne peut dire qu&rsquo;en la circonstance, de Gaulle ait fait preuve d&rsquo;une intelligence politique particuli\u00e8re, son attitude n&rsquo;\u00e9tant appr\u00e9ci\u00e9e ni des Sovi\u00e9tiques qui tenaient \u00e0 leur Pologne sovi\u00e9tis\u00e9e, ni des Anglo-Am\u00e9ricains qui tenaient \u00e0 laisser faire Staline sans qu&rsquo;un hurluberlu les montr\u00e2t du doigt. Il en fut d&rsquo;autant plus moqu\u00e9, ridiculis\u00e9, surtout par les antigaullistes proam\u00e9ricanistes de France, les gens tels que Monnet ou Raymond Aron. De Gaulle avait jou\u00e9 \u00e0 la <em>prima dona<\/em> d\u00e9pass\u00e9e, attendu qu&rsquo;il chantait dans le d\u00e9sert, pas moins, une vieille balade fran\u00e7aise sur l&rsquo;honneur et l&rsquo;honn\u00eatet\u00e9 alors que d\u00e9j\u00e0 le rythme de l&rsquo;Occident \u00e9tait le <em>swing<\/em> de l&rsquo;orchestrer de Glenn Miller, institu\u00e9 orchestre officiel et militaire de la VIII\u00e8me Air Force en Angleterre.<\/p>\n<\/p>\n<p><p>Effectivement, il ne montre pas une intelligence particuli\u00e8re car l&rsquo;intelligence nous dit que la politique est l'\u00a0\u00bbart du possible\u00a0\u00bb, qu&rsquo;il faut savoir se m\u00e9nager des alli\u00e9s puissants, &ndash; en l&rsquo;occurrence sinon l&rsquo;URSS, au moins les Anglo-Saxons, &ndash; et que l&rsquo;intelligence n&rsquo;a que faire de cette hypoth\u00e8se incroyable, hors de toute probabilit\u00e9 raisonnable, de la correspondance entre l'\u00a0\u00bbacte d&rsquo;honneur et d&rsquo;honn\u00eatet\u00e9\u00a0\u00bb et le \u00ab\u00a0bon placement politique \u00ab\u00a0. Mais de Gaulle n&rsquo;a que faire de cette intelligence, il n&rsquo;en a point l&rsquo;usage d&rsquo;ailleurs. Il a du caract\u00e8re, c&rsquo;est-\u00e0-dire qu&rsquo;il a dans son arsenal de dispositions intellectuelles et psychologiques la confiance intuitive pour ce qui doit durer (&laquo;<em>l&rsquo;avenir dure longtemps<\/em>&raquo;) et qu&rsquo;il la proclame avec sinc\u00e9rit\u00e9, en se r\u00e9f\u00e9rant \u00e0 des valeurs hautes telles que l&rsquo;intuition, sans vrai souci des puissances du jour. En aucune occasion, il ne ment \u00e0 ses interlocuteurs et il a l&rsquo;habitude de dire droitement les choses, sans rien dissimuler des int\u00e9r\u00eats des uns et des autres, &ndash; et cette remarque vaut pour cette affaire polonaise comme elle vaut pour le reste de sa carri\u00e8re diplomatique au sens le plus haut. (On mettra \u00e0 part ses interventions publiques, d\u00e9mocratiques et populaires, notamment sur l&rsquo;Alg\u00e9rie, o&ugrave; il sut se montrer sous un autre jour, &ndash; mais l\u00e0 n&rsquo;est vraiment pas le propos, puisqu&rsquo;il s&rsquo;agit de communication et nullement de caract\u00e8re.) Est-ce qu&rsquo;il n&rsquo;a pas eu raison du point de vue de l&rsquo;histoire, bien qu&rsquo;il ait \u00e9t\u00e9, dans cette partie polonaise, mis sur la touche et consid\u00e9r\u00e9 comme quantit\u00e9 n\u00e9gligeable sinon ridicule ? Est-ce qu&rsquo;il n&rsquo;a pas eu raison si l&rsquo;on consid\u00e8re les choses, vingt ans plus tard (&laquo;<em>l&rsquo;avenir dure longtemps<\/em>&raquo;), sa popularit\u00e9, son influence naturelle, ses triomphes dans nombre de peuples ext\u00e9rieurs ? Le caract\u00e8re, c&rsquo;est l&rsquo;avenir qui &laquo;<em>dure longtemps<\/em>&raquo;, alors que l&rsquo;intelligence prise seule n&rsquo;est jamais que l&rsquo;habilet\u00e9 du jour.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Variations autour de l&rsquo;\u00e9largissement de l&rsquo;OTAN<\/h3>\n<\/p>\n<p><p>&#8230; Ce qui doit nous ramener \u00e0 notre propos, autour de ces moments essentiels de la fin des ann\u00e9es 1980 et du d\u00e9but des ann\u00e9es 1990 o&ugrave; furent fix\u00e9s les accords verbaux de non-extension de l&rsquo;OTAN au-del\u00e0 de l&rsquo;ancienne Allemagne de l&rsquo;Est. La p\u00e9riode, on l&rsquo;a dit, \u00e9tait absolument exceptionnelle, et les relations diplomatiques marqu\u00e9es par une extr\u00eame franchise de part et d&rsquo;autre. Gorbatchev parlait de la \u00ab\u00a0maison commune europ\u00e9enne\u00a0\u00bb et tous les dirigeants politiques applaudissaient, oublieux de leurs habituels r\u00e9flexes de d\u00e9fiance et de prudence. C&rsquo;est dans cette atmosph\u00e8re absolument exceptionnelle que furent conclus les arrangements que l&rsquo;on a \u00e9voqu\u00e9s dans le texte initialement cit\u00e9 (le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/forum-au_commencement_tait_leur_confiance_05_01_2015.html\">5 janvier 2015<\/a>), ou Kouvaldine, alors conseiller de Gorbatchev, explique l&rsquo;absence d&rsquo;accord \u00e9crit : &laquo;<em>Nous avions confiance en vous.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Ce qu&rsquo;il faut savoir \u00e9galement est que cet accord oral fut le fondement de la pens\u00e9e strat\u00e9gique US jusqu&rsquo;en 1993-1994, que tous les experts s\u00e9rieux \u00e0 Washington ne cessaient de r\u00e9p\u00e9ter (\u00ab\u00a0L&rsquo;OTAN ne doit pas s&rsquo;\u00e9largir vers l&rsquo;Est\u00a0\u00bb). C&rsquo;est pour cela que fut cr\u00e9\u00e9 \u00e0 l&rsquo;OTAN en 1992 un \u00ab\u00a0machin\u00a0\u00bb baptis\u00e9e PfP (<em>Partnership for Peace<\/em>) qui \u00e9tait explicitement, quoiqu&rsquo;officieusement, pr\u00e9sent\u00e9 comme la r\u00e9ponse aux pays de l&rsquo;Europe de l&rsquo;Est demandant l&rsquo;adh\u00e9sion \u00e0 l&rsquo;OTAN : il s&rsquo;agissait d&rsquo;\u00e9tablir un partenariat qui \u00f4tait la substance de leur demande d&rsquo;adh\u00e9sion et justifiait qu&rsquo;on la leur refus\u00e2t conform\u00e9ment \u00e0 l&rsquo;engagement de Malte. Ce qui fit basculer la position US n&rsquo;a rien \u00e0 voir, ni avec les int\u00e9r\u00eats strat\u00e9giques du pays, ni avec un grand plan machiav\u00e9lique, ni avec un non-accord \u00e9crit. (E&ucirc;t-il \u00e9t\u00e9 \u00e9crit qu&rsquo;il f&ucirc;t devenu aussi rapidement et selon la n\u00e9cessit\u00e9 un \u00ab\u00a0chiffon de papier\u00a0\u00bb, par exemple \u00e0 l&rsquo;image fort r\u00e9cente de l&rsquo;accord sign\u00e9 le 21 f\u00e9vrier 2014 \u00e0 Kiev par les trois ministres des affaires \u00e9trang\u00e8res de l&rsquo;UE, Ianoukovitch et l&rsquo;opposition ukrainienne, qui servit imm\u00e9diatement de torche-cul \u00e0 <em>Pravy Sektor<\/em>, amenant la fuite de Ianoukovitch, les montages, les fusillades et la prise de pouvoir qu&rsquo;on sait.) Ce qui fit basculer la position US a tout \u00e0 voir avec cette pi\u00e8tre circonstance que nous rappelions encore le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-jugement_d_outre-tombe_sur_notre_nouvelle_guerre_froide_01_08_2014.html\">1er ao&ucirc;t 2014<\/a> :<\/p>\n<\/p>\n<p><p>&laquo;<em>Effectivement, la catastrophe ukrainienne a son origine dans la d\u00e9cision d&rsquo;\u00e9largir l&rsquo;OTAN, et Kennan, avec approbation du Friedman-du-jour, l&rsquo;avait bien vu, et cela attrista fortement ses v\u00e9n\u00e9rables vieux jours. La cerise sur la g\u00e2teau est de la m\u00eame aune m\u00e9diocre qui caract\u00e9rise cette \u00e9poque o&ugrave; triomphe la surpuissance autodestructrice : l&rsquo;id\u00e9e de l&rsquo;\u00e9largissement de l&rsquo;OTAN avait \u00e9t\u00e9 lanc\u00e9e par les d\u00e9mocrates qui allaient venir au pouvoir dans le chef du s\u00e9millant Bill Clinton, au printemps-\u00e9t\u00e9 1992, pour rameuter la communaut\u00e9 polonaise de Chicago, jusqu&rsquo;alors ferme soutien des d\u00e9mocrates et qui mena\u00e7ait de passer \u00e0 l&rsquo;ennemi (r\u00e9publicain) si bon ordre n&rsquo;y \u00e9tait mis ; la promesse de faire entrer la Pologne dans l&rsquo;OTAN, avec quelques autres, parut un bon argument, &ndash; et ainsi fut lanc\u00e9 ce train catastrophique. Au reste, quand le couple Clinton-Gore d\u00e9cida que cette promesse serait tenue de fa\u00e7on \u00e0 conforter la position du parti d\u00e9mocrate, et que la consigne fut lanc\u00e9e dans la bureaucratie, en 1993-1994, il n&rsquo;y avait pas un seul expert pour ne pas juger, \u00e0 l&rsquo;image de Kennan, que cette initiative \u00e9tait une catastrophe. (L&rsquo;actuel adjoint au secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN, l&rsquo;ancien ambassadeur US Alexander Russell \u00ab\u00a0Sandy\u00a0\u00bb Vershbow, qui anime aujourd&rsquo;hui l&rsquo;activisme otanien en Ukraine, \u00e9tait le premier, dans ces ann\u00e9es-l\u00e0, \u00e0 d\u00e9noncer mezzo voce et en petit comit\u00e9 l&rsquo;\u00e9largissement de l&rsquo;OTAN.) Mais la plupart se retinrent bien de clamer publiquement leur conviction, au contraire de Kennan, &ndash; question de caract\u00e8re (et de carri\u00e8re, \u00e9ventuellement)&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&#8230; Bref, la \u00ab\u00a0confiance\u00a0\u00bb dont parle Kouvaldine n&rsquo;incluait pas la situation du parti d\u00e9mocrate dans la communaut\u00e9 polonaise du Michigan, au printemps de 1992. (Elle n&rsquo;incluait pas non plus l&rsquo;\u00e9limination de Gorbatchev par Eltsine, le parcours hoquetant de vodka de Eltsine, soutenu par Wall Street, les capitalistes venus de l'\u00a0\u00bb\u00e9cole de Chicago\u00a0\u00bb et les oligarques bondissant sur l&rsquo;occasion.) La vraie occasion, celle du \u00ab\u00a0l&rsquo;\u00e9poque magique\u00a0\u00bb, \u00e9tait pass\u00e9 et le Syst\u00e8me reprenait la main. L\u00e0-dessus, qu&rsquo;on vienne nous expliquer que, quelle qu&rsquo;en soit la raison, la d\u00e9cision d&rsquo;\u00e9largir l&rsquo;OTAN (et le reste, comme l&rsquo;\u00e9pisode Eltsine) reste un \u00ab\u00a0bon coup\u00a0\u00bb pour l&rsquo;Ouest devenu bloc BAO fait un peu trop vite oublier que &laquo;<em>l&rsquo;avenir dure longtemps<\/em>&raquo;, si ce \u00ab\u00a0bon coup\u00a0\u00bb conduit \u00e0 la catastrophe ukrainienne qui donne au destin la possibilit\u00e9 de faire surgir la circonstance o&ugrave; le Syst\u00e8me pourrait \u00eatre conduit au terme de sa transmutation surpuissance-autodestruction. (Voir encore Orlov, ce <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-orlov_et_la_dissolution_du_rien__07_01_2015.html\">7 janvier 2015<\/a>.) &laquo;<em>L&rsquo;avenir dure longtemps<\/em>&raquo;, et nous n&rsquo;en sommes pas au terme.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">De Poutine \u00e0 Loren B. Thompson<\/h3>\n<\/p>\n<p><p>Ainsi dirons-nous \u00e0 notre lecteur qu&rsquo;\u00e0 notre sens, il n&rsquo;a pas raison, en aucune fa\u00e7on. La \u00ab\u00a0confiance\u00a0\u00bb avait toute sa place dans les accords de Malte et suivant, et elle \u00e9tait bien suffisante dans la circonstance diplomatique-devenue-historique que nous avons d\u00e9crite. (De m\u00eame observera-t-on que l&rsquo;un des accords les plus scrupuleusement observ\u00e9s de la Guerre froide fut une promesse orale de 1962, faite par Kennedy \u00e0 Krouchtchev, que les USA ne tenteraient pas l&rsquo;invasion de Cuba, dans l&rsquo;accord g\u00e9n\u00e9ral, en termes \u00e9galement non-\u00e9crits, qui conclut la crise des fus\u00e9es de Cuba d&rsquo;octobre 1962.)<\/p>\n<\/p>\n<p><p>La \u00ab\u00a0confiance\u00a0\u00bb, comme la sinc\u00e9rit\u00e9, l&rsquo;absence de dissimulation, etc., rehauss\u00e9es par la fermet\u00e9 du propos et la rehaussant en m\u00eame temps, sont parmi les attitudes intellectuelles et spirituelles qui forgent les grands caract\u00e8res et font la force de la communication, elle-m\u00eame grandie par ce fait, des hommes d&rsquo;&Eacute;tat. Qu&rsquo;est-ce qui fait de Poutine un dirigeant de grand caract\u00e8re, qu&rsquo;est-ce qui fait sa force, par opposition \u00e0 ses \u00ab\u00a0partenaires\u00a0\u00bb du bloc BAO qui lisent comme des robots les fiches pr\u00e9par\u00e9es par leur bureaucraties et remises en forme attrayante par leur <em>speechwriters<\/em>, parfait circuit-Syst\u00e8me bien de notre temps ? Ce n&rsquo;est ni son habilet\u00e9, ni sa science des \u00e9checs, ni sa retenue de caract\u00e8re, ni son exp\u00e9rience d&rsquo;analyste de renseignement, ni son \u00ab\u00a0froid r\u00e9alisme\u00a0\u00bb, etc., etc., &ndash; et volent les images et lieux communs. Ce qui fait sa force, c&rsquo;est sa sinc\u00e9rit\u00e9 et la puissance de ses convictions, comme les traits d&rsquo;un grand caract\u00e8re. Il ne s&rsquo;agit pas d'\u00a0\u00bbavoir raison\u00a0\u00bb ou d'\u00a0\u00bbavoir tort\u00a0\u00bb, de \u00ab\u00a0bien man&oelig;uvrer\u00a0\u00bb ou de \u00ab\u00a0mal man&oelig;uvrer\u00a0\u00bb, il s&rsquo;agit de disposer de la force, &ndash; force de conviction, force de persuasion, force de s\u00e9duction, etc., &ndash; que donne un caract\u00e8re s&rsquo;exprimant et s&rsquo;affirmant en d\u00e9ployant toutes ses capacit\u00e9s intellectuelles et spirituelles ; avec l&rsquo;aide de l&rsquo;intuition et de la perception juste ; avec l&rsquo;aide de la capacit\u00e9 d&rsquo;analyse, du jugement de l&rsquo;esprit. L&rsquo;honn\u00eatet\u00e9 de Poutine avec lui-m\u00eame est une sorte de \u00ab\u00a0confiance\u00a0\u00bb qu&rsquo;il met dans ses interventions et dans ses \u00e9changes avec ses interlocuteurs, et cela constitue la clef de son succ\u00e8s depuis sa r\u00e9\u00e9lection, car c&rsquo;est depuis sa r\u00e9\u00e9lection que se d\u00e9ploient des \u00e9v\u00e9nements qui conduisent effectivement \u00e0 faire appel \u00e0 cette sorte de caract\u00e8re.<\/p>\n<\/p>\n<p><p>Il ne s&rsquo;agit pas ici de plaider telle ou telle cause politique, car il est av\u00e9r\u00e9 que nous sommes <strong>\u00e0 nouveau<\/strong> dans une \u00e9poque historique qui ne se comprend qu&rsquo;avec un regard m\u00e9tahistorique d&rsquo;o&ugrave; doivent \u00eatre bannis l&rsquo;esprit de partisanerie, le parti-pris, le cynisme de la politique courante, le conformisme confortable des caract\u00e8res faibles. (Non pas que tout cela n&rsquo;existe pas, bien au contraire cela pullule, et on peut et doit le d\u00e9noncer au gr\u00e9 des rencontres ; mais aujourd&rsquo;hui, tout cela est sans effet profond, compar\u00e9 aux conditions d&rsquo;une puissance inou\u00efe auxquelles nous sommes confront\u00e9s.) De m\u00eame que nous devons \u00eatre capable de reconna&icirc;tre ce que nous croyons distinguer chez Poutine, de m\u00eame nous devons \u00eatre capables de reconna&icirc;tre ce qu&rsquo;un <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-un_cas_d_cole_loren_b_thompson_et_l_ukraine_05_01_2015.html\">Loren B. Thompson<\/a> \u00e9crit entre les lignes d&rsquo;un article plein de sous-entendus qui signalent que, derri\u00e8re l&rsquo;homme corrompu, un homme de caract\u00e8re est possible. Les grandes p\u00e9riodes historiques rompent les digues et s&rsquo;\u00e9crivent \u00e0 grands flots d\u00e9cha&icirc;n\u00e9s. Il faut savoir s&rsquo;y reconna&icirc;tre, &ndash; d\u00e9marche essentielle, &ndash; et, une fois reconnaissance faite, ne craindre aucun argument, f&ucirc;t-ce celui de la \u00ab\u00a0confiance\u00a0\u00bb, &ndash; et, bien au contraire, celui de la \u00ab\u00a0confiance\u00a0\u00bb d&rsquo;abord. Il s&rsquo;agit de vaincre le Syst\u00e8me dans ces instants o&ugrave;, \u00e0 cause de ses furieux emportements de surpuissance, il laisse passer un de ces instants de lumi\u00e8re qui forgent et r\u00e9v\u00e8lent les caract\u00e8res ; et alors, dans la confiance que peuvent choisir d&rsquo;accorder ces caract\u00e8res, il n&rsquo;y a nulle na\u00efvet\u00e9 mais un espoir mesur\u00e9 que les n\u00e9cessit\u00e9s du monde poussent \u00e0 mettre en avant. Pour dix ou cent \u00e9checs de cette tentative, il peut y avoir une r\u00e9ussite, &ndash; mais celle-l\u00e0 sera l&rsquo;unique, la sublime, le seul \u00e9v\u00e9nement qui peut faire basculer une \u00e9poque aussi profond\u00e9ment et hautement tragique qu&rsquo;est la n\u00f4tre.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur LEUR confiance&#8230; 7 janvier 2014 &ndash; Nous allons prendre l&rsquo;occasion de remarques d&rsquo;un lecteur qui a r\u00e9agi en deux temps \u00e0 notre Br\u00e8ve de crise du 5 janvier 2015, qui n&rsquo;en demandait pas tant. Mais cette occasion est int\u00e9ressante et elle fait le larron. Ce lecteur soul\u00e8ve un probl\u00e8me lui-m\u00eame des plus int\u00e9ressants,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[8565,8795,3109,6536,3621,16307,2631,2685,3483,3473,6665,2668,584,916,2699,3474,1296,8961],"class_list":["post-75691","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-alain","tag-avenir","tag-b","tag-caractere","tag-confiance","tag-crowe","tag-de","tag-gaulle","tag-gorbatchev","tag-loren","tag-malte","tag-orlov","tag-otan","tag-poutine","tag-talleyrand","tag-thompson","tag-ukraine","tag-vite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75691"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75691\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}