{"id":75724,"date":"2015-01-24T15:42:49","date_gmt":"2015-01-24T15:42:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/01\/24\/la-mort-dinternet-ou-de-google\/"},"modified":"2015-01-24T15:42:49","modified_gmt":"2015-01-24T15:42:49","slug":"la-mort-dinternet-ou-de-google","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/01\/24\/la-mort-dinternet-ou-de-google\/","title":{"rendered":"La mort d&rsquo;internet &#8230; ou de Google"},"content":{"rendered":"<p><h3 class=\"titrebloc\">La mort d&rsquo;internet &#8230; ou de Google<\/h3>\n<\/p>\n<p><p>\tA Davos, l&rsquo;impassible et glacial <em>F\u00fchrer<\/em> de Google, Eric Schmidt, annonce la mort d&rsquo;internet comme de quelque chose qui serait rapidement d\u00e9pass\u00e9 et inutile,  une sorte de dinosaure, promis \u00e0 dispara\u00eetre selon la logique vertueuse du monde parce qu&rsquo;il semble bien que ledit internet ne corresponde pas au dessein supra-physique de ce thaumaturge du bazar de simulacre de la postmodernit\u00e9 (nous parlons de Google et de sa philosophie). Schmidt d\u00e9crit ce qui remplacera internet, ce qui ferait au fond qu&rsquo;on passerait d&rsquo;un r\u00e9seau public, collectif et interconnect\u00e9 comme il l&rsquo;est aujourd&rsquo;hui \u00e0 l&rsquo;\u00e9tablissement d&rsquo;un r\u00e9seau individualiste touchant directement les consommateurs, via leurs cerveaux. C&rsquo;est la formule id\u00e9ale des transhumanistes \u00e9voluant vers le contr\u00f4le total de l&rsquo;humain et sa transformation progressive en un humano\u00efde robotis\u00e9, puis en un robot vaguement humano\u00efs\u00e9&#8230;<\/p>\n<\/p>\n<p><p>\tOn voit donc qu&rsquo;il y a une fa\u00e7on classique, commerciale et technologique, de consid\u00e9rer ces propos (ceux de Schmidt), ou une fa\u00e7on absolument ontologique de consid\u00e9rer qu&rsquo;il s&rsquo;agit, derri\u00e8re le discours d\u00e9bit\u00e9 sur le ton monocorde qu&rsquo;affectionne Schmidt, d&rsquo;une tentative d\u00e9lib\u00e9r\u00e9e de transformation radicale de la personne humaine, et donc de l&rsquo;esp\u00e8ce. Certaines appr\u00e9ciations, qui attribuent d&rsquo;exp\u00e9rience \u00e0 la galaxie-Google un climat de relations humaines et une dynamique professionnelle (?) ressemblant \u00e0 ceux d&rsquo;une secte qui auraient des projets de surhumanit\u00e9 conduisant \u00e0 l&rsquo;extra-humanit\u00e9, peuvent tout aussi bien accr\u00e9diter la seconde interpr\u00e9tation. Ils ne doivent pas h\u00e9siter une seconde, nous y sommes.<\/p>\n<\/p>\n<p><p>\tDans <em>Infowars.com<\/em>, Paul Joseph Watson r\u00e9sume le propos de Schmidt \u00e0 Davos de cette fa\u00e7on (le <a href=\"\/%E2%80%AAhttp:\/\/www.infowars.com\/googles-eric-schmidt-greases-skids-for-internet-brain-chip\/%E2%80%AC\" class=\"gen\">23 janvier 2015<\/a>) : \u00ab<em>Google CEO Eric Schmidt greased the skids for an Internet brain chip during a speech at the World Economic Forum in Davos, Switzerland earlier today when he predicted the end of the world wide web as an external concept.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Asked how he saw the Internet developing in future years, Schmidt responded. I will answer very simply that the Internet will disappear. There will be so many IP addressesso many devices, sensors, things that you are wearing, things that you are interacting with that you won&rsquo;t even sense it, he added. It will be part of your presence all the time. Imagine you walk into a room, and the room is dynamic. And with your permission and all of that, you are interacting with the things going on in the room.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Schmidt, who previously caused controversy amongst privacy advocates when he stated, If you have something that you don&rsquo;t want anyone to know, maybe you shouldn&rsquo;t be doing it in the first place, concluded his Davos speech by envisaging A highly personalized, highly interactive and very, very interesting world. When Schmidt speaks of sensors that will replace the Internet as a platform accessed only through an external device, he is talking about implantable brain chips&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tMais il y a une autre face de l&rsquo;intervention de Schmidt, qui est relev\u00e9e par <em>Business Insider<\/em>, le m\u00eame <a href=\"http:\/\/uk.businessinsider.com\/sheryl-sandberg-eric-schmidt-and-satya-nadella-at-davos-2015-1?r=US#ixzz3Pi3QyMxn\" class=\"gen\">23 janvier 2015<\/a>. Il concerne la position b\u00eatement commerciale de Google, la situation de son monopole, face \u00e0 l&rsquo;apparition en nombre grandissant de concurrents qui s&rsquo;approprient des parts de march\u00e9, tandis que la soci\u00e9t\u00e9 g\u00e9ante de l&rsquo;internet est sous le coup d&rsquo;une investigation de l&rsquo;UE, justement pour sa position monopolistique. Il importe d&rsquo;avoir \u00e0 l&rsquo;esprit que ce mouvement vient de la crise NSA\/Snowden et des r\u00e9v\u00e9lations qui ont \u00e9t\u00e9 faites sur la complicit\u00e9 et l&rsquo;interconnexion existantes entre Google et la NSA (voir le <a href=\"http:\/\/www.dedefensa.org\/article-la_nsa_une_menace_contre_l_conomie_us_09_10_2014.html\" class=\"gen\">9 octobre 2014<\/a>)&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Google chairman Eric Schmidt suggested today that Google&rsquo;s dominance  in both search and mobile device operating systems  is under threat from a new set of players intent on reordering the tech business. He was speaking at the World Economic Forum in Davos, Switzerland, on a panel with Vodafone CEO Vittorio Colao, Facebook COO Sheryl Sandberg, and Microsoft CEO Satya Nadella.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Schmidt was asked about the dominance of certain major companies, such as Facebook, Google and Apple who between them control the vast majority of the web and mobile internet. The context is that Google is under investigation by the EU into whether its search engine counts as a monopoly. Some regulators have suggested breaking up the company. Google has a roughly 90% share of the search market in Europe and its Android product has an up to an 80% share of the mobile device operating system market for phones, worldwide.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>And while Schmidt&rsquo;s answer wasn&rsquo;t exactly an admission that Google is going to crumble anytime soon, it did echo the thinking of some in the tech business who have noticed that smaller, specialist companies have begun slicing off niche chunks of Google&rsquo;s core business, or developing new search areas that Google has no access to. Both Facebook and Apple have search products for instance. (Facebook has its own internal search algorithm and Apple&rsquo;s App Store has a search function that powers its multi-billion app discovery process.)<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>On the question  of dominance, you now see so many strong tech platforms coming through and you&rsquo;re seeing a reordering, and a future reordering, of the leaders because of the rise of the app on the smartphone.  &#8230; all bets are off. We have a whole new set of players, he said. The major question for the future, he said, was, What are the apps that people are going to use? &#8230; I view that as a completely open market at this point. His point is that new players can come from nowhere and create seemingly massive businesses from nothing in a matter of months. Two recent examples are the workplace chat product Slack  recently valued at $1 billion after only being in existence for 8 months  and Snapchat, which in just a couple of years has come to dominate certain types of messaging, particularly among young people. Whether any such app might seriously damage Google is being openly discussed by investors. A recent analysts&rsquo; note from Baird Equity Research suggested Google was losing some of its mojo to competitors&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAinsi va cette \u00e9trange \u00e9poque o\u00f9 se m\u00ealent jusqu&rsquo;\u00e0 l&rsquo;intimit\u00e9 la plus oiseuse et la plus \u00e9trange le <em>business<\/em> dans ce qu&rsquo;il peut avoir de plus monstrueux et de plus faussaire, entre les $milliards et les connexions avec la NSA, et les projets d&rsquo;une science-fiction color\u00e9e d&rsquo;un \u00e9sot\u00e9risme de bazar o\u00f9 un CEO sorti de rien nous assure qu&rsquo;il pourrait r\u00e9pondre avec assurance et certitude \u00e0 la question fameuse Qui t&rsquo;a fait Dieu ?. Le vrai est que l&rsquo;amas de puissance et le fatras de technologisme que permet le Syst\u00e8me conduit effectivement \u00e0 proposer sur la place publique des ambitions relevant de la m\u00e9taphysique \u00e0 la port\u00e9e de toutes les bourses, sans vraiment exciter le moindre scepticisme. A Davos, aujourd&rsquo;hui, tous les r\u00eaves sont permis, d&rsquo;abord parce qu&rsquo;ils sont prot\u00e9g\u00e9s par une arm\u00e9e de gardes du corps clon\u00e9s et globalis\u00e9s en costumes sombres et lunettes noires, et de gabelous suisses veillant sur la bonne r\u00e9putation de la Conf\u00e9d\u00e9ration.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit d&rsquo;une situation compl\u00e8tement in\u00e9dite dans la r\u00e9partition des puissances, et dans l&rsquo;expos\u00e9 de l&rsquo;intentionnalit\u00e9 dans l&rsquo;usage de ces puissances. Ce qui est remarquable, c&rsquo;est ce proc\u00e9d\u00e9 du parler \u00e0 ciel ouvert (en plus, avec la superbe luminosit\u00e9 des cimes alpestres) dans l&rsquo;expos\u00e9 du complot pour remplacer Dieu en r\u00e9paration (Louis-Ferdinand C\u00e9line) par Dieu-Google, donc poursuivre le r\u00e9cit de l&rsquo;ampleur extraordinaire du complot machin\u00e9 par le <em>F\u00fchrer<\/em>-Schmidt ; et l\u00e0-dessus la plong\u00e9e dans la plus basse comptabilit\u00e9 pour rappeler que tout cela d\u00e9pend de la capacit\u00e9 de Google de tenir le choc des effets des r\u00e9v\u00e9lations de ses relations incestueuses avec la NSA. Ainsi, dans trois ou quatre ans, peut-\u00eatre serons-nous tous d\u00e9pendant des consignes de Schmidt et de son Dieu-Google, ou bien peut-\u00eatre Schmidt sera-t-il dans sa r\u00e9sidence de ch\u00f4mage dor\u00e9, \u00e0 rem\u00e2cher avec Marx et Nietzsche le catalogue des occasions rat\u00e9es. En attendant d\u00e9filent sous nos yeux, hors de tout contr\u00f4le de l&rsquo;esprit critique, hors de toute r\u00e9f\u00e9rence de mesure du philosophe, hors de toute appr\u00e9ciation d&rsquo;autorit\u00e9s morales qui pr\u00e9f\u00e8rent s&rsquo;en remettre au flux du Syst\u00e8me, les projets les plus ambitieux et les plus d\u00e9structurants.<\/p>\n<\/p>\n<p><p>\tNous n&rsquo;observons pas cela pour approuver ou d\u00e9noncer les projets de Schmidt dont nous avons <a href=\"http:\/\/www.dedefensa.org\/article-notre_intelligence_et_la_chute_07_06_2013.html\" class=\"gen\">d\u00e9j\u00e0<\/a> parl\u00e9, pour nous inqui\u00e9ter ou nous r\u00e9jouir du sort de Google,  on conna\u00eet nos positions l\u00e0-dessus,  mais pour sugg\u00e9rer de quel poids formidable cette avalanche de communication concernant les hypoth\u00e8ses expos\u00e9es et comment\u00e9es s\u00e9rieusement des bouleversements les plus consid\u00e9rables qu&rsquo;on puisse imaginer doit peser sur nos psychologies. L&rsquo;\u00e9poque postmoderne, qui se pr\u00e9sente comme l&rsquo;\u00e9poque du <em>big Now<\/em>, ce pseudo-<a href=\"http:\/\/www.dedefensa.org\/article-du_big_now_l_l_ternel_pr_sent__29_01_2014.html\" class=\"gen\">\u00e9ternel pr\u00e9sent<\/a> en version technologique, qui devrait donc proposer la stabilit\u00e9 assur\u00e9e d&rsquo;une sorte de meilleur des mondes enfin r\u00e9alis\u00e9, produit au contraire et paradoxalement les pouss\u00e9es d\u00e9stabilisantes et d\u00e9structurantes des psychologies les plus fortes qu&rsquo;on puisse imaginer. C&rsquo;est ainsi que naissent les \u00e9v\u00e9nements les plus inattendus,  c&rsquo;est-\u00e0-dire, pas n\u00e9cessairement ce que le <em>F\u00fchrer<\/em>-Schmidt nous promet pour ses lendemains qui clignotent&#8230;<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 24 janvier 2015 \u00e0 15H42<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mort d&rsquo;internet &#8230; ou de Google A Davos, l&rsquo;impassible et glacial F\u00fchrer de Google, Eric Schmidt, annonce la mort d&rsquo;internet comme de quelque chose qui serait rapidement d\u00e9pass\u00e9 et inutile, une sorte de dinosaure, promis \u00e0 dispara\u00eetre selon la logique vertueuse du monde parce qu&rsquo;il semble bien que ledit internet ne corresponde pas au&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6241,3244,3466,2662,2868,10091,16359,2650,16360,7106,4505,13181],"class_list":["post-75724","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-cerveau","tag-davos","tag-dieu","tag-en","tag-est","tag-google","tag-implants","tag-mort","tag-reparation","tag-robot","tag-schmidt","tag-transhumanisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75724"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75724\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}