{"id":75745,"date":"2015-02-06T05:29:13","date_gmt":"2015-02-06T05:29:13","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/02\/06\/finalement-si-lon-zapait-le-jsf\/"},"modified":"2015-02-06T05:29:13","modified_gmt":"2015-02-06T05:29:13","slug":"finalement-si-lon-zapait-le-jsf","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/02\/06\/finalement-si-lon-zapait-le-jsf\/","title":{"rendered":"Finalement, si l&rsquo;on \u201czapait\u201d le JSF ?"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Finalement, si l&rsquo;on zapait le JSF ?<\/h3>\n<\/p>\n<p><p>\tIl s&rsquo;agit d&rsquo;un article des plus s\u00e9rieux, sign\u00e9 par Amy Butler, une des grandes signatures du fameux <em>Aviation Week &#038; Space Technology<\/em>. (Le <a href=\"http:\/\/aviationweek.com\/defense\/proliferating-threats-open-door-f-35-follow\" class=\"gen\">4 f\u00e9vrier 2015<\/a>, publi\u00e9 dans le num\u00e9ro d&rsquo;AW&#038;ST du 5 f\u00e9vrier.) Cet hebdomadaire n&rsquo;\u00e9crit rien, surtout sur un sujet aussi br\u00fblant que le JSF\/F-35, sans avoir tourn\u00e9 au moins sept fois sa plume dans son encrier et consult\u00e9 les autorit\u00e9s qui importent. Par cons\u00e9quent, l&rsquo;article, \u00e9crit tout en douceur et en conditionnel mais citant des officiels du Pentagone et envisageant des options radicales, a une tr\u00e8s grande signification politique,  et au-del\u00e0, une signification civilisationnelle symbolique. D&rsquo;un point de vue politique concret, c&rsquo;est la sorte de texte qu&rsquo;on lance dans l&rsquo;atmosph\u00e8re survolt\u00e9e de Washington pour voir les r\u00e9actions des uns et des autres, \u00e0 propos d&rsquo;une affaire tr\u00e8s s\u00e9rieuse o\u00f9 l&rsquo;on envisage l&rsquo;une ou autre option non moins tr\u00e8s s\u00e9rieuse.<\/p>\n<\/p>\n<p><p>\t&#8230; Dans ce cas, l&rsquo;affaire tr\u00e8s s\u00e9rieuse n&rsquo;est rien moins que l&rsquo;\u00e9vocation d\u00e9taill\u00e9e, sinon chronologiquement d\u00e9crite, de la possibilit\u00e9 de l&rsquo;abandon du JSF\/F-35, avec diverses options envisageables, mais la favorite \u00e9tant indiscutablement le d\u00e9veloppement d&rsquo;un successeur au JSF ; bien entendu, une merveille qui repr\u00e9senterait la sixi\u00e8me g\u00e9n\u00e9ration, la g\u00e9n\u00e9ration d&rsquo;apr\u00e8s la cinqui\u00e8me g\u00e9n\u00e9ration que repr\u00e9sente le JSF (et le F-22) ; et, bien entendu, cette sixi\u00e8me g\u00e9n\u00e9ration promise \u00e0 un succ\u00e8s technologique triomphal et \u00e0 un d\u00e9veloppement ultra-rapide car elle profiterait des acquis de la cinqui\u00e8me g\u00e9n\u00e9ration &#8230; On est l\u00e0 dans une logique bureaucratique compl\u00e8tement invertie par l&rsquo;absurde, qui repr\u00e9sente une pure <em>narrative<\/em> fictionnelle pour dissimuler la catastrophe ainsi envisag\u00e9e, d&rsquo;ailleurs sans intention consciente \u00e0 cet \u00e9gard puisque la catastrophe bien r\u00e9elle n&rsquo;est pas envisag\u00e9e en tant que telle, puisqu&rsquo;un tel constat est impossible pour un programme de cette importance selon l&rsquo;<em>hybris<\/em> omnipr\u00e9sent de la bureaucratie technologiste am\u00e9ricaniste. Quoi qu&rsquo;il en soit des intentions conscientes de la <em>narrative<\/em>, l&rsquo;aveu qui se dessine objectivement est que la cinqui\u00e8me g\u00e9n\u00e9ration des avions de combat US est une pure catastrophe, un trou noir technologique o\u00f9 a sombr\u00e9 au neuf dixi\u00e8me le F-22, et o\u00f9 le JSF s&rsquo;appr\u00eaterait \u00e0 dispara\u00eetre, et que l&rsquo;on passerait \u00e0 la sixi\u00e8me en profitant des acquis d&rsquo;une g\u00e9n\u00e9ration qui a totalement sombr\u00e9 dans la catastrophe technologique et gestionnaire. L&rsquo;acrobatie de la logique est de tr\u00e8s haut vol. <\/p>\n<\/p>\n<p><p>\t Officiellement, la cause principale de la pr\u00e9occupation qui a \u00e9veill\u00e9 l&rsquo;angoisse du Pentagone serait la r\u00e9alisation que le JSF, bas\u00e9 sur les fameuse technologies furtives (<em>stealth<\/em>), se trouverait de plus en plus vuln\u00e9rable devant le d\u00e9veloppement des d\u00e9fenses anti-a\u00e9riennes qui se jouerait de ces fameuses technologies. On notera que cette pr\u00e9occupation est dans les esprits de nombreux commentateurs non-agr\u00e9\u00e9s par le Syst\u00e8me, pr\u00e9cis\u00e9ment depuis les ann\u00e9es 2009-2010 et l&rsquo;arriv\u00e9e \u00e0 maturit\u00e9 de nouveaux syst\u00e8mes de d\u00e9fense a\u00e9rienne russe, en m\u00eame temps que la disposition par les Russes de radars capables de d\u00e9tecter les avions de combat utilisant les technologies furtives. (Si l&rsquo;on creuse un peu plus l&rsquo;historique, on s&rsquo;aper\u00e7oit que l&rsquo;hypoth\u00e8se de cette menace contre les technologies furtives a toujours exist\u00e9, avec l&rsquo;hypoth\u00e8se de leur emploi pour la destruction d&rsquo;un F-117 furtif lors de la guerre du Kosovo, au printemps 1999. Dans tous les cas, le Pentagone lui-m\u00eame avait reconnu <em>de facto<\/em> d\u00e8s 2006,  voir le <a href=\"http:\/\/www.dedefensa.org\/article-le_jsf_de_plus_en_plus_facile_a_flinguer_14_03_2006.html\" class=\"gen\">14 mars 2006<\/a>,  la d\u00e9gradation des capacit\u00e9s furtives du JSF, constat\u00e9es comme nettement moindres que pr\u00e9vu.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>&#8230;In the case of the most expensive aircraft program in history, the Joint Strike Fighter (JSF), senior Pentagon officials have begun considering what might happen if the still-developmental F-35 were compromised by the proliferation of ever-more-capable air defenses.<\/em> [&#8230;] <MI There is a growing concern among senior officials in the Office of the Secretary of Defense about the proliferation of advanced air defense radars and anti-aircraft weapons, says an industry official familiar with these discussions. We took a long time on this. The threat is taking some turns on us. Senior officials are loath to cause alarm and jeopardize the coalition behind the F-35 and are thus tight-lipped about it.<D> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>We are starting to see the emergence of some stressing capabilities to our conventional forces, Al Shaffer, acting assistant secretary of defense for research and engineering, told Aviation Week during an interview last March. He was referring to the emergence of radars operating in very-high-frequency bands that can detect stealthy aircraft at long range. The concern is that these VHF radars could eventually pass targeting data to fire control elements for air defense systems.<\/em> [&#8230;] <em>Russian anti-stealth radar systems on display at the Moscow air show in 2013 justified concerns about stealth, and the Russians are thought to have made advances in integrating their air defenses. Also, a Chinese manufacturer last year showcased a so-called counter-stealth VHF active, electronically scanned array radar at the Zhuhai air show&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Notre \u00e9valuation de l&rsquo;apparition de cette inqui\u00e9tude du Pentagone est qu&rsquo;elle est <strong>directement li\u00e9e \u00e0 la crise ukrainienne<\/strong>, c&rsquo;est-\u00e0-dire \u00e0 la possibilit\u00e9 bien r\u00e9elle d&rsquo;un affrontement avec les Russes d&rsquo;une part ; c&rsquo;est-\u00e0-dire, \u00e9galement, avec le renforcement spectaculaire des liens strat\u00e9giques entre la Russie et la Chine \u00e0 la suite de cette crise, et des capacit\u00e9s militaires de la Chine elle-m\u00eame avec la livraison d&rsquo;armements russes tr\u00e8s avanc\u00e9s, comme celui de plusieurs bataillons de missiles sol-air S-400 <em>Triumf<\/em>. Dans ce cas o\u00f9 des conditions r\u00e9elles de conflit interf\u00e8rent sur les \u00e9valuations, l&rsquo;inqui\u00e9tude peut tr\u00e8s rapidement se transformer en panique comme on l&rsquo;a vu dans des cas pr\u00e9c\u00e9dents (apparition du MiG-15 contre les avions de combat US en Cor\u00e9e en 1950, soi-disant d\u00e9veloppement de bombardiers strat\u00e9giques sovi\u00e9tiques en 1954, puis des missiles intercontinentaux sovi\u00e9tiques en 1956, sup\u00e9riorit\u00e9 des MiG-17 et des MiG-21 sur les F-4 US en combat a\u00e9rien au Vietnam en 1965, etc.) Mais cette fois, les conditions sont tr\u00e8s diff\u00e9rentes sinon \u00e0 des ann\u00e9es-lumi\u00e8re des exemples cit\u00e9s, r\u00e9duisant ainsi \u00e0 n\u00e9ant l&rsquo;utilit\u00e9 op\u00e9rationnelle de l&rsquo;analogie, en raison de l&rsquo;ampleur colossale du programme JSF, de ses difficult\u00e9s techniques et gestionnaires sans nombre, des incertitudes \u00e9galement nombreuses de lancement d&rsquo;un rempla\u00e7ant, des d\u00e9lais \u00e9normes de ces d\u00e9cisions par rapport \u00e0 la rapidit\u00e9 de la diffusion de la crise en Ukraine et de l&rsquo;\u00e9volution de l&rsquo;antagonisme avec la Russie, etc. La vitesse des \u00e9v\u00e9nements avec l&rsquo;acc\u00e9l\u00e9ration de l&rsquo;Histoire et la contraction du temps, <strong>laissent sur-place, sinon en recul acc\u00e9l\u00e9r\u00e9e<\/strong> la machinerie bureaucratique du syst\u00e8me du technologisme, l&rsquo;un des deux composants du Syst\u00e8me avec le syst\u00e8me de la communication.<\/p>\n<\/p>\n<p><p>\t Ainsi envisage-t-on de d\u00e9velopper une r\u00e9flexion sur le th\u00e8me comment sauter&rsquo; par-dessus le JSF sans faire trop de d\u00e9g\u00e2ts, comme zaper le JSF et passer au d\u00e9veloppement du successeur de l&rsquo;avion triomphal d&rsquo;une cinqui\u00e8me g\u00e9n\u00e9ration qui n&rsquo;aurait ainsi jamais exist\u00e9 vraiment ; et l&rsquo;on ferait la chose en profitant de l&rsquo;exp\u00e9rience catastrophique du JSF, sans doute pour la renouveler,  <em>what else ?<\/em>,  et en cannibalisant des technologies brillantes mais inutiles du JSF pour les int\u00e9grer dans le sixi\u00e8me g\u00e9n\u00e9ration, sous doute pour les rendre caduques au moment de l&rsquo;usage,  <em>what else ?<\/em> Voici ce que nous en dit Amy Butler :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Pentagon is now planning for a substantial ramp-up in production for the fighter over the next five years. Even as the fifth-generation F-35 (bottom) is ushered into the fleet alongside fourth-generation predecessors, such as the F-16 (top), defense planners are eying options in case F-35 stealth technology is compromised<\/em>&#8230; [&#8230;]<\/p>\n<\/p>\n<p><p>\t<em> A follow-on to the F-35 could cannibalize some of these technologies and lessons for a new program but also incorporate more modern techniques and equipment, the industry official suggests. Options might include the use of cyberoffenses during campaign planning to cripple radars that could jeopardize stealthy allied aircraft. Improved thermal management systems could help guard against infrared threats, while advanced electronic countermeasures could protect a future jet at war.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Encore n&rsquo;a-t-on pas fait le tour des cons\u00e9quences incalculables d&rsquo;un abandon du JSF, si l&rsquo;on n&rsquo;a pas signal\u00e9 la cohorte des alli\u00e9s enfourn\u00e9s dans ce programme, en aveugle, fascin\u00e9s par le technologisme am\u00e9ricaniste et disciplin\u00e9s par les divers pr\u00e9bendes et manigances de la Grande R\u00e9publique (comme la liquidation en mai 2002 de <a href=\"http:\/\/www.dedefensa.org\/article-le_jsf_de_fortuyn_30_06_2002.html\" class=\"gen\">Pim Fortuyn<\/a>, leader populiste hollandais adversaire du JSF, quelques jours avant un vote crucial sur le JSF en Hollande, et son remplacement par un agent des SR hollandais infiltr\u00e9 dans le groupe politique). Butler reconna\u00eet que cette puissance formidable du programme JSF,  le rassemblement moutonnier de tous les alli\u00e9s asservis dans le programme,  peut devenir une terrible faiblesse dans l&rsquo;occurrence envisag\u00e9e. Assez curieusement, Butler n&rsquo;envisage que les faiblesses du JSF (en y ajoutant sa vuln\u00e9rabilit\u00e9 extr\u00eame \u00e0 l&rsquo;espionnage cybern\u00e9tique) comme sujet de pr\u00e9occupation pour ces alli\u00e9s, comme si le JSF continuait son bonhomme de chemin, alors qu&rsquo;il est question de l&rsquo;abandonner &#8230; A moins qu&rsquo;on ne r\u00e9serve une s\u00e9rie sp\u00e9ciale, estampill\u00e9e planche pourrie d&rsquo;honneur avec l&rsquo;exemplaire pay\u00e9 au prix fort (pour financer le successeur sixi\u00e8me g\u00e9n\u00e9ration ?), pour que ces alli\u00e9s aient tout de m\u00eame l&rsquo;impression d&rsquo;avoir un avion &#8230; Notre impression, \u00e0 nous, est celle d&rsquo;un bordel aux dimensions quasiment m\u00e9taphysiques, qui menace (dans le meilleur sens du mot pour notre compte) de faire passer le d\u00e9sordre-JSF en cat\u00e9gorie <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_tout_pour_le_pire_1998_2008_17_12_2014.html\" class=\"gen\">hyper-d\u00e9sordre<\/a>&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The main strength of the F-35global backing among Washington&rsquo;s alliescould become a weakness. Should the aircraft be compromised, perhaps by counterstealth technologies or a cyber hack, its impact would be equally global. A cyber intrusion into the program, in which terabytes of data were allegedly surveilled or stolen underscored this reality. Allies nervously awaited feedback on whether the so-called crown jewels of the F-35 were compromised in an alleged Chinese cyber intrusion into the program. Classified documents released by the notorious leaker Edward Snowden indicate some data related to the F-35 engine, thermal management system and radar were accessed by the hackers. Program spokesman Joe Dellavedova maintains that no damage was done to the program. Put simply, the F-35 is still a huge target for adversaries.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t L&rsquo;\u00e9tude continue, avec l&rsquo;annonce triomphale que l&rsquo;USAF et la Navy ont h\u00e9rit\u00e9 des acronymes pleins de promesse pour leurs \u00e9ventuels joyaux de sixi\u00e8me g\u00e9n\u00e9ration,  F-X pour l&rsquo;USAF, F\/A-XX pour la Navy. La d\u00e9cision, dans l&rsquo;urgence qu&rsquo;on comprend o\u00f9 l&rsquo;on est invit\u00e9 \u00e0 se presser extr\u00eamement doucement, est attendue pour 2017, comme cadeau d&rsquo;investiture pour le nouveau pr\u00e9sident (ou la nouvelle pr\u00e9sidente,  clin d&rsquo;il). Le choix lui sera donn\u00e9, entre poursuivre la catastrophe-JSF comme elle continue \u00e0 se d\u00e9velopper dans le sens autodestructeur, ou lancer un nouveau programme, <em>sexy<\/em>-sixi\u00e8me g\u00e9n\u00e9ration &#8230; D&rsquo;ici l\u00e0, c&rsquo;est pli\u00e9 et bien rang\u00e9, l&rsquo;Ukraine aura adh\u00e9r\u00e9 aux BRICS et \u00e0 l&rsquo;Organisation de Coop\u00e9ration de Shanghai.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>These senior officials are in the preliminary stages of examining options should stealthone of the F-35&rsquo;s key attributesbe compromised by new technology. The idea is to be able to hand off to the next presidential administration both a healthy F-35 programno small feat, after its years of pitfalls and overrunsand other options should the next president find the aircraft&rsquo;s technology outdated, the industry source says. The hope is the F-35&rsquo;s technology will be viable for decades to come.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, l&rsquo;on comprend bien que cet article, refl\u00e9tant un climat et des hypoth\u00e8ses aussi radicales, marque symboliquement mais aussi au niveau de la communication un grand tournant, d&rsquo;abord pour les psychologies \u00e0 fleur de peau lorsqu&rsquo;il s&rsquo;agit des attributs au moins symboliques de la puissance de l&rsquo;am\u00e9ricaniste, ensuite pour conditionner les pens\u00e9es vers cette possibilit\u00e9 catastrophique qui embrasse tout le domaine de l&rsquo;<em>hybris<\/em> exceptionnaliste de l&rsquo;am\u00e9ricanisme. Lorsqu&rsquo;on consid\u00e8re les notions de d\u00e9lai consid\u00e9rable pour ces op\u00e9rations, la dynamique irr\u00e9sistible de l&rsquo;effondrement du technologisme, le d\u00e9calage extraordinaire entre les planifications envisag\u00e9es et les \u00e9v\u00e9nements op\u00e9rationnels qui en sont la cause conjoncturelle, on comprend que cette perspective de l&rsquo;abandon du JSF n&rsquo;est pas un revers, m\u00eame catastrophique, mais bel et bien la reconnaissance d&rsquo;une impasse catastrophique du syst\u00e8me du technologisme qui renvoie sans le moindre doute \u00e0 la crise d&rsquo;effondrement du Syst\u00e8me, avec des cons\u00e9quences op\u00e9rationnelles \u00e9galement catastrophiques et tr\u00e8s rapides pour la situation strat\u00e9gique des USA (et de leurs alli\u00e9s moutonniers, certes,  mais qui s&rsquo;en soucie, vraiment ?).<\/p>\n<\/p>\n<p><p>\t(Une simple connaissance courante des situations des forces arm\u00e9es nous dit que la crise que constituerait la planification du r\u00e9\u00e9quipement des forces a\u00e9riennes concern\u00e9es, dont celles des USA au premier chef \u00e9videmment en cas d&rsquo;abandon du programme JSF,  et avec une d\u00e9cision report\u00e9e \u00e0 2017, alors que le programme se poursuivrait avec cette \u00e9p\u00e9e de Damocl\u00e8s suspendu au-dessus de lui !  placerait ces forces a\u00e9riennes dans une position sans pr\u00e9c\u00e9dent avec des effectifs en r\u00e9duction constante depuis des ann\u00e9es, et des \u00e9quipements compl\u00e8tement d\u00e9pass\u00e9s et extr\u00eamement vuln\u00e9rables&#8230; [Jusqu&rsquo;\u00e0 des incidents gravissimes et in\u00e9dits, car ne dit-on pas que l&rsquo;accident du F-16 grec sur une base espagnole, qui a tu\u00e9 une dizaine de pilotes fran\u00e7ais, serait du \u00e0 une d\u00e9ficience, sinon \u00e0 une vuln\u00e9rabilit\u00e9 catastrophiques \u00e0 des interventions ext\u00e9rieures, du F-16 qui constitue l&rsquo;\u00e9quipement principal de l&rsquo;USAF et de nombre de forces a\u00e9riennes ?]. On conna\u00eet depuis des ann\u00e9es les perspectives \u00e0 cet \u00e9gard, qui n&rsquo;ont fait que s&rsquo;aggraver depuis : voir le <a href=\"http:\/\/www.dedefensa.org\/article-l_usaf_vacille_sur_sa_crise_11_11_2007.html\" class=\"gen\">11 novembre 2007<\/a>, le <a href=\"http:\/\/www.dedefensa.org\/article-la_crise_des_f-15_une_crise_usaf_29_12_2007.html\" class=\"gen\">29 d\u00e9cembre 2007<\/a>, le <a href=\"http:\/\/www.dedefensa.org\/article-apr_s_les_f-15_les_f-16_17_05_2008.html\" class=\"gen\">17 mai 2008<\/a>, le <a href=\"http:\/\/www.dedefensa.org\/article-notes_autour_de_l_air_dominance_en_perdition_12_12_2008.html\" class=\"gen\">12 d\u00e9cembre 2008<\/a>.)<\/p>\n<\/p>\n<p><p>\tBien entendu, dans le contexte g\u00e9n\u00e9ral o\u00f9 les crises se multiplient dans tous les domaines comme effets et cons\u00e9quences de la crise d&rsquo;effondrement du Syst\u00e8me, on ne peut \u00e9viter de consid\u00e9rer la signification de la perspective ainsi offerte dans ce m\u00eame contexte g\u00e9n\u00e9ral. On a souvent \u00e9voqu\u00e9 cette hypoth\u00e8se, et l&rsquo;on se trouve aujourd&rsquo;hui devant son \u00e9vocation quasi-officielle, impliquant qu&rsquo;on en arrive \u00e0 une \u00e9tape o\u00f9 l&rsquo;hypoth\u00e8se tend \u00e0 se concr\u00e9tiser dans les faits op\u00e9rationnels. Un \u00e9chec du JSF marqu\u00e9 par la possibilit\u00e9 de son abandon, c&rsquo;est un revers que nous n&rsquo;h\u00e9siterions pas \u00e0 qualifier de d\u00e9cisif pour le syst\u00e8me du technologisme dans son ensemble, c&rsquo;est-\u00e0-dire pour le Progr\u00e8s lui-m\u00eame dans sa composante essentielle du technologisme. Il s&rsquo;agirait de la d\u00e9monstration qu&rsquo;on a atteint et d\u00e9pass\u00e9, dans un domaine fondamental du technologisme, le pic d&rsquo;efficience maximale et qu&rsquo;on se trouve sur la pente catastrophique de l&rsquo;inefficacit\u00e9, de la paralysie, de l&rsquo;impuissance, l\u00e0 o\u00f9 tout effort progressiste suppl\u00e9mentaire ne fait qu&rsquo;aggraver les conditions de la catastrophe dans un parfait mouvement d&rsquo;inversion caract\u00e9risant l&rsquo;\u00e9volution du Syst\u00e8me par la transmutation de sa dynamique de surpuissance en dynamique d&rsquo;autodestruction. Ainsi serait-il \u00e9crit que le JSF aurait tout de m\u00eame apport\u00e9 une contribution vitale et m\u00e9tahistorique \u00e0 la r\u00e9alisation de notre situation,  une d\u00e9monstration par l&rsquo;absurde de l&rsquo;impasse d&rsquo;une civilisation arriv\u00e9e au terme de sa possibilit\u00e9 de d\u00e9veloppement et \u00e0 l&rsquo;ach\u00e8vement de sa transmutation en contre-civilisation.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 6 f\u00e9vrier 2015 \u00e0 05H17<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalement, si l&rsquo;on zapait le JSF ? Il s&rsquo;agit d&rsquo;un article des plus s\u00e9rieux, sign\u00e9 par Amy Butler, une des grandes signatures du fameux Aviation Week &#038; Space Technology. (Le 4 f\u00e9vrier 2015, publi\u00e9 dans le num\u00e9ro d&rsquo;AW&#038;ST du 5 f\u00e9vrier.) Cet hebdomadaire n&rsquo;\u00e9crit rien, surtout sur un sujet aussi br\u00fblant que le JSF\/F-35, sans&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7770,4030,14710,4195,3633,3977,9003,10015,3019,2651,8116,4481,16079,9054,250,4310,2730,8289,7513,3411,3014,3519,4268,6532,4247],"class_list":["post-75745","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-abandon","tag-amy","tag-anti-aerienne","tag-aviation","tag-butler","tag-chine","tag-cinquieme","tag-contre-civilisation","tag-defense","tag-du","tag-furtive","tag-generation","tag-hyper-desordre","tag-inversion","tag-jsf","tag-progres","tag-russie","tag-s-400","tag-sixieme","tag-stealth","tag-systeme","tag-technologie","tag-technologisme","tag-vulnerabilite","tag-week"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75745"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75745\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}