{"id":75809,"date":"2015-03-16T05:38:38","date_gmt":"2015-03-16T05:38:38","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/03\/16\/glossairedde-crisis-la-maniaco-depression-du-monde\/"},"modified":"2015-03-16T05:38:38","modified_gmt":"2015-03-16T05:38:38","slug":"glossairedde-crisis-la-maniaco-depression-du-monde","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/03\/16\/glossairedde-crisis-la-maniaco-depression-du-monde\/","title":{"rendered":"<em>Glossaire.dde-crisis<\/em>: la maniaco-d\u00e9pression du monde"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\"><em>Glossaire.dde-crisis <\/em>: la maniaco-d\u00e9pression du monde<\/h2>\n<\/p>\n<p><p>16 mars 2015 &ndash; Ce <em>Glossaire.dde-crisis<\/em> reprend le texte de <em>dde.crisis<\/em> du 10 janvier 2012. Les conditions de cette politique de \u00ab\u00a0reprise\u00a0\u00bb des textes de divers num\u00e9ros de <em>dde.crisis<\/em> sont explicit\u00e9es dans le texte du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_glossairedde-crisis_28_11_2014.html\">28 novembre 2014<\/a> dans cette rubrique.<\/p>\n<\/p>\n<p><p>Cette livraison de <em>dde.crisis<\/em> tentait de d\u00e9velopper une th\u00e8se, prenant tr\u00e8s fortement en compte selon notre habitude la dimension psychologique, selon laquelle les \u00e9v\u00e8nements du monde, essentiellement dans la p\u00e9riode moderniste et surtout avec le \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_cha_nement_de_la_mati_re__05_11_2012.html\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00ab\u00a0, sont directement en rapport, selon des formes complexes de cause-\u00e0-effet, avec la pathologie de la maniaco-d\u00e9pression. De ce fait, cette affection devient, sous cette influence, l&rsquo;\u00e9tat normal de la psychologie humaine individuelle et collective face \u00e0 la crise.<\/p>\n<\/p>\n<p><p>Dans cette d\u00e9marche, le principe m\u00eame de notre hypoth\u00e8se est de prendre la r\u00e9f\u00e9rence de la maniaco-d\u00e9pression et d&rsquo;en inverser les termes selon la gravit\u00e9 qui est pr\u00eat\u00e9e habituellement aux \u00e9pisodes (maniaque et d\u00e9pressif). L\u00e0 aussi, nous retrouvons notre compagnon habituel de la phase crisique (ultime) postmoderne de la crise de la modernit\u00e9 : l&rsquo;inversion. L&rsquo;hypoth\u00e8se est conduite dans le champ de l'\u00a0\u00bbop\u00e9rationnalisation\u00a0\u00bb, c&rsquo;est-\u00e0-dire appliqu\u00e9e dans notre histoire crisique contemporaine, essentiellement \u00e0 partir du tournant de 1996 (JO d&rsquo;Atlanta) puis du 11 septembre 2001, puis de la crise financi\u00e8re de l&rsquo;automne 2008, jusqu&rsquo;aux \u00e9v\u00e9nements les plus r\u00e9cents (\u00ab\u00a0printemps arabe\u00a0\u00bb, mouvement <em>Occupy<\/em>, ultime limite chronologique pour ce texte qui est du d\u00e9but 2012)&#8230;<\/p>\n<\/p>\n<p><p>Notre intention ultime n&rsquo;\u00e9tait pas de \u00ab\u00a0psychanalyser\u00a0\u00bb une \u00e9poque mais, au contraire, \u00e0 partir de sympt\u00f4mes qui font le miel de la psychanalyse, de d\u00e9terminer la place de la psychologie dans cette \u00e9poque, &ndash; place centrale, sans aucun doute, &ndash; d&rsquo;y relever les pouss\u00e9es d&rsquo;inversion qui conduisent nombre de <em>sapiens<\/em> \u00e0 la psychologie trop faible pour r\u00e9sister \u00e0 se pr\u00e9cipiter dans les rets du Syst\u00e8me, c&rsquo;est-\u00e0-dire dans la plus extr\u00eame proximit\u00e9 du Mal. Selon cette perspective, le ph\u00e9nom\u00e8ne de la maniaco-d\u00e9pression du monde constitue la clef explicative de l'\u00a0\u00bbop\u00e9rationnalisation\u00a0\u00bb du Mal s&rsquo;exprimant par la modernit\u00e9, c&rsquo;est-\u00e0-dire le fondement op\u00e9rationnel de notre crise, et aussi la mesure eschatologique fondamentale de cette crise.<\/p>\n<\/p>\n<p><p>Le texte est suivi d&rsquo;une partie sp\u00e9cifique dite \u00ab\u00a0Notes du temps pr\u00e9sent\u00a0\u00bb, qui constitue notre appr\u00e9ciation critique <strong>minimale<\/strong> de ce texte de janvier 2012, en fonction des \u00e9v\u00e9nements qui se sont d\u00e9roul\u00e9s depuis et, <strong>surtout<\/strong>, de l&rsquo;\u00e9volution de notre pens\u00e9e \u00e0 cet \u00e9gard. Cette intervention est pr\u00e9sent\u00e9e de cette fa\u00e7on dans le texte r\u00e9f\u00e9renc\u00e9 ci-dessus :<\/p>\n<\/p>\n<p><p>&laquo;<em>Le texte sera retranscrit d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale tel qu&rsquo;il fut \u00e9crit et publi\u00e9 \u00e0 son \u00e9poque (sauf pour une coquille tra&icirc;nant ici ou l\u00e0, voire une maladresse formelle d&rsquo;\u00e9criture qui demande r\u00e9paration). Par contre, il y aura une sorte de \u00ab\u00a0commentaire\u00a0\u00bb venu du \u00ab\u00a0temps pr\u00e9sent\u00a0\u00bb, &ndash; car la pens\u00e9e \u00e9volue et la contraction du temps nourrit d&rsquo;autant plus cette \u00e9volution, &ndash; sous la forme de notes sur tel ou tel point de d\u00e9tail, sur tel ou tel sens d&rsquo;un jugement, montrant effectivement cette \u00e9volution et observant la fa\u00e7on dont cette \u00e9volution s&rsquo;est faite. Il s&rsquo;agit d&rsquo;une \u00ab\u00a0actualisation\u00a0\u00bb dans le sens le plus large possible, puisqu&rsquo;il s&rsquo;agit<\/em> <strong><em>aussi et surtout<\/em><\/strong> <em>d&rsquo;une volont\u00e9 de poursuivre, d&rsquo;\u00e9largir, d&rsquo;enrichir, de transmuter \u00e9ventuellement les diff\u00e9rents concepts expos\u00e9s, comment\u00e9s et document\u00e9s. On ne se trouve donc nullement dans le cas syst\u00e9matique d&rsquo;une reprise d&rsquo;archives telles quelles, mais d&rsquo;une reprise d&rsquo;archives en relation directe avec les \u00e9v\u00e9nements courants (de notre temps pr\u00e9sent), et surtout en relation serr\u00e9e avec l&rsquo;\u00e9volution de la pens\u00e9e depuis la publication de ces textes.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>____________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">La maniaco-d\u00e9pression du monde<\/h2>\n<\/p>\n<p><p>Nous allons d\u00e9velopper une tentative d&rsquo;explication de la situation actuelle et de la crise \u00e9videmment eschatologique qui la caract\u00e9rise en nous r\u00e9f\u00e9rant \u00e0 deux facteurs essentiellement: d&rsquo;une part la psychologie, d&rsquo;autre part ce que nous consid\u00e9rons comme la principale maladie de la psychologie, &ndash; l&rsquo;essence m\u00eame de la maladie, ou l&rsquo;essence du mal de la psychologie, &ndash; qui est la maniaco-d\u00e9pression. (On verra pourquoi, plus loin, nous la cat\u00e9gorisons comme la \u00ab\u00a0principale\u00a0\u00bb maladie de la psychologie.)<\/p>\n<\/p>\n<p><p>Nous avons d\u00e9j\u00e0 souvent cit\u00e9 le docteur psychiatre am\u00e9ricain Beard, identifiant en 1879 la neurasth\u00e9nie comme \u00ab\u00a0le mal am\u00e9ricain\u00a0\u00bb ou, dit autrement, ce que nous pourrions d\u00e9signer comme \u00ab\u00a0le mal de la modernit\u00e9\u00a0\u00bb. A la lumi\u00e8re des plus r\u00e9cents \u00e9v\u00e9nements et de l&rsquo;\u00e9volution de l&rsquo;interpr\u00e9tation que nous en faisons, nous serions tent\u00e9s plut\u00f4t de choisir la maniaco-d\u00e9pression comme \u00ab\u00a0mal de la modernit\u00e9\u00a0\u00bb. Pourtant, la maniaco-d\u00e9pression, qui est une maladie ancienne, n&rsquo;est pas sp\u00e9cifiquement li\u00e9e aux conditions de vie de la modernit\u00e9, au contraire de la neurasth\u00e9nie, ou \u00ab\u00a0fatigue nerveuse\u00a0\u00bb&#8230; (&laquo;<em>La nervosit\u00e9 am\u00e9ricaine est le produit de la civilisation am\u00e9ricaine.<\/em> [&#8230;] [N]<em>ous ne pouvons pas avoir la civilisation et tout le reste ; dans notre marche en avant, nous perdons de vue, et perdons en effet, la r\u00e9gion que nous avons traverse<\/em>.&raquo;)<\/p>\n<\/p>\n<p><p>Justement, ce qui nous int\u00e9resse comme identification du \u00ab\u00a0mal de la modernit\u00e9\u00a0\u00bb, c&rsquo;est justement ce qui n&rsquo;est pas li\u00e9 \u00e0 la modernit\u00e9, pour mettre en \u00e9vidence combien la modernit\u00e9 est pour nous une crise bien diff\u00e9rente de la crise d&rsquo;une \u00e9poque, d&rsquo;un temps, d&rsquo;une technique, d&rsquo;une circonstance; combien la modernit\u00e9 est, pour nous, le terme irr\u00e9m\u00e9diable de la crise fondamentale de notre civilisation devenue contre-civilisation&#8230; Dans ce cadre, la maniaco-d\u00e9pression, selon son appellation classique, nous para&icirc;t \u00eatre un \u00ab\u00a0mod\u00e8le\u00a0\u00bb ad\u00e9quat pour conduire notre enqu\u00eate sur ce qui nous appara&icirc;t sans aucun doute comme une pathologie, non pas d&rsquo;une civilisation, mais de \u00ab\u00a0la\u00a0\u00bb civilisation en g\u00e9n\u00e9ral, l\u00e0 o&ugrave; nous l&rsquo;avons conduite, comme terme qui se voudrait ultime pour ce qui est du sens du d\u00e9veloppement de notre esp\u00e8ce, &ndash; bref, ce qui serait la pathologie finale r\u00e9sultant de notre chute, &ndash; si l&rsquo;on accepte, comme nous y sommes inclin\u00e9s, la th\u00e9orie cyclique de la Tradition. Nous parlons bien de la maniaco-d\u00e9pression et nullement de ce qu&rsquo;elle est devenue, au travers de son nouveau nom d'\u00a0\u00bbaffection bipolaire\u00a0\u00bb, selon une expression plus \u00ab\u00a0scientifique\u00a0\u00bb que nous n&rsquo;affectionnons gu\u00e8re dans son \u00e9nonc\u00e9, dans le sens o&ugrave; elle tend \u00e0 neutraliser les caract\u00e8res essentiels, et qui nous importent essentiellement, de la maniaco-d\u00e9pression.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">D&rsquo;une affection \u00e0 un destin<\/h2>\n<\/p>\n<p><p>Il doit \u00eatre entendu et bien clairement compris et accept\u00e9 que nous n&rsquo;avons aucunement l&rsquo;intention d&rsquo;envisager la maniaco-d\u00e9pression d&rsquo;un point de vue m\u00e9dical classique. Ce point de vue ne nous int\u00e9resse en aucune fa\u00e7on, dans la mesure o&ugrave; il tend continuellement \u00e0 se replier sur la chimie, sur la mati\u00e8re organique la plus grossi\u00e8re, pour \u00e9viter toute question qui risquerait de compliquer la probl\u00e9matique de la chose en la projetant hors des bornes de la soi-disant \u00ab\u00a0hygi\u00e8ne mentale\u00a0\u00bb. De m\u00eame, cette d\u00e9marche conduit n\u00e9cessairement \u00e0 attirer vers le bas une situation qui affecte l&rsquo;\u00e2me et l&rsquo;esprit.<\/p>\n<\/p>\n<p><p>Il nous importe donc absolument d&rsquo;\u00e9viter le labyrinthe des d\u00e9finitions et identifications d&rsquo;une maladie \u00e0 laquelle, manifestement, la \u00ab\u00a0science moderne\u00a0\u00bb (la m\u00e9decine du monde occidentaliste et moderniste) ne comprend <strong>rien<\/strong> pour l&rsquo;essentiel de la chose, &ndash; c&rsquo;est-\u00e0-dire son essence m\u00eame. Par contre, pour notre propos, il nous importe d&rsquo;indiquer qu&rsquo;il existe une touche personnelle dans notre d\u00e9marche qui est de proposer une maladie humaine et individuelle comme mod\u00e8le de la crise fondamentale de l&rsquo;univers que nous traversons aujourd&rsquo;hui. Disons que \u00ab\u00a0nous avons connu et connaissons\u00a0\u00bb de mani\u00e8re personnelle et intime la maniaco-d\u00e9pression dans sa puissance comme source de souffrance et de d\u00e9sarroi, dans ses effets sur les relations et les sentiments entre des \u00eatres proches, sur leurs jugements, sur leurs <strong>\u00e2mes<\/strong> m\u00eame, dans sa capacit\u00e9 de subversion du monde au travers de la psychologie tortur\u00e9e. (1) Nous introduisons une dimension personnelle qui n&rsquo;est nullement anecdotique mais qui, au contraire, pr\u00e9tend rapprocher de ce que nous nommons \u00ab\u00a0l&rsquo;intuition haute\u00a0\u00bb, c&rsquo;est-\u00e0-dire l&rsquo;intuition comme inspiratrice de la pens\u00e9e, comme ma&icirc;tresse de la raison elle-m\u00eame en la prot\u00e9geant de son travers inf\u00e2me de [l&rsquo;<em>hybris<\/em>].<\/p>\n<\/p>\n<p><p>D&rsquo;autre part, loin de donner \u00e0 notre propos un aspect \u00e9motionnel, cette \u00ab\u00a0touche personnelle\u00a0\u00bb permet au contraire de comprendre combien l&rsquo;\u00e9motion n&rsquo;est qu&rsquo;un facteur extr\u00eamement relatif et mall\u00e9able dans une circonstance qui touche si profond\u00e9ment aux fondements de l&rsquo;\u00e2me humaine d&rsquo;une part, aux fondements structurels de l&rsquo;univers d&rsquo;autre part, &ndash; si l&rsquo;on accepte notre hypoth\u00e8se en forme d&rsquo;analogie. L&rsquo;\u00e9motion n&rsquo;est pas un facteur indiff\u00e9rent, elle n&rsquo;est pas un facteur informe et sans signification; elle n&rsquo;est pas un facteur, disons, \u00ab\u00a0sentimental\u00a0\u00bb dans le sens caricatural et informe du mot que l&rsquo;on comprend bien&#8230; Elle est un facteur qu&rsquo;on pourrait plut\u00f4t comparer \u00e0 un d\u00e9tonateur ou \u00e0 un incitateur, qui pousse vers l&rsquo;exploration et la compr\u00e9hension de certaines \u00e9nigmes fondamentales. Comment est-il possible qu&rsquo;une affection de la sorte puisse d\u00e9ranger si fondamentalement des engagements de l&rsquo;\u00e2me qu&rsquo;on croirait absolument assur\u00e9s? De quelle puissance s&rsquo;agit-il en v\u00e9rit\u00e9, que la puissance de cette affection qu&rsquo;est la maniaco-d\u00e9pression? Le sentiment n&rsquo;est pas, dans ce cas, un facteur indiff\u00e9rent, d&rsquo;autant qu&rsquo;il gouverne bien plus que nous le croyons, certains de nos jugements et de nos choix fondamentaux.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">De la pathologie individuelle \u00e0 la m\u00e9taphysique de la crise<\/h2>\n<\/p>\n<p><p>Un autre aspect important de ce \u00ab\u00a0mod\u00e8le\u00a0\u00bb de la maniaco-d\u00e9pression que nous allons utiliser comme moyen d&rsquo;interpr\u00e9tation de la crise du monde concerne la notion, existante dans la pathologie que nous citons, de l&rsquo;encha&icirc;nement des \u00e9pisodes d\u00e9pressifs et maniaques. Dans l&rsquo;analogie offerte pour notre crise, aucun de ces \u00e9pisodes ne se cl\u00f4t compl\u00e8tement pour laisser la place \u00e0 l&rsquo;autre apr\u00e8s un intervalle de \u00ab\u00a0normalit\u00e9\u00a0\u00bb; ils sont tous deux plus ou moins actifs et en \u00e9tat d&rsquo;activit\u00e9 potentielle parall\u00e8lement, certes jusqu&rsquo;\u00e0 des intensit\u00e9s parfois extraordinairement \u00e9loign\u00e9s mais sans jamais la rupture entre ce qui est actif et ce qui est compl\u00e8tement inerte. Cette remarque hypoth\u00e9tique concerne la projection illustrative et symbolique que nous voudrions faire, \u00e0 partir de la pathologie de la psychologie humaine, vers une situation hypoth\u00e9tique de notre monde au moment de sa crise fondamentale. Nous croyons que nous parviendrons \u00e0 mieux rendre compte des caract\u00e8res de cette crise, et \u00e0 approcher une conception qui donne \u00e0 la psychologie, au niveau collectif d&rsquo;un monde et d&rsquo;une crise, une place absolument essentielle. En agissant de la sorte (en maintenant ensemble les caract\u00e8res d\u00e9pressif et maniaque), nous saisissons en effet ce qui nous para&icirc;t \u00eatre la substance m\u00eame de la crise, qui est de disposer de tous les facteurs de sa pathologie fondamentale, au m\u00eame moment, par cons\u00e9quent disposant des outils capables de susciter un \u00e9v\u00e9nement fondamental, sans que son orientation soit assur\u00e9ment bonne ou mauvaise.<\/p>\n<\/p>\n<p><p>Cette fa\u00e7on de proc\u00e9der dans l&rsquo;analyse lanc\u00e9e pour substantiver l&rsquo;hypoth\u00e8se qui nous guide permet de justifier notre approche g\u00e9n\u00e9rale de la crise qui est d&rsquo;observer que son issue catastrophique n&rsquo;est nullement assur\u00e9e, ou, mieux encore, qu&rsquo;une issue catastrophique de la situation pr\u00e9sente n&rsquo;est pas n\u00e9cessairement une catastrophe pure et simple mais peut \u00eatre une purge gigantesque n\u00e9cessaire avant une hypoth\u00e9tique renaissance. Ainsi sommes-nous confront\u00e9s \u00e0 des perspectives extr\u00eames, m\u00e9langeant le pire et le meilleur, o&ugrave; le pire peut dissimuler le meilleur ou en \u00eatre le g\u00e9niteur inattendu. En assimilant d\u00e9pression et \u00e9pisode maniaque comme des affections parall\u00e8les, nous rendons compte en effet de la v\u00e9ritable manifestation du d\u00e9sordre de cette civilisation, qui est non seulement son absence de sens mais son absence de conscience de la n\u00e9cessit\u00e9 d&rsquo;un sens. La maladie, par sa forme de d\u00e9sordre pur, duplique le d\u00e9sordre du monde et fait r\u00e9aliser, parce qu&rsquo;elle est une pathologie, que le d\u00e9sordre du monde est lui-m\u00eame une pathologie. (2)<\/p>\n<\/p>\n<p><p>Ainsi l&rsquo;affection individuelle acquiert-elle, par un simple effort d&rsquo;extension de l&rsquo;interpr\u00e9tation, une dimension collective. Cette dimension collective, par le probl\u00e8me qu&rsquo;elle soul\u00e8ve, &ndash; le d\u00e9sordre du monde dans sa crise terminale et la catastrophe terminale comme \u00e9ventuelle voie de r\u00e9surrection, &ndash; est n\u00e9cessairement une introduction de cette crise terminale dans le domaine de la m\u00e9taphysique. Le lien est ainsi fermement \u00e9tabli entre l&rsquo;individu et la crise du monde, et entre la crise du monde et la dimension m\u00e9taphysique dont cette crise doit \u00eatre investie pour d\u00e9couvrir l&rsquo;essence de ce qui lui succ\u00e9dera. C&rsquo;est une \u00ab\u00a0eschatologisation\u00a0\u00bb de la crise de la civilisation, mais dans le sens de restituer un sens \u00e0 cette crise.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Puissance et substance de la maniaco-d\u00e9pression<\/h2>\n<\/p>\n<p><p>Notre hypoth\u00e8se fondamentale pour la compr\u00e9hension de la crise terminale, existentielle et eschatologique que nous connaissons est que, du point de vue du <em>sapiens<\/em> qui entend occuper le centre de la sc\u00e8ne du monde, la force principale (positive ou n\u00e9gative c&rsquo;est selon) est la psychologie et non la pens\u00e9e elle-m\u00eame. Nous sommes dans un monde o&ugrave; la raison humaine, d\u00e9j\u00e0 pervertie par plusieurs si\u00e8cles d&rsquo;une situation subversive du monde, se trouve confront\u00e9e \u00e0 des forces d&rsquo;une puissance extraordinaire, &ndash; les deux composants du Syst\u00e8me, le syst\u00e8me du technologisme et le syst\u00e8me de la communication, &ndash; qui introduisent un chaos de faits, d&rsquo;informations et d&rsquo;influences interdisant tout espoir \u00e0 cette raison subvertie qu&rsquo;elle puisse susciter une pens\u00e9e juste et vraie d\u00e9termin\u00e9e selon l&rsquo;habituelle d\u00e9marche de la chose. (3) La psychologie, par contre, est en soi une capacit\u00e9 de perception du monde sans le filtre de la pens\u00e9e, qui reste capable dans ce chaos g\u00e9n\u00e9ral de percevoir faits et informations bruts ; c&rsquo;est-\u00e0-dire que, si la psychologie peut bien s&ucirc;r percevoir la tromperie et la mystification sans s&rsquo;aviser de ces caract\u00e8res et donc se faire le v\u00e9hicule inconscient de cette tromperie et de cette mystification, &ndash; mais la raison, aujourd&rsquo;hui, ne fait pas mieux [puisqu&rsquo;elle fait pire], &ndash; elle est aussi capable de percevoir des <strong>v\u00e9rit\u00e9s<\/strong> qui \u00e9chappent au travail de d\u00e9formation du Syst\u00e8me. Le grand d\u00e9fi est, bien entendu, de distinguer ces v\u00e9rit\u00e9s du reste; il n&#8217;emp\u00eache, et c&rsquo;est l&rsquo;essentiel, que cette possibilit\u00e9-l\u00e0 existe.<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9mergence de la psychologie comme canal essentiel et surtout comme canal autonome (sans intervention de la raison humaine) de notre perception du monde est une cons\u00e9quence, non d&rsquo;un choix int\u00e9rieur, non d&rsquo;une n\u00e9cessit\u00e9 organique ou spirituelle, mais bien d&rsquo;une occurrence technique. C&rsquo;est le d\u00e9veloppement de \u00ab\u00a0notre\u00a0\u00bb Syst\u00e8me qui conduit \u00e0 cette mise en \u00e9vidence de la psychologie. Mystificateur par nature, \u00ab\u00a0persifleur\u00a0\u00bb, intoxicateur, d\u00e9sinformateur et virtualiste, le Syst\u00e8me a choisi de parfaire son empire sur la raison humaine par la communication. Ce d\u00e9veloppement a conduit au syst\u00e8me de la communication, dont on conna&icirc;t les sp\u00e9cificit\u00e9s \u00e9tranges, presque d&rsquo;autonomie. Le syst\u00e8me de la communication agit essentiellement par le canal de la psychologie. C&rsquo;est lui qui a suscit\u00e9 cette importance fondamentale de la psychologie, en transformant sa fonction de r\u00e9ceptacle passif de la perception du monde, en une fonction plus active, plus complexe, et qui s&rsquo;est r\u00e9v\u00e9l\u00e9e \u00eatre, par rapport au Syst\u00e8me, \u00e0 double tranchant. Le caract\u00e8re de Janus du syst\u00e8me de la communication, sur lequel nous nous sommes souvent arr\u00eat\u00e9s, a nourri l&rsquo;ambigu\u00eft\u00e9, du point de vue du Syst\u00e8me, de la perception du monde par notre psychologie dans l&rsquo;\u00e9poque postmoderniste o&ugrave; triomphe le syst\u00e8me de la communication. Ainsi trouve-t-on expos\u00e9e une de nos pr\u00e9misses menant au constat de la proximit\u00e9 extraordinaire de caract\u00e8res individuels et collectifs, par le biais de la psychologie, et d\u00e9bouchons-nous sur la question des pathologies.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La psychologie permet l&rsquo;appel \u00e0 l'\u00a0\u00bbintuition haute\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>Cette quasi-substitution de la psychologie, \u00e0 la place d&rsquo;une raison subvertie par la subversion initiale (le \u00ab\u00a0persiflage\u00a0\u00bb du XVIII\u00e8me si\u00e8cle), par le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb installant enfin le Syst\u00e8me tel que nous l&rsquo;identifions, constitue une sorte d&rsquo;automatisme organique renvoyant au comportement habituel, d&rsquo;une part ; mais \u00e9galement une ruse sublime, dont on peut deviner la racine m\u00e9taphysique, d&rsquo;autre part. En quelque sorte, c&rsquo;est notre sauvegarde, ceci qui interdit que nous soyons tout entier sous l'\u00a0\u00bbempire de la raison\u00a0\u00bb, &ndash; de la raison subvertie par la Mati\u00e8re, donc nous-m\u00eames prisonniers de la Mati\u00e8re.<\/p>\n<\/p>\n<p><p>De ce fait, l&rsquo;acc\u00e8s n&rsquo;est pas compl\u00e8tement ferm\u00e9 \u00e0 ce qui repr\u00e9sente la sauvegarde de l&rsquo;esprit, ce qui peut le sauver de l&rsquo;an\u00e9antissement en tant qu&rsquo;esprit dans la Chute. Puisqu&rsquo;elle ne distingue pas entre la tromperie et la v\u00e9rit\u00e9, la psychologie peut aussi bien permettre l&rsquo;acc\u00e8s \u00e0 notre esprit de ce que nous nommons l'\u00a0\u00bbintuition haute\u00a0\u00bb; si ce n&rsquo;\u00e9tait le cas, si la raison avait charge exclusive de la chose, la subversion qui la caract\u00e9rise et sa soumission au Syst\u00e8me interdisant l&rsquo;acc\u00e8s \u00e0 l&rsquo;esprit de toute \u00ab\u00a0intuition haute\u00a0\u00bb en tant que telle, elle condamnerait le ph\u00e9nom\u00e8ne de l&rsquo;intuition comme une aberration, ou le subvertirait \u00e0 sa fa\u00e7on en en faisant un \u00ab\u00a0accident\u00a0\u00bb utile parfois mais toujours folklorique d&rsquo;un domaine sous l&#8217;empire d&rsquo;elle-m\u00eame (la raison subvertie, donc le Syst\u00e8me). Effectivement, la raison, \u00e0 cause de sa subversion m\u00eame, a cette attitude r\u00e9ductionniste devant l'\u00a0\u00bbintuition haute\u00a0\u00bb mais elle ne contr\u00f4le pas l&rsquo;enti\u00e8ret\u00e9 du ph\u00e9nom\u00e8ne; le r\u00f4le de la psychologie tel qu&rsquo;on l&rsquo;a vu fait que l&rsquo;esprit peut parfois s&rsquo;ouvrir \u00e0 l&rsquo;intuition haute et l&rsquo;imposer en tant que telle \u00e0 sa raison, &ndash; r\u00e9g\u00e9n\u00e9rer sa propre raison, ce qu&rsquo;on pourrait d\u00e9signer, en se r\u00e9f\u00e9rant \u00e0 la vraie raison, celle d&rsquo;avant la subversion de la modernit\u00e9, comme \u00ab\u00a0faire entendre raison \u00e0 la raison\u00a0\u00bb&#8230; Ajoutons, ou rappelons plut\u00f4t que ce r\u00f4le m\u00e9canique mais central de la psychologie suppl\u00e9ant \u00e0 la raison subvertie pour permettre \u00e0 l&rsquo;esprit de \u00ab\u00a0faire entendre raison \u00e0 la raison\u00a0\u00bb, est possible gr\u00e2ce \u00e0 la puissance du syst\u00e8me de la communication avec ses effets sur la psychologie, qui peuvent \u00eatre b\u00e9n\u00e9fique lorsque ce Janus nous pr\u00e9sente sa face vertueuse.<\/p>\n<\/p>\n<p><p>C&rsquo;est dans ce contexte si singulier qu&rsquo;il faut envisager l&rsquo;hypoth\u00e8se de la maniaco-d\u00e9pression, et envisager l&rsquo;utilisation des \u00e9pisodes diff\u00e9rents d&rsquo;une fa\u00e7on tr\u00e8s inhabituelle. L&rsquo;\u00e9pisode d\u00e9pressif qui peut toucher la psychologie, alors que l&rsquo;\u00e9pisode maniaque continue \u00e0 emporter les raisons subverties par le Syst\u00e8me lui-m\u00eame dans un tel \u00e9pisode, permet d&rsquo;introduire une couleur lugubre dans le jugement sur l&rsquo;\u00e9tat du monde (en phase maniaque). La psychologie d\u00e9pressive, si elle parvient \u00e0 ne pas \u00eatre paralys\u00e9e par l&rsquo;aspect purement pathologique, si elle parvient \u00e0 susciter une r\u00e9action vitale d&rsquo;inspiration m\u00e9taphysique, alimente l&rsquo;esprit dans un jugement cr\u00e9pusculaire absolument justifi\u00e9 sur l&rsquo;\u00e9tat du monde et encourage d&rsquo;autant \u00e0 en appeler \u00e0 l&rsquo;intuition haute en tant que telle pour se forger une vision, une appr\u00e9ciation, une sublimit\u00e9 qui permettent de transformer cette vision critique intuitive en une pens\u00e9e structur\u00e9e, en une r\u00e9f\u00e9rence accept\u00e9e et consciente \u00e0 la perception m\u00e9taphysique de la situation du monde.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Historique d&rsquo;une psychologie : la guillotine et la Grande Peur<\/h2>\n<\/p>\n<p><p>Cette intervention essentielle de la psychologie dans le cadre d&rsquo;une pathologie de type maniaco-d\u00e9pressif devenu un ph\u00e9nom\u00e8ne collectif caract\u00e9rise, \u00e0 notre sens, l&rsquo;\u00e9pisode essentiel de la naissance directe (\u00e0 partir de racines plus lointaines) de la crise actuelle. Il s&rsquo;agit de l&rsquo;\u00e9pisode, essentiellement fran\u00e7ais mais d&rsquo;une influence directe et quasiment d\u00e9terminante sur le reste du monde (c&rsquo;est-\u00e0-dire sur l&rsquo;Europe, pour notre civilisation), de la s\u00e9quence XVIII\u00e8me si\u00e8cle-R\u00e9volution fran\u00e7aise, et de sa participation centrale, extr\u00eamement active, au ph\u00e9nom\u00e8ne de ce que nous nommons \u00ab\u00a0le d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb, comme matrice directe et irr\u00e9sistible de la crise actuelle apr\u00e8s la transmutation du ph\u00e9nom\u00e8ne en ce que nous nommons le Syst\u00e8me.<\/p>\n<\/p>\n<p><p>(Effectivement, dans cette s\u00e9quence, la dynamique du \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb est essentiellement assur\u00e9e, selon nous, par la R\u00e9volution fran\u00e7aise, pr\u00e9par\u00e9e par le XVIII\u00e8me si\u00e8cle. Les deux autres \u00ab\u00a0r\u00e9volutions\u00a0\u00bb, dont nous estimons qu&rsquo;elles ont jou\u00e9 un r\u00f4le \u00e9quivalent pour le d\u00e9veloppement de la crise, &ndash; la r\u00e9volution am\u00e9ricaniste et la r\u00e9volution du choix de la thermodynamique, &ndash; ne donneront leur effets que secondairement du point de vue chronologique, mais avec une puissance d\u00e9cupl\u00e9e par rapport \u00e0 la R\u00e9volution fran\u00e7aise.)<\/p>\n<\/p>\n<p><p>Selon cette interpr\u00e9tation, nous envisageons l&rsquo;\u00e9pisode que nous avons d\u00e9j\u00e0 longuement d\u00e9taill\u00e9 de l&rsquo;intervention du \u00ab\u00a0persiflage\u00a0\u00bb au XVIII\u00e8me si\u00e8cle, comme moyen d&rsquo;affaiblir et de subvertir les psychologies, comme un \u00e9pisode maniaque o&ugrave; la psychologie est effectivement saisie d&rsquo;une fausse exaltation repr\u00e9sent\u00e9e par cette activit\u00e9 qui veut para&icirc;tre comme une lib\u00e9ration de l&rsquo;esprit par l&rsquo;affirmation de son autonomie nihiliste et de la d\u00e9structuration des principes de hi\u00e9rarchie et de l\u00e9gitimit\u00e9. La fausse exaltation, appuy\u00e9e sur une fausse r\u00e9alit\u00e9 cr\u00e9\u00e9e par l&rsquo;aspect maniaque de la psychologie ainsi affaiblie, a pour effet de d\u00e9truire un ordre et une harmonie, ou, dans tous les cas, d&rsquo;achever leur destruction d\u00e9j\u00e0 entreprise par d&rsquo;autres moyens plus conventionnels durant les deux si\u00e8cles pr\u00e9c\u00e9dents.<\/p>\n<\/p>\n<p><p>Le facteur essentiel \u00e0 consid\u00e9rer est que la R\u00e9volution fran\u00e7aise [avec] le d\u00e9cha&icirc;nement de la Mati\u00e8re qu&rsquo;elle repr\u00e9sente, la mati\u00e8re la plus symbolique \u00e9tant l&rsquo;acier coupant de &laquo;<em>la guillotine permanente<\/em>&raquo;, prend en fait le relais de l&rsquo;\u00e9pisode maniaque, et devient \u00e9pisode maniaque elle-m\u00eame, qu&rsquo;elle ma&icirc;trise \u00e0 son profit. Le d\u00e9cha&icirc;nement de la mati\u00e8re transfigure l&rsquo;\u00e9pisode maniaque, le transmute \u00e0 son avantage, en inventant un univers peupl\u00e9 de n\u00e9cessaires entreprises radicales, habit\u00e9es d&rsquo;Id\u00e9es fondamentalement chaotiques et r\u00e9volutionnaires; l&rsquo;univers cr\u00e9\u00e9 par l&rsquo;\u00e9pisode maniaque, promet d&rsquo;autres univers, progressistes, exalt\u00e9s, d&rsquo;accomplissement du destin de l&rsquo;humanit\u00e9, qui continueraient n\u00e9cessairement l&rsquo;exaltation maniaque. L&rsquo;\u00e9pop\u00e9e napol\u00e9onienne aura de ces accents. (4)<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">De \u00ab\u00a0la Grande Peur\u00a0\u00bb de Ferrero \u00e0 la l\u00e9gitimit\u00e9 de Talleyrand<\/h2>\n<\/p>\n<p><p>L&rsquo;historien Guglielmo Ferrero avait baptis\u00e9 la p\u00e9riode entre 1789 et 1814 (Congr\u00e8s de Vienne), le temps de \u00ab\u00a0la Grande Peur\u00a0\u00bb. On peut ainsi consid\u00e9rer qu&rsquo;une p\u00e9riode d\u00e9pressive s&rsquo;est ouverte, parall\u00e8lement \u00e0 l&rsquo;\u00e9pisode maniaque d\u00e9j\u00e0 engag\u00e9 et transmut\u00e9 par le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb en l&rsquo;esquisse de la conqu\u00eate du monde, par transformation en un nouveau monde. Il y a chevauchement [de la p\u00e9riode maniaque et de la p\u00e9riode d\u00e9pressive], avec des rapports entre elles mais nullement des liens oblig\u00e9s de cause \u00e0 effet.<\/p>\n<\/p>\n<p><p>Ainsi, \u00ab\u00a0la Grande Peur\u00a0\u00bb selon Ferrero, suscit\u00e9e par l&rsquo;\u00e9pisode maniaque, allait \u00e9voluer de son c\u00f4t\u00e9 en une d\u00e9pression profonde qui allait susciter, pour se sauver d&rsquo;elle-m\u00eame et ainsi vaincre l&rsquo;\u00e9pisode maniaque, une r\u00e9action que Ferrero attribue fondamentalement au Fran\u00e7ais Talleyrand, notamment avec la rencontre, que Ferrero \u00e9rige en symbole de cette r\u00e9action sublime, entre Talleyrand et le tsar Alexandre Ier, le 30 mars 1814, \u00e0 Paris. Il en sortit une proclamation sur la paix en Europe proposant des orientations bas\u00e9es sur le principe fondamental de la l\u00e9gitimit\u00e9, notamment sur la souverainet\u00e9 et l&rsquo;identit\u00e9, cela dans la perspective de la d\u00e9faite de Napol\u00e9on, et cela \u00e9vitant le risque du basculement du monde civilis\u00e9 dans un d\u00e9sordre sanglant et pire que ce qui avait pr\u00e9c\u00e9d\u00e9.<\/p>\n<\/p>\n<p><p>Ferrero d\u00e9crit, parfaitement \u00e0 notre sens, Talleyrand durant l&rsquo;hiver 1813-1814, dans une sorte d'\u00a0\u00bbassignation \u00e0 r\u00e9sidence\u00a0\u00bb plus ou moins dor\u00e9e \u00e0 Paris, d\u00e9sert\u00e9 de tous, abandonn\u00e9, laiss\u00e9 \u00e0 la solitude de la disgr\u00e2ce et \u00e0 la menace de mesures plus coercitives contre lui, lui-m\u00eame plong\u00e9 dans une profonde d\u00e9pression comme s&rsquo;il vivait celle, collective, qu&rsquo;on a d\u00e9crite plus haut. &laquo;<em>Mais en s&rsquo;identifiant de plus en plus avec l&rsquo;agonie de l&rsquo;Europe d\u00e9vast\u00e9e par la peur et la force, il cherchait obstin\u00e9ment au fond de sa solitude les moyens de son salut personnel dans le salut commun. Pendant l&rsquo;hiver 1813-1814, pendant ce sombre hiver o&ugrave; l&rsquo;Empire, bless\u00e9 \u00e0 mort, terrifie et secoue le monde par ses derniers cris de fureur, il s&rsquo;enfonce dans une longue, solitaire et profonde m\u00e9ditation, qui le conduit jusqu&rsquo;aux racines de la grande peur. Cette m\u00e9ditation a sauv\u00e9 le monde alors<\/em>&hellip;&raquo;<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit de la situation arch\u00e9typique d&rsquo;un personnage de haute intuition, rencontrant, dans son drame personnel, le drame collectif, et trouvant alors la force de r\u00e9soudre le drame collectif en r\u00e9solvant le sien propre. Il y a l\u00e0 un transfert f\u00e9cond de l&rsquo;\u00e9pisode d\u00e9pressif de l&rsquo;Histoire elle-m\u00eame \u00e0 l&rsquo;individu d&rsquo;exception, et l&rsquo;individu, par la puissance \u00e0 lui donn\u00e9e par l&rsquo;intuition haute, trouvant l&rsquo;\u00e9nergie de transformer l&rsquo;aspect de l&rsquo;entropie mena\u00e7ante de l&rsquo;\u00e9pisode en un aspect structurant et salvateur. Dans ce cas, la d\u00e9pression est salvatrice, car on trouve dans son immobilit\u00e9 fig\u00e9e le mat\u00e9riel pour (re)construire des structures actives et f\u00e9condes. Tout cela fut transmut\u00e9 en une politique d&rsquo;o&ugrave; devait sortir l&rsquo;ordre europ\u00e9en nouveau du Congr\u00e8s de Vienne. La psychologie d\u00e9vast\u00e9e retrouve sa puissance et, appuy\u00e9e sur la d\u00e9pression transmut\u00e9e, abat l&rsquo;\u00e9pisode maniaque. Cela ne dura que jusqu&rsquo;en 1848, avec l&rsquo;ouverture d&rsquo;un nouvel \u00e9pisode maniaque, essentiellement du fait de la Prusse \u00e9voluant vers l&#8217;empire allemand&#8230;<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Inversions d\u00e9pressive et maniaque<\/h2>\n<\/p>\n<p><p>Les anciens disaient de la d\u00e9pression qu&rsquo;elle \u00e9tait &laquo;la mati\u00e8re qui est dans l&rsquo;\u00e2me mise en avant aux d\u00e9pens de la spiritualit\u00e9 de l&rsquo;\u00e2me&raquo;. Selon notre conception, qui justifie [notre] approche psychologique de la crise de la modernit\u00e9, cette modernit\u00e9, d\u00e9cisivement propuls\u00e9e par l&rsquo;\u00e9pisode d\u00e9clencheur du \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb&lsquo; (1776-1825), a invers\u00e9 cela. Cette conception justifie le constat m\u00e9dical, [selon] l&rsquo;approche telle que l&rsquo;\u00e9nonce un psychiatre de la neurasth\u00e9nie comme le Dr. Beard. D\u00e9sormais, l&rsquo;\u00e2me [n&rsquo;est plus menac\u00e9e par les effets du coup de force de la mati\u00e8re mais] par l&rsquo;acceptation de la tromperie [dissimulant le coup de force de la mati\u00e8re], apr\u00e8s avoir \u00e9t\u00e9 \u00e9puis\u00e9e par elle (exemple du \u00ab\u00a0persiflage\u00a0\u00bb). (5) Cette v\u00e9rit\u00e9 s&rsquo;est renforc\u00e9e jusqu&rsquo;\u00e0 l&rsquo;inversion absolue avec la pression machiniste jusqu&rsquo;\u00e0 l&rsquo;ivresse du syst\u00e8me du technologisme, et avec l&rsquo;action constante, obs\u00e9dante, contraignante du syst\u00e8me de la communication dans sa phase offensive. (L&rsquo;aspect de \u00ab\u00a0Janus\u00a0\u00bb du syst\u00e8me de la communication, si souvent signal\u00e9 par nous, n&rsquo;intervient qu&rsquo;\u00e0 partir de l&rsquo;entr\u00e9e en activit\u00e9 extr\u00eame de la crise g\u00e9n\u00e9rale d&rsquo;effondrement de notre contre-civilisation, lorsque apparaissent des instruments pouvant v\u00e9hiculer des attaques de type syst\u00e8me antiSyst\u00e8me, tel l&rsquo;Internet.)<\/p>\n<\/p>\n<p><p>Par contre, cette approche nous conduit \u00e0 observer la n\u00e9cessit\u00e9 d&rsquo;\u00e9tablir un rapport extr\u00eamement serr\u00e9 et complexe entre d\u00e9pression et \u00e9pisode maniaque, contrairement au sch\u00e9ma que sugg\u00e8re la m\u00e9decine occidentale qui en reste \u00e0 l&rsquo;explication chimique des ph\u00e9nom\u00e8nes. C&rsquo;est-\u00e0-dire que la psychologie elle-m\u00eame, \u00e0 c\u00f4t\u00e9 de la pathologie qu&rsquo;est la chose, [devient] elle-m\u00eame maniaco-d\u00e9pression, et qu&rsquo;alors cette perception conduit \u00e0 bouleverser la v\u00e9ritable place et les v\u00e9ritables significations de chaque type d&rsquo;\u00e9pisode. Il s&rsquo;agit d&rsquo;une conception absolument dynamique de la psychologie, aussi bien individuelle qu&rsquo;historique, et dans ses rapports entre les deux (le cas de Talleyrand), et non plus d&rsquo;une conception statique. Il ne s&rsquo;agit pas de plaider qu&rsquo;une situation a remplac\u00e9 l&rsquo;autre, mais que la modernit\u00e9 a impos\u00e9 cette nouvelle situation.<\/p>\n<\/p>\n<p><p>Cette approche doit nous servir de mod\u00e8le pour renforcer avec l&rsquo;aspect psychologique que nous tenons pour essentiel la r\u00e9vision compl\u00e8te de l&rsquo;histoire de la modernit\u00e9, telle que nous la proposons. Ainsi, la Grande D\u00e9pression, consid\u00e9r\u00e9e comme une calamit\u00e9 pour l&rsquo;Am\u00e9rique et pour l&rsquo;histoire du XX\u00e8me si\u00e8cle en g\u00e9n\u00e9ral, appara&icirc;t en v\u00e9rit\u00e9, selon notre approche qui est le point de vue m\u00e9tahistorique, [comme] un \u00e9v\u00e8nement de sauvegarde en portant un premier coup terrible au capitalisme am\u00e9ricaniste et, <strong>surtout<\/strong>, \u00e0 la psychologie am\u00e9ricaniste triomphante, dans une phase maniaque exacerb\u00e9e dans les ann\u00e9es 1920[. S]eul le caract\u00e8re d\u00e9pressif de l&rsquo;\u00e9poque permet cela, parce qu&rsquo;il introduit un malaise psychologique \u00e0 mesure de la catastrophe que d\u00e9crit cette mise \u00e0 nu d&rsquo;une partie du Syst\u00e8me qui active l'\u00a0\u00bbop\u00e9rationnalit\u00e9\u00a0\u00bb de la modernit\u00e9.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">La modernit\u00e9 change le r\u00f4le de la psychologie<\/h2>\n<\/p>\n<p><p>Ce qu&rsquo;il importe d&rsquo;observer, c&rsquo;est que la modernit\u00e9, essentiellement \u00e0 partir de la rupture du \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb qui lui donne tout son sens, a modifi\u00e9 le rythme et le sens des \u00e9v\u00e8nements psychologiques, &ndash; et, par cons\u00e9quent, le rythme et le sens de ses caract\u00e8res extr\u00eames qui peuvent devenir des pathologies. Avant le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb et, plus largement d&rsquo;un point de vue chronologique, avant la modernit\u00e9, existait un \u00e9tat plus stable, notamment pour la psychologie. Les conceptions admises, notamment concernant la d\u00e9pression, \u00e9taient alors enti\u00e8rement fond\u00e9es. La modernit\u00e9 introduit le rythme, le mouvement, c&rsquo;est-\u00e0-dire le changement permanent, et le changement permanent de plus en plus en forme d&rsquo;obsession compulsive parce que le but g\u00e9n\u00e9ral du changement jusqu&rsquo;\u00e0 l&rsquo;inversion de l&rsquo;essence du monde tarde \u00e0 se r\u00e9aliser alors qu&rsquo;il s&rsquo;agit l\u00e0 du but ultime et du but de sauvegarde de la modernit\u00e9. Si ce but n&rsquo;est pas atteint, la modernit\u00e9 meurt d&rsquo;elle-m\u00eame, et plus elle croit approcher de ce but, plus l&rsquo;essence du monde r\u00e9siste \u00e0 ses consignes d&rsquo;inversion, plus l&rsquo;obsession compulsive s&rsquo;accentue. En termes psychologiques, cette attitude se traduit par cette agitation permanente, par l&rsquo;affirmation d&rsquo;un univers de faux semblant, par un simulacre de v\u00e9rit\u00e9 qui demande un mouvement constant pour l&#8217;emp\u00eacher de se dissiper comme font les illusions. Ce sont les caract\u00e8res m\u00eames d&rsquo;une phase maniaque.<\/p>\n<\/p>\n<p><p>Ainsi dirions-nous qu&rsquo;\u00e0 la lumi\u00e8re et sous la pression de la modernit\u00e9, l&rsquo;\u00e9pisode maniaque, qui est tromperie pure, inversion de la v\u00e9rit\u00e9, simulacre du monde, constitue effectivement la d\u00e9marche centrale de cette modernit\u00e9. C&rsquo;est dans ce cas que se manifeste le plus pr\u00e9cis\u00e9ment le Mal, comme si l&rsquo;individu, ou l&rsquo;\u00e9poque, \u00e9tait compl\u00e8tement poss\u00e9d\u00e9 par le Mal (sans en \u00eatre pour autant, ni la source, ni m\u00eame la substance). Et le Mal se manifeste sous son vrai visage, qui est simulation du contraire de lui-m\u00eame, inversion de la v\u00e9rit\u00e9 du monde, tandis que le mouvement marqu\u00e9 par l&rsquo;obsession compulsive, par sa pression permanente et d\u00e9sordonn\u00e9e, emp\u00eache la pens\u00e9e, notamment sous la forme de la raison, de se rassembler, de se retrouver et de s&rsquo;ouvrir \u00e0 l&rsquo;intuition haute.<\/p>\n<\/p>\n<p><p>On comprend que, dans ces conditions, effectivement, l&rsquo;\u00e9pisode d\u00e9pressif signifie une sorte de d\u00e9fense paradoxale; la d\u00e9pression extrait la psychologie de l&rsquo;\u00e9pisode maniaque; elle lui impose la lourde charge d&rsquo;effectivement sentir tout le poids de la mati\u00e8re qui est dans l&rsquo;\u00e2me, mais elle permet aussi de se d\u00e9gager du tourbillon maniaque, m\u00e9nageant ainsi une chance de retrouver une certaine stabilit\u00e9 structur\u00e9e. En quelque sorte, la d\u00e9pression permet de retrouver la v\u00e9rit\u00e9 du monde, et comment cette v\u00e9rit\u00e9 elle-m\u00eame objet des attaques qu&rsquo;on a d\u00e9taill\u00e9es a conduit n\u00e9cessairement la psychologie \u00e0 la d\u00e9pression. Il s&rsquo;agit alors de d\u00e9passer les aspects n\u00e9gatifs de la d\u00e9pression pour, en s&rsquo;appuyant sur ce en quoi ces aspects rendent compte de la v\u00e9rit\u00e9 du monde, monter une d\u00e9fense puis une contre-attaque contre l&rsquo;illusion maniaque qu&rsquo;est la modernit\u00e9. Comme on le comprend, tous ces ph\u00e9nom\u00e8nes \u00e9voluent parall\u00e8lement, et la psychologie doit \u00e9voluer entre l&rsquo;un et l&rsquo;autre selon ce qu&rsquo;elle peut, pour se sauver elle-m\u00eame, d&rsquo;elle-m\u00eame.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">9\/11 : r\u00e9volution maniaque, flux et reflux d\u00e9pressifs<\/h2>\n<\/p>\n<p><p>&#8230;Bien entendu, toutes ces consid\u00e9rations \u00e0 l&rsquo;aide de la r\u00e9f\u00e9rence maniaco-d\u00e9pressive impliquent \u00e9videmment des \u00e9pisodes exog\u00e8nes, notamment ce que la m\u00e9decine occidentale nomme \u00ab\u00a0la d\u00e9pression exog\u00e8ne\u00a0\u00bb. Il n&rsquo;est pas n\u00e9cessairement d&rsquo;une audace insupportable, malgr\u00e9 la concentration de la m\u00e9decine sur la chimie interne, d&rsquo;envisager que les affections maniaco-d\u00e9pressives humaines individuelles, particuli\u00e8rement dans notre \u00e9poque de si forte pression du syst\u00e8me de la communication, n&rsquo;aient pas une part importante qui soit d&rsquo;origine exog\u00e8ne.<\/p>\n<\/p>\n<p><p>Sur ces consid\u00e9rations concernant l&rsquo;op\u00e9rationnalit\u00e9 du ph\u00e9nom\u00e8ne, l&rsquo;\u00e9v\u00e8nement nomm\u00e9 9\/11 occupe une place \u00e9videmment essentielle. Il se produit sur un terrain psychologique fertile ; apr\u00e8s un \u00e9pisode d\u00e9pressif s\u00e9v\u00e8re, entre 1991 et 1996, l&rsquo;Am\u00e9rique est brutalement pr\u00e9cipit\u00e9e dans un \u00e9pisode maniaque \u00e0 l&rsquo;occasion des Jeux Olympiques d&rsquo;Atlanta (juillet 1996). La puissance du ph\u00e9nom\u00e8ne, en 1996, est consid\u00e9rable quoiqu&rsquo;elle ait \u00e9t\u00e9 rarement not\u00e9e, et elle n&rsquo;est pas loin d&rsquo;\u00e9quivaloir en dynamique maniaque de caract\u00e8re exog\u00e8ne, \u00e0 celle de l&rsquo;attaque 9\/11. (6) L&rsquo;attaque du 11 septembre 2001, elle, frappe directement l&rsquo;\u00e9quilibre de la psychologie de la direction politique du syst\u00e8me de l&rsquo;am\u00e9ricanisme. De ce point de vue, l&rsquo;\u00e9pisode maniaque est proche de la folie et enferme cette direction dans une schizophr\u00e9nie convulsive dont elle n&rsquo;est plus sortie. L&rsquo;\u00e9lection d&rsquo;Obama et ce qui s&rsquo;ensuit a montr\u00e9 la vanit\u00e9 d&rsquo;attribuer au seul Bush ce brutal basculement pathologique.<\/p>\n<\/p>\n<p><p>Nous irons jusqu&rsquo;\u00e0 l&rsquo;hypoth\u00e8se qu&rsquo;il y eut \u00e0 cette occasion, avec 9\/11, de m\u00eame qu&rsquo;on fit l&rsquo;hypoth\u00e8se (Justin Raimondo) que cette attaque constituait un \u00ab\u00a0trou dans la continuit\u00e9 de l&rsquo;espace-temps\u00a0\u00bb, une rupture extraordinaire de fusion psychologique dans un \u00e9pisode maniaque d&rsquo;une puissance insens\u00e9e entre le Syst\u00e8me et son personnel politique et de direction g\u00e9n\u00e9rale. A l&rsquo;automne 2002, recevant l&rsquo;ambassadeur de France qui quittait son poste, le vice-pr\u00e9sident Cheney lui confiait : &laquo;<em>Vous autres, Europ\u00e9ens, vous n&rsquo;imaginez pas l&rsquo;ampleur de l&rsquo;effet qu&rsquo;a produit sur nous l&rsquo;attaque du 11 septembre, elle a chang\u00e9 notre psychologie<\/em>&#8230;&raquo; Litt\u00e9ralement, la direction politique au service du Syst\u00e8me, principalement am\u00e9ricaniste mais avec les renforcements habituels, devint un foyer constant d&rsquo;une psychologie maniaque pouss\u00e9e jusqu&rsquo;\u00e0 la schizophr\u00e9nie hallucinatoire. La politique qui en r\u00e9sulta, qui se poursuivit sans aucun changement notable avec Obama, fut baptis\u00e9e par Harlan K. Ullman \u00ab\u00a0politique de l&rsquo;id\u00e9ologie et de l&rsquo;instinct\u00a0\u00bb. L&rsquo;expression permet d&rsquo;entendre sans aucune h\u00e9sitation qu&rsquo;une mati\u00e8re \u00e0 la fois organique et pr\u00e9tendument \u00ab\u00a0spirituelle\u00a0\u00bb, &ndash; mais l&rsquo;organique gouvernant le spirituel et le d\u00e9formant \u00e0 mesure, \u00e0 cause de la bassesse du sujet et des sujets de la chose, &ndash; gouvernait d\u00e9sormais la politique par le biais d&rsquo;une courroie de transmission d\u00e9nomm\u00e9e \u00ab\u00a0id\u00e9ologie\u00a0\u00bb.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">L&rsquo;\u00e9pisode maniaque emprisonne la direction politique dans le Syst\u00e8me<\/h2>\n<\/p>\n<p><p>Ce qu&rsquo;il faut distinguer essentiellement, c&rsquo;est la bri\u00e8vet\u00e9 des \u00e9pisodes maniaques dans la population elle-m\u00eame, &ndash;pour suivre le cas US qui est exemplaire, &ndash; par contraste avec l&rsquo;enracinement du m\u00eame dans la population de l&rsquo;establishment et de la direction politique. Il y eut un \u00e9pisode maniaque populaire lors des Jeux Olympiques de 1996 \u00e0 Atlanta (&laquo;<em>ll n&rsquo;y a pas d&rsquo;olympisme ici, tout juste une kermesse \u00e9tats-unienne, ahurissante d&rsquo;ind\u00e9cence<\/em>&raquo;, \u00e9crivit <em>Le Monde<\/em> le 28 juillet 1996), mais ensuite un apaisement. Par contre, cette jubilation maniaque se poursuivit et s&rsquo;accentua dans la direction politique, notamment marqu\u00e9e par l&rsquo;hypoth\u00e8se \u00e9voqu\u00e9e par Alan Greenspan le 10 juin 1998 devant le Congr\u00e8s qu&rsquo;il \u00e9tait possible, &laquo;<em>en un sens, que<\/em> [notre \u00e9conomie] <em>ait d\u00e9pass\u00e9 l&rsquo;histoire<\/em>&#8230;&raquo; (7)<\/p>\n<\/p>\n<p><p>Ce fut cette direction politique, sp\u00e9cifiquement, qui r\u00e9agit \u00e0 9\/11 dans le sens maniaque. L&rsquo;effet de l&rsquo;attaque, qui d\u00e9montrait la vuln\u00e9rabilit\u00e9 des USA, le d\u00e9sordre de ses structures, fut [effectivement] de provoquer une production extraordinaire d'[<em>hybris<\/em>] comme l&rsquo;on dirait de la production organique d&rsquo;une masse imposante d&rsquo;adr\u00e9naline&#8230; Cette r\u00e9action provoqua des distorsions psychologiques graves, entra&icirc;nant la cr\u00e9ation d&rsquo;un univers fictif relevant [en effet] de la m\u00e9galomanie, allant jusqu&rsquo;aux \u00e9pisodes bien connus de d\u00e9clarations sur le fait que les USA d\u00e9sormais cr\u00e9ait l&rsquo;histoire \u00e0 leur guise (&laquo;<em>We&rsquo;re an empire now, and when we act, we create our own reality<\/em>&raquo;). (8) Nous baptis\u00e2mes cette r\u00e9action \u00ab\u00a0virtualisme\u00a0\u00bb pour d\u00e9signer l'\u00a0\u00bbop\u00e9rationnalit\u00e9\u00a0\u00bb de la chose, et il est \u00e9vident que ce terme concerne l&rsquo;activit\u00e9 maniaque en soi. C&rsquo;est dire qu&rsquo;il n&rsquo;y aucune machination, aucune fabrication faussaire, &ndash; <strong>m\u00eame<\/strong> s&rsquo;il y eut complot, et alors ce serait un complot accomplissant effectivement un dessein m\u00e9tahistorique qui conduirait \u00ab\u00a0l&rsquo;Empire\u00a0\u00bb \u00e0 sa perte, &ndash; ce qui est manifestement la voie suivie avec un ent\u00eatement, \u00e9galement, absolument maniaque depuis plus d&rsquo;une d\u00e9cennie. Il y eut donc bien, dans les directions politiques au service du Syst\u00e8me (les autres suivant Washington, en rang d&rsquo;oignons), un \u00e9pisode maniaque qui dure encore.<\/p>\n<\/p>\n<p><p>La r\u00e9action populaire fut, elle, tr\u00e8s diff\u00e9rente, dans cet \u00e9pisode \u00e0 partir de 9\/11. Il y eut, favoris\u00e9e par le Syst\u00e8me qui n&rsquo;a jamais imagin\u00e9 autre chose que la contrainte pour la population et qui jugea que la pression de la terreur pouvait faire l&rsquo;affaire, des \u00e9pisodes vari\u00e9s de flux et de reflux d\u00e9pressifs. Les pouss\u00e9es de patriotisme, toujours tr\u00e8s symboliques aux USA et sans rapport avec une conscience collective, nationale et historique, qui n&rsquo;existe pas, repr\u00e9sentaient des attitudes d\u00e9fensives devant ce qui \u00e9tait faussement pr\u00e9sent\u00e9 comme une menace existentielle. Il n&rsquo;y eut aucun moment de ces \u00e9pisodes maniaques comme celui des JO d&rsquo;Atlanta, et la rupture entre la population et la direction g\u00e9n\u00e9rale du Syst\u00e8me ne cessa de se creuser derri\u00e8re des apparences faussaires d&rsquo;unanimisme. C&rsquo;est dans cette agitation d\u00e9pressive nullement issue de la seule pathologie interne de la psychologie, mais puissamment renforc\u00e9e par des facteurs exog\u00e8nes, que le sentiment g\u00e9n\u00e9ral de la population se transforma, avec comme voie vers une tentative de gu\u00e9rison un antagonisme de plus en plus affirm\u00e9e contre une direction-Syst\u00e8me emport\u00e9e par sa m\u00e9galomanie.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">D\u00e9fense puis riposte<\/h2>\n<\/p>\n<p><p>On peut dire que les \u00e9v\u00e8nements eux-m\u00eames ont mis en \u00e9vidence l&rsquo;inversion qui s&rsquo;est faite dans l&rsquo;utilit\u00e9 et l&rsquo;usage des \u00e9pisodes diff\u00e9rents de la maniaco-d\u00e9pression. La crise commenc\u00e9e avec l&rsquo;effondrement financier de l&rsquo;automne 2008 a re\u00e7u le nom de Grande R\u00e9cession ; bien que l&rsquo;analogie fut dans tous les esprits, on n&#8217;employa pas l&rsquo;expression de Grande D\u00e9pression. Il s&rsquo;agissait au fond, pour les directions du Syst\u00e8me, de repousser le spectre de la mort du Syst\u00e8me que fut la Grande D\u00e9pression.. Ainsi l&rsquo;expression \u00e9choit-elle, comme un signe du destin, \u00e0 l&rsquo;\u00e9volution psychologique de la population.<\/p>\n<\/p>\n<p><p>C&rsquo;est en effet \u00e0 partir de 2008 que l&rsquo;\u00e9volution incertaine de la population, d\u00e9j\u00e0 marqu\u00e9e par la d\u00e9faite des r\u00e9publicains aux \u00e9lections de novembre 2007 et caract\u00e9ris\u00e9e par des \u00e9pisodes chaotiques au gr\u00e9 des \u00e9v\u00e8nements catastrophiques (l&rsquo;Irak, l&rsquo;ouragan <em>Katrina<\/em>), entra dans une phase d\u00e9pressive marqu\u00e9e. On peut consid\u00e9rer l&rsquo;\u00e9lection d&rsquo;Obama, et notamment l&rsquo;explosion d&rsquo;enthousiasme hyst\u00e9rique de la nuit suivant l&rsquo;\u00e9lection, comme une r\u00e9action maniaque isol\u00e9e saluant l&rsquo;espoir d&rsquo;un dirigeant politique per\u00e7u comme partageant la m\u00eame orientation psychologique. Nous avions d\u00e9j\u00e0 caract\u00e9ris\u00e9, en son temps, cette \u00e9lection comme celle du candidat per\u00e7u par le public comme ayant une compl\u00e8te et juste perception de la crise, c&rsquo;est-\u00e0-dire la perception d&rsquo;une crise marqu\u00e9e par le d\u00e9sarroi et la d\u00e9gradation des conditions sociales de la population. On sait ce qu&rsquo;il advint d&rsquo;Obama, un destin qui ne m\u00e9rite m\u00eame pas d&rsquo;\u00eatre rappel\u00e9. (9)<\/p>\n<\/p>\n<p><p>En attendant, la psychologie populaire suivit sa pente naturelle, vers la d\u00e9pression. Les r\u00e9sultats ont \u00e9t\u00e9 d&rsquo;une telle force \u00e0 partir de l&rsquo;\u00e9lection partielle du Massachusetts (20 janvier 2010) qui vit une inattendue d\u00e9faite d\u00e9mocrate et agit comme un catalyseur, que l&rsquo;on peut effectivement retenir le terme et parler d&rsquo;une sorte de \u00ab\u00a0Grande D\u00e9pression\u00a0\u00bb de la psychologie de l&rsquo;am\u00e9ricanisme, en m\u00eame temps que dans le reste de l&rsquo;ensemble am\u00e9ricaniste-occidentaliste. Ce qui importe alors n&rsquo;est certainement pas les changements politiques, les r\u00e9voltes violentes, les \u00ab\u00a0r\u00e9volutions\u00a0\u00bb au sens o&ugrave; l&rsquo;on entend la chose dans l&rsquo;histoire des XIX\u00e8me et XX\u00e8me si\u00e8cles; ce qui importe, c&rsquo;est la diffusion universelle de ce sentiment d\u00e9pressif de la psychologie, dans des conditions dynamiques telles que ce seul sentiment suffit \u00e0 constituer une base critique puissante, offensive, accusatrice du Syst\u00e8me et de ses s\u00e9ides qui continuaient et continuent \u00e0 \u00eatre emport\u00e9s dans le courant maniaque [marquant] sa psychologie jusqu&rsquo;\u00e0 un extr\u00eame irr\u00e9versible depuis 9\/11. C&rsquo;est cette fonction surprenante de base pour une r\u00e9action et une contre-attaque d&rsquo;un \u00e9tat psychologique d&rsquo;habitude caract\u00e9ris\u00e9 par la paralysie d\u00e9pressive qui est remarquable. L&rsquo;\u00e9v\u00e8nement marque les changements, v\u00e9ritablement r\u00e9volutionnaires ceux-l\u00e0, du fonctionnement et de l&rsquo;orientation de la psychologie, la puissance de son action, des effets de son action, etc. La Grande D\u00e9pression depuis 2008 est, psychologiquement, un double invers\u00e9 de la premi\u00e8re Grande D\u00e9pression des ann\u00e9es 1930.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Riposte d&rsquo;une d\u00e9pression transcend\u00e9e \u00e0 l&rsquo;attaque maniaque du Syst\u00e8me<\/h2>\n<\/p>\n<p><p>Les divers mouvements de contestation qu&rsquo;on a connus depuis 2009, et particuli\u00e8rement en 2011, constituent un excellent exemple d&rsquo;une r\u00e9action d\u00e9pressive transcend\u00e9e. Il s&rsquo;agit des mouvements type <em>Tea Party<\/em>, \u00ab\u00a0indign\u00e9s\u00a0\u00bb, \u00ab\u00a0printemps arabe\u00a0\u00bb, <em>Occupy<\/em>&#8230; Tous ces mouvements ont des caract\u00e8res assez similaires qui ont souvent surpris : des structures souvent informes ou pas de structures du tout, l&rsquo;absence de hi\u00e9rarchie, l&rsquo;absence de revendications, des affirmations souvent passives (occupations de lieux publics, principalement). Nous avons d\u00e9j\u00e0 beaucoup insist\u00e9 sur ces caract\u00e8res (voir dde.crisis du 10 mars 2011 pour le \u00ab\u00a0printemps arabe\u00a0\u00bb ou du 10 novembre 2011 pour le mouvement <em>Occupy<\/em>). (10) Peu nous importe ici les comportements individuels, ceux de certains groupes, certains affrontements in\u00e9vitables, il reste que la ligne de conduite de ces grands mouvements collectifs reste du type passif correspondant \u00e0 l&rsquo;\u00e9pisode d\u00e9pressif, justifi\u00e9 amplement par ailleurs par les diverses situations qui les ont engendr\u00e9s. Simplement, il y a transmutation de cette passivit\u00e9 impuissante du type d\u00e9pressif classique en une passivit\u00e9 cr\u00e9atrice, paradoxalement \u00ab\u00a0activiste\u00a0\u00bb, qui donne des effets importants en suscitant des r\u00e9actions d\u00e9sordonn\u00e9es des \u00e9l\u00e9ments-Syst\u00e8me en phase constamment maniaque.<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit bien d&rsquo;une m\u00eame pathologie \u00ab\u00a0binaire\u00a0\u00bb qui se s\u00e9pare en deux dans les moments paroxystiques, et qui nourrit une opposition active o&ugrave; la partie d\u00e9pressive parvient le plus souvent \u00e0 faire \u00e9voluer la situation \u00e0 son avantage. L\u00e0 encore, il ne faut pas s&rsquo;en tenir aux faits partiels, ni m\u00eame aux situations temporaires, mais bien consid\u00e9rer l&rsquo;\u00e9volution psychologique fondamentale. La partie d\u00e9pressive sort souvent r\u00e9g\u00e9n\u00e9r\u00e9e de ces affrontements, avec la sensation, justifi\u00e9e \u00e0 notre sens, d&rsquo;avoir gagn\u00e9 du terrain. (11) La partie maniaque, au contraire, tir\u00e9e vers la r\u00e9alit\u00e9 par la r\u00e9action de la partie d\u00e9pressive, est confront\u00e9e \u00e0 une situation qui ne r\u00e9pond en rien \u00e0 l&rsquo;image qu&rsquo;elle s&rsquo;en fait dans son agitation maniaque. Sa r\u00e9action correspond effectivement \u00e0 ce qu&rsquo;on observe dans les pathologies maniaco-d\u00e9pressives: le refus de la r\u00e9alit\u00e9 de la psychologie durant l&rsquo;\u00e9pisode maniaque, m\u00eame si cette r\u00e9alit\u00e9 se pr\u00e9sente comme extr\u00eamement dangereuse et pressante pour elle. C&rsquo;est alors le refus de toute le\u00e7on, de m\u00eame que la psychologie maniaque refuse tout enseignement de la r\u00e9alit\u00e9, \u00e0 cause de ce qu&rsquo;on peut et m\u00eame qu&rsquo;on doit qualifier d&rsquo;une v\u00e9ritable haine de cette r\u00e9alit\u00e9, dont on comprend ais\u00e9ment, en \u00e9largissant le propos \u00e0 la r\u00e9f\u00e9rence m\u00e9taphysique, qu&rsquo;elle correspond \u00e0 <strong>la haine de la v\u00e9rit\u00e9<\/strong>.<\/p>\n<\/p>\n<p><p>Cette fa\u00e7on d&rsquo;analyser les conflits et les tensions actuelles, qui ne sont plus du tout explicables par des notions d&rsquo;int\u00e9r\u00eat, de regroupements politiques ou g\u00e9opolitiques, voire id\u00e9ologiques, voire religieux, etc., a l&rsquo;avantage de rendre compte d&rsquo;une situation absolument in\u00e9dite dans l&rsquo;Histoire. Il s&rsquo;agit d&rsquo;une situation, n\u00e9e de notre fameux \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb, qui s&rsquo;est impos\u00e9e essentiellement \u00e0 cause de la puissance des deux sous-syst\u00e8mes du Syst\u00e8me que nous avons souvent d\u00e9finis, et dont nous avons souvent examin\u00e9 les effets, &ndash; le syst\u00e8me du technologisme et, essentiellement du fait de son action sur la psychologie, le syst\u00e8me de la communication.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Exercice m\u00e9tahistorique de contre-psychanalyse<\/h2>\n<\/p>\n<p><p>On devrait distinguer nos intentions dans cette tentative d&rsquo;interpr\u00e9tation d&rsquo;une \u00e9poque et d&rsquo;une crise que nous jugeons centrale et d\u00e9cisive. Il s&rsquo;agit du contraire d&rsquo;une psychanalyse, puisque nous partons de la description de toutes les causes fondamentales, souvent dissimul\u00e9es et profondes, des racines centrales du mal et de leurs sympt\u00f4mes parfaitement identifi\u00e9es, &ndash; exactement ce que recherche la psychanalyse d&rsquo;habitude, &ndash; pour aboutir \u00e0 identifier la pathologie de la psychologie qui exprime le mieux cette situation, &ndash; exactement ce qui est d&rsquo;habitude connu et conduit \u00e0 la psychanalyse. A partir de cette identification, on peut mieux comprendre le fondement du fonctionnement des divers acteurs humains de la p\u00e9riode, dans le d\u00e9roulement d&rsquo;une s\u00e9quence historique dont nous estimons que, dans sa partie essentielle qui est m\u00e9tahistorique, ces acteurs n&rsquo;ont que des r\u00f4les de figurants. (Selon la parole hautaine de Joseph de Maistre : &laquo;<em>Il n&rsquo;y a en ce monde que des usufruits et la propri\u00e9t\u00e9 est \u00e0 Dieu<\/em>.&raquo;) En d&rsquo;autres mots, la pathologie maniaco-d\u00e9pressive serait un des relais choisis par les forces sup\u00e9rieures en action pour d\u00e9terminer et orienter le comportement du <em>sapiens<\/em>, dans ces p\u00e9riodes fondamentales de crise, pour introduire des \u00e9v\u00e8nements nouveaux et inattendus, hors du rapport habituel de cause \u00e0 effet terrestre. (Maistre encore : &laquo;<em>Commun\u00e9ment, nous voyons une suite d&rsquo;effets produits par les m\u00eames causes; mais, \u00e0 certaines \u00e9poques, nous voyons des actions suspendues, des causes paralys\u00e9es et des effets nouveaux.<\/em>&raquo;)<\/p>\n<\/p>\n<p><p>Dans ce cadre tr\u00e8s g\u00e9n\u00e9ral, on a donc pu adopter une approche \u00e9sot\u00e9rique et symbolique, en se r\u00e9f\u00e9rant aux caract\u00e9ristiques de la pathologie, pour disposer ainsi d&rsquo;une analyse de l&rsquo;\u00e9volution de l&rsquo;\u00e9poque d\u00e9crite en se r\u00e9f\u00e9rant au facteur que nous jugeons essentiel de la psychologie, prise sur un plan collectif qui influence d\u00e9cisivement les psychologies individuelles. A partir des conditions g\u00e9n\u00e9rales existantes, on a pu d\u00e9terminer, dans le cadre de la pathologie maniaco-d\u00e9pressive qui d\u00e9crit parfaitement l&rsquo;\u00e9poque tourment\u00e9 de la modernit\u00e9 et rompt avec une certaine stabilit\u00e9 psychologique collective qui a pr\u00e9c\u00e9d\u00e9, que l&rsquo;\u00e9pisode maniaque pourrait \u00eatre per\u00e7u comme un \u00e9pisode de \u00ab\u00a0possession\u00a0\u00bb correspondant \u00e0 une sorte de \u00ab\u00a0pacte faustien\u00a0\u00bb o&ugrave; l&rsquo;\u00e9nergie d\u00e9cupl\u00e9e et l&rsquo;optimisme apparent de l&rsquo;exub\u00e9rance maniaque se paient de l&rsquo;utilisation dans un sens d\u00e9structurant et dissolvant de ces capacit\u00e9s.<\/p>\n<\/p>\n<p><p>Dans ce cadre g\u00e9n\u00e9ral, la pathologie ne nous sert, \u00e0 nous, que de forme transitoire; un \u00ab\u00a0outil\u00a0\u00bb, un moyen fourni par le Syst\u00e8me lui-m\u00eame (maniaco-d\u00e9pression, maladie de la modernit\u00e9) pour servir l&rsquo;impulsion des courants m\u00e9tahistoriques et faire voler en \u00e9clats les structures o&ugrave; nous contraint le Syst\u00e8me &#8230; Tout cela, \u00e9videmment, n&rsquo;est possible que parce que nous vivons une p\u00e9riode exceptionnelle, o&ugrave; les concepts habituels de la raison, encore plus lorsqu&rsquo;elle est subvertie, n&rsquo;ont plus cours.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La psychologie malade comme proximit\u00e9 du Mal<\/h2>\n<\/p>\n<p><p>Cette d\u00e9marche d&rsquo;interpr\u00e9tation de la situation de crise ultime o&ugrave; nous nous trouvons dans le temps pr\u00e9sent par la pathologie de la psychologie (la maniaco-d\u00e9pression) nous conduit \u00e0 observer combien ce sch\u00e9ma implique l&rsquo;appr\u00e9ciation de la plus grande proximit\u00e9 possible du Mal. On observera que cette id\u00e9e s&rsquo;accorde avec notre perception de l&rsquo;\u00e9pisode m\u00e9tahistorique de la modernit\u00e9, tel que nous l&rsquo;avons rappel\u00e9 plus haut, o&ugrave; la phase maniaque qu&rsquo;a constitu\u00e9 l&rsquo;\u00e9volution psychologique au XVIII\u00e8me si\u00e8cle, conduit au \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb de la fin du si\u00e8cle, avec la R\u00e9volution fran\u00e7aise.<\/p>\n<\/p>\n<p><p>On rappellera la position que nous avions d\u00e9fendue (dde.crisis du 10 septembre 2010) (12) dans notre d\u00e9marche d&rsquo;identification du Mal, comme \u00e9tant la Mati\u00e8re en tant que d\u00e9structuration et dissolution absolues, \u00e9quivalent en termes physiques \u00e0 l'\u00a0\u00bbentropisation\u00a0\u00bb. La r\u00e9f\u00e9rence que nous citions \u00e9tait celle de Plotin (Trait\u00e9 51 des <em>Enneades<\/em>), qui d\u00e9termine la pr\u00e9sence du Mal en l&rsquo;homme selon les faiblesses de l&rsquo;homme, <em>ditto<\/em> selon sa proximit\u00e9 de la Mati\u00e8re: &laquo;<em>Car on pourrait d\u00e8s lors arriver \u00e0 une notion du mal comme ce qui est non-mesure par rapport \u00e0 la mesure, sans limite par rapport \u00e0 la limite, absence de forme par rapport \u00e0 ce qui produit la forme et d\u00e9ficience permanente par rapport \u00e0 ce qui est suffisant en soi, toujours ind\u00e9termin\u00e9, stable en aucun fa\u00e7on, affect\u00e9 de toutes mani\u00e8res, insatiable, indigence totale. Et ces choses ne sont pas des accidents qui lui adviennent, mais elles constituent son essence en quelque sorte, et quelle que soit la partie de lui que tu pourrais voir, il est toutes ces choses. Mais les autres, ceux qui participeraient de lui et s&rsquo;y assimileraient, deviennent mauvais, n&rsquo;\u00e9tant pas mauvais en soi<\/em>.&raquo;<\/p>\n<\/p>\n<p><p>Par cons\u00e9quent, il nous semble logique de consid\u00e9rer qu&rsquo;une \u00ab\u00a0pathologie\u00a0\u00bb, qui est une manifestation d&rsquo;une faiblesse du corps comme de l&rsquo;esprit, soit effectivement une interpr\u00e9tation tout \u00e0 fait convenable et juste pour d\u00e9crire la proximit\u00e9 du Mal de l&rsquo;homme; plus pr\u00e9cis\u00e9ment, une pathologie de la psychologie, affectant ainsi la sp\u00e9cificit\u00e9 humaine par o&ugrave; transitent les courants d&rsquo;influence essentiels pour l&rsquo;esprit, pr\u00e9cis\u00e9ment aujourd&rsquo;hui o&ugrave; la raison subvertie ne peut plus tenir son r\u00f4le central d&rsquo;acceptation de ses courants ou de d\u00e9fense contre eux en raison de sa faiblesse; plus pr\u00e9cis\u00e9ment encore, la maniaco-d\u00e9pression, dans la mesure o&ugrave; cette pathologie offre deux \u00e9pisodes d&rsquo;elle-m\u00eame dont on a vu que l&rsquo;un est l&rsquo;arch\u00e9type m\u00eame de l&rsquo;exacerbation de toutes les faiblesses de la tromperie et de l&rsquo;illusion, ruses essentielles du Mal, et l&rsquo;autre une r\u00e9action certes d\u00e9pressive mais \u00e9galement de soudaine lucidit\u00e9 sur le m\u00e9canisme pervers de l&rsquo;\u00e9pisode maniaque, <strong>contre<\/strong> cet \u00e9pisode maniaque. On voit combien cette pathologie est d\u00e9finie, dans notre interpr\u00e9tation, en termes m\u00e9taphysiques et non plus en termes m\u00e9dicaux, et combien il est par cons\u00e9quent justifi\u00e9 de lui accorder l&rsquo;importance universelle que nous proposons.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Illustration et \u00ab\u00a0op\u00e9rationnalit\u00e9\u00a0\u00bb du conflit avec le Mal<\/h2>\n<\/p>\n<p><p>Notre d\u00e9marche consiste donc en une interpr\u00e9tation psychologique, et \u00ab\u00a0m\u00e9dicale\u00a0\u00bb pour son caract\u00e8re illustratif et r\u00e9aliste, du conflit m\u00e9taphysique fondamental selon notre appr\u00e9ciation. Il s&rsquo;agit moins de la position du <em>sapiens<\/em> dans le [pseudo-]conflit entre le Bien et le Mal que de la bataille permanente qui caract\u00e9rise la question de notre proximit\u00e9 plus ou moins grande du Mal. Cette approche m\u00e9taphysique est n\u00e9cessaire parce qu&rsquo;elle caract\u00e9rise absolument l&rsquo;\u00e9poque actuelle, qui est le terme de la modernit\u00e9, o&ugrave; tout se contracte effectivement dans cette question de la proximit\u00e9 du Mal, dans la mesure o&ugrave; le Mal s&rsquo;est install\u00e9 au c&oelig;ur de notre civilisation, ainsi devenue contre-civilisation, sous la forme de ce que nous nommons d&rsquo;une fa\u00e7on r\u00e9aliste \u00ab\u00a0le Syst\u00e8me\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>L&rsquo;interpr\u00e9tation que nous proposons de la maniaco-d\u00e9pression est alors \u00e0 la fois une explication de cette proximit\u00e9 exceptionnelle du Mal engendrant la catastrophe de la contre-civilisation, dans la bassesse de l&rsquo;esprit et de tous les comportements de <em>sapiens<\/em>, et une explication d&rsquo;une r\u00e9action contre cela, comme nous l&rsquo;avons laiss\u00e9e entendre; comment les courants m\u00e9tahistoriques, utilisant cette pathologie de la psychologie en en faisant une opportunit\u00e9, la retournent contre elle-m\u00eame, c&rsquo;est-\u00e0-dire contre le Syst\u00e8me et le Mal&#8230; D&rsquo;habitude, la d\u00e9pression qui suit l&rsquo;\u00e9pisode maniaque, qui encha&icirc;ne sur lui, qui est li\u00e9 \u00e0 lui, ent\u00e9rine la d\u00e9faite de la psychologie du fait de l&rsquo;illusion maniaque, et son rapprochement d\u00e9cisif du Mal; dans ce cas, par un retournement du type \u00ab\u00a0contre-feu\u00a0\u00bb que nous exposons souvent, une inversion sublime de la chose, la d\u00e9pression devient le havre de v\u00e9rit\u00e9, avec toute sa duret\u00e9 et toute son exigence, \u00e0 partir duquel on pourra, on devra r\u00e9agir contre la folie maniaque qui nous emporte vers le Mal.<\/p>\n<\/p>\n<p><p>Dans cette bataille, la question du Bien (qu&rsquo;est-ce qui est bon) est tr\u00e8s annexe, tant la situation est toute enti\u00e8re emport\u00e9e par cette terrible proximit\u00e9 du Mal. Tout revient \u00e0 cette proximit\u00e9 du Mal et les dangers d\u00e9cisifs qu&rsquo;elle suscite. Il suffit donc de se situer par rapport au Mal, et donc de commencer par identifier le Mal, dans tous les cas sa repr\u00e9sentation, et &oelig;uvrer \u00e0 sa compl\u00e8te destruction, sans aucun esprit de compromis possible. L&rsquo;avantage de cette hypoth\u00e8se de la maniaco-d\u00e9pression, telle que d\u00e9velopp\u00e9e, est qu&rsquo;elle met en \u00e9vidence le r\u00f4le de ce que nous jugeons \u00eatre le moteur et le n&oelig;ud de notre grande crise terminale, qui est la psychologie humaine, d&rsquo;une importance centrale alors que la raison s&rsquo;est perdue dans ses compromissions avec la Mati\u00e8re, avec le Mal; [il (l&rsquo;avantage)] est surtout de repr\u00e9senter d&rsquo;une fa\u00e7on concr\u00e8te, humaine, terrestre, la bataille contre le Mal, la puissance de cette bataille, ses effets d\u00e9vastateurs sur nous; avec elle, \u00ab\u00a0le Mal est nu\u00a0\u00bb, comme l&rsquo;on dit du roi&#8230;<\/p>\n<\/p>\n<p><p>En termes r\u00e9alistes et concrets, tout revient donc \u00e0 la question de la destruction du Syst\u00e8me, qui est effectivement la repr\u00e9sentation du Mal dans le contexte de la modernit\u00e9, celle-ci qui en est l&rsquo;inspiratrice. Quoi qu&rsquo;il en soit de ce qu&rsquo;on nomme \u00ab\u00a0l&rsquo;avenir\u00a0\u00bb, la destruction du Syst\u00e8me est une condition <em>sine qua non<\/em> de la sauvegarde, et, avec elle, de la gu\u00e9rison de la maniaco-d\u00e9pression qui caract\u00e9rise la forme de notre combat&#8230;<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Notes du temps pr\u00e9sent<\/h2>\n<\/p>\n<p><p>(1) Cette \u00ab\u00a0touche personnelle\u00a0\u00bb n&rsquo;est ni un symbole, ni une image, ni rien qui soit du seul champ th\u00e9orique. L&rsquo;auteur (PhG) a effectivement connu, non pas dans son chef mais dans le chef d&rsquo;une personne qui lui \u00e9tait extr\u00eamement proche, le drame individuel et humain de la maniaco-d\u00e9pression, la catastrophe inimaginable que cette pathologie apporte \u00e0 un destin (ou \u00e0 un destin commun). Il a exp\u00e9riment\u00e9 combien est grande la tendance intuitive \u00e0 identifier l&rsquo;action du Mal dans cette affection, &ndash; qui est, certes, bien autre chose que la souffrance physique. Il est n\u00e9cessaire, trois ans plus tard, de donner cette pr\u00e9cision, pour faire mieux comprendre combien cette d\u00e9marche intellectuelle de porter une pathologie individuelle au niveau collectif fondamental d&rsquo;une civilisation n&rsquo;est pas le produit de la seule hypoth\u00e8se intellectuelle. Il est par ailleurs possible, en pr\u00e9sence d&rsquo;une telle catastrophe individuelle, de nourrir son propre intellect en en tirant une telle hypoth\u00e8se que celle qui est envisag\u00e9e ici, et en m\u00eame temps d&rsquo;en faire une th\u00e9rapie psychologique pour soi-m\u00eame, pour faire sortir ce qu&rsquo;on juge \u00eatre un bien de cette manifestation \u00e9vidente du Mal.<\/p>\n<\/p>\n<p><p>(2) Ces observations impliquent effectivement que toute prospective de la crise d&rsquo;effondrement, de la forme de l&rsquo;effondrement, de ce qui suivra l&rsquo;effondrement, etc., est logiquement impossible. Dire le contraire serait contraire \u00e0 la logique et proposer effectivement des \u00ab\u00a0mod\u00e8les\u00a0\u00bb postcrisiques constituerait, m\u00eame involontairement et en toute innocence, une proposition <strong>n\u00e9cessairement faussaire<\/strong>. Nous dirions que cette conscience est d&rsquo;autant plus n\u00e9cessaire qu&rsquo;une telle observation lorsqu&rsquo;elle est accept\u00e9e, influe sur notre destin\u00e9 m\u00eame en nous for\u00e7ant \u00e0 des attitudes sp\u00e9cifiques qui perp\u00e9tuent notre bataille antiSyst\u00e8me absolument jusqu&rsquo;\u00e0 son terme, nous interdisant de consid\u00e9rer m\u00eame le Syst\u00e8me comme un \u00e9l\u00e9ment qui fasse partie de notre univers, pour nous interdire d&rsquo;\u00e9ventuellement composer avec lui. De ce point de vue, cette appr\u00e9ciation de la crise psychologique du monde selon la r\u00e9f\u00e9rence maniaco-d\u00e9pressive, &ndash; \u00e9pisode maniaque et \u00e9pisode d\u00e9pressif intimement li\u00e9s, &ndash; constitue une sorte de \u00ab\u00a0doctrine Cortez\u00a0\u00bb de notre bataille contre le Syst\u00e8me. <strong>Nous ne pouvons qu&rsquo;aller jusqu&rsquo;au bout<\/strong>, assur\u00e9s que nous sommes de ne pouvoir jamais rencontrer le Syst\u00e8me sur un terrain psychologique apais\u00e9, mais toujours sur un terrain psychologique crisique, &ndash; \u00e9pisode maniaque ou \u00e9pisode d\u00e9pressif. <strong>Le Syst\u00e8me est notre poison et nous ne pouvons composer avec le poison qui nous tue<\/strong>.<\/p>\n<\/p>\n<p><p>(3) Nous disons \u00e9galement la \u00ab\u00a0raison-subvertie\u00a0\u00bb (avec tiret), selon une pr\u00e9cision conceprtuelle qui est intervenue dans notre conception initiale, pr\u00e9sent\u00e9e le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde-crisis_la_crise_de_la_raison_humaine_29_11_2014.html\">29 novembre 2014<\/a> dans cette rubrique, \u00e0 partir d&rsquo;un texte <em>dde.crisis<\/em> datant du 10 juillet 2010. Les \u00e9v\u00e9nements du monde, le caract\u00e8re crisique absolu de l&rsquo;\u00e9poque que nous vivons, l&rsquo;inversion r\u00e9gnante de fa\u00e7on syst\u00e9matique qui caract\u00e9rise les actes des autorit\u00e9s en place, la subversion totale de la plupart des esprits des \u00e9lites-Syst\u00e8me, tout cela permet de conclure que la \u00ab\u00a0raison-subvertie\u00a0\u00bb est devenue une <strong>cat\u00e9gorie en soi<\/strong> du monde intellectuel du <em>sapiens<\/em>.<\/p>\n<\/p>\n<p><p>(4) Dans ce cas bien pr\u00e9cis, il doit \u00eatre entendu comme \u00e9vident que les \u00ab\u00a0Id\u00e9es\u00a0\u00bb qui sont cit\u00e9es sont des produits absolument subversifs, des Id\u00e9es-inverties par rapport au sens que l&rsquo;Id\u00e9e cr\u00e9atrice d&rsquo;id\u00e9al peut avoir dans un cadre structurant d&rsquo;harmonie, d&rsquo;\u00e9quilibre et d&rsquo;ordre comme en sugg\u00e8re la tradition selon notre interpr\u00e9tation. Ces Id\u00e9es sont des ruses de la Mati\u00e8re (ou du Mal) pour satisfaire la raison-subvertie et ainsi achever sa subversion. Elles sont un artifice de communication, une sorte d'\u00a0\u00bbhollywoodisme\u00a0\u00bb si l&rsquo;on veut une image convenante et facile, pour parfaire l&rsquo;illusion que repr\u00e9sente la R\u00e9volution fran\u00e7aise dans l&rsquo;\u00e9pisode maniaque manipul\u00e9 \u00e0 son avantage par la Mati\u00e8re d\u00e9cha&icirc;n\u00e9e.<\/p>\n<\/p>\n<p><p>(5) Dans ce passage, nous avons apport\u00e9 des modifications de pr\u00e9cision pour bien marquer la rupture fondamentale de la psychologie entre \u00ab\u00a0les temps d&rsquo;avant\u00a0\u00bb et \u00ab\u00a0le temps de la modernit\u00e9\u00a0\u00bb. Cela correspond \u00e0 un renversement complet du sens de la perception du monde, tel que nous nous le constatons \u00e0 partir de la Renaissance, notamment selon notre interpr\u00e9tation dans le deuxi\u00e8me Tome de <em>La Gr\u00e2ce de l&rsquo;Histoire<\/em>, Troisi\u00e8me Partie, et c&rsquo;est \u00e0 cela que se r\u00e9f\u00e8re le renversement auquel nous assistons avec la psychologie, avec la manifestation du Mal passant de la d\u00e9pression o&ugrave; il est \u00e0 visage d\u00e9couvert, \u00e0 l&rsquo;\u00e9pisode maniaque o&ugrave; il est absolument tromperie : &laquo;<em>La mati\u00e8re concr\u00e8te de ces remarques concerne principalement le retournement rupturiel de la r\u00e9f\u00e9rence fondamentale de l&rsquo;humanit\u00e9 de ce temps-l\u00e0 d&rsquo;autour de la Renaissance. Jusqu&rsquo;alors, cette r\u00e9f\u00e9rence s&rsquo;inscrivait comme une poutre-ma&icirc;tresse dans la Tradition fix\u00e9e dans le pass\u00e9 comme la source spirituelle de toutes choses, n\u00e9cessairement comme une trace de la lumi\u00e8re des origines o&ugrave; l&rsquo;infini de la perspective nimbait la cosmologie du monde; d\u00e9sormais, cette r\u00e9f\u00e9rence est l&rsquo;avenir, d\u00e9cr\u00e9t\u00e9 sublime, lav\u00e9e de tout soup\u00e7on de transcendance par la gr\u00e2ce interlope d&rsquo;une sorte de divinit\u00e9 faussaire parfaitement ma&icirc;tris\u00e9e, recompos\u00e9e selon des normes dites \u00ab\u00a0humanistes\u00a0\u00bb, pr\u00e9tendant hausser l&rsquo;univers \u00e0 l&rsquo;image de nos ambitions pr\u00e9tendues hautes, nous haussant nous-m\u00eames, du moins dans la pr\u00e9tention, selon les normes de notre hybris. La r\u00e9f\u00e9rence dite fondamentale change radicalement, du pass\u00e9 qui structure notre civilisation \u00e0 l&rsquo;avenir qui la transformera \u00e9videmment, si ce n&rsquo;est en cours&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>(6) C&rsquo;est un point historique que nous jugeons particuli\u00e8rement important, et sur lequel nous devons toujours insister. Il s&rsquo;agit du basculement de 1996, apr\u00e8s cinq ann\u00e9es de terrible d\u00e9pression du sentiment g\u00e9n\u00e9ral US, qui aurait pu faire croire \u00e0 la possibilit\u00e9 d&rsquo;une r\u00e9action salutaire, &ndash; selon l&rsquo;id\u00e9e introduite dans cette \u00e9tude que la d\u00e9pression peut et doit \u00eatre salvatrice; c&rsquo;e&ucirc;t \u00e9t\u00e9 alors une r\u00e9volte des citoyens am\u00e9ricains contre le syst\u00e8me de l&rsquo;am\u00e9ricanisme, for\u00e7ant \u00e0 des bouleversements de lui-m\u00eame par ce syst\u00e8me. Au contraire, la psychologie am\u00e9ricaniste, \u00e0 nouveau reprise par ses d\u00e9mons renvoyant \u00e9videmment au Syst\u00e8me et \u00e0 la tromperie moderniste, versa dans une phase maniaque absolument paroxystique. Les JO d&rsquo;Atlanta de juillet 1996 furent l&rsquo;\u00e9v\u00e9nement qui permit ce renversement, comme on le lit notamment dans un texte du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-d_atlanta-1996_new_orleans-2005_02_09_2005.html\">2 septembre 2005<\/a> sur ce site.<\/p>\n<\/p>\n<p><p>(7) Nous avions souvent rappel\u00e9 et comment\u00e9 cette d\u00e9claration d&rsquo;Alan Greenspan qui s&rsquo;inscrit \u00e9videmment dans l&rsquo;\u00e9pisode maniaque \u00e9voqu\u00e9 \u00e0 la note (6). On peut en trouver un rappel, par exemple le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-out_of_history_par_en-dessous__23_07_2012.html\">23 juillet 2012<\/a>.<\/p>\n<\/p>\n<p><p>(8) Paroles d&rsquo;un \u00ab\u00a0officiel\u00a0\u00bb de l&rsquo;\u00e9quipe GW Bush dite \u00e0 l&rsquo;\u00e9t\u00e9 2002 au journaliste Ron Suskind, voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_virtualisme_identifi_washington_23_10_2004.html\">23 octobre 2004<\/a>.<\/p>\n<\/p>\n<p><p>(9) Tout le destin d&rsquo;Obama est r\u00e9sum\u00e9 dans la formule \u00ab\u00a0<em>American<\/em> <a class=\"gen\" href=\" http:\/\/www.dedefensa.org\/article-american_gorbatchev_29_10_2008.html\">Gorbatchev<\/a>\u00a0\u00bb qu&rsquo;il repoussa malgr\u00e9 l&rsquo;objurgation du destin. Son refus d&rsquo;\u00eatre un \u00ab\u00a0<em>American<\/em> Gorbatchev\u00a0\u00bb qui aurait \u00e9cart\u00e9 la psychologie maniaque de la direction politique au profit d&rsquo;une d\u00e9marche volontariste d\u00e9couvrant l&rsquo;\u00e9tat d\u00e9pressif de l&rsquo;Am\u00e9rique marque sans doute l&rsquo;\u00e9chec d\u00e9cisif d&rsquo;une r\u00e9forme possible, la derni\u00e8re chance de r\u00e9forme du Syst\u00e8me. En un sens, l&rsquo;\u00e9pisode maniaque de la nuit suivant l&rsquo;\u00e9lection de novembre 2008 constituait paradoxalement un appel d\u00e9sesp\u00e9r\u00e9 de la psychologie collective au pr\u00e9sident \u00e9lu pour qu&rsquo;il accepte de s&rsquo;ouvrir \u00e0 l&rsquo;aspect d\u00e9pressif exprimant la v\u00e9ritable situation des USA. (Voir notre texte du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_enthousiasme_fou_du_desespoir_06_11_2008.html\">6 novembre 2008<\/a>, &laquo;<em>L&rsquo;enthousiasme fou du d\u00e9sespoir<\/em>&raquo;.) Le refus d&rsquo;Obama fait de lui \u00ab\u00a0le pr\u00e9sident intelligent le plus stupide\u00a0\u00bb de l&rsquo;histoire des USA et une sorte de deuxi\u00e8me mise en esclavage, de type postmoderne bien entendu, de la communaut\u00e9 Am\u00e9ricaine-Africaine des USA.<\/p>\n<\/p>\n<p><p>(10) Voir notamment les textes du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_chaine_crisique_ddecrisis_02_04_2011.html\">2 avril 2011<\/a> (la \u00ab\u00a0cha&icirc;ne crisique\u00a0\u00bb du \u00ab\u00a0printemps arabe\u00a0\u00bb) et du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_occupy_la_crise_ddecrisis_11_11_2011.html\">11 novembre 2011<\/a> (le mouvement <em>Occupy<\/em> Wall Street).<\/p>\n<\/p>\n<p><p>(11) Nous pr\u00e9ciserions l&rsquo;id\u00e9e de \u00ab\u00a0gagner du terrain\u00a0\u00bb de cette fa\u00e7on : la partie d\u00e9pressive a avanc\u00e9 d&rsquo;une fa\u00e7on significative dans la perception que la partie maniaque (la direction-Syst\u00e8me) est en crise profonde. Cette fa\u00e7on d&rsquo;attirer la partie maniaque vers une reconnaissance forc\u00e9e de la r\u00e9alit\u00e9 engendre effectivement un surcroit d&rsquo;incoh\u00e9rence de la part de cette partie maniaque. La poursuite (in\u00e9vitable par ailleurs) de l&rsquo;\u00e9pisode maniaque signifie une accentuation du simulacre, du poids de la v\u00e9rit\u00e9 du monde sur la psychologie, une fatigue suppl\u00e9mentaire de la psychologie de la partie maniaque, une accentuation de sa crise, de la perception de sa crise par elle-m\u00eame, etc. \u00ab\u00a0Gagner du terrain\u00a0\u00bb implique une avanc\u00e9e dans une bataille des psychologies, entre simulacre et v\u00e9rit\u00e9 du monde (entre \u00e9pisode maniaque et \u00e9pisode d\u00e9pressif).<\/p>\n<\/p>\n<p><p>(12) Voir notre texte du <em>Glossaire.dde-crisis<\/em> du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde-crisis_la_source_de_tous_les_maux_28_01_2015.html\">28 janvier 2015<\/a>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Glossaire.dde-crisis : la maniaco-d\u00e9pression du monde 16 mars 2015 &ndash; Ce Glossaire.dde-crisis reprend le texte de dde.crisis du 10 janvier 2012. Les conditions de cette politique de \u00ab\u00a0reprise\u00a0\u00bb des textes de divers num\u00e9ros de dde.crisis sont explicit\u00e9es dans le texte du 28 novembre 2014 dans cette rubrique. Cette livraison de dde.crisis tentait de d\u00e9velopper une&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[19],"tags":[354,370,4733,9625,3285,3228,8254,2631,3083,11830,2782,2670,6944,4223,3041,2995,10695,4280,10032,3099,2699,5261,5164],"class_list":["post-75809","post","type-post","status-publish","format-standard","hentry","category-glossairedde","tag-354","tag-370","tag-atlanta","tag-bipolaire","tag-congres","tag-crise","tag-dde-crisis","tag-de","tag-depression","tag-episode","tag-ferrero","tag-financiere","tag-greenwald","tag-jo","tag-mal","tag-maniaco-depression","tag-maniaque","tag-pathologie","tag-plotin","tag-psychologie","tag-talleyrand","tag-trouble","tag-vienne"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75809"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75809\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}