{"id":75818,"date":"2015-03-20T11:44:48","date_gmt":"2015-03-20T11:44:48","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/03\/20\/le-vote-de-mallarme\/"},"modified":"2015-03-20T11:44:48","modified_gmt":"2015-03-20T11:44:48","slug":"le-vote-de-mallarme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/03\/20\/le-vote-de-mallarme\/","title":{"rendered":"Le vote de Mallarm\u00e9"},"content":{"rendered":"<p><h2 class=\"common-article2\">Le vote de Mallarm\u00e9<\/h2>\n<\/p>\n<p><p>\t\u00abJe dis: une fleur! et, hors de l&rsquo;oubli o\u00f9 ma voix rel\u00e8gue aucun contour, en tant que quelque chose d&rsquo;autre que les calice sus, musicalement se l\u00e8ve, id\u00e9e m\u00eame et suave, l&rsquo;absente de tous bouquets.<\/p>\n<\/p>\n<p><p>\tApr\u00e8s la d\u00e9couverte de cette fine fleur, il \u00e9crit dans une lettre \u00e0 son ami Cazalis: \u00abJe viens de passer une ann\u00e9e effrayante, ma Pens\u00e9e s&rsquo;est pens\u00e9e et est arriv\u00e9e \u00e0 une Conception pure. Je dois t&rsquo;apprendre que je suis maintenant impersonnel, non plus St\u00e9phane que tu as connu, mais une aptitude qu&rsquo;a l&rsquo;Univers spirituel \u00e0 se voir et \u00e0 se d\u00e9velopper, \u00e0 travers ce qui fut moi.<\/p>\n<\/p>\n<p><p>\t\u00ab[<strong><em>A<\/em><\/strong>]<strong><em>ptitude qu&rsquo;a l&rsquo;Univers spirituel \u00e0 se voir et \u00e0 se d\u00e9velopper, \u00e0 travers ce qui fut moi<\/em><\/strong>\u00bb. Tout est dit. Certes avec des mots appartenant \u00e0 ce que notre po\u00e8te appelle la \u00ab\u00a0mentale denr\u00e9e\u00a0\u00bb, le langage ordinaire, mais le sens en est clair: il s&rsquo;agit d&rsquo;une soumission de ce que j&rsquo;ai \u00e9t\u00e9 ou ai cru \u00eatre, \u00e0 l&rsquo;Univers spirituel. Mallarm\u00e9 se soumet, fait soumission. En ces temps de <em>Soumission<\/em> houellebecquienne (son livre vient \u00e0 point illustrer le proph\u00e9tique du Livre), il n&rsquo;est pas sans int\u00e9r\u00eat de le rappeler. Parler, c&rsquo;est se soumettre qu&rsquo;on soit beauf, p\u00e9kin, charlie, humoriste bouffeur de mentale denr\u00e9e, ou gourmet bobo, intello raffin\u00e9 aimant l&rsquo;absente fleur, on est soumis \u00e0 l&rsquo;Univers. En arabe \u00e7a se dit: <strong>musulman<\/strong>.<\/p>\n<\/p>\n<p><p>\tQuand je parle, que je le veuille ou pas, je suis parl\u00e9 et comme le <em>je suis parl\u00e9<\/em> n&rsquo;a pas pour chacun les m\u00eames titres de noblesse, beaucoup de <em>je suis parl\u00e9<\/em> sont des <em>je suis charlie<\/em>, des je suis charlatan, charlot, coolie, bailli, etc., et en sont fiers. Et ces charlie votent dimanche&#8230; Il serait bon, en ces temps de libert\u00e9 d&rsquo;expression que chacun tourne sa langue sept fois dans sa bouche avant d&rsquo;en laisser sortir de la denr\u00e9e et qu&rsquo;\u00e0 la libert\u00e9 d&rsquo;expression, nos fr\u00e8res humains s&rsquo;affairent plut\u00f4t, non \u00e0 la libert\u00e9 de penser, chose impossible si l&rsquo;on suit Mallarm\u00e9, mais au devoir de penser, \u00e0 un penser qui se pense et qui donc serait un penser authentique. Ce devoir accompli, on leur laisserait la libert\u00e9 de s&rsquo;exprimer en esp\u00e9rant que moins d&rsquo;\u00e9normit\u00e9s en sortent sur Daesh, le Syrien qui ne devait pas exister, le Poutine pervers et autres insanit\u00e9s qu&rsquo;\u00e9ructent pr\u00e9sident, ministre, journalistes, calvistes, politologues, experts<\/p>\n<\/p>\n<p><p>\t\u00abJe dis: une fleur! et, hors de l&rsquo;oubli o\u00f9 ma voix rel\u00e8gue aucun contour, en tant que quelque chose d&rsquo;autre que les calice sus\u00bb&#8230; bon, bon d&rsquo;accord on conna\u00eet!.. Alors : je dis <em>marinelepen<\/em> et, hors l&rsquo;oubli o\u00f9 ma voix rel\u00e8gue son contour en tant que quelque chose d&rsquo;autres que ses coulisses sues, musicalement, se l\u00e8vera l&rsquo;id\u00e9e suave de la future pr\u00e9sente au grand banquet de l&rsquo;absence d\u00e9mocratique? Certes, elle m\u00e2che beaucoup de mentale denr\u00e9e, la pen, la femme qu&rsquo;elle est n&rsquo;est pas le Nom de l&rsquo;Univers, mais enfin, s&rsquo;il faut passer par la boucherie non casher pour se d\u00e9barrasser des gar\u00e7ons bouchers qui taillent dans la viande nationale, on peut oublier un temps son r\u00e9gime v\u00e9g\u00e9tarien et se mettre \u00e0 la peine Je me serais bien mis \u00e0 la merluche mais un doute existe malgr\u00e9 qu&rsquo;il ait dit qu&rsquo;un tzar-poutine vaut mieux que deux tulauras d\u00e9mocrates. J&rsquo;attends qu&rsquo;il dise: \u00ab Je dis bachar et hors de l&rsquo;oubli o\u00f9 ma voix rel\u00e8gue son contour, en tant que quelque chose d&rsquo;autre que les ragots d\u00e9suets, etc \u00bb. Dans [bachar] il y a <em>char<\/em> et il y a <em>bas<\/em>. Bon profil pour un boucher \u00e0 la Valls ou un autre <em>cr\u00e9tin<\/em> de la caste. Le nommer El-assad serait tomber en musulmonomanie et, fleurant le racisme, \u00e0 d\u00e9noncer \u00e0 fabi gai sot. Entre temps, l&rsquo;\u00e9tant niaou a retrouv\u00e9 la jouissance de son \u00eatre \u00e0 la pens\u00e9e qu&rsquo;il gaza. \u00ab\u00a0La litt\u00e9rature, d&rsquo;accord en cela avec la faim, consiste \u00e0 supprimer le monsieur qui reste en l&rsquo;\u00e9crivant\u00a0\u00bb. Sacr\u00e9 St\u00e9phane, on te ferait bien premier ministre et m\u00eame pr\u00e9sident !&#8230;<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Marc G\u00e9belin<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le vote de Mallarm\u00e9 \u00abJe dis: une fleur! et, hors de l&rsquo;oubli o\u00f9 ma voix rel\u00e8gue aucun contour, en tant que quelque chose d&rsquo;autre que les calice sus, musicalement se l\u00e8ve, id\u00e9e m\u00eame et suave, l&rsquo;absente de tous bouquets. Apr\u00e8s la d\u00e9couverte de cette fine fleur, il \u00e9crit dans une lettre \u00e0 son ami Cazalis:&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[11880,12740],"class_list":["post-75818","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-gebelin","tag-valls"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75818"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75818\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}