{"id":75820,"date":"2015-03-21T11:23:03","date_gmt":"2015-03-21T11:23:03","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/03\/21\/poutine-et-la-crimee-un-an-plus-tard\/"},"modified":"2015-03-21T11:23:03","modified_gmt":"2015-03-21T11:23:03","slug":"poutine-et-la-crimee-un-an-plus-tard","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/03\/21\/poutine-et-la-crimee-un-an-plus-tard\/","title":{"rendered":"Poutine et la Crim\u00e9e, un an plus tard"},"content":{"rendered":"<p><h4 class=\"breve-de-crise\">Poutine et la Crim\u00e9e, un an plus tard<\/h4>\n<p>Le r\u00e9cit qu&rsquo;a fait le pr\u00e9sident russe Poutine des \u00e9v\u00e9nements de Crim\u00e9e de mars 2014 constitue incontestablement un document pour l&rsquo;histoire. Il s&rsquo;agit de la description de l&rsquo;op\u00e9ration engag\u00e9e \u00e0 partir du 22-23 f\u00e9vrier 2014 par la Russie, aboutissant \u00e0 la partition de la Crim\u00e9e et son int\u00e9gration dans la F\u00e9d\u00e9ration de Russie apr\u00e8s le r\u00e9f\u00e9rendum de la mi-mars 2014. De nombreux commentaires ont d\u00e9j\u00e0 \u00e9t\u00e9 faits sur le r\u00e9cit qu&rsquo;a fait Poutne de cet \u00e9v\u00e9nement, et parmi ceux-ci la confirmation que l&rsquo;\u00e9tat d&rsquo;alerte des forces russes durant cette p\u00e9riode impliquait notamment les forces strat\u00e9giques nucl\u00e9aires.<\/p>\n<\/p>\n<p><p>\tMK Bhadrakumar commente \u00e0 son tour cette intervention de communication de Poutine, le <a href=\"http:\/\/blogs.rediff.com\/mkbhadrakumar\/2015\/03\/19\/putin-declassifies-the-crimea-file\/\" class=\"gen\">19 mars 2014<\/a> sur son site <em>Indian PunchLine<\/em>. Bhadrakumar insiste sur le fait que les Russes ont consid\u00e9r\u00e9 d\u00e8s l&rsquo;origine, \u00e0 partir d&rsquo;informations tr\u00e8s pr\u00e9cises, que les instigateurs et \u00e9ventuels protagonistes des op\u00e9rations de prise du pouvoir et d&rsquo;\u00e9ventuelles suites comme un investissement de la Crim\u00e9e par les milices d&rsquo;extr\u00eame-droite et n\u00e9o-nazies \u00e9taient essentiellement, sinon exclusivement les USA avec divers d\u00e9tachements de soutien (CIA notamment). D&rsquo;une fa\u00e7on tr\u00e8s caract\u00e9ristique qui peut \u00eatre interpr\u00e9t\u00e9e de diverses mani\u00e8re (de l&rsquo;ironie \u00e0 la volont\u00e9 d&rsquo;apaisement), Poutine continue dans son r\u00e9cit \u00e0 nommer la partie am\u00e9ricaniste nos partenaires et amis. Concernant S\u00e9bastopol et sa base navale, Poutine donne des pr\u00e9cisions sur le syst\u00e8me int\u00e9gr\u00e9 de d\u00e9fense c\u00f4ti\u00e8re <em>Bastion<\/em>, avec notamment  des missiles terre-mer SS-N-26 (Mach 2,0 au ras des flots, 300 km de port\u00e9e), qui avait \u00e9t\u00e9 d\u00e9ploy\u00e9 explicitement contre d&rsquo;\u00e9ventuelles actions de l&rsquo;US Navy durant l&rsquo;op\u00e9ration effectu\u00e9e en Crim\u00e9e :  <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Bastion is a defensive system. It is a coastal defence system, for territorial defence. It is not designed to attack anyone. But yes, it is an effective, state-of-the-art, high-precision weapon. For the moment, no-one else has this kind of weapon. It is probably the most effective coastal defence system in the world at present. So, yes, at a certain point, in order to make it clear that Crimea is reliably protected, we deployed these Bastion coastal systems there. And, in addition, we deliberately deployed these systems so that they could be seen from space.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tBhadrakumar consid\u00e8re r\u00e9trospectivement, \u00e0 la lumi\u00e8re de ces r\u00e9v\u00e9lations de Poutine et d&rsquo;autres \u00e9l\u00e9ments, que la crise ukrainienne a de plus en plus de chance (!) de figurer comme l&rsquo;un, sinon le plus grand d\u00e9sastre de politique ext\u00e9rieure pour les USA, pour un XXI\u00e8me si\u00e8cle d\u00e9j\u00e0 marqu\u00e9 par de nombreux d\u00e9sastres pour les USA. Il termine en sugg\u00e9rant que les Russes doivent d\u00e9tenir de tr\u00e8s nombreuses indications encore secr\u00e8tes sur les implications et les actions US en Ukraine, ce qui donne \u00e0 la Russie un certain levier de pression sur les USA. Il est manifeste que cette assertion, compte tenu des contacts habituels de Bhadrakumar dans les milieux diplomatiques de son pays, fait partie des pr\u00e9cisions officieuses que les Russes ont partag\u00e9es avec certains pays proches,  dans ce cas, notamment, l&rsquo;Inde en tant que pays faisant partie des BRICS. Il appara\u00eet assur\u00e9 que les USA ont du restreindre leur action en Ukraine en diverses occasions, de crainte de trop s&rsquo;exposer, soit \u00e0 des ripostes russes tr\u00e8s dangereuses, soit \u00e0 la diffusion d&rsquo;informations tr\u00e8s dommageables pour leur <em>narrative<\/em> officielle. (C&rsquo;est notamment \u00e0 cette lumi\u00e8re qu&rsquo;il faut rappeler l&rsquo;incident d&rsquo;un Su-24 russe rencontrant le USS <em>Donald Cool<\/em> en Mer Noire, tel que rapport\u00e9 le <a href=\"http:\/\/www.dedefensa.org\/article-su-24_versus_uss_donald_cook_23_04_2014.html\" class=\"gen\">23 avril 2014<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In retrospect, the big question that needs to be asked is whether the entire Ukraine crisis didn&rsquo;t turn out to be ultimately a botched-up color revolution&rsquo;. The US got in  their man in power in Kiev to replace the ousted government  Prime Minister Arseniy Yatsenyuk  but at what enormous cost and of what avail? The principal strategic objective of establishing US military presence in Crimea and vanquishing Russia&rsquo;s Black Sea Fleet altogether (which Catherine the Great had established in 1783) couldn&rsquo;t be realized. The successor regime in Kiev is indeed under American thumb but is unable to stabilize the situation. Meanwhile, the agenda of getting Ukraine into the EU and NATO got frustrated. Ukraine itself is irrevocably split and its economy is in free fall. The IMF&rsquo;s painful therapy may only aggravate the socio-economic tensions leading eventually to a popular uprising.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The dubious achievements that the US reasserted its Trans-Atlantic leadership or that NATO has been brought back to life or even that Russia has been isolated&rsquo; are also increasingly debatable. Ironically, the US diplomacy will now onward need to focus on rallying opinion how to thwart the major European powers from restoring their disrupted economic ties with Russia. The most awful miscalculation by Washington was regarding Putin&rsquo;s strong reaction to the capture of power by the Ukrainian nationalists backed by the US. Again, contrary to the US expectations that discredited Putin would be politically weakened, thanks to his decisive moves, his popularity rating in Russia today touches an incredible 86 percent.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>As more and more details get revealed in due course about the American operation to depose the elected government of Yanukovich  not only from Moscow but also other European capitals  Ukraine conflict will become eligible to take its place in history books as a great foreign-policy disaster for the US in the twenty first century and a serious blot on the Barack Obama presidency itself. The Russian intelligence surely is in possession of very damaging materials to expose the US role and Putin may have only scratched the surface.<\/em>\u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 21 mars 2015 \u00e0 11H24<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poutine et la Crim\u00e9e, un an plus tard Le r\u00e9cit qu&rsquo;a fait le pr\u00e9sident russe Poutine des \u00e9v\u00e9nements de Crim\u00e9e de mars 2014 constitue incontestablement un document pour l&rsquo;histoire. Il s&rsquo;agit de la description de l&rsquo;op\u00e9ration engag\u00e9e \u00e0 partir du 22-23 f\u00e9vrier 2014 par la Russie, aboutissant \u00e0 la partition de la Crim\u00e9e et son&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[15091,5474,2684,916,15758,1296],"class_list":["post-75820","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-bastion","tag-bhadrakumar","tag-crimee","tag-poutine","tag-su-24","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75820"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75820\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}