{"id":75841,"date":"2015-04-01T06:07:19","date_gmt":"2015-04-01T06:07:19","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/04\/01\/schumpeter-le-capitalisme-mondialise-et-la-democratie\/"},"modified":"2015-04-01T06:07:19","modified_gmt":"2015-04-01T06:07:19","slug":"schumpeter-le-capitalisme-mondialise-et-la-democratie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/04\/01\/schumpeter-le-capitalisme-mondialise-et-la-democratie\/","title":{"rendered":"Schumpeter, le capitalisme mondialis\u00e9 et la d\u00e9mocratie"},"content":{"rendered":"<p><h2 class=\"common-article2\">Schumpeter, le capitalisme mondialis\u00e9 et la d\u00e9mocratie<\/h2>\n<\/p>\n<p><p>\tDans son ma\u00eetre-ouvrage <em>Capitalisme, socialisme et d\u00e9mocratie<\/em> (1942), l&rsquo;\u00e9conomiste Joseph Schumpeter nous donne la meilleure clef de lecture de la construction euro-atlantiste : \u00ab<em>L&rsquo;impulsion fondamentale qui met et maintient en mouvement la machine capitaliste est imprim\u00e9e par les nouveaux objets de consommation, les nouvelles m\u00e9thodes de production et de transport, les nouveaux march\u00e9s, les nouveaux types d&rsquo;organisation industrielle, tous \u00e9l\u00e9ments cr\u00e9\u00e9s par l&rsquo;initiative capitaliste<\/em> () [qui] <em>r\u00e9volutionne incessamment de l&rsquo;int\u00e9rieur la structure \u00e9conomique, en d\u00e9truisant continuellement ses \u00e9l\u00e9ments vieillis et en cr\u00e9ant continuellement des \u00e9l\u00e9ments neufs. Ce processus de destruction cr\u00e9atrice constitue la donn\u00e9e fondamentale du capitalisme : c&rsquo;est en elle que consiste, en derni\u00e8re analyse, le capitalisme et toute entreprise capitaliste doit, bon gr\u00e9 malgr\u00e9, s&rsquo;y adapter<\/em>\u00bb. Plus une organisation devient grande, plus elle rencontre le succ\u00e8s, plus elle a besoin de march\u00e9s \u00e9tablis importants pour maintenir son rythme de croissance. L&rsquo;\u00e9largissement et l&rsquo;approfondissement du march\u00e9 peuvent \u00eatre obtenus par diff\u00e9rents proc\u00e9d\u00e9s. L&rsquo;innovation est la voie royale, mais al\u00e9atoire et potentiellement d\u00e9stabilisante. La mise en \u00e9bullition du march\u00e9 conduit \u00e0 la soci\u00e9t\u00e9 de consommation et de loisirs. L&rsquo;injection de liquidit\u00e9s par cr\u00e9ation de monnaie produit de l&rsquo;endettement public et priv\u00e9. Le commerce international \u00e9largit la base de consommateurs et abaisse le co\u00fbt du travail. L&rsquo;ouverture de march\u00e9s ext\u00e9rieurs se fait par la n\u00e9gociation ou la force. Arr\u00eatons-nous un instant sur les effets b\u00e9n\u00e9fiques pour le capitalisme mondialis\u00e9 de l&rsquo;immigration, des importations \u00e0 bas co\u00fbts et des unions douani\u00e8res.<\/p>\n<\/p>\n<p><p>\tL&rsquo;immigration participe de la croissance d\u00e9mographique du march\u00e9. Elle donne acc\u00e8s \u00e0 de nouveaux talents. L&rsquo;\u00e9tat d&rsquo;esprit de l&rsquo;immigr\u00e9, quittant tout pour une vie meilleure, est proche de celui de l&rsquo;entrepreneur. Vuln\u00e9rable \u00e9conomiquement, il est en g\u00e9n\u00e9ral un travailleur docile. L&rsquo;immigr\u00e9 est souvent contraint d&rsquo;accepter des conditions de travail et un salaire inf\u00e9rieurs \u00e0 ceux de l&rsquo;autochtone. Voire du travail clandestin si la l\u00e9gislation en vigueur est laxiste ou n&rsquo;est pas soutenue par les pouvoirs publics. Limmigration tire ainsi vers le bas les salaires pour les travaux les moins qualifi\u00e9s. Le jeu de l&rsquo;offre et de la demande augmente le nombre de travailleurs pauvres. Des millions de personnes au salaire minimum, au ch\u00f4mage ou travaillant au noir ; une pression \u00e0 la baisse des salaires et une d\u00e9pendance croissante vis-\u00e0-vis de l&rsquo;Etat-Providence ; le tout au profit des employeurs publics et priv\u00e9s, des consommateurs. Par ses transferts d&rsquo;argent vers son pays d&rsquo;origine, l&rsquo;immigr\u00e9 ouvre et rend solvables de nouveaux march\u00e9s.<\/p>\n<\/p>\n<p><p>\tLes importations massives de biens et services, quand elles proviennent de pays aux co\u00fbts du travail beaucoup plus bas, n&rsquo;entretiennent pas une saine concurrence mais d\u00e9stabilisent politiquement les pays consommateurs. Dans le cadre national, la production est r\u00e9gie par des l\u00e9gislations du travail, sociales, fiscales et environnementales, fruits d&rsquo;une lente maturation d\u00e9mocratique. Dans le prix d&rsquo;un bien ou service, il y a des salaires, des charges sociales, des imp\u00f4ts, des valeurs, le sang de tout un \u00e9cosyst\u00e8me culturel et productif [1]. Le commerce international d\u00e9r\u00e9gul\u00e9 a en outre de fortes r\u00e9percussions sur les politiques \u00e9conomique, mon\u00e9taire, de d\u00e9fense et des affaires \u00e9trang\u00e8res. Il retarde la prise de conscience \u00e9cologique, le consommateur n&rsquo;\u00e9tant plus expos\u00e9 \u00e0 la pollution imputable \u00e0 la production. En achetant massivement des biens et services import\u00e9s, le consommateur valide et renforce les \u00e9cosyst\u00e8mes dont ils sont originaires, au d\u00e9triment du sien. Les citoyens transf\u00e8rent du m\u00eame coup une part  toujours croissante de leurs pr\u00e9rogatives aux acteurs \u00e9conomiques ; ils leur donnent un pouvoir politique exorbitant. Au fil du temps, nous avons \u00e9chang\u00e9 l&rsquo;expression d\u00e9mocratique de notre volont\u00e9 contre des salaires et traitements, des dividendes et aides sociales, des prix bas&#8230; Corrompus, nous avons chang\u00e9 de r\u00e9gime politique sans m\u00eame nous en apercevoir. Le statut d&rsquo;importateur est une licence politique d\u00e9livr\u00e9e sur demande \u00e0 qui pense avoir les capacit\u00e9s et l&rsquo;\u00e9tat d&rsquo;esprit ad\u00e9quats. Formidable r\u00e9gression d\u00e9mocratique, aujourdhui \u00e0 la port\u00e9e de tous en quelques clics. Pour faire taire les r\u00e9sistances, le professeur de Harvard Michael Porter encourage les entreprises \u00e0 investir de fa\u00e7on responsable dans l&rsquo;\u00e9ducation, la sant\u00e9 [2] voire la d\u00e9fense [3]. Il en va de leur l\u00e9gitimit\u00e9 politique \u00e0 op\u00e9rer, donc de leurs futurs profits. Et l&rsquo;on trouve presque des accents patriotiques pour saluer les audacieux entrepreneurs qui, contre subventions et exon\u00e9rations fiscales, relocalisent leurs productions en France.<\/p>\n<\/p>\n<p><p>\tEn th\u00e9orie, le capitalisme s&rsquo;\u00e9panouit au sein d&rsquo;une union douani\u00e8re \u00e0 monnaie commune et ouverte sur le monde. L&rsquo;int\u00e9gration des pays voisins est l&rsquo;un de ses principaux enjeux strat\u00e9giques. Elle \u00e9largit le march\u00e9, le bassin de main d&rsquo;uvre et de talents, s\u00e9curise des approvisionnements en mati\u00e8res premi\u00e8res. Si les co\u00fbts du travail y sont plus bas, il y a l&rsquo;opportunit\u00e9 d&rsquo;augmenter les profits en relocalisant certaines productions, ce qui exerce une pression \u00e0 la baisse des salaires dans les secteurs impact\u00e9s de toute l&rsquo;union. Cet avantage peut \u00eatre \u00e9tendu \u00e0 de nombreux emplois r\u00e9put\u00e9s non d\u00e9localisables, dans le b\u00e2timent par exemple, avec la cr\u00e9ation d&rsquo;un statut de travailleur d\u00e9tach\u00e9. L&rsquo;int\u00e9gration future de nouveaux pays peut justifier l&rsquo;\u00e9limination <em>manu militari<\/em> de leaders politiques r\u00e9calcitrants, promoteurs d&rsquo;unions concurrentes susceptibles de restreindre l&rsquo;acc\u00e8s \u00e0 leurs march\u00e9s et mati\u00e8res premi\u00e8res. Ou l&rsquo;\u00e9preuve de force avec une autre union douani\u00e8re pour arracher de son orbite un pays prometteur ; faute de pouvoir s&rsquo;aligner sur le plan \u00e9conomique, la puissance adverse jouera alors de ses cartes militaire, nationaliste, voire religieuse. Il est enfin naturel pour une union de tenter de fusionner avec une autre organisation dont les \u00e9lites partagent les m\u00eames valeurs humanistes.<\/p>\n<\/p>\n<p><p>\tLe capitalisme mondialis\u00e9 est au capitalisme ce que l&rsquo;islamisme est \u00e0 l&rsquo;Islam : un d\u00e9veloppement avec sa logique, mortif\u00e8re quand elle est d\u00e9contextualis\u00e9e, hors sol. La Technique rendant tout cela possible ne porte pas en elle-m\u00eame de projet de soci\u00e9t\u00e9. Au contraire du capitalisme, qui en est l&rsquo;\u00e9cosyst\u00e8me s\u00e9lectif. Notre h\u00e9ritage humaniste justifia en leurs temps l&rsquo;\u00e9pop\u00e9e napol\u00e9onienne et la colonisation. La vigilance s&rsquo;impose face aux errements et manipulations de nos conditionnements culturels, sur le mode \u00e9nonc\u00e9 en souriant par un industriel chinois confront\u00e9 \u00e0 la hausse des salaires dans son pays: \u00ab<em>L&rsquo;heure est venue \u00e0 notre tour de soutenir le d\u00e9veloppement de la civilisation africaine, comme les Occidentaux l&rsquo;ont fait ici il y a trente ans<\/em>\u00bb [4]. Des Lumi\u00e8res \u00e0 un humanisme de bazar mondialis\u00e9. Avec \u00e7a, le capitalisme s\u00e9cr\u00e8te aussi un horizon m\u00e9taphysique : le transhumanisme. Eric Schmidt, patron de Google, d\u00e9clara cette ann\u00e9e au Forum de Davos : \u00ab<em>Internet est vou\u00e9 \u00e0 dispara\u00eetre<\/em>\u00bb. Comprenez que demain tous les objets seront connect\u00e9s et en interaction avec nous sans qu&rsquo;on s&rsquo;en rende compte [5]. Google saura tout, sera partout, authentique \u00ab<em>main invisible<\/em>\u00bb [6]. Eric Schmidt, Main de Dieu. Le pr\u00e9sident d&rsquo;Orange, St\u00e9phane Richard, fait p\u00e2le figure avec son \u00ab<em>Le t\u00e9l\u00e9phone sera la t\u00e9l\u00e9commande de la vie<\/em>\u00bb [7]. A notre \u00e9poque, le consommateur et le travailleur, ce dernier souvent \u00e0 son corps d\u00e9fendant, tuent \u00e0 petit feu le citoyen. Un choix de soci\u00e9t\u00e9 \u00abpayant\u00bb jusqu&rsquo;en 2007 [8]. Ce d\u00e9s\u00e9quilibre fait \u00e9cho \u00e0 celui qui, dans le triptyque du d\u00e9veloppement durable, voit l&rsquo;\u00e9conomie \u00e9craser le social et l&rsquo;environnement. Comment envisager une transition \u00e9cologique [9] en restant expos\u00e9 \u00e0 une concurrence internationale par les co\u00fbts (des mati\u00e8res premi\u00e8res, de l&rsquo;\u00e9nergie, du travail)? Alors que la robotisation s&rsquo;annonce d\u00e9stabilisante pour le travailleur [10] et qu&rsquo;Elon Musk, Bill Gates et Stephen Hawking mettent en garde l&rsquo;Humanit\u00e9 contre les dangers potentiels de l&rsquo;intelligence artificielle [11]. Oh, Sainte Destruction Cr\u00e9atrice.<\/p>\n<\/p>\n<p><p>\tLa dissolution du politique alimente l&rsquo;ins\u00e9curit\u00e9 globale, elle-m\u00eame fort bien recycl\u00e9e par le capitalisme mondialis\u00e9. Depuis quarante-cinq ans, la direction des affaires publiques en France se r\u00e9sume pour l&rsquo;essentiel \u00e0 l&rsquo;application m\u00e9canique d&rsquo;un programme qui n&rsquo;a rien de d\u00e9mocratique. L&rsquo;Egalit\u00e9 et la Fraternit\u00e9 sont sacrifi\u00e9es au nom d&rsquo;une Libert\u00e9 d\u00e9voy\u00e9e. Comment s&rsquo;\u00e9tonner qu&rsquo;aujourd&rsquo;hui une large majorit\u00e9 de l&rsquo;\u00e9lectorat s&rsquo;abstienne ou vote spectaculairement? Compter sur le retour de la croissance pour continuer sans opposition la fuite en avant rel\u00e8ve au mieux de l&rsquo;aveuglement id\u00e9ologique, le plus souvent de la l\u00e2chet\u00e9 et de l&rsquo;opportunisme, au pire de la corruption \u00e0 grande \u00e9chelle par argent public et priv\u00e9. <em>Homo homini lupus est<\/em> [12]. Ce n&rsquo;est pas le commerce en tant que tel qui fait avancer la civilisation universelle, fleur d\u00e9licate poussant sur le fumier, mais l&rsquo;\u00e9change d&rsquo;id\u00e9es. Dans la soci\u00e9t\u00e9 de l&rsquo;information, il n&rsquo;est pas n\u00e9cessaire de violer nos valeurs pour que f\u00e9condent les uvres de l&rsquo;esprit (brevets, technologies, proc\u00e9d\u00e9s, etc.). Hors de tout nationalisme, x\u00e9nophobie ou repli sur soi, la fronti\u00e8re peut seule unir plusieurs pays autour d&rsquo;un projet de soci\u00e9t\u00e9 \u00e0 la fois capitaliste, authentiquement lib\u00e9ral (les m\u00eames r\u00e8gles pour tous), d\u00e9mocratique et durable. Un peu plus digne d&rsquo;universalisation. La fronti\u00e8re est la condition n\u00e9cessaire de la politique qui fait sienne la devise du Mar\u00e9chal de Lattre de Tassigny : \u00ab<em>Ne pas subir<\/em>\u00bb. Pas de d\u00e9mocratie ni d&rsquo;\u00e9cologie sans souverainet\u00e9. A d\u00e9faut, Tocqueville nous aura pr\u00e9venus : \u00abMI>Qui cherche dans la libert\u00e9 autre chose qu&rsquo;elle-m\u00eame est fait pour servir<D>\u00bb.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">S\u00e9bastien Holu\u00e9<\/p>\n<\/p>\n<p><p>\t(Etudiant en Master 2 Prospective, Innovation, Strat\u00e9gie et Organisation du Conservatoire National des Arts et M\u00e9tiers [CNAM].)<\/p>\n<\/p>\n<p><\/p>\n<h4>Notes<\/h4>\n<p>[1] Voir PINARD LEGRY Agn\u00e8s, \u00ab Emery Jacquillat, le sauveur de la Camif \u00bb, Valeurs Actuelles, n\u00b04076, 8 janvier 2015, p.40-41<\/p>\n<\/p>\n<p><p>\t[2] PORTER Michael, KRAEMER Mark R., \u00ab The Big Idea : Creating Shared Value \u00bb,Harvard Business Review, janvier 2011<\/p>\n<\/p>\n<p><p>\t[3] GALLOIS Dominique, \u00ab Le minist\u00e8re de la d\u00e9fense innove pour boucler son budget \u00bb, Le Monde, <a href=\"http:\/\/www.lemonde.fr\/economie-francaise\/article\/2014\/12\/30\/le-ministere-de-la-defense-innove-pour-boucler-son-budget_4547272_1656968.html?xtmc=location_armee&#038;xtcr=5\" class=\"gen\">30 d\u00e9cembre 2014<\/a>. Consult\u00e9 le 20 mars 2015.<\/p>\n<\/p>\n<p><p>\t[4] FALLETTI S\u00e9bastien, \u00ab Quand la Chine devient trop ch\u00e8re et  d\u00e9localise \u00bb, Le Point, n\u00b02219, 19 mars 2015, p.84-89.<\/p>\n<\/p>\n<p><p>\t[5] COLOMBAIN J\u00e9r\u00f4me, \u00ab A Davos : comment Internet change le monde \u00bb, France Info, <a href=\"http:\/\/www.franceinfo.fr\/emission\/nouveau-monde\/2014-2015\/davos-comment-internet-change-le-monde-26-01-2015-06-50\" class=\"gen\">26 janvier 2015<\/a>. Consult\u00e9 le 19 mars 2015.<\/p>\n<\/p>\n<p><p>\t[6] SMITH Adam, <em>Th\u00e9orie des sentiments moraux<\/em>, 1759.<\/p>\n<\/p>\n<p><p>\t[7] RICHARD St\u00e9phane, \u00ab Le t\u00e9l\u00e9phone sera la t\u00e9l\u00e9commande de la vie \u00bb, propos recueillis par Marie de Greef-Madelin et Fr\u00e9d\u00e9ric Paya, Valeurs Actuelles, n\u00b04076, 8 janvier 2015, p.36-39.<\/p>\n<\/p>\n<p><p>\t[8] XERFI, \u00ab 30 ans de PIB par habitant : de la croissance \u00e0 la grande panne \u00bb, La Tribune, <a href=\"http:\/\/www.latribune.fr\/opinions\/tribunes\/30-ans-de-pib-par-habitant-de-la-croissance-a-la-grande-panne-460572.html\" class=\"gen\">14 mars 2015<\/a>. Consult\u00e9 le 16 mars 2015<\/p>\n<\/p>\n<p><p>\t[9] DESAUNAY C\u00e9cile, \u00ab Produire et consommer \u00e0 l&rsquo;\u00e8re de la transition \u00e9cologique \u00bb, Futuribles, n\u00b0403, novembre  d\u00e9cembre 2014, p.5-23<\/p>\n<\/p>\n<p><p>\t[10] \u00ab Les robots vont-ils prendre nos jobs ?  47% des emplois menac\u00e9s d&rsquo;ici \u00e0 vingt ans \u00bb, L&rsquo;Expansion, n\u00b0795, juin 2014, p.34-60<\/p>\n<\/p>\n<p><p>\t[11] COUE Philippe, \u00ab Intelligence artificielle  La plus grande invention de l&rsquo;homme ? \u00bb, Valeurs Actuelles, n\u00b04085, 12 mars 2015, p.89. Voir \u00e9galement LAPLANCHE Camille, \u00ab Cortana, pas si virtuelle \u00bb, idem, p.56<\/p>\n<\/p>\n<p><p>\t[12] \u00ab L&rsquo;homme est un loup pour l&rsquo;homme \u00bb, Plaute, <em>Asinaria<\/em>, 195 AV. JC.,<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schumpeter, le capitalisme mondialis\u00e9 et la d\u00e9mocratie Dans son ma\u00eetre-ouvrage Capitalisme, socialisme et d\u00e9mocratie (1942), l&rsquo;\u00e9conomiste Joseph Schumpeter nous donne la meilleure clef de lecture de la construction euro-atlantiste : \u00abL&rsquo;impulsion fondamentale qui met et maintient en mouvement la machine capitaliste est imprim\u00e9e par les nouveaux objets de consommation, les nouvelles m\u00e9thodes de production et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[5578,2686,10091,16523,16524,16522],"class_list":["post-75841","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-creatrice","tag-destruction","tag-google","tag-holue","tag-schmdt","tag-schumpeter"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75841"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75841\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}