{"id":75857,"date":"2015-04-13T04:59:00","date_gmt":"2015-04-13T04:59:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/04\/13\/notes-sur-les-trois-vies-de-lavion-rafale\/"},"modified":"2015-04-13T04:59:00","modified_gmt":"2015-04-13T04:59:00","slug":"notes-sur-les-trois-vies-de-lavion-rafale","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/04\/13\/notes-sur-les-trois-vies-de-lavion-rafale\/","title":{"rendered":"Notes sur les trois vies de l&rsquo;avion <em>Rafale<\/em>"},"content":{"rendered":"<p><h2>Notes sur les trois vies de l&rsquo;avion <em>Rafale<\/em><\/h2>\n<\/p>\n<p><p>13 avril 2015 &ndash; En un tout petit moins de deux mois, l&rsquo;avion fran\u00e7ais <em>Rafale<\/em> de Dassault a enregistr\u00e9 deux commandes \u00e0 l&rsquo;exportation (24 de l&rsquo;&Eacute;gypte le 12 f\u00e9vrier, 36 de l&rsquo;Inde le 10 avril), qui pr\u00e9sentent plusieurs caract\u00e9ristiques les rendant extr\u00eamement singuli\u00e8res et formant un \u00e9v\u00e9nement hors du commun. On \u00e9voque ici quelques points qui justifient le qualificatif de \u00ab\u00a0singuli\u00e8re\u00a0\u00bb et d\u00e9crivent cet \u00ab\u00a0\u00e9v\u00e9nement hors du commun\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&bull; D&rsquo;abord, il y a l&rsquo;\u00e9vidence d&rsquo;un avion de combat qui est offert \u00e0 l&rsquo;exportation depuis quasiment 1986, et formellement depuis 1987-1988 avec la Belgique, qui n&rsquo;a obtenu jusqu&rsquo;ici aucune commande, et qui en re\u00e7oit deux coup sur coup en un tout petit peu moins de deux mois. Le contraste entre ces \u00ab\u00a0presque 30 ans sans commande\u00a0\u00bb et ces \u00ab\u00a0deux commandes en un tout petit peu moins de deux mois\u00a0\u00bb est sans aucun doute singulier ; il s&rsquo;agit du m\u00eame avion de combat et aucun \u00e9v\u00e9nement extraordinaire, dans tous les cas dans l&rsquo;apparence de la pr\u00e9sentation publique des choses, ne justifie cette soudaine pr\u00e9cipitation. La banalit\u00e9 des commentaires convenus qu&rsquo;on a pu lire dans la presse-Syst\u00e8me et la presse sp\u00e9cialis\u00e9e, comme dans les discours officiels, ne satisfait gu\u00e8re l&rsquo;esprit.<\/p>\n<\/p>\n<p><p>&bull; Un autre fait significatif est que les deux commandes ont \u00e9t\u00e9 pass\u00e9es d&rsquo;une fa\u00e7on pr\u00e9cipit\u00e9e et urgente, par les deux autorit\u00e9s politiques supr\u00eames des deux pays concern\u00e9s, &ndash; le pr\u00e9sident \u00e9gyptien El Sisi et le Premier ministre indien Modi eux-m\u00eames, chacun passant manifestement au-dessus des processus bureaucratiques. C&rsquo;en est \u00e0 ce point que plut\u00f4t qu&rsquo;\u00e9crire \u00ab\u00a0la France a vendu en deux mois le <em>Rafale<\/em> \u00e0 l&rsquo;&Eacute;gypte et \u00e0 l&rsquo;Inde&#8230;\u00a0\u00bb, il serait plus juste d&rsquo;\u00e9crire qu'\u00a0\u00bben deux mois, l&rsquo;&Eacute;gypte et l&rsquo;Inde ont command\u00e9 le <em>Rafale<\/em> \u00e0 la France..\u00a0\u00bb. Il y a manifestement la m\u00eame d\u00e9marche politique chez les deux dirigeants, beaucoup plus que des longues n\u00e9gociations techniques accompagn\u00e9es de d\u00e9marches de marketing de la part du vendeur-solliciteur &#8230; (A cet \u00e9gard, il faut donc absolument s\u00e9parer la commande indienne de 36 avions des n\u00e9gociations qui ont lieu entre la France et l&rsquo;Inde depuis 2012 pour l&rsquo;acquisition de 126 <em>Rafale<\/em>. La d\u00e9cision de Modi rompt cette ligne de n\u00e9gociation et constitue un acte \u00e0 part. Les n\u00e9gociations commenc\u00e9es en 2012 continuent de leur c\u00f4t\u00e9, cette fois sur un chiffre sans doute ind\u00e9fini, puisqu&rsquo;on tiendrait sans doute compte de la commande de 36. Cette commande de 36 est effectivement, d&rsquo;un point de vue politique, un acte compl\u00e8tement diff\u00e9rent des n\u00e9gociations engag\u00e9es depuis 2012 et il faut donc la traiter \u00e0 part, en parall\u00e8le avec la commande \u00e9gyptienne.)<\/p>\n<\/p>\n<p><p>&bull; Dans les deux cas, les acheteurs veulent des <em>Rafale<\/em> les plus vite possible, sans complication de coop\u00e9ration, de r\u00e9partition de charges de travail, etc. C&rsquo;est un achat typique dit, dans le jargon ,\u00a0\u00bbcommande \u00ab\u00a0sur \u00e9tag\u00e8re\u00a0\u00bb, r\u00e9alis\u00e9 extr\u00eamement rapidement, en quelques petits mois. L&rsquo;essentiel est l&rsquo;acquisition et la disposition de l&rsquo;avion aussi vite que possible. Par exemple, dans le cas \u00e9gyptien, c&rsquo;est Sisi lui-m\u00eame qui a <strong>impos\u00e9<\/strong> la commande en octobre 2014, en demandant que les premiers exemplaires soient livr\u00e9s cette ann\u00e9e (2015), au point que certains avions devraient \u00eatre pr\u00e9lev\u00e9s sur les exemplaires sinon d\u00e9j\u00e0 produits dans tous les en voie de l&rsquo;\u00eatre, ceux-l\u00e0 destin\u00e9s primitivement \u00e0 l&rsquo;Arm\u00e9e de l&rsquo;Air fran\u00e7aise. Il semble que Modi demande des conditions similaires d&rsquo;urgence, &ndash; mais lui ne pourrait recevoir ses premiers <em>Rafale<\/em> qu&rsquo;au d\u00e9but 2016.<\/p>\n<\/p>\n<p><p>&bull; Dans les deux cas, des arguments politiques et op\u00e9rationnels sont avanc\u00e9s. Pour l&rsquo;&Eacute;gypte ce n&rsquo;est pas tant que Sisi a besoin de <em>Rafale<\/em> pour des op\u00e9rations a\u00e9riennes urgentes, notamment contre les foyers hostiles qui se d\u00e9veloppent en Libye  ; le facteur est consid\u00e9r\u00e9, mais il est secondaire &#8230; La cause en est l&rsquo;acc\u00e9l\u00e9ration du changement de politique ext\u00e9rieure de l&rsquo;&Eacute;gypte (distance prise avec l&rsquo;alliance US), qui se concr\u00e9tise parall\u00e8lement par un rapprochement strat\u00e9gique de la Russie, lui aussi en pleine acc\u00e9l\u00e9ration (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_gypte_tourne_le_dos_au_dollar_et_au_f-16_10_02_2015.html\">10 f\u00e9vrier 2015<\/a>). Le cas indien concerne le vieillissement acc\u00e9l\u00e9r\u00e9 de la flotte a\u00e9rienne militaire du pays qui compromet peut-\u00eatre d\u00e9cisivement l&rsquo;\u00e9quilibre militaire avec les deux voisins les plus importants de l&rsquo;Inde, le Pakistan et la Chine, alors que l&rsquo;avion fran\u00e7ais a \u00e9t\u00e9 jug\u00e9 par les militaires indiens comme parfaitement adapt\u00e9 \u00e0 certaines exigences op\u00e9rationnelles, \u00e0 c\u00f4t\u00e9 des avions russes et des projets de coop\u00e9ration de l&rsquo;Inde avec la Russie. Mais, finalement, peu importe ces raisons conjoncturelles et ces d\u00e9tails, qui peuvent \u00eatre sujets \u00e0 discussion. Ce qui importe, c&rsquo;est bien l&rsquo;urgence op\u00e9rationnelle qui surgit comme un argument majeur dans les deux cas, un argument si important que les deux autorit\u00e9s supr\u00eames des deux pays ont pris l&rsquo;affaire en main pour la conclure sans tarder.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Regard sur l&rsquo;histoire<\/h3>\n<\/p>\n<p><p>C&rsquo;est dans ce contexte d&rsquo;urgence et de conditions tr\u00e8s particuli\u00e8res de commande qu&rsquo;il nous fait consid\u00e9rer ces \u00e9v\u00e9nements, nous semble-t-il. C&rsquo;est \u00e9galement dans ce contexte qu&rsquo;il nous faut examiner le cas du <em>Rafale<\/em>, &ndash; car il s&rsquo;agit bien \u00ab\u00a0d&rsquo;un cas\u00a0\u00bb. C&rsquo;est de ce point de vue que \u00ab\u00a0le contraste entre ces &lsquo;presque 30 ans sans commande&rsquo; et ces &lsquo;deux commandes en un tout petit moins de deux mois'\u00a0\u00bb fait du <em>Rafale<\/em> \u00ab\u00a0un cas\u00a0\u00bb tr\u00e8s singulier.<\/p>\n<\/p>\n<p><p>C&rsquo;est de ce point de vue qu&rsquo;il nous semble utile, et m\u00eame n\u00e9cessaire de pr\u00e9senter un historique de l&rsquo;avion de combat <em>Rafale<\/em> dans le domaine de l&rsquo;exportation des armements. Cet historique ne doit \u00eatre ni industriel, ni militaire, ni m\u00eame du point de vue national et des rapports entre nations exportatrices d&rsquo;armements technologiquement tr\u00e8s avanc\u00e9s. Le contexte choisi doit \u00eatre le plus haut, le plus vaste, et le plus significatif possible. Il doit s&rsquo;inscrire dans l&rsquo;historique de la crise g\u00e9n\u00e9rale qui affecte ce que nous nommons le Syst\u00e8me, o&ugrave; la France, productrice du <em>Rafale<\/em>, occupe une place tr\u00e8s singuli\u00e8re et originale malgr\u00e9 tous les efforts qui ont \u00e9t\u00e9 faits pour la rendre conforme et similaire en tous points \u00e0 tous ses coreligionnaires du bloc am\u00e9ricaniste-occidentaliste (<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_bloc_bao_10_12_2012.html\">bloc BAO<\/a>).<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le <em>Rafale<\/em> antimoderne et antiSyst\u00e8me<\/h3>\n<\/p>\n<p><p>De <strong>ce point de vue crisique<\/strong> (de la dynamique des crises, dans le cadre de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_l_effondrement_du_syst_me_12_01_2014.html\">la crise d&rsquo;effondrement du Syst\u00e8me<\/a>), le <em>Rafale<\/em> fran\u00e7ais constitue \u00e0 lui seul une illustration fondamentale et remarquable du sort du syst\u00e8me du technologisme. D&rsquo;une fa\u00e7on extr\u00eamement paradoxale, ce syst\u00e8me-<em>Rafale<\/em> n\u00e9 du syst\u00e8me du technologisme, marquerait par sa r\u00e9ussite tardive dans l&rsquo;exportation, comme les commandes \u00e9gyptienne et indienne pourraient bien en \u00eatre l&rsquo;ouverture pressante, la d\u00e9monstration <em>a contrario<\/em> de la crise de l&rsquo;effondrement en cours du syst\u00e8me du technologisme, laquelle marquerait alors la fin, entre autres \u00e9v\u00e8nements du genre, de cette dynamique du d\u00e9veloppement de cette sorte d&rsquo;avions de combat comme production la plus avanc\u00e9e de ce syst\u00e8me du technologisme.<\/p>\n<\/p>\n<p><p>De ce point de vue crisique toujours, le <em>Rafale<\/em> est l&rsquo;illustration remarquable de la position compl\u00e8tement ambigu\u00eb de la France, position conserv\u00e9e malgr\u00e9 les directions politiques extr\u00eamement basses et compl\u00e8tement acquises au Syst\u00e8me qui se sont succ\u00e9d\u00e9es depuis pr\u00e8s de dix ans, et m\u00eame, en \u00e9tant plus rigoureux, depuis pr\u00e8s de trente ans (justement, dur\u00e9e de vie du <em>Rafale<\/em>). Cette situation ambigu\u00eb est celle d&rsquo;une France agit\u00e9e par des forces contradictoires qui, m\u00eame pour les plus vieilles comme sa destin\u00e9e historique \u00e0 vocation transcendantale telle qu&rsquo;on la voit si bien d\u00e9finie par Joseph de Maistre, sont et restent toutes tr\u00e8s actives. Il en r\u00e9sulte que, par rapport \u00e0 la situation n\u00e9e du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_cha_nement_de_la_mati_re__05_11_2012.html\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a> de 1776-1825, et dans le cadre de la constitution du Syst\u00e8me comme repr\u00e9sentation op\u00e9rationnelle de l&rsquo;\u00e9v\u00e9nement 1776-1825, la France est, pourrait-on dire, par rapport au Syst\u00e8me, \u00ab\u00a0un pied dedans-un pied dehors\u00a0\u00bb. Ainsi le <em>Rafale<\/em> est-il \u00e0 la fois l&rsquo;illustration de la puissance du Syst\u00e8me (dans sa composante syst\u00e8me du technologisme), \u00e0 la fois l&rsquo;acteur et l&rsquo;illustration de la puissance grandissante de la r\u00e9sistance antiSyst\u00e8me. (Ce dernier point de son identification ontologique, qui est pour nous le point dominant, est notamment explicit\u00e9 le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notre_raison_d_tre_21_07_2005.html\">21 juillet 2005<\/a>, dans une analyse o&ugrave; le <em>Rafale<\/em> est d\u00e9crit par nous comme un \u00ab\u00a0artefact antimoderne\u00a0\u00bb.)<\/p>\n<\/p>\n<p><p>Ce contexte du Syst\u00e8me ayant \u00e9t\u00e9 trac\u00e9, on comprend alors que nous envisagions notre propre description du destin du <em>Rafale<\/em> uniquement par rapport aux productions du bloc BAO, essentiellement anglo-saxonnes, essentiellement US. Les productions hors-bloc BAO, essentiellement russes, n&rsquo;ont jamais fait partie int\u00e9grante du Syst\u00e8me, et elles en font de moins en moins partie. (Comme la France, la Russie est \u00ab\u00a0un pied dedans-un pied dehors\u00a0\u00bb par rapport au Syst\u00e8me, mais un \u00ab\u00a0pied-dehors\u00a0\u00bb devenu beaucoup plus consid\u00e9rable, \u00e0 mesure que le \u00ab\u00a0pied-dedans\u00a0\u00bb de la France grossissait \u00e0 vue d&rsquo;&oelig;il ces derni\u00e8res ann\u00e9es. N\u00e9anmoins, ces divergences tactiques-anatomiques de volume du pied n&rsquo;entame nullement la p\u00e9rennit\u00e9 des positions ambig\u00fces par rapport au Syst\u00e8me, comme celle de la France que nous d\u00e9crivons ici.) Cela ne signifie pas que ces productions technologiques (fran\u00e7aises, russes) sont moins bonnes ou meilleures, &ndash; car l\u00e0 n&rsquo;est pas notre propos. Cela signifie que la production russe n&rsquo;entre pas comme acteur majeur dans le cours de la destin\u00e9e du syst\u00e8me du technologisme, m\u00eame si elle en use et y figure souvent \u00e0 son avantage ; or, ce qui nous int\u00e9resse d\u00e9cid\u00e9ment au travers de ces <em>Notes d&rsquo;Analyse<\/em>, c&rsquo;est bien la destin\u00e9e du syst\u00e8me du technologisme, au-del\u00e0 de celle du <em>Rafale<\/em> et incluant celle du <em>Rafale<\/em>.<\/p>\n<\/p>\n<p><p>Du point de vue historiquement s\u00e9quentiel, nous allons d\u00e9crire l&rsquo;historique du <em>Rafale<\/em>, et par cons\u00e9quent l&rsquo;illustration de cette situation ontologique si particuli\u00e8re, au travers de notre th\u00e8se des \u00ab\u00a0trois vies du <em>Rafale<\/em>\u00a0\u00bb (des \u00ab\u00a0vies\u00a0\u00bb par rapport \u00e0 la question hautement politique de l&rsquo;exportation, parce que la question de l&rsquo;exportation de ces syst\u00e8mes ne peut \u00eatre que politique). Cela n\u00e9cessite un historique de son destin, et une interpr\u00e9tation bien entendu de cet historique.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Premi\u00e8re vie du <em>Rafale<\/em>, ou les occasions g\u00e2ch\u00e9es<\/h3>\n<\/p>\n<p><p>La premi\u00e8re \u00ab\u00a0vie\u00a0\u00bb du <em>Rafale<\/em> commence en 1985-1986, avec des opportunit\u00e9 exceptionnelles pour l&rsquo;avion fran\u00e7ais, notamment de devenir un deuxi\u00e8me \u00ab\u00a0avion de combat europ\u00e9en\u00a0\u00bb \u00e0 c\u00f4t\u00e9 de l&rsquo;Eurofighter\/<em>Typhoon<\/em>, avec l&rsquo;avantage sur ce dernier d&rsquo;\u00eatre un avion qui vole tandis que l&rsquo;Eurofighter est un hybride qui peinera toujours \u00e0 se faire prendre pour un avion de combat s\u00e9rieux. Qui plus est, le <em>Rafale<\/em> a l&rsquo;occasion de d\u00e9buter cette carri\u00e8re europ\u00e9enne par un contrat de coop\u00e9ration avec la Belgique, impliquant une commande belge acquise, donc une premi\u00e8re commande export qui aurait pu \u00eatre effectivement concr\u00e9tis\u00e9e autour de 1988.<\/p>\n<\/p>\n<p><p>Tout cela s&rsquo;\u00e9croule en 1989, essentiellement \u00e0 cause des maladresses et incoh\u00e9rences fran\u00e7aises que nous situerions \u00e0 deux tiers de la part des gouvernements fran\u00e7ais impliqu\u00e9s, et \u00e0 un tiers de la part du constructeur. En quatre petites ann\u00e9es, la France a g\u00e2ch\u00e9 des chances sans pr\u00e9c\u00e9dent et qui ne se repr\u00e9senteront plus d&rsquo;accaparer \u00e0 partir des ann\u00e9es 1990 l&rsquo;essentiel du march\u00e9 europ\u00e9en des avions de combat post-F-16, y compris en d\u00e9bauchant l&rsquo;un ou l&rsquo;autre des participants \u00e0 l&rsquo;Eurofighter dans tous les cas pour une partie de leurs commandes. On mesurera l&rsquo;exceptionnalit\u00e9 de la situation en rappelant qu&rsquo;en 1985-1986 la Hollande elle-m\u00eame soutenait un tel projet jusqu&rsquo; en \u00eatre l&rsquo;initiatrice au sein du GEIP (Groupement europ\u00e9en Ind\u00e9pendant de Programmes) pr\u00e9sid\u00e9 par le secr\u00e9taire d&rsquo;&Eacute;tat hollandais \u00e0 la d\u00e9fense Ouwellingen, &ndash; et Dieu sait, et nous avec Lui, la puissance du tropisme pro-am\u00e9ricain des Hollandais.<\/p>\n<\/p>\n<p><p>Cette tranche de la premi\u00e8re \u00ab\u00a0vie\u00a0\u00bb du <em>Rafale<\/em> est largement document\u00e9e dans un texte du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_rafale_et_l_exportation_i_10_10_2009.html\">10 octobre 2009<\/a> et de deux autres, plus personnels puisque li\u00e9s \u00e0 l&rsquo;exp\u00e9rience personnelle de Philippe Grasset, les deux du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-journalisme_made_in_cia_iii_n_dia-phg_belgique_et_jsf-rafale_24_10_2014.html\">24 octobre 2014<\/a> et du m\u00eame <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-m_moires_du_dehors_dia-phg_bruxelles_1987-1988_24_10_2014.html\">24 octobre 2014<\/a>.<\/p>\n<\/p>\n<p><p>Les ann\u00e9es 1990 sont plus \u00ab\u00a0classiques\u00a0\u00bb. Elles montrent un affrontement \u00e0 l&rsquo;exportation entre le <em>Rafale<\/em> et les USA, chaque fois \u00e0 l&rsquo;avantage des USA qui imposent dans l&rsquo;apr\u00e8s-Guerre froide une influence politique \u00e9crasante. La bataille la plus embl\u00e9matique de cette d\u00e9cennie fut celle men\u00e9e aux &Eacute;mirats arabes Unis, en 1995-1997. Les USA l&#8217;emport\u00e8rent avec une version sp\u00e9ciale du F-16, reconnue d&rsquo;ailleurs de qualit\u00e9 exceptionnelle par les Fran\u00e7ais eux-m\u00eames, le F-16C Block 60. Mais le point d\u00e9terminant fut et resta le poids de la puissance militaro-politique des USA.<\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il en soit, le <em>Rafale<\/em> restait encore un concurrent respect\u00e9, un avion de combat qui avait ses chances \u00e0 l&rsquo;exportation.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Deuxi\u00e8me vie du <em>Rafale<\/em> (I) : du coma&#8230;<\/h3>\n<\/p>\n<p><p>Nous datons la deuxi\u00e8me \u00ab\u00a0vie\u00a0\u00bb du <em>Rafale<\/em>, qui est en fait, du point de vue de l&rsquo;exportation, un coma assez s\u00e9v\u00e8re suivi d&rsquo;une hibernation, du 11 septembre 2001. Cette date c\u00e9l\u00e8bre entre toutes \u00e9tablit une politique US d&rsquo;h\u00e9g\u00e9monie globale bas\u00e9e sur la brutalit\u00e9, la pression jusqu&rsquo;\u00e0 des actes ill\u00e9gaux et des menaces concr\u00e8tes jusqu&rsquo;\u00e0 l&rsquo;\u00e9limination (voir ce que Retchetnikov dit de la CIA, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_monde_selon_le_renseignement_russe_10_04_2015.html\">10 avril 2015<\/a>), l&rsquo;influence exerc\u00e9e encore plus par le poids des armes que par l&rsquo;habilet\u00e9 de la diplomatie. Dans un texte datant du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_jsf_post-9_11_20_12_2002.html\">20 d\u00e9cembre 2002<\/a>, extrait de notre Lettre d&rsquo;Information <em>Context<\/em>, nous d\u00e9finition cette strat\u00e9gie fondamentale du programme JSF qui entra dans sa phase de d\u00e9veloppement et de marketing coercitif sinon terroriste en 1999-2001&#8230;<\/p>\n<\/p>\n<p><p>&laquo;<em>9\/11 a tout chang\u00e9. L&rsquo;\u00e9v\u00e9nement a suscit\u00e9 une politisation radicale de tous les domaines aux USA. La question des armements y figure au premier rang, particuli\u00e8rement dans son aspect le plus avanc\u00e9 des technologies. C&rsquo;est encore plus le cas d&rsquo;un syst\u00e8me aux pr\u00e9tentions globales comme le JSF, qui repr\u00e9sente \u00e0 lui seul une strat\u00e9gie \u00e0 l&rsquo;exportation, voire la seule strat\u00e9gie \u00e0 l&rsquo;exportation possible (concevable) des &Eacute;tats-Unis. Il y a un JSF post-9\/11, qui diff\u00e8re fondamentalement du JSF d&rsquo;avant l&rsquo;attaque.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>La r\u00e9action \u00e0 9\/11 a \u00e9t\u00e9 double aux USA : r\u00e9affirmation agressive et panique profonde. Le JSF et la strat\u00e9gie \u00e0 l&rsquo;exportation qu&rsquo;il repr\u00e9sente constituent \u00e9videmment le relais quasiment automatique de la premi\u00e8re r\u00e9action, celle de la r\u00e9affirmation agressive. Le JSF est devenu une \u00ab\u00a0arme\u00a0\u00bb pour \u00e9tablir un nouvel ordre (am\u00e9ricain) que l&rsquo;attaque 9\/11 rend imp\u00e9ratif.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>L&rsquo;approche US est d\u00e9sormais unilat\u00e9raliste, globalisatrice, totalement int\u00e9gr\u00e9e. Il ne s&rsquo;agit ni d&rsquo;une strat\u00e9gie ni d&rsquo;un complot mais d&rsquo;une tendance extr\u00eame qui est une fatalit\u00e9. Plus que d&rsquo;une \u00ab\u00a0offensive am\u00e9ricaine\u00a0\u00bb \u00e0 l&rsquo;exportation, nous parlerons d&rsquo;une vision du monde qu&rsquo;il importe d&rsquo;imposer. Le JSF est l&rsquo;exemple le plus \u00e9labor\u00e9 d&rsquo;un point de vue structurel et philosophique de cette situation. &Eacute;lectris\u00e9s d&rsquo;une fa\u00e7on contrast\u00e9e mais additionn\u00e9e, \u00e0 la fois par la conviction intime de leur puissance (hubris) et par la perception des relations internationales comme des rapports de force, \u00e0 la fois par le sentiment de l&rsquo;urgence, voire de panique \u00e0 cause de la perception apocalyptique de 9\/11, les Am\u00e9ricains en viennent \u00e0 proposer, &mdash;mais le terme \u00ab\u00a0d\u00e9cider\u00a0\u00bb serait plus appropri\u00e9 &mdash; qu&rsquo;un syst\u00e8me global et totalement int\u00e9gr\u00e9 soit consid\u00e9r\u00e9 et appliqu\u00e9. Pour ce qui nous importe et ce que nous en connaissons, ce syst\u00e8me se nommerait : JSF. (Cons\u00e9quence : ne dites plus Made In USA, dites Made In JSF.)<\/em>&raquo;<\/p>\n<\/p>\n<p><p>On signalera une concr\u00e9tisation op\u00e9rationnelle de cette situation, dans le cas du march\u00e9 hollandais o&ugrave; le <em>Rafale<\/em> \u00e9tait concurrent mais fut balay\u00e9 alors qu&rsquo;il s&rsquo;\u00e9tait techniquement et \u00e9conomiquement situ\u00e9 tr\u00e8s pr\u00e8s du JSF, avec l&rsquo;avantage d&rsquo;exister et d&rsquo;\u00eatre tr\u00e8s proches des conditions op\u00e9rationnelles, au contraire du JSF-papier qui ressemblait \u00e0 une bande dessin\u00e9 type-<em>Comics<\/em>. (Selon les notations des Hollandais eux-m\u00eames : 6,97 contre 6,95, &ndash; voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_hollande_le_jsf_et_le_destin_de_l_europe_30_01_2002.html\">30 janvier 2002<\/a> et le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_hollande_choisit_le_jsf_l_actualite_d_un_echec_et_l_avenir_d_une_erreur_15_02_2002.html\">15 f\u00e9vrier 2002<\/a>.) L&rsquo;extrait ci-dessous d&rsquo;un texte du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_une_volution_h_g_monique_18_11_2009.html\">18 novembre 2009<\/a> met en \u00e9vidence la perspective historique du cas hollandais de 2002, dans un \u00e9tat d&rsquo;esprit bien diff\u00e9rent de celui de 1985, et les m\u00e9thodes d&rsquo;une exceptionnelle brutalit\u00e9. Le cas du JSF contre le <em>Rafale<\/em> fait partie de la grande saga des <em>Stay-Behind<\/em>, alias <em>Gladio<\/em>&#8230;<\/p>\n<\/p>\n<p><p>&laquo;<em>En un peu plus de quinze ans, cette situation nouvelle et r\u00e9volutionnaire s&rsquo;est \u00e9tablie dans l&rsquo;exportation des armements, sous l&rsquo;impulsion des USA et \u00e0 l&rsquo;image de leurs arguments id\u00e9ologiques. La situation commerciale habituelle de conqu\u00eate des march\u00e9s puis de leur d\u00e9fense comme positions acquises est effectivement devenue une situation strat\u00e9gique actant l&rsquo;h\u00e9g\u00e9monie militaire et politique sur ces march\u00e9s. Il ne suffit plus de parler d&rsquo;influence, de pressions, etc., m\u00eame si ces \u00e9l\u00e9ments sont de plus en plus pr\u00e9sents et actifs. Il est d\u00e9sormais question d&rsquo;une structure g\u00e9n\u00e9rale o&ugrave; les \u00ab\u00a0clients\u00a0\u00bb sont devenus des \u00ab\u00a0correspondants\u00a0\u00bb choisis par Washington pour \u00e0 la fois absorber le mat\u00e9riel US et tenir leur place dans une structure militaire globale contr\u00f4l\u00e9e par le Pentagone.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Cette situation est la cons\u00e9quence d&rsquo;une longue maturation. Les USA poss\u00e9daient, \u00e0 la fin de la Guerre froide, particuli\u00e8rement en Europe qui est le mod\u00e8le le plus convaincant et le plus achev\u00e9 de cette situation d&rsquo;h\u00e9g\u00e9monie, une formidable base d&rsquo;influence. Les diff\u00e9rents moyens et relais \u00ab\u00a0ouverts\u00a0\u00bb sont connus, situ\u00e9s \u00e0 la jonction de l&rsquo;action l\u00e9gale de lobbying et de l&rsquo;action d&rsquo;influence du renseignement. Mais il existe \u00e9galement des moyens tangentiels fondamentaux, dont on ignore en g\u00e9n\u00e9ral le poids. Il s&rsquo;agit essentiellement du tissu de relais d&rsquo;influence et d&rsquo;action \u00e9tabli \u00e0 partir de 1947-1948 sous la direction du MI6 (tr\u00e8s vite en perte d&rsquo;importance) et du renseignement US (CIA et DIA, SR des forces arm\u00e9es), et structurellement \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;OTAN, au travers des r\u00e9seaux Stay Behind (SB), plus connus sous le nom g\u00e9n\u00e9rique de leur branche italienne depuis les r\u00e9v\u00e9lations de 1990, de r\u00e9seau Gladio.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>L&rsquo;importance de l&rsquo;influence des SB sur la p\u00e9n\u00e9tration des ventes d&rsquo;armes US en Europe n&rsquo;a jamais \u00e9t\u00e9 explor\u00e9e parce qu&rsquo;elle est indirecte et exerc\u00e9e comme une cons\u00e9quence naturelle. Une des raisons du maintien en activit\u00e9 des SB apr\u00e8s 1990 est certainement leurs capacit\u00e9s d&rsquo;influence sur ce domaine, au travers des cadres europ\u00e9ens des SB (arm\u00e9e, renseignement, certains cadres industriels). La structure d&rsquo;influence US en Europe est une remarquable r\u00e9ussite pour l&rsquo;exportation des armements.<\/em> [&#8230;] <em>Le r\u00e9sultat de cette implantation fit des march\u00e9s europ\u00e9ens, \u00e0 l&rsquo;exception de la France, un territoire conquis qu&rsquo;il s&rsquo;agissait de g\u00e9rer. L&rsquo;exemple n\u00e9erlandais et le choix du JSF illustrent cette gestion.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>En 1998, une r\u00e9union secr\u00e8te entre des chefs militaires n\u00e9erlandais (sans mandat politique) et leurs correspondants industriels US avait abouti \u00e0 un accord pour le choix du JSF. En mars 2002, le gouvernement prit une d\u00e9cision dans ce sens, que le Parlement devait ratifier. Le 5 mai 2002, le leader populiste Pym Fortuyn, vainqueur probable aux \u00e9lections du 16 mai, rencontra une d\u00e9l\u00e9gation US conduite par l&rsquo;ambassadeur Clifford Sorel, o&ugrave; l&rsquo;on trouvait \u00e9galement des g\u00e9n\u00e9raux hollandais. Fortuyn leur signifia son refus de voter pour le programme JSF, ce qui impliquait une d\u00e9faite du programme au Parlement. Le lendemain, Fortuyn \u00e9tait assassin\u00e9 dans des conditions tr\u00e8s contest\u00e9es. Il fut remplac\u00e9 \u00e0 la t\u00eate des populistes par un inconnu, Mat Herben, dont il s&rsquo;av\u00e9ra qu&rsquo;il avait travaill\u00e9 pendant 22 ans pour les services d&rsquo;information de la d\u00e9fense, qui sont une antenne du SR militaire hollandais. Broos Schnez, de la direction du parti populiste, d\u00e9clara le 28 juin 2002, apr\u00e8s que son parti ait \u00e9t\u00e9 conduit par Herben \u00e0 voter pour le JSF: \u00ab\u00a0We were flabbergasted. The Netherlands needs to know what kind of person he is and he&rsquo;s not honest. He is an old ministry of defence official and perhaps his job was to infiltrate the operation to get the party to vote for the fighter, something which we were always against. I&rsquo;d advise him to go to a good lawyer and clear his name, but nothing is happening, and that&rsquo;s strange.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>L&rsquo;entr\u00e9e dans le programme JSF acquise, Herben donna sa d\u00e9mission de la direction du parti fond\u00e9 par Fortuyn et disparut. L&rsquo;affaire \u00e9tait close. Ce fut une remarquable op\u00e9ration r\u00e9alis\u00e9e dans le plus pur style SB, dont l&rsquo;implantation dans les SR hollandais (dont venait Herben) depuis la fin des ann\u00e9es 1940 est largement document\u00e9e. S&rsquo;il s&rsquo;agit de la manifestation la plus dramatique de l&rsquo;activit\u00e9 de ce r\u00e9seau europ\u00e9en\/OTAN d&rsquo;influence US, elle n&rsquo;en est pas moins exemplaire. On retrouve cette sorte de sch\u00e9ma dans nombre de pays europ\u00e9ens. Son efficacit\u00e9 ne s&rsquo;est jamais d\u00e9mentie.<\/em>&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Deuxi\u00e8me vie du <em>Rafale<\/em> (II) : &#8230; \u00e0 l&rsquo;hibernation<\/h3>\n<\/p>\n<p><p>&#8230; Il y a donc \u00e0 partir de (9\/11) et ensuite cette longue, tr\u00e8s longue p\u00e9riode, du coma \u00e0 l&rsquo;hibernation, o&ugrave; les plans d&rsquo;investissement du monde par le JSF furent mis \u00e0 ex\u00e9cution aux niveaux du marketing et de la gestion d&rsquo;influence, mettant KO tous ceux qui auraient pr\u00e9tendu \u00e0 concurrencer, et cette p\u00e9riode venant jusqu&rsquo;\u00e0 nous \u00e0 peu pr\u00e8s. (Le verrouillage eut lieu notamment \u00e0 partir de 2002, lorsque les huit pays \u00ab\u00a0choisis\u00a0\u00bb pour figurer la base d&rsquo;investissement du monde par le JSF commenc\u00e8rent \u00e0 entrer dans le programme par le biais de divers \u00ab\u00a0contrats\u00a0\u00bb d'\u00a0\u00bbobservateur\u00a0\u00bb, de participants par l&rsquo;achat de l&rsquo;un ou l&rsquo;autre \u00ab\u00a0prototype\u00a0\u00bb de pr\u00e9s\u00e9rie, etc.)<\/p>\n<\/p>\n<p><p>Certes, des march\u00e9s, des \u00ab\u00a0comp\u00e9titions\u00a0\u00bb eurent lieu pendant cette p\u00e9riode qui dura jusqu&rsquo;en 2011-2012 (voir plus loin), o&ugrave; le <em>Rafale<\/em> figura, o&ugrave; il fut m\u00eame donn\u00e9 favori &ndash; pour perdre \u00e0 chaque fois, &ndash; quelques coups d&rsquo;\u00e9p\u00e9e dans l&rsquo;eau&#8230; Bien entendu, la politique joua son r\u00f4le dans ces \u00e9checs, mais la politique invertie dirait-on, c&rsquo;est-\u00e0-dire l&rsquo;extraordinaire m\u00e9diocrit\u00e9 de la direction fran\u00e7aise depuis le dernier sursaut du discours de Villepin \u00e0 l&rsquo;ONU et de l&rsquo;opposition franco-allemande (plus la Belgique en bandouill\u00e8re) \u00e0 la guerre contre l&rsquo;Irak de 2003. (Mais m\u00eame ce sursaut ne r\u00e9pondait pas \u00e0 une strat\u00e9gie coh\u00e9rente, dirig\u00e9e contre la politique-Syst\u00e8me d\u00e9structurante des USA ; plut\u00f4t un sursaut inconscient quoique ne manquant pas de panache de la singularit\u00e9 fran\u00e7aise, un reste de gaullisme qui tra&icirc;nait dans les soupentes du Quai d&rsquo;Orsay.) Cette inversion du pouvoir fran\u00e7ais avec son alignement sur les USA, avec les singularit\u00e9s des divers pr\u00e9sidents, fut la cause souterraine de tous ces \u00e9checs, tous les interlocuteurs (acheteurs potentiels) ne sentant plus rien de la coh\u00e9rence et de la puissance souveraine du gaullisme. Le march\u00e9 br\u00e9silien, par exemple, fut exemplaire : la commande de <em>Rafale<\/em> que voulait le pr\u00e9sident Lula fut pulv\u00e9ris\u00e9e par l&rsquo;absurde politique extr\u00e9miste anti-iranienne de Sarkozy, qui participa au sabotage d&rsquo;une initiative turco-br\u00e9silienne aupr\u00e8s de l&rsquo;Iran et d\u00e9cida Lula \u00e0 abandonner ce projet (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-comment_la_france_le_rafale_a_perdu_le_br_sil_24_05_2011.html\">24 mai 2011<\/a>).<\/p>\n<\/p>\n<p><p>Pendant cette p\u00e9riode o&ugrave; l&rsquo;ombre du JSF semblait paralyser \u00ab\u00a0le march\u00e9\u00a0\u00bb, l&rsquo;activit\u00e9 de l&rsquo;exportation \u00e0 partir du bloc BAO se r\u00e9sumait aux habituelles man&oelig;uvres corruptrices des Britanniques (les march\u00e9s saoudiens), au suivi des \u00e9quipements US (F-15, F-16, F-18) impos\u00e9s par les USA aux divers vassaux, \u00e0 l&rsquo;intrusion \u00e9pisodique de l&rsquo;<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_aventure_br_silienne_du_gripen_21_12_2013.html\">outsider<\/a> de convenance contr\u00f4l\u00e9 par les Anglo-Saxons (le <em>Gripen<\/em> pseudo-su\u00e9dois). Le <em>Rafale<\/em>, jugeait-on avec bien des arguments, \u00e9tait d\u00e9sormais fig\u00e9 dans les glaces de l&rsquo;hibernation impos\u00e9e par le JSF, dont l&rsquo;\u00e9closion triomphale n&rsquo;allait pas tarder \u00e0 faire na&icirc;tre le monde nouveau de l&rsquo;aviation de combat : le \u00ab\u00a0si\u00e8cle du JSF\u00a0\u00bb, le XXI\u00e8me. Mais ce qui se passa alors fut si inattendu pour les esprits habitu\u00e9s \u00e0 la quasi-divinit\u00e9 US&#8230; Ce qui aurait du \u00eatre l&rsquo;installation d&rsquo;une sorte d&#8217;emprisonnement <em>ad vitam aeternam<\/em> sous la garde du ge\u00f4lier USA-JSF bascula compl\u00e8tement.<\/p>\n<\/p>\n<p><p>Cette p\u00e9riode de coma-hibernation pour le <em>Rafale<\/em> et de triomphe pour le JSF fut en r\u00e9alit\u00e9 marqu\u00e9 par un ph\u00e9nom\u00e8ne incroyable, extraordinaire, stup\u00e9fiant, &ndash; tous ces qualificatifs pour ceux qui croyaient \u00e0 l&rsquo;\u00e9ternelle omnipotence de la puissance US comme on croit \u00e0 la virginit\u00e9 de Marie ; et ce ph\u00e9nom\u00e8ne \u00e9tant la dissolution progressive (ne parlons pas de d\u00e9structuration, ce programme n&rsquo;ayant jamais eu la moindre structure) du programme JSF tout au long de la premi\u00e8re d\u00e9cennie du si\u00e8cle. C&rsquo;est autour de 2010-2011 (voir par exemple le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_jsf_et_l_effet_fratricide__04_10_2010.html\">4 octobre 2010<\/a>, le , le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_jsf_et_la_chute_15_12_2011.html\">15 d\u00e9cembre 2011<\/a>, etc.) que les observateurs courants des affaires a\u00e9rospatiales commenc\u00e8rent \u00e0 se douter qu&rsquo;il s&rsquo;\u00e9tait pass\u00e9 quelque chose de formidable durant la premi\u00e8re d\u00e9cennie du si\u00e8cle, et qu&rsquo;il devint possible de concevoir que non seulement le JSF \u00e9tait une usine \u00e0 gaz d&rsquo;une dimension qu&rsquo;on n&rsquo;avait jamais connue, mais encore une usine \u00e0 gaz postmoderne, qui pourrait tr\u00e8s bien ne jamais parvenir \u00e0 exister, son existence limit\u00e9 \u00e0 quelques \u00ab\u00a0tchouc-tchouc\u00a0\u00bb de vol avec visibilit\u00e9 parfaite, sous surveillance m\u00e9dicale et avec infusion permanente de cortisone pour \u00e9viter l&rsquo;infection fatale. A partir de l\u00e0, d\u00e9lais, surco&ucirc;t, r\u00e9gressions m\u00eame ne cess\u00e8rent d&rsquo;\u00eatre mis \u00e0 jour, de s&rsquo;accumuler, jusqu&rsquo;\u00e0 former une sorte d&rsquo;immense d\u00e9sordre ou de trou noir c&rsquo;est selon ; le syst\u00e8me de la communication lui-m\u00eame bascula et le JSF, jusqu&rsquo;alors divinit\u00e9 magique, devint la ris\u00e9e des \u00e9ditorialistes avec le b\u00e9n\u00e9fice douteux d&rsquo;une publicit\u00e9 d\u00e9vastatrice ; on \u00e9tait pass\u00e9 du <em>JSF-loving<\/em> au <em>JSF-bashing<\/em>&#8230;<\/p>\n<\/p>\n<p><p>Ainsi attendions-nous Godot-JSF lorsque nous commen\u00e7\u00e2mes \u00e0 distinguer qu&rsquo;il s&rsquo;agissait du JSF-<em>Titanic<\/em>, \u00e0 l&rsquo;image de son concepteur triomphant, les &Eacute;tats-Unis d&rsquo;Am\u00e9rique ; effondrement par l&rsquo;int\u00e9rieur, rong\u00e9 par les <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_les_termites__10_04_2013.html\">termites<\/a>, d&rsquo;un programme gigantesque prisonnier d&rsquo;un technologisme qui entamait sa propre course vers l&rsquo;effondrement. On conna&icirc;t les derni\u00e8res p\u00e9rip\u00e9ties de la chose puisque d\u00e9sormais le roi est tellement nu qu&rsquo;on arrive \u00e0 distinguer son anatomie de Frankenstein d\u00e9g\u00e9n\u00e9r\u00e9 promis \u00e0 l&rsquo;auto-dissolution dans son trou noir. (Voir par exemple le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-eurofighter_f-22_jsf_l_effondrement_de_l_avion_de_combat_02_10_2014.html\">2 octobre 2014<\/a>, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-finalement_si_l_on_zapait_le_jsf__06_02_2015.html\">6 f\u00e9vrier 2015<\/a>, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-de_la_folie-jsf_au_d_part_de_wheeler_13_03_2015.html\">13 mars 2015<\/a>.)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Nous y voici : la \u00ab\u00a0troisi\u00e8me vie\u00a0\u00bb du <em>Rafale<\/em><\/h3>\n<\/p>\n<p><p>Ainsi abordons-nous la \u00ab\u00a0troisi\u00e8me vie\u00a0\u00bb du <em>Rafale<\/em>, qui serait plus \u00ab\u00a0trente apr\u00e8s\u00a0\u00bb que le <em>Vingt ans apr\u00e8s<\/em> de notre cher Alexandre Dumas. Depuis la d\u00e9couverte du pot-aux-roses (2011-2012), les avatars se sont multipli\u00e9s. Nous avons parl\u00e9 de ceux du JSF, mais il faut parler aussi et surtout de ceux des USA, &ndash; car, comme nous l&rsquo;avons si souvent dit, le JSF est une repr\u00e9sentation monstrueuse et symbolique \u00e0 la fois, dans la dynamique du technologisme qui s&rsquo;effondre, du destin des USA, c&rsquo;est-\u00e0-dire du destin du Syst\u00e8me. Les crises syrienne et surtout ukrainienne, avec l&rsquo;incoh\u00e9rente politique de force devenant une caricature de l&rsquo;<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_l_id_al_de_puissance_09_04_2014.html\">id\u00e9al de puissance<\/a>, sont un signe puissant de ce destin dont on commence \u00e0 s&rsquo;aviser tr\u00e8s pr\u00e9cis\u00e9ment. Le d\u00e9sordre monstrueux de la paralysie et de l&rsquo;impuissance du pouvoir washingtonien qui n&rsquo;est plus \u00ab\u00a0\u00e0 prendre\u00a0\u00bb mais qui est dissous en une multitude de \u00ab\u00a0centres\u00a0\u00bb tentant d&rsquo;annexer l&rsquo;un ou l&rsquo;autre de ses restes soumet les psychologies notamment des dirigeants non-US \u00e0 une terrible tension et p\u00e9n\u00e8tre peu \u00e0 peu les esprits soi-disant \u00ab\u00a0globalis\u00e9s\u00a0\u00bb au b\u00e9n\u00e9fice des USA (du Syst\u00e8me) du caract\u00e8re catastrophique et in\u00e9luctable du destin de l&rsquo;am\u00e9ricanisme. Cette perception presque m\u00e9tahistorique inonde et impr\u00e8gne tous les jugements aux diff\u00e9rents niveaux de la sp\u00e9culation, dans les diff\u00e9rents domaines de la situation g\u00e9n\u00e9rale. Celui de l&rsquo;armement, et l\u00e0-dedans celui du domaine ma&icirc;tre parce que porteur de souverainet\u00e9 de l&rsquo;avion de combat (1), ne sont pas \u00e9pargn\u00e9s, au contraire, surtout lorsqu&rsquo;on dispose d&rsquo;un guide et d&rsquo;un r\u00e9v\u00e9lateur tels que le JSF qui paye si g\u00e9n\u00e9reusement de sa personne.<\/p>\n<\/p>\n<p><p>C&rsquo;est de cette \u00e9volution psychologique puis intellectuelle que nous voulons parler pour avancer l&rsquo;explication essentielle de ce que nous nommons la \u00ab\u00a0troisi\u00e8me vie\u00a0\u00bb du <em>Rafale<\/em>, &ndash; celle qui pourrait \u00eatre per\u00e7ue comme \u00ab\u00a0la belle vie\u00a0\u00bb de l&rsquo;avion de combat fran\u00e7ais, et cela bien qu&rsquo;elle soit \u00e9galement l&rsquo;illustration d&rsquo;une \u00e9poque de plus en plus, voire absolument cr\u00e9pusculaire. Durant ces 3-4 derni\u00e8res ann\u00e9es, apr\u00e8s qu&rsquo;il f&ucirc;t apparu \u00e9vident qu&rsquo;Obama ne changerait rien \u00e0 la <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\">politique-Syst\u00e8me<\/a> et que la crise de l&rsquo;automne 2008 ne changerait rien au fonctionnement du Syst\u00e8me, est n\u00e9 et s&rsquo;est d\u00e9velopp\u00e9 un sentiment nouveau d&rsquo;antiam\u00e9ricanisme, \u00e0 c\u00f4t\u00e9 de l&rsquo;antiam\u00e9ricanisme classique, id\u00e9ologique sinon \u00ab\u00a0civilisationnel\u00a0\u00bb. On pourrait nommer cela de l'\u00a0\u00bbantiam\u00e9ricanisme catastrophiste\u00a0\u00bb, c&rsquo;est-\u00e0-dire la perception que les USA sont moins en d\u00e9clin classique que dans une course d\u00e9cliniste se caract\u00e9risant par une sorte de d\u00e9mence, de fureur de d\u00e9truire, voire une tendance suicidaire (voir \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_tout_pour_le_pire_1998_2008_17_12_2014.html\">Lincoln-1838<\/a>\u00ab\u00a0).<\/p>\n<\/p>\n<p><p>Nous ne disons pas que cela est r\u00e9alis\u00e9 consciemment, nous faisons l&rsquo;hypoth\u00e8se que cela existe de plus en plus fortement dans les psychologies, inconsciemment, avec suffisamment de force pour influencer les esprits de fa\u00e7on radicale. Sans nul doute, la crise ukrainienne, avec le comportement incroyable des repr\u00e9sentants d&rsquo;occasion du pouvoir US (Nuland &#038; Cie), l&#8217;emprisonnement de la <em>narrative<\/em> (le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_terminisme-narrativiste_26_02_2015.html\">d\u00e9terminisme-narrativiste<\/a>), les risques ainsi sollicit\u00e9s d&rsquo;affrontement avec la Russie, puissance nucl\u00e9aire strat\u00e9gique, tout cela a jou\u00e9 un r\u00f4le capital durant ces quatorze derniers mois, notamment aupr\u00e8s de dirigeants qui ne d\u00e9pendent pas pour leur survie (\u00e9ventuellement leur survie physique) d&rsquo;un alignement sur la folie USA. D&rsquo;o&ugrave; leur recherche de plus en plus pressante, dans une agitation g\u00e9n\u00e9rale o&ugrave; les bruits de possibles conflits de grande envergure, voire de guerres g\u00e9n\u00e9ralis\u00e9es sinon mondiales, ne manquent pas, de sources alternatives d&rsquo;armements qui ne les coupent pas compl\u00e8tement du bloc BAO tout en prenant nettement leurs distances de la \u00ab\u00a0philosophie\u00a0\u00bb de la d\u00e9mence anglo-saxonne (on peut mettre UK dans le m\u00eame sac). Notre hypoth\u00e8se est bien que la d\u00e9cision de Modi, comme celle de Sisi, sont de cet ordre&#8230; (Avec, dans le second cas, la volont\u00e9 de briser le poids presque surhumain de la bureaucratie indienne en train de n\u00e9gocier l&rsquo;achat des 126 <em>Rafale<\/em> initiaux et d\u00e9cider une commande de 36 avec livraison acc\u00e9l\u00e9r\u00e9e qui est d&rsquo;abord un acte politique.)<\/p>\n<\/p>\n<p><p>Cela n&#8217;emp\u00eache pas ces deux pays (&Eacute;gypte et Inde) d&rsquo;acheter du mat\u00e9riel russe (surtout l&rsquo;Inde d&rsquo;une fa\u00e7on r\u00e9guli\u00e8re, bient\u00f4t l&rsquo;&Eacute;gypte \u00e0 nouveau en piste). Mais un engagement exclusif avec les seuls Russes, outre les objections op\u00e9rationnelles et industrielles de la source unique, serait consid\u00e9r\u00e9 comme trop \u00ab\u00a0marqu\u00e9\u00a0\u00bb du point de vue de l&rsquo;orientation politique et risquerait de nourrir la perception qu&rsquo;on passe d&rsquo;un ma&icirc;tre \u00e0 un autre. Les deux pays se sont donc tourn\u00e9s vers la France, comme ils ont d\u00e9j\u00e0 fait \u00e0 d&rsquo;autres reprises, et cette fois encore avec l&rsquo;avantage de disposer d&rsquo;un syst\u00e8me qui est certainement aujourd&rsquo;hui le meilleur avion de combat polyvalent du monde. (Et sans doute le dernier aussi achev\u00e9, si l &lsquo;on en juge par la courbe catastrophique du syst\u00e8me du technologisme d\u00e9vor\u00e9 par ses propres exc\u00e8s comme le JSF nous en fait gracieusement la d\u00e9monstration, &ndash; mais ceci est certainement un autre d\u00e9bat.)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Les manipulateurs de la \u00ab\u00a0troisi\u00e8me vie\u00a0\u00bb : le gaullisme malgr\u00e9 tout<\/h3>\n<\/p>\n<p><p>&#8230; C&rsquo;est en somme une bien \u00e9trange aventure. \u00ab\u00a0Les autres\u00a0\u00bb sont venus solliciter la France avec \u00e0 l&rsquo;esprit ou dans leur part de m\u00e9moire collective le r\u00f4le que la France gaulliste, bien mieux pr\u00e9par\u00e9e qu&rsquo;on ne croit par la IV\u00e8me r\u00e9publique, reconquit magnifiquement dans les ann\u00e9es 1960 ; le r\u00f4le d&rsquo;une diff\u00e9rence fondamentale et souveraine, d&rsquo;une sp\u00e9cificit\u00e9 ancr\u00e9e dans des si\u00e8cles d&rsquo;histoire qui emp\u00eache ce pays d&rsquo;\u00eatre compl\u00e8tement soumis au Syst\u00e8me et aux USA, malgr\u00e9 le travail de trahison et de m\u00e9diocrit\u00e9 inlassable de ses \u00e9lites qui est devenu au fil des d\u00e9cennies sinon d&rsquo;un ou deux si\u00e8cles leur fa\u00e7on \u00e0 elles de sacrifier au principe de la Tradition qu&rsquo;elles d\u00e9testent tant. En quelque sorte, ces pays obligent la France \u00e0 tenir le r\u00f4le qui lui est impos\u00e9 par l&rsquo;histoire (&laquo;<em>La France exerce sur l&rsquo;Europe une v\u00e9ritable magistrature, qu&rsquo;il serait inutile de contester&#8230;<\/em>&raquo; \u00e9crit notre ami, le comte Joseph [de Maistre]) ; aujourd&rsquo;hui, n\u00e9cessit\u00e9 d&rsquo;\u00e9poque, ce r\u00f4le impos\u00e9 d&rsquo;une \u00ab\u00a0v\u00e9ritable magistrature\u00a0\u00bb exerc\u00e9e sur le principe de souverainet\u00e9 qui est op\u00e9rationnalis\u00e9 dans ce domaine g\u00e9n\u00e9ral de l&rsquo;armement de haute technologie par le domaine supr\u00eame de l&rsquo;avion de combat ; et ce r\u00f4le-l\u00e0 tenu par la pression des circonstances et d&rsquo;autres nations, malgr\u00e9 une direction politique absolument catastrophique d&rsquo;inculture et de bassesse, et totalement ignorante de ce qu&rsquo;est la souverainet\u00e9. Bref, la France se passe de pr\u00e9sident puisqu&rsquo;elle a un Sisi ou un Modi pour la rappeler \u00e0 sa mission.<\/p>\n<\/p>\n<p><p>Ainsi, \u00e0 notre sens, faut-il voir ses commandes qu&rsquo;on d\u00e9crirait selon le go&ucirc;t des jeux de mots facile de l&rsquo;\u00e9poque comme \u00ab\u00a0en rafale\u00a0\u00bb, mais plut\u00f4t rafale d&rsquo;un vent nouveau et diff\u00e9rent ; ces commandes qui pourraient bien \u00eatre suivies d&rsquo;autres du m\u00eame type, et qui ram\u00e8neront pour les USA et le porteur d&rsquo;eau UK la France \u00e0 sa fonction normale de faux-\u00ab\u00a0alli\u00e9\u00a0\u00bb et tra&icirc;tre \u00e0 visage d\u00e9couvert qu&rsquo;on hait bien plus que l&rsquo;Ennemi du jour, avec une constance et une rage comme sont coutumiers les Anglo-Saxons. Comme, en plus, les services de renseignement fran\u00e7ais se permettent d&rsquo;avoir <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-en_passant_le_renseignement_fran_ais_et_l_ukraine_11_04_2015.html\">leur avis<\/a> sur l&rsquo;invasion sans fin de l&rsquo;Ukraine par la Russie&#8230; Les salons parisiens, quand ils s&rsquo;en apercevront, vont pouvoir \u00e0 nouveau g\u00e9mir sur le <em>French-bashing<\/em> qui les attriste tant, eux qui cultivent tant l&rsquo;affection outre-atlantique.<\/p>\n<\/p>\n<p><h4>Note<\/h4>\n<\/p>\n<p><p>1) Sur la question des rapports du principe fondamental de la souverainet\u00e9 et de l&rsquo;armement de haute technologie (hors nucl\u00e9aires, certes, qui doit \u00eatre consid\u00e9r\u00e9 \u00e0 part et hors de ce d\u00e9bat), et pr\u00e9cis\u00e9ment <strong>sinon exclusivement<\/strong> de l&rsquo;avion de combat, voir divers textes sur ce site : le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-les_technologies_de_souverainete_usage_et_utilite_en_temps_de_crise_par_philippe_grasset_29_04_2004.html\">29 avril 2004<\/a>, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-technologies_de_souverainet__27_05_2004.html\">27 mai 2004<\/a>, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-une_mission_par_tous_les_temps_10_12_2007.html\">10 d\u00e9cembre 2007<\/a><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur les trois vies de l&rsquo;avion Rafale 13 avril 2015 &ndash; En un tout petit moins de deux mois, l&rsquo;avion fran\u00e7ais Rafale de Dassault a enregistr\u00e9 deux commandes \u00e0 l&rsquo;exportation (24 de l&rsquo;&Eacute;gypte le 12 f\u00e9vrier, 36 de l&rsquo;Inde le 10 avril), qui pr\u00e9sentent plusieurs caract\u00e9ristiques les rendant extr\u00eamement singuli\u00e8res et formant un \u00e9v\u00e9nement&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[3066,4645,4646,3734,3303,3735,2631,9550,4413,3203,3090,250,14492,16560,3219,16561,2746,16562],"class_list":["post-75857","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-americaniste","tag-antimoderne","tag-antisysteme","tag-avions","tag-belgique","tag-combat","tag-de","tag-egypte","tag-gladio","tag-hollande","tag-influence","tag-jsf","tag-modi","tag-onde","tag-rafale","tag-sii","tag-souverainete","tag-stay-behind"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75857"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75857\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}