{"id":75886,"date":"2015-05-02T17:43:58","date_gmt":"2015-05-02T17:43:58","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/05\/02\/la-chanceliere-est-elle-une-bonne-rente-pour-la-cia\/"},"modified":"2015-05-02T17:43:58","modified_gmt":"2015-05-02T17:43:58","slug":"la-chanceliere-est-elle-une-bonne-rente-pour-la-cia","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/05\/02\/la-chanceliere-est-elle-une-bonne-rente-pour-la-cia\/","title":{"rendered":"La chanceli\u00e8re est-elle une bonne \u201crente\u201d pour la CIA ?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La chanceli\u00e8re est-elle une bonne \u00ab\u00a0rente\u00a0\u00bb pour la CIA ?<\/h2>\n<\/p>\n<p><p>&laquo;<em>Is Merkel a CIA Asset?<\/em>&raquo;, interroge Finian Cunnigham (sur <em>Sputnik.News<\/em>, le <a class=\"gen\" href=\"http:\/\/sputniknews.com\/columnists\/20150430\/1021571145.html#ixzz3Yyyb9xcG\">30 avril 2015<\/a>). Effectivement, &ndash; au terme d'\u00a0\u00bbagent\u00a0\u00bb (de la CIA), nous pr\u00e9f\u00e9rons le terme <em>asset<\/em> qui veut aussi bien dire un \u00ab\u00a0actif\u00a0\u00bb, une \u00ab\u00a0valeur boursi\u00e8re\u00a0\u00bb, un \u00ab\u00a0bien\u00a0\u00bb (immobilier), un \u00ab\u00a0bien-meuble\u00a0\u00bb, <strong>une \u00ab\u00a0rente\u00a0\u00bb peut-\u00eatre m\u00eame, \u00e0 l&rsquo;excellent rapport<\/strong> ; c&rsquo;est-\u00e0-dire quelque chose qui vous rapporte \u00e0 condition d&rsquo;\u00eatre plac\u00e9e dans certaines situations, et dont la valeur, du point de vue du sens de la chose qui est la dynamique productrice d&rsquo;argent, devient \u00e0 peu pr\u00e8s nulle lorsqu&rsquo;elle n&rsquo;est plus dans ces \u00ab\u00a0certaines situations\u00a0\u00bb. (Un \u00ab\u00a0agent\u00a0\u00bb, par contre, est en soi producteur d&rsquo;avantages, &ndash; des informations en l&rsquo;occurrence, &ndash; pour son contractant ; un \u00ab\u00a0agent\u00a0\u00bb agit si l&rsquo;on ose dire, il provoque ces \u00ab\u00a0certaines situations\u00a0\u00bb o&ugrave; il trouve des valeurs int\u00e9ressantes, il est producteur actif et souvent quasi-autonome, et l'\u00a0\u00bbagent\u00a0\u00bb peut lui-m\u00eame manipuler les <em>assets<\/em> de l&rsquo;agence pour laquelle il travaille. Mais un \u00ab\u00a0agent\u00a0\u00bb pour un chef d&rsquo;Etat ou de gouvernement, c&rsquo;est un peu trop risqu\u00e9.)<\/p>\n<\/p>\n<p><p>&#8230; Quoi qu&rsquo;il en soit, la question se pose toujours et elle se pose de plus en plus, et ainsi m\u00e9ritant bien qu&rsquo;on fasse le point sur la r\u00e9ponse \u00e0 donner, et ici sur la r\u00e9ponse que sugg\u00e8re le commentateur. Cunningham d\u00e9veloppe son argument, essentiellement \u00e0 partir des r\u00e9centes r\u00e9v\u00e9lations d&rsquo;il y a une d\u00e9cade selon lesquelles le BND allemand travaille de fa\u00e7on directe pour la NSA (et sans le moindre doute pour la CIA, \u00e9ventuellement pour le MI6, dans les m\u00eames conditions de compl\u00e8te all\u00e9geance), en espionnant pour le compte de ces mentors anglo-saxons les propres entreprises strat\u00e9giques allemandes ou \u00e0 int\u00e9r\u00eats allemands importants. Merkel \u00e9tait au courant et n&rsquo;a rien trouv\u00e9 \u00e0 redire. L&rsquo;affaire n&rsquo;a pas fait grand&rsquo;bruit hors d&rsquo;Allemagne, o&ugrave; elle a eu son tintamarre, &ndash; parce que ces affaires ne font d\u00e9sormais plus grand&rsquo;bruit, tant l&rsquo;habitude de la corruption mise au jour est grande, et tant les soup\u00e7ons \u00e0 l&rsquo;encontre de Merkel ne sont ni surprenants, ni nouveaux (voir notamment le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_cas_significatif_de_la_chanceli_re_merkel_01_12_2014.html\">1er d\u00e9cembre 2014<\/a>).<\/p>\n<\/p>\n<p><p>La crise ukrainienne \u00e9tait largement pr\u00e9par\u00e9e de ce point de vue des relations USA-Allemagne avec la crise pr\u00e9c\u00e9dente Snowden\/NSA ; avec le cas personnel de la chanceli\u00e8re, par les divers rebondissements de l&rsquo;automne 2013 autour des \u00ab\u00a0\u00e9coutes\u00a0\u00bb extr\u00eamement directes et intrusives de la NSA sur le t\u00e9l\u00e9phone portable personnel sinon intime de <em>Frau<\/em> Merkel, en plus de son action (celle de la NSA) en Allemagne. Il est certain qu&rsquo;on a cru distinguer une crise fondamentale entre l&rsquo;Allemagne et les USA notamment, \u00e0 cette occasion (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-allemagne-usa_le_grand_schisme_12_12_2013.html\">12 d\u00e9cembre 2013<\/a>), tout de m\u00eame temp\u00e9r\u00e9es par certaines doutes concernant cette m\u00eame Allemagne qu&rsquo;elle puisse bien tenir son rang et tenir t\u00eate (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_nsa_de_merkel_timochenko_et_une_question_allemande__01_04_2014.html\">1er avril 2014<\/a>). Les doutes n&rsquo;\u00e9taient pas de trop.<\/p>\n<\/p>\n<p><p>Finalement, dans tous les cas \u00e0 ce jour, il appara&icirc;t clairement que les \u00ab\u00a0promesses\u00a0\u00bb de fermet\u00e9 de l&rsquo;Allemagne \u00e0 l&rsquo;encontre des USA se sont dilu\u00e9es dans une incertitude remarquable concernant la politique allemande, et particuli\u00e8rement la position de Merkel, dans la crise ukrainienne et par rapport aux relations avec la Russie. On comprend donc ais\u00e9ment qu&rsquo;on puisse faire du cas-Merkel l&rsquo;occasion d&rsquo;un commentaire complet, \u00e0 la lumi\u00e8re du dernier scandale en date qu&rsquo;on a mentionn\u00e9 (les \u00e9coutes du BND pour le compte de la NSA), d&rsquo;ailleurs marqu\u00e9 par une plainte officielle de EADS d\u00e9pos\u00e9e devant la justice allemande.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>The claims that Merkel&rsquo;s government knew about German state intelligence spying on behalf of the Americans against the country&rsquo;s own industrial interests raise disturbing questions about the integrity of German government leaders. The apparent betrayal of German national interests by Chancellor Angela Merkel is not only evident over the recent industrial spying scandal on behalf of America. The slavish pursuit by Merkel of Washington&rsquo;s anti-Russian policy over Ukraine &mdash; in contradistinction to her country&rsquo;s national interests &mdash; also cogently suggests that the chancellor is serving a foreign master.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Recent reports that German state intelligence was spying on behalf of the Americans against the country&rsquo;s own industrial interests are bad enough. But then added to that are claims that the government of Chancellor Angela Merkel knew about the espionage &mdash; and turned a blind eye. This raises disturbing questions about the integrity of German government leaders, and primarily Angela Merkel. Is Merkel an asset for American intelligence, serving the geopolitical interests of Washington rather than the good of her own nation, or the wider good of Europe?<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>The news story in question refers to reports in the German media last week of how Germany&rsquo;s Federal Intelligence (BND) collaborated with the US National Security Agency (NSA) in spying on multinational European defence companies, including EADS and Eurocopter. The specific eavesdropping on these firms &mdash; in which Germany has major national economic interests &mdash; reportedly dates back to 2008. It is inconceivable that the highest levels of German government, including Chancellor Merkel &mdash; did not know about the industrial espionage. Yet Merkel appears to have countenanced the illegal activity, even though such activity would have vitiated German national interests, affording advantage to American competitors&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cunningham examine la position des services de renseignement vis-\u00e0-vis de leurs confr\u00e8res anglo-saxons, essentiellement des USA, et leur compl\u00e8te soumission \u00e0 ces derniers, d&rsquo;ailleurs plus ou moins formalis\u00e9es par des trait\u00e9s secrets. Cunningham rappelle ensuite la p\u00e9n\u00e9tration massive de la CIA dans le monde m\u00e9diatique allemand, et les r\u00e9v\u00e9lations de l&rsquo;ann\u00e9e derni\u00e8re, du journaliste Ulfkotte, sur les pratiques extravagantes de la CIA \u00e0 cet \u00e9gard (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_journalisme_made_in_cia_aujourd_hui_et_hier_20_10_2014.html\">20 octobre 2014<\/a> et le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-et_si_la_cia_achetait_les_lecteurs_de_la_presse_allemande__07_11_2014.html\">20 novembre 2014<\/a>). Il termine par les remarques qu&rsquo;on se fait \u00e9videmment sur les pressions intensives que la crise ukrainienne a d&ucirc; activer, de Washington sur Berlin, pour un alignement sans r\u00e9serve &#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>There is no reason to believe that the same domineering relation does not hold between US secret government and other European counterparts. But given Germany&rsquo;s central importance to the economy and policies of the European Union and its historical growing ties with Russia since the Second World War, Berlin would be a prime target for the Americans to exert leverage for their geopolitical advantage.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>When we look at German policy towards Russia over the Ukraine conflict it seems absurd on the face of it. German small businesses, major export companies and farmers are losing heavily from the Western sanctions imposed on Russia and from Moscow&rsquo;s counter-sanctions. Polls also indicate German public opinion is not supportive of the hostile policies, policies that have emanated from Washington and which the European allies have adopted, largely at the behest of Berlin&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Depuis ces diverses observations, ou parall\u00e8lement \u00e0 elles, nous avons pu enregistrer certains \u00e9v\u00e8nements qui seraient en temps normal du domaine de l&rsquo;anecdote, qui le sont certainement pour un commentateur-Syst\u00e8me tenu au garde-\u00e0-vous par sa <em>narrative<\/em>, mais acqui\u00e8rent une autre dimension dans le cadre du sujet que nous traitons. La premi\u00e8re se trouve dans les remarques que fit Alexander Mercouris autour de la rencontre de Moscou de f\u00e9vrier 2015, entre Poutine, Merkel et Hollande. Nous avions not\u00e9 ceci, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_crise_touche_le_bloc_bao_de_plein_fouet_09_02_2015.html\">9 f\u00e9vrier 2015<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>D&rsquo;abord un \u00e9v\u00e9nement qui nous a paru int\u00e9ressant \u00e0 relever, tel que l&rsquo;interpr\u00e8te Alexander Mercouris (dans le \u00ab\u00a0Saker\u00a0\u00bb-US le <\/em><a class=\"gen\" href=\"http:\/\/vineyardsaker.blogspot.be\/2015\/02\/talks-in-moscow-two-part-analysis.html\">7 f\u00e9vrier 2015<\/a><em> et \u00ab\u00a0Russia Insider\u00a0\u00bb le <\/em><a class=\"gen\" href=\"http:\/\/russia-insider.com\/en\/2015\/02\/08\/3242\">7 f\u00e9vrier 2015<\/a><em>)&#8230; Les circonstances d\u00e9crites par Mercouris sont particuli\u00e8rement int\u00e9ressantes, \u00e0 la lumi\u00e8re des hypoth\u00e8ses qu&rsquo;il propose. Il observe que Merkel et Hollande sont venus \u00e0 Moscou, non pas avec un plan pour l&rsquo;Ukraine, &ndash; et nous dirions avec l&rsquo;id\u00e9e implicite qu&rsquo;un plan pour l&rsquo;Ukraine \u00e9tait une mati\u00e8re secondaire, &ndash; mais pour avoir un entretien \u00ab\u00a0franc et complet\u00a0\u00bb avec Poutine, &ndash; et nous dirions dans l&rsquo;intention de conna&icirc;tre un point de vue sur la v\u00e9rit\u00e9 de la situation qui soit compl\u00e8tement d\u00e9gag\u00e9 de ce qu&rsquo;ils entendent jusqu&rsquo;ici, qui soit aussi \u00ab\u00a0prot\u00e9g\u00e9\u00a0\u00bb de toute incursion et observation ext\u00e9rieures&#8230;<\/em><\/p>\n<\/p>\n<p><p>&laquo;<em>\u00ab\u00a0One of the most interesting things about the Moscow talks is that they mainly happened without the presence of aides and officials i.e. Putin, Hollande and Merkel were by themselves save for interpreters and stenographers. Putin and Merkel are known to be masters of detail and given his background as an enarque I presume Hollande also is. However the German and French officials will be very unhappy about this. The Russians less so because since the meeting is taking place in the Kremlin they are listening in to the discussions via hidden microphones.<\/em> [&#8230;] <em>There has been an extraordinary degree of secrecy about this whole episode and it rather looks as if Merkel and Hollande were anxious to stop leaks and to prevent information about the talks from getting out. Presumably this is why their officials were barred from the meeting. From whom one wonders do Merkel and Hollande want to keep details of the meeting secret? From the media? From other members of their own governments? From the Americans?&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Ensuite, il y a une simple observation de Poutine, en r\u00e9ponse \u00e0 une question qui lui \u00e9tait pos\u00e9e lors de l&rsquo;\u00e9mission annuelle \u00ab\u00a0questions-r\u00e9ponses\u00a0\u00bb o&ugrave; le pr\u00e9sident russe r\u00e9pond \u00e0 des questions du public, qui \u00e9tait rappel\u00e9e sur <em>Sputnik<\/em>-fran\u00e7ais, le <a class=\"gen\" href=\"http:\/\/fr.sputniknews.com\/international\/20150416\/1015685507.html#ixzz3Yr2o3a6n\">16 avril 2015<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>A la question de commenter l&rsquo;\u00e9tat des relations g\u00e9opolitiques avec l&rsquo;Europe, <\/em>[Poutine r\u00e9pond]<em>: \u00ab\u00a0Il est difficile de parler \u00e0 des gens qui chuchotent m\u00eame chez eux de peur des \u00e9coutes am\u00e9ricaines. <\/em><strong><em>Et ceci n&rsquo;est pas une blague, je ne plaisante pas<\/em><\/strong><em>\u00ab\u00a0.<\/em>&raquo; (Nous avouons bien volontiers que c&rsquo;est le \u00ab\u00a0Et ceci n&rsquo;est pas une blague, je ne plaisante pas\u00a0\u00bb qui nous a le plus impressionn\u00e9. Parmi les divers dirigeants de notre monde enfi\u00e9vr\u00e9, Poutine est certainement celui qui se rapproche le plus, dans ses interventions, de la sinc\u00e9rit\u00e9, et d&rsquo;ailleurs la <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-du_bon_usage_de_poutine_16_04_2015.html\">force de son propos<\/a> l&rsquo;exige autant qu&rsquo;elle en t\u00e9moigne.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>En confrontant ces diverses observations et remarques, et sans qu&rsquo;il n&rsquo;y ait <strong>rien de d\u00e9cisivement nouveau<\/strong> sinon les r\u00e9v\u00e9lations sur le comportement du BND connu et couvert par cons\u00e9quent par Merkel, nous serions sans h\u00e9sitation tent\u00e9s de juger l&rsquo;hypoth\u00e8se de Cunningham <strong>compl\u00e8tement fond\u00e9e<\/strong> ; sans plus de surprise ni, peut-\u00eatre d&rsquo;indignation, puisque, \u00e0 la lumi\u00e8re de l&rsquo;histoire r\u00e9cente, des relations USA-Allemagne, des moyens de pression US et de la carri\u00e8re de Merkel (jeunesse en RDA, dans une famille de dignitaires du parti) qui rend difficile de n&rsquo;avoir pu rencontrer l&rsquo;une ou l&rsquo;autre occurrence pas n\u00e9cessairement pendable mais n\u00e9anmoins compromettante dans le cadre id\u00e9ologico-rigide de notre psychologie en politique, c&rsquo;est <strong>le contraire qui serait \u00e9tonnant<\/strong> : il serait finalement difficile de croire que Merkel \u00ab\u00a0<em>is not a CIA asset<\/em>\u00ab\u00a0&#8230; La situation allemande, et m\u00eame europ\u00e9enne, est donc particuli\u00e8rement douloureuse \u00e0 cet \u00e9gard : Merkel \u00e9tant ce qu&rsquo;elle est, Tusk \u00e9tant \u00e9videmment un agent d&rsquo;influence US par Pologne interpos\u00e9e, Juncker \u00e9tant une sorte d&rsquo;appendice germaniste, qui partage manifestement la m\u00eame position que Merkel (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-_preuve_de_force_et_lutte_mort_31_05_2014.html\">31 mai 2014<\/a>), dans tous les cas par indiff\u00e9rence ou laisser-faire lorsqu&rsquo;on se rappelle son d\u00e9part de la fonction de Premier ministre luxembourgeois, et enfin une France absente, sinon complice par b\u00e9atitudes satisfaite&#8230; (Si l&rsquo;on veut rajouter perfide Albion, toujours au charbon&#8230;)<\/p>\n<\/p>\n<p><p>Nous ne serons certainement pas plong\u00e9s dans la plus profonde affliction par ce constat. Encore une fois (il y a d\u00e9j\u00e0 eu des cas pr\u00e9c\u00e9dents d\u00e9crivant la f\u00e9lonie des locataires du bloc BAO \u00e0 l&rsquo;avantage des USA), l&rsquo;int\u00e9r\u00eat de la situation pr\u00e9sente est de nous exposer au grand jour ce qui nous \u00e9tait jusqu&rsquo;alors dissimul\u00e9, ou \u00e0 demi dissimul\u00e9 ; en effet, cette situation-l\u00e0, des dirigeants allemands, luxembourgeois, des institutions europ\u00e9ennes, de la Pologne, etc., existe depuis de nombreuses ann\u00e9es, et pour les plus anciens, depuis des d\u00e9cennies. Simplement, nous nous en doutions un peu mais n&rsquo;avions aucune certitude car aucun \u00e9v\u00e9nement ne nous faisait prendre conscience de l&rsquo;\u00e9tat des choses et de la trahison des esprits aussi vivement que les \u00e9v\u00e8nements d&rsquo;aujourd&rsquo;hui. Au contraire, aujourd&rsquo;hui le soleil brille sur la r\u00e9alit\u00e9 des comportements europ\u00e9ens et des positions politiques <strong>r\u00e9elles<\/strong> des uns et des autres. Par cons\u00e9quent, avec notre habituel pessimisme roboratif, qui conduit par inversion vertueuse \u00e0 un optimisme inattendu, nous observerions : 1) qu&rsquo;avec un tel acquis, un tel paquet d&rsquo;<em>assets<\/em>, on se demande bien comment les USA, depuis un demi-si\u00e8cle, n&rsquo;ont pas fait qu&rsquo;une seule bouch\u00e9e et \u00e0 plusieurs reprises du reste du monde, avec l&rsquo;Europe incluse dans le lot ; et 2) que tous ces dirigeants archi-corrompus et align\u00e9s \u00e0 la baguette, ont d&rsquo;autant plus de mal \u00e0 tenir leur \u00ab\u00a0rang\u00a0\u00bb \u00e0 la satisfaction de leurs employeurs, dans le cadre de crises de cette envergure, \u00e0 la t\u00eate de pays dont la population ne les aime gu\u00e8re, et encore moins leur politique, et dans une occurrence o&ugrave;, au bout du compte, ils ne peuvent tout de m\u00eame pas partager tous les objectifs des USA lorsque l&rsquo;un d&rsquo;eux peut d\u00e9boucher sur la probabilit\u00e9 d&rsquo;une guerre en Europe \u00e0 l&rsquo;occasion de l&rsquo;Ukraine &#8230; Ainsi ont-ils parfois l&rsquo;esprit de chuchoter \u00e0 Poutine pour que la NSA n&rsquo;y comprenne rien, et Poutine a-t-il l&rsquo;esprit de les inviter \u00e0 un barbecue dans son bunker s\u00e9curis\u00e9, pour qu&rsquo;on puisse parler \u00e0 l&rsquo;aise, en toute confiance et entre amis, des affaires europ\u00e9ennes &#8230;<\/p>\n<\/p>\n<p><p>Mis en ligne le 2 mai 2015 \u00e0 17H44<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La chanceli\u00e8re est-elle une bonne \u00ab\u00a0rente\u00a0\u00bb pour la CIA ? &laquo;Is Merkel a CIA Asset?&raquo;, interroge Finian Cunnigham (sur Sputnik.News, le 30 avril 2015). Effectivement, &ndash; au terme d&rsquo;\u00a0\u00bbagent\u00a0\u00bb (de la CIA), nous pr\u00e9f\u00e9rons le terme asset qui veut aussi bien dire un \u00ab\u00a0actif\u00a0\u00bb, une \u00ab\u00a0valeur boursi\u00e8re\u00a0\u00bb, un \u00ab\u00a0bien\u00a0\u00bb (immobilier), un \u00ab\u00a0bien-meuble\u00a0\u00bb, une \u00ab\u00a0rente\u00a0\u00bb peut-\u00eatre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2748,12182,1571,4215,10437,4614,2667,4633,3871,916,1296],"class_list":["post-75886","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-allemagne","tag-bnd","tag-cunningham","tag-eads","tag-espionnage","tag-juncker","tag-mercouris","tag-merkel","tag-nsa","tag-poutine","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75886"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75886\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}