{"id":75928,"date":"2015-05-28T10:41:53","date_gmt":"2015-05-28T10:41:53","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/05\/28\/de-la-syrie-a-lukraine-esquisse-des-derniers-temps\/"},"modified":"2015-05-28T10:41:53","modified_gmt":"2015-05-28T10:41:53","slug":"de-la-syrie-a-lukraine-esquisse-des-derniers-temps","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/05\/28\/de-la-syrie-a-lukraine-esquisse-des-derniers-temps\/","title":{"rendered":"De la Syrie \u00e0 l&rsquo;Ukraine, esquisse des derniers temps"},"content":{"rendered":"<p><h3>De la Syrie \u00e0 l&rsquo;Ukraine, esquisse des derniers temps<\/h3>\n<\/p>\n<p><p>\tSi l&rsquo;on veut en tirer le plus grand profit possible, on lira ce texte et l&rsquo;on \u00e9coutera et regardera l&rsquo;entretien t\u00e9l\u00e9vis\u00e9 recommand\u00e9 avec une attention d\u00e9barrass\u00e9e de tout esprit partisan, sans penser \u00e0 un aspect religieux (pour l&rsquo;approuver ou pour le d\u00e9noncer), mais comme devant un de ces t\u00e9moignages qui importent et, surtout, alimentent notre perception g\u00e9n\u00e9rale d&rsquo;une crise d&rsquo;effondrement qui ne peut \u00eatre comprise que comme un \u00e9v\u00e9nement eschatologique, et qui par cons\u00e9quent doit b\u00e9n\u00e9ficier de la recherche d&rsquo;une description \u00e0 mesure. Le texte ci-dessous est de Natalia Bourkova, sur <em>Sputnik<\/em>-fran\u00e7ais le <a href=\"http:\/\/fr.sputniknews.com\/analyse\/20150526\/1016267215.html#ixzz3bJuZ65Ae\" class=\"gen\">26 mai 2015<\/a> ; il s&rsquo;appuie sur un entretien t\u00e9l\u00e9vis\u00e9 d&rsquo;un peu plus de 24 minutes de M\u00e8re Agn\u00e8s-Mariam de la Croix, M\u00e8re sup\u00e9rieure du couvent syrien Saint Jacques le Mutil\u00e9, r\u00e9alis\u00e9 le <a href=\"http:\/\/www.tvlibertes.com\/mere-agnes-mariam-de-la-croix-en-syrie-hollande-est-schizophrenique\/\" class=\"gen\">22 mai 2015<\/a> sur <em>TVLibert\u00e9s.com<\/em>. (Le DVD vaut l&rsquo;\u00e9coute parce qu&rsquo;il nous montre une religieuse pleine de mesure et remarquablement inform\u00e9e, au langage ferme et rationnel, dont l&rsquo;in\u00e9vitable aspect \u00e9motif devant la trag\u00e9die que l&rsquo;on devine n&rsquo;intervient en rien sur sa coh\u00e9rence.)  <\/p>\n<\/p>\n<p><p>\tLe th\u00e8me d\u00e9velopp\u00e9 par M\u00e8re Agn\u00e8s-Mariam de la Croix est bien entendu la situation en Syrie, \u00e0 laquelle Bourkova rajoute en conclusion et d&rsquo;une fa\u00e7on justifi\u00e9e une r\u00e9f\u00e9rence \u00e0 l&rsquo;Ukraine. Mais ce th\u00e8me d\u00e9velopp\u00e9, ainsi que les r\u00e9f\u00e9rences aux absurdes et grotesques positions politiques de nos dirigeants (notamment vis-\u00e0-vis du r\u00e9gime syrien d&rsquo;Assad), ne sont que des artefact conjoncturels ; le th\u00e8me structurel, parfaitement illustr\u00e9 par la cr\u00e9ation, le d\u00e9veloppement, l&rsquo;action de <em>Daesh<\/em>, alias \u00c9tat Islamique, autant que par les positions incoh\u00e9rentes des autres acteurs vis-\u00e0-vis de lui, est bien entendu celui de la signification fondamentale de cette violence sauvage et nihiliste, entrant dans une description eschatologique de la r\u00e9volte de l&rsquo;homme contre l&rsquo;homme. (\u00ab<em>Le cas ukrainien ne fait que confirmer, pour la \u00e9ni\u00e8me fois, la v\u00e9racit\u00e9 de ce constat. Il a d&rsquo;ailleurs \u00e9t\u00e9 d\u00e9crit dans les Evangiles apocalyptiques, M\u00e8re Agn\u00e8s-Mariam y fait r\u00e9f\u00e9rence, o\u00f9 l&rsquo;on retrouve le d\u00e9tail de ce que serait la r\u00e9volte de l&rsquo;homme contre lui-m\u00eame les temps derniers venus<\/em>\u00bb&#8230; C&rsquo;est pour r\u00e9pondre \u00e0 la derni\u00e8re question, dans les 2-3 derni\u00e8res minutes du DVD, que M\u00e8re Agn\u00e8s-Mariam de la Croix d\u00e9veloppe ce th\u00e8me des derniers temps, \u00e9galement sur ce m\u00eame ton ferme et mesur\u00e9 qui est d&rsquo;autant plus convaincant \u00e0 l&rsquo;avantage du sujet trait\u00e9.)<\/p>\n<\/p>\n<p><p>\tLes \u00e9v\u00e8nements en cours,  ici au Moyen-Orient autour du cas <em>Daesh<\/em> et de la Syrie, et autour de l&rsquo;Ukraine,  acqui\u00e8rent sans aucun doute et visiblement une tournure eschatologique que tous les points de vue peuvent identifier sans pour autant \u00e9pouser telle ou telle th\u00e8se. La situation du monde commence \u00e0  appara\u00eetre,  si cela est possible et concevable intellectuellement et cela semble l&rsquo;\u00eatre,   comme <strong>objectivement eschatologique<\/strong>, c&rsquo;est-\u00e0-dire pouvant \u00eatre per\u00e7us comme nous disant un \u00ab<em>discours sur la fin des temps<\/em>\u00bb (voir la signification rapide et sans n\u00e9cessit\u00e9 de complication d&rsquo; <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Eschatologie\" class=\"gen\">eschatologie<\/a>). Cette interpr\u00e9tation s\u00e9mantique peut \u00eatre transcrite d&rsquo;un point de vue graphique et dynamique, d&rsquo;autant plus que le discours prend effectivement de plus en plus cette forme objective qui rejoint la d\u00e9marche du constat de l&rsquo;\u00e9vidence. Le cas <em>Daesh<\/em> en est tr\u00e8s significatif, notamment dans la fa\u00e7on que cette vague incertaine dans son parcours, furieuse et d&rsquo;une brutalit\u00e9 inou\u00efe dans son comportement, effectue des mouvements tourbillonnants, exactement comme un tourbillon aspire tout ce qui le compose, ou si l&rsquo;on veut comme si l&rsquo;\u00e9v\u00e9nement de ce tourbillon se formaient en aspirant les \u00e9v\u00e8nements qui le composent vers une sorte de trou noir et r\u00e9alisant effectivement un mouvement dans le sens qu&rsquo;on pourrait apparenter \u00e0 une fin des temps (ou aux derniers temps). Cette dynamique tourbillonnante est parfaitement adapt\u00e9e \u00e0 ce qu&rsquo;on peut rationnellement concevoir comme une d\u00e9marche m\u00e9tahistorique de type eschatologique que constituerait l&rsquo;\u00e9pisode des derniers temps. La raison, celle qui parvient \u00e0 se d\u00e9gager de la subversion du d\u00e9cha\u00eenement de la Mati\u00e8re (hors de la <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde-crisis_la_crise_de_la_raison_humaine_29_11_2014.html\" class=\"gen\">raison-subvertie<\/a>), s&rsquo;y retrouve parfaitement, tant l&rsquo;\u00e9v\u00e9nement terrestre qu&rsquo;on identifie s&rsquo;impose parfaitement comme la transcription \u00e9v\u00e8nementielle de cette d\u00e9marche m\u00e9tahistorique.<\/p>\n<\/p>\n<p><p>\tLa politique g\u00e9n\u00e9rale et les diverses crises qui la composent (la politique g\u00e9n\u00e9rale n&rsquo;est plus faite que de crises) suivent ce m\u00eame sch\u00e9ma, qui offre ce spectacle \u00e9trange de concilier ce qui semble inconciliable, \u00e0 la fois apparence de mouvement hyst\u00e9rique et incontr\u00f4lable et \u00e0 la fois apparence de surplace. Pour cette raison et pour aller \u00e0 un autre exemple montrant l&rsquo;universalit\u00e9 du ph\u00e9nom\u00e8ne et renfor\u00e7ant l&rsquo;hypoth\u00e8se des derniers temps, on peut parler de l&rsquo;impuissance et de la paralysie du gouvernement washingtonien qui se manifeste pourtant partout et de toutes les fa\u00e7ons dans une d\u00e9bauche insens\u00e9e de paroles, de pseudo-d\u00e9cisions, de machinations sans fin et inextricables, d&rsquo;effets voulus et de r\u00e9actions inattendus et d\u00e9vastatrices pour soi-m\u00eame (<em>blowback<\/em>), de calculs tordus et idiots tr\u00e8s vite mis \u00e0 jour,  et de tout cela comme s&rsquo;il ne restait rien sinon toujours de cette sorte de destruction caract\u00e9risant les derniers temps. La situation g\u00e9n\u00e9rale suit \u00e9galement le m\u00eame sch\u00e9ma, depuis 2008, avec son incapacit\u00e9 de rompre, soit en sortant des suites de la crise de 2008, soit en se pr\u00e9cipitant dans une nouvelle crise du m\u00eame domaine caoutchouteux de la finance, qui vit au rythme des crises comme un cam\u00e9 de ses doses d&rsquo;h\u00e9ro\u00efne, dont on pourrait attendre une sorte de paroxysme lib\u00e9rateur.<\/p>\n<\/p>\n<p><p>\tNous ne nous \u00e9loignons pas de notre sujet,  qui est plus, selon notre appr\u00e9ciation comme on l&rsquo;a comprise, celui des derniers temps que celui de <em>Daesh<\/em> et de la Syrie. Simplement, <em>Daesh<\/em> et la Syrie, avec leur cort\u00e8ge d&rsquo;horreurs, de souffrances, et surtout d&rsquo;une profonde et diabolique inutilit\u00e9 nihiliste, constituent sans aucun doute une illustration \u00e9vidente de ce que nous voulons montrer par ce rapide commentaire. La M\u00e8re Agn\u00e8s-Mariam de la Croix est une personne de grande qualit\u00e9 et de haute valeur dans la description de cet aspect du d\u00e9sordre eschatologique du monde qui a transform\u00e9 radicalement la situation g\u00e9n\u00e9rale en quelques ann\u00e9es. Ce n&rsquo;est peut-\u00eatre pas encore la fin de la fin des temps,  qui peut le dire dans des temps qui ridiculisent nos pr\u00e9tentions \u00e0 la prospective ?,  mais nous pouvons d\u00e9sormais en distinguer les caract\u00e8res et nous dire en-dedans de nous-m\u00eames, sans aucune pr\u00e9tention d&rsquo;en conna\u00eetre plus que cela mais avec l&rsquo;intuition haute de notre c\u00f4t\u00e9 : Nous y sommes. Le Syst\u00e8me, notre fameux Syst\u00e8me, est d\u00e9sormais hors de tout contr\u00f4le dans sa trajectoire d&rsquo;effondrement qui sera l&rsquo;\u00e9pisode op\u00e9rationnel fondamental de l&rsquo;\u00e9v\u00e9nement eschatologique.<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>dedefensa.org<\/em><\/p>\n<\/p>\n<p><\/p>\n<h2 class=\"common-article2\">De la Syrie \u00e0 l&rsquo;Ukraine, esquisse des derniers temps<\/h2>\n<\/p>\n<p><p>\tR\u00e9cemment interrog\u00e9e par TV Libert\u00e9s, M\u00e8re Agn\u00e8s-Mariam de la Croix, M\u00e8re sup\u00e9rieure du couvent syrien Saint Jacques le Mutil\u00e9, avait d\u00e9fini la strat\u00e9gie syrienne de Fran\u00e7ois Hollande comme \u00e9tant schyzophr\u00e9nique.<\/p>\n<\/p>\n<p><p>\tSa logique est irr\u00e9prochable: alors donc que l&rsquo;EI, accessoirement soutenu par des fractions d&rsquo;Al-Qa\u00efda et de Jabhat Al-Nosra  sauf querelles intestines sporadiques  inonde litt\u00e9ralement la Syrie, l&rsquo;Irak et la Libye, que des citadelles terroristes d\u00fbment fortifi\u00e9es bordent la fronti\u00e8re syro-libanaise (notamment du c\u00f4t\u00e9 d&rsquo;Ersal), il semblerait pour le peu normal de renouer diplomatiquement avec Assad. Ne serait-ce qu&rsquo;au nom de l&rsquo;Europe, de plus en plus expos\u00e9e gr\u00e2ce aux courant d&rsquo;air de Shengen. Nous relevons n\u00e9anmoins une r\u00e9action contraire au bon sens.<\/p>\n<\/p>\n<p><p>\tCertains experts, tel Bassam Tahhan, ont tendance \u00e0 croire que l&rsquo;obstination fran\u00e7aise n&rsquo;est que le fruit v\u00e9reux de l&rsquo;orgueil de la classe dirigeante. On s&rsquo;est tromp\u00e9, Al-Nosra n&rsquo;est pas compos\u00e9 de gentils rebelles, mais le reconna\u00eetre, non, c&rsquo;est trop demander! Je pense pour ma part que cet argument est trop indulgent. Il disculpe les vrais coupables et indemnisent les ignorants qui pour beaucoup se targuent d&rsquo;une ignorance qui les arrange, dans le genre, je ne vois que ce que je veux voire, tant pis si le tableau bross\u00e9 ne correspond pas \u00e0 la r\u00e9alit\u00e9 du terrain.<\/p>\n<\/p>\n<p><p>\tM\u00e8re Agn\u00e8s-Mariam de la Croix nous apprend ainsi, propos souvent tr\u00e8s nuanc\u00e9s \u00e0 l&rsquo;appui, que l&rsquo;ASL dont on avait initialement parl\u00e9 existait bel et bien mais qu&rsquo;elle s&rsquo;est vite d\u00e9sagr\u00e9g\u00e9e et s&rsquo;est fondue dans ce qu&rsquo;elle a appel\u00e9 Le Croissant-Rouge Libre qui est compos\u00e9 de membres la\u00efcs orient\u00e9s dans leur combat contre l&rsquo;agresseur salafiste. Le probl\u00e8me, c&rsquo;est que ces jeunes gens, des volontaires, sont pour la plupart au ch\u00f4mage. Ils ont donc la choix entre rejoindre les rangs de l&rsquo;arm\u00e9e syrienne  option privil\u00e9gi\u00e9e par la majorit\u00e9  ou rejoindre ceux de l&rsquo;EI o\u00f9 ils sont nourris comme des dieux et toucheraient un salaire honorable. Cette observation nous am\u00e8ne \u00e0 une conclusion tr\u00e8s simple qui est la th\u00e8se centrale de la R\u00e9v\u00e9rende M\u00e8re: le combat qui est men\u00e9 en Syrie n&rsquo;est pas une confrontation sanglante entre un peuple lib\u00e9ral et ce que le mainstream appelle vulgairement le r\u00e9gime d&rsquo;Assad mais bien une guerre du peuple dans son ensemble contre des groupes terroristes h\u00e9t\u00e9rog\u00e8nes. Nous ne sommes par cons\u00e9quent pas dans une optique de guerre civile, comme on a longtemps voulu nous le faire croire, mais dans une optique de guerre populaire contre une n\u00e9buleuse terroriste particuli\u00e8rement expansive et totalitaire dont les int\u00e9r\u00eats sont opportun\u00e9ment soutenus par des forces subversives aux fins obscures que l&rsquo;intervenante se garde de nommer.<\/p>\n<\/p>\n<p><p>\tCes forces subversives et ces fins obscures  avant tout au sens moral du terme  nous les connaissons tr\u00e8s bien. Il suffit de se demander comment est-ce qu&rsquo;une organisation terroriste arrive \u00e0 vendre le p\u00e9trole syrien vol\u00e9 \u00e0 la Turquie, un pays membre de l&rsquo;OTAN \u00e0 qui l&rsquo;on fait en plus miroiter l&rsquo;\u00e9ventualit\u00e9 d&rsquo;une int\u00e9gration \u00e0 l&rsquo;UE. C&rsquo;est sans compter qu&rsquo;Isra\u00ebl, faisant fi de ses int\u00e9r\u00eats long-termistes, est aussi demandeur. Par ailleurs, l&rsquo;aviation am\u00e9ricaine a \u00e9t\u00e9 plus d&rsquo;une fois accus\u00e9e de balancer du mat\u00e9riel militaire dans les zones contr\u00f4l\u00e9es par l&rsquo;EI, soi-disant par erreur. Cette erreur se r\u00e9p\u00e8te constamment.<\/p>\n<\/p>\n<p><p>\tFaut-il s&rsquo;en \u00e9tonner quand on sait que le si\u00e8ge perfide de la Syrie n&rsquo;est qu&rsquo;une \u00e9tape provisoire qui devra conduire \u00e0 l&#8217;embrasement d&rsquo;un conflit sur le sol iranien? L&rsquo;Iran d\u00e9truit, le croissant chiite qui est l&rsquo;Axe de R\u00e9sistance par excellence se morcellera avant de se r\u00e9duire en poussi\u00e8re. L&rsquo;UE \u00e9tant sous la houlette am\u00e9ricaine, cela explique son alliance contre-nature avec les monarchies wahabbites du Golfe pour qui l&rsquo;EI n&rsquo;est au fond qu&rsquo;un concurrent, un embryon de califat qui, si sa construction aboutit, priverait l&rsquo;Arabie Saoudite du r\u00f4le central symbolique qu&rsquo;elle d\u00e9tient au cur du monde sunnite. Pour le reste, m\u00eame paire de gants: n&rsquo;est-ce pas la cha\u00eene qatari Al-Jazeera qui a diffus\u00e9 le 8 mai de l&rsquo;ann\u00e9e en cours un d\u00e9bat portant sur l&rsquo;\u00e9ventuelle n\u00e9cessit\u00e9 de massacrer les alaouites? Selon les donn\u00e9es des derniers sondages, l&rsquo;\u00e9crasante majorit\u00e9 du peuple qatari partagerait cette vision qui n&rsquo;a rien \u00e0 envier aux horreurs historiques des guerres de religion. On le voit bien, le clan n\u00e9oconservateur am\u00e9ricain instrumentalise avec beaucoup d&rsquo;adresse cette intol\u00e9rance hallucin\u00e9e et hallucinante, jouant sur les contradictions ethniques et confessionnelles des peuples \u00e0 soumettre ou \u00e0 g\u00e9nocider.<\/p>\n<\/p>\n<p><p>\tLe cas ukrainien ne fait que confirmer, pour la \u00e9ni\u00e8me fois, la v\u00e9racit\u00e9 de ce constat. Il a d&rsquo;ailleurs \u00e9t\u00e9 d\u00e9crit dans les Evangiles apocalyptiques, M\u00e8re Agn\u00e8s-Mariam y fait r\u00e9f\u00e9rence, o\u00f9 l&rsquo;on retrouve le d\u00e9tail de ce que serait la r\u00e9volte de l&rsquo;homme contre lui-m\u00eame les temps derniers venus. Ne voyons-nous pas une oligarchie supranationale d\u00e9tentrice du syst\u00e8me financier mondial alimenter sa machine \u00e0 sous en sang? Ne la voyons-nous pas exploiter des entit\u00e9s fanatiques marginales de nature ultra-nationaliste (band\u00e9ristes ukrainiens) ou religieuse (Al-Qa\u00efda et d\u00e9riv\u00e9, EI) \u00e0 des fins de division et de purge? S&rsquo;il faudra livrer l&rsquo;Europe, aucun souci, les peuples ne valant de toute fa\u00e7on rien.<\/p>\n<\/p>\n<p><p>\tQuelles sont les circonstances envisageables qui pourraient mettre un terme au fonctionnement de cette machine infernale? C&rsquo;est difficile \u00e0 dire. Peut-\u00eatre faudrait-il enfin que ces m\u00eames peuples se r\u00e9veillent comme l&rsquo;a d\u00e9j\u00e0 fait une grande partie du peuple syrien et celui du Donbass? L&rsquo;Histoire y apportera une r\u00e9ponse.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Natalia Bourkova<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De la Syrie \u00e0 l&rsquo;Ukraine, esquisse des derniers temps Si l&rsquo;on veut en tirer le plus grand profit possible, on lira ce texte et l&rsquo;on \u00e9coutera et regardera l&rsquo;entretien t\u00e9l\u00e9vis\u00e9 recommand\u00e9 avec une attention d\u00e9barrass\u00e9e de tout esprit partisan, sans penser \u00e0 un aspect religieux (pour l&rsquo;approuver ou pour le d\u00e9noncer), mais comme devant un&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[16662,16663,16039,2631,7548,2622,16661,3387,3867,12735,9656,1296],"class_list":["post-75928","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-agnes-mariam","tag-bourkova","tag-croix","tag-de","tag-eschatologie","tag-la","tag-mere","tag-noir","tag-syrie","tag-tourbillon","tag-trou","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75928"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75928\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}