{"id":75946,"date":"2015-06-11T05:51:54","date_gmt":"2015-06-11T05:51:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/06\/11\/le-don-de-soi\/"},"modified":"2015-06-11T05:51:54","modified_gmt":"2015-06-11T05:51:54","slug":"le-don-de-soi","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/06\/11\/le-don-de-soi\/","title":{"rendered":"Le don de soi"},"content":{"rendered":"<p><h2 class=\"common-article2\">Le don de soi<\/h2>\n<\/p>\n<p><p>\t<em>Nous poursuivons, dans le sillage de la \u00ab R\u00e9volution spirituelle \u00bb notre r\u00e9flexion critique portant sur les d\u00e9rives contemporaines qui menacent l&rsquo;int\u00e9grit\u00e9 de l&rsquo;\u00eatre et sa transformation r\u00e9elle. Dans un contexte de \u00ab lutte de tous contre tous \u00bb, seul, le don de soi permet \u00e0 l&rsquo;individu de se lib\u00e9rer de la tutelle des illusions mortif\u00e8res. C&rsquo;est, sans doute, le v\u00e9ritable testament du Christ, ce passeur d&rsquo;esp\u00e9rance devant l&rsquo;\u00e9ternel <\/em><\/p>\n<\/p>\n<p><p>\t<em>Certains confondent la g\u00e9n\u00e9rosit\u00e9 avec un d\u00e9sir d&rsquo;autodestruction, pointant du doigt les exactions d&rsquo;une pl\u00e9iade d&rsquo;extr\u00e9mistes se r\u00e9clamant de tel ou tel courant spirituel. Mais encore ? \u00catre pr\u00e9sent au monde c&rsquo;est faire preuve de compassion en toutes choses. Faire preuve de compassion nous oblige \u00e0 intervenir, d&rsquo;une mani\u00e8re ou d&rsquo;une autre, afin de soulager la mis\u00e8re d&rsquo;autrui. Certains de mes objecteurs argueront, avec justesse, qu&rsquo;il importe, d&rsquo;abord et avant tout, de prendre soin de notre intime personne. Mais, c&rsquo;est l&rsquo;autre qui m&rsquo;interpelle au gr\u00e9 du dialogue de l&rsquo;intime. L&rsquo;autre, ce compagnon de vie malgr\u00e9 la solitude du r\u00e9el.<\/em><\/p>\n<\/p>\n<p><p>\t________________ <\/p>\n<\/p>\n<p><\/p>\n<h3>L&#8217;empire des sens<\/h3>\n<\/p>\n<p><p>\tQu&rsquo;est-ce que la d\u00e9cadence ? Les soci\u00e9t\u00e9s humaines p\u00e9rissent de trop s&rsquo;attacher aux biens de ce monde. C&rsquo;est l&rsquo;id\u00e9alisme combattif qui porte les civilisations vers leur sommet. L&rsquo;abject calcul int\u00e9ress\u00e9 s&rsquo;inocule dans la m\u00e9moire collective lorsque les peuples ont oubli\u00e9 leur propre histoire, alors que les \u00e9lites aux manettes se gavent comme d&rsquo;immondes porcs jamais rassasi\u00e9s. Ubu Roi n&rsquo;est que le \u00ab bon berger \u00bb des foules avides de pains et de jeux. Les plaisirs propos\u00e9s aux consommateurs sont comparables \u00e0 des vessies en voie de putr\u00e9faction. Les lanternes sont \u00e9teintes depuis que les philosophes ont \u00e9t\u00e9 remplac\u00e9s par des \u00ab communicants \u00bb. La cit\u00e9 ressemble, \u00e0 s&rsquo;y m\u00e9prendre, \u00e0 un cirque d&rsquo;o\u00f9 retentissent les voix des victimes et de leurs bourreaux, toutes id\u00e9ologies confondues.<\/p>\n<\/p>\n<p><p>\tJamais rassasi\u00e9s, nos Ubu de dirigeants se vautrent dans la boue des illusions perdues d&rsquo;une marche vers le progr\u00e8s qui n&rsquo;est qu&rsquo;une habile fa\u00e7on de d\u00e9trousser les citoyens d\u00e9boussol\u00e9s. Les politiques sont des d\u00e9trousseurs de contribuables qui s&rsquo;acharnent \u00e0 \u00ab pr\u00e9lever une livre de chair \u00bb sur le cadavre exquis de nos consciences viol\u00e9es. Aveugl\u00e9s que nous sommes par la mort, nous avons oubli\u00e9 que la cr\u00e9ation proc\u00e8de du don, cette facult\u00e9 qui pousse l&rsquo;\u00eatre int\u00e8gre \u00e0 se surpasser malgr\u00e9 les circonstances. Justement, malgr\u00e9 les circonstances. Notre qu\u00eate effr\u00e9n\u00e9e de plaisirs fugaces cache ce mal-\u00eatre qui est le lot d&rsquo;une part croissance des consommateurs travestis en citoyens. \u00ab Je consomme, donc je suis \u00bb, jusqu&rsquo;\u00e0 \u00e9puisement des stocks tant que la ligne de cr\u00e9dit sera reconduite.<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;est donc pas surprenant que le plus grand nombre confonde la sensualit\u00e9 avec la propension \u00e0 se gratter jusqu&rsquo;au sang qui caract\u00e9rise tous les bons pervers-narcissiques qui se respectent. Comme je le mentionnais dans un autre billet, il faut jouir peu importe le prix \u00e0 payer ! N&rsquo;\u00e9tant jamais rassasi\u00e9s, insatisfaits perp\u00e9tuels, nous pourchassons de vagues fantasmes qui se jouent de nous, en nous entra\u00eenant vers l&rsquo;ab\u00eeme de l&rsquo;\u00e9go\u00efsme triomphant qui caract\u00e9rise notre \u00e9poque et nos murs. Fiers consommateurs, nous succombons comme les moutons de Panurge au claquement du fouet d&rsquo;Ubu promoteur.<\/p>\n<h3>La victime propitiatoire <\/h3>\n<\/p>\n<p><p>\tLe consommateur est la victime propitiatoire destin\u00e9e \u00e0 rendre les dieux du casino complaisants face \u00e0 la demande incessante de cr\u00e9dit. Il s&rsquo;agit d&rsquo;une \u00e9conomie de la rapine qui a remplac\u00e9e celle de l&rsquo;antique don : toute la soci\u00e9t\u00e9 au grand complet devant \u00eatre sacrifi\u00e9e sur l&rsquo;autel des jeux du cirque. Incapables de s&rsquo;extraire de cette machination, nos cong\u00e9n\u00e8res pr\u00e9f\u00e8rent sacrifier leurs proches, en repoussant toujours plus loin l&rsquo;\u00e9ch\u00e9ance fatidique. Il faut \u00ab sauver sa peau \u00bb, d&rsquo;abord et avant tout, en attendant de savoir \u00e0 quelle sauce nous serons mang\u00e9s. M\u00e9nageant le chou et la ch\u00e8vre, et nos propres fesses, nous nous tortillons comme des lombrics \u00e0 travers \u00ab l&rsquo;air du temps \u00bb  cette incommensurable imposture de l&rsquo;\u00eatre. Notre vide existentiel s&rsquo;apparente \u00e0 un travestissement en mode continu. Les victimes font semblant d&rsquo;\u00eatre des gagnants !<\/p>\n<\/p>\n<p><p>\tEn d&rsquo;autres circonstances, nous pr\u00e9tendons \u00eatre les victimes, alors que nous sacrifions nos proches avec une f\u00e9lonie consomm\u00e9e. Nous avons rompus tous les contrats qui nous liaient avec nos semblables et les divinit\u00e9s tut\u00e9laires qui veillaient sur la cit\u00e9. Vivant \u00e0 cr\u00e9dit, nous ne r\u00e9alisons m\u00eame pas que nous sommes les prochains sur la liste au cur d&rsquo;une \u00e9conomie financi\u00e8re o\u00f9 tout se vaut et s&rsquo;annule de mani\u00e8re instantan\u00e9e. Il convient, donc, de calmer la fureur de nos bailleurs de fond en proc\u00e9dant au sacrifice de tout ce qui assurait la p\u00e9rennit\u00e9 de nos soci\u00e9t\u00e9s moribondes. Nous \u00ab mettons au monde \u00bb des enfants qui seront offerts aux Molochs qui pr\u00e9sident aux destin\u00e9es de ce march\u00e9 de dupes qui s&rsquo;est infiltr\u00e9 par tous les pores de la cit\u00e9. L&rsquo;\u00e9go\u00efsme est un perp\u00e9tuel sacrifice qui finit, en bout de ligne, par dissoudre ceux et celles qui prenaient plaisir \u00e0 dominer le jeu.<\/p>\n<h3>Les gagnants et les perdants<\/h3>\n<\/p>\n<p><p>\tL&rsquo;\u00e9thique protestante du n\u00e9olib\u00e9ralisme professe que les gagnants ont fait l&rsquo;objet d&rsquo;une \u00e9lection divine et qu&rsquo;ils ont, cons\u00e9quemment, tous les droits sur le reste de l&rsquo;humanit\u00e9. Il s&rsquo;agit d&rsquo;une \u00e9thique de la boucherie qui permet de justifier tous les exc\u00e8s qu&rsquo;un imp\u00e9rialisme peut se permettre en fin de parcours. Les perdants, ch\u00f4meurs ou travailleurs au statut pr\u00e9caire, m\u00e9ritent leur sort et n&rsquo;ont qu&rsquo;\u00e0 bien se tenir. Rien n&rsquo;est donn\u00e9 dans ce syst\u00e8me de valeurs : tout est \u00e0 vendre. Et, les classes moyennes presque disparues, une nouvelle caste de parvenus affiche un niveau de vie qui n&rsquo;a rien \u00e0 envier aux Pharaons des \u00e9poques antiques. <\/p>\n<\/p>\n<p><p>\tTous les exc\u00e8s sont permis, m\u00eame ceux qui sont inimaginables. Il s&rsquo;agit de transgresser toute forme de d\u00e9cence au d\u00e9triment des plus faibles. L&rsquo;essentiel consistant \u00e0 pratiquer le Feng Sui \u00e0 son domicile, \u00e0 faire de g\u00e9n\u00e9reuses donations \u00e0 un mus\u00e9e ou \u00e0 crier son amour du Sauveur dans le cadre de douteuses liturgies qui s&rsquo;apparentent \u00e0 des sessions de motivation pour vendeurs. Il convient d&rsquo;affirmer haut et fort son attachement \u00e0 l&rsquo;environnement et son humanisme de circonstance. \u00ab Tout est bon dans le cochon \u00bb afin de ravaler la fa\u00e7ade du nouveau pharisien milliardaire. <\/p>\n<\/p>\n<p><p>\tLes perdants doivent se contenter de leurs tickets alimentaires et faire amende honorable lorsque les autorit\u00e9s leur demandent des comptes. Parce que les perdants doivent rendre des comptes et se justifier en temps r\u00e9el. Les gagnants, eux, sont  \u00ab justifi\u00e9s \u00bb par le Tr\u00e8s-Haut qui leur accorde toute sa mansu\u00e9tude. L&rsquo;avarice et la pr\u00e9varication repr\u00e9sentent les deux mamelles de ce syst\u00e8me de contre-valeurs sur lequel s&rsquo;appuient les puissants de ce monde. Comme \u00e0 l&rsquo;\u00e9poque de Dickens, il convient de sp\u00e9culer sur tout : la nourriture, les terrains vagues, l&rsquo;air que l&rsquo;on respire, le ventre des femmes enceintes, la na\u00efvet\u00e9 des enfants et l&rsquo;espoir en d\u00e9perdition. Des familles enti\u00e8res sont jet\u00e9es \u00e0 la rue et, prestement, remplac\u00e9es par les nouveaux travailleurs mobiles de l&rsquo;\u00e9conomie mondialiste. Les citoyens de nagu\u00e8re, ceux et celles qui s&rsquo;\u00e9taient \u00e9tablis sur les fondations du labeur de leur famille respective, deviennent les nouveaux perdants de cette \u00e9conomie de la fuite en avant.<\/p>\n<h3>Le don comme lib\u00e9ration<\/h3>\n<\/p>\n<p><p>\tRien ne sert de retarder le moment de votre lib\u00e9ration en sp\u00e9culant sur l&rsquo;antimati\u00e8re ou en crachant \u00e0 la gueule des plus faibles. \u00c0 une \u00e9poque o\u00f9, m\u00eame, les fonds de pension des mieux nantis d&rsquo;entre-nous sont menac\u00e9s de liquidation, il serait peut-\u00eatre temps d&rsquo;ouvrir les yeux pour de bon. Cessez d&rsquo;envoyer du fric \u00e0 l&rsquo;\u00e9tranger pour le compte d&rsquo;obscures ONG am\u00e9ricaines et donnez-vous la peine de porter secours \u00e0 vos proches. L&rsquo;entraide n&rsquo;est plus l&rsquo;apanage de quelques fraternit\u00e9s d&rsquo;initi\u00e9s : c&rsquo;est, d\u00e9sormais, une condition sine qua non de la survie en milieu post-capitaliste. Investissez dans votre communaut\u00e9 respective, pas sur le parquet de la bourse.<\/p>\n<\/p>\n<p><p>\tLe \u00ab don de soi \u00bb, ce n&rsquo;est pas mettre une somme d&rsquo;argent dans une enveloppe que l&rsquo;on glisse dans une bo\u00eete anonyme  \u00e7a n&rsquo;a rien \u00e0 voir ! Il s&rsquo;agit d&rsquo;\u00ab \u00eatre pr\u00e9sent au monde \u00bb qui vous entoure, de cesser de consid\u00e9rer autrui comme un comp\u00e9titeur ou une entrave \u00e0 votre libert\u00e9. Parce que la libert\u00e9 ne consiste pas \u00e0 r\u00e9duire en cendre la vie de votre entourage. Les anciens philosophes grecs parlaient de la n\u00e9cessit\u00e9 d&rsquo;\u00ab \u00eatre donn\u00e9 au monde \u00bb, pour que l&rsquo;\u00eatre puisse, enfin, se lib\u00e9rer du n\u00e9ant. L&rsquo;authentique lib\u00e9ration requiert le don de soi, c&rsquo;est-\u00e0-dire une pr\u00e9sence d&rsquo;esprit qui uvre pour que le cur redevienne l&rsquo;organe privil\u00e9gi\u00e9 de nos \u00e9changes avec autrui.<\/p>\n<\/p>\n<p><p>\tDans un monde o\u00f9 l&rsquo;\u00e9thique du \u00ab donnant-donnant \u00bb fausse jusqu&rsquo;aux rapports familiaux, il serait peut-\u00eatre temps de r\u00e9apprendre \u00e0 donner gratuitement. Donner cette part de notre intimit\u00e9 que l&rsquo;on peut se permettre de partager avec ceux qui croisent notre chemin de vie. Se donner sans retenue au moment pr\u00e9sent et ne rien regretter, puisque demain nous permettra de poursuivre le \u00ab grand uvre \u00bb. L&rsquo;\u00ab uvre au noir \u00bb, cette alchimie juste et bonne qui permet aux hommes et aux femmes qui s&rsquo;en donnent la peine de vaincre la mort. Ici et maintenant. <\/p>\n<\/p>\n<p>\n<p class=\"signature\">Patrice-Hans Perrier<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le don de soi Nous poursuivons, dans le sillage de la \u00ab R\u00e9volution spirituelle \u00bb notre r\u00e9flexion critique portant sur les d\u00e9rives contemporaines qui menacent l&rsquo;int\u00e9grit\u00e9 de l&rsquo;\u00eatre et sa transformation r\u00e9elle. Dans un contexte de \u00ab lutte de tous contre tous \u00bb, seul, le don de soi permet \u00e0 l&rsquo;individu de se lib\u00e9rer de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[4363,3228,2631,7979,12606,11373],"class_list":["post-75946","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-capitalisme","tag-crise","tag-de","tag-don","tag-perrier","tag-soi"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75946"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75946\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}