{"id":75948,"date":"2015-06-12T05:49:18","date_gmt":"2015-06-12T05:49:18","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/06\/12\/petite-genealogie-de-la-double-verite\/"},"modified":"2015-06-12T05:49:18","modified_gmt":"2015-06-12T05:49:18","slug":"petite-genealogie-de-la-double-verite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/06\/12\/petite-genealogie-de-la-double-verite\/","title":{"rendered":"Petite g\u00e9n\u00e9alogie de la double v\u00e9rit\u00e9"},"content":{"rendered":"<p><h2 class=\"common-article2\">Petite g\u00e9n\u00e9alogie de la double v\u00e9rit\u00e9<\/h2>\n<\/p>\n<p><p>\tLes th\u00e9ologiens m\u00e9di\u00e9vaux de l&rsquo;Occident chr\u00e9tien se sont livr\u00e9s des batailles id\u00e9ologiques d&rsquo;envergure. Elles pouvaient les conduire jusqu&rsquo;\u00e0 l&rsquo;excommunication. L&rsquo;enjeu des disputes \u00e9tait de taille. Orphelins de la philosophie antique, disqualifi\u00e9e depuis que le christianisme fut d\u00e9clar\u00e9 religion d&rsquo;\u00e9tat et que l&rsquo;Acad\u00e9mie d&rsquo;Ath\u00e8nes fut ferm\u00e9e par l&#8217;empereur Justinien en 529, il leur fallait ordonner et concilier les \u00e9l\u00e9ments scripturaires et la raison.<\/p>\n<\/p>\n<p><p>\tVers le douzi\u00e8me et le treizi\u00e8me si\u00e8cle, ils argument\u00e8rent \u00e0 partir de leurs interpr\u00e9tations du Commentateur. C&rsquo;est ainsi qu&rsquo;\u00e9tait d\u00e9sign\u00e9 Ibn Rochd, l&rsquo;Averro\u00e8s des Latins. Homme de science, m\u00e9decin et juriste, il avait travaill\u00e9 les textes d&rsquo;Aristote en g\u00e9n\u00e9ral pass\u00e9s par le filtre des n\u00e9oplatoniciens sur instruction du calife de Cordoue, Youssef  Abou Yacoub de la dynastie marocaine et berb\u00e8re des Almohades. Pour les historiens soucieux de tracer la tradition \u00ab la\u00efque \u00bb en pays musulman, il leur faudrait verser au dossier l&rsquo;exigence intellectuelle d&rsquo;un prince tout \u00e0 fait orthodoxe et pieux qui invite son ministre de la Justice \u00e0 interroger exhaustivement l&rsquo;uvre d&rsquo;un scientifique pa\u00efen.<\/p>\n<\/p>\n<p><p>\tLes anti-Averro\u00efstes, comme certains Averro\u00efstes d&rsquo;ailleurs, attribu\u00e8rent \u00e0 Ibn Rochd une th\u00e9orie connue comme la double v\u00e9rit\u00e9, celle selon la foi et celle selon la raison. Ils ne l&rsquo;avaient pas lu. Selon toute probabilit\u00e9, ils n&rsquo;ont jamais eu un acc\u00e8s direct au texte du \u00ab Discours d\u00e9cisif sur l&rsquo;accord de la religion et de la philosophie \u00bb. Le Cadi, sorte de juge supr\u00eame, avait \u00e9tabli dans cet ouvrage que le Livre r\u00e9v\u00e9l\u00e9 encourage voire fait obligation aux hommes en ayant la capacit\u00e9, les philosophes et les gens de d\u00e9monstration, d&rsquo;interpr\u00e9ter les versets \u00e9quivoques selon la raison. Il y \u00e9nonce un axiome qui gouverne l&rsquo;\u00e9conomie de l&rsquo;ensemble de sa d\u00e9monstration juridique \u00ab la v\u00e9rit\u00e9 ne peut se contredire et elle porte t\u00e9moignage pour elle-m\u00eame \u00bb. Cependant, pour \u00e9viter la multiplication des sectes, ph\u00e9nom\u00e8ne dont il \u00e9tait le contemporain et qu&rsquo;il d\u00e9plorait, Ibn Rochd recommandait aux autorit\u00e9s politiques de pratiquer une sorte de prophylaxie sociale. Les r\u00e9sultats des travaux des philosophes s&rsquo;ils sont divulgu\u00e9s \u00e0 la masse peu sensible au syllogisme peuvent la d\u00e9router par la rh\u00e9torique dialecticienne vers l&rsquo;impi\u00e9t\u00e9.<\/p>\n<\/p>\n<p><p>\tAverro\u00e8s juriste, fils et petit-fils de juriste, a produit du Droit, science \u00e0 laquelle se sont adonn\u00e9s les Musulmans avec \u00e9nergie et application. Car si le Coran est source du Droit, tous les cas ny figurent pas explicitement d&rsquo;o\u00f9 le n\u00e9cessaire Qyass ou syllogisme juridique. Et c&rsquo;est ainsi que le juge use de sa raison dans l&rsquo;interpr\u00e9tation du Livre Sacr\u00e9.<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;y a pas d&rsquo;antinomie ni de conciliation \u00e0 op\u00e9rer entre un Texte R\u00e9v\u00e9l\u00e9 qui est le Vrai et l&#8217;emploi d&rsquo;instruments logiques de la pens\u00e9e pour le comprendre. Ils sont \u00e0 disposition de l&rsquo;homme pour qu&rsquo;il glorifie l&rsquo;Incommensurable, sens le moins \u00e9loign\u00e9 de l&rsquo;expression rarement comprise ALLAH OU AKBAR&rsquo;. (1)<\/p>\n<\/p>\n<p><p>\tCette invitation \u00e0 la r\u00e9serve  est une v\u00e9ritable  mise en garde contre la vulgarisation scientifique mal conduite surtout en mati\u00e8re religieuse.  Elle a \u00e9t\u00e9 \u00e0 l&rsquo;origine d&rsquo;un mythe d&rsquo;une long\u00e9vit\u00e9 consternante, soutenant un surgeon n\u00e9 avec le d\u00e9veloppement d&rsquo;une litt\u00e9rature orientaliste, le caract\u00e8re fourbe des Arabes, leur double discours. Le r\u00e9gime de v\u00e9rit\u00e9 double est absent chez le Commentateur, mais il a servi les scolastiques et \u00e9col\u00e2tres dans leurs difficult\u00e9s avec la logique. Il leur fallait loger les myst\u00e8res de l&rsquo;Eucharistie, persistance de la substance et transsubstantiation, et la nature de J\u00e9sus homme, Dieu et fils de Dieu dans une seule hypostase ainsi que la Trinit\u00e9 selon les Cat\u00e9gories du Stagirite. Le pouvoir de l&rsquo;intelligence \u00e9tait entre les mains du corps constitu\u00e9 des clercs de l&rsquo;\u00c9glise qui s\u00e9cr\u00e9taient le dogme de concile en concile. D\u00e8s lors qu&rsquo;un Siger de Brabant et un Jean de Jandun r\u00e9cusent la distinction r\u00e9elle de l&rsquo;existence et de l&rsquo;essence, ils demeurent impuissants \u00e0 justifier les fondements de la foi. Cit\u00e9 par le Tribunal de l&rsquo;Inquisition \u00e0 r\u00e9pondre d&rsquo;h\u00e9r\u00e9sie et condamn\u00e9 par la Curie \u00e0 l&rsquo;internement, Siger et bien d&rsquo;autres \u00e0 sa suite n&rsquo;ont eu d&rsquo;autre \u00e9chappatoire que d&rsquo;invoquer la th\u00e9orie d&rsquo;une double v\u00e9rit\u00e9.<\/p>\n<\/p>\n<p><p>\tThomas l&rsquo;Aquinate, adopt\u00e9 par les P\u00e8res de l&rsquo;\u00c9glise, cl\u00f4turera la tentative m\u00e9taphysique scolastique en disjoignant  les couples riv\u00e9s de l&rsquo;essence et de l&rsquo;existence et de mati\u00e8re et puissance, distinction faite par Aristote de fa\u00e7on logique et non dans la r\u00e9alit\u00e9 des \u00c9tants. Au concile de Trente (1545-1563) sa Somme th\u00e9ologique fut plac\u00e9e sur l&rsquo;autel aupr\u00e8s de la Bible. Jusqu&rsquo;en 1912, le Code du Droit canonique fit du Thomisme la doctrine officielle de l&rsquo;\u00c9glise. <\/p>\n<\/p>\n<p><h3>L&rsquo;intellect, cet hors du corps<\/h3>\n<\/p>\n<p><p>\tUn autre proc\u00e8s fut fait au philosophe enturbann\u00e9 de Cordoue.<\/p>\n<\/p>\n<p><p>\tAverro\u00e8s aurait fait \u00e9merger le concept d&rsquo;un Intellect universel et \u00c9ternel pour tous les hommes, lesquels ne serait pas dou\u00e9s chacun de sa propre intelligence. Beaucoup plus ardue est la lecture du Commentaire fait par le philosophe enturbann\u00e9 du \u00ab De anima \u00bb d&rsquo;Aristote. Le texte est tr\u00e8s accident\u00e9 car connu gr\u00e2ce \u00e0 la traduction latine qu&rsquo;en a faite Michel Scott, cinquante ans apr\u00e8s la mort de son auteur. Scott apr\u00e8s un s\u00e9jour en Andalousie s&rsquo;est r\u00e9fugi\u00e9 en Sicile aupr\u00e8s de son m\u00e9c\u00e8ne Fr\u00e9d\u00e9ric II, lui-m\u00eame arabophone et \u00e9rudit dont il devint l&rsquo;astronome attitr\u00e9. Averro\u00e8s \u00e0 son tour commentait non l&rsquo;original mais les interpr\u00e9tations des p\u00e9ripat\u00e9ticiens tardifs, Th\u00e9mistius et Alexandre d&rsquo;Aphrodise. Il fallait bien une triple \u00e9rudition, latine arabe et grecque \u00e0 des m\u00e9di\u00e9vistes pour r\u00e9aliser une r\u00e9troversion vers l&rsquo;arabe depuis le latin m\u00e9di\u00e9val tardif afin d&rsquo;extraire les concepts averro\u00efstes.<\/p>\n<\/p>\n<p><p>\tEn effet, \u00e0 l&rsquo;examiner de pr\u00e8s Averro\u00e8s s&rsquo;av\u00e8re \u00eatre un pr\u00e9curseur en psychologie et en no\u00e9tique. Il a pos\u00e9 quelques jalons qui d\u00e9tr\u00f4nent le sujet d&rsquo;une production purement endog\u00e8ne de sa pens\u00e9e.  Sans d\u00e9poss\u00e9der l&rsquo;homme de son intellect et de ses capacit\u00e9s de cogitation, imagination et rem\u00e9moration anatomiquement d\u00e9j\u00e0 topographi\u00e9es par Gallien, il a contribu\u00e9 \u00e0 d\u00e9centrer le sujet de sa pure subjectivit\u00e9. Averro\u00e8s \u00e9tablit que l&rsquo;Intellect, intelligible lui-m\u00eame fait d&rsquo;intelligibles non corruptibles et s\u00e9par\u00e9s, est incorporel et non nombr\u00e9 selon les individus. Se joignant \u00e0 l&rsquo;intellect agent, il actualise les intelligibles dans l&rsquo;\u00e2me humaine. L&rsquo;acte de pens\u00e9e est la r\u00e9ception de l&rsquo;intelligible mis \u00e0 disposition de la capacit\u00e9 imaginative et m\u00e9morative.<\/p>\n<\/p>\n<p><p>\tL&rsquo;intellect mat\u00e9riel d&rsquo;Averro\u00e8s est donc un univers d&rsquo;intellect en puissance dans lequel \u00ab baignent \u00bb  les intellects des individu\u00e9s humains. Il peut aussi \u00eatre compris comme un intellect global en puissance, inn\u00e9, affect\u00e9 \u00e0 chaque individu qui en fait ce qu&rsquo;il peut en l&rsquo;actualisant par l&rsquo;apprentissage.<\/p>\n<\/p>\n<p><p>\tAinsi la g\u00e9n\u00e9ration de la pens\u00e9e individuelle, corruptible, r\u00e9sulte de la jonction de l&rsquo;Intellect mat\u00e9riel, substance s\u00e9par\u00e9e, avec l&rsquo;Intellect r\u00e9cepteur.<\/p>\n<\/p>\n<p><p>\tIl existe alors un r\u00e9servoir d&rsquo;Intelligibles qui ne sont pas localisables dans l individu. Ils ne lui appartiennent pas en propre, il les saisit \u00e0 la faveur d&rsquo;une rencontre, les assimile par l&rsquo;effort et l&rsquo;exercice.<\/p>\n<\/p>\n<p><p>\tLa part la plus noble de l&rsquo;homme, le n\u00f4us, l&rsquo;intellect, est d&rsquo;origine divine selon Aristote. Ibn Rochd s&rsquo;approprie d&rsquo;autant cette assertion qu&rsquo;elle est en accord avec le sens obvie coranique \u00ab Dieu a insuffl\u00e9 en Adam son \u00e2me \u00bb. La B\u00e9atitude s&rsquo;obtient quand l&rsquo;Intellect humain, no\u00e8me lui-m\u00eame se mire g\u00e9n\u00e9rant des no\u00e8mes.<\/p>\n<\/p>\n<p><p>\tPourtant, cet Intellect mat\u00e9riel r\u00e9manent d&rsquo;Averro\u00e8s et non individuel n&rsquo;appartient pas au Monde des Id\u00e9es \u00e9ternelles platoniciennes.<\/p>\n<\/p>\n<p><p>\tIl est d&rsquo;une certaine permanence et plasticit\u00e9.<\/p>\n<\/p>\n<p><p>\tAverro\u00e8s, outre qu&rsquo;il interroge le substrat du sujet de la pens\u00e9e, pose que l&rsquo;intellection \u00e9chappe \u00e0 la mat\u00e9rialit\u00e9 des corps.<\/p>\n<\/p>\n<p><p>\tL&rsquo;inconscient collectif jungien est-il pr\u00e9figur\u00e9 dans cet Intellect s\u00e9par\u00e9 qui fait penser l&rsquo;homme \u00e0 partir de donn\u00e9es qui ne lui appartiennent pas en propre ?<\/p>\n<\/p>\n<p><p>\tLa structure sociale, les formes de production \u00e9conomique et de reproduction familiale en est-elle une autre qui inscrit la conscience humaine dans un p\u00e9rim\u00e8tre dont il n&rsquo;a pas la ma\u00eetrise ?<\/p>\n<\/p>\n<p><p>\tUn mat\u00e9rialisme vulgaire traquera la pens\u00e9e dans des circuits neuronaux, dans l&rsquo;activit\u00e9 c\u00e9r\u00e9brale \u00e9lectrique propag\u00e9e selon un influx, dans les neurotransmetteurs largu\u00e9s puis captur\u00e9s. Elle n&rsquo;y est pas r\u00e9ductible.  Le d\u00e9veloppement des imageries c\u00e9r\u00e9brales les plus sophistiqu\u00e9es appel\u00e9es \u00e0 la rescousse par les programmes \u00e9tasunien et europ\u00e9en d&rsquo;exploration de l&rsquo;enc\u00e9phale  en vue, c&rsquo;est \u00e0 craindre avec un certain degr\u00e9 de certitude, d&rsquo;un contr\u00f4le total de l&rsquo;individu isol\u00e9 dans des ensembles- ne viendra pas \u00e0 bout de ce qu&rsquo;est l&rsquo;intellection.<\/p>\n<h3>Les r\u00e9alit\u00e9s multipli\u00e9es pour un intellect en simulacre <\/h3>\n<\/p>\n<p><p>\tPour Averro\u00e8s (Cordoue 1126 &#8211; Marrakech 1198) en bon logicien, la dialectique des rh\u00e9toriciens et des th\u00e9ologiens se fonde sur des pr\u00e9misses de l&rsquo;ordre de l&rsquo;opinion, m\u00eame partag\u00e9e par tous. Elle obtient l&rsquo;assentiment du plus grand public sur une opinion et non sur un fait ou une assertion av\u00e9r\u00e9. Le philosophe, en l&rsquo;homme de science ne peut se contenter de raisonnements inductifs d&rsquo;une faible intensit\u00e9 d\u00e9monstrative. L&rsquo;assentiment peut d\u00e8s lors s&rsquo;obtenir sur des fausses pr\u00e9misses.<\/p>\n<\/p>\n<p><p>\tQuand Ibn Rochd dans son Grand Commentaire sur le Livre III du de Anima d&rsquo;Aristote a explor\u00e9, comme il l&rsquo;a fait dans d&rsquo;autres ouvrages et opuscules, la nature de la facult\u00e9 rationnelle de l&rsquo;homme, il ne pouvait imaginer que s&rsquo;organiserait plusieurs si\u00e8cles plus tard la fabrique d&rsquo;un consentement g\u00e9n\u00e9ralis\u00e9 de l&rsquo;humanit\u00e9 \u00e0 un discours imagin\u00e9 par quelques-uns. <\/p>\n<\/p>\n<p><p>\tL&rsquo;homme individu\u00e9 incorpore des images mises en circulation \u00e0 son intention ; elles deviennent le r\u00e9servoir de sa pens\u00e9e&rsquo; excentr\u00e9e doublement. L&rsquo;homme n&rsquo;intellecte pas, il int\u00e8gre des segments et des s\u00e9quences \u00e9labor\u00e9s par des centres \u00ab ex machina \u00bb qu&rsquo;il saisit par ses facult\u00e9s sensorielle \u00e9motive et imaginative et auxquels il accorde son assentiment.<\/p>\n<\/p>\n<p><p>\tPh\u00e8dre de Platon est une uvre de jeunesse qui d\u00e9nonce l&rsquo;\u00e9criture coupable de pr\u00e9senter un discours qui une fois fix\u00e9 sous une forme rigide n&rsquo;est plus d\u00e9fendu de fa\u00e7on vivante devant un auditoire par son auteur et est donc susceptible de d\u00e9formations et d&rsquo;incompr\u00e9hension. Ce dialogue socratique condamne bien avant l invention de l&rsquo;imprimerie le poison ou pharmakon d&rsquo;une transmission et diffusion du savoir exc\u00e9dant l&rsquo;oralit\u00e9. Jacques Derrida l&rsquo;avait largement comment\u00e9 dans son texte la Pharmacie de Platon paru la premi\u00e8re fois en 1968 dans la revue Tel Quel. L&rsquo;engouement outre atlantique pour Derrida, vient de son anti-structuralisme qui a \u00e9t\u00e9 \u00e0 son insu l&rsquo;amorce du mouvement antimat\u00e9rialiste et surtout antimarxiste lequel a fait d\u00e9river le petit monde intellectuel europ\u00e9en et l&rsquo;a jet\u00e9 dans l&rsquo;id\u00e9ologie de la diss\u00e9mination dilution de l&rsquo;\u00e9mancipation humaine r\u00e9duite \u00e0 l&rsquo;\u00e9chelle  de petits groupes communautaires. (2)<\/p>\n<\/p>\n<p><p>\tApr\u00e8s l&rsquo;imprimerie, le cin\u00e9matographe a pris en charge la rh\u00e9torique persuasive. Michel Desmurget chercheur au CNRS prend \u00e0 sa fa\u00e7on en l&rsquo;absence d&rsquo;un Socrate la description des <a href=\"https:\/\/www.youtube.com\/watch?v=NvMNf0Po1wY\" class=\"gen\">effets d\u00e9l\u00e9t\u00e8res<\/a> de la t\u00e9l\u00e9vision sur les capacit\u00e9s d&rsquo;intellection des enfants qui en subissent les programmes.  Les Intellects individu\u00e9s sont immerg\u00e9s dans le grand bain du Discours Courant.<\/p>\n<\/p>\n<p><p>\tDepuis quelques d\u00e9cennies, et de fa\u00e7on r\u00e9guli\u00e8re, avec un d\u00e9calage temporel de plus en plus limit\u00e9, nous apprenons que des instances organisent des opinions \u00e9lev\u00e9es au statut de v\u00e9rit\u00e9s \u00e0 l&rsquo;usage du commun.<\/p>\n<\/p>\n<p><p>\tRaymond Aron, le comp\u00e9titeur de Jean Sartre qui a int\u00e9gr\u00e9 la rue d&rsquo;Ulm un an avant lui, avait \u00e9t\u00e9 bel et bien \u00e9t\u00e9 recrut\u00e9 par la CIA, \u00e0 l&rsquo;instar de nombreux autres intellectuels qui ont promu une intelligence du monde sous l&rsquo;enseigne de la Libert\u00e9. Il a \u00e9t\u00e9 charg\u00e9 de co-animer le <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Congr\u00e8s_pour_la_libert\u00e9_de_la_culture\" class=\"gen\">Congr\u00e8s International pour la Libert\u00e9 de la culture<\/a> cr\u00e9\u00e9 \u00e0 Berlin en 1950 et domicili\u00e9 \u00e0 Paris. Actif dans 37 pays, dirig\u00e9 par un agent de la CIA, il a recrut\u00e9 un tr\u00e8s grand nombre d&rsquo;intellectuels engag\u00e9s dans la guerre id\u00e9ologique contre le communisme r\u00e9duit \u00e0 un totalitarisme. Aron n&rsquo;a pas \u00e9t\u00e9 seulement un philosophe au sens chercheur de v\u00e9rit\u00e9 ou de sagesse au sens antique ou humaniste, il a \u00e9t\u00e9 \u00e9ditorialiste au Figaro puis \u00e0 l&rsquo;Express et chroniqueur \u00e0 Europe 1. Bien avant que le journaliste allemand <a href=\"http:\/\/www.dedefensa.org\/article-journalisme_made_in_cia_iv_les_deux_mondes_de_udo_ulfkotte_27_10_2014.html\" class=\"gen\">Udo Ulfkotte<\/a> du Frankfurter Allgemeine Zeitung ne publie son livre o\u00f9 est relat\u00e9e par le menu la manipulation des m\u00e9dias grand public, d\u00e8s 1967, par de multiples organisations \u00e9tasuniennes.<\/p>\n<\/p>\n<p><p>\tOn peut retrouver dans Plaidoyer pour une Europe d\u00e9cadente  de Raymond Aron publi\u00e9 en 1977 (\u00e0 la veille des \u00e9lections l\u00e9gislatives en 1978 o\u00f9 la gauche m\u00eame d\u00e9sunie risquait de gagner dans un contexte de stagflation) la source des id\u00e9es d\u00e9clinistes d\u00e9fendues par les atlantistes fran\u00e7ais, laudateurs de Reagan et Thatcher. La r\u00e9duction de l&rsquo;id\u00e9e du communisme, la mise en commun pour le profit de tous des moyens de production mais aussi la d\u00e9cision par tous de la nature de la production des moyens de vie et de subsistance des humains, \u00e0 un totalitarisme conduisant in\u00e9vitablement au Goulag a \u00e9volu\u00e9 au point de transformer le capitalisme sauvage en seul horizon possible. Le triomphe de la Libert\u00e9 contre la justice et l\u00e9galit\u00e9 fut d&rsquo;autant plus complet que l&rsquo;URSS s&rsquo;est effondr\u00e9e.<\/p>\n<\/p>\n<p><p>\tL&rsquo;avocastre <LIEN=http:\/\/www.dedefensa.org\/article-_declinologue_ou_decliniste_ou_l_hypocrisie_par_la_semantique_17_03_2006.html>Nicolas Baverez promu intellectuel pour sarkozystes reprenait avec all\u00e9gresse que la menace suicidaire pour la France est sa tol\u00e9rance pour le syndicalisme et l&rsquo;encadrement dans des r\u00e8gles l\u00e9gales du capitalisme. La crise \u00e9conomique et financi\u00e8re de 2008 d&rsquo;un genre nouveau, sous forme d&rsquo;une surproduction de la Dette, non encore jugul\u00e9e \u00e0 ce jour, a peine \u00e0 att\u00e9nuer leur d\u00e9fense d&rsquo;un capitalisme sans fronti\u00e8res.<\/p>\n<h3>Ceci est beau, suite donn\u00e9e \u00e0 la quiddit\u00e9 improbable d&rsquo;une pipe<\/h3>\n<\/p>\n<p><p>\tLa mise en circulation d&rsquo;un Intellect usin\u00e9 d&rsquo;Intelligibles, petits moteurs historiques actionnant le mental des masses, par des intellectuels mercenaire et quelques autres suiveurs aveugles ne se limite pas \u00e0 fournir un mod\u00e8le social sans l&rsquo;accompagner de sa propre esth\u00e9tique.<\/p>\n<\/p>\n<p><p>\tPendant plus de vingt ans, la CIA a d\u00e9velopp\u00e9 comme arme puissante de la Guerre froide l&rsquo;art conceptuel et abstrait des Rothko et Pollock.<\/p>\n<\/p>\n<p><p>\tElle a financ\u00e9 Nelson Rockefeller, alors \u00e0 la direction du MOMA de New York, pour organiser des expositions de l&rsquo;expressionnisme abstrait et contribuer \u00e0 le faire coter artificiellement chez les galli\u00e9ristes, les mus\u00e9es et riches collectionneurs. Ainsi furent impos\u00e9s le co\u00fbt et le go\u00fbt de \u00ab Blanc sur Blanc \u00bb et de quelques traces pigment\u00e9es sur toiles parfois d\u00e9chir\u00e9es.<\/p>\n<\/p>\n<p><p>\tAinsi furent m\u00e9pris\u00e9s les B\u00e9otiens qui ne voyaient dans cet art  que d\u00e9g\u00e9n\u00e9rescence, escroquerie intellectuelle et absence de substance.<\/p>\n<\/p>\n<p><p>\tL&rsquo;ali\u00e9nation de l&rsquo;esprit humain se faisait sous l&#8217;embl\u00e8me tot\u00e9mique \u00ab <a href=\"http:\/\/www.zerohedge.com\/news\/2015-05-15\/you-buy-rothko-how-cia-covertly-nurtured-modern-art-cold-war-weapon\" class=\"gen\">free enterprise painting<\/a> \u00bb.<\/p>\n<\/p>\n<p><h3>Usinage continu de r\u00e9els juxta r\u00e9els<\/h3>\n<\/p>\n<p><p>\tLa grande acquisition des ann\u00e9es Nouvel Observateur, Tel Quel et autres organes d&rsquo;\u00e9dition et de presse influents, par le jeu de la D\u00e9construction D\u00e9structuration, est la fragmentation de la pens\u00e9e politique. D\u00e9sormais, elle se limite \u00e0 la mise en avant de particularismes socio-ethniques qui effacent la compr\u00e9hension du Syst\u00e8me, un capitalisme livr\u00e9 \u00e0 son mouvement propre.<\/p>\n<\/p>\n<p><p>\tSes agents travaillent \u00e0 \u00e9laborer une r\u00e9plique d\u00e9natur\u00e9e de toute d\u00e9fense du corps social asservi. Leurs outils de pr\u00e9dilection dans un geste continu de retournement dialectique du moindre affleurement contradictoire sont les ONG et associations de d\u00e9fense de communaut\u00e9s d\u00e9tach\u00e9es de leur socle national.<\/p>\n<\/p>\n<p><p>\tElles b\u00e9n\u00e9ficient de financements g\u00e9n\u00e9reux et d&rsquo;entra\u00eenement de faiseurs d&rsquo;opinion et d&rsquo;aspirants-dirigeants. Elles pullulent et infiltrent tout le tissu social.<\/p>\n<\/p>\n<p><p>\tSyndicats, associations de d\u00e9fense des locataires d&rsquo;HLM, comit\u00e9s de lutte contre l&rsquo;islamophobie, pas une niche de la contestation potentielle de l&rsquo;ordre n&rsquo;est omise.<\/p>\n<\/p>\n<p><p>\tOuvertement, l&rsquo;Open Society Institute de Georges Soros accorde quelques pr\u00e9bendes au <a href=\"http:\/\/www.liberation.fr\/societe\/2013\/09\/20\/les-figures-montantes-du-militantisme-musulman_933591\" class=\"gen\">CCIF<\/a> (comme elle a p\u00e9n\u00e9tr\u00e9 le mouvement de jeunesse s\u00e9n\u00e9galais <a href=\"http:\/\/oeildafrique.com\/yen-a-marre-filimbi-balai-citoyen-une-jeunesse-africaine-recuperee-par-le-milliardaire-americain-george-soros\/\" class=\"gen\">Y en a marre<\/a>) pour le compte de l&rsquo;USAID. Dans les banlieues fran\u00e7aises, il tient bourse ouverte pour des associations qui soutiennent les victimes du d\u00e9lit de faci\u00e8s.<\/p>\n<\/p>\n<p><p>\tLes \u00c9tats sont une entrave pour les multinationales sans patrie, les nations avec une forte tradition une g\u00eane pour le transnationalisme capitaliste qui pr\u00e9tend les dissoudre dans une totale anomie. <\/p>\n<\/p>\n<p><p>\tAl Qa\u00efda, Jabhat Al Nosra, Daesh sont des versions successives  d&rsquo;une r\u00e9alit\u00e9 fabriqu\u00e9e par des centres de confection sur mesure d&rsquo;instruments qui alt\u00e8rent le monde et la facult\u00e9 de le percevoir. Il est des Syriens qui croient sinc\u00e8rement que Daesh est une cr\u00e9ation de Bachar el Assad, comme il en est d&rsquo;autres qui le voient comme un mouvement de Lib\u00e9ration Nationale.<\/p>\n<\/p>\n<p><p>\tSur quelles pr\u00e9misses fonder une quelconque v\u00e9rit\u00e9 quand la r\u00e9alit\u00e9 s&rsquo;\u00e9vanouit, fantomatique, remplac\u00e9e par une r\u00e9alit\u00e9 seconde issue du fantasme de quelques clercs cyniques ou idiots. Face \u00e0 cela, le doute m\u00e9thodologique doit s&rsquo;appliquer \u00e0 tous les faits et toutes les donn\u00e9es, mais ne risque-t-il pas de rendre impossible tout jugement ?<\/p>\n<\/p>\n<p><p>\tLa R\u00e9alit\u00e9 seconde ou parall\u00e8le est une entit\u00e9 holistique qui, une fois amorc\u00e9e, g\u00e9n\u00e8re ses \u00e9v\u00e8nements et les servants qui l&rsquo;entretiennent. Seules des violences historiques de grande ampleur peuvent d\u00e9chirer le temps et faire advenir de tels adventices. L&rsquo;ind\u00e9pendance fut rendue \u00e0 l&rsquo;Inde selon les conditions d&rsquo;une partition foment\u00e9e par les Britanniques, accompagn\u00e9e de luttes fratricides meurtri\u00e8res et de d\u00e9placements de populations enti\u00e8res. Sans le concours du Pakistan pas d&rsquo;Al Qa\u00efda, pas de Moudjahidin et absence de toute les s\u00e9quences d\u00e9riv\u00e9es, incluse la com\u00e9die surr\u00e9aliste de Abbottabad. Pas de Daesh non plus. <\/p>\n<\/p>\n<p><p>\tLe r\u00e9gime de la v\u00e9rit\u00e9 fabriqu\u00e9e ne peut r\u00e9sister face \u00e0 la permanence de la passion humaine inextinguible pour la v\u00e9rit\u00e9 et la justice. C&rsquo;est une des manifestations de la part divine insuffl\u00e9e dans l&rsquo;humain.<\/p>\n<\/p>\n<p><p>\tTant que l&rsquo;humanit\u00e9 subsiste. Ayant eu un d\u00e9but, elle peut tout aussi bien dispara\u00eetre.  Elle uvre activement  pour faire advenir les conditions de son extinction.<\/p>\n<\/p>\n<p><p>\tLa philosophie m\u00e9di\u00e9vale, en particulier arabe, ne se limite pas \u00e0 un enfermement totalitaire dans une th\u00e9ologie dogmatique. Ses philosophes pouvaient se tromper, leurs erreurs sont pardonnables. Ils s&rsquo;attelaient en effet inlassablement \u00e0 la recherche de la v\u00e9rit\u00e9. Leur qu\u00eate m\u00e9taphysique et scientifique pourrait \u00e9clairer de leur pieuse sinc\u00e9rit\u00e9 cette modernit\u00e9 plong\u00e9e dans un long cr\u00e9puscule en d\u00e9pit de ses lumi\u00e8res artificielles. <\/p>\n<\/p>\n<p>\n<p class=\"signature\">Badia Benjelloun<\/p>\n<\/p>\n<h4>Notes<\/h4>\n<p>(1) Litt\u00e9ralement, Dieu est encore plus grand.<\/p>\n<\/p>\n<p><p>\tOu encore, quel que soit x, f\u00fbt-il tr\u00e8s grand, Dieu est encore plus grand. D&rsquo;o\u00f9 l&rsquo;Incommensurabilit\u00e9.<\/p>\n<\/p>\n<p><p>\t(2)  La Diss\u00e9mination Seuil Points septembre 1993.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Petite g\u00e9n\u00e9alogie de la double v\u00e9rit\u00e9 Les th\u00e9ologiens m\u00e9di\u00e9vaux de l&rsquo;Occident chr\u00e9tien se sont livr\u00e9s des batailles id\u00e9ologiques d&rsquo;envergure. Elles pouvaient les conduire jusqu&rsquo;\u00e0 l&rsquo;excommunication. L&rsquo;enjeu des disputes \u00e9tait de taille. Orphelins de la philosophie antique, disqualifi\u00e9e depuis que le christianisme fut d\u00e9clar\u00e9 religion d&rsquo;\u00e9tat et que l&rsquo;Acad\u00e9mie d&rsquo;Ath\u00e8nes fut ferm\u00e9e par l&#8217;empereur Justinien en&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3280,16706,3953,3104,3696,3090,5445],"class_list":["post-75948","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-aron","tag-averroes","tag-benjelloun","tag-cia","tag-double","tag-influence","tag-verite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75948"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75948\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}