{"id":75966,"date":"2015-06-23T16:06:34","date_gmt":"2015-06-23T16:06:34","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/06\/23\/quelques-mots-sur-laccointance-nouvelle-moscou-ryad\/"},"modified":"2015-06-23T16:06:34","modified_gmt":"2015-06-23T16:06:34","slug":"quelques-mots-sur-laccointance-nouvelle-moscou-ryad","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/06\/23\/quelques-mots-sur-laccointance-nouvelle-moscou-ryad\/","title":{"rendered":"Quelques mots sur l&rsquo;accointance nouvelle Moscou-Ryad"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Quelques mots sur l&rsquo;accointance nouvelle Moscou-Ryad<\/h3>\n<\/p>\n<p><p>\tComme d&rsquo;habitude,  personne n&rsquo;a rien vu venir (\u00ab<em>No one  as usual &#8211; saw it coming<\/em>\u00bb) &#8230; C&rsquo;est ainsi que P\u00e9p\u00e9 Escobar salue (le <a href=\"http:\/\/sputniknews.com\/columnists\/20150622\/1023689645.html#ixzz3dri3RWmT\" class=\"gen\">23 juin 2015<\/a>, sur <em>Sputnik.News<\/em>) l&rsquo;annonce d&rsquo;une nouvelle entente, cette fois entre la Russie et l&rsquo;Arabie saoudite \u00e0 l&rsquo;occasion du Davos de l&rsquo;Est, le SPIEF ou <em>Saint-Petersburg Economic Forum<\/em>. (Voir le <a href=\"http:\/\/www.dedefensa.org\/article-l_isolement_progresse_grand_accord_arabie-russie_et_poutine_invit_ryad_21_06_2015.html\" class=\"gen\">21 juin 2015<\/a>.) Effectivement, la nouvelle a pris tout le monde de cours, tellement que beaucoup parmi ce tout le monde-l\u00e0 n&rsquo;en ont pas dit grand&rsquo;chose, sinon pas un mot. Tout juste si Fabius a demand\u00e9 \u00e0 consulter une carte, pour voir o\u00f9 se situe l&rsquo;Arabie d&rsquo;une part, la Russie d&rsquo;autre part, tout en se demandant comment Assad continue \u00e0 exister malgr\u00e9 l&rsquo;interdiction qui lui avait \u00e9t\u00e9 signifi\u00e9e (par Fabius le m\u00eame) de ne plus exister.<\/p>\n<\/p>\n<p><p>\tP\u00e9p\u00e9 ne porte pas la maison des Saoud dans son cur. Manifestement, lui aussi a \u00e9t\u00e9 surpris, mais comme tous les antiSyst\u00e8me il r\u00e9agit selon la seule r\u00e9f\u00e9rence solide dont il dispose,  Poutine et la Russie, en l&rsquo;occurrence,  et conduit son commentaire avec tout le pragmatisme n\u00e9cessaire d\u00e8s lors qu&rsquo;il peut avoir cette r\u00e9f\u00e9rence comme base de sa r\u00e9flexion. De ce point de vue, il observe que l&rsquo;accord, s&rsquo;il se confirme, s&rsquo;il est substantiv\u00e9 par des actes, contient de tr\u00e8s nombreuses opportunit\u00e9s d&rsquo;avanc\u00e9es pour Moscou, au d\u00e9triment de l&rsquo;Empire du Chaos (on aura compris qui Escobar d\u00e9signe par son expression favorite). Il termine avec ce qu&rsquo;il faut de prudence, mais aussi en admettant que l&rsquo;Arabie, dans l&rsquo;\u00e9tat d&rsquo;incertitude et de d\u00e9stabilisation o\u00f9 elle se trouve, peut fort bien jouer le jeu russe \u00e0 fond et qu&rsquo;on se trouve alors, effectivement, devant des possibilit\u00e9s insoup\u00e7onn\u00e9es&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>It remains to be seen, long-term, whether this is not a desperate Saudi play to extract concessions from its imperial protector. But assuming this is a real deal, Moscow retains the ability to match both Iran and Saudi Arabia&rsquo;s interests, and ensure this concerted pivoting to the Middle East may turn out to be as spectacular as Russia&rsquo;s pivoting to Asia and China&rsquo;s New Silk Roads. There is no evidence so far to attest that the House of Saud has conclusively seen which way the wind is blowing, that is, towards the 21st century Silk Road Eurasian caravan, no matter any exceptionalist wishful thinking to the contrary.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>They are fearful; they are paranoid; they are vulnerable; and they need new friends. No one better than Putin  and Russian intelligence  to play the new groove in multiple ways. The House of Saud can hardly be trusted; see the latest, Wikileaks-released, Saudi cables. So this may turn out to be a geopolitical\/geoeconomic bonanza. But it can also be a case of keeping your friends close, and your enemies closer.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tOn recueille diff\u00e9rents commentaires int\u00e9ressants, plut\u00f4t de commentateurs r\u00e9gionaux que de la part de commentateurs du bloc BAO. Ces derniers restent \u00e0 la fois stup\u00e9faits de la possible dimension de la rencontre et de l&rsquo;\u00e9ventuelle entente, et m\u00e9prisants pour toute nouvelle entreprise qui ne vient pas de leur camp ; ils ressentent de toutes les fa\u00e7ons cette rencontre, d\u00e9j\u00e0 sans aucun doute dans le champ de la communication, comme une \u00e9pouvantable insulte inflig\u00e9e \u00e0 la feuille de route de la <em>narrative<\/em> du triomphe-Syst\u00e8me du bloc am\u00e9ricaniste-occidentaliste. <\/p>\n<\/p>\n<p><p>\t On notera le commentaire de Abdulrahman al-Rashed, sur le r\u00e9seau anglais de <em>Al-Arabiya<\/em>, la station de TV saoudienne, le <a href=\"http:\/\/english.alarabiya.net\/en\/views\/news\/middle-east\/2015\/06\/20\/The-Russians-are-coming-to-Saudi-Arabia.html\" class=\"gen\">20 juin 2015<\/a>. Journaliste de grande renomm\u00e9e internationale, al-Rashed est l&rsquo;ancien <em>General Manager<\/em> de <em>Al Arabiya News Channel<\/em> justement, et un ancien r\u00e9dacteur-en-chef de quotidien saoudien bas\u00e9 \u00e0 Londres, <em>Asharq al-Awsat<\/em>. Ces diverses r\u00e9f\u00e9rences font de lui un commentateur bien proche de la maison des Saoud, et l&rsquo;on retiendra alors comme un signe significatif que tout son commentaire exsude d&rsquo;abord une rancune peu ordinaire \u00e0 l&rsquo;encontre des USA, rancune nettement inspir\u00e9e par la cause sunnite et la fureur saoudienne.<\/p>\n<\/p>\n<p><p>\tAinsi observe-t-il sur un ton furieux que les USA ont soutenu Bagdad malgr\u00e9 sa politique sectaire et ont laiss\u00e9 le r\u00e9gime d&rsquo;Assad susciter la plus grande trag\u00e9die de l&rsquo;histoire de la r\u00e9gion avec 250 000 morts et 10 millions de r\u00e9fugi\u00e9s ; l\u00e0-dessus, il pr\u00e9sente le rapprochement de Ryad de la Russie, pourtant d\u00e9nonc\u00e9e encore en mars dernier par l&rsquo;Arabie comme impardonnable soutien d&rsquo;Assad, comme un \u00e9v\u00e9nement d&rsquo;une extr\u00eame importance qui marque d&rsquo;abord une sorte de d\u00e9claration d&rsquo;ind\u00e9pendance du royaume des Saoud \u00e0 l&rsquo;\u00e9gard des consignes du bloc BAO\/des USA, et notamment des consignes \u00e0 l&rsquo;encontre de la Russie dans l&rsquo;affaire ukrainienne&#8230; Dans tous les cas, al-Rashed pr\u00e9dit que l&rsquo;on ira loin sur la route de la coop\u00e9ration avec la Russie, simplement parce qu&rsquo;aujourd&rsquo;hui la Russie est un acteur essentiel de la situation politique dans la r\u00e9gion,  plus essentiel que les USA ? Tout le monde comprend entre les lignes que cette question est diablement pos\u00e9e, et que la r\u00e9ponse ne d\u00e9pend plus des automatismes du pass\u00e9&#8230; <\/p>\n<\/p>\n<p><p>\t\u00ab<em>In my opinion, the most important feature of the Deputy Crown Prince&rsquo;s visit was that it was not customary; it took place at a time when the United States and its European allies decided to economically boycott Russia, sanctioning Moscow over events in Ukraine. This time, the Saudi government took an unusual step and decided to do the opposite: rekindle its relations with Moscow, grow business ties, and sign agreements and deals in vital fields such as gas and nuclear and military technologies. This is one of the rare times that Riyadh takes an opposing line to Washington. But the reason is clear: the Saudis who supported the Western position to boycott Iran for 20 years discovered that Washington betrayed them when it decided to collaborate with Tehran, without coming to an understanding with its partners who had joined the initial boycott!<\/em> [&#8230;] <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Although Saudi Arabia reinstated its relationship with Moscow nearly 14 years ago, it has remained limited. No important promises of cooperation had been implemented so far: Saudi Arabia did not buy Scud missiles as agreed, and Russia did not get anything out of the gas deals. However today, it appears that the MoscowRiyadh road has become more active. Russia&rsquo;s ambassador to Riyadh, Oleg Ozerov, has said that Russia has been granted an area of land to build the new headquarters of the embassy in Riyadh&rsquo;s Diplomatic Quarter. In Moscow, President Vladimir Putin reiterated his call to Saudi King Salman bin Abdulaziz to visit Russia. President Putin has also received an invitation to visit Riyadh.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Saudi Arabia wants Russia, which is a key player in Syria, Yemen and Lebanon, to be on its side. Russia plays an important role in the military balance with Iran, a task that will need intensive and incessant efforts.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Tout le monde se rappelle la pr\u00e9c\u00e9dente tentative de rapprochement entre les USA et l&rsquo;Arabie, qui avait pris le visage un tantinet satanique de Prince <a href=\"http:\/\/www.dedefensa.org\/article-de_poutine-bandar_l_gypte_et_la_syrie_24_08_2013.html\" class=\"gen\">Bandar<\/a>. A cette \u00e9poque, la Syrie \u00e9tait la priorit\u00e9 de l&rsquo;Arabie,  car, d\u00e9couvre-t-on en lisant Bruce Riedel, directeur de l&rsquo;<em>Intelligence Project<\/em> \u00e0 la Brookings Institution, dans son article du <a href=\"http:\/\/www.al-monitor.com\/pulse\/originals\/2015\/06\/saudi-crown-prince-russia-deals.html\" class=\"gen\">21 juin 2015<\/a> dans <em>Al Monitor<\/em>, que la Syrie n&rsquo;est plus la priorit\u00e9 saoudienne&#8230; (Syria is not <D>[<em>Saudi Deputy Crown Prince Mohammed bin Salman&rsquo;<\/em>] <em>priority. He wants help in Yemen where the war is stalemated.<\/em> [&#8230;] <em>The Russian option is good for Mohammed&rsquo;s image as a global player&#8230;<\/em>.\u00bb) Aujourd&rsquo;hui, Bandar est oubli\u00e9, d&rsquo;autant plus que les conditions sont si diff\u00e9rentes, parce que l&rsquo;Arabie est en position de faiblesse par rapport \u00e0 Moscou.<\/p>\n<\/p>\n<p><p>\tIl semble bien \u00e9tonnant de poser ce constat, alors que la sph\u00e8re am\u00e9ricaniste-occidentaliste ne cesse de r\u00e9sonner des ricanements joyeux concernant l&rsquo;isolement de la Russie. Le Docteur Theodore Karasik, directeur de recherche de l&rsquo;<em>Institute for Near East and Gulf Military Analysis<\/em> \u00e0 Douba\u00ef, observe les choses d&rsquo;un il bien diff\u00e9rent puisque, si l&rsquo;on r\u00e9sume son article dans <em>Azeri Daily<\/em> du <a href=\"http:\/\/azeridaily.com\/analytics\/8119\" class=\"gen\">22 juin 2015<\/a>, on observera qu&rsquo;il conclut quasiment que la Russie est sur le point de prendre la place des USA comme arbitre de la situation dans la r\u00e9gion, et que l&rsquo;Arabie a pris acte de cette r\u00e9alit\u00e9 &#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The visit of Saudi Deputy Crown Prince Mohammed bin Salman to meet with Russian President Vladimir Putin in St. Petersburg is extraordinary and politically significant.<\/em> [&#8230;] <em>Unlike Prince Bandar&rsquo;s approach, Arab and Russian interlocutors are noting that Mohammed bin Salman is approaching Moscow in a weakened position.<\/em> [&#8230;] <em>Hence, the Saudis see Russia in the role of negotiator on all political questions. Russia&rsquo;s relations with multiple sides in the Yemen and Syrian conflict is of utmost importance. If successful, Russia stands to gain substantially at the expense of the United States. The Kingdom&rsquo;s engagement policy with the Russians may indeed produce peace dividends and further alter the geopolitical landscape.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tKarasik, de son poste de Douba\u00ef, dispose \u00e9videmment de nombreuses et pr\u00e9cieuses indications, qu&rsquo;il nous fait partager directement ou indirectement. Son analyse des causes du rapprochement entre l&rsquo;Arabie et la Russie, est tr\u00e8s d\u00e9taill\u00e9e, et d\u00e9taill\u00e9e du point de vue de l&rsquo;Arabie parce que, d\u00e9cid\u00e9ment, <strong>c&rsquo;est l&rsquo;Arabie qui est demanderesse<\/strong>. Un point nous a paru particuli\u00e8rement int\u00e9ressant, en rapprochant deux indications que nous donne Karasik concernant une situation tr\u00e8s sensible ; effectivement rapproch\u00e9es, ces deux indications nous permettent de d\u00e9velopper une analyse extr\u00eamement int\u00e9ressante sur un point pr\u00e9cis des questions de s\u00e9curit\u00e9, qui fait de plus en plus de d\u00e9g\u00e2ts dans les pays arabes par rapport aux USA. Karasik donne d&rsquo;abord des d\u00e9tails tr\u00e8s pr\u00e9cis et d&rsquo;un grand int\u00e9r\u00eat sur la situation saoudienne dans le conflit du Y\u00e9men, et sur les rapports tr\u00e8s peu  satisfaisants de l&rsquo;Arabie avec les USA \u00e0 cet \u00e9gard &#8230; L\u00e0 aussi, il est question d&rsquo;un tr\u00e8s net d\u00e9sengagement US de la r\u00e9gion.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Saudi Arabia, under the so-called Salman Doctrine, is facing increasing challenges.  An Arab official told me that, in his opinion, the Houthis are increasing their presence&rsquo; in the Kingdom&rsquo;s southern provinces of Najran and Jizan, and that Houthi SCUD missiles are making their way through the defensive shields provided by the Americans, notably the PAC-3 system. To the North, Saudi proxy fighters in Syria are facing complications because of Turkish and Qatari support networks. That Riyadh sees Moscow as a necessity now is a geo-political reality. Putin knows this fact and said as much to Turkish President Recep Tayyip Erdogan stop playing a double game&rsquo; when they met in Baku last week.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Saudis are waking up to the fact that the Kremlin&rsquo;s influence in Iran, Syria and Yemen is a strategic asset. Another Arab official told me that the Kingdom is in strategic over-stretch and not receiving the support it needs from the United States. To be sure, America is providing intelligence for Saudi air strikes but the Obama Administration is clearly withdrawing from the region on a political level, uncommitted to any serious action in the Arab world.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tUn peu plus loin, Karasik rend compte d&rsquo;une visite la semaine derni\u00e8re de la d\u00e9l\u00e9gation saoudienne \u00e0 l&rsquo;exposition militaire Arm\u00e9e 2015 qui se tient \u00e0 Moscou, et de l&rsquo;int\u00e9r\u00eat des Saoudiens pour du mat\u00e9riel militaire russe,  rien moins, parmi les syst\u00e8mes cit\u00e9s, que des syst\u00e8mes de d\u00e9fense a\u00e9rienne S-300 et S-400 et des missiles sol-sol \u00e0 courte\/moyenne port\u00e9e jusqu&rsquo;\u00e0 500kilom\u00e8tres (\u00e0 capacit\u00e9s nucl\u00e9aires pour les Russes) SS26 <em>Iskander<\/em>-E. Dans l&rsquo;extrait de l&rsquo;article cit\u00e9 ci-apr\u00e8s, on notera une remarque (soulign\u00e9 par l&#8217;emploi du gras par nous) qui nous para\u00eet int\u00e9ressante &#8230; \u00ab<em>Another salient Saudi group that visited Russia this past week was from Mohammed bin Salman&rsquo;s Ministry of Defence. The Saudi military delegation went to the Kubinka international military-technical forum Army 2015.&rsquo; The Saudis are interested in negotiating both defensive and offensive weapon systems including the S-300 and\/or the S-400 air defence systems and also the Russian tactical missile complex Iskander-E.<\/em><strong><em> Russian sources told me that the Saudis seem desperate to buy new systems from a reliable seller.<\/em><\/strong>\u00bb<\/p>\n<\/p>\n<p><p>\tOn comparera alors cette observation que les Saoudiens cherchent des fournisseurs fiables de syst\u00e8mes d&rsquo;armes avec le fait mentionn\u00e9 plus haut que les missiles <em>Scud<\/em> tir\u00e9s par les Houthis du Y\u00e9men contre des objectifs en Arabie semblent ne pas \u00eatre tous arr\u00eat\u00e9s par la d\u00e9fense a\u00e9rienne saoudienne, assur\u00e9e en fait par des batteries de missiles <em>Patriot<\/em> PAC-3, d&rsquo;origine US et mani\u00e9es par du personnel US. On a alors le choix entre deux hypoth\u00e8ses, les deux pouvant d&rsquo;ailleurs \u00eatre chacune valables selon les situations : l&rsquo;inefficacit\u00e9 du <em>Patriot<\/em> d&rsquo;une part, ce qui <a href=\"http:\/\/www.dedefensa.org\/article-d_une_guerre_du_golfe_l_autre_la_fable_virtualiste_du_patriot_21_04_2003.html\" class=\"gen\">n&rsquo;est pas<\/a> une surprise ; la manipulation de l&#8217;emploi (ou du non-emploi) des syst\u00e8mes d&rsquo;armes US par les servants US, selon les int\u00e9r\u00eats politiques US. (Le deuxi\u00e8me point a eu un pr\u00e9c\u00e9dent r\u00e9cent, avec la commande <em>Rafale<\/em> par l&rsquo;\u00c9gypte [voir le <a href=\"http:\/\/www.dedefensa.org\/article-face_au_jsf_le_rafale_est_un_non-_tre_07_05_2015.html\" class=\"gen\">7 mai 20215<\/a>] : \u00ab<em>Lors de l&rsquo;attaque conjointe, notamment avec des forces a\u00e9riennes d&rsquo;\u00c9gypte et des EAU, contre la Libye \u00e0 l&rsquo;\u00e9t\u00e9 2014, les \u00c9miratis avaient l&rsquo;intention d&rsquo;utiliser leurs F-16. Il y eut alors une intervention US des plus brutales, allant jusqu&rsquo;\u00e0 une intervention directe de techniciens US qui rendirent les F-16 inutilisables pour les pilotes \u00e9miratis. Sisi rapporta la fureur des \u00c9miratis et expliqua qu&rsquo;il ne pouvait admettre une telle situation potentielle pour son compte, pour ses propres F-16, et qu&rsquo;il se tournait donc vers les Fran\u00e7ais dont il savait par exp\u00e9rience et par r\u00e9putation qu&rsquo;ils respectent les souverainet\u00e9s des pays acheteurs.<\/em>\u00bb) Tout cela (les USA et leur barda d&rsquo;armes \u00e0 la technologie mesur\u00e9e en $milliards) ne semble pulserais fiable pour les amis saoudiens&#8230;<\/p>\n<\/p>\n<p><p>\t Karasik termine son analyse d&rsquo;une mani\u00e8re tranchante, en mettant effectivement en \u00e9vidence deux points : 1) le tournant des relations entre l&rsquo;Arabie et la Russie est d&rsquo;une extr\u00eame importance, et 2) il a lieu comme une reconnaissance par un des acteurs centraux de la r\u00e9gion (l&rsquo;Arabie) du r\u00f4le fondamental que tient la Russie au Moyen-Orient, r\u00f4le encore plus fondamental d\u00e9sormais, avec ces nouvelles relations entre l&rsquo;Arabie et la Russie. Dans ce monde \u00e9trange o\u00f9 les actes les plus divers semblent parfois compl\u00e8tement mis en forme par la seule perception, il y a bien entendu un monde de diff\u00e9rence entre la situation actuelle et, disons, la situation de d\u00e9cembre 2014 o\u00f9 il se clamait partout que l&rsquo;Arabie avait fait cause commune avec les USA, en manipulant le prix du p\u00e9trole, pour travailler \u00e0 un effondrement qu&rsquo;on pr\u00e9voyait ultra-rapide,  l&rsquo;affaire de quelques semaines, quoi,  de l&rsquo;\u00e9conomie russe&#8230;<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Overall, the Saudi-Russian relationship is taking off in a new direction of cooperation. But it is clear  for now  that the Saudis need Russia more than the other way around. That is a significant change that guarantees that the Kremlin will be a major player in the future security and economic development of the Middle East, whether the West likes it or not.  Cooperation is across almost every major sector and it is likely to extend to mitigating a mutual nightmare for both countries:  The Islamic State.&rsquo; Stay tuned.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t&#8230; Ainsi le paysage moyen-oriental se nuance-t-il,  d\u00e9cisivement ? Fondamentalement ? Il est bien trop t\u00f4t pour le dire et peut-\u00eatre m\u00eame n&rsquo;est-ce pas la bonne question, d&rsquo;autant qu&rsquo;il est en principe difficile d&rsquo;attendre d&rsquo;une nuance un prolongement fondamental. (Mais on ne sait jamais, par les temps qui courent si vite, peut-\u00eatre un nuance peut-elle faire basculer un monde, si elle s&rsquo;exprime au bon moment, et au bon endroit&#8230; M\u00eame dans ce cas, la retenue est de rigueur.) Tout au plus pourra-t-on juger, mais ce n&rsquo;est pas rien, que le d\u00e9sordre-<a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_hyperd_sordre_d_sordre_et_chaos_16_02_2015.html\" class=\"gen\">hyperd\u00e9sordre<\/a> du monde continue sa course folle et majestueuse, avec l&rsquo;extr\u00eame difficult\u00e9 de fixer les positions, de distinguer les alliances, de classer les uns et les autres en amis-ennemis et, surtout, de distinguer quelque plan ou Grand Jeu que ce soit. Tout au plus pourrait-on jouer \u00e0 calculer ou \u00e0 deviner ce que les nouveaux rapports entre la Russie et l&rsquo;Arabie entra\u00eeneraient comme redistribution chaotique dans les relations de soutien et d&rsquo;antagonisme au sein de la myriade d&rsquo;acteurs du d\u00e9sordre de la r\u00e9gion. Tenons-nous-en \u00e0 l&rsquo;amusante interrogation d\u00e9j\u00e0 vue dans le texte <a href=\"http:\/\/www.dedefensa.org\/article-l_isolement_progresse_grand_accord_arabie-russie_et_poutine_invit_ryad_21_06_2015.html\" class=\"gen\">r\u00e9f\u00e9renc\u00e9<\/a> de savoir si, un jour, l&rsquo;Arabie ne demanderait pas \u00e0 rejoindre les BRICS&#8230; L&rsquo;action ou l&rsquo;inaction, c&rsquo;est selon, de Empire du Chaos cher \u00e0 P\u00e9p\u00e9 Escobar et \u00e0 ses sarcasmes continue \u00e0 semer son lot d&rsquo;effets et de cons\u00e9quences inattendues et impr\u00e9vues, qui se retournent g\u00e9n\u00e9ralement contre celui qui les a enfant\u00e9s par le souci habituel de l&rsquo;inversion.<\/p>\n<\/p>\n<p><p>\tTout de m\u00eame&#8230; La position inflexible de la Russie par rapport \u00e0 certains principes fondamentaux, particuli\u00e8rement ceux de la souverainet\u00e9 et de la l\u00e9gitimit\u00e9, constitue dans ce tourbillon furieux la seule position que l&rsquo;on puisse accorder \u00e0 la sagesse. Bien plus que les coups g\u00e9opolitiques, que les d\u00e9clarations tonitruantes, que les grandes envol\u00e9es sur les valeurs, que les le\u00e7ons de morale, c&rsquo;est cela qui donne \u00e0 ce pays cette fermet\u00e9 qui fait qu&rsquo;\u00e0 un moment ou l&rsquo;autre l&rsquo;on se tourne vers lui tandis que le bloc BAO ne cesse de jacasser \u00e0 propos de son isolement (celui de la Russie). Ce n&rsquo;est pas pour rien que l&rsquo;un des exemples politiques de Poutine est de Gaulle, l&rsquo;homme des principes, et ainsi la Russie donne-t-elle en permanence \u00e0 la pauvre France \u00e9puis\u00e9e par le poids des stup\u00e9fiantes incomp\u00e9tences de ses \u00e9lites-Syst\u00e8me une le\u00e7on \u00e9vidente de grande politique, par le simple rappel du r\u00f4le que ce pays aurait du tenir puisqu&rsquo;il est capable de produire des personnages (de Gaulle) de cette sorte.<\/p>\n<\/p>\n<p><p>\tL&rsquo;on n&rsquo;ira pas plus loin. Ce nouvel avatar de la situation moyenne-orientale met par-dessus tout en \u00e9vidence la situation g\u00e9n\u00e9rale d&rsquo;incontr\u00f4labilit\u00e9 et d&rsquo;impr\u00e9visibilit\u00e9 des relations internationales, par cons\u00e9quent la puissance plus que jamais d\u00e9cha\u00een\u00e9e de la Crise G\u00e9n\u00e9rale d&rsquo;effondrement du Syst\u00e8me. Ce constat n&rsquo;a rien de particuli\u00e8rement audacieux ni d&rsquo;original. Il ne fait que confirmer l&rsquo;orientation prise,  d\u00e9cisivement, cette fois on peut s&rsquo;aventurer \u00e0 le dire,  depuis au moins la grande crise financi\u00e8re de l&rsquo;automne 2008 encha\u00eenant presque aussit\u00f4t sur le printemps arabe et le reste.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 23 juin 2015 \u00e0 16H09<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quelques mots sur l&rsquo;accointance nouvelle Moscou-Ryad Comme d&rsquo;habitude, personne n&rsquo;a rien vu venir (\u00abNo one as usual &#8211; saw it coming\u00bb) &#8230; C&rsquo;est ainsi que P\u00e9p\u00e9 Escobar salue (le 23 juin 2015, sur Sputnik.News) l&rsquo;annonce d&rsquo;une nouvelle entente, cette fois entre la Russie et l&rsquo;Arabie saoudite \u00e0 l&rsquo;occasion du Davos de l&rsquo;Est, le SPIEF ou&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2996,16729,5667,3934,3356,2651,708,4900,12773,6582,16731,12798,2707,3246,3600,916,8053,16730,3867,9076],"class_list":["post-75966","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-alliance","tag-aravie","tag-bandar","tag-chaos","tag-desordre","tag-du","tag-empire","tag-escobar","tag-hyperdesordre","tag-iskander","tag-karasik","tag-mohammed","tag-moscou","tag-moyen-orient","tag-petrole","tag-poutine","tag-renversement","tag-saoul","tag-syrie","tag-yemen"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75966"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75966\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}