{"id":75977,"date":"2015-06-29T14:25:00","date_gmt":"2015-06-29T14:25:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/06\/29\/pour-vaincre-le-systeme-il-faut-vouloir-etre-antisysteme\/"},"modified":"2015-06-29T14:25:00","modified_gmt":"2015-06-29T14:25:00","slug":"pour-vaincre-le-systeme-il-faut-vouloir-etre-antisysteme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/06\/29\/pour-vaincre-le-systeme-il-faut-vouloir-etre-antisysteme\/","title":{"rendered":"Pour vaincre le Syst\u00e8me, il faut vouloir \u00eatre antiSyst\u00e8me"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Pour vaincre le Syst\u00e8me, il faut vouloir \u00eatre antiSyst\u00e8me<\/h2>\n<\/p>\n<p><p>C&rsquo;est Ho Chi Minh, l'\u00a0\u00bbOncle Ho\u00a0\u00bb, qui, en 1945, \u00e9non\u00e7a la doctrine dite de l'\u00a0\u00bbennemi principal\u00a0\u00bb. Entre les Fran\u00e7ais et les Chinois, Ho d\u00e9termina que les Chinois \u00e9taient les plus dangereux parce qu&rsquo;ils mena\u00e7aient d&rsquo;absorber le Vietnam (alors partie de l&rsquo;Indochine) tandis que les Fran\u00e7ais tentaient de s&rsquo;en d\u00e9gager dans des conditions honorables, qui sauvegarderaient certains de leurs int\u00e9r\u00eats et de leur influence, en tentant d&rsquo;installer des directions qui leur seraient proches ou avec lesquelles ils auraient de bonnes relations. Cette doctrine \u00ab\u00a0tactique\u00a0\u00bb sacrifiait momentan\u00e9ment des objectifs qui pourraient plus tard \u00eatre repris. Pour les Fran\u00e7ais, avec Leclerc en mission en Indochine,la doctrine permettait d&rsquo;engager des pourparlers avec le Vietminh, avec l&rsquo;espoir d&rsquo;\u00e9viter un conflit qui mena\u00e7ait de leur co&ucirc;ter beaucoup, &ndash; ce qui, si l&rsquo;op\u00e9ration avait r\u00e9ussi, aurait transform\u00e9 l&rsquo;aspect \u00ab\u00a0tactique\u00a0\u00bb de cette doctrine en un accomplissement strat\u00e9gique. Finalement, les pourparlers \u00e9chou\u00e8rent et la guerre d&rsquo;Indochine devenait alors in\u00e9vitable. Il n&#8217;emp\u00eache que la doctrine de l'\u00a0\u00bbennemi principal\u00a0\u00bb, qui rassemble, selon d&rsquo;ailleurs une technique vieille comme le monde, des partis adverses au nom d&rsquo;un int\u00e9r\u00eat sup\u00e9rieur qui leur est commun, avait prouv\u00e9 toute sa justification et devenait un mod\u00e8le pour nombre de circonstances.<\/p>\n<\/p>\n<p><p>Nous sommes, aujourd&rsquo;hui, entre partis divers de tendance antiSyst\u00e8me, plac\u00e9s dans des circonstances approchantes qui m\u00e9ritent qu&rsquo;on envisage la doctrine de l'\u00a0\u00bbennemi principal\u00a0\u00bb. Cela est d&rsquo;autant plus vrai que jamais, au grand jamais dans l&rsquo;histoire, un \u00ab\u00a0ennemi principal\u00a0\u00bb n&rsquo;a autant figur\u00e9 comme tel, et m\u00eame comme irr\u00e9ductible \u00ab\u00a0ennemi principal\u00a0\u00bb, que ne le figure aujourd&rsquo;hui le Syst\u00e8me. Divers \u00e9pisodes en cours mettent en \u00e9vidence cette circonstance. Nous en choisissons deux parmi tant d&rsquo;autres et nous commen\u00e7ons par le moins pressant <strong>pour l&rsquo;instant<\/strong> et nous poursuivrons par le plus \u00ab\u00a0chaud\u00a0\u00bb, le plus pressant, qui est l&rsquo;affaire grecque. L&rsquo;on verra que, dans cette approche comparative, la le\u00e7on de la doctrine de l'\u00a0\u00bbennemi principal\u00a0\u00bb s&rsquo;adresse essentiellement aux Europ\u00e9ens, et encore plus pr\u00e9cis\u00e9ment aux Fran\u00e7ais.<\/p>\n<\/p>\n<p><p>&bull; Retenons d&rsquo;abord l&rsquo;affaire \u00ab\u00a0des trait\u00e9s\u00a0\u00bb, &ndash; pas seulement le TTIP, si fameux en Europe, mais \u00e9galement le TPP, particuli\u00e8rement d&rsquo;actualit\u00e9 aux USA, et aussi le TISA, troisi\u00e8me trait\u00e9 moins connu qui est pourtant le plus terrible de cette affreuse trilogie. L&rsquo;Am\u00e9ricain Kevin Zeese d\u00e9finit les trois trait\u00e9s de cette fa\u00e7on, avec pour nous l&rsquo;accent sur le troisi\u00e8me, TISA (<em>Trade and services agreement<\/em>), qui est le moins connu et le plus d\u00e9vastateur des trois :<\/p>\n<\/p>\n<p><p>&laquo;<em>That&rsquo;s each of the three big treaties that Obama&rsquo;s currently negotiating. TPP&rsquo;s going to be the first one, Trans-Pacific Partnership. Covers all the global Pacific except for China, they&rsquo;re excluded. And there&rsquo;s the Atlantic version<\/em> [TTIP] <em>that&rsquo;s being negotiated with Europe right now. In a lot of trouble in Europe, the Europeans are fighting about that very aggressively and there&rsquo;s not going to be as much unity there as there is in the Pacific. And then the bigger one, the most important one I think, is the Trade and Services Agreement, called TISA. Fifty countries. Services is 80 percent of our economy and includes everything from postal services, which they want to privatize, educational services, health services, accounting services, financial services, water, food, all these services are going to be part of that one. That&rsquo;s the big one, that&rsquo;s going to be the third one, most likely.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Kevin Zeese est l&rsquo;organisateur d&rsquo;un lobby, <em>PopularResistence.org<\/em> (un lobby peut \u00eatre, doit \u00eatre vertueux selon notre conception, s&rsquo;il est utilis\u00e9 dans un sens antiSyst\u00e8me). Zeese est avocat, il a servi dans l&rsquo;\u00e9quipe de campagne \u00e9lectorale de Ralph Nader en 2004, il a travaill\u00e9 dans le parti ind\u00e9pendant. Il a \u00e9t\u00e9 candidat pour le S\u00e9nat des USA en 2006, ayant r\u00e9ussi l&rsquo;exploit de recevoir l&rsquo;investiture du <em>Green Party<\/em> (gauche populiste) du parti libertarien (extr\u00eame-droite traditionniste) et du parti populiste (rassemblement populiste droite-gauche). Il est interrog\u00e9 par Paul Jay, de la cha&icirc;ne TV TRNN (<em>The Real News Network<\/em>), interview reprise le <a class=\"gen\" href=\"http:\/\/www.flushthetpp.org\/choreographed-corruption-passes-fast-track-but-not-over-yet\/\">26 juin 2015<\/a> sur <em>FlushTheTPP.org<\/em>. Voici le passage o&ugrave; Zeese d\u00e9crit la version US de la th\u00e9orie de l'\u00a0\u00bbennemi principal\u00a0\u00bb, dans les positions et les votes qui ont eu lieu et qui auront lieu au Congr\u00e8s, concernant le TPP. (Malgr\u00e9 les votes qui ont donn\u00e9 la <em>Fast-Track Authority<\/em> \u00e0 Obama, la bataille, extr\u00eamement complexe, n&rsquo;est pas finie, comme Zeese l&rsquo;explique par ailleurs dans l&rsquo;interview&#8230; ) (Nous mettons en gras l&rsquo;une ou l&rsquo;autre formule qui nous para&icirc;t importante.)<\/p>\n<\/p>\n<p><p><strong><em>Jay<\/em><\/strong> : &laquo;<em>Okay, just a final&#8230; quickly. Some of the no votes, it&rsquo;s kind of a strange alliance here. You have on one side people like Sherrod Brown, maybe Elizabeth Warren. On the other side you have Rand Paul, Ted Cruz, Marco Rubio. Very different interests, one would think. But these people are voting no. why?<\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zeese<\/em><\/strong> : &laquo;<em>Well, it&rsquo;s really a debate between<\/em><strong><em> the populists and the elitists<\/em><\/strong><em>. It&rsquo;s really a debate<\/em><strong><em> between people and money<\/em><\/strong><em>, and that&rsquo;s really what the dividing line is. And I think someone like Ted Cruz, while he of course raises money for his presidential campaign, he also has a populist kind of piece of the Republican side. Sherrod Brown is certainly a populist on the Democrat side. So is Elizabeth Warren and Bernie Sanders. And so it really is that kind of division. It&rsquo;s more about money. <\/em><strong><em>Do you put money first, or people first?<\/em><\/strong><em> And that&rsquo;s really what it comes down to.<\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Jay<\/em><\/strong> : &laquo;<em>Ted Cruz puts people before money?<\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zeese<\/em><\/strong> : &laquo;<em>He does, for his party. I mean, for people on the, who are Conservative, they see Ted Cruz as fighting for what their populist beliefs are, so yes.<\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Jay<\/em><\/strong> : &laquo;<em>Some people are suggesting Cruz and Rubio, it&rsquo;s primarily they don&rsquo;t want to give Obama any more power. That&rsquo;s what it&rsquo;s mostly<\/em>&#8230; [inaud.]&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zeese<\/em><\/strong> : &laquo;<em>That&rsquo;s one of the aspects of this. Is that&#8230; and a lot of members of Congress, Harry Reid for example, they don&rsquo;t want to give more power to the executive at any time, because this is really a shift of power from the Constitution. The Commerce Clause says the Congress has the power to regulate trade between nations. And people don&rsquo;t think we should be shifting that power to the President. With the Republicans right now there&rsquo;s also the personal view. They don&rsquo;t like President Obama, they don&rsquo;t trust President Obama, and so they don&rsquo;t want to give it to him, as well. But there&rsquo;s also a general view that we should really have the Congress playing their role and not giving up their Constitutional power to any president. And so I think that&rsquo;s part of it, but it&rsquo;s also personal.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Retenez ces formules, parce qu&rsquo;elles ont leur r\u00e9elle valeur, avec une signification simple et d\u00e9cisive : \u00ab\u00a0un d\u00e9bat entre les \u00e9litistes et les populistes\u00a0\u00bb (\u00ab\u00a0\u00e9litistes\u00a0\u00bb pour les \u00e9lites-Syst\u00e8me, populistes pour le reste, le peuple, les 99%, c&rsquo;est-\u00e0-dire potentiellement ceux qui <strong>devraient \u00eatre<\/strong> antiSyst\u00e8me) ; \u00ab\u00a0un d\u00e9bat entre les gens et l&rsquo;argent\u00a0\u00bb ; un d\u00e9bat en forme de question : \u00ab\u00a0Placez-vous votre priorit\u00e9 d&rsquo;abord dans l&rsquo;argent ou d&rsquo;abord dans les gens ?\u00a0\u00bb Et les personnalit\u00e9s (tous des s\u00e9nateurs ayant vot\u00e9 \u00ab\u00a0non\u00a0\u00bb au TPP, dans ce cas) que Zeese installe sur la m\u00eame de ligne de pens\u00e9e, qui \u00ab\u00a0placent leur priorit\u00e9 d&rsquo;abord dans les gens plut\u00f4t que dans l&rsquo;argent\u00a0\u00bb, vont de l&rsquo;ind\u00e9pendant pseudo-socialiste-Saunders, de la d\u00e9mocrate-progressive Warren, au r\u00e9publicain-libertarien Rand Paul, aux r\u00e9publicains populistes Cruz et Rubio.<\/p>\n<\/p>\n<p><p>La question qui se pose aux Europ\u00e9ens, et notamment au Parlement Europ\u00e9en qui est directement concern\u00e9 par ces trait\u00e9s qui portent un bouleversement tellurique sans pr\u00e9c\u00e9dent de toute notre civilisation, est de savoir si eux aussi sont capables de transgresser les lignes de s\u00e9paration entre tel groupe et tel groupe, s&rsquo;ils sont capables, pour certains d&rsquo;entre eux, d&rsquo;envoyer au diable les consignes-Syst\u00e8me qui \u00ab\u00a0d\u00e9monisent\u00a0\u00bb une partie d&rsquo;entre d&rsquo;autres, &ndash; tout cela emp\u00eachant de cr\u00e9er une alliance fondamentale contre l'\u00a0\u00bbennemi principal\u00a0\u00bb ? (Il est stup\u00e9fiant de constater combien peu parmi les hommes politiques, y compris \u00e0 tendance antiSyst\u00e8me ou avec profession de foi antiSyst\u00e8me, comprennent que les d\u00e9monisations de type soci\u00e9tal et id\u00e9ologique constituent l&rsquo;exercice favori de manipulation du Syst\u00e8me pour alimenter la discorde chez l&rsquo;adversaire, chez les antiSyst\u00e8me.)<\/p>\n<\/p>\n<p><p>&bull; Bien entendu, la m\u00eame situation r\u00e8gne, les m\u00eames anath\u00e8mes veillent, les m\u00eames regroupements attendent d\u00e9sesp\u00e9r\u00e9ment de se faire dans l&rsquo;affaire de la crise grecque qui, aujourd&rsquo;hui, secoue l&rsquo;Europe, &ndash; <em>ditto<\/em> \u00ab\u00a0les institutions\u00a0\u00bb, selon Tsipras, &ndash; pour les jours qui viennent, dans une occurrence de rupture que personne n&rsquo;aurait imagin\u00e9e possible il y a seulement six mois. La crise grecque met \u00e0 nu tous les m\u00e9canismes, l&rsquo;autoritarisme, la volont\u00e9 de puissance et d&rsquo;entropisation que constitue l&rsquo;UE, appendice europ\u00e9aniste du bloc am\u00e9ricano-europ\u00e9aniste. (Comme nous \u00e9crivions ce <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_renaissance_de_la_trag_die_28_06_2015.html\">28 juin 2015<\/a>, \u00e0 propos de la Gr\u00e8ce face au Syst\u00e8me, car il ne s&rsquo;agit pas d&rsquo;autre chose : &laquo;<em>Qu&rsquo;elle sache, quoi qu&rsquo;il en soit, qu&rsquo;elle nous a d\u00e9j\u00e0 beaucoup donn\u00e9s, en nous r\u00e9v\u00e9lant que non seulement le roi est nu, mais qu&rsquo;il ne cache m\u00eame plus qu&rsquo;il est nu, qu&rsquo;il se fout d&rsquo;\u00eatre nu, que sa nudit\u00e9 est le moyen d&rsquo;accomplir ses desseins d&rsquo;assassinat du monde, que sa nudit\u00e9 mortelle est bien le destin qu&rsquo;il nous r\u00e9serve.<\/em>&raquo;)<\/p>\n<\/p>\n<p><p>Les r\u00e9actions aux \u00e9v\u00e8nements du week-end sont int\u00e9ressantes, d&rsquo;abord quand elles sont particuli\u00e8rement inint\u00e9ressantes, notamment de la part des experts en l\u00e9nification, venus de l&rsquo;UE ou associ\u00e9es (successivement Moscovici [&laquo;<em>Malgr\u00e9 efforts inlassables, #Eurogroupe conclu sans accord. #Gr\u00e8ce doit rester dans zone euro.<\/em>&raquo;], Donald Tusk [M\u00eame chose], Eric Woerth et Benoist Apadou, tous deux de la patrie des gaullistes [successivement &laquo;<em>Sid\u00e9rant comportement de Mr #Tsipras! C&rsquo;est plus dur de gouverner que d&rsquo;\u00eatre populiste&#8230;<\/em>&raquo;, &laquo;<em>J&rsquo;avoue ne pas comprendre la position du gvt grec ! Le bras d&rsquo;honneur aux cr\u00e9anciers qui tentent de sauver la Gr\u00e8ce est surr\u00e9aliste !<\/em>&raquo;]). Ces sornettes sans fin, d&rsquo;une pauvret\u00e9 \u00e0 ne pas croire, doivent d&rsquo;autant mieux \u00e9clairer les r\u00e9actions de cette autre cat\u00e9gorie de personnes que RT-fran\u00e7ais d\u00e9taille, le <a class=\"gen\" href=\"http:\/\/francais.rt.com\/international\/3711-crise-grecque--gouverneurs-bce-cherchent-solution\">29 juin 2015<\/a> : &laquo;<em>Pour Jean-Luc M\u00e9lenchon, du Parti de Gauche, la Gr\u00e8ce fait preuve de dignit\u00e9 face \u00e0 des cr\u00e9anciers carnassiers. A l&rsquo;autre bout de l&rsquo;h\u00e9micycle, le Front National, par la voix de Florian Philippot, le r\u00e9f\u00e9rendum est une \u00ab\u00a0le\u00e7on de d\u00e9mocratie.\u00a0\u00bb De l&rsquo;autre c\u00f4t\u00e9 de la Manche, le leader du parti ind\u00e9pendantiste britannique Ukip appelle la Gr\u00e8ce a regagner sa souverainet\u00e9, dans un message qui se veut supportif. Pour Pablo Iglesias, le leader du parti espagnol Podemos, dont des militants viennent d&rsquo;\u00eatre \u00e9lus maires de Madrid et Barcelone, \u00ab\u00a0Le Fonds mon\u00e9taire international et le gouvernement allemand attaquent la d\u00e9mocratie. Ils d\u00e9truisent le projet politique de l&rsquo;Europe.\u00a0\u00bb L&rsquo;homme politique s&rsquo;est exprim\u00e9 de cette mani\u00e8re face \u00e0 la presse, ajoutant que le FMI voulait \u00ab\u00a0\u00e9trangler la Gr\u00e8ce.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Face aux ectoplasmes pr\u00e9c\u00e9demment consult\u00e9s, qu&rsquo;ont donc en commun ces quelques noms parmi d&rsquo;autres, sinon celui d&rsquo;avoir un \u00ab\u00a0ennemi principal\u00a0\u00bb parfaitement identifi\u00e9, quelque forme qu&rsquo;il prenne pour chacun (on conna&icirc;t la nature exceptionnellement transformatrice du Syst\u00e8me, qui change de visage et d&rsquo;aspect avec une immense maestria). Il nous para&icirc;t \u00e9vident qu&rsquo;il est absolument n\u00e9cessaire que quelque chose, quelque circonstance, quelque coup du sort suscite un rassemblement tactique de ces antiSyst\u00e8me, &ndash; sans se cacher une seconde que l&rsquo;importance du combat est telle que la tactique se transformera vite en strat\u00e9gie, lorsqu&rsquo;il appara&icirc;tra d&rsquo;une fa\u00e7on aveuglante que l'\u00a0\u00bbennemi principal\u00a0\u00bb n&rsquo;est pas une occurrence temporaire et conjoncturelle, mais un facteur absolu et totalement structurel, sinon totalitaire, indiquant la seule bataille qu&rsquo;on puisse concevoir aujourd&rsquo;hui de mener.<\/p>\n<\/p>\n<p><p>Le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-in_extremis__12_04_2012.html\">12 avril 2012<\/a>, nous \u00e9crivions d\u00e9j\u00e0, \u00e0 propos de M\u00e9lenchon, en pleine pr\u00e9sidentielles de 2012 : &laquo;<em>Ainsi rel\u00e8ve-t-on une ambigu\u00eft\u00e9 dans l&rsquo;attitude de M\u00e9lenchon, ambigu\u00eft\u00e9 qu&rsquo;il n&rsquo;est pas le seul \u00e0 porter, qui se marque le plus souvent quand surgit une personnalit\u00e9 politique qui entend affirmer une position de forte substance. Le d\u00e9calage est consid\u00e9rable entre son discours socio-politique int\u00e9rieur, fortement \u00ab\u00a0id\u00e9ologis\u00e9\u00a0\u00bb et proclam\u00e9 partout, et son discours fondamental de \u00ab\u00a0politique de la grande crise\u00a0\u00bb, celui qui nous int\u00e9resse, et qui est dit mezzo voce, pour des oreilles attentives ou incr\u00e9dules. Le premier soul\u00e8ve peut-\u00eatre les foules mais il est d&rsquo;une pauvret\u00e9 inh\u00e9rente \u00e0 l'\u00a0\u00bbid\u00e9ologisation\u00a0\u00bb de notre temps (de droite, de gauche, ou du centre, ou d&rsquo;o&ugrave; que vous le voulez). Malgr\u00e9 les apparences, il joue \u00e0 fond pour le Syst\u00e8me, en perp\u00e9tuant les clivages artificiels qui emp\u00eachent les alliances antiSyst\u00e8me fondamentales. Les attaques de M\u00e9lenchon contre la FN font partie de ce folklore assez vain, r\u00e9ducteur et peu glorieux, et en plus complice du Syst\u00e8me. (Cela nous rappelle une confidence d\u00e9sabus\u00e9e de R\u00e9gis Debray d\u00e9but mai 2002, alors que d&rsquo;immenses manifs&rsquo;, essentiellement de gauche, parcouraient la France contre un Le Pen assur\u00e9 de ne jamais pouvoir gagner ce deuxi\u00e8me tour, et que nous nous interrogions sur la signification et l&rsquo;h\u00e9ro\u00efsme de cette mobilisation : \u00ab\u00a0Qu&rsquo;est-ce que tu veux, chaque g\u00e9n\u00e9ration a besoin de sa guerre d&rsquo;Espagne..\u00a0\u00bb. Les temps ont chang\u00e9, pour ce qui est de l&rsquo;h\u00e9ro\u00efsme.)<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em> &#8230;Ce qui rend d&rsquo;autant plus pr\u00e9cieux et brillant, l&rsquo;autre aspect de l&rsquo;intervention de M\u00e9lenchon, sa \u00ab\u00a0politique de la grande crise\u00a0\u00bb&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Pas un mot \u00e0 retrancher, nous semble-t-il, mais trois ann\u00e9es \u00e0 rajouter tout de m\u00eame, &ndash; et s&rsquo;il n&rsquo;y a pas un mot \u00e0 retrancher, il n&rsquo;y en a malheureusement aucun \u00e0 rajouter dans le sens de l&rsquo;avancement des choses. Depuis 2012, les \u00e9v\u00e8nements se sont extraordinairement aggrav\u00e9s, le Syst\u00e8me attaque aujourd&rsquo;hui absolument \u00e0 visage d\u00e9couvert, sans le moindre souci de la moindre des apparences, avec quelques pi\u00e8tres psychologies aux abois (Moscovici, Tusk) tentant d\u00e9sesp\u00e9r\u00e9ment de garder le visage lisse de l&rsquo;innocence appoint\u00e9e. Devant des \u00e9v\u00e8nements d&rsquo;une telle ampleur, si grands et si importants, si compl\u00e8tement d\u00e9clench\u00e9s par la puissance des forces incontr\u00f4l\u00e9es de la Grande Crise d&rsquo;effondrement du Syst\u00e8me, si au-dessus du <em>sapiens<\/em>-courant que les vacanciers sur la route du soleil ne s&rsquo;aper\u00e7oivent de rien, comment ne parvient-on pas \u00e0 se rassembler pour pr\u00e9senter un front commun lorsqu&rsquo;on poss\u00e8de un peu de conscience de la puissance de cataclysme, &ndash; comment ne parvient-on pas \u00e0 comprendre qu&rsquo;il le faut, et qu&rsquo;il faut avoir les tripes, bref les <em>cojones<\/em> pour le dire leste, de le clamer haut et fort ? Il serait bien temps que les antiSyst\u00e8me soient vraiment antiSyst\u00e8me, puisque, par ailleurs, il est \u00e9crit qu&rsquo;ils n&rsquo;\u00e9chapperont pas \u00e0 leur destin&#8230;<\/p>\n<\/p>\n<p><p>Mis en ligne le 29 juin 2015 \u00e0 14H24<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour vaincre le Syst\u00e8me, il faut vouloir \u00eatre antiSyst\u00e8me C&rsquo;est Ho Chi Minh, l&rsquo;\u00a0\u00bbOncle Ho\u00a0\u00bb, qui, en 1945, \u00e9non\u00e7a la doctrine dite de l&rsquo;\u00a0\u00bbennemi principal\u00a0\u00bb. Entre les Fran\u00e7ais et les Chinois, Ho d\u00e9termina que les Chinois \u00e9taient les plus dangereux parce qu&rsquo;ils mena\u00e7aient d&rsquo;absorber le Vietnam (alors partie de l&rsquo;Indochine) tandis que les Fran\u00e7ais tentaient&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[16746,5825,3081,3841,5824,8315,5826,16743,3140,13422,12786,9014,2895,8549,4070,16744,16377,12708,4495,16745,12709,2828,2609,945],"class_list":["post-75977","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antidsysteme","tag-chi","tag-ennemi","tag-grece","tag-ho","tag-melenchon","tag-minh","tag-moscovici","tag-paul","tag-philippot","tag-populistes","tag-principal","tag-rand","tag-reese","tag-saunders","tag-tisa","tag-tisseras","tag-tpp","tag-traite","tag-trsipras","tag-ttip","tag-tusk","tag-ue","tag-warren"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75977"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75977\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}