{"id":76003,"date":"2015-07-13T10:20:42","date_gmt":"2015-07-13T10:20:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/07\/13\/vertigo\/"},"modified":"2015-07-13T10:20:42","modified_gmt":"2015-07-13T10:20:42","slug":"vertigo","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/07\/13\/vertigo\/","title":{"rendered":"<em>Vertigo<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\"><em>Vertigo<\/em><\/h2>\n<\/p>\n<p><p>13 juillet 2015 &ndash; Il est tr\u00e8s difficile, en ce jour pr\u00e9cis\u00e9ment, apr\u00e8s ce qui s&rsquo;est pass\u00e9 ce week-end \u00e0 Bruxelles, de commencer une analyse de <strong>la situation g\u00e9n\u00e9rale<\/strong> par autre chose que l&rsquo;affaire europ\u00e9enne, &ndash; lorsque et parce que, comme c&rsquo;est notre cas, l&rsquo;on s&rsquo;y trouve en son c&oelig;ur, g\u00e9ographiquement et professionnellement, mais aussi socialement et psychologiquement&#8230; Il le faudrait pourtant parce qu&rsquo;\u00e0 c\u00f4t\u00e9 de cette \u00ab\u00a0crise grecque\u00a0\u00bb \u00e9videmment devenue une Grande Crise europ\u00e9enne, partout grondent les crises et chacune peut autant pr\u00e9tendre potentiellement repr\u00e9senter la catastrophe prioritaire, &ndash; que ce soit en Chine, avec <a class=\"gen\" href=\"http:\/\/sputniknews.com\/business\/20150711\/1024498097.html\">les suites<\/a> du <em>krach<\/em>, en Ukraine o&ugrave; s&rsquo;affirme l&rsquo;<a class=\"gen\" href=\"http:\/\/rt.com\/news\/273253-ukraine-nationalist-battalions-threat\/\">affrontement<\/a> entre <em>Pravy Sektor<\/em> et le pouvoir de Kiev, dans les <a class=\"gen\" href=\"http:\/\/www.washingtontimes.com\/news\/2015\/jul\/9\/dunford-russia-greatest-threat-national-security\/#ixzz3fUB1cMQ6\">relations <\/a> des USA avec la Russie, en &Eacute;gypte qui se trouve face \u00e0 <a class=\"gen\" href=\"http:\/\/www.debka.com\/article\/24732\/US-Israeli-Egyptian-mobile-sensor-fence-projects-to-block-further-ISIS-Mid-East-expansion-\">une pouss\u00e9e<\/a> de l&rsquo;EI\/<em>Daesh<\/em>, aux USA o&ugrave; montent des appels \u00e0 l&rsquo;<a class=\"gen\" href=\"http:\/\/www.unz.com\/pbuchanan\/a-coming-era-of-civil-disobedience\/\">incivisme<\/a>, dans les n\u00e9gociations sur le nucl\u00e9aire iranien o&ugrave; tout accord r\u00e9solvant enfin la crise sera \u00e0 coup s&ucirc;r l&rsquo;objet d&rsquo;une <a class=\"gen\" href=\"http:\/\/rt.com\/usa\/273259-congressional-disapproval-iran-deal\/\">nouvelle crise<\/a> encore plus complexe&#8230; La liste est sans fin et la diversit\u00e9 des causes conjoncturelles et des cons\u00e9quences possibles extr\u00eame ; et notre but devrait \u00eatre, plut\u00f4t que d&rsquo;\u00eatre emprisonn\u00e9 par nos proximit\u00e9s en leur consacrant toute notre attention, de nous servir de nos proximit\u00e9s pour tenter en permanence d&#8217;embrasser la totalit\u00e9, l&rsquo;universalit\u00e9 de la crise g\u00e9n\u00e9rale, de la Grande Crise d&rsquo;effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>L&rsquo;analyse ne doit \u00eatre guid\u00e9e que par la perception d&rsquo;eux-m\u00eames que nous imposent les \u00e9v\u00e8nements plut\u00f4t que pr\u00e9tendre ma&icirc;triser la compr\u00e9hension de ces \u00e9v\u00e8nements par une rationalit\u00e9 imp\u00e9rative qui est n\u00e9cessairement la victime de toutes les faiblesses qui accablent nos psychologies et infectent cette raison (nous parlons de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde-crisis_la_crise_de_la_raison_humaine_29_11_2014.html\">raison-subvertie<\/a>). Aujourd&rsquo;hui, la psychologie est extraordinairement sollicit\u00e9e, que l&rsquo;on s&rsquo;en aper\u00e7oive ou pas qu&rsquo;importe, et il nous semble que resurgit ou simplement se renforce en une nouvelle \u00e9tape, au travers de divers paroxysmes, le ph\u00e9nom\u00e8ne de la <strong>fascination<\/strong>, \u00e0 la fois si justifi\u00e9e par la pression et la conscience des \u00e9v\u00e8nements, \u00e0 la fois si d\u00e9licate \u00e0 cause de ses effets sur la psychologie allant du meilleur au pire ; fascination de la crise, fascination des causes diverses de la crise qui entra&icirc;nerait l&rsquo;autodestruction, fascination du Syst\u00e8me pour son autodestruction, fascination de sa propre destruction. C&rsquo;est un ph\u00e9nom\u00e8ne psychologique qui n&rsquo;est pas appr\u00e9ciable en lui-m\u00eame, qui contient effectivement des \u00e9l\u00e9ments \u00ab\u00a0allant du meilleur au pire\u00a0\u00bb. C&rsquo;est un ph\u00e9nom\u00e8ne qui est devenu un th\u00e8me de notre r\u00e9flexion, &ndash; cette fascination de la crise, cette fascination pour l&rsquo;accomplissement de toutes choses dans cette saison eschatologique, &ndash; qui nous hante depuis longtemps, sur ce site, et sur lequel nous ne cessons de revenir, selon des sujets bien diff\u00e9rents, avec l&rsquo;usage de mots que l&rsquo;on conna&icirc;t bien (outre \u00ab\u00a0fascination\u00a0\u00bb, \u00ab\u00a0Armageddon\u00a0\u00bb, \u00ab\u00a0apocalypse\u00a0\u00bb, \u00ab\u00a0eschatologie\u00a0\u00bb, etc.). Il suffit, comme exemple le plus simple, de piocher dans le moteur de recherche de <em>dedefensa.org<\/em> dans l&rsquo;un ou l&rsquo;autre de ces mots-clefs pour retrouver ce th\u00e8me qui, \u00e0 notre sens, conditionne absolument notre psychologie \u00e0 tous depuis 2007-2008, qu&rsquo;on le r\u00e9alise ou pas.<\/p>\n<\/p>\n<p><p>&#8230; Il suffit d&rsquo;aller voir, en mesurant la tendance qu&rsquo;indiquent les sujets trait\u00e9s, en d\u00e9couvrant leur chronologie, etc., \u00e0 tant de nos textes dont les titres indiquent clairement la pr\u00e9occupation, soit directement, soit indirectement sinon parfois par d\u00e9rision selon le sujet trait\u00e9 &#8230; Il suffit d&rsquo;aller au <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-peur_et_fascination_de_son_propre_an_antissement_22_05_2007.html\">22 mai 2007<\/a> (&laquo;<em>Peur et fascination de son propre an\u00e9antissement<\/em>&raquo;), au <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_apocalypse_propos_05_09_2007.html\">5 septembre 2007<\/a> (&laquo;<em>L&rsquo;apocalypse, \u00e0 propos<\/em>&raquo;), au <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_fascination_de_la_crise_27_12_2007.html\">27 d\u00e9cembre 2007<\/a> (&laquo;<em>La fascination de la crise<\/em>&raquo;), au <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-rationalisation_de_l_apocalypse_ou_desir_de_crise__24_12_2008.html\">24 d\u00e9cembre 2008<\/a> (&laquo;<em>Rationalisation de l&rsquo;apocalypse ou d\u00e9sir de crise<\/em>&raquo;), au <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-une_putain_de_bonne_question__17_02_2010.html\">17 f\u00e9vrier 2010<\/a> (&laquo;<em>Une putain de bonne question<\/em>&raquo;), au <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_fascination_de_la_spirale_de_la_mort_07_09_2011.html\">7 septembre 2011<\/a> (&laquo;<em>La fascination de la spirale de la mort<\/em>&raquo;), au <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-fascination_de_la_civil_war_17_08_2012.html\">17 ao&ucirc;t 2012<\/a> (&laquo;<em>Fascination de la &lsquo;Civil War&rsquo;<\/em>&raquo;), au <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_fascination_d_armageddon_14_03_2014.html\">14 mars 2014<\/a> (&laquo;<em>Notes sur la fascination d&rsquo;Armageddon<\/em>&raquo;), au <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_im-monde_davos_26_01_2015.html\">26 janvier 2015<\/a> (&laquo;<em>L&rsquo;im-Monde \u00e0 Davos<\/em>&raquo;)&#8230;<\/p>\n<\/p>\n<p><p>A notre sens, c&rsquo;est bien de cela, de ce <strong>ph\u00e9nom\u00e8ne psychologique<\/strong> r\u00e9glant notre perception de la Grande Crise g\u00e9n\u00e9rale que parle Emmanuel Todd dans une interview qu&rsquo;il a donn\u00e9e au <em>Soir<\/em> de Bruxelles, le 10 juillet 2015 (repris par <em>Lescrises.fr<\/em> le <a class=\"gen\" href=\"http:\/\/www.les-crises.fr\/on-assiste-a-la-3e-autodestruction-de-leurope-sous-direction-allemande-par-emmanuel-todd\/\">12 juillet 2015<\/a>). Nous choisissons un passage qui se d\u00e9marque d&rsquo;une fa\u00e7on notable de l&rsquo;analyse rationnelle de la situation trait\u00e9e (la Gr\u00e8ce, l&rsquo;Europe, etc.), que Todd fait avec fougue et vigueur dans le reste de l&rsquo;interview, de l&rsquo;appr\u00e9ciation id\u00e9ologique qui l&rsquo;accompagne avec malheureusement les renvois aux clich\u00e9s et lieux communs des d\u00e9bats parisiens qui ne servent qu&rsquo;\u00e0 occulter l&rsquo;essentiel du ph\u00e9nom\u00e8ne, le fondement du drame, la puissance de la trag\u00e9die&#8230; Justement, parce qu&rsquo;il s&rsquo;agit de la Gr\u00e8ce o&ugrave; l&rsquo;on inventa la repr\u00e9sentation de la trag\u00e9die il y a vingt-cinq si\u00e8cles, le terme est absolument n\u00e9cessaire et bienvenu, comme nous l&rsquo;avons d\u00e9j\u00e0 employ\u00e9 de fa\u00e7on sp\u00e9cifique (le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_renaissance_de_la_trag_die_28_06_2015.html\">28 juin 2015<\/a> : &laquo;<em>Notes sur la (re)naissance de la trag\u00e9die<\/em>&raquo;). Pour nous, il est bien s&ucirc;r \u00e9vident dans toute sa puissance symbolique, comme formidable illustrateur de la situation ; et, parlant de la \u00ab\u00a0trag\u00e9die grecque\u00a0\u00bb dont l&rsquo;universalit\u00e9 est connue, justement nous ne parlons pas de la seule Gr\u00e8ce ni de la seule Europe, mais de la Grande Crise eschatologique qui nous bouleverse, &ndash; nous parlons de notre destin g\u00e9n\u00e9ral :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>\u00ab\u00a0La crise grecque va-t-elle devenir une trag\u00e9die ? Ne l&rsquo;est-elle pas d\u00e9j\u00e0 ?\u00a0\u00bb, interrogions-nous en t\u00eate de cette analyse&#8230; C&rsquo;est la Gr\u00e8ce qui a invent\u00e9 la trag\u00e9die telle que nous la connaissons, dans toute la force de son symbole, dans la transcendance, dans sa destin\u00e9e historique repr\u00e9sent\u00e9e dans l&rsquo;art supr\u00eame de la repr\u00e9sentation sc\u00e9nique et symbolique de la destin\u00e9e du monde. Nietzsche fit de La naissance de la trag\u00e9die une fresque assez obscure o&ugrave; il opposait des tendances imm\u00e9moriales \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;histoire de la Gr\u00e8ce des origines pour figurer les grands affrontements de l&rsquo;histoire du monde, &ndash; et du monde de notre temps, par cons\u00e9quent, tant notre temps ressemble aux Derniers Temps d&rsquo;une civilisation aux abois et devenue \u00ab\u00a0contre-civilisation\u00a0\u00bb. Aujourd&rsquo;hui, la Gr\u00e8ce, devenue un petit pays d&rsquo;importance n\u00e9gligeable dans les d\u00e9comptes bureaucratiques et postmodernistes, reprend sa place au centre dans la question de la trag\u00e9die du monde ressuscit\u00e9e.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Voici donc ce passage, d&rsquo;Emmanuel Todd, qui semble s&rsquo;adresser \u00e0 la \u00ab\u00a0crise europ\u00e9enne\u00a0\u00bb extrapol\u00e9e et exprim\u00e9e par la \u00ab\u00a0crise grecque\u00a0\u00bb mais qui, en fait, concerne la grande Crise d&rsquo;effondrement du Syst\u00e8me (avec, soulign\u00e9 par nous, les passages correspondant \u00e0 ce que nous voulons signifier dans notre propos) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>&#8230;L&rsquo;euro est le trou noir de l&rsquo;\u00e9conomie mondiale. L&rsquo;Europe s&rsquo;est obstin\u00e9e dans une attitude d&rsquo;\u00e9chec \u00e9conomique incroyable qui \u00e9voque en fait un \u00e9l\u00e9ment de folie. On est dans l&rsquo;irrationnel et la folie: une sorte d&rsquo;exc\u00e8s de rationalit\u00e9 qui produit un irrationnel collectif. D&rsquo;un c\u00f4t\u00e9, \u00e7a peut encore durer tr\u00e8s longtemps. Mais d&rsquo;un autre c\u00f4t\u00e9, ce que j&rsquo;ai senti, et pas seulement chez les Allemands et chez les Grecs, <\/em><strong><em>c&rsquo;est le d\u00e9but d&rsquo;un vertige, d&rsquo;une attirance par la crise<\/em><\/strong><em>. Personne n&rsquo;ose dire que \u00e7a ne marche pas, personne n&rsquo;ose prendre la responsabilit\u00e9 d&rsquo;un \u00e9chec &ndash; car c&rsquo;est un \u00e9chec ahurissant, l&rsquo;histoire de l&rsquo;euro! &ndash; mais on sent aussi chez les acteurs<\/em><strong><em> une sorte de besoin d&rsquo;en finir. Plut\u00f4t une fin effroyable qu&rsquo;un effroi sans fin<\/em><\/strong><em>. Dans ce cas, la Gr\u00e8ce serait le d\u00e9tonateur. Les gens sont au bord d&rsquo;une prise de conscience du tragique r\u00e9el de la situation. Le tragique r\u00e9el de la situation, c&rsquo;est que l&rsquo;Europe est un continent qui, au XXe si\u00e8cle, de fa\u00e7on cyclique, se suicide sous direction allemande. Il y a d&rsquo;abord eu la guerre de 14, puis la deuxi\u00e8me guerre mondiale. L\u00e0, le continent est beaucoup plus riche, beaucoup plus paisible, d\u00e9militaris\u00e9, \u00e2g\u00e9, arthritique. Dans ce contexte ralenti, comme au ralenti, on est en train sans doute d&rsquo;assister \u00e0 la troisi\u00e8me autodestruction de l&rsquo;Europe, et de nouveau sous direction allemande.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Fascination, certes, et donc les \u00e9v\u00e8nements commandent&#8230; Il devient alors d&rsquo;autant plus imp\u00e9ratif comme nous l&rsquo;avons d\u00e9j\u00e0 sugg\u00e9r\u00e9, si l&rsquo;on veut appr\u00e9cier ces \u00e9v\u00e8nements d&rsquo;une fa\u00e7on rationnelle, de le faire non pas selon nos propres conceptions mais selon ce qu&rsquo;ils (les \u00e9v\u00e8nements) nous pr\u00e9sentent d&rsquo;eux-m\u00eames, et dans ce qu&rsquo;il y a de plus puissant dans ce qu&rsquo;ils nous disent d&rsquo;eux-m\u00eames, puisqu&rsquo;assez puissants jusqu&rsquo;\u00e0 nous capturer dans la fascination. Cela compris et affirm\u00e9, nous pouvons alors d\u00e9velopper notre appr\u00e9ciation, notre analyse et notre jugement, et observer que nous \u00e9prouvons l&rsquo;impression g\u00e9n\u00e9rale, dans la p\u00e9riode actuelle, de nous trouver une fois de plus dans une p\u00e9riode nouvelle, marqu\u00e9e effectivement par un sentiment de vertige (<em>vertigo<\/em>) renouvel\u00e9, et \u00e9videmment li\u00e9 \u00e0 la question de la fascination.<\/p>\n<\/p>\n<p><p>Ce sentiment \u00e0 la signification diffuse mais \u00e0 la tr\u00e8s forte expression d\u00e9sormais a commenc\u00e9 \u00e0 se d\u00e9velopper, selon la perception que nous en avons et selon l&rsquo;analyse que nous en faisons, notamment \u00e0 partir du moment (disons autour de la signature de Minsk2, en f\u00e9vrier 2015) o&ugrave; la crise ukrainienne a commenc\u00e9 \u00e0 sembler changer de nature&#8230; Cette crise au d\u00e9part extr\u00eamement \u00ab\u00a0dure\u00a0\u00bb et pleine de possibilit\u00e9 d&rsquo;affrontements au plus haut niveau entre les plus d\u00e9cisives puissances de la plan\u00e8te (on \u00e9voquait la r\u00e9f\u00e9rence de la crise des missiles de Cuba, d&rsquo;octobre 1962), a sembl\u00e9 commencer \u00e0 changer de nature par d\u00e9litement, par une sorte de dissolution tout en gardant son caract\u00e8re crisique aigu. Il faut du temps pour substantiver de telles impressions. La crise ukrainienne reste toujours aussi forte, aussi centrale, mais elle est devenue moins \u00ab\u00a0dure\u00a0\u00bb dans le sens de la brutalit\u00e9, moins exigeante, moins exclusive ; finalement, il s&rsquo;av\u00e8re qu&rsquo;elle prend sa place en ayant acc\u00e9l\u00e9r\u00e9, renforc\u00e9 et grandi d&rsquo;une fa\u00e7on exceptionnelle le grand courant crisique qui balaie absolument la situation du monde. Finalement ou plut\u00f4t pour l&rsquo;instant puisque rien n&rsquo;est fini tant que la Grande Crise n&rsquo;est pas accomplie, ce qu&rsquo;elle a apport\u00e9 \u00e0 la situation, c&rsquo;est une sorte de d\u00e9sordre baroque, une absence de principe si compl\u00e8te qu&rsquo;on semble \u00e9voluer dans un univers diff\u00e9rent, o&ugrave; se m\u00e9langent des tendances diverses qui semblaient ne jamais devoir resurgir de cette fa\u00e7on si assur\u00e9e ou qui semblent totalement nouvelles (notamment le nazisme, les tourbillons de s\u00e9dition de forces diverses, et jusqu&rsquo;\u00e0 des bruits de \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/russia-insider.com\/en\/politics\/hillarious-interview-ukraine-mp-says-government-being-subverted-gay-conspiracy\/ri8612\">complot<\/a> <em>gay<\/em>\u00ab\u00a0). Quoi qu&rsquo;il en soit, cette crise-l\u00e0 a d\u00e9j\u00e0 apport\u00e9 beaucoup&#8230;<\/p>\n<\/p>\n<p><p>Du coup, l&rsquo;int\u00e9r\u00eat doit se porter sur ce \u00ab\u00a0grand mouvement\u00a0\u00bb que la crise ukrainienne a formidablement renforc\u00e9 mais n&rsquo;a pas annex\u00e9 enti\u00e8rement \u00e0 elle, comme on aurait pu le penser \u00e0 un moment tout au long de f\u00e9vrier \u00e0 d\u00e9cembre 2014 ; et ce grand \u00ab\u00a0mouvement\u00a0\u00bb, certes, c&rsquo;est la Grande Crise de l&rsquo;effondrement du Syst\u00e8me dont certains pourraient juger \u00e9videmment dans la p\u00e9riode actuelle (on a vu combien cela est discutable), qu&rsquo;elle est repr\u00e9sent\u00e9e d&rsquo;une fa\u00e7on \u00e9vidente par la \u00ab\u00a0crise grecque\u00a0\u00bb\/\u00a0\u00bbcrise europ\u00e9enne\u00a0\u00bb en cours. Mais l&rsquo;essentiel reste bien d&rsquo;observer qu&rsquo;avec l&rsquo;accord Minsk2 dans la crise ukrainienne, ce \u00ab\u00a0grand mouvement\u00a0\u00bb a acquis d&rsquo;autres caract\u00e9ristiques, une autre \u00ab\u00a0structure\u00a0\u00bb (dr\u00f4le de mot pour le cas, mais on l&rsquo;utilise pour la facilit\u00e9) ; d&rsquo;autres crises, d\u00e9j\u00e0 en cours, des crises nouvelles, etc., y apparaissent pour tenir leur place mais d&rsquo;une mani\u00e8re diff\u00e9rente en fonction des conditions nouvelles, pour devenir une forme d&rsquo;activit\u00e9 crisique enti\u00e8rement nouvelle&#8230; Il s&rsquo;agit du \u00ab\u00a0tourbillon crisique\u00a0\u00bb que nous avons d\u00e9j\u00e0 commenc\u00e9 \u00e0 consid\u00e9rer, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_m_krach_chinois_s_quence_no_future_du_tourbillon_crisique__10_07_2015.html\">10 juillet 2015<\/a>.<\/p>\n<\/p>\n<p><p>&#8230; Nous nous trouvons, avec ce texte que vous lisez, que nous avons d\u00e9cid\u00e9 de composer justement <strong>\u00e0 cause<\/strong> de la pression de divers \u00e9v\u00e8nements qui mobilisent l&rsquo;attention des r\u00e9sistants antiSyst\u00e8me et des figurants-Syst\u00e8me, etc., que nous avons compos\u00e9 en plusieurs \u00e9tapes justement \u00e0 cause de la pression des \u00e9v\u00e8nements, devant la t\u00e2che redoutable de tenter de lib\u00e9rer les uns et les autres, et de nous lib\u00e9rer nous-m\u00eames, de ces pressions tendant \u00e0 nous enfermer dans un seul sujet, un seul courant d&rsquo;attention, dans une concentration emprisonn\u00e9e. Ce ph\u00e9nom\u00e8ne nous touche, nous en Europe, comme nous l&rsquo;avons signal\u00e9 plus haute, pour ce moment en cours comme s&rsquo;il n&rsquo;y avait que la \u00ab\u00a0crise grecque\u00a0\u00bb\/\u00a0\u00bbcrise europ\u00e9enne\u00a0\u00bb. Bien entendu, il touche les autres de la m\u00eame fa\u00e7on, c&rsquo;est-\u00e0-dire en les isolant dans leurs sujets d&rsquo;int\u00e9r\u00eat (dans \u00ab\u00a0leurs\u00a0\u00bb crises) et en ignorant les autres.<\/p>\n<\/p>\n<p><p>Par exemple, hier matin, le site <em>Antiwar.com<\/em>, si c\u00e9l\u00e8bre et important dans le courant antiSyst\u00e8me et n\u00e9cessairement dans la communication sur les crises, ne publiait dans son catalogue de 79 textes pr\u00e9sent\u00e9s en premi\u00e8re page, pas une seule nouvelle sur la r\u00e9union de l&rsquo;Eurogroupe de samedi \u00e0 Bruxelles o&ugrave; il fut essentiellement question, dans des conditions dramatiques, de la possibilit\u00e9 du fameux <em>Grexit<\/em>. (Tout juste <em>Antiwar.com<\/em> publie-t-il deux informations class\u00e9es en position compl\u00e8tement secondaire, et effectivement secondaires m\u00eame si elles pourraient prendre de l&rsquo;importance, sur la Gr\u00e8ce elle-m\u00eame, l&rsquo;une en corr\u00e9lation avec une relation avec la <a class=\"gen\" href=\"http:\/\/www.independent.co.uk\/news\/world\/europe\/greece-debt-crisis-greece-admits-it-did-sign-a-gas-pipeline-deal-with-russia-10381441.html?printService=print\">Russie<\/a>, l&rsquo;autre avec une <a class=\"gen\" href=\"http:\/\/www.bloomberg.com\/news\/articles\/2015-07-10\/greece-to-keep-nato-ties-even-if-it-exits-euro-stoltenberg-says\">position<\/a> de l&rsquo;OTAN.) Cela n&rsquo;a aucun rapport avec un d\u00e9sint\u00e9r\u00eat sp\u00e9cifique comme par exemple l&rsquo;esprit d&rsquo;isolement des USA, alors qu&rsquo;<em>Antiwar.com<\/em> a dans ses quinze premi\u00e8res ann\u00e9es d&rsquo;activit\u00e9, &ndash; disons jusqu&rsquo;\u00e0 la crise ukrainienne, &ndash; toujours publi\u00e9 des nouvelles qui nous int\u00e9ressaient \u00e9galement, qui correspondaient pr\u00e9cis\u00e9ment au classement des pr\u00e9occupations antiSyst\u00e8me en g\u00e9n\u00e9ral, signalant qu&rsquo;il y avait encore un \u00ab\u00a0sens coh\u00e9rent\u00a0\u00bb et un \u00ab\u00a0centre identifiable\u00a0\u00bb de la situation crisique g\u00e9n\u00e9rale.<\/p>\n<\/p>\n<p><p>&#8230; Dans ce texte que vous lisez, tout se passe comme si nous disions \u00e0 notre lecteur (mais peut-\u00eatre bien \u00e0 nous-m\u00eames \u00e9galement) : \u00ab\u00a0Psst, essayez d&rsquo;abandonner votre prison\/votre camisole de force de la concentration sur un \u00e9v\u00e8nement, pour une r\u00e9flexion plus g\u00e9n\u00e9rale sur ce qui est train de se passer&#8230;\u00a0\u00bb. Faisons donc comme si l&rsquo;on nous avait entendu et comme si nous nous \u00e9tions entendus nous-m\u00eames, l&rsquo;un ou l&rsquo;autre dans tous les cas, et \u00e9tudions la nouvelle situation crisique g\u00e9n\u00e9rale qui constitue \u00e0 la fois la cause de cet enfermement de notre attention, et le moyen de nous sortir de cet enfermement.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Usage et vertus du \u00ab\u00a0tourbillon crisique\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>Pour d\u00e9signer ce ph\u00e9nom\u00e8ne que nous avons d\u00e9crit d&rsquo;accumulation et d&rsquo;activit\u00e9 de crises, et l&rsquo;identifier, on a vu que nous proposons l&rsquo;expression de \u00ab\u00a0tourbillon crisique\u00a0\u00bb, marquant une vitesse rotationnelle en constante augmentation, et qu&rsquo;on peut d\u00e9finir comme un d\u00e9cha&icirc;nement (\u00e0 l&rsquo;image du \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_cha_nement_de_la_mati_re__05_11_2012.html\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00ab\u00a0). (D&rsquo;autres expressions que \u00ab\u00a0tourbillon crisique\u00a0\u00bb seraient possibles : \u00ab\u00a0avalanche crisique\u00a0\u00bb, \u00ab\u00a0ph\u00e9nom\u00e8ne crisique diluvien\u00a0\u00bb, mais ces termes ne rendent pas compte de ce mouvement tournant d&#8217;emprisonnement de l&rsquo;<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_notre_kosmos_crisique__27_03_2013.html\">infrastructure<\/a> <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_facteur_crisique__30_04_2013.html\">crisique<\/a> qu&rsquo;implique le mouvement du tourbillon.)<\/p>\n<\/p>\n<p><p>Pour bien pr\u00e9ciser les choses \u00e0 la suite d&rsquo;une question d&rsquo;un lecteur (\u00ab\u00a0Tourbillon ou chaos\u00a0\u00bb, voir le <em>Forum<\/em> du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/forum-le_krach_chinois_s_quence_no_future_du_tourbillon_crisique__10_07_2015.html\">10 juillet 2015<\/a>), ce que nous \u00e9tudions ici est une dynamique (\u00ab\u00a0tourbillon\u00a0\u00bb) et non un \u00e9tat (\u00ab\u00a0chaos\u00a0\u00bb, &ndash; tout en notant qu&rsquo;en r\u00e9alit\u00e9, nous <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_hyperd_sordre_d_sordre_et_chaos_16_02_2015.html\">privil\u00e9gions<\/a> constamment et explicitement en l&rsquo;\u00e9tat actuel des choses le terme \u00ab\u00a0d\u00e9sordre\u00a0\u00bb sur le terme \u00ab\u00a0chaos\u00a0\u00bb). Cette dynamique a un sens spatial, un fonctionnement bien d\u00e9fini et, surtout, pour notre cas et selon notre analyse, une capacit\u00e9 \u00e0 la fois de r\u00e9unir et de tenir ensemble par la seule force dynamique et non par des affinit\u00e9s, des proximit\u00e9s et des r\u00e9actions de cause \u00e0 effet, des \u00e9v\u00e8nements crisiques \u00e0 la disparit\u00e9 extr\u00eame.<\/p>\n<\/p>\n<p><p>On a d\u00e9j\u00e0 lu (ce <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_krach_chinois_s_quence_no_future_du_tourbillon_crisique__10_07_2015.html\">10 juillet 2015<\/a>) que nous annoncions la pr\u00e9sentation de ce nouveau concept \u00e9videmment crisique de \u00ab\u00a0tourbillon crisique\u00a0\u00bb :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;[&#8230;N]<em>ous identifions<\/em> [&#8230;] <em>l&rsquo;expression nouvelle de \u00ab\u00a0tourbillon crisique\u00a0\u00bb. Nous devons tr\u00e8s rapidement offrir une analyse d\u00e9taill\u00e9e quoique dans le courant de nos rubriques d'\u00a0\u00bbactualit\u00e9\u00a0\u00bb, de ce nouveau concept dont nous pensons qu&rsquo;il est rendu n\u00e9cessaire par l&rsquo;\u00e9volution extr\u00eamement rapide de la situation g\u00e9n\u00e9rale (contraction du Temps, acc\u00e9l\u00e9ration tr\u00e8s rapide de l&rsquo;histoire en constante mutation m\u00e9tahistorique).<\/em> [&#8230;] <em>Dans cette optique, le \u00ab\u00a0tourbillon crisique\u00a0\u00bb<\/em> [&#8230; serait] <em>un ph\u00e9nom\u00e8ne pour l&rsquo;instant fait de d\u00e9sordre pur, d&rsquo;\u00e9nergie tournante en constante acc\u00e9l\u00e9ration, un ph\u00e9nom\u00e8ne qui n&rsquo;est pas encore en phase d&rsquo;autodestruction (celle qui caract\u00e9rise l&rsquo;effondrement final du Syst\u00e8me), mais toujours dans cette phase o&ugrave; l&rsquo;aspect surpuissance et l&rsquo;aspect autodestruction sont concomitants et m\u00eame parfois confondus&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Dans le m\u00eame texte, nous poursuivions notre d\u00e9marche en tentant d&rsquo;avancer une premi\u00e8re description analytique de ce ph\u00e9nom\u00e8ne de \u00ab\u00a0tourbillon crisique\u00a0\u00bb, sur deux plans, &ndash; celui de sa substance en un sens, de sa composition ; celui de sa sp\u00e9cificit\u00e9 politique et profonde, et sans doute dissimul\u00e9e, en un autre sens, selon ses manifestations et ses soubresauts que nous pouvons tenter d&rsquo;interpr\u00e9ter&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Pour tenter d&rsquo;\u00eatre encore plus clair, ce n&rsquo;est pas exactement le ph\u00e9nom\u00e8ne que nous \u00e9tudiions, pour le compte d&rsquo;Orlov et pour la compte de nos conceptions qui diff\u00e8rent sur tel ou tel aspect tout en se rejoignant sur le principal, lorsque nous avons observ\u00e9 le concept du \u00ab\u00a0trou noir financier\u00a0\u00bb d&rsquo;Orlov (le<\/em> <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_trou_noir_de_dimitri_orlov_02_07_2015.html\">2 juillet 2015<\/a><em>). Notre id\u00e9e est que, d&rsquo;une part nous n&rsquo;allons pas, &ndash; nous n&rsquo;allons pas<\/em> <strong><em>encore<\/em><\/strong> <em>vers une r\u00e9duction, une dissolution syst\u00e9matique du ph\u00e9nom\u00e8ne par quasi-entropisation dissolvante de la mati\u00e8re; nous sommes encore en phase dynamique furieuse o&ugrave; se c\u00f4toient (bis) surpuissance et autodestruction, m\u00eame si nous approchons<\/em> <strong><em>n\u00e9cessairement<\/em><\/strong><em> de la phase d&rsquo;autodestruction pure. Notre autre id\u00e9e, la plus essentielle, est qu&rsquo;il ne faut pas, dans le contexte de la Grande Crise d&rsquo;effondrement du Syst\u00e8me, poursuivre la cat\u00e9gorisation des crises (financi\u00e8re, politique, soci\u00e9tale, culturelle, psychologique) puisqu&rsquo;il s&rsquo;agit du \u00ab\u00a0tourbillon crisique\u00a0\u00bb (le concept identifi\u00e9 permet de bien mieux comprendre la situation \u00e0 partir de laquelle on l&rsquo;a forg\u00e9), &ndash; parce que le \u00ab\u00a0tourbillon crisique\u00a0\u00bb est \u00e9videmment un Tout qui homog\u00e9n\u00e9ise et r\u00e9duit \u00e0 rien les sp\u00e9cificit\u00e9s crisiques pour ne garder des crises que leur substance crisique et la doper d&rsquo;une formidable \u00e9nergie. C&rsquo;est de ce point de vue que nous pr\u00e9cisons de mani\u00e8re imag\u00e9e que le &lsquo;krach&rsquo; chinois a \u00ab\u00a0no future\u00a0\u00bb parce que, m\u00eame s&rsquo;il a des effets multiples, diluviens, en cascade, il n&rsquo;en produira aucun qui soit sp\u00e9cifique de lui, de fa\u00e7on n\u00e9gative ou m\u00eame positive ; en quelque sorte, c&rsquo;est un &lsquo;krach&rsquo; boursier nihiliste et d\u00e9j\u00e0 entropique-Syst\u00e8me.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>En fait, on pourrait avancer qu&rsquo;avec ce \u00ab\u00a0tourbillon crisique\u00a0\u00bb, il s&rsquo;agit du d\u00e9veloppement, &ndash; peut-\u00eatre ultime, &ndash; du ph\u00e9nom\u00e8ne de \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-de_la_chaine_crisique_au_temps_crisique__24_02_2011.html\">cha&icirc;ne<\/a> <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_chaine_crisique_ddecrisis_02_04_2011.html\">crisique<\/a>\u00a0\u00bb identifi\u00e9 au d\u00e9but de 2011 avec le \u00ab\u00a0printemps arabe\u00a0\u00bb. Si l&rsquo;on veut, la (les) cha&icirc;ne(s) crisiques \u00ab\u00a0se d\u00e9cha&icirc;nent\u00a0\u00bb dans les deux sens du mot (deviennent de plus en plus virulentes et perdent de plus en plus leurs d\u00e9pendances communes et leurs liens de cause \u00e0 effet) ; pourtant, les crises restent regroup\u00e9es entre elles, et m\u00eame de plus en plus, productrices d&rsquo;autres crises, jusqu&rsquo;\u00e0 un pullulement crisique extraordinaire. Simplement, il y a de moins en moins de rapport de cause \u00e0 effet direct (\u00ab\u00a0cha&icirc;ne crisique\u00a0\u00bb) et de plus en plus un mouvement al\u00e9atoire concernant les liens et effets entre ces crises ; mais il y a surtout la cr\u00e9ation et l&rsquo;alimentation d&rsquo;un puissant mouvement tournant sur lui-m\u00eame, d&rsquo;une formidable temp\u00eate tourbillonnante, &ndash; le \u00ab\u00a0tourbillon crisique\u00a0\u00bb, o&ugrave; c&rsquo;est la nature crisique elle-m\u00eame qui agit, d&rsquo;elle-m\u00eame, transformant en crise tout ce qu&rsquo;elle touche, tout ce qu&rsquo;elle fr\u00f4le, tout ce qu&rsquo;elle appr\u00e9cie, sans coh\u00e9rence politique cr\u00e9atrice, sans logique politique d&rsquo;encha&icirc;nement &#8230; (C&rsquo;est \u00e0 nous ensuite, une fois chaque ph\u00e9nom\u00e8ne crisique d\u00e9clench\u00e9, de voir quel est son sens, \u00e9ventuellement son sens politique si c&rsquo;est le cas et si c&rsquo;est possible, &ndash; et c&rsquo;est en ce sens que nous disions plus haut que \u00ab\u00a0[l]&rsquo;analyse ne doit \u00eatre guid\u00e9e que par la perception d&rsquo;eux-m\u00eames que nous imposent les \u00e9v\u00e8nements plut\u00f4t que pr\u00e9tendre ma&icirc;triser la compr\u00e9hension de ces \u00e9v\u00e8nements par une rationalit\u00e9 imp\u00e9rative qui est n\u00e9cessairement la victime de toutes les faiblesses qui accablent nos psychologies et infectent cette raison&#8230;.\u00a0\u00bb)<\/p>\n<\/p>\n<p><p>Mais ce qui nous int\u00e9resse, bien entendu, ce sont les effets non pas \u00ab\u00a0op\u00e9rationnels\u00a0\u00bb directs dont on a vus qu&rsquo;ils sont manifestement insaisissables, mais bien les effets indirects fondamentaux sur la marche de la Grande Crise d&rsquo;effondrement du Syst\u00e8me. Dire de cet \u00ab\u00a0tourbillon crisique\u00a0\u00bb qu&rsquo;il est manifestement l&rsquo;expression dynamique la plus prodigieuse du d\u00e9veloppement de la Grande Crise ne nous dit rien, en effet, de ces fameux \u00ab\u00a0effets indirects\u00a0\u00bb. Ce \u00e0 quoi nous pensons n&rsquo;a justement qu&rsquo;un rapport lointain avec des \u00e9v\u00e8nements, m\u00eame indirects, qui seraient issus de ces crises amalgam\u00e9es en \u00ab\u00a0tourbillon\u00a0\u00bb (par exemple <em>Grexit<\/em>, troubles en Chine, affrontement de type soci\u00e9tal et de r\u00e9volte civique aux USA, etc.), &ndash; m\u00eame si nous ne songeons pas <strong>une seconde<\/strong> \u00e0 nier leur importance \u00e9ventuelle, et m\u00eame bien entendu \u00e0 consid\u00e9rer l&rsquo;hypoth\u00e8se que tel ou tel \u00e9v\u00e9nement, soudain, peut devenir\/devient d\u00e9cisif pour faire entrer la grande Crise effectivement sur son plateau final, dans son bouquet lib\u00e9rateur, etc. Nous ne nous attardons pas \u00e0 ces diverses possibilit\u00e9s et \u00e0 l&rsquo;hypoth\u00e8se op\u00e9rationnelle fondamentale parce que nous n&rsquo;en savons rien, que nous n&rsquo;en pouvons rien savoir, et peut-\u00eatre m\u00eame, &ndash; vertu de l&rsquo;<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-de_l_inconnaissance_du_systeme_13_07_2011.html\">inconnaissance<\/a>, &ndash; qu&rsquo;il est n\u00e9cessaire que nous n&rsquo;en sachions rien. A cet \u00e9gard, il y a d&rsquo;autres forces que les n\u00f4tres (celle du <em>sapiens<\/em>) en marche, et elles nous dominent de tout en tout et de tout sur tout, et elles nous dispensent de disperser notre vaste intelligence et notre ma&icirc;trise \u00e9vidente de l&rsquo;univers dans des analyses sophistiqu\u00e9es et faussaires d&rsquo;avance.<\/p>\n<\/p>\n<p><p>Justement, il est bienvenu de tenter par instants, de se retrouver, de se rassembler soi-m\u00eame, de cesser de tourner au gr\u00e9 du tourbillon en se d\u00e9doublant, donc de s&rsquo;observer soi-m\u00eame \u00ab\u00a0tourner au gr\u00e9 du tourbillon\u00a0\u00bb pour pouvoir d\u00e9gager une appr\u00e9ciation g\u00e9n\u00e9rale, un jugement qui rendra compte de la situation g\u00e9n\u00e9rale &#8230; (Ainsi en est-on arriv\u00e9 \u00e0 examiner l&rsquo;hypoth\u00e8se de cette \u00ab\u00a0phase nouvelle\u00a0\u00bb de la Grande crise depuis Minsk2 et l&rsquo;apparition de ce que nous pouvons identifier comme ce ph\u00e9nom\u00e8ne du \u00ab\u00a0tourbillon crisique\u00a0\u00bb.) Par cons\u00e9quent, et pour aller dans ce sens de l&rsquo;observation de nous-m\u00eames dans ces circonstances, il est un domaine o&ugrave; nous pouvons aventurer une r\u00e9flexion concomitante \u00e0 ce \u00ab\u00a0tourbillon crisique\u00a0\u00bb, et c&rsquo;est bien s&ucirc;r celui de l&rsquo;effet du \u00ab\u00a0tourbillon\u00a0\u00bb sur la psychologie humaine. (C&rsquo;est pourquoi nous tentons d&rsquo;attirer l&rsquo;attention de notre lecteur qui suit, haletant, heure par heure, le sort de la Gr\u00e8ce ou celui de l&rsquo;appel \u00e0 l&rsquo;incivilit\u00e9 aux USA \u00e0 cause du \u00ab\u00a0mariage pour tous\u00a0\u00bb et du sort m\u00e9moriel du drapeau de la Conf\u00e9d\u00e9ration des &Eacute;tats d&rsquo;Am\u00e9rique de 1861.)<\/p>\n<\/p>\n<p><p>Le point central et ultime de notre d\u00e9marche est effectivement l&rsquo;effet du \u00ab\u00a0tourbillon de crise\u00a0\u00bb sur la psychologie, &ndash; beaucoup plus important \u00e0 notre sens que l&rsquo;effet sur les march\u00e9s, sur les r\u00e9gimes politiques, sur les forces d\u00e9stabilisatrices ici et l\u00e0, qui pullulent les uns et les autres mais dans tous les sens et pour la seule production de d\u00e9sordre ; et cet effet du \u00ab\u00a0tourbillon de crise\u00a0\u00bb sur la psychologie, de la fascination au vertige, etc., jusqu&rsquo;\u00e0 enfin trouver des impulsions conduisant les psychologies humaines \u00e0 produire elles-m\u00eames des effets qui vont dans le sens qu&rsquo;on doit souhaiter, d&rsquo;\u00e9nergie, d&rsquo;ardeur, d&rsquo;audace, etc. Ce que nous avan\u00e7ons, c&rsquo;est que ces effets psychologiques productifs doivent participer \u00e0 la pr\u00e9paration de ce qui va suivre, c&rsquo;est-\u00e0-dire \u00e0 la recherche de l&rsquo;acc\u00e9l\u00e9ration de la Grande Crise d&rsquo;effondrement du Syst\u00e8me, qui doit rester le but ultime. (Il est si important de rester dans le domaine de la psychologie, pour ne pas s&rsquo;effrayer soi-m\u00eame \u00e0 la pens\u00e9e des \u00e9v\u00e8nements que l&rsquo;on pourrait susciter avec une telle formule, avec des mots comme \u00ab\u00a0d\u00e9sordre\u00a0\u00bb, \u00ab\u00a0chaos\u00a0\u00bb, etc. ; frayeur tout \u00e0 fait d\u00e9plac\u00e9e d&rsquo;ailleurs, puisqu&rsquo;il est acquis que les \u00e9v\u00e8nements ont leur propre force, leur propre production de \u00ab\u00a0d\u00e9sordre\u00a0\u00bb et de \u00ab\u00a0chaos\u00a0\u00bb, qu&rsquo;ils se suffisent \u00e0 eux-m\u00eames pour produire \u00ab\u00a0d\u00e9sordre\u00a0\u00bb et \u00ab\u00a0chaos\u00a0\u00bb, qu&rsquo;il s&rsquo;agit simplement pour nous d&rsquo;accompagner, de renforcer somme toute humblement par la tension de nos observations&#8230;)<\/p>\n<\/p>\n<p><p>La dynamique du tourbillon qui ne pr\u00e9sente aucune coh\u00e9rence explicative doit nous <strong>forcer<\/strong> \u00e0 suivre les crises, \u00e0 les interpr\u00e9ter (faussement ou pas, qu&rsquo;importe), \u00e0 chercher des explications (c&rsquo;est d&rsquo;autant plus pressant que c&rsquo;est inutile), etc., \u00e0 chercher et encore chercher en produisant une grande tension psychologique. La dynamique du \u00ab\u00a0tourbillon crisique\u00a0\u00bb <strong>force<\/strong> le <em>sapiens<\/em>, malgr\u00e9 son \u00e9puisement psychologique, \u00e0 <strong>croire<\/strong> de plus en plus fortement \u00e0 la Grande Crise d&rsquo;effondrement, m\u00eame au prix d&rsquo;une dramatisation de la perception, d&rsquo;une amplification de l&rsquo;interpr\u00e9tation parfois d&rsquo;une fa\u00e7on absolument grotesque (qu&rsquo;importe), qu&rsquo;on peut d&rsquo;ailleurs fort bien critiquer pour continuer \u00e0 exercer la vigueur et la vigilance de son jugement &#8230; En un mot que nous esp\u00e9rons assez clair, le \u00ab\u00a0tourbillon crisique\u00a0\u00bb doit exister comme il existe pour <strong>forcer<\/strong> les psychologies humaines et leurs perceptions \u00e0 se hausser au niveau de l&rsquo;enjeu de la Grande Crise&#8230; (Cette t\u00e2che ne peut \u00eatre laiss\u00e9e aux seules intelligences qui pr\u00e9tendent d&rsquo;abord se r\u00e9gler elles-m\u00eames avec la raison comme maitresse d&rsquo;&oelig;uvre, car alors c&rsquo;est la raison-subvertie. Il faut d&rsquo;abord accepter le d\u00e9cha&icirc;nement des psychologies avec la perception de la Grande Crise, car par l\u00e0 \u00e9galement se glissent les brusques illuminations de l&rsquo;intuition haute &#8230; La raison, elle, si elle est laiss\u00e9 \u00e0 elle-m\u00eame selon sa situation pr\u00e9sente [raison-subvertie], se contentera de s&rsquo;enfermer dans ses habituelles supputations qui satisfont son <em>hybris<\/em> [que va-t-il se passer, comment expliquer ceci, cela, etc.] et freinent toute participation active \u00e0 la mont\u00e9e n\u00e9cessaire d la tension psychologique.)<\/p>\n<\/p>\n<p><p>Notre id\u00e9e (suite) est que ce \u00ab\u00a0tourbillon crisique\u00a0\u00bb est l\u00e0 \u00e0 la fois pour nous faire prendre conscience de la v\u00e9rit\u00e9 de situation de la Grande Crise d&rsquo;effondrement du syst\u00e8me ; \u00e0 la fois pour nous faire mesurer sa substance en m\u00eame temps universelle et d\u00e9gag\u00e9e des sens sp\u00e9cifiques et particuliers de tel et tel \u00e9v\u00e9nements crisiques (telle et telle crises) qui la composent n\u00e9cessairement puisqu&rsquo;elle est la r\u00e9ceptacle de tout \u00e0 cet \u00e9gard ; \u00e0 la fois pour nous <strong>forcer<\/strong> \u00e0 jouer notre r\u00f4le qui est d&rsquo;accro&icirc;tre, de grandir, de dramatiser la perception de ce qui doit \u00eatre de plus en plus tenu d&rsquo;\u00eatre consid\u00e9r\u00e9 comme la Grande Crise d&rsquo;effondrement du Syst\u00e8me, et ainsi contribuer \u00e0 son acc\u00e9l\u00e9ration, \u00e0 sa maturation, \u00e0 son d\u00e9veloppement en constante acc\u00e9l\u00e9ration &#8230;<\/p>\n<\/p>\n<p><p>Nous ignorons enfin si l&rsquo;on peut avancer la remarque finale et fondamentale, &ndash; nous ignorons <strong>si c&rsquo;est le cas<\/strong>, si l&rsquo;\u00e9pisode actuel du \u00ab\u00a0tourbillon crisique\u00a0\u00bb qui se r\u00e9alise maintenant, est celui de l&rsquo;enclenchement final du m\u00e9canisme de l&rsquo;effondrement du Syst\u00e8me. Mais nous ne pouvons ignorer que nous nous trouvons dans une posture exceptionnelle par rapport \u00e0 ce qui est normalement concevable. Il est extraordinaire, il est <strong>fascinant<\/strong>, justement, de songer que l&rsquo;on se trouve au c&oelig;ur de ce \u00ab\u00a0tourbillon crisique\u00a0\u00bb, normalement compl\u00e8tement emport\u00e9 par lui, et qu&rsquo;en m\u00eame temps nous nous trouvons comme en-dehors, que nous disposons tout de m\u00eame de la possibilit\u00e9 d&rsquo;observer la chose avec une sorte de deuxi\u00e8me regard (\u00ab\u00a0de nous observer en train d&rsquo;observer la Grande crise d&rsquo;effondrement du Syst\u00e8me\u00a0\u00bb).<\/p>\n<\/p>\n<p><p>&#8230; Ce point nous est apparu d\u00e8s le 11 septembre 2001 et l&rsquo;on voit bien qu&rsquo;il est rest\u00e9 dans notre perception et dans notre esprit comme l&rsquo;un des plus grands \u00ab\u00a0acquis\u00a0\u00bb, l&rsquo;une des plus grandes nouveaut\u00e9s de la position du <em>sapiens<\/em> dans cette p\u00e9riode enti\u00e8rement nouvelle, sans pr\u00e9c\u00e9dent, sans parall\u00e8le, sans rien du tout de semblable dans l&rsquo;histoire du monde, &ndash; selon une perspective qui rejoint ce qu&rsquo;on d\u00e9crit ici :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>D&rsquo;abord, il y a ceci: en m\u00eame temps que nous subissions cet \u00e9v\u00e9nement<\/em> [l&rsquo;attaque 9\/11] <em>d&rsquo;une force et d&rsquo;une ampleur extr\u00eames, nous observions cet \u00e9v\u00e9nement en train de s&rsquo;accomplir et, plus encore, nous nous observions les uns les autres en train d&rsquo;observer cet \u00e9v\u00e9nement. L&rsquo;histoire se fait, soudain dans un d\u00e9roulement explosif et brutal, nous la regardons se faire et nous nous regardons en train de la regarder se faire. On sait \u00e9galement que ceux qui ont d\u00e9cid\u00e9 et r\u00e9alis\u00e9 cette attaque l&rsquo;ont fait, et pr\u00e9cis\u00e9ment ce qu&rsquo;elle est, parce qu\u00a0\u00bbils savaient qu&rsquo;existe cet \u00e9norme ph\u00e9nom\u00e8ne d&rsquo;observation des choses en train de se faire, et de nous-m\u00eames en train d&rsquo;observer. Le monde est comme une addition de poup\u00e9es russes, une duplication de la r\u00e9alit\u00e9 en plusieurs r\u00e9alit\u00e9s s&rsquo;enfilant les unes sur les autres.<\/em>&raquo; (Premier paragraphe de l&rsquo;essai <em>Les Chroniques de l&rsquo;\u00e9branlement<\/em> de Philippe Grasset, \u00e9ditions Mols, 2003.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il est \u00e9vident que cette situation ne peut \u00eatre tenue pour un hasard, ni m\u00eame une \u00ab\u00a0n\u00e9cessit\u00e9 du hasard\u00a0\u00bb si l&rsquo;on veut faire le bel esprit. Cette situation contient pour nous un imp\u00e9ratif transcendant. Elle nous engage \u00e0 tenir un r\u00f4le actif dans le cours de l&rsquo;\u00e9v\u00e8nement eschatologique en cours. Il est essentiel que ce r\u00f4le soit celui qui convient, et non pas une tromperie de plus de notre raisons-subvertie.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vertigo 13 juillet 2015 &ndash; Il est tr\u00e8s difficile, en ce jour pr\u00e9cis\u00e9ment, apr\u00e8s ce qui s&rsquo;est pass\u00e9 ce week-end \u00e0 Bruxelles, de commencer une analyse de la situation g\u00e9n\u00e9rale par autre chose que l&rsquo;affaire europ\u00e9enne, &ndash; lorsque et parce que, comme c&rsquo;est notre cas, l&rsquo;on s&rsquo;y trouve en son c&oelig;ur, g\u00e9ographiquement et professionnellement, mais&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4646,4012,5448,4270,3631,10859,8294,3696,2651,2803,7548,398,3583,3125,3841,16483,3099,16787,16786,6092,3867,3014,3625,12735,1296],"class_list":["post-76003","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-antisysteme","tag-apocalypse","tag-armageddon","tag-autodestruction","tag-bruxelles","tag-chaine","tag-crisique","tag-double","tag-du","tag-effondrement","tag-eschatologie","tag-europe","tag-fascination","tag-grasset","tag-grece","tag-grexit","tag-psychologie","tag-regard","tag-regarder","tag-se","tag-syrie","tag-systeme","tag-todd","tag-tourbillon","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76003"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76003\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}