{"id":76062,"date":"2015-08-15T15:27:47","date_gmt":"2015-08-15T15:27:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/08\/15\/la-syrie-les-mots-magiques-et-le-determinisme-narrativiste\/"},"modified":"2015-08-15T15:27:47","modified_gmt":"2015-08-15T15:27:47","slug":"la-syrie-les-mots-magiques-et-le-determinisme-narrativiste","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/08\/15\/la-syrie-les-mots-magiques-et-le-determinisme-narrativiste\/","title":{"rendered":"La Syrie, les \u201cmots magiques\u201d et le d\u00e9terminisme-narrativiste"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Les \u00ab\u00a0mots magiques\u00a0\u00bb et le d\u00e9terminisme-narrativiste<\/h2>\n<\/p>\n<p><p>L&rsquo;organisation de presse washingtonienne McClatchy, presse-Syst\u00e8me sans le moindre doute mais souvent productrice de choses loin d&rsquo;\u00eatre inint\u00e9ressantes, sort un article extr\u00eamement r\u00e9v\u00e9lateur sur les causes et les raisons de la politique syrienne des USA \u00e0 partir du mois d&rsquo;ao&ucirc;t 2011. Il y est question, &ndash; qui s&rsquo;en \u00e9tonnerait car qui s&rsquo;\u00e9tonnerait de quoi aujourd&rsquo;hui ? &ndash; des \u00ab\u00a0mots magiques\u00a0\u00bb au nom desquels cette politique fut suivie et d\u00e9velopp\u00e9e durant exactement quatre ann\u00e9es. On est habitu\u00e9 \u00e0 croire en g\u00e9n\u00e9ral que toute cette affaire \u00e9tait, par exemple, un montage des <em>neocons<\/em> ; nous aussi, il nous est arriv\u00e9 d&rsquo;y croire en nous en voulant un peu tant cette explication \u00e9cul\u00e9e peine \u00e0 absorber toute la substance extraordinaire des \u00e9v\u00e8nements que nous vivons, avec leurs contradictions, leur inconsistante, etc&#8230; Eh bien nous voil\u00e0 rassur\u00e9s parce que pas vraiment, mais alors pas du tout ; nul <em>neocon<\/em> n\u00e9cessaire, des mots simplement, quelques mots qui \u00e9taient calcul\u00e9es pour tailler sur mesure la \u00ab\u00a0stature historique\u00a0\u00bb du pr\u00e9sident&#8230;<\/p>\n<\/p>\n<p><p>&laquo;<em>Apr\u00e8s un mois d&rsquo;\u00e9changes d&rsquo;e-mails, d&rsquo;analyses de renseignement, d&rsquo;\u00e9valuation l\u00e9gales entre divers minist\u00e8res et agences, la Maison-Blanche se d\u00e9cida pour une d\u00e9claration \u00e9crite que le pr\u00e9sident Obama lirait le 18 ao&ucirc;t 2011. On y trouvait un pr\u00e9ambule saluant les manifestations pacifiques<\/em>[ anti-Assad] <em> qui s&rsquo;opposaient \u00e0 la \u00ab\u00a0brutalit\u00e9 f\u00e9roce\u00a0\u00bb du r\u00e9gime, et puis il y avait cette ligne d\u00e9cisive : \u00ab\u00a0Pour la survie du peuple syrien, le temps est venu pour le pr\u00e9sident Assad de quitter le pouvoir\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Les conseillers politiques impliqu\u00e9s dans le dossier furent d\u00e9sormais r\u00e9f\u00e9rence \u00e0 cette phrase sous l&rsquo;expression \u00ab\u00a0les mots magiques\u00a0\u00bb&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Ainsi, avec ces \u00ab\u00a0<em>magic words<\/em>\u00a0\u00bb \u00e9tait \u00e9tablie <strong>toute la strat\u00e9gie<\/strong> des USA dans l&rsquo;affaire syrienne&#8230; Le texte de McClatchy est long mais cela ne doit pas d\u00e9courager sa lecture. Il est le fruit d&rsquo;une enqu\u00eate minutieuse, qui s&rsquo;est \u00e9tendue sur une ann\u00e9e et a comport\u00e9 notamment des interviews en profondeur d&rsquo;au moins neuf hauts fonctionnaires du d\u00e9partement d&rsquo;&Eacute;tat (certains sont nomm\u00e9s, d&rsquo;autres ont demand\u00e9 l&rsquo;anonymat) qui ont travaill\u00e9 tous sur le dossier syrien.<\/p>\n<\/p>\n<p><p>Au d\u00e9part, le but \u00ab\u00a0strat\u00e9gique\u00a0\u00bb US \u00e9tait simple : il ne fallait surtout pas renouveler le chapitre \u00e9gyptien, c&rsquo;est-\u00e0-dire la chute de Moubarak et ce qui s&rsquo;ensuivit, au cours desquels l&rsquo;administration Obama parut lente, peu inspir\u00e9e, h\u00e9sitante&#8230; La Syrie, et surtout Assad, semblaient pr\u00e9senter tous les \u00ab\u00a0avantages\u00a0\u00bb d&rsquo;une telle contre-offensive \u00ab\u00a0strat\u00e9gique\u00a0\u00bb de pour communication puisqu&rsquo;il s&rsquo;agissait de demander le d\u00e9part d&rsquo;un homme dont tout le monde disait, d\u00e9j\u00e0 depuis quelques mois, qu&rsquo;il n&rsquo;en avait plus que pour quelques semaines (avant de devoir quitter ignominieusement le pouvoir, peut-\u00eatre pour le pire des sorts), voire que \u00ab\u00a0ses jours \u00e9taient compt\u00e9s\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Ainsi en vint-on aux \u00ab\u00a0mots magiques\u00a0\u00bb dont on a parl\u00e9 plus haut. Frederic Hof, actuellement au Centre Farik Haruri de l&rsquo;Atlantic Council, menait la <em>task force<\/em> du d\u00e9partement d&rsquo;&Eacute;tat charg\u00e9e de la r\u00e9ponse \u00e0 l&rsquo;insurrection syrienne &#8230; &laquo;<em>A ce point, une d\u00e9claration pr\u00e9sidentielle disant que Assad devait abandonner le pouvoir aurait du refl\u00e9ter une strat\u00e9gie de s\u00e9curit\u00e9 nationale pour la Syrie. Elle aurait du refl\u00e9ter quelque chose de substantiel, la fa\u00e7on dont les &Eacute;tats-Unis entendaient proc\u00e9der. Cela fut compos\u00e9 enti\u00e8rement en circuit ferm\u00e9, dans un effort tr\u00e8s rapide pour placer le pr\u00e9sident \u00ab\u00a0dans le bon c\u00f4t\u00e9 de l&rsquo;histoire\u00a0\u00bb, en se basant sur l&rsquo;appr\u00e9ciation absolument fausse et absolument sans la moindre assurance ni la moindre pr\u00e9somption que le type<\/em> [Assad] <em>\u00e9tait sur le point de quitter le pouvoir dans les vingt minutes qui venaient&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>A c\u00f4t\u00e9 de cela, le texte rapporte que la position g\u00e9n\u00e9rale de la communaut\u00e9 de s\u00e9curit\u00e9 nationale \u00e9tait une compl\u00e8te incertitude sur l&rsquo;int\u00e9r\u00eat strat\u00e9gique de la Syrie pour les USA, sur la valeur, le cr\u00e9dit, les capacit\u00e9s de l&rsquo;opposition, ni m\u00eame sur l&rsquo;aide que les USA pouvaient apporter \u00e0 une politique de <em>regime change<\/em> en Syrie ; la Maison-Blanche elle-m\u00eame \u00e9tait persuad\u00e9e que la Syrie n&rsquo;avait que tr\u00e8s peu d&rsquo;importance strat\u00e9gique pour les USA, que de toutes les fa\u00e7ons elle ne serait jamais proche des USA quel que f&ucirc;t le r\u00e9gime&#8230; &laquo;<em>La Maison-Blanche et le d\u00e9partement d&rsquo;&Eacute;tat, et moi y compris, nous f&ucirc;mes absolument coupables dans l&#8217;emploi d&rsquo;une rh\u00e9torique pr\u00e9tentieuse sans aucun argument, aucune base solide pour la justifier<\/em>&#8230; [&#8230;] <em>Il y eut \u00e9norm\u00e9ment de verbiage absolument d\u00e9pourvu de la moindre d\u00e9termination de faire en sorte que le projet soit men\u00e9 \u00e0 son terme. <\/em>&raquo; (Hof) Une autre source au d\u00e9partement d&rsquo;&Eacute;tat explique : &laquo;<em>C&rsquo;\u00e9tait toujours \u00ab\u00a0il faut que nous ayons l&rsquo;air de dominer et de contr\u00f4ler le probl\u00e8me, que nous ayons l&rsquo;air de faire quelque chose, mais il ne faut pas s&rsquo;y laisser prendre\u00a0\u00bb&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Enfin, il y eut les pressions que subit l&rsquo;administration Obama pour poursuivre et accentuer sa \u00ab\u00a0politique\u00a0\u00bb anti-Assad, sa \u00ab\u00a0strat\u00e9gie\u00a0\u00bb d\u00e9finie par un seul but qui \u00e9tait l&rsquo;\u00e9limination d&rsquo;un homme, sans aucune autre disposition fondamentale, sans aucun autre but strat\u00e9gique, dans une affaire o&ugrave; l&rsquo;int\u00e9r\u00eat strat\u00e9gique des USA \u00e9tait largement mis en cause, sinon inexistant pour certains des acteurs principaux. Ces pressions vinrent de deux groupes &#8230;<\/p>\n<\/p>\n<p><p>D&rsquo;une part, la presse US elle-m\u00eame, qui ne cessa d&rsquo;exercer une pression portant sur la question de la l\u00e9gitimit\u00e9 d&rsquo;Assad, donc sur la n\u00e9cessit\u00e9 de son d\u00e9part. &laquo;<em>Pour \u00eatre franc, <\/em>explique l&rsquo;ambassadeur Ford, alors en poste \u00e0 Damas pour repr\u00e9senter les USA et lui-m\u00eame pendant de nombreux mois agitateur US n&deg;1 (type \u00ab\u00a0r\u00e9volution de couleur\u00a0\u00bb) en faveur des r\u00e9volt\u00e9s anti-Assad, <em>la presse, les m\u00e9dias ne cessaient de nous presser. Ils n&rsquo;\u00e9taient nullement impartiaux l\u00e0-dessus parce que, d\u00e8s que les r\u00e9publicains commenc\u00e8rent \u00e0 dire qu&rsquo;il<\/em> [Assad] <em>n&rsquo;avait aucune l\u00e9gitimit\u00e9, la question revint tous les jours en conf\u00e9rence de presse : Croyez-vous qu&rsquo;il ait une l\u00e9gitimit\u00e9 ? Qu&rsquo;est-ce que nous aurions d&ucirc; r\u00e9pondre ? Oui, il a une l\u00e9gitimit\u00e9 ?<\/em>&raquo;<\/p>\n<\/p>\n<p><p>D&rsquo;autre part, la pression des alli\u00e9 du bloc BAO, particuli\u00e8rement les Europ\u00e9ens, <strong>particuli\u00e8rement les Fran\u00e7ais<\/strong> &#8230;. C&rsquo;est l&rsquo;habituelle inversion aujourd&rsquo;hui, <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-wallerstein_yeats_et_l_apr_ssyst_me_24_05_2014.html\">\u00e0-la-Wallerstein<\/a> : qui est le caniche de qui ? (Charmante question pour la France, n&rsquo;est-ce pas&#8230;) Les asservis pro-US, dont la France est un brillant exemple, finissent tr\u00e8s vite par \u00e9mettre sans arr\u00eat des exigences de durcissement suppl\u00e9mentaire de leur ma&icirc;tre, si bien que les gens de l&rsquo;\u00e9quipe Obama ne craignaient rien tant que les visites des ministres fran\u00e7ais. Lors d&rsquo;une visite de Jupp\u00e9 en juin 2011 (donc avant la d\u00e9claration d&rsquo;aout 2011 d&rsquo;Obama), le m\u00eame Ford rapporte qu&rsquo;il craignait par-dessus tout qu&rsquo;Hillary Clinton, emport\u00e9e par sa fougue interventionniste ranim\u00e9e par son interlocuteur, n&rsquo;oubli\u00e2t la ligne g\u00e9n\u00e9rale qu&rsquo;il tentait de soutenir au sein du d\u00e9partement et qu&rsquo;elle se laiss\u00e2t entra&icirc;ner par Jupp\u00e9, devenu extraordinaire et improbable <em>neocon<\/em>, et demander le d\u00e9part d&rsquo;Assad&#8230;<\/p>\n<\/p>\n<p><p>Ainsi appara&icirc;t dans ce tr\u00e8s long texte de McClatchy une stup\u00e9fiante v\u00e9rit\u00e9 de situation, &ndash; ou plut\u00f4t ce qui devrait \u00eatre une stup\u00e9fiante v\u00e9rit\u00e9 de situation pour la plupart des gens de communication, ceux qui soutinrent la m\u00eame <em>narrative<\/em> pendant quatre ann\u00e9es, &ndash; puisque, par ailleurs, pour nous, rien de stup\u00e9fiant l\u00e0-dedans, <em>narrative<\/em> confirm\u00e9e et situation conforme \u00e0 notre hypoth\u00e8se d&rsquo;un Syst\u00e8me \u00e9crasant, de l&rsquo;absence de toute politique, de toute strat\u00e9gie dans le chef des pays du bloc BAO, USA en premier&#8230; Nous allons \u00e9noncer quelques remarques g\u00e9n\u00e9rales qui constitueront le terme et l&rsquo;essentiel de notre commentaire.<\/p>\n<\/p>\n<p><p>&bull; Effectivement, la premi\u00e8re chose qui doit retenir l&rsquo;attention, c&rsquo;est cette absence de strat\u00e9gie, ou bien la \u00ab\u00a0strat\u00e9gie\u00a0\u00bb r\u00e9duite \u00e0 une phrase de dix mots concoct\u00e9e apr\u00e8s de longs \u00e9changes et \u00e9mettant une banalit\u00e9 extr\u00eame bas\u00e9e sur une appr\u00e9ciation compl\u00e8tement faussaire de la r\u00e9alit\u00e9, dans le but explicite, &ndash; fondement de la \u00ab\u00a0strat\u00e9gie\u00a0\u00bb, &ndash; que le pr\u00e9sident soit \u00ab\u00a0du bon c\u00f4t\u00e9 de l&rsquo;histoire\u00a0\u00bb. Il n&rsquo;est donc question que d&rsquo;<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_raison_devenue_idiote_utile_de_l_affectivit__11_06_2012.html\">affectivisme<\/a> avec une importance \u00e9norme accord\u00e9e \u00e0 la communication. Pour le reste, lorsqu&rsquo;on parle <strong>v\u00e9ritablement de l&rsquo;enjeu strat\u00e9gique<\/strong>, il s&rsquo;av\u00e8re que l&rsquo;opinion la plus courante dans l&rsquo;administration, dans tous les cas \u00e0 la Maison-Blanche, est que la Syrie n&rsquo;a gu\u00e8re d&rsquo;int\u00e9r\u00eat strat\u00e9gique pour les USA. Ainsi le cadre est-il bien trac\u00e9 et compl\u00e9t\u00e9, toute l&rsquo;action politique \u00e9tant verrouill\u00e9e dans la <em>narrative<\/em> dont on reconna&icirc;t quasi-explicitement qu&rsquo;elle n&rsquo;a strictement aucun rapport avec la r\u00e9alit\u00e9 strat\u00e9gique. La \u00ab\u00a0v\u00e9rit\u00e9 de la situation\u00a0\u00bb est \u00e0 d\u00e9terminer au niveau de cette occurrence \u00e0 la fois d\u00e9risoire et path\u00e9tique ; on sent, on devine le d\u00e9sint\u00e9r\u00eat d&rsquo;Obama pour toute cette affaire, sinon dans son aspect de communication, ce qui rend assez suspect son affectivisme \u00e0 lui, qui lui tient lieu de politique, au profit d&rsquo;un cynisme assez <em>cool<\/em> et bien dans sa mani\u00e8re ; en d&rsquo;autres termes, Obama s&rsquo;en fout (de la Syrie et du reste) mais tient \u00e0 son \u00ab\u00a0image\u00a0\u00bb d&rsquo;\u00eatre \u00ab\u00a0du bon c\u00f4t\u00e9 de l&rsquo;histoire\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<p><p>&bull; Il se d\u00e9duit imm\u00e9diatement de ce qui pr\u00e9c\u00e8de que toutes les th\u00e9ories, les \u00ab\u00a0Grands Jeux\u00a0\u00bb, les projets plan\u00e9taires, les grands th\u00e8mes de l&rsquo;h\u00e9g\u00e9monie US, les complots pour la mettre en place tout cela qui a \u00e9t\u00e9 d\u00e9taill\u00e9 en si grand nombre durant toute la crise syrienne devrait \u00eatre tr\u00e8s s\u00e9rieusement r\u00e9vis\u00e9, sinon jet\u00e9 \u00e0 la poubelle de la pseudo-histoire (ou disons \u00e0 l&rsquo;histoire r\u00e9duite \u00e0 une poubelle). Cette remarque vaut pour les grands strat\u00e8ges-Syst\u00e8me dans la presse-Syst\u00e8me, mais encore plus pour la myriade de commentateurs antiSyst\u00e8me qui semblent ne jamais devoir arr\u00eater de d\u00e9voiler les plans machiav\u00e9liques des USA, et qui continuent aujourd&rsquo;hui avec l&rsquo;Ukraine. (On serait curieux de rassembler les th\u00e8ses et descriptions des grands plans US sur la Syrie pendant la p\u00e9riode consid\u00e9r\u00e9e, et de les comparer avec les t\u00e9moignages que nous apporte le texte de McClatchy ; mais comme l&rsquo;on voit, par exemple avec <em>The Moon of Alabama<\/em> du <a class=\"gen\" href=\"http:\/\/www.moonofalabama.org\/2015\/08\/narrative-and-reality-of-the-us-war-on-syria.html\">14 ao&ucirc;t 2015<\/a>, l&rsquo;enqu\u00eate de McClatchy est simplement \u00e9cart\u00e9e comme une man&oelig;uvre d&rsquo;intoxication, mise sur le m\u00eame plan que deux articles du Washington <em>Post<\/em> et du New York <em>Times<\/em> qui ne disent pas du tout la m\u00eame chose sur le fondement de la d\u00e9marche qu&rsquo;ils d\u00e9crivent.)<\/p>\n<\/p>\n<p><p>&bull; Il serait temps, avec l&rsquo;\u00e9clairage de quelques textes de cet acabit de mesurer le vide absolu, l&rsquo;inexistence compl\u00e8te de la politique US r\u00e9duite \u00e0 la simple application, compl\u00e8tement aveugle de la <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\">politique-Syst\u00e8me<\/a>&#8230; Car, bien s&ucirc;r, il y a une politique, ou une dynamique tenant lieu de politique, qui n&rsquo;a rien, strictement rien \u00e0 voir avec le <em>sapiens<\/em> basique du Syst\u00e8me, qui est toute enti\u00e8re impos\u00e9e par le Syst\u00e8me et sa dynamique surpuissante, qui consiste en une pouss\u00e9e d\u00e9structurante et dissolvante constante. Outre celui d&rsquo;op\u00e9rationnaliser cette politique, le <em>sapiens<\/em>-Syst\u00e8me n&rsquo;a pour r\u00f4le que de lui donner une justification pour l&rsquo;aligner sur les pr\u00e9occupations de sa hi\u00e9rarchie, qui sont du seul ordre de la communication (\u00ab\u00a0\u00eatre du bon c\u00f4t\u00e9 de l&rsquo;histoire\u00a0\u00bb). A part cela, du c\u00f4t\u00e9 <em>sapiens<\/em>, rien, le vide absolu, une sorte de d\u00e9sert intellectuel o&ugrave; pas un seul complot, f&ucirc;t-il le plus sophistiqu\u00e9, ne survivrait un seul jour, mort de sottise comme l&rsquo;on meurt de soif. Il est \u00e0 peu pr\u00e8s assur\u00e9 qu&rsquo;on est loin, du c\u00f4t\u00e9 des <em>Sapiens<\/em>-Syst\u00e8me, <strong>mais surtout du c\u00f4t\u00e9 des antiSyst\u00e8me<\/strong>, d&rsquo;admettre cette explication que les USA et leur \u00ab\u00a0politique\u00a0\u00bb sont aussi vides qu&rsquo;une coquille vide datant du Tertiaire. On dirait que nombre d&rsquo;antiSyst\u00e8me n&rsquo;ont la sensation de ne pouvoir exister que dans la mesure de la puissance de ce qui les menace dans l&rsquo;ordre de l&rsquo;humain dressant des plans machiav\u00e9liques.<\/p>\n<\/p>\n<p><p>&bull; Il y a le ph\u00e9nom\u00e8ne bien connu de surench\u00e8re des irresponsables, en g\u00e9n\u00e9ral des \u00ab\u00a0croyants\u00a0\u00bb de la <em>narrative<\/em> totalement immerg\u00e9s dans l&rsquo;affectivisme qu&rsquo;ils prennent pour une \u00ab\u00a0politique morale\u00a0\u00bb. La plupart ont bien entendu \u00e9t\u00e9 mobilis\u00e9s par les instances sup\u00e9rieures, sur lesquelles ils sont compl\u00e8tement align\u00e9s, mais bient\u00f4t conduits \u00e0 justifier \u00e0 leurs propres yeux cet alignement par une v\u00e9ritable croyance dans la politique dont ils doivent faire la promotion, &ndash; \u00e9vacuant ainsi tout sentiment de culpabilit\u00e9, de l\u00e2chet\u00e9, de conformisme et d&rsquo;asservissement. Ces redoutables asservis deviennent ais\u00e9ment beaucoup, beaucoup \u00ab\u00a0plus royalistes que le roi\u00a0\u00bb, et ne cessent d&rsquo;exiger toujours plus de z\u00e8le, toujours plus de d\u00e9nonciations, toujours plus de forces. La limite est atteinte chez ceux qui ont totalement \u00e9limin\u00e9 toute ind\u00e9pendance de jugement au profit d&rsquo;un d\u00e9cha&icirc;nement paroxystique de l&rsquo;affectivisme, les plus redoutables \u00e9tant ceux qui dissimule la chose derri\u00e8re l&rsquo;apparat du discours retenu, de l&rsquo;affirmation \u00e9quilibr\u00e9e, de l&rsquo;arrogance de bon aloi, caract\u00e9risant les plus grandes intelligences de nos temps \u00e9tranges (Jupp\u00e9, excellent exemple). Du c\u00f4t\u00e9 de la presse-Syst\u00e8me, compl\u00e8tement align\u00e9e sur le Syst\u00e8me et les directions politiques, l&rsquo;absence compl\u00e8te de responsabilit\u00e9, ainsi que du moindre compte \u00e0 rendre \u00e0 quelque r\u00e9alit\u00e9 que ce soit, permet le d\u00e9cha&icirc;nement des exigences pour un durcissement continuel, pour des pr\u00e9cisions concernant la politique en cours pour trouver par quel biais exiger son durcissement, etc. De ce c\u00f4t\u00e9, nous dirions qu&rsquo;on est beaucoup, beaucoup \u00ab\u00a0plus stalinien que Staline\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&bull; La s\u00e9quence ainsi d\u00e9crite renvoie compl\u00e8tement \u00e0 la dynamique de notre <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_terminisme-narrativiste_26_02_2015.html\">d\u00e9terminisme-narrativiste<\/a>, et \u00e0 une influence totale du Syst\u00e8me. Il y a l&rsquo;abdication compl\u00e8te de tous les acteurs de tenter de comprendre la logique de ce qui est en cours, c&rsquo;est-\u00e0-dire d&#8217;embrasser la situation dans son ensemble. Le rythme de l&rsquo;action, des d\u00e9lib\u00e9rations, des d\u00e9cisions, etc., \u00e9touffe toute vell\u00e9it\u00e9 de distinguer combien sont vaines et faussaires cette action, ces d\u00e9lib\u00e9rations et ces d\u00e9cisions. Cette situation est bien connu et exsude plus qu&rsquo;aucune autre une v\u00e9rit\u00e9 d&rsquo;elle-m\u00eame qui est une parfaite description de la crise en \u00e9clairant d&rsquo;une lumi\u00e8re crue l&rsquo;irresponsabilit\u00e9 et l&rsquo;inconscience des acteurs. Il reste, &ndash; rien que cela, &ndash; \u00e0 explorer l&rsquo;origine des forces qui agissent comme elles le font &#8230; Nous avons souvent \u00e9voqu\u00e9 ce probl\u00e8me et conduit certaines hypoth\u00e8ses qui s&rsquo;inscrivent dans le cadre de notre rangement m\u00e9tahistorique qui s&rsquo;ordonne autour de l&rsquo;\u00e9v\u00e9nement du \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_cha_nement_de_la_mati_re__05_11_2012.html\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00ab\u00a0. De ce point de vue, il n&rsquo;y a aucune raison pour nous de modifier cette d\u00e9marche, mais au contraire, \u00e0 la lecture de cette enqu\u00eate, de l&rsquo;accentuer plus encore.<\/p>\n<\/p>\n<p><p>&bull; Une derni\u00e8re remarque qui est en accord avec tout ce que nous relevons \u00e0 propos de la psychologie, concerne la quasi-pathologie des psychologies des acteurs concern\u00e9s. L&rsquo;effet obtenu est un cloisonnement de l&rsquo;esprit et la r\u00e9duction de la m\u00e9moire \u00e0 un instrument de constat lui-m\u00eame cloisonn\u00e9 et nullement \u00e0 un instrument de p\u00e9dagogie. La description d&rsquo;une p\u00e9riode pass\u00e9e qui offre une explication permettant de comprendre la plupart des aspects incompr\u00e9hensibles de cette p\u00e9riode, tout en rencontrant ce qu&rsquo;on devine du sentiment, des comportements, des faiblesses et des aveuglements des uns et des autres, ne sugg\u00e8re aucun rem\u00e8de efficace pour la p\u00e9riode pr\u00e9sente o&ugrave; l&rsquo;on reproduit les m\u00eames errements avec une quasi-innocence refaite \u00e0 neuf. La description est faite comme s&rsquo;il s&rsquo;agissait de quelque chose d&rsquo;ext\u00e9rieur \u00e0 soi, quelque chose qui, justement, a \u00e9t\u00e9 impos\u00e9e. L&rsquo;on sent bien, et l&rsquo;on comprend aussi bien \u00e0 suivre les \u00e9v\u00e8nements, que les m\u00eames errements, les m\u00eames faiblesses, les m\u00eames absurdit\u00e9s seront r\u00e9p\u00e9t\u00e9es dans d&rsquo;autres circonstance, &ndash; comme en Ukraine, par exemple, et m\u00eame en pire. Il s&rsquo;agit d&rsquo;esprits et d&rsquo;intelligences quoi sont compl\u00e8tement infect\u00e9es par le Syst\u00e8me, qu&rsquo;ils se placent dans un camp ou l&rsquo;autre (du c\u00f4t\u00e9 du Syst\u00e8me ou du c\u00f4t\u00e9 des antiSyst\u00e8me).<\/p>\n<\/p>\n<p><p>Pour nous, il ne fait aucun doute que de telles analyses, comme d&rsquo;autre part les d\u00e9clarations du G\u00e9n\u00e9ral Flynn (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-daesh-d_sordre_et_le_g_n_ral_flynn_en_vedette_am_ricaine_12_08_2015.html\">12 ao&ucirc;t 2015<\/a> et le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-vertigo_suite_chinoise_14_08_2015.html\">14 ao&ucirc;t 2015<\/a> pour leur mise en \u00e9vidence), constituent des avanc\u00e9es pr\u00e9cieuses sur la voie de la compr\u00e9hension du fonctionnement g\u00e9n\u00e9ral du Syst\u00e8me et de la Grande Crise d&rsquo;effondrement du Syst\u00e8me. Que tout cela vienne du Syst\u00e8me lui-m\u00eame (de la presse-Syst\u00e8me ou d&rsquo;ex\u00e9cutants du Syst\u00e8me) ne fait que mettre en \u00e9vidence combien les seules voies d&rsquo;une compr\u00e9hension compl\u00e8te de la crise du Syst\u00e8me ne peuvent venir que du Syst\u00e8me lui-m\u00eame. (Ci-apr\u00e8s, le texte de McClatchy.<em>News<\/em> du <a class=\"gen\" href=\"http:\/\/www.mcclatchydc.com\/news\/nation-world\/world\/article31016274.html#storylink=cpy\">13 ao&ucirc;t 2015<\/a>, sign\u00e9 de Hannah Allam.)<\/p>\n<\/p>\n<p><p><em>dedefensa.org<\/em><\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\">The &lsquo;magic words:&rsquo; How a simple phrase enmeshed the U.S. in Syria&rsquo;s crisis<\/h2>\n<\/p>\n<p><p>&laquo; By the summer of 2011, the Syrian uprising was spiraling into a full-fledged insurgency, with ragtag militias eclipsing the nonviolent opposition and dealing serious blows to the once-untouchable regime of Bashar Assad.<\/p>\n<\/p>\n<p><p>&raquo; Inside the Obama administration, a debate was heating up between senior officials who opposed U.S. involvement and others who urged the White House to do something, anything, to boost a then-nascent rebel movement. European allies and Arab partners added to the pressure by calling nonstop, leaning on the United States to denounce Assad in a symbolic move that they hoped would catalyze regime change in Damascus.<\/p>\n<\/p>\n<p><p>&raquo; After a month of interagency emails, intelligence assessments and legal reviews, the White House settled on a written statement that President Barack Obama would issue on Aug. 18, 2011. There was a preamble hailing the peaceful demonstrators who stood up to the regime&rsquo;s \u00ab\u00a0ferocious brutality,\u00a0\u00bb and then the money line: \u00ab\u00a0For the sake of the Syrian people, the time has come for President Assad to step aside.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&raquo; Senior aides referred to them as the \u00ab\u00a0magic words.\u00a0\u00bb [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; In multiple interviews over the past year, nine of the most senior Syria policymakers from across the government, some of whom spoke on the record and others on condition of anonymity so as to freely describe sensitive internal debates, recounted how a seemingly risk-free gesture of solidarity with dissidents yoked the United States to the anti-Assad cause even though he&rsquo;s no longer the primary target as the policy evolves into what Secretary of State John Kerry called an \u00ab\u00a0ISIL-first\u00a0\u00bb strategy. \u00ab\u00a0It&rsquo;s an ISIS-first war,\u00a0\u00bb agreed one former senior U.S. official who was closely involved in Syria planning for the first two years of the conflict. \u00ab\u00a0Of course, there&rsquo;s nothing second, but they just don&rsquo;t say that.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&raquo; Obama had made clear to his Middle East hands that he wanted to avoid U.S. entanglement in Syria. But he also wanted to avoid the vilification that came when the United States was perceived to have been moving too slowly to support the Egyptian uprising in early 2011. To bridge these two objectives, policymakers said, they settled on a gamble. They bet that calling for Assad to step aside would be painless for the United States because he was on his way out anyway, facing the same reversal of fortune as the autocrats in Tunisia, Egypt and Libya during that era of popular uprisings.<\/p>\n<\/p>\n<p><p>&raquo; Based on what would turn out to be flawed and incorrect assessments that Assad&rsquo;s fall was imminent, the planners said, they dismissed naysayers among them who pointed out that the words could be construed as an implicit pledge of U.S. help and, worse, that there was no backup strategy should Assad remain.<\/p>\n<\/p>\n<p><p>&raquo; Frederic Hof, who led the State Department&rsquo;s response to the Syrian uprising and is now with the Rafik Hariri Center for the Middle East at the Atlantic Council, said that Obama&rsquo;s statement should&rsquo;ve come only after \u00ab\u00a0a very careful and very comprehensive interagency planning process\u00a0\u00bb that identified U.S. objectives in Syria and offered the president policy options as part of a broader, agreed-upon strategy.<\/p>\n<\/p>\n<p><p>&raquo; \u00ab\u00a0At that point, a presidential statement saying Assad must step side would reflect an approved national security strategy for Syria. It would reflect something of substance, it would reflect the manner in which the United States intends to proceed,\u00a0\u00bb Hof said. \u00ab\u00a0This was done entirely backwards, in this rush to get the president on &lsquo;the right side of history&rsquo; based on a faulty and thoroughly unsupported, unsubstantiated assumption that this guy was going to be gone in 20 minutes.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&raquo; Ryan Crocker, a former career diplomat and noted Arabist who&rsquo;s served as ambassador to Iraq, Afghanistan and Syria, called the president&rsquo;s statement \u00ab\u00a0an uh-oh moment, based, I think, on a fundamental misunderstanding of the basic history and dynamics inside Syria.\u00a0\u00bb Current and former officials who worked on the conflict in its infancy, as well as outside experts who advised the policymakers, now speak of the debate over the so-called magic words as an early lesson in the divisions within the administration that persist today as hindrances to a coherent U.S. response to the Syrian conflict.<\/p>\n<\/p>\n<p><p>&raquo; Unlike in discussions over how to handle Libya, for example, senior U.S. officials never agreed on Syria&rsquo;s strategic value, the potential of the political opposition, the trustworthiness of the rebels and to what degree the United States could &ndash; or should &ndash; help to bring about regime change. \u00ab\u00a0The White House and the State Department both &ndash; and I include myself in this &ndash; were guilty of high-faluting rhetoric without any kind of hard policy tools to make the rhetoric stick,\u00a0\u00bb said Robert Ford, who as the U.S. ambassador to Syria would become the American face of the conflict.<\/p>\n<\/p>\n<p><p>&raquo; However, he said, even if the White House had resisted the intense lobbying of that summer, the public campaign and private diplomacy to draw in the United States would&rsquo;ve continued. After all, the pressures had gotten to him all the way in Damascus. \u00ab\u00a0To be fair to the White House, they did ask me shortly before the president made the announcement whether it was a good idea. And I said, &lsquo;well, you might as well go ahead at this point,&rsquo; \u00a0\u00bb Ford recalled. \u00ab\u00a0That was a mistake.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&raquo; What the Oval Office intended as a cost-free gesture to support the seemingly imminent overthrow of Assad was received on the battlefield &ndash; and to rebel supporters within the administration &ndash; as a tacit pledge of U.S. help to get the job done. But Assad hung on and the help didn&rsquo;t arrive, leaving the insurgents bitter and disillusioned over what they now consider the first of many broken promises of Western assistance. \u00ab\u00a0It began a pattern of rhetoric getting out in front of action,\u00a0\u00bb Hof said. \u00ab\u00a0There&rsquo;s been a lot of verbiage unaccompanied by real determination to make it happen.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&raquo; Such a call from Obama, Hof argued, was \u00ab\u00a0not idle chitchat, it&rsquo;s not an advisory opinion, and it&rsquo;s not Dutch-uncle advice to the president of Syria. It&rsquo;s directive in nature, and, therefore, we damn well better make it happen.\u00a0\u00bb Obama&rsquo;s call for Assad to go was no spontaneous cri de coeur from a world leader who&rsquo;d had enough of the blood-soaked images coming from Syria.<\/p>\n<\/p>\n<p><p>&raquo; Instead, it was a carefully orchestrated moment that capped weeks of debate over what Obama should say, according to officials whose accounts converge in showing an administration that was caught off guard by the Arab Spring protests, ill-informed about Assad&rsquo;s staying power and under pressure at home and abroad from those who saw an opportunity to hit Iran via its ally in Damascus. Even critics of Obama&rsquo;s handling of the conflict say that any examination of the decision-making should take into account the pressures and frenzy of that moment in the Middle East.<\/p>\n<\/p>\n<p><p>&raquo; An unprecedented wave of uprisings against Arab autocrats already had toppled the leaders of Tunisia and Egypt by the summer of 2011. Yemen&rsquo;s president was on his way out and Gadhafi was on the run in Libya. Demonstrations in Bahrain had just forced the cancellation of that country&rsquo;s Grand Prix, a major Formula One racing event. \u00ab\u00a0You were constantly pivoting from portfolio to portfolio, knowing there were linkages between them all,\u00a0\u00bb recalled Jeffrey Feltman, who then oversaw the State Department&rsquo;s Middle East policy as assistant secretary of Near Eastern Affairs. \u00ab\u00a0It was really hectic a lot of the time.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&raquo; The protests shattered the status quo of the Middle East, ushering in a dangerous era of untested political actors and trigger-happy militiamen of all loyalties. The U.S. foreign policy machine, not known for being nimble in the smoothest of times, was struggling to find ways to protect American interests and evaluate the new forces that were seizing power across the region.<\/p>\n<\/p>\n<p><p>&raquo; The goal had been to \u00ab\u00a0ratchet up\u00a0\u00bb the Syria response incrementally, starting with U.S. condemnation of the violence and eventually suggesting that Assad had lost legitimacy, two former policymakers said. But the conflict was moving too quickly and the U.S.&rsquo;s allies in Europe, especially the French, were relentless in their lobbying for a denunciation of Assad, they said. The United States already had imposed sanctions against Assad and his cronies for human rights abuses that May. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; \u00ab\u00a0There was never a view, from the highest levels, that the U.S. had a big, important role &ndash; or should have a big, important role &ndash; in the Syrian civil war,\u00a0\u00bb another former senior policymaker said. \u00ab\u00a0It was always, &lsquo;Let&rsquo;s look like we&rsquo;re on top of this problem, let&rsquo;s look like we&rsquo;re doing something, but let&rsquo;s not own it.'\u00a0\u00bb He and other officials said that confusion &ndash; both inside and outside the administration &ndash; arose in large part because the administration could never bring itself to bluntly communicate that view, especially after having joined the NATO-led intervention that helped to overthrow Libya&rsquo;s Muammar Gadhafi, whose atrocities paled in comparison to the Assad regime&rsquo;s tactics.<\/p>\n<\/p>\n<p><p>&raquo; Plus, senior Middle East policymakers were still stinging from criticism of their response to the popular uprising against Egypt&rsquo;s Hosni Mubarak and were determined to change the U.S. image by responding more swiftly on Syria. \u00ab\u00a0People around the president were very chastened by their slow, excessively prudent reaction to the Egyptian revolution. That was the view at the time,\u00a0\u00bb the same Syria policymaker said. \u00ab\u00a0They weren&rsquo;t going to be caught flat-footed in that way. And, to be fair, they weren&rsquo;t.<\/p>\n<\/p>\n<p><p>&raquo; \u00ab\u00a0They made a totally different mistake.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&raquo; The Syrian regime picked August, which coincided with the Islamic holy month of Ramadan, to launch an operation that left hundreds dead in the anti-Assad stronghold of Hama. Amateur footage uploaded to the Internet showed lifeless civilians amid thick, black smoke.<\/p>\n<\/p>\n<p><p>&raquo; And there was another urgent development: reports were emerging of heavy regime losses, inspiring greater confidence in the rebels and giving credence to internal assessments that Assad would fall by Christmas, perhaps even by Thanksgiving. European campaigning kicked into overdrive. The allies had successfully talked the United States into an active role against Gadhafi and now wanted the same support to take down Assad. They reiterated calls for a coordinated, simultaneous demand for Assad&rsquo;s departure. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; As the regime widened its attacks on opposition targets that month, Syrian activists and their supporters around the world lambasted the United States for failing to call for Assad&rsquo;s ouster, forcing Clinton to go on the defensive at a public appearance on Aug. 16, 2011. Clinton said that the United States lacked the leverage in Syria that it enjoyed in other countries with stronger economic and political ties. She also noted that Turkey and Saudi Arabia already had called for regime change in Damascus, so Assad surely had gotten the message. \u00ab\u00a0It&rsquo;s not going to be any news if the United States says, &lsquo;Assad needs to go,&rsquo; Clinton said at the time. \u00ab\u00a0OK, fine, what&rsquo;s next?\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&raquo; The administration didn&rsquo;t dwell on that question. Two days later, on Aug. 18, Obama called for Assad&rsquo;s ouster in coordination with the leaders of the United Kingdom, France and Germany, who issued their own joint statement. The president also signed an executive order that immediately froze all assets of the Syrian government that fell under U.S. jurisdiction and banned Americans from doing business with the regime. The \u00ab\u00a0magic words\u00a0\u00bb finally had been uttered, after five months of violence and a death toll of 1,800.<\/p>\n<\/p>\n<p><p>&raquo; Syrian opposition factions cheered, with news reports from that day quoting jubilant activists. Razan Zaitouneh, a lawyer and vocal opposition activist, told Britain&rsquo;s Guardian newspaper that she interpreted the statement as a sign that the international community was ready to get serious about addressing Assad&rsquo;s atrocities. \u00ab\u00a0This statement is the right start,\u00a0\u00bb she was quoted as saying. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; Today, the remnants of the opposition groups that rejoiced at Obama&rsquo;s statement, thinking that they had a superpower in their corner, now understand the words as they were intended by the speechwriters in Washington &ndash; as only \u00ab\u00a0a preference and a prediction,\u00a0\u00bb as one former senior official explained it.<\/p>\n<\/p>\n<p><p>&raquo; Zaitouneh, the once-hopeful activist who went on to win two State Department awards for her work, was seized along with her husband and two colleagues in December 2013 &ndash; not by the regime she risked her life to oppose but reportedly by one of the many jihadist groups that have proliferated over the years. The activists&rsquo; fates are unknown. At the time of her abduction, U.S. officials who dealt with her confided, Zaitouneh was so let down by the response from Washington that she wasn&rsquo;t even on speaking terms with her old American contacts. That sense of betrayal is pervasive among opposition activists and armed rebels who say they wasted months on halfhearted, abortive projects and forged bonds with U.S. officials who turned out to be powerless or unwilling to help them. [&#8230;]<\/p>\n<\/p>\n<p><p>Hannah Allam, McClatchy.News<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00ab\u00a0mots magiques\u00a0\u00bb et le d\u00e9terminisme-narrativiste L&rsquo;organisation de presse washingtonienne McClatchy, presse-Syst\u00e8me sans le moindre doute mais souvent productrice de choses loin d&rsquo;\u00eatre inint\u00e9ressantes, sort un article extr\u00eamement r\u00e9v\u00e9lateur sur les causes et les raisons de la politique syrienne des USA \u00e0 partir du mois d&rsquo;ao&ucirc;t 2011. Il y est question, &ndash; qui s&rsquo;en \u00e9tonnerait&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[10372,6510,2862,7556,4896,6208,4014,3867],"class_list":["post-76062","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-alabama","tag-decision","tag-determinisme-narrativiste","tag-mcclatchy","tag-moon","tag-obama","tag-of","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76062"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76062\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}