{"id":76063,"date":"2015-08-17T08:52:14","date_gmt":"2015-08-17T08:52:14","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/08\/17\/trump-varoufakis-et-la-logique-catastrophique-des-convergences\/"},"modified":"2015-08-17T08:52:14","modified_gmt":"2015-08-17T08:52:14","slug":"trump-varoufakis-et-la-logique-catastrophique-des-convergences","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/08\/17\/trump-varoufakis-et-la-logique-catastrophique-des-convergences\/","title":{"rendered":"Trump-Varoufakis et la logique catastrophique des convergences"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Trump-Varoufakis et la logique catastrophique des convergences<\/h2>\n<\/p>\n<p><p>Il n&rsquo;y a pas tr\u00e8s longtemps, puisqu&rsquo;il s&rsquo;agit d&rsquo;un texte du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_syst_me_produit_d_sormais_ses_dissidents_officiels_31_07_2015.html\">31 juillet 2015<\/a>, nous relevions le fait, &ndash; que nous voulions \u00ab\u00a0objectif\u00a0\u00bb, c&rsquo;est-\u00e0-dire sans nous interroger sur les parti-pris, les id\u00e9ologies, les engagements des uns et des autres, &ndash; que le Syst\u00e8me produisait de plus en plus de \u00ab\u00a0dissidents officiels\u00a0\u00bb, notamment \u00e0 cause des contraintes que ses <em>narrative<\/em>, et surtout la dynamique de la logique du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_terminisme-narrativiste_26_02_2015.html\">d\u00e9terminisme-narrativiste<\/a> imposent aux psychologies jusqu&rsquo;\u00e0 devenir insupportable \u00e0 certains&#8230; Nous concluions de cette fa\u00e7on :<\/p>\n<\/p>\n<p><p>&laquo;<em>Sans qu&rsquo;il soit n\u00e9cessaire de parler de \u00ab\u00a0r\u00e9volte\u00a0\u00bb ou d'\u00a0\u00bbinsurrection\u00a0\u00bb, de d\u00e9mission fracassante, de mise en cause sans retour, de rupture tonitruante, de \u00ab\u00a0coup de communication\u00a0\u00bb m&ucirc;rement pr\u00e9par\u00e9, au contraire selon une dynamique parfaitement rest\u00e9e dans les r\u00e8gles, ce qu&rsquo;on voit marque essentiellement une \u00e9volution des v\u00e9rit\u00e9s de situation (mise \u00e0 sac de la Gr\u00e8ce, schizophr\u00e9nie \u00e0 Kiev-la-folle) qui fait que le simple exercice de leurs fonctions par des \u00ab\u00a0officiels\u00a0\u00bb du Syst\u00e8me conduit \u00e0 mettre ces \u00ab\u00a0officiels\u00a0\u00bb en confrontation directe avec le Syst\u00e8me, sans pourtant qu&rsquo;ils perdent compl\u00e8tement ou en partie leurs statuts. L&rsquo;on va m\u00eame jusqu&rsquo;\u00e0 envisager des proc\u00e8s-guignols contre eux o&ugrave; serait expos\u00e9, s&rsquo;ils ont lieu, le d\u00e9sordre extraordinaire o&ugrave; baigne le Syst\u00e8me, et ces proc\u00e8s toujours selon l&rsquo;ivresse de vengeance du Syst\u00e8me apr\u00e8s que son hybris se soit heurt\u00e9 \u00e0 une r\u00e9sistance. C&rsquo;est un grand progr\u00e8s par rapport \u00e0 l&rsquo;\u00e8re Snowden. D\u00e9sormais, le Syst\u00e8me, englu\u00e9 avec toute sa surpuissance dans les marais furieux de ses contradictions construites sur des narrative comme l&rsquo;on dirait \u00ab\u00a0sur du sable\u00a0\u00bb, produit directement, toujours aussi furieusement, des antiSyst\u00e8me directement issus de ses rangs. Comme l&rsquo;on dit fameusement, camarade, on n&rsquo;arr\u00eate pas le progr\u00e8s&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Dans ce texte, nous \u00e9voquons les voyages en Crim\u00e9e de parlementaires fran\u00e7ais aussi bien que certains avatars de l&rsquo;ancien ministre grec Varoufakis, pour avoir r\u00e9v\u00e9l\u00e9 certaines v\u00e9rit\u00e9s extr\u00eamement d\u00e9sagr\u00e9ables sur le fonctionnement de l&rsquo;Eurogroupe. Par contre, nous ne disions pas un mot de Donald <em>The Donald<\/em> Trump ; nous allons poursuivre en parlant de lui, avant de revenir \u00e0 Varoufakis pour constater que nous parlons du m\u00eame sujet \u00e9voqu\u00e9 dans le texte auquel nous faisons r\u00e9f\u00e9rence.<\/p>\n<\/p>\n<p><p><em>The Donald<\/em> est sans aucun doute un tr\u00e8s \u00e9trange et d\u00e9routant personnage, sur lequel il est bien difficile de se faire une opinion arr\u00eat\u00e9e, et dont on comprend ais\u00e9ment qu&rsquo;il puisse \u00eatre consid\u00e9r\u00e9 comme d\u00e9testable. Nous avons d\u00e9j\u00e0 observ\u00e9 combien sa popularit\u00e9 reposait sur tout ce qu&rsquo;il n&rsquo;\u00e9tait pas, bien plus que sur tout ce qu&rsquo;il est (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-sanders_comme_trump_des_candidatures_crisiques_13_08_2015.html\">13 ao&ucirc;t 2015<\/a>), et le ph\u00e9nom\u00e8ne remarquable est que cette popularit\u00e9 \u00ab\u00a0par d\u00e9faut\u00a0\u00bb s&rsquo;installe dans la dur\u00e9e, ne s&rsquo;affaiblit pas malgr\u00e9 sa propre faiblesse, \u00e9vidente dans cette forme m\u00eame de popularit\u00e9 toujours per\u00e7ue comme \u00e9ph\u00e9m\u00e8re &#8230; Quoi qu&rsquo;il en soit, effectivement, cette popularit\u00e9 augmente, et nous voulons nous arr\u00eater ici \u00e0 Justin Raimondo, qui est un commentateur exp\u00e9riment\u00e9, d&rsquo;ob\u00e9dience libertarienne tr\u00e8s affirm\u00e9e, extr\u00eamement exp\u00e9riment\u00e9, etc.<\/p>\n<\/p>\n<p><p>Le <a class=\"gen\" href=\"http:\/\/original.antiwar.com\/justin\/2015\/07\/12\/donald-trump-a-false-flag-candidate\/\">12 juillet 2015<\/a>, Raimondo mettait en ligne un texte sans la moindre concession sur Trump, dont il faisait un candidat-bidon, sinon un candidat-faussaire, un candidat-trompeur, &ndash; non, mieux encore puisque tout le monde emploie l&rsquo;expression, un candidat <em>false flag<\/em> destin\u00e9 (en divisant les r\u00e9publicains, voire en devenant un troisi\u00e8me candidat) \u00e0 faire gagner Hillary Clinton, la p\u00e9tulante <em>neocon<\/em>, le pire de tous les cauchemars qu&rsquo;entretient Raimondo. Officiellement, c&rsquo;est-\u00e0-dire d&rsquo;une mani\u00e8re explicite et substantiv\u00e9e, il n&rsquo;a pas chang\u00e9 d&rsquo;avis ; n\u00e9anmoins il est bien r\u00e9v\u00e9lateur d&rsquo;une \u00e9volution au moins souterraine (exactement un mois plus tard, le <a class=\"gen\" href=\"http:\/\/original.antiwar.com\/justin\/2015\/08\/11\/the-foreign-policy-of-the-gop\/\">12 ao&ucirc;t 2015<\/a>), le passage qu&rsquo;il consacre \u00e0 Trump dans le compte-rendu qu&rsquo;il fait du d\u00e9bat que Fox.<em>News<\/em> a organis\u00e9 avec les candidats majeurs du parti r\u00e9publicain, o&ugrave; l&rsquo;on trouvait Trump malgr\u00e9 la haine f\u00e9roce et digne du \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb que lui voue la cha&icirc;ne TV de Rupert Murdoch.<\/p>\n<\/p>\n<p><p>&laquo;<em>The one intrusion of reality into these proceedings was &ndash; naturally &ndash; provided by The Donald, who sidestepped a question about his position on healthcare by saying: \u00ab\u00a0First of all, I&rsquo;d like to just go back to one. In July of 2004, I came out strongly against the war with Iraq, because it was going to destabilize the Middle East. And I&rsquo;m the only one on this stage that knew that and had the vision to say it. And that&rsquo;s exactly what happened.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<strong><em>Baier<\/em><\/strong> : \u00ab\u00a0<em>But on ObamaCare&hellip;\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<strong><em>Trump<\/em><\/strong> \u00ab\u00a0<em>And the Middle East became totally destabilized.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>The part about him being \u00ab\u00a0the only person on stage\u00a0\u00bb to have opposed the Iraq war isn&rsquo;t quite true: Rand Paul, back when he was himself &ndash; or, at least, when he was not the over-calculating politician he has become &ndash; opposed the Iraq war. However, it was refreshing to hear this outburst of truth on a stage full of Republican blind men who would rather pluck out their own eyes than see what the rest of the world acknowledges as indisputable. The look of dismay on Brett Baier&rsquo;s face was almost worth the price of having to sit through hours of posturing and lies&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; A c\u00f4t\u00e9 de Justin Raimondo, on trouve Patrick Buchanan, deux hommes politiquement proches dans le grand rassemblement conservateur US qu&rsquo;on a baptis\u00e9 \u00ab\u00a0pal\u00e9o-conservateur\u00a0\u00bb (isolationniste et antiguerre). Lui, Buchanan, il soutient Trump depuis le premier jour, l\u00e0 non plus nullement par affection pour Trump mais parce que Trump fonce comme un bulldozer \u00e0 la vitesse d&rsquo;une <em>blitzkrieg<\/em> dans l&rsquo;argument que Buchanan affectionne plus que tout autre : l&rsquo;immigration essentiellement venue du Sud d\u00e9nonc\u00e9e comme une invasion des USA, &ndash; immigration d\u00e9sormais colossale puisque le <em>Census Bureau<\/em> annonce qu&rsquo;elle atteint, ill\u00e9gaux et l\u00e9gaux additionn\u00e9s, 42,1 millions de personnes. Buchanan en remet une couche le <a class=\"gen\" href=\"http:\/\/www.unz.com\/pbuchanan\/gop-elites-call-for-purge-of-trump\/\">14 ao&ucirc;t 2015<\/a> dans <em>UNZ.com<\/em>. Il d\u00e9crit comment les caciques du GOP veulent liquider Trump et le d\u00e9fend en acceptant les r\u00e9f\u00e9rences des adversaires de Trump, c&rsquo;est-\u00e0-dire en citant des r\u00e9f\u00e9rences en Europe \u00e0 propos de la bataille anti-<em>establishment<\/em> (antiSyst\u00e8me pour nous) et en d\u00e9fendant le principe de souverainet\u00e9 et d&rsquo;identit\u00e9 nationales.<\/p>\n<\/p>\n<p><p>&laquo;<em>Trump would be wise to maintain his freedom of action. For there is a plot afoot in The Washington Post Conservative Club to purge Trump from the Republican Party before the primaries begin. \u00ab\u00a0A political party has a right to &hellip; secure its borders,\u00a0\u00bb asserts the Post&rsquo;s George Will, \u00ab\u00a0a duty to exclude interlopers.\u00a0\u00bb Will wants The Donald \u00ab\u00a0excommunicated\u00a0\u00bb and locked out of all GOP debates until he kneels and takes a loyalty oath to the nominee. \u00ab\u00a0Marginalizing Trump\u00a0\u00bb carries no risk of \u00ab\u00a0alienating a substantial Republican cohort,\u00a0\u00bb Will assures us, for these \u00ab\u00a0Trumpites\u00a0\u00bb are neither Republicans nor conservatives. Better off without such trash.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>The Post&rsquo;s Michael Gerson says \u00ab\u00a0establishment Republicans\u00a0\u00bb must \u00ab\u00a0make clear that<\/em> [Trump] <em>has moved beyond the boundaries of serious and civil discourse.\u00a0\u00bb He loathes the Trumpites as much as Will. Trump&rsquo;s followers are \u00ab\u00a0xenophobic,\u00a0\u00bb Gerson tells CNN. They have a \u00ab\u00a0resentment of outsiders, of Mexico, of China, and immigrants. That&rsquo;s more like a European right-wing party, a UKIP or a National Front in France. Republicans can&rsquo;t incorporate that.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>But if the GOP has no room for Trump&rsquo;s followers, it has no future. For there simply aren&rsquo;t that many chamber-of-commerce and country-club Republicans. Gerson mentions with disgust the U.K. Independence Party and France&rsquo;s National Front. What do those parties have in common? Both are anti-New World Order. Both arose to recapture the lost independence and sovereignty of their nations from the nameless, faceless bureaucrats of Brussels, those EU hacks who now dictate the kinds of laws and societies the Brits and French are permitted to have&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; &#8230; Nous voici donc en Europe (FN,UKIP, etc.), et dans un d\u00e9bat (souverainet\u00e9 et identit\u00e9s nationales) qui nous est familier, et qu&rsquo;on trouve \u00e9galement autour de la question de l&rsquo;euro, et de la r\u00e9cente crise qui vient de d\u00e9chirer l&rsquo;Europe en opposant l&rsquo;<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_n_cessaire_lutte_mort_avec_l_orque_26_07_2015.html\">Orque<\/a> qu&rsquo;est l&rsquo;UE et la Gr\u00e8ce, avec diverses positions, diverses personnalit\u00e9s, etc., qu&rsquo;il est difficile de regrouper sous quelques \u00e9tiquettes qui faciliteraient la pens\u00e9e la feraient tomber dans le pi\u00e8ge de la conformation aux us et coutumes de la pens\u00e9e-Syst\u00e8me. C&rsquo;est par rapport \u00e0 cette question de l&rsquo;appartenance au Syst\u00e8me, et de la r\u00e9bellion contre le syst\u00e8me que nous citons Jacques Sapir \u00e0 propos du Grec Varoufakis (&laquo; Quel avenir pour Varoufakis?&raquo;, le <a class=\"gen\" href=\"http:\/\/russeurope.hypotheses.org\/4209\">13 ao&ucirc;t 2015<\/a>). Sapir, qui a montr\u00e9 de plus en plus d&rsquo;int\u00e9r\u00eat pour Varoufakis, esquisse la description de sa trajectoire d&rsquo;une position au c&oelig;ur du Syst\u00e8me \u00e0 une position antiSyst\u00e8me, avec ce qui pourrait \u00eatre un rassemblement, ou bien un ph\u00e9nom\u00e8ne d&rsquo;imitation d&rsquo;autres personnalit\u00e9s venant elle aussi du Syst\u00e8me. On peut lire ce passage, qui donne une id\u00e9e g\u00e9n\u00e9rale de l&rsquo;orientation de la r\u00e9flexion (Sapir cite Stefano Fassina et son \u00ab\u00a0appel contre l&rsquo;euro\u00a0\u00bb [voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-une_insurrection_contre_l_euro__05_08_2015.html\">5 ao&ucirc;t 2015<\/a>].)&#8230;<\/p>\n<\/p>\n<p><p>&laquo;<em>D&rsquo;ailleurs, il faut remarquer qu&rsquo;il h\u00e9berg\u00e9 sur son blog l&rsquo;appel de Stefano Fassina \u00e0 un front des mouvements de lib\u00e9ration anti-Euro. C&rsquo;est un geste qui est tr\u00e8s symbolique. Car Fassina, lui aussi, vient de l&rsquo;int\u00e9rieur du \u00ab\u00a0syst\u00e8me\u00a0\u00bb. Il fut vice-ministre des finances du gouvernement Letta en Italie. C&rsquo;est un membre influent du parti de centre-gauche, le Parti D\u00e9mocrate, auquel appartient l&rsquo;actuel Premier-ministre, Matteo Renzi. Or, aujourd&rsquo;hui, il est devenu l&rsquo;un des plus virulents opposants \u00e0 l&rsquo;Euro en Italie et son appel n&rsquo;est rien de moins que l&rsquo;un des plus virulents br&ucirc;lots qui ait \u00e9t\u00e9 \u00e9crit contre l&rsquo;Euro. Varoufakis et Fassina sont donc repr\u00e9sentatifs de cette fracture qui s&rsquo;est produite au sein du \u00ab\u00a0syst\u00e8me\u00a0\u00bb, de ce que l&rsquo;un de mes amis italiens, le professeur Bagnai, appelle le PUDE ou Parti Unique De l&rsquo;Euro. Leur trajectoire vers des positions anti-Euro p\u00e8se d&rsquo;autant plus qu&rsquo;ils ont \u00e9t\u00e9 ant\u00e9rieurement des partisans de l&rsquo;Euro. On pourrait en dire de m\u00eame d&rsquo;ailleurs avec Oskar Lafontaine, qui en tant que dirigeant du SPD fut l&rsquo;un des p\u00e8res fondateurs de l&rsquo;Euro, et qui a, en 2013, vir\u00e9 sa cuti d&rsquo;opposant r\u00e9solu \u00e0 la monnaie unique. Ce fait est d\u00e9sormais tr\u00e8s important. De plus en plus le camp des \u00e9conomistes et des politiciens anti-Euro, ou \u00e0 tout le moins tr\u00e8s Euro-critiques, est rejoint par des personnes qui \u00e9taient il y a peu encore des partisans de l&rsquo;Euro mais que la r\u00e9alit\u00e9 de cet Euro a rattrap\u00e9 et qui ont compris qu&rsquo;il n&rsquo;y a pas d&rsquo;avenir possible en Europe tant que l&rsquo;on gardera l&rsquo;Euro.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Un de nos lecteurs (voir le <em>Forum<\/em> du texte du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-vertigo_suite_chinoise_14_08_2015.html\">14 ao&ucirc;t 2015<\/a>, ce <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/forum-vertigo_suite_chinoise_14_08_2015.html\">16 ao&ucirc;t 2015<\/a>, le message de <em>GEO<\/em>) signale un message de retour de M\u00e9lenchon, qui montre \u00e9galement une mont\u00e9e de la tension. D&rsquo;une fa\u00e7on diff\u00e9rente mais toujours dans le m\u00eame sens, l&rsquo;affirmation de Jeremy Corbyn, dont l&rsquo;orientation est radicalement diff\u00e9rente de celle du <em>New Labour<\/em> de Blair et dont l&rsquo;ascension vers la direction du parti travailliste soul\u00e8ve une v\u00e9ritable fureur chez ce m\u00eame Blair, &ndash; excellent signe pour notre compte, &ndash; constitue un ph\u00e9nom\u00e8ne similaire pour sa ligne principale (voir RT le <a class=\"gen\" href=\"http:\/\/www.rt.com\/uk\/312558-corbyn-labour-poll-electorate\/\">15 ao&ucirc;t 2015<\/a>, &laquo;<em>Not just lefties: Corbyn most popular Labour candidate with entire electorate, says new poll<\/em>&raquo;).<\/p>\n<\/p>\n<p><p>&bull; Nous choisissons \u00e0 dessein des circonstances, des personnalit\u00e9s que beaucoup de choses s\u00e9parent, parfois jusqu&rsquo;\u00e0 sembler inconciliables. Nous montrons \u00e9galement, parall\u00e8lement, la rapidit\u00e9 de l&rsquo;\u00e9volution actuelle des r\u00e9flexions, des r\u00e9actions, des \u00e9valuations. On comprend \u00e9videmment qu&rsquo;il y a une similitude profonde, m\u00eame si l&rsquo;id\u00e9e impliqu\u00e9e en apparence choque certains et d\u00e9pla&icirc;t \u00e0 d&rsquo;autres, dans le fait de voir des personnalit\u00e9s aussi diff\u00e9rentes faire appel directement ou indirectement, d&rsquo;une fa\u00e7on consciente ou inconsciemment, aux principes de souverainet\u00e9 et d&rsquo;identit\u00e9 nationales par le biais de cons\u00e9quences directes ou indirectes de ces principes. La diff\u00e9rence des personnalit\u00e9s, des circonstances, des orientations est en soi une indication imp\u00e9rative que l&rsquo;on approche des engagements fondamentaux, o&ugrave; il ne sera plus question que de Syst\u00e8me et d&rsquo;antiSyst\u00e8me, dans une situation o&ugrave; la tension commence \u00e0 faire <strong>craquer de l&rsquo;int\u00e9rieur<\/strong> le tissu de r\u00e9sistance du Syst\u00e8me, avec des appr\u00e9ciations <strong>de l&rsquo;ext\u00e9rieur<\/strong> que ces craquements se produisent effectivement.<\/p>\n<\/p>\n<p><p>Bien entendu, les \u00e9v\u00e8nements ext\u00e9rieurs, notamment l&rsquo;\u00e9volution <a class=\"gen\" href=\" http:\/\/www.dedefensa.org\/article-vertigo_suite_chinoise_14_08_2015.html\">chinoise<\/a> mais aussi nombre de pr\u00e9visions catastrophiques plus ou moins solides, offrent le cadre assombri et tragique n\u00e9cessaire \u00e0 l&rsquo;\u00e9volution que nous d\u00e9crivons, et m\u00eame le cadre assombri et tragique que les acteurs eux-m\u00eames r\u00e9clament plus ou moins consciemment pour que leur action soit effectivement per\u00e7ue et ressentie (y compris par eux-m\u00eames) selon la conception eschatologique qui importe&#8230; (Entendez les ricanements satisfaits de M\u00e9lenchon, par rapport \u00e0 la d\u00e9valuation chinoise, qui saluent la n\u00e9cessaire dramatisation des \u00e9v\u00e8nements : &laquo;<em>Les Chinois d\u00e9valuent leur monnaie sous cot\u00e9e pour rendre leur salaires comp\u00e9titifs ! Bref les Chinois jouent aux Allemands&hellip; Les Allemands vont d\u00e9guster. Car leurs ch\u00e8res grosses bagnoles vont couter l\u00e0-bas bien plus cher et les machines-outils seront bien moins remplac\u00e9es si la production baisse. R\u00e9sultat les Chinois font aux Allemands ce que l&rsquo;Allemagne fait \u00e0 l&rsquo;Europe tout enti\u00e8re. La pagaille g\u00e9n\u00e9rale est garantie. Un terrible coup de froid sur le moteur absurde de la croissance mondiale sans fin se dessine \u00e0 horizon rapproch\u00e9. L&rsquo;Europe va trinquer. La Gr\u00e8ce va couler&#8230;<\/em>&raquo;)<\/p>\n<\/p>\n<p><p>Une seule chose compte, &ndash; que notre essence m\u00eame devienne antiSyst\u00e8me. Ainsi apparaissent des parall\u00e8les qui se r\u00e9v\u00e8lent comme des convergences,&ndash; on ne leur demande pas leur avis ! &ndash; qui auraient sembl\u00e9 il y a quelques mois impensables, absurdes sinon obsc\u00e8nes. C&rsquo;est que, d\u00e9sormais, il doit nous appara&icirc;tre de plus en plus en pleine lumi\u00e8re que le Syst\u00e8me, qui ram\u00e8ne tout \u00e0 lui, a monopolis\u00e9 pour lui seul tout l&rsquo;impensable, toute l&rsquo;absurdit\u00e9, toute l&rsquo;obsc\u00e9nit\u00e9 du monde ; et celui qui, sortant de lui, se retrouve amen\u00e9 \u00e0 se manifester contre lui, ne peut \u00eatre impensable, absurde ni obsc\u00e8ne, &ndash; f&ucirc;t-ce <em>The Donald<\/em> soi-m\u00eame. Il ne s&rsquo;agit pas d&rsquo;un concours de beaut\u00e9 morale, d&rsquo;\u00e9l\u00e9gance politique et de vertu citoyenne, mais d&rsquo;une bataille qui a la duret\u00e9 rocailleuse et furieuse de la survie.<\/p>\n<\/p>\n<p><p>&#8230; On observera d&rsquo;ailleurs, pour animer le symbole qui nous vient sous la plume et lui donner un peu plus de consistance, combien Trump et Varoufakis sont, en quelque sorte, \u00e0 la fois les images et les caricatures de deux arch\u00e9types essentiels du Syst\u00e8me, &ndash; le milliardaire excentrique, inculte et grossier qui a fait sa fortune dans la sp\u00e9culation compl\u00e8tement am\u00e9ricaniste d&rsquo;une part, et d&rsquo;autre part le <em>playboy<\/em>\/ministre-<em>rock&rsquo;n&rsquo;roll<\/em> sophistiqu\u00e9, adepte de la th\u00e9orie des jeux qui s&rsquo;habille d&rsquo;un <em>tea-shirt<\/em> et roule \u00e0 moto comme un de ces <em>wonder-boys<\/em> des grands groupes de l&rsquo;internet&#8230; Peut-on r\u00eaver figures plus embl\u00e9matiques de la postmodernit\u00e9, donc du Syst\u00e8me ? Les voil\u00e0 propuls\u00e9s dans le r\u00f4le de l&rsquo;antiSyst\u00e8me qui conchie le Syst\u00e8me encore mieux que vous et moi parce qu&rsquo;il vient de son c&oelig;ur et qu&rsquo;il le conna&icirc;t par c&oelig;ur&#8230;<\/p>\n<\/p>\n<p><p>Si vous croyez aux signes du Ciel plut\u00f4t que de chercher des complots et des <em>false flags<\/em> dans les poubelles du Syst\u00e8me, ce qui n&rsquo;est pas le choix le plus stupide, alors il faut donner \u00e0 ce symboles des deux arch\u00e9types du Syst\u00e8me pouss\u00e9s vers l&rsquo;antiSyst\u00e8me tout son poids symbolique. &Eacute;ventuellement, on peut le placer dans le courant fi\u00e9vreux qui s&rsquo;affirme actuellement, depuis quelques jours, &ndash; \u00ab\u00a0fi\u00e8vre de l&rsquo;automne 2015\u00a0\u00bb ou \u00ab\u00a0fi\u00e8vre de septembre 2015\u00a0\u00bb qui multiplient les signes d&rsquo;une catastrophe imminente (voir aussi le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_n_cessaire_lutte_mort_avec_l_orque_26_07_2015.html\">26 juillet 2015<\/a>), &ndash; ou plut\u00f4t les signes d&rsquo;une catastrophe multiple (voir le <a class=\"gen\" href=\"http:\/\/www.historel.net\/jclbernard\/septembre2015\/\">11 ao&ucirc;t 2015<\/a>) selon une agitation extr\u00eame du syst\u00e8me de la communication ; moins \u00ab\u00a0officielle\u00a0\u00bb (avec participation\/complicit\u00e9 du Syst\u00e8me) que cela ne fut avant le faux-<em>buzz<\/em> gigantesque du 1er janvier 2 000 ou la Fin des Temps de d\u00e9cembre 2012 du calendrier Mayas, bien plus appuy\u00e9e sur une situation g\u00e9n\u00e9rale potentiellement catastrophique dont les d\u00e9placements paradoxaux de personnalit\u00e9s type-Trump\/Varoufakis font \u00e9videmment partie&#8230; On voit que nous sommes partis d&rsquo;\u00e9v\u00e8nements aujourd&rsquo;hui assez courants et anodins (cela aussi, signe des temps, que de tels \u00e9v\u00e8nements puissent \u00eatre qualifi\u00e9s d'\u00a0\u00bbanodins\u00a0\u00bb) pour aboutir aux in\u00e9vitables allusions \u00e0 la Grande Crise d&rsquo;effondrement du Syst\u00e8me. Tous les chemins m\u00e8nent \u00e0 Rome disait-on, toutes les voies de la pens\u00e9e conduisent \u00e0 notre Grande Crise peut-on rectifier.<\/p>\n<\/p>\n<p><p>Mis en ligne le 17 ao&ucirc;t 2015 \u00e0 08H51<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trump-Varoufakis et la logique catastrophique des convergences Il n&rsquo;y a pas tr\u00e8s longtemps, puisqu&rsquo;il s&rsquo;agit d&rsquo;un texte du 31 juillet 2015, nous relevions le fait, &ndash; que nous voulions \u00ab\u00a0objectif\u00a0\u00bb, c&rsquo;est-\u00e0-dire sans nous interroger sur les parti-pris, les id\u00e9ologies, les engagements des uns et des autres, &ndash; que le Syst\u00e8me produisait de plus en plus&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8847,3335,16869,2604,7548,2985,3841,5000,3330,2943,3387,5870,7588,4337,7823,3321,6750],"class_list":["post-76063","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-8847","tag-buchanan","tag-catastrophiques","tag-des","tag-eschatologie","tag-fin","tag-grece","tag-illegale","tag-immigration","tag-mexique","tag-noir","tag-octobre","tag-previsions","tag-raimondo","tag-sapir","tag-septembre","tag-temps"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76063"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76063\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}