{"id":76118,"date":"2015-09-19T18:14:16","date_gmt":"2015-09-19T18:14:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/09\/19\/lusaf-et-la-russie-en-syrie\/"},"modified":"2015-09-19T18:14:16","modified_gmt":"2015-09-19T18:14:16","slug":"lusaf-et-la-russie-en-syrie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/09\/19\/lusaf-et-la-russie-en-syrie\/","title":{"rendered":"L&rsquo;USAF et la Russie en Syrie"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">L&rsquo;USAF et la Russie en Syrie<\/h2>\n<\/p>\n<p><p>Une appr\u00e9ciation de la pr\u00e9sence militaire russe en Syrie (ou pas) est venue d&rsquo;un g\u00e9n\u00e9ral de l&rsquo;US Air Force, lors d&rsquo;une intervention \u00e0 l&rsquo;une des deux conventions annuelles de l&rsquo;Air Force Association (AFA), le principal lobby officiel de l&rsquo;USAF. Comme on l&rsquo;a d\u00e9j\u00e0 dit \u00e0 plusieurs reprises, les interventions des chefs de l&rsquo;USAF aux conventions de l&rsquo;AFA repr\u00e9sentent en g\u00e9n\u00e9ral les communications les plus directes et les plus conformes aux conceptions et aux analyses de l&rsquo;USAF, tant sur le plan op\u00e9rationnel que sur le plan plus large, politico-militaire. L&rsquo;intervention du g\u00e9n\u00e9ral Hesterman, actuel adjoint au chef d&rsquo;\u00e9tat-major de l&rsquo;USAF doit donc \u00eatre analys\u00e9e avec int\u00e9r\u00eat. Avant ce poste, Hesterman a \u00e9t\u00e9 le chef des forces a\u00e9riennes pour CENTCOM (Central Command), de 2013 \u00e0 2015 ; la Syrieest do,nc un de ses points d&rsquo;int\u00e9r\u00eat particulier.<\/p>\n<\/p>\n<p><p><a href=\"http:\/\/www.airforcemag.com\/DRArchive\/Pages\/2015\/September%202015\/September%2021%202015\/The-Russia-Calculus-in-Syria.aspx\">Son appr\u00e9ciation<\/a> (selon le <em>Daily Digest<\/em> d&rsquo;AFA) est assez claire quoiqu&rsquo;indirecte : les Russes sont en Syrie ou sont sur le point d&rsquo;y \u00eatre, \u00e0 un niveau op\u00e9rationnel \u00e9lev\u00e9. Ce d\u00e9ploiement ne constitue aucune menace directe pour les forces a\u00e9riennes US (\u00ab\u00a0Ces gens ne sont pas int\u00e9ress\u00e9s par des actions a\u00e9riennes contre les forces US pr\u00e9sentes sur le th\u00e9\u00e2tre\u00a0\u00bb) ; les Russes sont l\u00e0 pour prot\u00e9ger Assad contre des incursions adverse et faire en sorte que \u00ab\u00a0les ennemis d&rsquo;Assad\u00a0\u00bb, y compris des forces US, ne \u00ab\u00a0s&rsquo;approchent pas trop de lui\u00a0\u00bb. Dans ces conditions nouvelles, estime Hesterman qui ne manifeste gu\u00e8re d&rsquo;anatagonisme vis\u00e0-vis de cette incursion des Russes, le conflit en Syrie devra se terminer par un arrangement politique o&ugrave; les Russes auront une place importante.<\/p>\n<\/p>\n<blockquote>\n<p><p>Par contre, Hesterman se montre beaucoup moins assur\u00e9 quant au nouvel \u00e9quilibre des forces que va amener la pr\u00e9sence des Russes, si elle rendra \u00ab\u00a0la situation pire ou meilleure\u00a0\u00bb (y compris et surtout pour les USA, peut-on comprendre). Cela semble indiquer que l&rsquo;USAF tient la pr\u00e9sence russe pour acquise, qu&rsquo;elle l&rsquo;accepte quasiment comme l\u00e9gitime, qu&rsquo;elle la juge comme d\u00e9cisive pour conduire \u00e0 de n\u00e9cessaires n\u00e9gociations, mais qu&rsquo;elle ignore ce que cette pr\u00e9sence produira comme nouvelle situation strat\u00e9gique. (Sur ce dernier point, on peut comprendre qu&rsquo;il y a l\u00e0 la crainte que la pr\u00e9sence russe constitue une tr\u00e8s s\u00e9rieuse mise en cause de la pr\u00e9pond\u00e9rance US qui r\u00e9gnait jusqu&rsquo;alors dans la r\u00e9gion, ce qui est notamment l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article\/situation-syrienne-et-strategie-israelienne\">analyse isra\u00e9lienne<\/a>. Mais Hesterman ne semble pas estimer que quoi que ce soit puisse, ni m\u00eame doive \u00eatre fait contre cela. C&rsquo;est un des premiers signes que la direction militaire US est pr\u00eate \u00e0 reconna&icirc;tre un s\u00e9rieux d\u00e9clin de son statut h\u00e9g\u00e9monique dans la zone vitale contr\u00f4l\u00e9e par CENTCOM, au profit de la Russie.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&laquo; <em>The introduction of Russian military forces and equipment into the Syrian civil war will make the conflict \u00ab\u00a0far more complicated,\u00a0\u00bb but the long-term impact on the fighting is very unclear, the former head of Air Forces Central Command said at ASC15 on Sept. 16. Lt. Gen. John Hesterman, the Air Force assistant vice chief of staff and former AFCENT commander from July 2013 to June 2015, said any operational commander would be concerned about \u00ab\u00a0misinterpretation\u00a0\u00bb in an environment where coalition aircraft are already flying anti-ISIS sorties over Syria. \u00ab\u00a0But those guys aren&rsquo;t interested in being in the air against the United States there,\u00a0\u00bb Hesterman said, adding these forces are reinforcing Syrian President Bashar al-Assad&rsquo;s regime and making sure the US and its domestic enemies \u00ab\u00a0don&rsquo;t get too close.\u00a0\u00bb Hesterman added that anyone who has had to pay close attention to Syria will eventually conclude that the fighting will only end through a negotiated settlement, and with Russia&rsquo;s entry into the fighting it likely gives Moscow a seat \u00ab\u00a0when negotiations start.\u00a0\u00bb The impact on the military balance, however, remains unclear. \u00ab\u00a0I don&rsquo;t know if it makes it worse or better,\u00a0\u00bb he added.<\/em> &raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;USAF et la Russie en Syrie Une appr\u00e9ciation de la pr\u00e9sence militaire russe en Syrie (ou pas) est venue d&rsquo;un g\u00e9n\u00e9ral de l&rsquo;US Air Force, lors d&rsquo;une intervention \u00e0 l&rsquo;une des deux conventions annuelles de l&rsquo;Air Force Association (AFA), le principal lobby officiel de l&rsquo;USAF. Comme on l&rsquo;a d\u00e9j\u00e0 dit \u00e0 plusieurs reprises, les interventions&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[248,3143,8473,7059,3318,3650,16956,2774,2730,3867,41],"class_list":["post-76118","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-afa","tag-air","tag-association","tag-centcom","tag-force","tag-hegemonie","tag-hesterman","tag-israel","tag-russie","tag-syrie","tag-usaf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76118"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76118\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}