{"id":76122,"date":"2015-09-21T13:07:16","date_gmt":"2015-09-21T13:07:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/09\/21\/la-fed-ou-le-temps-suspendu\/"},"modified":"2015-09-21T13:07:16","modified_gmt":"2015-09-21T13:07:16","slug":"la-fed-ou-le-temps-suspendu","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/09\/21\/la-fed-ou-le-temps-suspendu\/","title":{"rendered":"La Fed, ou le temps suspendu"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La Fed, ou le temps suspendu<\/h2>\n<\/p>\n<p><p>La Federal Reserve a pris la d\u00e9cision, ce jeudi 17 septembre, de ne pas relever son taux directeur d&rsquo;int\u00e9r\u00eat, qui reste quasiment au niveau z\u00e9ro (entre 0% et 0,25%) depuis fin 2008. La d\u00e9cision de rel\u00e8vement du taux est attendue depuis un certain temps, selon les indications qu&rsquo;avait donn\u00e9es la Federal Reserve elle-m\u00eame, et la r\u00e9union de la Federal Open Market Committee (FOMC) du 17 \u00e9tait largement d\u00e9sign\u00e9e comme le moment o&ugrave; ce rel\u00e8vement serait annonc\u00e9. Il n&rsquo;en a rien \u00e9t\u00e9. Alors que la pr\u00e9sidente de la Federal Reserve, Janet Yellen, continue \u00e0 annoncer qu&rsquo;une d\u00e9cision de rel\u00e8vement (minime) devrait \u00eatre prise d&rsquo;ici la fin 2015, en octobre ou en d\u00e9cembre (les deux derni\u00e8res r\u00e9unions pr\u00e9vues de la FOMC pour 2015), le nombre de membres de la FOMC estimant que ce rel\u00e8vement n&rsquo;aura pas lieu \u00ab\u00a0avant 2016 <strong>au plus t\u00f4t<\/strong>\u00a0\u00bb est pass\u00e9 de deux \u00e0 quatre.<\/p>\n<\/p>\n<p><p>Dans un texte du 19 septembre (en fran\u00e7ais), <em>WSWS.org<\/em> <a href=\"http:\/\/www.wsws.org\/fr\/articles\/2015\/sep2015\/feam-s19.shtml\">explique la d\u00e9cision<\/a> de la Federal Reserve en s&rsquo;en tenant g\u00e9n\u00e9ralement aux faits et sans sa forme comment\u00e9e habituelle. Une place tr\u00e8s importante est donn\u00e9e dans cette analyse \u00e0 l&rsquo;\u00e9volution de l&rsquo;\u00e9conomie mondiale, \u00e0 l&rsquo;image du communiqu\u00e9 officiel et de la pr\u00e9sentation que la pr\u00e9sidente de la Fed a faite des r\u00e9sultats de la r\u00e9union lors d&rsquo;une conf\u00e9rence de presse.<\/p>\n<\/p>\n<p><p>&laquo; <em>La r\u00e9union jeudi de l&rsquo;Open Market Committee de la Fed (FOMC), qui \u00e9labore sa politique, a suscit\u00e9 de fortes inqui\u00e9tudes \u00e0 l&rsquo;\u00e9chelle internationale \u00e9tant donn\u00e9 le net ralentissement de la croissance mondiale et la volatilit\u00e9 extr\u00eame des march\u00e9s financiers. Le fait que la r\u00e9union de la Fed ait \u00e9t\u00e9 au centre de l&rsquo;attention internationale t\u00e9moigne du degr\u00e9 auquel l&rsquo;\u00e9conomie mondiale tout enti\u00e8re est devenue d\u00e9pendante des perfusions d&rsquo;argent des grandes banques centrales dans les march\u00e9s financiers.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La d\u00e9claration du FOMC a d&rsquo;abord suscit\u00e9 une quasi-euphorie sur les march\u00e9s, faisant remonter le Dow Jones Industrial Average de plus de 100 points dans la premi\u00e8re heure suivant sa publication. Lorsque la cha&icirc;ne c\u00e2bl\u00e9e am\u00e9ricaine CNBC a annonc\u00e9 la d\u00e9cision \u00e0 14 heures, il y eut une acclamation audible depuis le parquet de la Bourse de New York. Mais la reprise s&rsquo;est essouffl\u00e9e et les actions am\u00e9ricaines ont termin\u00e9 la journ\u00e9e sur des r\u00e9sultats mitig\u00e9s. Le Dow a ferm\u00e9 avec 65 points de baisse et l&rsquo;indice 500 de Standard &#038; Poor a chut\u00e9 de 5 points, tandis que le Nasdaq bouclait sur une l\u00e9g\u00e8re hausse de pr\u00e8s de 5 points.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il semblerait que l&rsquo;exub\u00e9rance initiale devant la d\u00e9cision de retarder la hausse des taux a \u00e9t\u00e9 temp\u00e9r\u00e9e par l&rsquo;inqui\u00e9tude sur l&rsquo;\u00e9tat de l&rsquo;\u00e9conomie et du syst\u00e8me financier mondiaux comme en t\u00e9moigne la d\u00e9claration du FOMC. S&rsquo;\u00e9cartant nettement de d\u00e9clarations pr\u00e9c\u00e9dentes de la Fed, qui se r\u00e9f\u00e8re rarement aux conditions internationales, ce dernier communiqu\u00e9 a d&rsquo;abord constat\u00e9 que les exportations \u00e9taient \u00ab\u00a0molles\u00a0\u00bb et que l&rsquo;inflation avait \u00e9volu\u00e9 bien en de\u00e7\u00e0 de l&rsquo;objectif de 2 pour cent de la Fed pour dire ensuite: \u00ab\u00a0Les r\u00e9cents d\u00e9veloppements \u00e9conomiques et financiers mondiaux risquent de limiter quelque peu l&rsquo;activit\u00e9 \u00e9conomique et sont susceptibles de mettre davantage de pression \u00e0 la baisse sur l&rsquo;inflation \u00e0 court terme\u00a0\u00bb. C&rsquo;\u00e9tait l\u00e0 une allusion \u00e0 des donn\u00e9es montrant un net ralentissement de l&rsquo;activit\u00e9 industrielle, des exportations et de l&rsquo;inflation de la Chine qui repr\u00e9sente la moiti\u00e9 de la croissance mondiale depuis le krach de 2008. Les march\u00e9s boursiers chinois ont subi des pertes \u00e9normes et le yuan a \u00e9t\u00e9 d\u00e9valu\u00e9 inopin\u00e9ment le mois dernier.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La stagnation de la Chine a exacerb\u00e9 les probl\u00e8mes \u00e9conomiques et financiers d&rsquo;autres soi-disant \u00ab\u00a0\u00e9conomies de march\u00e9 \u00e9mergentes\u00a0\u00bb d\u00e9pendant fortement des exportations de mati\u00e8res premi\u00e8res comme le Br\u00e9sil, la Russie, la Turquie, l&rsquo;Afrique du Sud et certaines \u00e9conomies asiatiques. Ces pays ont connu une forte baisse de leur croissance, de leurs exportations et de la valeur de leurs devises, tandis que leurs dettes sont devenues de plus en plus insoutenables du \u00e0 la force croissante du dollar am\u00e9ricain. En m\u00eame temps, l&rsquo;\u00e9conomie europ\u00e9enne cro&icirc;t \u00e0 peine et celle du Japon s&rsquo;est contract\u00e9e au deuxi\u00e8me trimestre.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les signes d&rsquo;une intensification de la r\u00e9cession abondent&#8230;<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>La convergence de ces d\u00e9veloppements a suscit\u00e9 des bonds erratiques sur les march\u00e9s boursiers aux USA et dans le monde, le mois dernier. &Agrave; un moment, apr\u00e8s une chute de pr\u00e8s de 1.000 points du Dow Jones quelques minutes apr\u00e8s l&rsquo;ouverture, William C. Dudley, le pr\u00e9sident de la Federal Reserve Bank de New York, a dit aux journalistes que les d\u00e9veloppements internationaux avaient rendu \u00ab\u00a0moins convaincants\u00a0\u00bb les arguments en faveur d&rsquo;une hausse des taux d&rsquo;int\u00e9r\u00eat de la Fed en septembre. Cette intervention, en rassurant l&rsquo;aristocratie financi\u00e8re et en lui disant que la Fed continuerait \u00e0 garantir ses fortunes et reporterait probablement une hausse des taux, a eu l&rsquo;effet escompt\u00e9 de pr\u00e9venir un effondrement complet du march\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Parmi les organisations et les individus ayant demand\u00e9 \u00e0 la Fed de ne pas augmenter les taux \u00e0 sa r\u00e9union de jeudi il y avait le Fonds mon\u00e9taire international, la Banque mondiale, l&rsquo;ancien secr\u00e9taire am\u00e9ricain au Tr\u00e9sor, Lawrence Summers, l&rsquo;investisseur milliardaire Warren Buffett et le PDG de Goldman Sachs, Lloyd Blankfein. La semaine derni\u00e8re, l&rsquo;\u00e9conomiste en chef de la Banque mondiale a dit au Financial Times que la Fed risquait de d\u00e9clencher \u00ab\u00a0panique et agitation\u00a0\u00bb si elle relevait les taux.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Alors que dans les milieux financiers le sentiment pr\u00e9domine pour repousser une hausse des taux aussi longtemps que possible, des forces oppos\u00e9es soutiennent que plus la Fed attend avant de commencer \u00e0 augmenter les taux, plus l&rsquo;incertitude r\u00e8gne et pire seront les cons\u00e9quences \u00e9conomiques et financi\u00e8res. La semaine derni\u00e8re, l&rsquo;\u00e9conomiste en chef am\u00e9ricain de JPMorgan Chase a exhort\u00e9 la Fed \u00e0 commencer \u00e0 relever les taux \u00e0 sa r\u00e9union jeudi. Un membre du FOMC, Jeffrey Lacker, pr\u00e9sident de la Fed de Richmond, en Virginie, a vot\u00e9 contre la d\u00e9cision de maintenir les taux \u00e0 pr\u00e8s de z\u00e9ro, disant qu&rsquo;il favorisait une augmentation imm\u00e9diate de 0,25 pour cent. Son vote \u00e9tait la premi\u00e8re dissidence au sein du FOMC cette ann\u00e9e.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Dans son communiqu\u00e9, le FOMC a cherch\u00e9 \u00e0 rassurer les march\u00e9s; m\u00eame s&rsquo;il commen\u00e7ait \u00e0 relever ses taux d\u00e8s octobre ou d\u00e9cembre, les augmentations seraient petites et progressives. La d\u00e9claration disait: \u00ab\u00a0Le Comit\u00e9 pr\u00e9voit \u00e0 pr\u00e9sent que, m\u00eame si l&#8217;emploi et l&rsquo;inflation sont proches des niveaux mandat\u00e9s, il se peut que les conditions \u00e9conomiques n\u00e9cessitent, pendant un certain temps, le maintien du taux de la Fed en dessous des niveaux que le Comit\u00e9 <\/em>[de la Fed]<em> estime \u00eatre normaux \u00e0 long terme\u00a0\u00bb. Dans une conf\u00e9rence de presse suivant la sortie de la d\u00e9claration, la pr\u00e9sidente de la Fed Janet Yellen a r\u00e9it\u00e9r\u00e9 la pr\u00e9occupation de la banque centrale au sujet des d\u00e9veloppements mondiaux. \u00ab\u00a0A la lumi\u00e8re de l&rsquo;incertitude accrue \u00e0 l&rsquo;\u00e9tranger\u00a0\u00bb, a-t-elle dit, \u00ab\u00a0le Comit\u00e9 a jug\u00e9 opportun d&rsquo;attendre\u00a0\u00bb, ajoutant, \u00ab\u00a0&Eacute;tant donn\u00e9 les interconnexions \u00e9conomiques et financi\u00e8res significatives entre les Etats-Unis et le reste du monde, la situation \u00e0 l&rsquo;\u00e9tranger m\u00e9rite d&rsquo;\u00eatre suivie de pr\u00e8s\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Les critiques de la d\u00e9cision de la Federal Reserve n&rsquo;ont certainement pas manqu\u00e9. Pour eux, il s&rsquo;agit d&rsquo;abord de l&rsquo;\u00e9volution de l&rsquo;\u00e9conomie, et plus encore du contr\u00f4le de l&rsquo;\u00e9volution de l&rsquo;\u00e9conomie. <em>ZeroHedge.com<\/em> publie, hier 20 septembre, une <a href=\"http:\/\/www.zerohedge.com\/news\/2015-09-20\/what-does-fed-know-we-dont-bridgewaters-ray-dalio-answers\">longue analyse<\/a> t\u00e9moignant de l&rsquo;\u00e9tat de l&rsquo;\u00e9conomie US, notamment en s&rsquo;appuyant sur des donn\u00e9es de <a href=\"https:\/\/en.wikipedia.org\/wiki\/Ray_Dalio\">Ray Dalio<\/a>, de Bridgewaters Associates. La conclusion est qu&rsquo;en l&rsquo;absence d&rsquo;une hausse des taux d&rsquo;int\u00e9r\u00eat et donc en cons\u00e9quence de la politique que suit la Federal Reserve, l&rsquo;\u00e9conomie US est sur la voie d&rsquo;une s\u00e9v\u00e8re r\u00e9cession, sinon d&rsquo;une d\u00e9pression. Le m\u00eame 20 septembre, Martin Armstrong met en ligne sur son site un commentaire aussi court qu&rsquo;il est sans appel, avec son titre qui est repris dans la premi\u00e8re ligne du texte : &laquo; <em>Yellen Is Trapped in the <a href=\"http:\/\/www.armstrongeconomics.com\/archives\/37256\">Worst Nightmare Ever<\/a><\/em> &raquo;&#8230; Voici le d\u00e9but et la fin de ce commentaire de Armstrong, avec l&rsquo;un et l&rsquo;autre mots qui nous importe principalement.<\/p>\n<\/p>\n<blockquote>\n<p><p>&laquo; <em>Yellen a h\u00e9rit\u00e9 d&rsquo;un v\u00e9ritable cauchemar. La d\u00e9cision de jeudi de la Fed d&rsquo;\u00e0 nouveau repousser la d\u00e9cision de faire sortir les taux d&rsquo;int\u00e9r\u00eat de sa ligne du z\u00e9ro illustre le fait que l&rsquo;\u00e9conomie du monde est totalement foutue<\/em>. [&#8230;]  <em>C&rsquo;est la pire des situations de <strong>d\u00e9sordre<\/strong> possibles et au plus ils attendront pour normaliser les taux d&rsquo;int\u00e9r\u00eat, au plus la crise g\u00e9n\u00e9rale s&rsquo;aggravera parce qu&rsquo;ils n&rsquo;auront absolument <strong>plus aucun contr\u00f4le<\/strong> sur l&rsquo;\u00e9conomie. Une fois que cela appara&icirc;tra au grand jour, l&rsquo;enfer se d\u00e9cha&icirc;nera<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il est vrai que cette r\u00e9union du 17 septembre \u00e9tait attendue avec int\u00e9r\u00eat, aussi bien d&rsquo;ailleurs pour son aspect symbolique que pour sa dimension op\u00e9rationnelle \u00e9vidente avec la question de la hausse des taux d&rsquo;int\u00e9r\u00eat. Elle \u00e9tait attendue symboliquement aussi, parce que depuis 2013 on attend et on annonce cette hausse qui prendrait l&rsquo;allure d&rsquo;une sorte d&rsquo;affirmation solennelle (et symbolique, certes) que \u00ab\u00a0nous\u00a0\u00bb sommes sortis de la crise dite de la Grande R\u00e9cession de 2008-2009, au cours de laquelle ces taux furent amen\u00e9s quasiment au plancher z\u00e9ro (en d\u00e9cembre 2008). La d\u00e9cision de jeudi dernier, telle qu&rsquo;elle a \u00e9t\u00e9 annonc\u00e9e, n&rsquo;a pas d\u00e9clench\u00e9 de commentaires particuli\u00e8rement sensationnels, ni \u00e9veill\u00e9 un int\u00e9r\u00eat inhabituel ; ainsi tout s&rsquo;est-il pass\u00e9 comme si la d\u00e9cision avait \u00e9t\u00e9 plut\u00f4t de ne pas d\u00e9cider, alors que, pourtant, ce choix de ne pas toucher aux taux d&rsquo;int\u00e9r\u00eat constituait une d\u00e9cision importante ; mais non, la Fed annonce qu&rsquo;elle d\u00e9cide effectivement de ne rien faire et tout se passe dans la perception qu&rsquo;on en recueille comme si elle n&rsquo;avait rien d\u00e9cid\u00e9&#8230; C&rsquo;est alors que les mots employ\u00e9s par Martin Armstrong ont tout leur int\u00e9r\u00eat : d&rsquo;une part, le d\u00e9sordre de la situation g\u00e9n\u00e9rale de l&rsquo;\u00e9conomie, qui se retrouve dans tous les autres domaines, que ce soit ceux de la politique et de la strat\u00e9gie, de la culture, de la psychologie, etc., qui est donc une condition m\u00eame d&rsquo;une \u00e9poque et d&rsquo;un monde ; d&rsquo;autre part, l&rsquo;absence compl\u00e8te de contr\u00f4le des autorit\u00e9s en place sur cette situation de d\u00e9sordre (par d\u00e9finition certes, mais il faut le dire puisque certains croient au \u00ab\u00a0chaos contr\u00f4l\u00e9\u00a0\u00bb), particuli\u00e8rement dans les pays du bloc BAO et aux USA par rapport au(x) r\u00f4le(s) qui leur sont impartis par le Syst\u00e8me, dans le Syst\u00e8me, &ndash; l\u00e0 aussi, cette absence de contr\u00f4le \u00ab\u00a0qui se retrouve dans tous les autres domaines, [&#8230;] qui est donc une condition m\u00eame d&rsquo;une \u00e9poque et d&rsquo;un monde\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Armstrong emploie essentiellement ces mots (d\u00e9sordre, absence de contr\u00f4le) pour d\u00e9crire l&rsquo;aspect technique des situations envisag\u00e9es ; nous sugg\u00e9rons de les utiliser plus g\u00e9n\u00e9ralement pour d\u00e9crire l&rsquo;essence m\u00eame de la situation, qui est litt\u00e9ralement en processus de compl\u00e8te dissolution, et qui touche n\u00e9cessairement tous les domaines (en ce sens o&ugrave; la politique de la Federal Reserve est d&rsquo;une certaine fa\u00e7on \u00e9quivalente \u00e0 la politique US en Syrie, pour ce qui est de la position des acteurs cens\u00e9s \u00e9noncer, conduire et appliquer ces politiques). La r\u00e9f\u00e9rence de la Federal Reserve \u00e0 la situation internationale qui tient d\u00e9sormais une place essentielle dans ses analyses jusqu&rsquo;\u00e0 les influencer d&rsquo;une fa\u00e7on d\u00e9cisive, aurait conduit <em>in illo tempore<\/em> \u00e0 une conclusion politique int\u00e9ressante, sur la r\u00e9duction acc\u00e9l\u00e9r\u00e9e de l&rsquo;h\u00e9g\u00e9monie US dans le syst\u00e8me financier et le syst\u00e8me \u00e9conomique mondial. Si cela reste en partie le cas, il s&rsquo;agit \u00e9galement, et m\u00eame plus encore, de l&rsquo;indication incontestable de la puissance du d\u00e9sordre de la situation g\u00e9n\u00e9rale, car c&rsquo;est bien ce d\u00e9sordre qui p\u00e8se de tout son poids sur les prises de position, et qui accule les directions \u00e0 des d\u00e9cisions \u00e0 court terme, \u00e0 potentialit\u00e9 contre-productive tr\u00e8s importante, et dans tous les cas qui accroissent naturellement l&rsquo;absence de contr\u00f4le de ces directions.<\/p>\n<\/p>\n<p><p>Si l&rsquo;on veut une autre image, on admettra que la forme de la d\u00e9cision de la Federal Reserve, qui semble tenir plus compte de la situation \u00e9conomique mondiale (hors-USA) que de la situation \u00e9conomique des USA, constitue un indice d&rsquo;une sorte de globalisation accomplie dans une sorte de \u00ab\u00a0gouvernance mondiale\u00a0\u00bb o&ugrave; des entit\u00e9s telles que l&rsquo;UE, l&rsquo;OTAN, la Federal Reserve, jouent des r\u00f4les effectivement transnationaux et supranationaux, &ndash; par exemple beaucoup plus qu&rsquo;\u00e0 l&rsquo;ONU o&ugrave; les nations sont encore fermement pr\u00e9sentes et repr\u00e9sent\u00e9es. (Dans le cas de la Federal Reserve, le fait que sa d\u00e9cision favorise <strong>\u00e9galement<\/strong> Wall Street et les super-riches US renforcent <em>a contrario <\/em>l&rsquo;image, en confirmant que Wall Street et les super-riches US ne font plus partie de l&rsquo;entit\u00e9-USA avec ses int\u00e9r\u00eats nationaux mais d&rsquo;une internationale de l&rsquo;entassement des richesses, de la sp\u00e9culation, de la d\u00e9r\u00e9gulation et d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale de la d\u00e9structuration syst\u00e9matique.) <\/p>\n<\/p>\n<blockquote>\n<p><p>Si l&rsquo;on accepte l&rsquo;image, alors la \u00ab\u00a0gouvernance mondiale\u00a0\u00bb que tout le monde annonce, qui pour l&rsquo;applaudir, qui pour la d\u00e9noncer, est ainsi accomplie <em>de facto<\/em>, elle est n\u00e9cessairement l&rsquo;<strong>enfant naturel <\/strong>du d\u00e9sordre et elle g\u00e9n\u00e8re n\u00e9cessairement, comme par <strong>g\u00e9n\u00e9ration spontan\u00e9e<\/strong>, l&rsquo;absence de contr\u00f4le. Elle sacrifie \u00e0 sa puissance et \u00e0 son impunit\u00e9 compl\u00e8te tous les principes de la l\u00e9gitimit\u00e9 et de l&rsquo;autorit\u00e9, ratant ainsi de transmuter la souverainet\u00e9 de ses composants qu&rsquo;elle a sacrifi\u00e9e en une nouvelle assise principielle.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le r\u00e9sultat, cette d\u00e9cision de la Fed, qui est vraiment une fa\u00e7on de d\u00e9cider de ne rien d\u00e9cider parce qu&rsquo;on ne comprend rien \u00e0 ce qui se passe, ressemble \u00e0 s&rsquo;y m\u00e9prendre, selon notre point de vue de non-sp\u00e9cialiste de la chose, \u00e0 l&rsquo;aveu que faisait le directeur de la DIA, que nous avons d\u00e9j\u00e0 repris \u00e0 deux reprises, dont une fois le 13 ao&ucirc;t dernier \u00e0 propos justement de l&rsquo;\u00e9conomie puisqu&rsquo;il s&rsquo;agit des <a href=\"http:\/\/www.dedefensa.org\/article\/vertigo-suite-chinoise\">graves remous de la Chine<\/a> &#8230; Et le g\u00e9n\u00e9ral Flynn, donc, disant, un jour avant son d\u00e9part (en ao&ucirc;t 2014) de directeur de l&rsquo;une des plus importantes agences de renseignement du monde, ceci qui pourrait ais\u00e9ment \u00eatre transpos\u00e9 au monde financier et \u00e9conomique : &laquo;<em>Ce que je vois, c&rsquo;est la g\u00e9ographie strat\u00e9gique et les fronti\u00e8res sur la carte du monde qui changent litt\u00e9ralement sous nos yeux. Ce changement est sans cesse en train d&rsquo;acc\u00e9l\u00e9rer \u00e0 cause de l&rsquo;explosion des m\u00e9dias sociaux. Et nous, dans la communaut\u00e9 du renseignement, <strong>nous essayons d&rsquo;y comprendre quelque chose<\/strong>&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Mis en ligne le 21 septembre 2015 \u00e0 13H08<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fed, ou le temps suspendu La Federal Reserve a pris la d\u00e9cision, ce jeudi 17 septembre, de ne pas relever son taux directeur d&rsquo;int\u00e9r\u00eat, qui reste quasiment au niveau z\u00e9ro (entre 0% et 0,25%) depuis fin 2008. La d\u00e9cision de rel\u00e8vement du taux est attendue depuis un certain temps, selon les indications qu&rsquo;avait donn\u00e9es&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[13630,3977,3032,5393,2926,2632,7777,16963,3851,4207,3372,3132,16964],"class_list":["post-76122","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-armstrong","tag-chine","tag-dia","tag-federal","tag-flynn","tag-globalisation","tag-gouvernance","tag-janet","tag-mondiale","tag-reserve","tag-street","tag-wall","tag-yellen"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76122"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76122\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}