{"id":76164,"date":"2015-10-12T08:57:53","date_gmt":"2015-10-12T08:57:53","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/10\/12\/troupes-au-sol-iraniennes-en-syrie\/"},"modified":"2015-10-12T08:57:53","modified_gmt":"2015-10-12T08:57:53","slug":"troupes-au-sol-iraniennes-en-syrie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/10\/12\/troupes-au-sol-iraniennes-en-syrie\/","title":{"rendered":"Troupes au sol iraniennes en Syrie"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Troupes au sol iraniennes en Syrie<\/h2>\n<\/p>\n<p><p>Que se passera-t-il lorsque l&rsquo;Iran engagera des troupes au sol (boots on the ground) en Syrie pour soutenir Bachar al Assad. Le principe en avait \u00e9t\u00e9 retenu il y a quelques semaines, autant que l&rsquo;on sache, lors de r\u00e9unions des repr\u00e9sentants de la coalition mont\u00e9e par Vladimir Poutine, c&rsquo;est-\u00e0-dire la Russie, l&rsquo;Iran, l&rsquo;Irak et de la Syrie, sans mentionner le Hezbollah.<\/p>\n<\/p>\n<p><p>Depuis lors, l&rsquo;Iran a engag\u00e9 quelques militaires aux c\u00f4t\u00e9s des troupes syriennes loyalistes (Un g\u00e9n\u00e9ral iranien a d&rsquo;ailleurs r\u00e9cemment \u00e9t\u00e9 tu\u00e9 dans un engagement avec Daesh). Mais il ne s&rsquo;agissait que de d\u00e9tachements exploratoires. Pendant ce temps l\u00e0, comme on le sait, la Russie a d\u00e9clench\u00e9 des tirs a\u00e9riens et maritimes contre Daesh, en soutien d&rsquo;une offensive pr\u00e9sent\u00e9e comme importante men\u00e9e par les troupes de Bachar al Assad pour r\u00e9cup\u00e9rer les terrains perdus depuis un an.<\/p>\n<\/p>\n<p><p>Tout ceci cependant ne suffit manifestement pas \u00e0 arr\u00eater Daesh, qui poursuit ses offensives et se rapproche de Damas. Les Russes manifestement ne veulent pas engager d&rsquo;effectifs terrestres, en dehors de quelques conseillers militaires. On le comprend. Ils refusent de courir le risque d&rsquo;un enlisement tel qu&rsquo;autrefois subi par l&rsquo;URSS en Afghanistan. L&rsquo;intervention d&rsquo;importants moyens iraniens est donc indispensable. Mais l&rsquo;on sait bien \u00e0 T\u00e9h\u00e9ran que cela changera radicalement la fa\u00e7on dont l&rsquo;Iran est per\u00e7u, tant \u00e0 Washington que par les r\u00e9gimes arabes du Golfe et \u00e0 Isra\u00ebl. Tous y verront la concr\u00e9tisation d&rsquo;un axe chiite risquant de s&rsquo;opposer directement aux int\u00e9r\u00eats am\u00e9ricains, isra\u00e9liens et sunnites.<\/p>\n<\/p>\n<p><p>Les troupes iraniennes en Syrie, surtout si elles obtiennent comme pr\u00e9vu d&rsquo;importants succ\u00e8s, susciteront probablement des r\u00e9actions \u00e9ventuellement militaires. Mais les Iraniens disposent d&rsquo;atouts non n\u00e9gligeables pour se d\u00e9fendre eux-m\u00eames. Sans compter les six Mig31 russes tr\u00e8s modernes apparemment en cours de livraison, ainsi que les batteries de missiles S300 livr\u00e9s par la Russie et en cours d&rsquo;installation, elle n&rsquo;est pas sans moyens a\u00e9riens propres. Il ne serait pas concevable que, si elle \u00e9tait attaqu\u00e9e, soit dans son espace a\u00e9rien, soit sur le terrain syrien, elle ne r\u00e9ponde pas. La Russie ne pourra pas \u00e0 ce moment rester \u00e0 l&rsquo;\u00e9cart. Elle devra, m\u00eame si elle le fait prudemment, soutenir militairement les effectifs iraniens sur le terrain &ndash; selon des formes \u00e0 d\u00e9terminer. Quant \u00e0 l&rsquo;Iran, se sent-elle pr\u00eate \u00e0 faire face aux nombreuses cons\u00e9quences militaires et diplomatiques en r\u00e9sultant?<\/p>\n<\/p>\n<p><p>On sait que depuis longtemps Isra\u00ebl avait menac\u00e9 l&rsquo;Iran de frappes destructrices. Si la nouvelle posture de l&rsquo;Iran l&rsquo;inqui\u00e8te, \u00e0 tort ou \u00e0 raison, on ne voit pas pourquoi Tel Aviv n&rsquo;y refourrerait pas. Aux Etats-Unis, il en sera de m\u00eame. Les forces politiques tr\u00e8s puissantes ayant reproch\u00e9 \u00e0 Obama d&rsquo;avoir c\u00e9d\u00e9 \u00e0 l&rsquo;Iran sur la question du nucl\u00e9aire retrouveraient toute leur virulence. L&rsquo;Iran serait incapable de faire face \u00e0 ce double adversaire. Ceci entrainerait dans le m\u00eame temps la ruine d\u00e9finitive de Bachar al Assad, priv\u00e9 de tout appui s\u00e9rieux. Ajoutons qu&rsquo;en cons\u00e9quence de tout cela, Daesh retrouverait une nouvelle vigueur en profitant du d\u00e9sordre g\u00e9n\u00e9ral qui s&rsquo;installerait.<\/p>\n<\/p>\n<p><p>L&rsquo;avenir quoiqu&rsquo;il arrive appara&icirc;t donc extr\u00eamement complexe, sinon noir. Pourrait-on compter sur des interventions d&rsquo;urgence du Conseil de S\u00e9curit\u00e9, voire de l&rsquo;Union europ\u00e9enne, pour calmer le jeu?<\/p>\n<\/p>\n<p><p>Il semble pourtant \u00e9vident que si les Etats-Unis et la Russie s&rsquo;entendaient d\u00e8s maintenant pour envoyer suffisamment de troupes au sol pour \u00e9liminer Daesh, sans chercher \u00e0 renverser Bachar al Assad, les \u00e9v\u00e8nements prendraient une autre tournure. La Syrie ne deviendrait pas l&rsquo;Afghanistan. L&rsquo;affaire pourrait \u00eatre r\u00e9gl\u00e9e assez vite. La Russie a d\u00e9j\u00e0 fait part de sa volont\u00e9 de coop\u00e9rer militairement avec l&rsquo;Occident de nombreuses fa\u00e7ons. Elle semble de bonne foi. Mais la volont\u00e9 de d\u00e9truire Poutine est si forte \u00e0 Washington que les Etats-Unis refuseront cette coop\u00e9ration, quel que soit le prix que devra en payer le reste du monde.<\/p>\n<\/p>\n<p><h4>Jean-Paul Baquiast<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Troupes au sol iraniennes en Syrie Que se passera-t-il lorsque l&rsquo;Iran engagera des troupes au sol (boots on the ground) en Syrie pour soutenir Bachar al Assad. Le principe en avait \u00e9t\u00e9 retenu il y a quelques semaines, autant que l&rsquo;on sache, lors de r\u00e9unions des repr\u00e9sentants de la coalition mont\u00e9e par Vladimir Poutine, c&rsquo;est-\u00e0-dire&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[4202,5997,2773,3867,11184],"class_list":["post-76164","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-assad","tag-engagement","tag-iran","tag-syrie","tag-terrestre"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76164"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76164\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}