{"id":76171,"date":"2015-10-16T01:34:17","date_gmt":"2015-10-16T01:34:17","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/10\/16\/debout\/"},"modified":"2015-10-16T01:34:17","modified_gmt":"2015-10-16T01:34:17","slug":"debout","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/10\/16\/debout\/","title":{"rendered":"Debout"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Debout<\/h2>\n<\/p>\n<p><p>En dehors des agressions spectaculaires men\u00e9es en moyenne une fois tous les deux ans contre Gaza par l&rsquo;entit\u00e9 occupante, la colonisation de la Palestine est une histoire quotidienne.<\/p>\n<\/p>\n<p><p>D&rsquo;expropriations de terres agricoles, de destructions de maisons, de check point fixes et mobiles, d&rsquo;un Mur qui mord la Cisjordanie et disjoint les villages et les villes.<\/p>\n<\/p>\n<p><p>De harassements administratifs sans fin.<\/p>\n<\/p>\n<p><p>D&rsquo;humiliations.<\/p>\n<\/p>\n<p><p>D&#8217;emprisonnements d&rsquo;hommes, de femmes et d&rsquo;enfants.<\/p>\n<\/p>\n<p><p>D&rsquo;assassinats &lsquo;cibl\u00e9s&rsquo;.<\/p>\n<\/p>\n<p><p>De manifestations au cours desquelles se chante &laquo; Mort aux Arabes &raquo;.<\/p>\n<\/p>\n<p><p>Et d&rsquo;attaques par les colons arm\u00e9s appuy\u00e9s par des soldats se soldant par des morts.<\/p>\n<\/p>\n<p><p>Les auteurs de l&rsquo;incendie, bien identifi\u00e9s, qui a br&ucirc;l\u00e9 la maison de la famille Dawabcheh et tous ses habitants dans leur sommeil dans le village de Douma  pr\u00e8s de Naplouse, ne sont toujours pas inculp\u00e9s. Une rumeur odieuse a m\u00eame \u00e9t\u00e9 orchestr\u00e9e qui pr\u00e9tendait \u00e0 l&rsquo;origine non criminelle de cette nouvelle modalit\u00e9 de four cr\u00e9matoire. Cette d\u00e9n\u00e9gation rappelle la formidable machinerie de propagande mise en branle lors de l&rsquo;assassinat film\u00e9 en direct de l&rsquo;enfant <a href=\"file:\/\/localhost\/(1)%09https\/::fr.wikipedia.org:wiki:Affaire_Mohammed_al-Durah\">Mohamed Doura<\/a>.<\/p>\n<\/p>\n<p><p>Depuis le premier octobre 2015, les FO sionistes ont arr\u00eat\u00e9 560 Palestiniens, plus de la moiti\u00e9 sont des enfants ou des mineurs. Pr\u00e8s de 110 l&rsquo;ont \u00e9t\u00e9 dans <a href=\"https:\/\/www.middleeastmonitor.com\/news\/middle-east\/21609-israel-arrested-560-palestinians-since-start-of-october\">les villes de la Palestine de 1948<\/a>. <a href=\"http:\/\/www.ism-france.org\/temoignages\/7-Palestiniens-tues-samedi-14-en-deux-jours-24-sur-ces-onze-derniers-jours-article-19771\">Du premier au 11 octobre<\/a>, 24 Palestiniens ont \u00e9t\u00e9 tu\u00e9s par les soldats de l&rsquo;occupation, 11 dans la bande de Gaza et 13 en Cisjordanie et J\u00e9rusalem. Plus de 1300 bless\u00e9s ont \u00e9t\u00e9 r\u00e9pertori\u00e9s.<\/p>\n<\/p>\n<p><p>La col\u00e8re a gagn\u00e9 la population quand fut connu que l&rsquo;Autorit\u00e9 Palestinienne a &laquo; livr\u00e9 &raquo; des jeunes de H\u00e9bron aux forces de l&rsquo;occupation fin septembre. Dans le cadre des accords d&rsquo;Oslo, le r\u00f4le assign\u00e9 \u00e0 l&rsquo;AP  est d&rsquo;assurer la s\u00e9curit\u00e9 de l&rsquo;occupant. Pr\u00e8s de 80% des pr\u00e9bendes offertes \u00e0 l&rsquo;institution indig\u00e8ne est d\u00e9di\u00e9e \u00e0 l&rsquo;administration sous-traitante de la police et de l&rsquo;arm\u00e9e isra\u00e9lienne.<\/p>\n<\/p>\n<p><p>La jeunesse palestinienne dans l&rsquo;ensemble de la Palestine historique entreprend son troisi\u00e8me soul\u00e8vement, de simples pierres \u00e0 la main.<\/p>\n<\/p>\n<p><p>D&rsquo;avoir fait flotter le drapeau palestinien devant le si\u00e8ge de l&rsquo;ONU n&rsquo;a rien chang\u00e9 pour les millions de Palestiniens prisonniers sur leur propre terre ni pour les autres millions r\u00e9fugi\u00e9s qui attendent r\u00e9solument l&rsquo;application de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/R%C3%A9solution_194_de_l'Assembl%C3%A9e_g%C3%A9n%C3%A9rale_des_Nations_unies\">la r\u00e9solution 194<\/a> de l&rsquo;ONU adopt\u00e9e le 11 d\u00e9cembre 1948.<\/p>\n<\/p>\n<p><p>La sc\u00e9nette jou\u00e9e par l&rsquo;actuel Premier du r\u00e9gime de Tel Aviv \u00e0 la tribune de l&rsquo;ONU- ses deux minutes de silence pour appuyer le risque all\u00e9gu\u00e9 d&rsquo;un an\u00e9antissement du peuple juif par la bombe nucl\u00e9aire, inexistante \u00e0 cette heure- ne pouvait \u00eatre accueillie par le parterre africain et asiatique, comme elle l&rsquo;e&ucirc;t \u00e9t\u00e9 devant le Congr\u00e8s \u00e9tasunien. Une th\u00e9\u00e2tralisation ridicule et arrogante devant des repr\u00e9sentants de continents d\u00e9cim\u00e9s par un syst\u00e8me occidental pr\u00e9dateur, assassin et atteint de c\u00e9cit\u00e9 mentale pour ses crimes sans nombre.<\/p>\n<\/p>\n<p><p>L&rsquo;id\u00e9ologie sioniste avec ses pr\u00e9tentions territoriales et coloniales singuli\u00e8res appuy\u00e9es sur une croyance religieuse et avanc\u00e9es par des ath\u00e9es se d\u00e9lite. Comme s&rsquo;\u00e9rode la capacit\u00e9 du capital \u00e0 g\u00e9n\u00e9rer du profit, et shunter la production mat\u00e9rielle pour sa prolif\u00e9ration est une fiction qui oublie dans l&rsquo;\u00e9quation de d\u00e9part une donn\u00e9e essentielle. Sa co-substance, innomm\u00e9e, en est le sacrifice humain commis au travers des guerres men\u00e9es contin&ucirc;ment depuis plus de deux si\u00e8cles  sur toute la plan\u00e8te.<\/p>\n<\/p>\n<p><h4>Badia Benjelloun<\/h4>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"> <\/h2>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Po\u00e8me<\/h2>\n<\/p>\n<p><p>Ils sont \u00e0 angle droit avec l&rsquo;horizontale.<\/p>\n<\/p>\n<p><p>Leurs mains nou\u00e9es se d\u00e9tendent<\/p>\n<\/p>\n<p><p>Elles inondent alors le jour \u00e9corch\u00e9<\/p>\n<\/p>\n<p><p>De vastes orages.<\/p>\n<\/p>\n<p><p>Entre deux songes<\/p>\n<\/p>\n<p><p>A la faveur d&rsquo;un arc en ciel<\/p>\n<\/p>\n<p><p>Leur douleur se fait plus rare<\/p>\n<\/p>\n<p><p>La col\u00e8re effrite les murs qui les enserrent<\/p>\n<\/p>\n<p><p>Leurs bras d\u00e9li\u00e9s \u00e9crivent<\/p>\n<\/p>\n<p><p>A m\u00eame le nuage moussu<\/p>\n<\/p>\n<p><p>Le travail obstin\u00e9 de leurs racines.<\/p>\n<\/p>\n<p><p>Leurs jambes nourries de l&rsquo;ardente aurore<\/p>\n<\/p>\n<p><p>Les soul\u00e8vent, les portent \u00e0 hauteur de leur \u00eatre<\/p>\n<\/p>\n<p><p>&Agrave; chaque envol un arc de foudre<\/p>\n<\/p>\n<p><p>Court d&rsquo;une colline \u00e0 l&rsquo;autre<\/p>\n<\/p>\n<p><p>Et ressuscite le chant trop longtemps enfoui<\/p>\n<\/p>\n<p><p>Dans les flancs de la terre meurtrie<\/p>\n<\/p>\n<p><p>Leurs mots d&rsquo;amour sont des jets lapidaires<\/p>\n<\/p>\n<p><p>Dont ils d\u00e9lestent leur besace<\/p>\n<\/p>\n<p><p>Leur extr\u00eame jeunesse les presse<\/p>\n<\/p>\n<p><p>Et l&rsquo;olivier l\u00e0-bas alourdi<\/p>\n<\/p>\n<p><p>Attend d&rsquo;\u00eatre d\u00e9livr\u00e9.<\/p>\n<\/p>\n<p><p>Ils lui ont promis de ne pas tarder<\/p>\n<\/p>\n<p><p>A recueillir son offrande.<\/p>\n<\/p>\n<p><h4>B.B.<\/h4>\n<\/p>\n<p><h4> <\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debout En dehors des agressions spectaculaires men\u00e9es en moyenne une fois tous les deux ans contre Gaza par l&rsquo;entit\u00e9 occupante, la colonisation de la Palestine est une histoire quotidienne. D&rsquo;expropriations de terres agricoles, de destructions de maisons, de check point fixes et mobiles, d&rsquo;un Mur qui mord la Cisjordanie et disjoint les villages et les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3953,2774,5521,3814],"class_list":["post-76171","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-benjelloun","tag-israel","tag-occupation","tag-palestiniens"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76171"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76171\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}