{"id":76197,"date":"2015-10-27T13:06:52","date_gmt":"2015-10-27T13:06:52","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/10\/27\/la-foret-chante\/"},"modified":"2015-10-27T13:06:52","modified_gmt":"2015-10-27T13:06:52","slug":"la-foret-chante","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/10\/27\/la-foret-chante\/","title":{"rendered":"La for\u00eat chante"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\">La for\u00eat chante<\/h2>\n<\/p>\n<p><p>27 octobre 2015 &ndash; Ce matin, il y eut la promenade quotidienne avec <em>Klara<\/em>, dont <a href=\"http:\/\/www.dedefensa.org\/article\/lart-de-la-fugue-en-foret\">je vous ai d\u00e9j\u00e0 parl\u00e9<\/a>. C&rsquo;est le deuxi\u00e8me jour de grand soleil, apr\u00e8s des semaines d&rsquo;agitations et d&rsquo;incertitudes climatiques diverses. Mais le \u00ab\u00a0grand soleil\u00a0\u00bb, en automne, c&rsquo;est quelque chose de tout \u00e0 fait particulier ; c&rsquo;est le paradoxe d&rsquo;une lumi\u00e8re retenue et pourtant \u00e9clatante, toute en nuances et qui pourtant vous \u00e9claire jusqu&rsquo;au fond de vous-m\u00eame, une lumi\u00e8re comme r\u00e9duite \u00e0 sa source mais qui semble rena&icirc;tre de partout, translucide et l\u00e9g\u00e8re, une lumi\u00e8re de gr\u00e2ce pure. Les couleurs de l&rsquo;automne, innombrables, chatoyantes et changeantes, transfigur\u00e9es par cette lumi\u00e8re unique, semblent faites pour grandir l&rsquo;\u00e2me po\u00e9tique.<\/p>\n<\/p>\n<p><p>Toutes ces pens\u00e9es \u00e9taient-elles en moi, ce matin ? Rien n&rsquo;est moins s&ucirc;r, car mon humeur \u00e9tait sombre, &ndash; pour changer commentera-t-on sarcastiquement. Puis vint la marche dans la for\u00eat et l&rsquo;effleurement de l&rsquo;enchantement naquit. La for\u00eat o&ugrave; je fais ma promenade n&rsquo;est pas uniforme en sous-bois mais plut\u00f4t par endroits \u00e9pars, des taillis souvent volumineux alternant avec des espaces vides de belle ampleur ; elle a par contre une imposante frondaison du dessus, comme une voute v\u00e9g\u00e9tale. Cet arrangement parut, ce matin, comme voulu par le Ciel, pour en faire une &oelig;uvre magnifique. Au-dessus de ma compagne fid\u00e8le beaucreronne et de moi, c&rsquo;\u00e9tait une voute dor\u00e9e, resplendissante, comme si les feuilles pr\u00eates \u00e0 tomber \u00e9taient des feuilles d&rsquo;or fr\u00e9missantes ; et la lumi\u00e8re rebondissait sur les taillis \u00e9pars, et ainsi formant comme l&rsquo;on dirait de l&rsquo;arche d&rsquo;une cath\u00e9drale car tous ces ors et toute cette lumi\u00e8re ne ternissait rien du clair-obscur de la for\u00eat qui lui laisse des projections de son ombre profonde au milieu de la lumi\u00e8re. Je gardais encore un peu de mon humeur sombre mais laissais la beaut\u00e9 du monde amadouer peu \u00e0 peu mon \u00e2me. \u00ab\u00a0Courage, semblait me dire <em>Klara<\/em> qui conna&icirc;t bien des secrets du monde, dans peu de temps cela ira bien mieux encore.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Ainsi se poursuivit la promenade jusqu&rsquo;\u00e0 son point extr\u00eame, puis le retour entam\u00e9. J&rsquo;arrivai \u00e0 ce m\u00eame passage sur le retour, un peu plus prot\u00e9g\u00e9 par la topographie des bruits de la civilisation, voiture ou train dans le lointain, parfois un a\u00e9ronef pour dire comme dans le temps ; il faut dire que ce matin, la civilisation \u00e9tait particuli\u00e8rement discr\u00e8te&#8230; C&rsquo;est alors que, marchant dans le silence et dans la lumi\u00e8re marqu\u00e9e d&rsquo;ombres propices, sans gu\u00e8re de vent sinon pas du tout, avec le ciel \u00e9clatant dans les \u00e9chancrures de la voute, je sentis qu&rsquo;il se passait quelque chose. Cela ne me parut pas un \u00e9l\u00e9ment nouveau, mais plut\u00f4t quelque chose qui avait exist\u00e9 au long de ma promenade mais que je n&rsquo;avais pas devin\u00e9, peut-\u00eatre un reste d&rsquo;inattention humaine, les restes de l&rsquo;humeur sombre voire mes limites naturelles, et que soudain je commen\u00e7ais \u00e0 percevoir. Je tendis l&rsquo;oreille, litt\u00e9ralement, pour percevoir d&rsquo;abord que le silence \u00e9tait complet (la civilisation d\u00e9finitivement muette et les oiseaux semblant d\u00e9cid\u00e9s \u00e0 respecter ce moment) ; puis que ce silence complet l&rsquo;\u00e9tait en fait pour que je puisse entendre quelque chose d&rsquo;au-del\u00e0 du silence. C&rsquo;est une de ces occurrences o&ugrave; vous devez, non pas aff&ucirc;ter vos sens, mais les adapter pour les projeter dans une dimension nouvelle.<\/p>\n<\/p>\n<p><p>Ainsi le silence laissa-t-il place \u00e0 un l\u00e9ger chuintement que j&rsquo;avais, dans l&rsquo;instant pr\u00e9c\u00e9dent, devin\u00e9 plus qu&rsquo;entendu, et qui, bient\u00f4t, se transforma en une sorte de basse continue mais non pas uniforme et \u00e0 peine sugg\u00e9r\u00e9e, dont je ne pouvais identifier ni la forme ni la mati\u00e8re. C&rsquo;\u00e9tait ce chuintement en basse continue qui, peu \u00e0 peu, prenait la forme d&rsquo;une harmonie \u00e9trange, plut\u00f4t sugg\u00e9r\u00e9e qu&rsquo;interpr\u00e9t\u00e9e ; j&rsquo;avais alors atteint, me dit-elle en connaisseuse, presque la m\u00eame oreille que <em>Klara<\/em> pour distinguer les sons. Puis la vue, transport\u00e9e par l&rsquo;audition, se mit elle aussi au diapason et, bient\u00f4t, je vis ce que je ne voyais pas. L&rsquo;espace vide enserr\u00e9 mais non contraint dans cette floraison chamarr\u00e9e, \u00e9clatante et presque \u00e9blouissante dans le clair-obscur, \u00e9tait parcouru de feuilles mortes qui tombaient \u00e0 leur rythme, en dansant comme fait une feuille que n&rsquo;entrave aucun souffle d&rsquo;air ; et ce mouvement infiniment multipli\u00e9, cette danse a\u00e9rienne et gracieuse, finissait par produire par le seul frottemet de l&rsquo;air une harmonie de tous ces sons presque inaudibles pour chacun, mais additionn\u00e9s et eux aussi multipli\u00e9s, pour produire enfin, au-del\u00e0, quelque chose qui ressemblait \u00e0 une structure sonore, fondamentalement form\u00e9e selon les lois \u00e9ternelles de l&rsquo;harmonie. C&rsquo;est alors que mon oreille embrassa le monde et que je dis, d\u00e9j\u00e0 \u00e0 l&rsquo;arr\u00eat et d\u00e9sormais comme interdit mais dans le sens d&rsquo;\u00eatre presque emport\u00e9 dans mon immobilit\u00e9 devant ce spectacle invisible et inaudible, et pourtant plus sublime qu&rsquo;aucun autre en cet instant : \u00ab\u00a0Et c&rsquo;est ainsi que la for\u00eat chante\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<p><p>L&rsquo;instant dura ce qu&rsquo;il dura, qu&rsquo;importe la mesure. Je repris ma marche, la t\u00eate pleine de cette harmonie subtile et sans \u00e9gale que je n&rsquo;entendais d\u00e9j\u00e0 plus. Bient\u00f4t, nous atteignons la clairi\u00e8re, les premi\u00e8res maisons, et nous sortons de la for\u00eat. \u00ab\u00a0La for\u00eat chantait\u00a0\u00bb, dis-je \u00e0 <em>Klara<\/em> qui, occup\u00e9e \u00e0 sentir quelque tr\u00e9sor cach\u00e9 dans les herbes, me r\u00e9pondit distraitement : \u00ab\u00a0&Eacute;videmment&#8230;\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Mon humeur ne m&rsquo;a pas quitt\u00e9 pour autant mais peut-\u00eatre, quelque part en moi, s&rsquo;est gliss\u00e9 un fragment de pierre pr\u00e9cieuse qui ressemble \u00e0 un morceau d&rsquo;\u00e9ternit\u00e9. Je regrettai un instant que l&rsquo;humaine nature soit dot\u00e9e de tant de capacit\u00e9s dont elle ne cesse de se f\u00e9liciter, qu&rsquo;elle ne puisse se satisfaire de la splendeur et de l&rsquo;harmonie du monde. Cette pens\u00e9e est assez vaine parce que nous sommes ce que nous sommes, mais il faut l&rsquo;avoir eue pour comprendre que \u00ab\u00a0se satisfaire de la splendeur et de l&rsquo;harmonie du monde\u00a0\u00bb, m\u00eame pour un instant, c&rsquo;est entrevoir l&rsquo;\u00e9ternit\u00e9.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La for\u00eat chante 27 octobre 2015 &ndash; Ce matin, il y eut la promenade quotidienne avec Klara, dont je vous ai d\u00e9j\u00e0 parl\u00e9. C&rsquo;est le deuxi\u00e8me jour de grand soleil, apr\u00e8s des semaines d&rsquo;agitations et d&rsquo;incertitudes climatiques diverses. Mais le \u00ab\u00a0grand soleil\u00a0\u00bb, en automne, c&rsquo;est quelque chose de tout \u00e0 fait particulier ; c&rsquo;est le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[11544,17066,2651,12322,11143,2701,15240,2878],"class_list":["post-76197","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-automne","tag-chuintement","tag-du","tag-eternite","tag-foret","tag-harmonie","tag-klara","tag-monde"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76197"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76197\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}