{"id":76201,"date":"2015-10-29T10:19:44","date_gmt":"2015-10-29T10:19:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/10\/29\/lineluctable-retour-vers-lesprit\/"},"modified":"2015-10-29T10:19:44","modified_gmt":"2015-10-29T10:19:44","slug":"lineluctable-retour-vers-lesprit","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/10\/29\/lineluctable-retour-vers-lesprit\/","title":{"rendered":"L&rsquo;in\u00e9luctable retour vers l&rsquo;Esprit"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">L&rsquo;In\u00e9luctable retour vers l&rsquo;Esprit<\/h2>\n<\/p>\n<p><p>Nous avons, dans le pr\u00e9c\u00e9dent article <em><a href=\"http:\/\/www.dedefensa.org\/article\/de-la-resistance-de-lesprit-a-lesprit-de-resistance\">&laquo; De la r\u00e9sistance de l&rsquo;Esprit \u00e0 l&rsquo;esprit de r\u00e9sistance <\/a>&raquo;<strong>, <\/strong><\/em>examin\u00e9 le processus menant d&rsquo;une situation o&ugrave; l&rsquo;Esprit immanent exerce invisiblement son action d&rsquo;harmonisation sur la collectivit\u00e9 des hommes, \u00e0 une autre, o&ugrave; cet exercice s&rsquo;est interrompu, du fait m\u00eame d&rsquo;une grave alt\u00e9ration de la participation consciente du corps social \u00e0 un \u00e9change qui lui \u00e9tait b\u00e9n\u00e9fique. Dans cette situation nouvelle, \u00e0 laquelle la civilisation chr\u00e9tienne a fini par aboutir, priv\u00e9e de l&rsquo;inspiration du Principe, l&rsquo;Occident avance \u00e0 l&rsquo;aveuglette, multiplie les comportements irrationnels, qui sont autant d&rsquo;erreurs si on les consid\u00e8re par rapport \u00e0 des lois naturelles qui, elles, fonctionnent imperturbablement de la m\u00eame fa\u00e7on depuis l&rsquo;origine de la Cr\u00e9ation. Une telle perte de rep\u00e8res m\u00e8ne tout droit \u00e0 la folie et au chaos comme nous pouvons le constater en ce moment m\u00eame presque partout dans le monde.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Continuit\u00e9 de l&rsquo;action Providentielle<\/h3>\n<\/p>\n<p><p>Cependant, un dispositif bien m\u00e9connu existe, permettant aux populations d&rsquo;\u00e9chapper au destin fatal auquel elles sont promises. En effet, si, de par la rupture quasi totale qui s&rsquo;est produite, les bienfaits inh\u00e9rents \u00e0 la situation harmonieuse v\u00e9cue \u00e0 l&rsquo;origine ne peuvent plus \u00eatre distribu\u00e9s \u00e0 l&rsquo;ensemble des nations occidentales, un m\u00e9canisme providentiel permet tout de m\u00eame de continuer \u00e0 diffuser ceux-ci individuellement \u00e0 ceux et celles que la Providence entend favoriser, simple cons\u00e9quence de l&rsquo;action de la loi universelle d&rsquo;\u00e9quilibre et de compensation.<\/p>\n<\/p>\n<p><p>L&rsquo;existence de cette loi, et son application effective, aide \u00e0 nous faire mieux comprendre que le monde et l&rsquo;humanit\u00e9 ont \u00e9t\u00e9, sont, et seront toujours soumis \u00e0 des lois naturelles dont, jusqu&rsquo;ici, la science positive moderne n&rsquo;a pu percevoir le mode et l&#8217;emprise r\u00e9elle de leur fonctionnement, leurs influences, qui nous affectent directement, provenant d&rsquo;un univers auquel nous sommes hi\u00e9rarchiquement soumis, et au sein duquel les \u00e9chelles du temps et de l&rsquo;espace diff\u00e8rent des n\u00f4tres dans des proportions gigantesques.<\/p>\n<\/p>\n<p><p>Il est donc bien entendu, pour celui qui sait observer et qui dispose des outils pour le faire, que la lente d\u00e9gradation \u00e0 laquelle est soumise la civilisation occidentale, n&rsquo;est pas une fatalit\u00e9 menant irr\u00e9m\u00e9diablement celle-ci vers l&rsquo;ab&icirc;me. Concomitamment, d&rsquo;autres m\u00e9canismes agissent parall\u00e8lement afin de redonner \u00e0 une humanit\u00e9 \u00e9puis\u00e9e et devenue folle, mais toujours aussi indispensable aux buts cosmologiques de la Cr\u00e9ation, de nouvelles chances de r\u00e9tablir l&rsquo;harmonie avec les lois et m\u00e9canismes universels.<\/p>\n<\/p>\n<p><p>Ainsi, \u00e0 chaque stade de l&rsquo;histoire marqu\u00e9 par un degr\u00e9 sp\u00e9cifique de d\u00e9gradation spirituelle, ont toujours correspondu des dispositions providentielles permettant un rattrapage. Du fait m\u00eame que nous vivons sous l&#8217;emprise permanente des illusions et des mensonges qui sont la sp\u00e9cificit\u00e9 m\u00eame de notre monde, peu nombreux sont les hommes s&rsquo;\u00e9tant rendu compte de la lente d\u00e9gradation qui les affectait d&rsquo;une part et, d&rsquo;autre part, encore moins nombreux ceux ayant d\u00e9cel\u00e9 la nature du secours qui avait \u00e9t\u00e9 mis \u00e0 leur port\u00e9e.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Des textes trait\u00e9s avec d\u00e9dain, et une Gr\u00e2ce qui persiste<\/h3>\n<\/p>\n<p><p>Notre \u00e9poque, tout particuli\u00e8rement marqu\u00e9e par une rupture totale de relation avec<em>&laquo; les puissances de l&rsquo;air &raquo;<\/em> comme les appelait Saint Augustin, ne se trouve ainsi point priv\u00e9e des bienfaits de la Gr\u00e2ce. Marqu\u00e9e profond\u00e9ment par la tyrannie d&rsquo;un scientisme outrancier, compl\u00e8tement ferm\u00e9e au monde de l&rsquo;Esprit et \u00e0 l&rsquo;id\u00e9e m\u00eame de son existence, elle a tout de m\u00eame suscit\u00e9 des figures iconoclastes qui, par leur renomm\u00e9e mondiale, ont su affirmer, contre vents et mar\u00e9es et au risque de perdre leur r\u00e9putation, l&rsquo;existence du monde de l&rsquo;Esprit et son ind\u00e9niable influence sur la soci\u00e9t\u00e9 humaine. Carl Gustav Jung, m\u00e9decin et psychanalyste c\u00e9l\u00e8bre, fait partie de celles-l\u00e0 au d\u00e9but du si\u00e8cle pr\u00e9c\u00e9dent. Ses convictions, dans ce domaine, livr\u00e9es au travers de tr\u00e8s nombreux \u00e9crits, ne font aucun doute. <em>&laquo; L&rsquo;Ame et la Vie &raquo;, <\/em>recueil d&rsquo;articles rassembl\u00e9s apr\u00e8s sa mort, nous permet d&rsquo;appr\u00e9hender l&rsquo;extraordinaire profondeur de sa connaissance du sujet dont il avait \u00e9valu\u00e9 l&rsquo;importance, jug\u00e9e d\u00e9cisive pour la soci\u00e9t\u00e9 future. J&rsquo;avais \u00e9t\u00e9 frapp\u00e9 par l&rsquo;affirmation suivante :<\/p>\n<\/p>\n<p><p><em>&laquo; Que l&rsquo;on n&rsquo;imagine pas que l&rsquo;on comprend le monde uniquement par l&rsquo;intellect ; on le comprend tout autant par le sentiment. Aussi le jugement de l&rsquo;intellect repr\u00e9sente-t-il tout au plus la moiti\u00e9 de la v\u00e9rit\u00e9 ; et il doit, s&rsquo;il est sinc\u00e8re, avouer son insuffisance . Il y a des dons de l&rsquo;esprit ; il y en a aussi du c&oelig;ur qui ne sont pas moins importants. Mais on les oublie facilement parce que, dans ces cas-l\u00e0, l&rsquo;intelligence est souvent plus faible que le c&oelig;ur. Et pourtant, les hommes de cette sorte sont souvent plus utiles et plus pr\u00e9cieux pour le bien de la soci\u00e9t\u00e9 que ne le sont les autres &raquo;.<\/em><\/p>\n<\/p>\n<p><p>Comment ne pas reconna&icirc;tre, dans ces quelques phrases, la localisation et la nature du mal qui affecte si profond\u00e9ment la civilisation occidentale aujourd&rsquo;hui ? Comment ne pas y voir \u00e9galement un rep\u00e8re pos\u00e9 sur le parcours de l&rsquo;histoire par la Providence ? Nous aurons, j&rsquo;esp\u00e8re, l&rsquo;occasion de revenir sur ce volet de l&rsquo;&oelig;uvre de CG Jung qui, d&rsquo;ailleurs, n&rsquo;est pas le seul \u00e0 vouloir nous montrer le chemin \u00e0 suivre.<\/p>\n<\/p>\n<p><p>Plus pr\u00e8s de nous, et dans son c\u00e9l\u00e8bre ouvrage <em>&laquo; De l&rsquo;Unit\u00e9 Transcendante des religions &raquo;, <\/em>le philosophe et m\u00e9taphysicien de la Tradition Frithjof Schuon, d\u00e9crit, mieux encore, le processus de rattrapage objet de cet article :<\/p>\n<\/p>\n<p><p><em>&laquo; la d\u00e9ch\u00e9ance cyclique entra&icirc;ne une obscuration quasi g\u00e9n\u00e9rale, et va en m\u00eame temps de pair avec un accroissement plus ou moins consid\u00e9rable des populations, surtout de leurs couches inf\u00e9rieures ; or, ladite d\u00e9ch\u00e9ance implique une tendance cosmique compl\u00e9mentaire et compensatrice qui agira \u00e0 l&rsquo;int\u00e9rieur m\u00eame de la collectivit\u00e9 sociale afin de restaurer au moins symboliquement la qualit\u00e9 primitive : premi\u00e8rement, cette collectivit\u00e9 sera comme perc\u00e9e par des exceptions, et cela pour ainsi dire parall\u00e8lement \u00e0 son accroissement quantitatif, comme si l&rsquo;\u00e9l\u00e9ment qualitatif (ou &laquo; sattwique &raquo;, conforme \u00e0 l&rsquo;&Ecirc;tre pur) contenu dans la collectivit\u00e9 envisag\u00e9e se concentrait, par un effet compensateur de la dilatation quantitative, sur des cas particuliers ; deuxi\u00e8mement, les moyens spirituels seront de plus en plus ais\u00e9s pour ceux qui sont qualifi\u00e9s et dont les aspirations sont s\u00e9rieuses, et cela en raison de la m\u00eame loi cosmique de compensation &raquo;.<\/em><\/p>\n<\/p>\n<p><p>Il va sans dire, si le lecteur a bien suivi le fil de cet article, que ces affirmations de Frithjof Schuon s&rsquo;av\u00e8rent capitales au yeux de tous ceux qui recherchent les moyens qui sont encore \u00e0 notre disposition pour permettre \u00e0 notre civilisation occidentale et, ne l&rsquo;oublions pas, chr\u00e9tienne, de sortir de l&rsquo;impasse dans laquelle elle se trouve.<\/p>\n<\/p>\n<p><p>On peut, bien entendu, ne pas croire \u00e0 l&rsquo;existence d&rsquo;une telle possibilit\u00e9 ; je r\u00e9pondrai alors simplement, \u00e0 ceux qui manifestent un tel sentiment, que nous sommes litt\u00e9ralement cern\u00e9s, de nos jours, par les milliers de ces cas particuliers qui sont autant de preuves vivantes de l&rsquo;\u00e9mergence de ce ph\u00e9nom\u00e8ne. Frithjof Schuon pr\u00e9cise en outre, que, pour les cas consid\u00e9r\u00e9s, les moyens spirituels leur seront de plus en plus ais\u00e9s ; en r\u00e9alit\u00e9, les choses vont bien au-del\u00e0, et d\u00e9passent largement les seules possibilit\u00e9s d&rsquo;am\u00e9lioration personnelle, une impl\u00e9mentation acc\u00e9l\u00e9r\u00e9e de nouveaux concepts dans la conscience de la soci\u00e9t\u00e9 civile \u00e9tant un des aspects des talents multiples auxquels celle-ci peut compter pour s&rsquo;extraire de sa folie.<\/p>\n<\/p>\n<p><p>Sans doute jugera-t-on d\u00e9lirants les \u00e9l\u00e9ments d\u00e9velopp\u00e9s dans cet article, comme l&rsquo;on peut juger encore plus d\u00e9lirantes les tentatives path\u00e9tiques d&rsquo;utiliser sans discontinuer les m\u00eames recettes qui ne marchent jamais, afin de r\u00e9soudre les probl\u00e8mes que nous rencontrons, recettes gentiment mises \u00e0 notre disposition par un syst\u00e8me que l&rsquo;on croit combattre, et dont le c&oelig;ur nucl\u00e9aire tient \u00e0 p\u00e9renniser ses pouvoirs et ses privil\u00e8ges au-del\u00e0 de toutes limites. En politique, par exemple, une tr\u00e8s grosse majorit\u00e9 reste toujours persuad\u00e9e qu&rsquo;elle a encore son mot \u00e0 dire ; c&rsquo;est proprement ridicule et, sur ce plan particulier, un effort de r\u00e9\u00e9ducation cons\u00e9quent va devoir \u00eatre entrepris, mais seulement par ceux et celles qui auront assimil\u00e9 la marche occulte du syst\u00e8me. En r\u00e9alit\u00e9, et sur un plan purement m\u00e9taphysique sur lequel je reviendrai plus tard, notre monde caract\u00e9ris\u00e9 par les illusions et les mensonges, participe d&rsquo;une certaine mani\u00e8re \u00e0 la marche de l&rsquo;univers, et ceux qui veulent s&rsquo;en extraire, de par leurs qualit\u00e9s et dispositions inn\u00e9es qui finissent par leur en r\u00e9v\u00e9ler la supercherie, le font pour pouvoir acc\u00e9der \u00e0 un autre monde dans lequel ils se reconnaissent. Cette d\u00e9marche, ne va pas sans des obstacles et des difficult\u00e9s \u00e9normes.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Un d\u00e9nouement rapide par une participation volontaire<\/h3>\n<\/p>\n<p><p>Les conseils et indications salutaires donn\u00e9s par Carl Gustav Jung, Frithjof Schuon et d&rsquo;autres vers lesquels nous ne manquerons pas de nous rapprocher plus tard, nous confirment l&rsquo;existence de lois cosmiques et naturelles qui ont ceci de particulier, qu&rsquo;elles s&rsquo;appliqueront de toute mani\u00e8re quel que soit l&rsquo;\u00e9tat du monde, m\u00eame dans des situations semblant irr\u00e9m\u00e9diablement d\u00e9grad\u00e9es pour cause de catastrophe naturelle, conflits majeurs, etc. Si donc nous sommes convaincus qu&rsquo;une telle r\u00e9alit\u00e9 repr\u00e9sente une opportunit\u00e9 sans pr\u00e9c\u00e9dent d&rsquo;amoindrir tr\u00e8s sensiblement la gravit\u00e9 des catastrophes vers lesquelles nous nous dirigeons, autant participer et aider \u00e0 la conclusion rapide d&rsquo;un processus irr\u00e9versible dont le principal objet vise \u00e0 remplacer des \u00e9lites ayant manifestement atteint depuis longtemps leur seuil d&rsquo;incomp\u00e9tence, par de nouvelles, aptes \u00e0 g\u00e9rer efficacement les imp\u00e9ratifs d&rsquo;une \u00e9poque nouvelle, d&rsquo;un nouveau cycle, qui sera plac\u00e9 sous l&rsquo;\u00e9gide de l&rsquo;Art.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"> Un r\u00e8gne de l&rsquo;Art qui r\u00e9clame une rotation des \u00e9lites<\/h3>\n<\/p>\n<p><p> Il n&rsquo;existe, en effet, que quatre modes mis \u00e0 la disposition de la soci\u00e9t\u00e9 des hommes et par lesquels celle-ci peut, depuis l&rsquo;antiquit\u00e9, exprimer le meilleur d&rsquo;elle m\u00eame : la philosophie, la religion, la science et l&rsquo;Art. Chaque cycle pr\u00e9c\u00e9dent a ainsi \u00e9t\u00e9 marqu\u00e9 par l&rsquo;influence pr\u00e9pond\u00e9rante d&rsquo;un de ces modes : l&rsquo;antiquit\u00e9 par la philosophie, puis jusqu&rsquo;\u00e0 la fin du Moyen-\u00e2ge par la religion, puis depuis la Renaissance jusqu&rsquo;\u00e0 nos jours, par la science et sa technique. Bien entendu, le lecteur ne doit pas comprendre que chacun de ces modes s&rsquo;exer\u00e7ait de fa\u00e7on exclusive, mais que chacune de ces \u00e9poques \u00e9tant profond\u00e9ment marqu\u00e9e par l&rsquo;un d&rsquo;eux, les autres subissaient, d&rsquo;une certaine mani\u00e8re sa loi. C&rsquo;est ainsi que, par exemple, la religion, au cours du Moyen-\u00e2ge, ayant atteint sa pleine puissance, les sciences, qui existaient bien \u00e0 cette \u00e9poque, \u00e9taient en quelque sorte &laquo; religionis\u00e9es &raquo;. De m\u00eame, pour ce qui concerne la Renaissance, la religion, subissant l&rsquo;influence d&rsquo;une science en plein essor, s&rsquo;est vue &laquo; scientifi\u00e9e &raquo;. L&rsquo;\u00e9poque dans laquelle nous sommes sur le point d&rsquo;entrer, sera, elle, marqu\u00e9e par la pr\u00e9dominance de l&rsquo;Art. Il ne s&rsquo;agit pas, bien entendu, d&rsquo;une h\u00e9g\u00e9monie de toutes les formes d&rsquo;art, mais de l&rsquo;inclusion, dans cette \u00e9poque m\u00eame, du meilleur de ce que chaque \u00e9poque pr\u00e9c\u00e9dente a connu. Cette synth\u00e8se, qui verra na&icirc;tre pour la premi\u00e8re fois des \u00e9changes harmonieux entre la philosophie, la religion et la science, sera, elle, plac\u00e9e sous l&rsquo;\u00e9gide de l&rsquo;esth\u00e9tique dont l&rsquo;importance et la pr\u00e9pond\u00e9rance appara&icirc;tront graduellement \u00e0 la conscience des soci\u00e9t\u00e9s humaines. Est-il encore besoin de pr\u00e9ciser, que l&rsquo;accession \u00e0 ce dernier mode d&rsquo;expression de l&rsquo;humanit\u00e9, verra le retour effectif et triomphal de sciences tant d\u00e9cri\u00e9es et combattues depuis l&rsquo;aube des temps, telles que l&rsquo;Art royal alchimique, l&rsquo;\u00e9sot\u00e9risme, la science des nombres, dans leurs formes les plus abouties, c&rsquo;est-\u00e0-dire, toutes r\u00e9unies dans la Gnose chr\u00e9tienne ?<\/p>\n<\/p>\n<p><p> Krishnamurti affirmait que : <em>&laquo; Ce n&rsquo;est pas un signe de bonne sant\u00e9 mentale que d&rsquo;\u00eatre bien adapt\u00e9 \u00e0 une soci\u00e9t\u00e9 malade &raquo;. <\/em>Rajoutons, pour conclure, que, de nos jours, les inadapt\u00e9s sont l\u00e9gions, qu&rsquo;il y a une raison profonde \u00e0 cela, et qu&rsquo;en r\u00e9alit\u00e9 ils repr\u00e9sentent l&rsquo;opportunit\u00e9 majeure que notre soci\u00e9t\u00e9 doit saisir.<\/p>\n<\/p>\n<p><h4> Pierre Audabram<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;In\u00e9luctable retour vers l&rsquo;Esprit Nous avons, dans le pr\u00e9c\u00e9dent article &laquo; De la r\u00e9sistance de l&rsquo;Esprit \u00e0 l&rsquo;esprit de r\u00e9sistance &raquo;, examin\u00e9 le processus menant d&rsquo;une situation o&ugrave; l&rsquo;Esprit immanent exerce invisiblement son action d&rsquo;harmonisation sur la collectivit\u00e9 des hommes, \u00e0 une autre, o&ugrave; cet exercice s&rsquo;est interrompu, du fait m\u00eame d&rsquo;une grave alt\u00e9ration de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3281,17072,17074,1035,17073,17075,2716],"class_list":["post-76201","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-art","tag-audabram","tag-frithjof","tag-jung","tag-krishnamurti","tag-schuon","tag-tradition"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76201"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76201\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}