{"id":76220,"date":"2015-11-07T14:20:24","date_gmt":"2015-11-07T14:20:24","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/11\/07\/le-torchon-brule-entre-bho-et-le-pentagone\/"},"modified":"2015-11-07T14:20:24","modified_gmt":"2015-11-07T14:20:24","slug":"le-torchon-brule-entre-bho-et-le-pentagone","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/11\/07\/le-torchon-brule-entre-bho-et-le-pentagone\/","title":{"rendered":"Le torchon br\u00fble entre BHO et le Pentagone"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le torchon br&ucirc;le entre BHO et le Pentagone<\/h2>\n<\/p>\n<p><p>Deux journaux, le m\u00eame jour, se font l&rsquo;\u00e9cho de fortes dissensions entre la Maison-Blanche et le Pentagone : Le <a href=\"http:\/\/www.washingtontimes.com\/news\/2015\/nov\/5\/obama-pushes-military-frustration-to-highest-level\/?page=all#pagebreak\">Washington <em>Times<\/em><\/a> et le <a href=\"http:\/\/www.washingtonexaminer.com\/article\/2575693\">Washington <em>Examiner<\/em><\/a>, tous les deux le 5 novembre (le 6 novembre pour nous). Ces dissensions sont nouvelles, ponctuellement provoqu\u00e9es par la \u00ab\u00a0strat\u00e9gie\u00a0\u00bb adopt\u00e9e par la Maison-Blanche pour la Syrie, notamment la d\u00e9cision d&rsquo;envoyer de 30 \u00e0 50 \u00ab\u00a0conseillers\u00a0\u00bb, geste qui symbolise la fameuse formule <em>Boots on the Ground<\/em> et qui a d\u00e9j\u00e0 \u00e9t\u00e9 l&rsquo;objet ces derniers joues du <a href=\"http:\/\/www.dedefensa.org\/article\/syrie-us-boots-on-the-ground-et-bruit-de-fond\">lancement d&rsquo;une campagne d&rsquo;opposition<\/a> au niveau de l&rsquo;opinion publique.<\/p>\n<\/p>\n<p><p>D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, les critiques portent \u00e9videmment sur la forme m\u00eame de la \u00ab\u00a0strat\u00e9gie\u00a0\u00bb, le terme attirant \u00e9videmment la critique par le simple fait du nombre ridiculement bas de soldats pseudo-non-combattants engag\u00e9s. On parle ici des d\u00e9clarations officielles, sans tenir compte de la r\u00e9alit\u00e9 sur le terrain o&ugrave; l&rsquo;on sait que des forces US ou sous patronage US sont engag\u00e9es depuis longtemps, en nombre souvent significatifs. Mais il s&rsquo;agit d&rsquo;un autre monde. Nous parlons d&rsquo;une querelle de communication \u00e0 partir de  <em>narrativre<\/em> en vogue et en cours&#8230; Pourtant, cette querelle recouvre, malgr\u00e9 sa compl\u00e8te irr\u00e9alit\u00e9, des dissensions beaucoup plus profondes. Par cons\u00e9quent, les critiques sont \u00e9videntes et souvent fond\u00e9es, et d\u00e9veloppent des arguments qui ne le sont pas moins.<\/p>\n<\/p>\n<p><p>On donne d&rsquo;abord quelques extraits du Washington <em>Examiner<\/em> qui concernent surtout des experts et sp\u00e9cialistes de l&rsquo;<em>establishment<\/em> washingtonien. Leur appr\u00e9ciation est qu&rsquo;il sera quasiment impossible pour les \u00ab\u00a0conseillers\u00a0\u00bb de ne pas \u00eatre engag\u00e9s dans une forme ou l&rsquo;autre de combat, en raison des conditions qu&rsquo;ils vont rencontrer en Syrie.<\/p>\n<\/p>\n<p><p><em>&laquo; \u00ab\u00a0There are places where combat is more prevalent, but the wide use of<\/em> [<em>improvised explosive devices<\/em>], <em>suicide vests, and snipers, there&rsquo;s no place in Syria or Iraq that is not dead center in a combat zone,\u00a0\u00bb said Chris Harmer, an analyst with the Institute for the Study of War. \u00ab\u00a0It&rsquo;s a distinction without a difference at this point. Anybody who goes to Syria in an American uniform is going to be a high-value target for a lot of different terrorist organization.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>The reality of the dangers facing U.S. troops is more complex than either side claims, due to the new age of conflicts where enemies blend into society rather than facing off on traditional battlefields.It is now \u00ab\u00a0very, very difficult\u00a0\u00bb to define the frontlines of battle, said P.J. Crowley, a professor at George Washington University and a former assistant secretary for public affairs at the State Department. \u00ab\u00a0The nature of modern conflict does not fit neatly into these kinds of categories, categories that have a lot more to do with fighting standing armies representing states than fighting non-state actors that can blend easily into a civilian population,\u00a0\u00bb Crowley said<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>This type of fighting sees people who are not traditionally in combat roles, such as truck drivers tasked with carrying supplies, get ambushed and face violence, Harmer said. Because they see the situation first hand, they know they are in combat regardless of the \u00ab\u00a0double speak\u00a0\u00bb in Washington, he said. \u00ab\u00a0To the troops it makes no difference at all. They&rsquo;re probably vaguely irritated by the verbal semantics, but anyone on the ground in Syria or Iraq knows they are in combat,\u00a0\u00bb he said&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>Le Washington <em>Times<\/em>, lui, se concentre sur le r\u00e9actions extr\u00eamement vives des parlementaires, avec bien entendu l&rsquo;inoxudable John McCain en t\u00eate. Mais, sans surtout rien lui enlever toute l&rsquo;insondable absurdit\u00e9 de ces postions habituelles autant que de sa \u00ab\u00a0philosophie\u00a0\u00bb naturelle, on admettra que, pour ce cas de la \u00ab\u00a0strat\u00e9gie\u00a0\u00bb obamienne, les arguments de McCain ont du poids. Certes, l&rsquo;argument n&rsquo;est pas difficile, mais dans tous les cas il le d\u00e9veloppe avec bon sens. Savourez donc ce moment rarissime o&ugrave; McCain dit des choses sens\u00e9es. Qui plus est, McCain nous donne un aper\u00e7u, qui est sans aucun doute bien r\u00e9el, de l&rsquo;intense insatisfaction qui r\u00e8gne dans les rangs des militaires et fonctionnaires divers du Pentagone, car il a de son c\u00f4t\u00e9 (celui de McCain) nombre de connexions et des confidences permanentes.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&laquo; <em>\u00ab\u00a0There&rsquo;s a level of dissatisfaction among the uniformed military that I&rsquo;ve never seen in my time here,\u00a0\u00bb said Senate Armed Services Committee Chairman <a href=\"http:\/\/www.washingtontimes.com\/topics\/john-mccain\/\">John McCain<\/a> in an interview. \u00ab\u00a0For some of us who are a little older, let&rsquo;s go back and read the Pentagon Papers &mdash; what the administration is doing is the kind of incrementalism that defined much of the Vietnam conflict.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p><strong>&raquo; <\/strong><em>The Arizona Republican is known as a fierce critic of President Obama&rsquo;s foreign policy, but his complaints were echoed by an unlikely source: Rep. Adam Smith, the ranking Democrat on the House Armed Services Committee. \u00ab\u00a0Frustration among the uniformed service is real,\u00a0\u00bb the <a href=\"http:\/\/www.washingtontimes.com\/topics\/washington\/\">Washington<\/a> Democrat said, adding that the administration \u00ab\u00a0does keep things in the <a href=\"http:\/\/www.washingtontimes.com\/topics\/white-house\/\">White House<\/a> and has not been more inclusive in the decision-making process.\u00a0\u00bb But Mr. Smith also defended the administration&rsquo;s overall approach to the troubled Middle East, arguing that the \u00ab\u00a0sheer complexity of the situation\u00a0\u00bb following the Arab Spring and the rise of the Islamic State &mdash; also known as ISIS &mdash; have defied a simple U.S. solution. \u00ab\u00a0I don&rsquo;t think dropping 50,000 U.S. troops down is going to fix the situation,\u00a0\u00bb he said.<\/em> &raquo; [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; &#8230;<em>But <a href=\"http:\/\/www.washingtontimes.com\/topics\/john-mccain\/\">Mr. McCain<\/a> argued that the frustration on Capitol Hill and at the Pentagon stems from the <a href=\"http:\/\/www.washingtontimes.com\/topics\/george-w-bush-administration\/\">administration<\/a>&lsquo;s \u00ab\u00a0complete lack of any kind of coherent strategy, much less a strategy that would have any success on the battlefield\u00a0\u00bb against Islamic State and the Assad regime. \u00ab\u00a0We&rsquo;re sending 50 &mdash; count them, 50 &mdash; special operations soldiers to <a href=\"http:\/\/www.washingtontimes.com\/topics\/syria\/\">Syria<\/a>, and they will have &lsquo;no combat role,&rsquo; the president says,\u00a0\u00bb said <a href=\"http:\/\/www.washingtontimes.com\/topics\/john-mccain\/\">Mr. McCain<\/a>. \u00ab\u00a0Well, what are they being sent there for? To be recreation officers? You&rsquo;re in a combat zone, and to say they&rsquo;re not in combat is absurd.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>But the <a href=\"http:\/\/www.washingtontimes.com\/topics\/white-house\/\">White House<\/a>, he argued, has effectively blinded itself to such absurdities by promoting a system over the past seven years that suppresses dissenting voices. \u00ab\u00a0Compliant and easily led military leaders get promoted,\u00a0\u00bb he said. \u00ab\u00a0People who have spoken truth to power get retired.\u00a0\u00bb He pointed to the cases of Marine Gen. James Mattis, reportedly dismissed as head of U.S. Central Command in 2013 for pressuring civilian officials in the <a href=\"http:\/\/www.washingtontimes.com\/topics\/white-house\/\">White House<\/a> on potential military options against Iran; and Army Lt. Gen. Michael T. Flynn, allegedly pushed out as head of the Defense Intelligence Agency last year amid clashes with the <a href=\"http:\/\/www.washingtontimes.com\/topics\/white-house\/\">White House<\/a> over his leadership style.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>When it comes to actual policy, <a href=\"http:\/\/www.washingtontimes.com\/topics\/john-mccain\/\">Mr. McCain<\/a> lamented, the <a href=\"http:\/\/www.washingtontimes.com\/topics\/george-w-bush-administration\/\">administration<\/a> pursues half-measures and decisions, \u00ab\u00a0when they are made, consistently disregard recommendations from the uniformed military.\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<p><p>On observe d\u00e9j\u00e0 \u00e0 un d\u00e9tail combien la mati\u00e8re extraordinairement complexe du Moyen-Orient, devenue hyper-complexe quand on passe \u00e0 la formulation d&rsquo;une \u00ab\u00a0strat\u00e9gie\u00a0\u00bb \u00e0 la Maison-Blanche, conduit \u00e0 des situation pleines de contradiction. Aucune ne doit contrarier l&rsquo;esprit mais, au contraire, le remplir d&rsquo;une certaine satisfaction car c&rsquo;est dans ces labyrinthes byzantins qu&rsquo;apparaissent des forces antiSyst\u00e8me inopin\u00e9es et compl\u00e8tement inconscientes, qui effectuent n\u00e9anmoins un rude travail antiSyst\u00e8me.<\/p>\n<\/p>\n<p><p> McCain cite, parmi les chefs militaires frustr\u00e9s, <a href=\"http:\/\/www.dedefensa.org\/article\/daesh-desordre-et-le-general-flynn-en-vedette-americaine\">le g\u00e9n\u00e9ral Flynn<\/a> dont on a <a href=\"http:\/\/www.dedefensa.org\/article\/le-general-flynn-passe-a-lest\">beaucoup parl\u00e9<\/a>. Le voil\u00e0 donc incorpor\u00e9 <em>de facto<\/em> dans le camp de McCain en pleine r\u00e9volte contre la \u00ab\u00a0strat\u00e9gie\u00a0\u00bb d&rsquo;Obama, et le plus sympathique de cette situation est qu&rsquo;il n&rsquo;y a pas contradiction. Par ailleurs, &ndash; et pour nous, de fa\u00e7on bien plus importante, &ndash; Flynn est un des \u00ab\u00a0lanceurs d&rsquo;alerte\u00a0\u00bb les plus inattendus, &ndash; un de ceux que McCain d\u00e9nonce et consid\u00e8re comme tra&icirc;tre de fa\u00e7on routini\u00e8re, &ndash; lorsqu&rsquo;il (Flynn) d\u00e9voile la fa\u00e7on dont l&rsquo;administration Obama a objectivement soutenu, arm\u00e9, renforc\u00e9 le groupe <em>Daesh<\/em> depuis 2011-2012 malgr\u00e9 les avertissements circonstanci\u00e9s de la DIA, avertissant qu&rsquo;on \u00e9tait ainsi en train de contribuer d\u00e9cisivement \u00e0 la la cr\u00e9ation d&rsquo;un Frankenstein. Sur ce point, McCain est compl\u00e8tement dans le camp oppos\u00e9 de Flynn, qu&rsquo;il d\u00e9noncerait comme \u00ab\u00a0tra&icirc;tre\u00a0\u00bb pour un peu, puisqu&rsquo;il est, lui (McCain), pour l&rsquo;armement maximal pout tout ce qui bouge en Syrie, pourvu que cela soit extr\u00e9miste et ennemi jur\u00e9 de Assad, et donc pratiquement alli\u00e9 objectif de <em>Daesh<\/em> malgr\u00e9 qu&rsquo;il d\u00e9nonce le peu de moyens envisag\u00e9s pour combattre <em>Daesh<\/em>. (On a vu plus d&rsquo;une fois McCain aux c\u00f4t\u00e9 des chefs islamistes, comme on l&rsquo;a vu, en Ukraine, aupr\u00e8s de leaders n\u00e9o-nazis.)<\/p>\n<\/p>\n<blockquote>\n<p><p>L\u00e0 aussi, superbe exemple, <em>ad nomine<\/em>, des contradictions directes qu&rsquo;engendrent les p\u00e9rip\u00e9ties en lacets, en croisements, en redoublements, de la sc\u00e8ne politique washingtonienne, et qu&rsquo;o,n commence \u00e0 bien conna&icirc;tre. Superbe exemple, en fait, d&rsquo;une psychologie g\u00e9n\u00e9rale et d&rsquo;une communication fonctionnant selon ce que nous d\u00e9signons comme le \u00ab\u00a0<em><a href=\"http:\/\/www.dedefensa.org\/article\/du-big-now-a-lleternel-present\">Big Now<\/a><\/em>\u00ab\u00a0, c&rsquo;est-\u00e0-dire cette situation postmoderne o&ugrave; le pr\u00e9sent est tellement hypertrophi\u00e9 comme d\u00e9monstration de la justesse des th\u00e8ses suivies et appliqu\u00e9es, que le pass\u00e9 m\u00eame proche n&rsquo;existe plus, non seulement pour l&rsquo;esprit (la m\u00e9moire) mais pour la psychologie elle-m\u00eame : <strong>il est devenu incoh\u00e9rent et incompr\u00e9hensible qu&rsquo;il y ait un passs\u00e9 avec ses enseignements<\/strong>, &ndash; donc, pas de pass\u00e9, pas d&rsquo;enseignement, et fermez le ban.<\/p>\n<\/p>\n<p><p>Quant au futur, \u00e0 partir duquel certains pr\u00e9tendaient<em> in illo tempore<\/em> envisager l&rsquo;avenir de l&rsquo;homme selon leurs conceptions, , il a \u00e9t\u00e9 r\u00e9pudi\u00e9 puisqu&rsquo;il s&rsquo;av\u00e8re compl\u00e8tement contradictoire avec l&rsquo;avenir justement, \u00e0 cause des imp\u00e9ratifs faussaires de la postmodernit\u00e9, comme on l&rsquo;a vu de plus en plus souvent ces derniers temps. (Pour la diff\u00e9rence d\u00e9cisive entre \u00ab\u00a0futur\u00a0\u00bb et \u00ab\u00a0avenir\u00a0\u00bb, voir notamment <a href=\"http:\/\/www.dedefensa.org\/article\/la-bataille-du-neantissement-de-lhistoire\">la note du texte du 6 juin 2015<\/a> sur \u00ab\u00a0la bataille pour le &lsquo;n\u00e9antissement&rsquo; de l&rsquo;Histoire\u00a0\u00bb.) Cela implique que la plupart des acteurs politiques, priv\u00e9s de toute m\u00e9moire historique et de toute capacit\u00e9 de pojection rationnelle des possibilit\u00e9s des \u00e9v\u00e8nements \u00e0 venir, et donc <strong>embarrass\u00e9s strictement d&rsquo;aucune coh\u00e9rence<\/strong>, &ndash; \u00e0 part celles des \u00e9normes st\u00e9r\u00e9otypes en forme d&rsquo;image symboliques d&rsquo;Epinal qu&rsquo;ils acceptent avec enthousiasme, comme Poutine et Assad par exemple, &ndash; sont capables d&rsquo;accepter des modifications radicales de situations et d&rsquo;acteurs sans y suspecter la moindre contradiction, et sans \u00e9prouver la n\u00e9cessit\u00e9 de s&rsquo;expliquer de tels ph\u00e9nom\u00e8nes.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Par contre, le tableau g\u00e9n\u00e9ral qu&rsquo;on a de cette m\u00e9sentente entre le Pentagone et la Maison-Blanche est inhabituel d&rsquo;ampleur, d&rsquo;\u00e9cho public et de s\u00e9rieux du fait des personnalit\u00e9s impliqu\u00e9es. Il constitue peut-\u00eatre un point int\u00e9ressant et important de blocage de l&rsquo;appareil de s\u00e9curit\u00e9 nationale aux USA, c&rsquo;est-\u00e0-voir selon les \u00e9v\u00e8nements, essentiellement \u00e0 cause de la personnalit\u00e9 et de la psychologie de l&rsquo;homme, le pr\u00e9sident, qui est incapable de prendre une d\u00e9cision claire et tranch\u00e9e puisque sa politique naturellement mod\u00e9r\u00e9e est constamment d\u00e9form\u00e9e chez lui par son d\u00e9sir de ne pas se mettre \u00e0 dos la majorit\u00e9 super-belliciste des repr\u00e9sentants de l&rsquo;<em>establishment<\/em>, et donc aved une tendance irr\u00e9sistible \u00e0 nuancer des d\u00e9cisions effectivement mod\u00e9r\u00e9es par des aspects bellicistes n\u00e9cessairement incomplets et sans v\u00e9ritable effet. Cas classique d&rsquo;un homme qui veut marier l&rsquo;eau et le feu, ne m\u00e9contenter personne, rencontrer ses propres convictions qui se d\u00e9marquent de la majorit\u00e9 belliciste, etc. Le r\u00e9sultat est catastrophique mais ne manque pas d&rsquo;une certaine allure exotique. Il permet \u00e0 la basse-cour washingtonienne de s&rsquo;exclamer dans tous les sens et \u00e0 l&rsquo;action des centres subversifs US de continuer \u00e0 se d\u00e9velopper dans un contexte g\u00e9n\u00e9ral d&rsquo;incontr\u00f4labilit\u00e9. Et m\u00eame, enfin, lorsqu&rsquo;on voit ce que propose Obama, on se dit que ce d\u00e9sordre lui-m\u00eame n&rsquo;est pas plus destructeur que ce que se pr\u00e9pare \u00e0 \u00eatre la \u00ab\u00a0strat\u00e9gie\u00a0\u00bb du pr\u00e9sident.<\/p>\n<\/p>\n<p><p>Mis en ligne le 7 novembre 2015 \u00e0 14H09<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le torchon br&ucirc;le entre BHO et le Pentagone Deux journaux, le m\u00eame jour, se font l&rsquo;\u00e9cho de fortes dissensions entre la Maison-Blanche et le Pentagone : Le Washington Times et le Washington Examiner, tous les deux le 5 novembre (le 6 novembre pour nous). Ces dissensions sont nouvelles, ponctuellement provoqu\u00e9es par la \u00ab\u00a0strat\u00e9gie\u00a0\u00bb adopt\u00e9e par&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4646,3285,12572,2926,7408,4063,6208,3856,3440],"class_list":["post-76220","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antisysteme","tag-congres","tag-daesh","tag-flynn","tag-incertitude","tag-mccain","tag-obama","tag-revolte","tag-strategie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76220"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76220\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}