{"id":76223,"date":"2015-11-09T13:58:24","date_gmt":"2015-11-09T13:58:24","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/11\/09\/la-psyche-de-gi-joe\/"},"modified":"2015-11-09T13:58:24","modified_gmt":"2015-11-09T13:58:24","slug":"la-psyche-de-gi-joe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/11\/09\/la-psyche-de-gi-joe\/","title":{"rendered":"La psych\u00e9 de G.I. Joe"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La psych\u00e9 de G.I. Joe<\/h2>\n<\/p>\n<p><p>9 novembre 2015 &ndash; Je vais m&rsquo;attacher \u00e0 un aspect tr\u00e8s important, le plus important d&rsquo;ailleurs, dans tous les travaux de ce site, &ndash; la psychologie ; plus pr\u00e9cis\u00e9ment, la psychologie US depuis que les Russes sont en Syrie. Je crois en effet qu&rsquo;il existe une tr\u00e8s forte possibilit\u00e9 que cette intervention russe, &ndash; sans l&rsquo;avoir voulu pr\u00e9cis\u00e9ment, mais peut-\u00eatre inconsciemment, qui sait&#8230;, &ndash;  inflige, si ce n&rsquo;est d\u00e9j\u00e0 fait mais encore mal ressenti, <strong>un choc psychologique terrible \u00e0 la psychologie US<\/strong>. Je parle de la psychologie militariste et expansionniste qui gouverne cette puissance dont l&rsquo;oxyg\u00e8ne, le sang m\u00eame, la fonction vitale se nomme : <em>hybris<\/em>. Je vais m\u00eame avancer, dans ce <em>Journal dde.crisis<\/em> o&ugrave; je me sens apr\u00e8s tout plus libre que dans les textes courants du site pour laisser vagabonder l&rsquo;inspiration des forces intuitives, que ce choc psychologique ne pourrait se comparer qu&rsquo;\u00e0 ceux, respectivement, de Pearl Harbor et du 11 septembre 2001. La forme est diff\u00e9rente certes, l&rsquo;intensit\u00e9 apparente sans commune mesure, la chronologie compl\u00e8tement sans comparaison, mais l&rsquo;effet profond, souterrain, me semble pouvoir \u00eatre envisag\u00e9 comme \u00e9tant similaire. Il y a aussi la question du sens, du point de vue trivial de l&rsquo;orientation strat\u00e9gique ; au contraire de Pearl Harbor et de 9\/11, le sens de ce choc n&rsquo;appara&icirc;trait nullement comme une sorte d&rsquo;appel puissant et en apparence r\u00e9ussi pour la mobilisation d&rsquo;une \u00ab\u00a0puissance assoupie\u00a0\u00bb, mais comme la d\u00e9couverte du <strong>trou noir et glac\u00e9 de la d\u00e9route<\/strong> puisque se produisant alors que les USA vivent depuis pr\u00e8s de quinze ans en \u00e9tat permanent de guerre et de mobilisation.<\/p>\n<\/p>\n<p><p>Je crois que nous allons tr\u00e8s vite lire sur le site un texte sur le th\u00e8me : \u00ab\u00a0Les Russes en Syrie, s&rsquo;ils n&rsquo;ont pas chang\u00e9 le monde, vont provoquer, ou peut-\u00eatre ont d\u00e9j\u00e0 provoqu\u00e9 au sein de cette communaut\u00e9 de s\u00e9curit\u00e9 nationale de Washington qui constitue la colonne vert\u00e9brale du Syst\u00e8me bien plus que tout le reste (y compris la finance), une terrible crise psychologique\u00a0\u00bb. On y \u00e9tudiera les causes de ce ph\u00e9nom\u00e8ne et la fa\u00e7on dont les USA peuvent soit tenter d&rsquo;y rem\u00e9dier, soit ne m\u00eame plus avoir la force de tenter d&rsquo;y rem\u00e9dier. Moi, dans ce texte-l\u00e0, je vais m&rsquo;attacher \u00e0 tenter de montrer en quoi il pourrait s&rsquo;agir d&rsquo;un \u00ab\u00a0choc psychologique\u00a0\u00bb \u00e9quivalent \u00e0 ceux de Pearl Harbor et de 9\/11, mais avec cette capitale dimension d&rsquo;inversion (le \u00ab\u00a0trou noir et glac\u00e9 de la d\u00e9route\u00a0\u00bb).<\/p>\n<\/p>\n<p><p>Pour Pearl Harbor, c&rsquo;est \u00e9vident : le choc de <strong>l&rsquo;attaque venue de l&rsquo;ext\u00e9rieur<\/strong> est d&rsquo;une tr\u00e8s grande force et modifie de fond en comble la psychologie de l&rsquo;am\u00e9ricanisme, suscitant une intense et imm\u00e9diate mobilisation. Laissons de c\u00f4t\u00e9 les implications int\u00e9rieures et manigances diverses : l&rsquo;attaque jetant les USA dans la guerre, donc constituant <a href=\"http:\/\/www.dedefensa.org\/article\/notes-tres-longues-sur-le-trou-noir-du-xxeme-siecle\">le rem\u00e8de <strong>temporaire<\/strong><\/a> de la Grande D\u00e9pression ; les man&oelig;uvres de Roosevelt pour au moins favoriser ce conflit, sinon le pr\u00e9cipiter, jusqu&rsquo;aux soup\u00e7ons dont certains sont notablement \u00e9tay\u00e9s selon lesquels Roosevelt \u00e9tait au courant de l&rsquo;attaque mais n&rsquo;en avait pas averti le commandement de l&rsquo;US Navy, notamment l&rsquo;amiral Stark commandant la Flotte du Pacifique \u00e0 Hawaii. Je garde le fait psychologique qu&rsquo;il faut lier tr\u00e8s serr\u00e9 au fait de l&rsquo;\u00e9v\u00e9nement survenu <strong>du dehors (ou au dehors<\/strong>) des USA. C&rsquo;est cela en effet, cette incursion du dehors de la nation exceptionnelle, choisie par le Seigneur, qui importe par-dessus tout ; il n&rsquo;y a pas de plus grand sacril\u00e8ge ni de plus grand malheur qu&rsquo;une intervention hostile contre cette \u00ab\u00a0Cit\u00e9 de Dieu\u00a0\u00bb, une intervention qui viendrait des terres et des projets vulgaires con\u00e7us dans le reste du monde, qui est d&rsquo;une substance beaucoup plus basse.<\/p>\n<\/p>\n<p><p>&#8230; Pour cette raison, je ne retiens pas le Vietnam et sa d\u00e9faite de 1975 comme un de ces \u00ab\u00a0chocs psychologiques\u00a0\u00bb, parce que la catastrophe vietnamienne est d&rsquo;abord le produit d&rsquo;une guerre civile int\u00e9rieure (r\u00e9volte des Noirs, r\u00e9volte des campus, mouvements de contestation et de contre-culture, etc., se cristallisant dans l&rsquo;opposition \u00e0 la guerre du Vietnam). Les agitations int\u00e9rieures, les malheurs int\u00e9rieurs, les dangers int\u00e9rieurs, font partie de ce qui est concevable et paradoxalement acceptable, m\u00eame si la mort et le suicide pourrait sanctionner l&rsquo;\u00e9pisode. C&rsquo;est l&rsquo;aspect tr\u00e8s paradoxal de la citation qu&rsquo;on fait souvent sur ce site, du fameux discours de Lincoln de 1838 :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Si la destruction devait un jour nous atteindre, nous devrions en \u00eatre nous-m\u00eames les premiers et les ultimes artisans. En tant que nation d&rsquo;hommes libres, nous devons \u00e9ternellement survivre, ou mourir en nous suicidant<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il y a certes dans ces deux phrases une sinistre pr\u00e9diction, et c&rsquo;est dans ce sens qu&rsquo;on les cite souvent ; mais il y a aussi <strong>une incroyable affirmation d&rsquo;arrogance et d&rsquo;<em>hybris<\/em><\/strong>, d&rsquo;affirmer que seuls les &Eacute;tats-Unis sont capables de d\u00e9truire les Etats-Unis, c&rsquo;est-\u00e0-dire que nulle force ext\u00e9rieure n&rsquo;est autoris\u00e9e en fait \u00e0 entretenir de tels projets \u00e0 leur encontre, et qu&rsquo;il puisse y avoir des occurrences qui puissent survenir dans ce sens repr\u00e9sente un choc absolument fantastique. Pour cette raison, les troubles int\u00e9rieurs qui rendent compte des al\u00e9as de la seule histoire universelle possible pour ce pays unique, c&rsquo;est-\u00e0-dire sa propre histoire, constituent bien moins un choc psychologique que les troubles venus de l&rsquo;ext\u00e9rieur, n\u00e9cessairement sacril\u00e8ges, avec tout le poids du choc qui est presque un d\u00e9fi inf\u00e2me lanc\u00e9 au Seigneur-Cr\u00e9ateur de la chose.<\/p>\n<\/p>\n<p><p>Ainsi en venons-nous \u00e0 9\/11, qui a <strong>quelque chose d&rsquo;infiniment myst\u00e9rieux pour moi<\/strong>. (Et qui dit \u00ab\u00a0myst\u00e9rieux\u00a0\u00bb dans le cas de la Grande R\u00e9publique bidon-<em>gilden<\/em> qui est toute enti\u00e8re une construction dont le but extrahumain et surhumain est d\u00e8s l&rsquo;origine la d\u00e9structuration et la dissolution du monde, dit <strong>n\u00e9cessairement mal\u00e9fique<\/strong> ; encore plus, certes si l&rsquo;on tient compte de tout ce qui a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 depuis \u00e0 son propos, &ndash; cela pour les plus innocents, les autres \u00e9tant depuis longtemps au courant.)<\/p>\n<\/p>\n<p><p>9\/11, donc, ou 11 septembre 2001&#8230; Je suis port\u00e9 \u00e0 croire qu&rsquo;il y a eu des manigances, des complicit\u00e9s, voire plus, du r\u00e9gime en place (GW Bush et sa multitude d&rsquo;acolytes), dans tous les cas de certains de ces composants, dans la manufacture de cette attaque. Parmi les divers suspects, on placerait volontiers en t\u00eate de liste des personnages comme Cheney et Rumsfeld ; pourtant, je crois absolument \u00e0 la sinc\u00e9rit\u00e9 de Cheney disant \u00e0 l&rsquo;ambassadeur de France venu le saluer en novembre 2002, avant le d\u00e9part de l&rsquo;ambassadeur de Washington :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Vous autres, Europ\u00e9ens, vous n&rsquo;imaginez pas l&rsquo;ampleur de l&rsquo;effet qu&rsquo;a produit sur nous l&rsquo;attaque du 11 septembre<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ainsi, en poussant l&rsquo;hypoth\u00e8se \u00e0 l&rsquo;extr\u00eame mais sans nulle exag\u00e9ration ni invraisemblance, on aurait un personnage, instigateur sinon inform\u00e9 de l&rsquo;attaque ou de sa possibilit\u00e9 avant qu&rsquo;elle n&rsquo;ait eu lieu, affirmer que cette attaque a eu sur lui un effet psychologique extraordinaire&#8230; <strong>Comme si le largement-attendu se transformait, une fois r\u00e9alis\u00e9, en compl\u00e8tement-inattendu<\/strong>, avec l&rsquo;effet psychologique \u00e0 mesure. Mais peut-\u00eatre, si l&rsquo;on observe l&rsquo;Histoire au plus long de ses termes et du plus haut de ses sommets m\u00e9tahistoriques, le montage 9\/11, si montage il y eut, n&rsquo;est-il qu&rsquo;une fa\u00e7on particuli\u00e8rement vicieuse de donner raison \u00e0 Lincoln. (D&rsquo;ailleurs, certains pourraient dire la m\u00eame chose, s&rsquo;ils croient \u00e0 la manigance, du cas Roosevelt\/Pearl Harbor, pour le r\u00e9sultat final et l&rsquo;encha&icirc;nement jusqu&rsquo;\u00e0 nous que d\u00e9clenche la Deuxi\u00e8me Guerre mondiale.)<\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il en soit, le choc 9\/11 est l\u00e0 et bien l\u00e0. Nous vivons sous ses effets sans nombre, ses r\u00e9pliques et contre-r\u00e9pliques depuis pr\u00e8s de quinze ans&#8230; Fort bien, mais comment pourrais-je en venir \u00e0 la situation pr\u00e9sente, \u00e0 l&rsquo;intervention de la Russie en Syrie, et comment parviendrais-je \u00e0 aligner cet \u00e9v\u00e9nement sur les deux pr\u00e9c\u00e9dents ? Je vais tenter de m&rsquo;expliquer. Que contient en substance cet \u00e9v\u00e9nement (c&rsquo;est justement sur quoi portera le texte \u00e0 venir mentionn\u00e9 plus haut) ? (Ici, on tient l&rsquo;\u00e9l\u00e9ment nucl\u00e9aire \u00e0 part, <a href=\"http:\/\/www.dedefensa.org\/article\/la-routinisation-de-la-troisieme-guerre-mondiale\">comme on a vu d\u00e9battre<\/a> ceux qui parlaient r\u00e9cemment de la Troisi\u00e8me Guerre mondiale, sans m\u00eame effleurer le fait nucl\u00e9aire, &ndash; toujours la psychologie&#8230;)<\/p>\n<\/p>\n<p><p>&#8230; Non d&rsquo;ailleurs, nullement \u00ab\u00a0que contient cet \u00e9v\u00e9nement ?\u00a0\u00bb, mais plut\u00f4t : que nous dit cet \u00e9v\u00e9nement des Russes en Syrie ? Qu&rsquo;entendons-nous de lui, \u00e0 Washington ? Un bavardage continuel, un \u00ab\u00a0bruit de fond\u00a0\u00bb qui devient assourdissant concernant les capacit\u00e9s russes, le constat qu&rsquo;elles sont peut-\u00eatre, sans doute, sup\u00e9rieures \u00e0 celles des USA. Un fameux colonel de l&rsquo;US Army, Douglas MacGregor, qui dit l&rsquo;indicible :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>In early September he circulated a PowerPoint presentation showing that in a head-to-head confrontation pitting the equivalent of a U.S. armored division against a likely Russian adversary, the U.S. division would be defeated. \u00ab\u00a0Defeated isn&rsquo;t the right word,\u00a0\u00bb Macgregor <a href=\"http:\/\/www.zerohedge.com\/news\/2015-11-07\/legendary-us-army-commander-says-russia-would-annihilate-us-head-head-battle\">told me last week<\/a>. <strong>\u00ab\u00a0The right word is annihilated.\u00a0\u00bb<\/strong><\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il s&rsquo;agit de la p\u00e9n\u00e9tration dans les esprits que l&rsquo;arm\u00e9e des &Eacute;tats-Unis n&rsquo;est plus au-dessus absolument des autres, quelque chose d&rsquo;intouchable, d&rsquo;une autre cat\u00e9gorie sup\u00e9rieure ; peut-\u00eatre m\u00eame l&rsquo;arm\u00e9e des &Eacute;tats-Unis est-elle devenue quelque chose de l&rsquo;int\u00e9rieur des &Eacute;tats-Unis qui est tr\u00e8s susceptible <strong>d&rsquo;\u00eatre battu par quelque chose de l&rsquo;ext\u00e9rieur<\/strong> (la Russie, pensez !). Et alors, il s&rsquo;agit des &Eacute;tats-Unis eux-m\u00eames&#8230; En effet, les \u00e9v\u00e8nements, les circonstances, les conceptions ont fait que l&rsquo;arm\u00e9e, la force militaire, est devenue la repr\u00e9sentation des USA, <strong>de l&rsquo;int\u00e9rieur m\u00eame des USA, de la substance des USA, projet\u00e9e partout dans le monde<\/strong> (plus de mille bases, ses bombardiers universels, ses porte-avions au-dessus de toutes les mers du globe, bla-bla-bla). C&rsquo;est donc, avec l&rsquo;affreuse r\u00e9v\u00e9lation de la-Russie-en-Syrie en train de se faire, la r\u00e9alisation psychologique que ce qui repr\u00e9sente l&rsquo;int\u00e9rieur fondamental des USA pourrait \u00eatre battu, vaincu par quelque chose d&rsquo;ext\u00e9rieur &#8230; Voil\u00e0 ce qui repr\u00e9sente peut-\u00eatre bien, peut-\u00eatre s&ucirc;rement, \u00e0 mon sens, un formidable choc psychologique en devenir, sinon d\u00e9j\u00e0 sur le point d&rsquo;\u00eatre subi, <strong>sinon m\u00eame d\u00e9j\u00e0-ass\u00e9n\u00e9<\/strong>. Un nouveau Pearl-Harbor, un nouveau 9\/11, mais cette fois avec toute la puissance des USA d\u00e9ploy\u00e9e en ordre de combat au contraire compl\u00e8tement de Pearl-Harbor et de 9\/11 ; cette fois<strong> sans aucune position possible<\/strong> de renversement, de riposte, de sauvegarde jusqu&rsquo;\u00e0 la victoire finale, comme dans les films d&rsquo;Hollywood des <em>good old times<\/em>, quand le 7eme de cavalerie, John Wayne en t\u00eate, arrivait toujours \u00e0 temps.<\/p>\n<\/p>\n<p><p>&#8230; Dans ce cas horrible, et pour tenir compte de la pr\u00e9diction de Lincoln, la Grande r\u00e9publique en toc pr\u00e9f\u00e9rerait-elle le suicide \u00e0 la perspective, m\u00eame th\u00e9orique, mais s&ucirc;rement psychologique, de voir son int\u00e9rieur d&rsquo;elle-m\u00eame vaincue par quelque chose d&rsquo;ext\u00e9rieur ? Alors, pour la premi\u00e8re fois, on pourrait dire que les &Eacute;tats-Unis d&rsquo;Am\u00e9rique auraient apport\u00e9 quelque chose de constructif et d&rsquo;utile \u00e0 la longue lign\u00e9e des civilisations qui font l&rsquo;histoire du monde, en r\u00e9ussissant \u00e0 porter le coup d\u00e9cisif \u00e0 la n\u00f4tre qui ne m\u00e9rite plus que cela.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La psych\u00e9 de G.I. Joe 9 novembre 2015 &ndash; Je vais m&rsquo;attacher \u00e0 un aspect tr\u00e8s important, le plus important d&rsquo;ailleurs, dans tous les travaux de ce site, &ndash; la psychologie ; plus pr\u00e9cis\u00e9ment, la psychologie US depuis que les Russes sont en Syrie. Je crois en effet qu&rsquo;il existe une tr\u00e8s forte possibilit\u00e9 que&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[354,370,1294,3176,3896,3175,3080,2730,5491,5230,3867,1010],"class_list":["post-76223","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-354","tag-370","tag-cheney","tag-harbor","tag-lincoln","tag-pearl","tag-roosevelt","tag-russie","tag-suicide","tag-superiorite","tag-syrie","tag-vietnam"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76223"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76223\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}