{"id":76250,"date":"2015-11-23T06:41:26","date_gmt":"2015-11-23T06:41:26","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/11\/23\/union-nationale-contre-letat-islamique-ei\/"},"modified":"2015-11-23T06:41:26","modified_gmt":"2015-11-23T06:41:26","slug":"union-nationale-contre-letat-islamique-ei","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/11\/23\/union-nationale-contre-letat-islamique-ei\/","title":{"rendered":"Union nationale contre l&rsquo;Etat islamique (EI)"},"content":{"rendered":"<p><p>Union nationale contre l&rsquo;Etat islamique (EI)<\/p>\n<\/p>\n<p><p><strong>L&rsquo;EI se pr\u00e9sente aujourd&rsquo;hui comme un pouvoir \u00e0 multi-faces ayant entrepris de conqu\u00e9rir la plan\u00e8te. Il utilise pour cela les moyens religieux, militaires, \u00e9conomiques que l&rsquo;\u00e9volution r\u00e9cente du monde a mis \u00e0 sa disposition.<\/strong><\/p>\n<\/p>\n<p><p>Pour le combattre, la France qui fait partie de ses premi\u00e8res cibles, doit utiliser toutes les ressources dont elle dispose. Il sera indispensable que ses forces politiques acceptent de r\u00e9aliser pour ce faire une v\u00e9ritable Union nationale, allant de l&rsquo;extr\u00eame gauche jusqu&rsquo;au Front national.<\/p>\n<\/p>\n<p><p>&bull; Renforcer consid\u00e9rablement, quels qu&rsquo;en soient les co&ucirc;ts, les moyens humains et mat\u00e9riels de ses forces militaires et de police. (1) La m\u00eame chose s&rsquo;impose en mati\u00e8re judiciaire, sans parler de r\u00e9formes du droit. Sait-on que la plupart des juges passent l&rsquo;essentiel de leur temps \u00e0 traiter des probl\u00e8mes de proc\u00e9dure soulev\u00e9s par les centaines d&rsquo;avocats \u00e0 la solde des terroristes &quot;pr\u00e9sum\u00e9s&quot; plac\u00e9s en garde \u00e0 vue ou assign\u00e9s \u00e0 r\u00e9sidence. Sans quoi ceux-ci, malgr\u00e9 leur dangerosit\u00e9, seront rel\u00e2ch\u00e9s.<\/p>\n<\/p>\n<p><p>&bull; Engager une politique d&rsquo;investissement consid\u00e9rable, l\u00e0 encore quels qu&rsquo;en soient les co&ucirc;ts, en mati\u00e8re scientifique, technologique et industriel. Il s&rsquo;agira de se doter \u00e0 nouveau d&rsquo;un potentiel qu&rsquo;elle a laiss\u00e9 se d\u00e9truire. Un point essentiel sera l&rsquo;acquisition des outils num\u00e9riques indispensables. Ces divers investissements viseront simultan\u00e9ment les applications militaires et civiles.<\/p>\n<\/p>\n<p><p>&bull; Accepter en contrepartie les sacrifices n\u00e9cessaires en mati\u00e8re de consommations non essentielles.<\/p>\n<\/p>\n<p><p>&bull; Au plan europ\u00e9en, convaincre l&rsquo;Union europ\u00e9enne (UE) et les Etats membres de la n\u00e9cessit\u00e9 pour la France de telles politiques, quelles qu&rsquo;en soient les cons\u00e9quences, notamment en mati\u00e8re de dette. Il faudra par ailleurs les inciter \u00e0 faire de m\u00eame en ce qui les concerne, de fa\u00e7on \u00e0 obtenir des politiques europ\u00e9ennes communes. En cas de refus &ndash; ce qui serait inconcevable &ndash; la France, sans rechercher \u00e0 sortir de l&rsquo;UE, devra se r\u00e9soudre \u00e0 ne pas appliquer les points des trait\u00e9s europ\u00e9ens l&#8217;emp\u00eachant de mener cette politique de d\u00e9fense.<\/p>\n<\/p>\n<p><p>&bull; Au plan international, organiser une coop\u00e9ration totale et sans arri\u00e8res pens\u00e9es avec les Etats qui, tels en premier lieu la Russie, ont engag\u00e9 une telle politique. Dans le m\u00eame esprit, il faudra consid\u00e9rer l&rsquo;Iran commeu ne alli\u00e9e et cesser de combattre Bashar al Assad, lui aussi alli\u00e9 de fait contre l&rsquo;EI. .A l&rsquo;inverse il faudra prendre toutes distances n\u00e9cessaires avec les Etats qui directement ou indirectement, ont suscit\u00e9 l&rsquo;EI et continuent \u00e0 le financer. Parmi ces Etats, se trouvent en premier lieu les monarchies p\u00e9troli\u00e8res du Golfe (\u00e0 qui on devra cesser de vendre des armes). On y ajoutera  dans une certaine mesure, malheureusement, les Etats-Unis, responsables depuis 15 ans de la situation actuelle.et qui continuent, malgr\u00e9 de bonnes paroles, \u00e0 mener campagne contre la Russie en s&rsquo;acharnant \u00e0 limiter son influence au Moyen Orient.<\/p>\n<\/p>\n<p><p>Cette guerre sera longue et imposera des pertes humaines et mat\u00e9rielles qu&rsquo;il faudra accepter. L&rsquo;EI sera difficile \u00e0 \u00e9radiquer, compte tenu des positions que la faiblesse des &Eacute;tats, y compris la France, lui avait permis d&rsquo;acqu\u00e9rir.<\/p>\n<\/p>\n<p><h4>Jean Paul Baquiast<\/h4>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Notes<\/h2>\n<\/p>\n<p><p>1) Nous avons pr\u00e9c\u00e9demment publi\u00e9 une note en ce sens. Elle demeure plus que jamais d&rsquo;actualit\u00e9.<\/p>\n<\/p>\n<p><p>*) Post scriptum : Sur les aides am\u00e9ricaines, anglaises et turques \u00e0 l&rsquo;EI, <a href=\"http:\/\/tlaxcala-int.org\/article.asp?reference=16612\">voir cet article<\/a> tr\u00e8s bien document\u00e9.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Union nationale contre l&rsquo;Etat islamique (EI) L&rsquo;EI se pr\u00e9sente aujourd&rsquo;hui comme un pouvoir \u00e0 multi-faces ayant entrepris de conqu\u00e9rir la plan\u00e8te. Il utilise pour cela les moyens religieux, militaires, \u00e9conomiques que l&rsquo;\u00e9volution r\u00e9cente du monde a mis \u00e0 sa disposition. Pour le combattre, la France qui fait partie de ses premi\u00e8res cibles, doit utiliser toutes&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[7895,12572,2687,3867],"class_list":["post-76250","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-baquiast","tag-daesh","tag-france","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76250"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76250\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}