{"id":76290,"date":"2015-12-12T06:09:07","date_gmt":"2015-12-12T06:09:07","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/12\/12\/kiev-la-folle-tragedie-bouffe\/"},"modified":"2015-12-12T06:09:07","modified_gmt":"2015-12-12T06:09:07","slug":"kiev-la-folle-tragedie-bouffe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/12\/12\/kiev-la-folle-tragedie-bouffe\/","title":{"rendered":"\u201cKiev-la-folle\u201d, trag\u00e9die-bouffe"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">\u00ab\u00a0Kiev-la-folle\u00a0\u00bb, trag\u00e9die-bouffe<\/h2>\n<\/p>\n<p><p>12 d\u00e9cembre 2015 &ndash; Il y a deux ans d\u00e9j\u00e0, nous \u00e9tions entr\u00e9s dans la crise ukrainienne apr\u00e8s la rupture entre Ianoukovitch et l&rsquo;UE (18 novembre 2013). Moi, je n&rsquo;avais rien vu venir tr\u00e8s pr\u00e9cis\u00e9ment, suivant d&rsquo;une fa\u00e7on tr\u00e8s \u00e9pisodique les \u00ab\u00a0r\u00e9volutions de couleur\u00a0\u00bb, les parcours des oligarques, la corruption, etc. <strong>La crise me prit par surprise comme une trag\u00e9die et c&rsquo;en fut une effectivement <\/strong>; entre l&rsquo;\u00e9pisode de novembre 2013 et le coup d&rsquo;&Eacute;tat de f\u00e9vrier 2014 (deux ans bient\u00f4t ou d\u00e9j\u00e0 ) l&rsquo;Ukraine s&#8217;embrasa tragiquement. Apr\u00e8s la symphonie brutale et orchestr\u00e9e comme on est usurp\u00e9 du Maidan, il y eut <a href=\"http:\/\/www.dedefensa.org\/article\/la-tragedie-de-kiev-en-direct-signez-ou-vous-etes-morts\">la \u00ab\u00a0nuit des dupes\u00a0\u00bb du 21 f\u00e9vrier<\/a> qui aboutit \u00e0 la fuite de Ianoukovitch, puis tr\u00e8s vite la s\u00e9cession de la Crim\u00e9e et la guerre cruelle du Donbass, avec les tourments int\u00e9rieurs au son de la croix gamm\u00e9e et du fric US distribu\u00e9 aux oligarques, et le frisson de la possibilit\u00e9 de l&rsquo;apocalypse nucl\u00e9aire qui courait dans ces sombres \u00e9v\u00e8nements. L&rsquo;art de l&rsquo;irr\u00e9el et la haine de la v\u00e9rit\u00e9 de cette contre-civilisation <strong>achev\u00e8rent de tuer la r\u00e9alit\u00e9<\/strong> et je concoctai fi\u00e9vreusement <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">le concept de d\u00e9terminisme-narrativiste<\/a>. Puis la crise s&rsquo;est subrepticement mais irr\u00e9m\u00e9diablement encalmin\u00e9e dans Minsk1, puis Minsk 2, etc., gr\u00e2ce \u00e0 la patience habile de Poutine, le sens de la man&oelig;uvre couarde de Merkel-Hollande, l&rsquo;incomp\u00e9tence stupide de Porochenko et la lourde stupidit\u00e9 du pseudo-\u00e9l\u00e9phant (le noble animal m\u00e9rite mieux) des USA dans le magasin de porcelaine. Tout ce qui se fait depuis verrouille le d\u00e9sastre : le sabotage de l&rsquo;alimentation d&rsquo;\u00e9lectricit\u00e9 de la Crim\u00e9e par l&rsquo;Ukraine conduit les Russes \u00e0 intervenir d&rsquo;urgence et \u00e0 acc\u00e9l\u00e9rer l&rsquo;int\u00e9gration de la Crim\u00e9e dans la Russie ; l&rsquo;intervention du FMI pour annuler la dette russe de l&rsquo;Ukraine fait un peu plus tomber les masques (le FMI instrument des USA, cela allait mieux quand cela se voyait moins) et ne sauve l&rsquo;Ukraine de rien.<\/p>\n<\/p>\n<p><p>La v\u00e9rit\u00e9-de-situation de l&rsquo;Ukraine, aujourd&rsquo;hui, c&rsquo;est cette sc\u00e8ne grotesque qui <a href=\"http:\/\/www.zerohedge.com\/news\/2015-12-11\/caught-tape-ukraine-premier-assaulted-parliament\">a eu lieu hier ou avant-hier<\/a>, je ne sais, \u00e0 la <em>Rada<\/em>. Le Premier ministre Iatseniouk, si s\u00e9duisant avec sa t\u00eate ras\u00e9e d&rsquo;avorton sorti d&rsquo;une fausse couche bureaucratique, parle \u00e0 la tribune ; un d\u00e9put\u00e9 du parti du pr\u00e9sident Porochenko, Olej Barna, arrive d&rsquo;un pas \u00e9nergique vers la tribune, un bouquet de roses \u00e0 la main ; d\u00e9sar\u00e7onn\u00e9 et n&rsquo;y comprenant rien, Iatseniouk le laisse monter derri\u00e8re lui, peut-\u00eatre aime-t-il les roses et qu&rsquo;on lui conte fleurette, peut-\u00eatre est-ce la tendresse pense-t-il en acceptant le bouquet et ainsi les bras embarrass\u00e9s ; Barna le saisit alors par les \u00e9paules pour l&rsquo;\u00e9jecter de la tribune ; Iatseniouk r\u00e9siste sans trop y croire ; l&rsquo;autre le saisit par l&rsquo;entrejambes, litt\u00e9ralement par les couilles puisque Iatseniouk doit \u00eatre dot\u00e9 de ce noble instrument, pour achever le travail ; la <em>Rada<\/em> bascule avec l&rsquo;orateur dans le d\u00e9sordre complet tandis qu&rsquo;on voit Iatseniouk se remettant, contemplant la sc\u00e8ne, posant le bouquet, puis le reprenant apr\u00e8s tout et s&rsquo;\u00e9clipsant avec la discr\u00e9tion des grands hommes tandis que le baston cogne dur autour de lui entre disons une trentaine d&rsquo;\u00e9lus de la nation&#8230; La v\u00e9rit\u00e9-de-situation de l&rsquo;Ukraine, aujourd&rsquo;hui, c&rsquo;est le trou noir du d\u00e9sordre (ici avec sa touche de grotesquerie tr\u00e8s ukrainienne) qui grandit sans cesse comme s&rsquo;il ne devait jamais cesser.<\/p>\n<\/p>\n<p><p>Ainsi vont les crises aujourd&rsquo;hui : elles naissent dans un bruit terrible de trag\u00e9die puis s&rsquo;\u00e9tiolent peu \u00e0 peu ; elles se d\u00e9structurent, se dissolvent dans cette dr\u00f4le d&rsquo;esp\u00e8ce de trag\u00e9die devenue bouffonnerie sans perdre leur caract\u00e8re d&rsquo;origine puisqu&rsquo;il est dit qu&rsquo;elles doivent durer jusqu&rsquo;\u00e0 l&rsquo;entropisation par la n\u00e9antisation du Grand Tout. <strong>La trag\u00e9die de la crise ukrainienne est devenue une trag\u00e9die-bouffe<\/strong>, ayant pris sa place dans le processus de d\u00e9structuration-dissolution du monde, jusqu&rsquo;\u00e0 la n\u00e9antisation de l&rsquo;entropisation. La crise couve toujours, elle peut exploser \u00e0 nouveau comme font les volcans \u00e9pisodiquement, car rien ne cesse jamais dans ce processus de destruction du monde enferm\u00e9 dans sa contradiction de l&rsquo;infinitude qui finira par engloutir le <em>diabolus ex machina<\/em> lui-m\u00eame. C&rsquo;est bien son propre monde que le Syst\u00e8me r\u00e9duit \u00e0 la n\u00e9antisation de l&rsquo;entropisation,<strong> comme si c&rsquo;\u00e9tait lui-m\u00eame.<\/strong><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Kiev-la-folle\u00a0\u00bb, trag\u00e9die-bouffe 12 d\u00e9cembre 2015 &ndash; Il y a deux ans d\u00e9j\u00e0, nous \u00e9tions entr\u00e9s dans la crise ukrainienne apr\u00e8s la rupture entre Ianoukovitch et l&rsquo;UE (18 novembre 2013). Moi, je n&rsquo;avais rien vu venir tr\u00e8s pr\u00e9cis\u00e9ment, suivant d&rsquo;une fa\u00e7on tr\u00e8s \u00e9pisodique les \u00ab\u00a0r\u00e9volutions de couleur\u00a0\u00bb, les parcours des oligarques, la corruption, etc. La crise&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[17195,17197,17196,2631,3356,11929,15636,17198,2945,11994,15691,15132,1296],"class_list":["post-76290","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-barna","tag-baston","tag-bouquet","tag-de","tag-desordre","tag-entropisation","tag-iatseniouk","tag-inoukovitch","tag-maidan","tag-neantisation","tag-rada","tag-roses","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76290"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76290\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}