{"id":76291,"date":"2015-12-12T13:04:44","date_gmt":"2015-12-12T13:04:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/12\/12\/vers-une-ukrainisation-de-la-turquie\/"},"modified":"2015-12-12T13:04:44","modified_gmt":"2015-12-12T13:04:44","slug":"vers-une-ukrainisation-de-la-turquie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/12\/12\/vers-une-ukrainisation-de-la-turquie\/","title":{"rendered":"Vers une \u201cukrainisation\u201d de la Turquie ?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Vers une \u00ab\u00a0ukrainisation\u00a0\u00bb de la Turquie ?<\/h2>\n<\/p>\n<p><p>On nous dit que les affaires vont soudainement tr\u00e8s bien entre la Turquie et l&rsquo;Ukraine. Le \u00ab\u00a0Calife \u00e0 la place du Calife\u00a0\u00bb et le \u00ab\u00a0roi du chocolat\u00a0\u00bb, &ndash; respectivement MM. Erdogan et Porochenko, &ndash; se sont trouv\u00e9s comme pacte d&rsquo;amiti\u00e9 une fondamentale inimit\u00e9 commune qui les pousse \u00e0 mettre en place une alliance irr\u00e9sistible. Erdogan s&rsquo;appuie sur l&rsquo;OTAN et les USA, Porochenko sur Joe Biden et les USA, ce qui vous a un air de famille ; Erdogan alimente <em>Daesh<\/em> en bons conseils et en camions-citernes, Porochenko laisse faire ses croix gamm\u00e9es, ce qui vous a un air de complicit\u00e9. Tous les deux, bien s&ucirc;r, se jugent assez assur\u00e9s des \u00ab\u00a0valeurs\u00a0\u00bb postmodernes pour r\u00e9clamer une admission des plus rapides dans l&rsquo;UE, ce qui a de moins en moins de chances de se faire ; en attendant cette issue qui ne viendra pas, ces deux pays sont, par des moyens divers, des nuisances constantes pour l&rsquo;UE, qui doit supporter la pesanteur extr\u00eame de leur all\u00e9geance suppos\u00e9e.<\/p>\n<\/p>\n<p><p>Voici donc quelques mots sur \u00ab\u00a0les affaires\u00a0\u00bb que Turcs et Ukrainiens envisagent de faire ensemble d\u00e9sormais li\u00e9s par leur commun sentiment antirusse (<em>Russia Insider<\/em> <a href=\"http:\/\/russia-insider.com\/en\/politics\/kiev-cozying-turkey-wake-fallout-russia\/ri11801\">du 12 d\u00e9cembre<\/a>, repris de <em>International Business Times<\/em>) :<\/p>\n<\/p>\n<p><p>&laquo; <em>As tensions between Moscow and Ankara continue, Turkey has turned to another Kremlin foe and Eastern European state: Ukraine. Defense firms in Turkey and Ukraine have begun talks on tank modernization programs, <a href=\"http:\/\/www.defensenews.com\/story\/defense\/land\/vehicles\/2015\/12\/06\/turkish-ukraine-defense-firms-in-talks-for-tank-upgrades\/76889304\/\">Defense News reported Sunday<\/a><\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Both Turkey and Ukraine find themselves at odds with the Kremlin. Russia applied harsh economic sanctions against Ankara after Turkey shot down a Russian jet at the end of November, saying the aircraft crossed into its sovereign airspace. Moscow denies this allegation. Ukraine continues to battle Russian-backed separatists in the Eastern Donbass region in a conflict that has left over 8,000 people dead. Moscow continues to deny playing any direct military role in the conflict in Ukraine. The situation has prompted the leaders of Turkey and Ukraine to <a href=\"http:\/\/en.interfax.com.ua\/news\/general\/307945.html\">warm relations<\/a>. \u00ab\u00a0We have agreed on a plan of our actions and preparations for my visit to Turkey, which is due in the first quarter of 2016,\u00a0\u00bb Ukrainian President Petro Poroshenko said at the start of the month. \u00ab\u00a0We are expecting this visit to make a breakthrough.\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>Si le processus n&rsquo;est pas vraiment \u00e9tonnant, il est remarquable par l&rsquo;esp\u00e8ce de mim\u00e9tisme qui est en cours d&rsquo;installation entre les deux directions, tant la politique semble ne pouvoir se concevoir aujourd&rsquo;hui que sur l&rsquo;apriorisme de l&rsquo;histilit\u00e9 comme r\u00e9f\u00e9rence, y compris les r\u00e9f\u00e9rences communes. Notre hypoth\u00e8se sugg\u00e8re de consid\u00e9rer une \u00e9volution de la Turquie qui pourrait avoir lieu si aucun \u00e9v\u00e9nement majeur ne vient d\u00e9bloquer ses relations avec la Russie. Un tel d\u00e9blocage semble particuli\u00e8rement difficile en raison de l&rsquo;extr\u00eame fermet\u00e9 de la politique russe qui est un \u00e9l\u00e8ment nouveau et tr\u00e8s puissant d&rsquo;une part, de l&rsquo;attitude pour l&rsquo;instant intransigeante d&rsquo;Erdogan, facilit\u00e9e par son isolement int\u00e9rieur volontaire et l&rsquo;\u00e9volution de son pouvoir vers une sorte d&rsquo;absolutisme constitutionnel d&rsquo;autre part.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il semblerait alors possible que la Turquie d&rsquo;Erdogan suive une \u00e9volution tr\u00e8s sp\u00e9cifique, se comportant d\u00e9sormais comme l&rsquo;Ukraine de Porochenko, empilant menace sur menace <a href=\"http:\/\/russia-insider.com\/en\/russia-fires-moon-shot-over-bosphorus-turks-threaten-war\/ri11792\">contre les Russes<\/a>, parlant de guerre, de riposte, pratiquant divers actes d&rsquo;ill\u00e9galit\u00e9 internationale, figurant avec \u00e0 sa t\u00eate une structure n\u00e9potique, corrompue et mafieuse (le clan Erdogan), etc. A notre sens, la politique turque ne se trouve pas loin, d\u00e9sormais, d&rsquo;\u00eatre engag\u00e9e sur la voie de se trouver r\u00e9duite au cadre d&rsquo;action et \u00e0 la pratique ukrainiennes, elle-m\u00eame r\u00e9duite \u00e0 d\u00e9velopper des s\u00e9ries d&rsquo;anath\u00e8mes antirusses comme axe fondamental de sa politique g\u00e9n\u00e9rale. C&rsquo;est ce que nous nommons l'\u00a0\u00bbukrainisation\u00a0\u00bb de la Turquie, qui constitue un processus d&rsquo;abaissement de la politique ext\u00e9rieure \u00e0 un simple antagonisme sans issue ni perspective constructive, sinon le ridicule des menaces de destruction de la Russie ; dans ce cadre, la politique se r\u00e9duit de plus en plus \u00e0 ne consid\u00e9rer qu&rsquo;une seule r\u00e9f\u00e9rence, qui est l&rsquo;hostilit\u00e9 \u00e0 la Russie, et consid\u00e9rant <strong>ses liens avec les autres en fonction de l&rsquo;attitude des autres vis-\u00e0-vis de cette orientation<\/strong>.<\/p>\n<\/p>\n<p><p>Il y a l\u00e0 un \u00ab\u00a0mod\u00e8le\u00a0\u00bb assez nouveau de \u00ab\u00a0faillitisation\u00a0\u00bb des &Eacute;tats (la nouveaut\u00e9 de la chose justifiant de proposer un terme nouveau pour la qualifier) ; c&rsquo;est-\u00e0-dire un processus non pas de faillite normale (il y aura toujours un FMI  de fortune ou un <em>bankster<\/em> d&rsquo;infortune pour sauver la baraque au dernier moment) mais bien de d\u00e9veloppement des structures et du statut de l&rsquo;&Eacute;tat vers une sorte de faillite volontaire, par processus de corruption psychologique avec le reste qui suit selon un objectif de plus en plus unique et essentiellement n\u00e9gatif ; une faillite qui s&rsquo;effectue dans la mesure de son abaissement, de sa r\u00e9duction \u00e0 des processus n\u00e9gatifs de communication essentiellement et au choix d&rsquo;une <em>narrative<\/em> \u00e9galement n\u00e9gative (antirusse) \u00e0 la place de la prise en compte des v\u00e9rit\u00e9s-de-situation.<\/p>\n<\/p>\n<p><p>A la lumi\u00e8re de l&rsquo;exemple ukrainien, ce \u00ab\u00a0mod\u00e8le\u00a0\u00bb nous para&icirc;t beaucoup plus cr\u00e9dible comme effet des processus-Syst\u00e8me, que le mod\u00e8le traditionnel des \u00ab\u00a0&Eacute;tats-faillis\u00a0\u00bb (\u00ab\u00a0<em>failed states<\/em>\u00ab\u00a0). Il installe l&rsquo;impuissance et la paralysie \u00e0 mesure des emportements de la rh\u00e9torique, c&rsquo;est-\u00e0-dire la faillite soutenue par la jactance et une sorte de politique du sur-place puisqu&rsquo;enti\u00e8rement conditionn\u00e9e par la n\u00e9gativit\u00e9 des liens avec la Russie. (La Russie est la seule r\u00e9f\u00e9rence \u00e0 consid\u00e9rer \u00e0 cet \u00e9gard \u00e0 cause de sa puissance pri,ncipielle [la souverainet\u00e9] et l&rsquo;effet antiSyst\u00e8me de plus en plus marqu\u00e9 de sa politique.) Il s&rsquo;agit d&rsquo;une sorte de faillite <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-les-termites\">par les termites<\/a> (consid\u00e9r\u00e9es comme un symbole de l&rsquo;\u00e9volution d\u00e9crite), qui minent la psychologie, effectivement \u00e9voluant vers une sorte de n\u00e9antisation de toute existence souveraine. Au bout du compte, ce \u00ab\u00a0mod\u00e8le\u00a0\u00bb n&rsquo;est m\u00eame plus celui de vassal du bloc-BAO mais plut\u00f4t de parasite du Syst\u00e8me qui embarrasse le Syst\u00e8me plus qu&rsquo;il ne le sert bien qu&rsquo;il en soit sa cr\u00e9ature, et dont le sort serait de plus en plus de tourner en rond sur lui-m\u00eame, nourrissant son propre d\u00e9sordre encore plus que diss\u00e9miner ce d\u00e9sordre hors de lui-m\u00eame, et minant d\u00e9cisivement sa propre substance. En effet et bien entendu, l\u00a0\u00bbukrainisation\u00a0\u00bb, ou \u00ab\u00a0mod\u00e8le ukrainien\u00a0\u00bb, laisse libre \u00e0 chacun de ses adeptes de d\u00e9velopper sa propre forme de d\u00e9sordre int\u00e9rieur, celui de \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/kiev-la-folle-tragedie-bouffe\">Kiev-la-folle<\/a>\u00a0\u00bb s&rsquo;\u00e9tant d\u00e9j\u00e0 impos\u00e9 comme typique et tr\u00e8s sp\u00e9cifique comme il convient \u00e0 un arch\u00e9type ; ainsi pourrait-on penser, pour assurer la <em>narrative<\/em> et rassurer les esprits inquiets, qu&rsquo;il s&rsquo;agit d&rsquo;une sorte de souverainet\u00e9, mais invertie : la souverainet\u00e9 qui s&rsquo;exprime dans le choix souverain qu&rsquo;on fait de la forme de sa propre impuissance et du d\u00e9sordre de soi-m\u00eame.<\/p>\n<\/p>\n<p><p>Mis en ligne le 12 d\u00e9cembre 2015 \u00e0 12H58<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vers une \u00ab\u00a0ukrainisation\u00a0\u00bb de la Turquie ? On nous dit que les affaires vont soudainement tr\u00e8s bien entre la Turquie et l&rsquo;Ukraine. Le \u00ab\u00a0Calife \u00e0 la place du Calife\u00a0\u00bb et le \u00ab\u00a0roi du chocolat\u00a0\u00bb, &ndash; respectivement MM. Erdogan et Porochenko, &ndash; se sont trouv\u00e9s comme pacte d&rsquo;amiti\u00e9 une fondamentale inimit\u00e9 commune qui les pousse \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[17199,12611,3737,4321,13382,916,2730,3867,1296],"class_list":["post-76291","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-anatheme","tag-antirussisme","tag-erdogan","tag-narrative","tag-porochenko","tag-poutine","tag-russie","tag-syrie","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76291"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76291\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}