{"id":76308,"date":"2015-12-21T05:23:52","date_gmt":"2015-12-21T05:23:52","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/12\/21\/le-serpent-et-son-image\/"},"modified":"2015-12-21T05:23:52","modified_gmt":"2015-12-21T05:23:52","slug":"le-serpent-et-son-image","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/12\/21\/le-serpent-et-son-image\/","title":{"rendered":"Le serpent et son image"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Le serpent et son image<\/h2>\n<\/p>\n<p><p>Lisant dans votre Journal du <a href=\"http:\/\/www.dedefensa.org\/article\/de-la-fascination-de-la-surpuissance\">20 d\u00e9cembre<\/a> (&laquo; De la fascination de la surpuissance &raquo;) ces paroles que de Gaulle prononcent en ao&ucirc;t 1940 : \u00ab\u00a0<em>Le sort de la guerre est jou\u00e9. L&rsquo;Am\u00e9rique ne va pas tarder \u00e0 entrer en guerre avec toute sa puissance industrielle, l&rsquo;Allemagne a perdu. Il nous faut maintenant songer \u00e0 l&rsquo;apr\u00e8s-guerre&#8230;<\/em>\u00ab\u00a0, je ne peux m&#8217;emp\u00eacher de sourire. Je souris car je les ai entendues prononcer sur Internet il y a quelques jours \u00e0 peine. Je souris car vous commencez votre billet en disant que vous ne savez plus exactement d&rsquo;o&ugrave; vient l&rsquo;anecdote, et qu&rsquo;il me faut quelques temps pour pouvoir me rappeler o&ugrave; je les ai moi-m\u00eame entendues si r\u00e9cemment.<\/p>\n<\/p>\n<p><p>C&rsquo;\u00e9tait dans une vid\u00e9o ajout\u00e9e le 14 d\u00e9cembre, d&rsquo;un d\u00e9bat tenu lui-m\u00eame le 9 d\u00e9cembre \u00e0 Paris autour d&rsquo;un num\u00e9ro de la Revue D\u00e9fense Nationale (<a href=\"http:\/\/melenchon.fr\/2015\/12\/13\/pour-un-nouvel-independantisme-debat-sur-la-defense-nationale\/\">lien<\/a>). Le conf\u00e9rencier \u00e9tait Jean-Philippe Immarigeon, et il faisait une intervention intitul\u00e9e &laquo; Etat de l&#8217;empire \u00e9tats-unien &raquo;, dont l&rsquo;objet \u00e9tait <strong>non<\/strong> <strong>pas<\/strong> la puissance mais <strong>le rapport<\/strong> que l&rsquo;on a \u00e0 la puissance \u00e9tasunienne, la repr\u00e9sentation de cette puissance par l&rsquo;image, et le trouble dans les jugements qu&rsquo;engendre cette repr\u00e9sentation de la puissance.<\/p>\n<\/p>\n<p><p>Ayant \u00e9cout\u00e9 cette conf\u00e9rence avec \u00e0 l&rsquo;esprit le r\u00e9cent d\u00e9veloppement de votre int\u00e9r\u00eat autour de l&rsquo;enjeu de l&rsquo;interpr\u00e9tation de la nature exacte de la puissance du Syst\u00e8me, ou de la lucidit\u00e9 autour du ph\u00e9nom\u00e8ne de &laquo; surpuissance &raquo;, ou de la &laquo; profondeur du mal &raquo;, pourrions-nous dire encore (1), j&rsquo;avais h\u00e9sit\u00e9 \u00e0 signaler cette conf\u00e9rence. Je le fais maintenant, en transformant (tr\u00e8s !) rapidement le post destin\u00e9 au Forum en lignes pour Ouverture Libre.<\/p>\n<\/p>\n<p><p>Je ne peux que conseiller aux lecteurs de <em>defensa.org<\/em> qui n&rsquo;ont pas encore fait leur religion \u00e0 ce sujet de prendre la peine d&rsquo;\u00e9couter dans cette optique les vingt et quelques minutes de <a href=\"https:\/\/www.youtube.com\/watch?v=LJYW0vW6EW8\">l&rsquo;intervention de M. Immarigeon<\/a>.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Parenth\u00e8se sur les images et la repr\u00e9sentation de la puissance<\/h3>\n<\/p>\n<p><p>Immarigeon commence sa conf\u00e9rence en relevant de mani\u00e8re int\u00e9ressante comment les Etats-Unis, en 1939-45, ont recouru au trucage des images pour repr\u00e9senter une puissance de production industrielle pourtant <strong>r\u00e9elle<\/strong> alors &#8211; et aujourd&rsquo;hui encore, dans une certaine mesure (le &laquo; d\u00e9chainement de la mati\u00e8re &raquo; certes, qui s&rsquo;exprime aujourd&rsquo;hui par la destruction totale &ndash; d&rsquo;une puissance inou\u00efe, effectivement &ndash; de l&rsquo;environnement, des sols, des aquif\u00e8res et de la vie l\u00e0 o&ugrave; sont exploit\u00e9, par exemple, le gaz de schiste et les schistes bitumineux).<\/p>\n<\/p>\n<p><p>Le point essentiel est ici de constater combien les Etats-Unis ont plac\u00e9, <strong>au centre de toutes les repr\u00e9sentations d&rsquo;eux-m\u00eames<\/strong>, leur puissance de production industrielle. Et qu&rsquo;ils l&rsquo;ont fait par tous les moyens, preuve de l&rsquo;importance de cet enjeu de repr\u00e9sentation (trucages certes, comme le dit Immarigeon, mais aussi recours \u00e0 la puissance de la production industrielle elle-m\u00eame &ndash; cin\u00e9matographique &#8211; pour diffuser cette repr\u00e9sentation de la puissance de la production industrielle &#8211; celle de la &laquo; ferraille &raquo;.<\/p>\n<\/p>\n<p><p>R\u00e9sultat (recherch\u00e9 ou non, consciemment ou non) de l&rsquo;op\u00e9ration ?<\/p>\n<\/p>\n<p><p>Je dirais : emp\u00eacher les esprits de questionner ou m\u00eame de simplement mettre en perspective la production industrielle (le &laquo; d\u00e9cha&icirc;nement de la mati\u00e8re &raquo;), par l&rsquo;\u00e9tat de choc ou d&rsquo;h\u00e9b\u00e9tude ou de lassitude de l&rsquo;esprit critique qu&rsquo;engendre le simple d\u00e9ferlement brut, massif et r\u00e9p\u00e9t\u00e9 de ces images repr\u00e9sentant la production industrielle, ann\u00e9es apr\u00e8s ann\u00e9es, d\u00e9cennies apr\u00e8s d\u00e9cennies. La fascination du serpent, indeed. Tous les d\u00e9bats sur la &laquo; croissance &raquo;, le PIB (un peu pass\u00e9 de mode certes), notre mode de vie occidentale, le d\u00e9veloppement \u00e0 l&rsquo;occidentale, y a-t-il une alternative ou TINA ? la possibilit\u00e9 ou le bien-fond\u00e9, voire la l\u00e9gitimit\u00e9, de la d\u00e9croissance, le technologisme, le &laquo; solutionnisme &raquo; etc., en ont \u00e9t\u00e9 influenc\u00e9s et totalement neutralis\u00e9s jusqu&rsquo;\u00e0 aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Retour \u00e0 De Gaulle<\/h3>\n<\/p>\n<p><p>Si ce qui a toujours guid\u00e9 l&rsquo;action de Charles de Gaulle, c&rsquo;est, comme vous l&rsquo;\u00e9crivez, une id\u00e9e de la France (le destin de la France), cela explique non seulement sa r\u00e9ussite globale mais aussi des mouvements qui peuvent sembler contradictoires \u00e0 certains (recourir aux USA en 1939, sortir de l&rsquo;OTAN en 1966).<\/p>\n<\/p>\n<p><p>Dans sa conf\u00e9rence, Immarigeon parle de l&rsquo;analyse correcte que fait de Gaulle de la puissance industrielle r\u00e9elle des Etats-Unis en 1940, ce qui semble lui donner la certitude de leur victoire in\u00e9luctable. C&rsquo;est l\u00e0 qu&rsquo;il reprend (en plus rel\u00e2ch\u00e9) les m\u00eames paroles de De Gaulle que vous citez dans votre billet (\u00ab\u00a0<em>Le sort de la guerre est jou\u00e9. L&rsquo;Am\u00e9rique ne va pas tarder \u00e0 entrer en guerre avec toute sa puissance industrielle, l&rsquo;Allemagne a perdu<\/em>\u00ab\u00a0).<\/p>\n<\/p>\n<p><p>(Et lorsque l&rsquo;on regarde la guerre men\u00e9e par les USA et l&rsquo;Allemagne dans l&rsquo;Atlantique (le &laquo; front de l&rsquo;Ouest &raquo;), c&rsquo;est bien une guerre de production industrielle : l&rsquo;enjeu se r\u00e9sume presque au tonnage produit et transport\u00e9 de l&rsquo;autre c\u00f4t\u00e9 de l&rsquo;Atlantique &#8211; comprenant celui amen\u00e9 depuis l&rsquo;Ecosse en Mer Blanche pour ravitailler l&rsquo;URSS dans ce que les Allemands ont appel\u00e9 &laquo; Eismeerfront &raquo; et qui a men\u00e9 les hommes et les navires presque jusqu&rsquo;au P\u00f4le Nord (2) &#8211; contre le tonnage coul\u00e9 par les sous-marins allemands. Dans le Pacifique, la logique de guerre industrielle par simple surclassement en nombre de l&rsquo;ennemi (10 contre 1, voire 100 contre 1) est peu ou prou la m\u00eame (Voire la conf\u00e9rence d&rsquo;Immarigeon, vers 10 minute 40 secondes ; la s\u00e9quence commence \u00e0 7 :57 min.)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Pour en terminer avec la puissance et, incidemment, avec le productivisme (en attendant le tour du Syst\u00e8me)<\/h3>\n<\/p>\n<p><p>Mais il ne faut pas s&rsquo;arr\u00eater \u00e0 l&rsquo;aspect superficiel de cette production ni \u00e0 sa (sur)repr\u00e9sentation par l&rsquo;image, qui nous laisserait vaincu d&rsquo;entr\u00e9e de jeu. La conf\u00e9rence d&rsquo;Immarigeon passe alors (quelque peu rapidement, mais l&rsquo;analyse a \u00e9t\u00e9 faite mille fois et la chose d\u00e9montr\u00e9e) \u00e0 la question de la productivit\u00e9 du syst\u00e8me industriel \u00e9tats-unien, qui est d&rsquo;une indigence remarquable. Ceci parce que le syst\u00e8me s&rsquo;est construit &#8211; et vit depuis lors &ndash; sur l&rsquo;acc\u00e8s \u00e0 des ressources gigantesques (la ressource \u00e9nerg\u00e9tique des hydrocarbures fluides, p\u00e9trole et gaz) qui lui ont permis de <strong>produire \u00e9norm\u00e9ment<\/strong> tout en se contentant d&rsquo;une productivit\u00e9 tr\u00e8s basse &ndash; c&rsquo;est-\u00e0-dire de produire massivement avec un <strong>gaspillage monstrueux<\/strong> (les deux &ndash; production massive et gaspillage monstrueux &ndash; participant \u00e0 la destruction sans pareille de la biosph\u00e8re, des paysages, des oc\u00e9ans, des p\u00f4les, des formes vivantes et de la vie des \u00eatres humains). Production massive, gaspillage monstrueux, absence de r\u00e9flexion et destruction sont bien les sympt\u00f4me de la dynamique de &laquo; <strong>surpuissance-autodestruction <\/strong>&raquo; <strong>intrins\u00e8que<\/strong> au &laquo; <strong>d\u00e9cha&icirc;nement de la mati\u00e8re &raquo;<\/strong> analys\u00e9es sur ce site (<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">ici<\/a> ou <a href=\"http:\/\/www.dedefensa.org\/article\/sur-lautodestruction-de-notre-contre-civilisation-devenue-systeme\">l\u00e0<\/a>).<\/p>\n<\/p>\n<p><p>C&rsquo;est parce que De Gaulle avait r\u00e9fl\u00e9chis (analys\u00e9, per\u00e7u, observ\u00e9 ou m\u00e9dit\u00e9) non sur l&rsquo;image mais sur la <em>r\u00e9alit\u00e9<\/em> de la puissance des Etats-Unis (industrielle, productiviste), et sur le sens r\u00e9el de la puissance &ndash; ou plus exactement du pouvoir (pouvoir <em>agir<\/em> &ndash; souverainement, correctement, selon des principes), qu&rsquo;il a pu en 1965 et avec la m\u00eame force de conviction qu&rsquo;il a montr\u00e9 en 1940, quitter l&rsquo;OTAN et se distancier compl\u00e8tement de la &laquo; puissance &raquo; \u00e9tatsunienne (pour ne pas dire la percevoir comme un danger, car cela serait peut-\u00eatre anachronique. Mais ceci nous ram\u00e8ne par contre \u00e0 aujourd&rsquo;hui et aux analyses russes sur le &laquo; technologisme &raquo; et le caract\u00e8re &laquo; herm\u00e9tique &raquo; (irr\u00e9formable et suicidaire) du Syst\u00e8me).<\/p>\n<\/p>\n<p><h4>Christian Steiner<\/h4>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Note<\/h2>\n<\/p>\n<p><p>(1) et dont l&rsquo;enjeu est, si j&rsquo;ai bien compris, comment nous raconterons l&rsquo;histoire \u00e0 nos petits-enfants apr\u00e8s la disparition du Syst\u00e8me &ndash; l&rsquo;histoire de ce qui nous est arriv\u00e9 pour avoir permis au Syst\u00e8me de s&rsquo;installer, sur quelles illusions et r\u00e9alit\u00e9s il a fonctionn\u00e9, comment notre psychologie a eu tant de peine \u00e0 lui r\u00e9sister, comment le Syst\u00e8me n&rsquo;est pas viable et, <em>a contrario<\/em>, ce qui est viable, ce qui fait monde&hellip; <\/p>\n<\/p>\n<p><p>(2) r\u00e9gion arctique devenu par la suite l&rsquo;un des endroit les plus nucl\u00e9aris\u00e9s de la plan\u00e8te pendant la Guerre froide et aujourd&rsquo;hui encore, puis l&rsquo;un des endroits souffrant le plus de la pollution chimique mondiale qui s&rsquo;y accumule en bout de cha&icirc;ne trophique, et l&rsquo;un des endroits qui souffre le plus du r\u00e9chauffement global. Notre contre-civilisation ne peut s&#8217;emp\u00eacher de d\u00e9truire les derniers espaces sauvages, les espaces les plus beaux et subtils, les plus importants \u00e0 l&rsquo;\u00e9quilibre d\u00e9licat de la plan\u00e8te et de la vie. <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le serpent et son image Lisant dans votre Journal du 20 d\u00e9cembre (&laquo; De la fascination de la surpuissance &raquo;) ces paroles que de Gaulle prononcent en ao&ucirc;t 1940 : \u00ab\u00a0Le sort de la guerre est jou\u00e9. L&rsquo;Am\u00e9rique ne va pas tarder \u00e0 entrer en guerre avec toute sa puissance industrielle, l&rsquo;Allemagne a perdu. Il&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2631,2604,3532,2685,2645,3535,3084,3851,3534,8388,2804],"class_list":["post-76308","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-de","tag-des","tag-deuxieme","tag-gaulle","tag-guerre","tag-industrielle","tag-mobilisation","tag-mondiale","tag-production","tag-productivite","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76308"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76308\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}