{"id":76313,"date":"2015-12-22T07:31:29","date_gmt":"2015-12-22T07:31:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/12\/22\/kurt-ve-ceren\/"},"modified":"2015-12-22T07:31:29","modified_gmt":"2015-12-22T07:31:29","slug":"kurt-ve-ceren","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/12\/22\/kurt-ve-ceren\/","title":{"rendered":"<em>Kurt Ve Ceren<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><em>Kurt Ve Ceren<\/em><\/h2>\n<\/p>\n<p><p>Les probl\u00e8mes auquel le monde actuel est confront\u00e9 sont devenus si complexes et paradoxaux que personne ne propose plus d&rsquo;explications encore moins de solutions. Restent les questions.<\/p>\n<\/p>\n<p><p>Pourquoi le Turc Erdogan a-t-il cet \u00e9t\u00e9 d\u00e9cid\u00e9 de faire passer en Europe des Syriens r\u00e9fugi\u00e9s sur son territoire ainsi que d&rsquo;autres d\u00e9plac\u00e9s aid\u00e9s et guid\u00e9s par la police turque? Pourquoi la supercherie \u00e9vent\u00e9e, Merkel lui a quand m\u00eame donn\u00e9 trois milliards pour les garder chez lui? Merkel est-elle s&ucirc;re que ces milliards iront aux r\u00e9fugi\u00e9s et pas dans la poche du sultan? Pourquoi Poutine, apr\u00e8s avoir dit \u00e0 l&rsquo;Onu aux Etatsuniens &laquo; Avez-vous conscience de ce que vous avez fait &raquo;, pour le chaos qu&rsquo;ils ont caus\u00e9 ces derni\u00e8res ann\u00e9es partout o&ugrave; ils sont mis leurs boots on the ground, a-t-il donn\u00e9 les plans de vol de ses avions \u00e0 ces m\u00eame Etatsuniens? Plans de vol qui ont permis \u00e0 l&rsquo;Erdogan plus ami de l&rsquo;Occident que des Russes, de leur abattre un bombardier les doigts dans le nez? Avant l&rsquo;affaire du Su24 Poutine ignorait-il que le p\u00e9trole vol\u00e9 en Syrie et en Irak transitait par la Turquie et \u00e9tait vendu par elle? Pourquoi a-t-il mis si longtemps \u00e0 attaquer les longues files de camions d&rsquo;Isis qui serpentent dans le d\u00e9sert, cibles non arm\u00e9es, facile \u00e0 d\u00e9truire? A-t-il voulu m\u00e9nager Erdogan \u00e0 qui, quelque mois auparavant, il avait propos\u00e9 son ol\u00e9oduc? On a parl\u00e9 \u00e0 ce moment d&rsquo;un coup de maitre poutinien. Pendant ce temps, le Turc constituait des milices Tatares pour aller emb\u00eater Poutine en Crim\u00e9e. Ignore-t-il que les voyous ne sont pas partisans de la morale kantienne? Que toute faiblesse \u00e0 leur \u00e9gard leur est un encouragement \u00e0 pers\u00e9v\u00e9rer? Pourquoi raconte-t-il dans ses conf\u00e9rences de presse qu&rsquo;\u00e0 Leningrad il a appris que &laquo; dans les combats de rue (des combats de voyous donc) c&rsquo;est celui qui frappe le premier qui gagne &raquo;? Pourquoi lorsqu&rsquo;il s&rsquo;adresse aux Yankees, dit-il &laquo; nos partenaires &raquo;? Est-ce de la diplomatie? Est-ce pour ne pas f\u00e2cher l&rsquo;oncle Sam, vouloir \u00e0 tout prix \u00eatre reconnu par lui parce que Poutine aime l&rsquo;Occident comme Pierre le Grand l&rsquo;a aim\u00e9 ? Qu&rsquo;il le pr\u00e9f\u00e8re \u00e0 l&rsquo;Orient, surtout le chinois avec lequel il n&rsquo;a fait des contrats l\u00e9onins que forc\u00e9 par la b\u00eatise occidentale? Est-il na\u00eff vis-\u00e0-vis des Occidentaux am\u00e9ricanis\u00e9s qui jouent la politique du pire m\u00eame si cette derni\u00e8re n&rsquo;est pas gagnante partout, loin de l\u00e0, comme en Ukraine? Est-il absurde de se demander sur quelle autre fronti\u00e8re se fera la prochaine provocation, ourdie peut-\u00eatre par des Polonais-slaves-catholiques-anti-Russes-pathologiques et pro-Yankees, \u00e0 laquelle Poutine devra cette fois r\u00e9pondre sauf \u00e0 \u00eatre pris pour un voyou faible! A Kaliningrad ?<\/p>\n<\/p>\n<p><p>Pourquoi la Chine est-elle devenue capitaliste dans son syst\u00e8me \u00e9conomique en restant communiste, c&rsquo;est-\u00e0-dire autoritaire, dans son syst\u00e8me politique, avec le succ\u00e8s que l&rsquo;on sait? (L&rsquo;Urss aurait-elle d&ucirc; faire de m\u00eame pour \u00e9viter l&rsquo;implosion?). Choix qui la met aujourd&rsquo;hui objectivement du c\u00f4t\u00e9 de l&rsquo;Empire alors qu&rsquo;elle est membre des Brics qui contestent l&rsquo;Empire? Lesquels Brics ont pour leader politique la Russie \u00e0 cause de son armement nucl\u00e9aire et de son ancienne aura, et pour leader \u00e9conomique la Chine qui trouve injuste qu&rsquo;une Sib\u00e9rie russe soit si d\u00e9sesp\u00e9r\u00e9ment vide d&rsquo;hommes alors que la Chine en a trop? L&rsquo;Europe Lisbonne-Vladivostok \u00e9tait-ce une utopie? Qui en Occident n&rsquo;en a pas eu le courage?<\/p>\n<\/p>\n<p><p>Pourquoi \u00e0 contrario, la Russie, \u00e0 la chute de l&rsquo;Urss est-elle devenue capitaliste en \u00e9conomie et lib\u00e9rale en politique? Cela fut-il une erreur? Une erreur in\u00e9vitable ou \u00e9vitable? Une erreur voulue par l&rsquo;Occident qui lui envoya ses Chicago Boys pour privatiser, et par certains ex-Communists-Boys qui ont profit\u00e9 du marasme pour piller leur propre patrie. Si bien qu&rsquo;on se demande maintenant avec les troubles \u00e9conomiques qui r\u00e9sultent des sanctions europ\u00e9ennes, qui fait la politique de la Russie ? Est-ce Poutine seul ou avec les oligarques? Idem pour la banque de Russie: Un patriote ou un &laquo; occidental &raquo;. En quoi les liens financiers et \u00e9conomiques \u00e9troits de la Russie avec l&rsquo;occident paralysent-ils sa politique? Et la condamnent-ils \u00e0 terme?<\/p>\n<\/p>\n<p><p>Ces deux fa\u00e7ons d&rsquo;\u00e9voluer des deux pays qui avaient adopt\u00e9 le marxisme en \u00e9conomie et les principes de la r\u00e9volution fran\u00e7aise en politique, est-ce qu&rsquo;on en a compris le sens profond? De m\u00eame, est-on en train de comprendre le sens profond de la crise mortelle que traverse notre Occident et qui, peut-\u00eatre, est plus mortelle encore que la crise qui affecte les deux ex- champions d&rsquo;un marxisme occidental. Qui croit encore que le renouveau viendra de l&rsquo;Ouest ?<\/p>\n<\/p>\n<p><p>Une illustration de ces probl\u00e8mes presque par l&rsquo;absurde est la position d&rsquo;Emmanuel Todd notre anthropologue-historien-d\u00e9mographe. Il a approuv\u00e9 le mariage homosexuel au titre de sa vision lib\u00e9rale du monde et sans doute aussi de sa vision &laquo; lib\u00e9r\u00e9e &raquo; de la probl\u00e9matique sexuelle. Qu&rsquo;&laquo; un homme + une femme &raquo; lui paraisse d\u00e9pass\u00e9 ou d\u00e9passable est int\u00e9ressant. Dans le cadre d&rsquo;une conf\u00e9rence \u00e0 b\u00e2tons rompus tenue r\u00e9cemment, il l&rsquo;attribue au fait qu&rsquo;il a eu une grand-m\u00e8re lesbienne et que donc, mon Dieu, il ne faut pas faire un plat de ces histoires! Mais, dans la minute qui suit, il s&rsquo;\u00e9tonne que cette nouveaut\u00e9, cet &laquo; int\u00e9r\u00eat &raquo;, cette &laquo; compassion &raquo; un peu excessive il faut bien le dire pour l&rsquo;homosexualit\u00e9, soit devenue une sorte de marqueur de l&rsquo;occident, une d\u00e9finition de l&rsquo;intelligence d\u00e9mocratique, tandis qu&rsquo;en Russie, cette Russie qu&rsquo;il d\u00e9fend souvent avec talent, une loi a \u00e9t\u00e9 vot\u00e9e interdisant non pas certes  l&rsquo;homosexualit\u00e9, mais &laquo; la propagande homosexuelle &raquo;! La cerise sur le g\u00e2teau \u00e9tant alors qu&rsquo;il avoue ensuite qu&rsquo;il ne comprend pas, -lui l&rsquo;anthropologue confirm\u00e9 qui a \u00e9tudi\u00e9 les familles de presque toute la terre- que les pays occidentaux attachent tant d&rsquo;importance \u00e0 l&rsquo;homosexualit\u00e9, en fasse un cheval de bataille? Faut-il lui sugg\u00e9rer modestement une autre approche du probl\u00e8me? Une qui serait M\u00e9tahistorique? Eschatologique? M\u00e9taphysique? Pourquoi d\u00e9fend-il la Russie et avoue-t-il ing\u00e9nument que si la crise devait s&rsquo;aggraver il chercherait refuge aux Usa, pays en pleine d\u00e9liquescence d&rsquo;apr\u00e8s ses propres analyses? Est-ce parce qu&rsquo;il est Juif de culture anglo-saxonne? Mais les Juifs sont appr\u00e9ci\u00e9s aussi en Russie et en Isra\u00ebl. D&rsquo;ailleurs les Juifs russes d&rsquo;Isra\u00ebl ne sont-ils pas le garant que Poutine respectera toujours les int\u00e9r\u00eats de l&rsquo;\u00e9tat juif, voire le prot\u00e8gera mieux peut-\u00eatre que ne le feront les Usa dont la politique imp\u00e9riale s&rsquo;effiloche? Autrement dit, quand l&rsquo;Empire menace la Russie sur ses marches, il d\u00e9fend la Russie contre les pr\u00e9tentions de l&rsquo;Empire et l\u00e0, sachant que le m\u00eame Empire est \u00e0 l&rsquo;origine du chaos proche oriental au moins depuis 1991, il ne manque pas de faire la fine bouche au sujet d&rsquo;Assad, &laquo; boucher &raquo; de son peuple selon les pieds nickel\u00e9s Hollande-Fabius-Valls, en oubliant qu&rsquo;en son temps Bachar fut le soutien de Bush p\u00e8re contre l&rsquo;Irak et qu&rsquo;il accepta sur son territoire les prisons de la Cia o&ugrave; on torturait \u00e0 c&oelig;ur joie les r\u00e9calcitrants anti US! Et \u00e0 cela ne faudrait-il pas lui rappeler qu&rsquo;une juda\u00eft\u00e9 bien comprise devrait se nourrir \u00e0 une source plus profonde, que des rabbins fran\u00e7ais (Rav Dynovisz), sur You Tube, ne se privent pas d&rsquo;expliquer, Thora et Talmud \u00e0 la main, que le cr\u00e9ateur d&rsquo;Isis ce sont les Usa, que les morts du 13.11 sont les victimes innocentes mais expiatoires de cette politique mortif\u00e8re combinant la d\u00e9liquescence venue de Californie avec &quot;Eagles of death metal&quot; (sans doute vaguement homosexuelle), \u00e0 l&rsquo;extr\u00e9misme musulman et que donc, l&rsquo;Armageddon y retrouve ses petits Satans, ses petits Lucifers et ses petits Sorads? Et ce d&rsquo;autant plus, que l&rsquo;eschatologie coranique dit en gros la m\u00eame chose que la juive en nous annon\u00e7ant en plus, le retour du Mahdi et de J\u00e9sus r\u00e9incarn\u00e9 pour bient\u00f4t \u00e0&hellip; Damas !<\/p>\n<\/p>\n<p><p>Enfin, tentons un post-scriptum m\u00e9tahistorique pour \u00e9clairer davantage la question des Turcs. Partis aux \u00e2ges obscurs de leur lointaine Sib\u00e9rie, apr\u00e8s avoir fait halte en Mongolie, en Perse et enfin en Anatolie, les Ottomans ont voulu de l&rsquo;Europe. En 1683, \u00e0 Vienne, arr\u00eat\u00e9s par les Autrichiens et les Polonais, ils ne nous ont laiss\u00e9 que les croissants. Quelques trois si\u00e8cles plus tard sont-ils en train de reprendre le Drang nach Westen par Syriens interpos\u00e9s, sorte de &laquo; janissaires musulmans &raquo; envoy\u00e9s sur place pour pr\u00e9parer le terrain qui ne sera vraiment occupable que vers 2050 ? Qui conna&icirc;t <strong><em>Kurt ve Ceren<\/em><\/strong>?&#8230; &laquo; la Biche et le Loup &raquo; en turc. Ca rappelle le Loup et l&rsquo;Agneau de La Fontaine mais ce n&rsquo;est pas une fable, c&rsquo;est l&rsquo;origine mythologique des Turcs qui se disent n\u00e9s de l&rsquo;accouplement d&rsquo;un loup et d&rsquo;une biche. Vers 450, les chroniqueurs Fran\u00e7ais racontent qu&rsquo;Attila, lors de son grand raid d\u00e9vastateur en Occident, avait un loup sur sa banni\u00e8re. Depuis ces temps lointains plus aucune trace du fauve&#8230; \u00e0 moins que la Biche-Erdogan en ait laiss\u00e9 repousser les dents, qu&rsquo;il ait commenc\u00e9 \u00e0 planter son poignard dentaire dans le dos de ses amis. Des descendants de Turcs qui parlent un proto-turc, il y en a sur tout le territoire de la Russie, de Yakutsk \u00e0 Kara Deniz. Poutine l&rsquo;a-t-il \u00e0 l&rsquo;esprit? &laquo; Soit je ressuscite les anciens Turcs, soit je me paye l&rsquo;Europe! &raquo;, r\u00eave le sultan fou Erdogan. Quand on vous dit qu&rsquo;il n&rsquo;y a rien \u00e0 comprendre sauf&hellip; le petit &laquo; croissant &raquo; sur le [<strong>g<\/strong>]. (*)<\/p>\n<\/p>\n<p><h4>Marc G\u00e9belin<\/h4>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Note<\/h2>\n<\/p>\n<p><p>En turc comme en d&rsquo;autres langues les m\u00eames lettres se prononcent diff\u00e9remment si on leur accole un accent dessus ou dessous. C&rsquo;est le cas du [g] qui peut porter au dessus de lui un petit croissant et qui alors ne se prononce pas [g]. C&rsquo;est ce qu&rsquo;on appelle le <strong>yumusak ge<\/strong> (le [s] de yumusak s&rsquo;\u00e9crivant avec une c\u00e9dille dessous comme notre [\u00e7]). Cette lettre indique simplement un allongement de la voyelle pr\u00e9c\u00e9dente et surtout pas le son [g] du fran\u00e7ais. Si bien qu&rsquo;Erdogan est en fait un Erdo:an. Mais pour qui a de la m\u00e9moire, le croissant turc est un symbole guerrier qui du haut des remparts de Vienne en 1683 \u00e9tait bien visible aux Autrichiens. Les p\u00e2tissiers en ont fait le croissant du petit d\u00e9jeuner. J&rsquo;ajoute que les &laquo; Loups gris &raquo; aiment aussi ce joli symbole.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kurt Ve Ceren Les probl\u00e8mes auquel le monde actuel est confront\u00e9 sont devenus si complexes et paradoxaux que personne ne propose plus d&rsquo;explications encore moins de solutions. Restent les questions. Pourquoi le Turc Erdogan a-t-il cet \u00e9t\u00e9 d\u00e9cid\u00e9 de faire passer en Europe des Syriens r\u00e9fugi\u00e9s sur son territoire ainsi que d&rsquo;autres d\u00e9plac\u00e9s aid\u00e9s et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3737,11880,916,12823,2613],"class_list":["post-76313","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-erdogan","tag-gebelin","tag-poutine","tag-questions","tag-turquie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76313"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76313\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}