{"id":76321,"date":"2015-12-26T11:47:27","date_gmt":"2015-12-26T11:47:27","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2015\/12\/26\/operation-reussie-lenergie-schiste-us-en-crise-grave\/"},"modified":"2015-12-26T11:47:27","modified_gmt":"2015-12-26T11:47:27","slug":"operation-reussie-lenergie-schiste-us-en-crise-grave","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2015\/12\/26\/operation-reussie-lenergie-schiste-us-en-crise-grave\/","title":{"rendered":"Op\u00e9ration r\u00e9ussie\u00a0: l&rsquo;\u00e9nergie-schiste US en crise grave"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Op\u00e9ration r\u00e9ussie : l&rsquo;\u00e9nergie-schiste US en crise grave<\/h2>\n<\/p>\n<p><p>Depuis un an, le prix du p\u00e9trole est une des plus importantes variables de la situation \u00e9conomique, avec un effondrement consid\u00e9rable, et des effets multiples dont l&rsquo;effet g\u00e9n\u00e9ral est bien entendu un accroissement de l&rsquo;instabilit\u00e9 du Syst\u00e8me aux niveaux financier, commercial et \u00e9conomique, et strat\u00e9gique en g\u00e9n\u00e9ral. On sait que ce processus pour l&rsquo;actuelle s\u00e9quence a commenc\u00e9 en d\u00e9cembre 2014, selon une d\u00e9cision politique prise en coordination et en tr\u00e8s grand secret imm\u00e9diatement \u00e9vent\u00e9 par les autorit\u00e9s am\u00e9ricanistes et saoudiennes. Le but \u00e9tait l&rsquo;effondrement de la Russie. Un texte de <em>Sputnik<\/em>-fran\u00e7ais, reprenant des informations d&rsquo;abord venues de la <em>Federal Reserve<\/em> de l&rsquo;&Eacute;tat du Texas, puis de commentaires divers, nous annonce que la premi\u00e8re victime (dans l&rsquo;ordre chronologique) est la grande campagne d&rsquo;exploitation de gaz et de p\u00e9trole de schiste aux USA, qui impliquait une ambition \u00e9conomique et strat\u00e9gique consid\u00e9rable (certains ont salu\u00e9 ou feint de craindre une r\u00e9surgence de la toute-puissance de l'\u00a0\u00bbhyperpuissance\u00a0\u00bb-que-vous-savez  \u00e0 cette occasion). Cet effondrement industriel aux USA n&rsquo;est pas une surprise puisque une tr\u00e8s grande majorit\u00e9 de commentateurs avait soulign\u00e9 ce risque d\u00e8s l&rsquo;offensive de d\u00e9cembre 2014, mais sa concr\u00e9tisation est d\u00e9sormais assez impressionnante pour constituer un fait strat\u00e9gique majeur qui doit pourtant \u00eatre dfini en d&rsquo;autres termes que strat\u00e9giques.<\/p>\n<\/p>\n<p><p>On reprend ici <a href=\"http:\/\/fr.sputniknews.com\/economie\/20151225\/1020564102\/faillites-usa-schiste-hydrocarbures.html#ixzz3vMlhEobN\">le texte de <em>Sputnik<\/em>-fran\u00e7ais<\/a> sur ce cas, du 25 d\u00e9cembre. (On peut aussi consulter <a href=\"http:\/\/www.zerohedge.com\/news\/2015-12-25\/oil-bankruptcies-hit-highest-level-crisis-and-theres-more-come-fed-warns\">le texte de <em>ZeroHedge.com<\/em><\/a> du 25 d\u00e9cembre \u00e9galement, beaucoup plus d\u00e9taill\u00e9 et techniquement tr\u00e8s d\u00e9velopp\u00e9.)<\/p>\n<\/p>\n<p><p>&laquo; <em>Les faillites parmi les soci\u00e9t\u00e9s p\u00e9troli\u00e8res et gazi\u00e8res am\u00e9ricaines ont atteint un niveau record depuis la grande d\u00e9pression des ann\u00e9es 30, rapporte la R\u00e9serve f\u00e9d\u00e9rale de Dallas. Au moins neuf soci\u00e9t\u00e9s am\u00e9ricaines du secteur p\u00e9trolier et gazier, dont la dette commune d\u00e9passe deux milliards de dollars, ont engag\u00e9 la proc\u00e9dure de faillite au quatri\u00e8me trimestre de l&rsquo;ann\u00e9e en cours, rapporte la banque<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Les mouvements les plus spectaculaires se produisent actuellement sur les cours du p\u00e9trole. Les prix du baril en Europe et aux Etats-Unis chutent \u00e0 une vitesse vertigineuse pour flirter avec leur plus bas niveau depuis 2008 et 2004 respectivement. Les cours du gaz naturel am\u00e9ricains sont d\u00e9j\u00e0 au plancher depuis treize ans, signalent les analystes qui parlent de plus en plus souvent d&rsquo;un retour des ann\u00e9es 30<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Une baisse prolong\u00e9e du prix du baril de p\u00e9trole pourrait compromettre les financements de recherche de p\u00e9trole de schiste aux Etats-Unis d\u00e8s 2016. En effet, cette baisse des cours du brut met \u00e0 rude \u00e9preuve les entreprises du secteur, qui ne sont plus rentables avec de tels prix. Le taux de d\u00e9faut dans le secteur pourrait d\u00e9passer les 10 % l&rsquo;an prochain outre-Atlantique selon Fitch, un record historique. Si on a un prix \u00e0 50 dollars, il y aura toute une partie des p\u00e9troles de schiste qui ne sera plus rentable, et on sait qu&rsquo;avec moins de b\u00e9n\u00e9fices, on a moins d&rsquo;investissements<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Les experts se demandent en effet s&rsquo;il ne s&rsquo;agit pas de la fin du fameux boom des hydrocarbures de schiste. C&rsquo;est en tout cas ce que pr\u00e9dit l&rsquo;un des ma&icirc;tres de l&rsquo;\u00e9nergie de Wall Street, Andrew John Hall qui a notamment pr\u00e9dit une fin rapide du boom des hydrocarbures de schiste et donc un retour du p\u00e9trole conventionnel. Selon ce dernier, les sp\u00e9cialistes auraient fait des erreurs sur les sp\u00e9cificit\u00e9s des hydrocarbures de schiste, notamment sur leur dur\u00e9e de vie et le fonctionnement des march\u00e9s du gaz et du p\u00e9trole. Il explique notamment qu&rsquo;il y a, d&rsquo;un c\u00f4t\u00e9, les Etats-Unis qui produisent \u00e0 pleine capacit\u00e9 des hydrocarbures de schiste ayant une dur\u00e9e de vie de cinq ans et de l&rsquo;autre, les pays de l&rsquo;Organisation des pays exportateurs de p\u00e9trole (OPEP) qui d\u00e9tiennent la majorit\u00e9 des gisements qualifi\u00e9s de super-g\u00e9ants (r\u00e9serves sup\u00e9rieures \u00e0 700 milliards de tonnes) et qui produisent par quotas et donc \u00e9puisent moins vite leurs r\u00e9serves. Dans ces conditions, suppose Andrew John Hall, on ne peut qu&rsquo;avoir un retour du p\u00e9trole conventionnel dans les prochaines ann\u00e9es<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Cette situation US \u00e9tait donc pr\u00e9visible et pr\u00e9vue, mais elle n&rsquo;a pas particuli\u00e8rement inqui\u00e9t\u00e9 la direction washingtonienne ni les milieux financiers, habitu\u00e9s \u00e0 fonctionner selon une perspective des trois mois suivants et d\u00e9sormais enferm\u00e9s dans diverses <a href=\"http:\/\/www.dedefensa.org\/article\/la-globalisation-qui-fait-pschitt\">\u00ab\u00a0bulles\u00a0\u00bb de communication<\/a> compl\u00e8tement herm\u00e9tiques (\u00ab\u00a0infranchissables\u00a0\u00bb). Diverses nouvelles ont \u00e9t\u00e9 diffus\u00e9es depuis un an sur la situation en aggravation du domaine p\u00e9trole\/gaz de schiste, concernant diverses zones et divers projets (voir par exemple <a href=\"http:\/\/fr.sputniknews.com\/analyse\/20150203\/1014303857.html\">le cas polonais<\/a> d\u00e8s f\u00e9vrier 2014).<\/p>\n<\/p>\n<p><p>Comme on l&rsquo;a d\u00e9j\u00e0 mentionn\u00e9, cette s\u00e9quence est d&rsquo;origine politique et du d\u00e9but d\u00e9cembre 2014, avec une connivence entre les USA et l&rsquo;Arabie, dans le but, voulu par Washington, de mettre \u00ab\u00a0la Russie en genoux\u00a0\u00bb. L&rsquo;Arabie, qui vit au rythme de conceptions totalement d\u00e9structur\u00e9es et aventureuses par rapport \u00e0 sa politique traditionnelle de prudence, a suivi, y voyant un moyen de priver Assad et la Syrie de son principal alli\u00e9, &ndash; ce qui faisait pr\u00e9voir \u00e0 ce moment (d\u00e9cembre 2014), par les analystes-Syst\u00e8me du domaine fonctionnant par commentaires \u00ab\u00a0copi\u00e9-coll\u00e9\u00a0\u00bb repris r\u00e9guli\u00e8rement de leurs textes depuis 2011, que Assad \u00ab\u00a0n&rsquo;en avait plus que pour quelques semaines\u00a0\u00bb. En attendant, un an plus tard, la m\u00eame grande man&oelig;uvre strat\u00e9gique d\u00e9cha&icirc;nant l&rsquo;effondrement du prix du p\u00e9trole, est en train de peaufiner la deuxi\u00e8me victime (toujours ordre chronologique) apr\u00e8s le cas de l&rsquo;\u00e9nergie-schiste US, savoir l&rsquo;Arabie elle-m\u00eame. (Et toujours le m\u00eame pr\u00e9sident en Syrie&#8230;) Un article tr\u00e8s int\u00e9ressant de Daniel Lazare sur <em><a href=\"https:\/\/consortiumnews.com\/2015\/12\/22\/the-coming-saudi-crack-up\/\">ConsortiumNews du 22 d\u00e9cembre<\/a><\/em>, nous d\u00e9crit la chose.<\/p>\n<\/p>\n<p><p>&laquo; &#8230;<em>Topping the kingdom&rsquo;s list of woes is the economy. With its stubbornly high unemployment rate and growing wealth gap between the rich and poor, Saudi Arabia has long been the sick man of the Persian Gulf. Even though planners have been talking about economic diversification since the 1970s, the kingdom was actually <a href=\"http:\/\/www.sciencedirect.com\/science\/article\/pii\/S0301420715000215\">more dependent<\/a> on oil as of 2013 than 40 years earlier. \u00ab\u00a0Saudization\u00a0\u00bb of the workforce is another mantra, yet the labor market remains polarized between a private sector dominated by foreign guest workers, mainly from South Asia, and a public sector filled with Saudi \u00ab\u00a0<a href=\"http:\/\/www.wsj.com\/articles\/gulf-countries-target-sofa-men-to-trim-spending-1447196088\">sofa men<\/a>\u00a0\u00bb who spend their days lounging about in government offices. Riyadh wishes that young people would take jobs in hotels, oil refineries and the like, but most prefer to wait for a high-paid government sinecure to open up &ndash; which is one reason why <a href=\"https:\/\/www.quandl.com\/collections\/saudi-arabia\/saudi-arabia-unemployment\">the jobless rate among young people<\/a> is as high as 29 percent<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Given this combination of oil dependence and joblessness, a two-thirds drop in the price of crude since mid-2014 couldn&rsquo;t be more painful. But what makes it even more frightening is the growing realization that, with softening demand due to the global slowdown and growing over-supply due to the fracking revolution, low prices will be a fact of life for years to come. This prospect does not bode well for a country dependent on oil for 91 percent of its foreign revenue, one that is currently burning through its foreign reserves at <a href=\"http:\/\/www.post-gazette.com\/opinion\/Op-Ed\/2015\/11\/22\/The-Saudis-are-stumbling-and-might-take-the-Middle-East-down-with-them\/stories\/201511220134\">the rate of $10 billion a month<\/a>.<\/em>.. &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>Bien entendu, la d\u00e9cision US-Arabie de d\u00e9cembre 2014 n&rsquo;est pas la seule responsable de cette situation g\u00e9n\u00e9rale (effondrement du prix du p\u00e9trole), mais elle en est le d\u00e9tonateur, la clef strat\u00e9gique, l&rsquo;incitateur psychologique d\u00e9clenchant la cascade diluvienne de l&rsquo;effondrement. (Des op\u00e9rations annexes vont dans le m\u00eame sens de l&rsquo;effondrement-d\u00e9sordre du march\u00e9 de l&rsquo;\u00e9nergie, \u00e9galement favoris\u00e9es selon son antipolitique r\u00e9pondant aux normes de la d\u00e9mence par le bloc-BAO, et toujours le couple US-Arabie, avec le pouvoir washingtonien \u00e9puis\u00e9 d&rsquo;impuissance et de paralysie, et compl\u00e8tement d\u00e9structur\u00e9 jusqu&rsquo;\u00e0 la folie. On pense ici \u00e0 l&rsquo;activit\u00e9 d&rsquo;exploitation du p\u00e9trole de <em>Daesh<\/em>, n\u00e9buleuse terroriste-affairiste parfaitement en ligne avec le capitalisme autodestructeur.) Quoi qu&rsquo;il en soit, le r\u00e9sultat est l\u00e0 : la crise du prix du p\u00e9trole s&rsquo;effectue avec toute la puissance possible, sans aucun frein ni aucune borne gr\u00e2ce \u00e0 cette impulsion politique de d\u00e9part.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Bien entendu (suite), la Russie est n\u00e9cessairement \u00e9galement touch\u00e9e, comme tous les producteurs d&rsquo;\u00e9nergie le sont. Ce cas met en \u00e9vidence ce qui constitue l&rsquo;une des faiblesses politiques, non pas du pays lui-m\u00eame, mais de la position de Poutine qui reste d\u00e9pendante des r\u00e8gles \u00e9conomiques et financi\u00e8res du Syst\u00e8me avec lequel il n&rsquo;a certainement pas compl\u00e8tement rompu. Cet aspect de la question m\u00e9rite une \u00e9tude \u00e0 part dans la situation o&ugrave; elle se trouve, parce que d&rsquo;importants facteurs sp\u00e9cifiques \u00e0 la Russie interviennent. Mais on comprend bien entendu que cet affaiblissement russe n&rsquo;a absolument rien \u00e0 voir avec le r\u00e9sultat qu&rsquo;attendaient les USA et l&rsquo;Arabie \u00e0 l&rsquo;origine de leur grande man&oelig;uvre g\u00e9o-\u00e9nerg\u00e9tique puisqu&rsquo;il ne s&rsquo;agissait ni plus ni moins que la liquidation de la Russie en tant qu&rsquo;&Eacute;tat ind\u00e9pendant et souverain, et cela en l&rsquo;espace de quelques semaines, et sans rire&#8230;<\/p>\n<\/p>\n<p><p>Le r\u00e9sultat de la man&oelig;uvre USA-Arabie n&rsquo;est pas g\u00e9opolitique, ou bien \u00e9conomico-financier, ou bien \u00e9nerg\u00e9tique, m\u00eame s&rsquo;il y a de tout cela bien entendu dans les effets ; non plus qu&rsquo;il ne donne le moindre avantage \u00e0 quiconque sinon en provoquant une aggravation g\u00e9n\u00e9rale de la situation, in\u00e9galement r\u00e9partie entre les trois acteurs. <strong>Le r\u00e9sultat est eschatologique en introduisant un facteur de d\u00e9sordre universel de plus<\/strong>, un composant de plus dans la course extraordinaire au d\u00e9s\u00e9quilibre d\u00e9structurant et dissolvant de la situation g\u00e9n\u00e9rale, et du Syst\u00e8me lui-m\u00eame par cons\u00e9quent. Il est eschatologique dans le sens o&ugrave; il renforce le caract\u00e8re absolument insaisissable et incontr\u00f4lable par les forces humaines de la situation, et en rendant la Crise G\u00e9n\u00e9rale encore plus ind\u00e9pendante si c&rsquo;est possible de l&rsquo;action humaine.<\/p>\n<\/p>\n<p><p>Mis en ligne le 26 d\u00e9cembre 2015 \u00e0 11H42<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Op\u00e9ration r\u00e9ussie : l&rsquo;\u00e9nergie-schiste US en crise grave Depuis un an, le prix du p\u00e9trole est une des plus importantes variables de la situation \u00e9conomique, avec un effondrement consid\u00e9rable, et des effets multiples dont l&rsquo;effet g\u00e9n\u00e9ral est bien entendu un accroissement de l&rsquo;instabilit\u00e9 du Syst\u00e8me aux niveaux financier, commercial et \u00e9conomique, et strat\u00e9gique en g\u00e9n\u00e9ral.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3259,3498,3228,2631,2686,2651,2803,4396,7559,4967,2622,3600,3477,2730,3558,15828,2804],"class_list":["post-76321","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-arabie","tag-boom","tag-crise","tag-de","tag-destruction","tag-du","tag-effondrement","tag-energetique","tag-eschatologique","tag-gaz","tag-la","tag-petrole","tag-prix","tag-russie","tag-saoudite","tag-schiste","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76321"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76321\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}