{"id":76343,"date":"2016-01-07T00:36:16","date_gmt":"2016-01-07T00:36:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/01\/07\/la-somme-de-toutes-les-peurs-1\/"},"modified":"2016-01-07T00:36:16","modified_gmt":"2016-01-07T00:36:16","slug":"la-somme-de-toutes-les-peurs-1","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/01\/07\/la-somme-de-toutes-les-peurs-1\/","title":{"rendered":"\u201cLa somme de toutes les peurs\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\"> \u00ab\u00a0La somme de toutes les peurs\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>07 janvier 2016 &ndash; La peur est-elle une politique, nous voulons dire une \u00ab\u00a0politique-en-soi\u00a0\u00bb ? C&rsquo;est-\u00e0-dire la suscitation d&rsquo;une \u00e9motion (la peur) pour installer une politique sp\u00e9cifique, con\u00e7ue pr\u00e9cis\u00e9ment pour un terme long ? C&rsquo;est une th\u00e8se largement r\u00e9pandue depuis l&rsquo;attaque du 11 septembre 2001 (9\/11) au point que chaque acte qu&rsquo;on peut placer dans le courant g\u00e9n\u00e9ral de d\u00e9stabilisation lanc\u00e9e depuis cette date est appr\u00e9ci\u00e9e comme un moyen, fabriqu\u00e9 ou pas, de poursuivre le d\u00e9veloppement de cette \u00ab\u00a0politique de la peur\u00a0\u00bb. La m\u00eame th\u00e8se implique que cette \u00ab\u00a0politique de la peur\u00a0\u00bb doit \u00eatre consid\u00e9r\u00e9 implicitement mais allant-de-soi comme une politique \u00ab\u00a0de contr\u00f4le social\u00a0\u00bb ; c&rsquo;est-\u00e0-dire pour ma&icirc;triser des populations, notamment dans les pays du bloc-BAO, pr\u00e9sent\u00e9s comme des d\u00e9mocraties en g\u00e9n\u00e9ral exemplaires. Le dernier exemple en date de cette interpr\u00e9tation est la France, entre les deux s\u00e9ries d&rsquo;attentats de janvier et de novembre 2015 qui ont suscit\u00e9 des changements institutionnels tels que certains estiment que la France se transforme institutionnellement en une sorte de \u00ab\u00a0d\u00e9mocratie totalitaire\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Une des caract\u00e9ristiques de ces th\u00e8ses sur la \u00ab\u00a0politique de la peur\u00a0\u00bb et sur le \u00ab\u00a0contr\u00f4le social\u00a0\u00bb qu&rsquo;elle implique est qu&rsquo;elles sont partag\u00e9es aussi bien par des agents du Syst\u00e8me que par des \u00ab\u00a0dissidents\u00a0\u00bb qui s&rsquo;estiment eux-m\u00eames antiSyst\u00e8me. Dans le cas qui nous occupe aujourd&rsquo;hui, il s&rsquo;agit sans le moindre doute d&rsquo;une personnalit\u00e9 qu&rsquo;on peut appr\u00e9cier comme <strong>faisant partie des \u00e9lites-Syst\u00e8me, mais sans que cela engage n\u00e9cessairement une opinion-Syst\u00e8me conforme sur tous les sujets<\/strong>. Il s&rsquo;agit d&rsquo;un sociologue prestigieux de l&rsquo;universit\u00e9 de l&rsquo;Arizona : le <a href=\"https:\/\/en.wikipedia.org\/wiki\/David_Altheide\">Dr. David Altheide<\/a>, Professeur-R\u00e9gent Em\u00e9rite \u00e0 l&rsquo;\u00e9cole de transformation sociale et de justice sociale, au Coll\u00e8ge des Arts et Sciences lib\u00e9rales de l&rsquo;universit\u00e9 de l&rsquo;Arizona. Le Dr. Altheide est un homme couvert de distinctions et de divers titres, qui a effectu\u00e9 de nombreux s\u00e9jours \u00e0 l&rsquo;\u00e9tranger comme professeur d\u00e9tach\u00e9, auteur de livres fameux de sociologie qui font autorit\u00e9, etc. (Le titre de <em>Regent&rsquo;s Professor<\/em> qu&rsquo;il porte &laquo; <em>is conferred on ASU faculty who have made pioneering contributions in their areas of expertise, who have achieved a sustained level of distinction, and who enjoy national and international recognition for these accomplishments<\/em>. &raquo;)<\/p>\n<\/p>\n<p><p>Le Dr. Altheide a \u00e9t\u00e9 l&rsquo;invit\u00e9 d&rsquo;une \u00e9mission de radio du r\u00e9seau <em>Sputnik<\/em>, dite <em>Brave New World<\/em>, pr\u00e9sent\u00e9 par John Harrison. <a href=\"http:\/\/sputniknews.com\/radio_brave_new_world\/20160101\/1032503862\/happy-new-fear-2016.html#ixzz3w9QHqAE7\">Le 1<sup>er<\/sup> janvier 2016<\/a>, un r\u00e9sume condens\u00e9 des interventions d&rsquo;Altheide a \u00e9t\u00e9 publi\u00e9. Il permet tr\u00e8s largement de comprendre la position du sociologue sur la question de \u00ab\u00a0la politique de la peur\u00a0\u00bb comme moyen de \u00ab\u00a0contr\u00f4le social\u00a0\u00bb, avec un r\u00f4le essentiel accord\u00e9 aux m\u00e9dias. Le th\u00e8me de l&rsquo;\u00e9mission \u00e9tait pr\u00e9sent\u00e9 de cette fa\u00e7on : &laquo; <em>As we celebrate the New Year, one question that we should perhaps ask ourselves is: how are we doing on the fear stakes? Are we more for less afraid? Afraid of war, economic uncertainty, debt, insecurity, immigrants? Or are we overcoming our fears?<\/em> &raquo; L&rsquo;introduction r\u00e9sumait ainsi l&rsquo;enti\u00e8ret\u00e9 du propos : &laquo; <em>Son opinion est que nous \u00e9prouvons beaucoup plus de peurs que dans le pass\u00e9 <\/em>&raquo; (\u00e9tant admis qu&rsquo;en g\u00e9n\u00e9ral la p\u00e9riode consid\u00e9r\u00e9e pour la \u00ab\u00a0p\u00e9riode actuelle\u00a0\u00bb est celle qui commence le 11 septembre 2001).<\/p>\n<\/p>\n<p><p>&laquo; <em>Dr Altheide&rsquo;s point of view is basically that the media in the US, but not only the US, has become commercialised, and through using what is called: &lsquo;media logic&rsquo;, media outlets learn very quickly that fear can be used as a form of entertainment in order to attract and keep audiences. The presentation and development of threats, at both local and international levels, is a useful way to maintain audience reach even though, as Dr Altheide points out, life in the United States, at least for most people, is not full of threats. The media do this to attract a certain &lsquo;quality of audience&rsquo; that can be sold something. Culture soon gets used to this, and soon we find a situation where the communication of threat becomes something one expects. It becomes almost comforting to be constantly told that threats exit, so that we can be afraid. We are entering a dystopian Brave New World where we need our daily fix of fear<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>The size of countries also seems to play an important part. Dr Altheide mentioned that large countries tend to be more all encompassing in their ability to convince citizens of a particular interpretation of fear about a concept, belief or subject that may change over time, for example: capitalism, communism, Islam, migrants, medicare. The object is to convince us that we should be frightened of these, that they present threats, and by and large we are convinced by the messages that we are bombarded with every day<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>The emergence of social media has not, it seems, positively affected the dominance of the mainstream media and dissolved their power to create myths on national and\/or local levels. The reason for this, as Dr Altheide suggests, is that the social media tends to empower individuals and small groups, thus the population is in fact being fragmented, not unified around a particular cause, and thus the power of people who use social media to fight messages created by the mainstream media is weakening<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>The social media is a very visual form of communication and does not need facts. This visualisation, that often becomes trivialisation, is something that is now being adopted by the mainstream media, in fact it has now become common knowledge in the US media that there are no more facts, according to Dr Altheide. Instead we have opinion, scientific evidence is also treated as opinion. Even having a conversation in such a  fear-based world is difficult<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Nous apporterons \u00e0 ces diverses appr\u00e9ciations quelques observations qui marqueront de notre part d&rsquo;\u00e9ventuelles divergences et dans tous les cas notre propre point de vue, avant d&rsquo;aborder le sujet central qui est trait\u00e9 ici, qui concerne \u00ab\u00a0les peurs\u00a0\u00bb (et non \u00ab\u00a0la peur\u00a0\u00bb). D&rsquo;autre part, nous insistons sur le dernier paragraphe, qui m\u00e9ritait en plus de sa place dans l&rsquo;expos\u00e9 un traitement sp\u00e9cifique qui a \u00e9t\u00e9 <a href=\"http:\/\/www.dedefensa.org\/article\/et-avance-masquee-la-verite\">effectu\u00e9 par ailleurs<\/a>, dans le <em>Journal dde.crisis<\/em>. (&laquo; <em>Les m\u00e9dias sociaux constituent une forme visuelle de communication qui ne n\u00e9cessite pas de faits. Cette visualisation, qui devient souvent une trivialisation, est une m\u00e9thode qui a \u00e9t\u00e9 maintenant adopt\u00e9e par<\/em> [les m\u00e9dias-Syst\u00e8me], <em>en fait il y a m\u00eame d\u00e9sormais une attitude g\u00e9n\u00e9rale des m\u00e9dias US selon laquelle les faits n&rsquo;existent plus, selon le Dr. Altheide. A la place, nous avons des opinions, et m\u00eame les preuves scientifiques sont aussi consid\u00e9r\u00e9es comme des opinions. Avoir une conversation dans un monde si compl\u00e8tement install\u00e9 dans la peur est devenue tr\u00e8s difficile. <\/em>&raquo;)<\/p>\n<\/p>\n<blockquote>\n<p><p>&bull; La premi\u00e8re observation est que \u00ab\u00a0la peur\u00a0\u00bb est un sentiment universel et, somme toute, assez fond\u00e9 dans nombre de cas, et qu&rsquo;il joue \u00e9videmment un r\u00f4le central dans la manufacture de la politique, dans l&rsquo;\u00e9volution de l&rsquo;opinion publique, etc. La modernit\u00e9 n&rsquo;a mis aucun frein \u00e0 ce penchant, bien au contraire ; en cherchant \u00e0 s\u00e9culariser et \u00e0 rationaliser des attitudes souvent marqu\u00e9es par l&rsquo;irrationalit\u00e9 et les croyances de ce qu&rsquo;on nommait avec un m\u00e9pris assez lourd et \u00e0 peine dissimul\u00e9 \u00ab\u00a0les peurs ancestrales\u00a0\u00bb, elle a aggrav\u00e9 le probl\u00e8me que pose \u00ab\u00a0la peur\u00a0\u00bb par ses effets souvent excessifs et extr\u00eames ; cette aggravation consista finalement \u00e0 habiller d&rsquo;une apparence de raison ce qui \u00e9tait par cons\u00e9quent un sentiment assez courant et s&rsquo;adressant \u00e0 des entit\u00e9s extrahumaines, avec le r\u00e9sultat <strong>de le rendre beaucoup plus, infiniment plus \u00ab\u00a0politiquement transmissible\u00a0\u00bb<\/strong>. La \u00ab\u00a0Grande Peur de l&rsquo;An Mil\u00a0\u00bb est un sujet encore discut\u00e9 et qui reste fort incertain dans ses effets, tandis que \u00ab\u00a0la Grande Peur de 1789\u00a0\u00bb (terme qualitativement d\u00e9velopp\u00e9 par Guglielmo Ferrero) qui dura jusqu&rsquo;en 1815 constitue un ph\u00e9nom\u00e8ne politique indiscutable. (Cette opinion nous est d&rsquo;autant plus ch\u00e8re que cette p\u00e9riode est pour nous celle du \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00a0\u00bb et de la R\u00e9volution Fran\u00e7aise poursuivie par l&rsquo;Empire napol\u00e9onien.)<\/p>\n<\/p>\n<p><p>&bull; Si la rationalisation des \u00ab\u00a0peurs\u00a0\u00bb est le premier effet de la modernit\u00e9, le second est l&rsquo;universalisation, sinon l&rsquo;objectivation des peurs gr\u00e2ce \u00e0 la globalisation du syst\u00e8me de la communication introduisant effectivement un effet d'\u00a0\u00bbobjectivation\u00a0\u00bb des peurs. Les peurs s\u00e9cularis\u00e9es et rationnalis\u00e9es deviennent \u00ab\u00a0objectives\u00a0\u00bb, c&rsquo;est-\u00e0-dire fond\u00e9es, irr\u00e9futables donc impliquant l&rsquo;irr\u00e9futabilit\u00e9 de la menace. Bien \u00e9videmment, il y a manipulation, nous dirions <strong>presque par n\u00e9cessit\u00e9 ontologique de la communication qui ne peut \u00eatre que manipulation sans n\u00e9cessit\u00e9 d&rsquo;un manipulateur<\/strong>, &ndash; m\u00eame si certains d&rsquo;entre eux prennent le train en marche. (L&rsquo;image, essentiellement, \u00e0 partir des &oelig;uvres de peintres-id\u00e9ologues comme David pendant la R\u00e9volution, puis l&rsquo;image avec la photographie, le cin\u00e9ma et la t\u00e9l\u00e9vision, est le v\u00e9hicule d\u00e9vastateur et maximaliste de cette manipulation. Lorsqu&rsquo;on sait qu&rsquo;un tr\u00e8s grand nombre de citoyens US, voire des pr\u00e9sidents, ont appris l&rsquo;histoire en voyant les films d&rsquo;Hollywood, &ndash; lorsqu&rsquo;on sait que Reagan a \u00ab\u00a0con\u00e7u\u00a0\u00bb la SDIde 1983  [<em>Strategic Defense Initiative<\/em>] apr\u00e8s lecture de BD des science-fiction [Flash Gordon, <em>Captain America<\/em> &#038; Cie], &ndash; \u00ab\u00a0lorsqu&rsquo;on sait\u00a0\u00bb, comment h\u00e9siter une seconde sur la qualificatif de \u00ab\u00a0manipulation\u00a0\u00bb r\u00e9alis\u00e9e quasiment par inconscience automatis\u00e9e [cas de Reagan sans nul doute] ? Et alors, il faut aussit\u00f4t conclure en pr\u00e9cisant que ce qualificatif n&rsquo;implique nullement qu&rsquo;un ordre et une orientation soient rigoureusement respect\u00e9s, qu&rsquo;il y ait un complot ma&icirc;trisant le tout [il y a une multitude de \u00ab\u00a0complots\u00a0\u00bb se t\u00e9lescopant les uns et les autres, aussi impuissants que pullulants, donc sans effet coordinateur et mobilisateur, et producteurs de d\u00e9sordre]. La \u00ab\u00a0manipulation\u00a0\u00bb implique d&rsquo;abord une m\u00e9canique du syst\u00e8me de la communication en \u00e9tat de surpuissance continuelle, surtout lorsqu&rsquo;il s&rsquo;agit d&rsquo;un ensemble o&ugrave; les images tiennent une grande place, avec des effets extr\u00eamement divers et souvent contradictoires. Le syst\u00e8me de la communication <a href=\"http:\/\/www.dedefensa.org\/article\/janus-au-grand-galop\">est un Janus<\/a>, l&rsquo;auxiliaire principale du Syst\u00e8me toujours pr\u00eat \u00e0 trahir le Syst\u00e8me&#8230;).<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Il n&#8217;emp\u00eache et il est indubitable que des \u00ab\u00a0campagnes de peur\u00a0\u00bb se mirent en place ou furent organis\u00e9e avec un succ\u00e8s consid\u00e9rable, et notamment, principalement bien s&ucirc;r, aux USA. La p\u00e9riode entre 1947-48 et 1963-64, avec le McCarthysme d&rsquo;une part et d&rsquo;autre part le danger d&rsquo;une attaque nucl\u00e9aire sovi\u00e9tique (en fait, la dangerosit\u00e9 absolue de l&rsquo;arme nucl\u00e9aire, qui est la v\u00e9rit\u00e9-de-situation qui structure notablement cette \u00ab\u00a0peur\u00a0\u00bb en \u00ab\u00a0Grande Peur\u00a0\u00bb), est un exemple proche de la perfection, un \u00ab\u00a0mod\u00e8le\u00a0\u00bb, \u00ab\u00a0le Mod\u00e8le\u00a0\u00bb. La crainte de l&rsquo;arme nucl\u00e9aire utilis\u00e9e par l&rsquo;agression sovi\u00e9tique, ou communiste impie-et-ath\u00e9e, est quasiment un caract\u00e8re constitutif de la psychologie de l&rsquo;am\u00e9ricanisme durant cette p\u00e9riode. Il fallut la crise des missiles de Cuba d&rsquo;octobre 1962 et la fa\u00e7on dont elle fut aussit\u00f4t pr\u00e9sent\u00e9e comme la crise du danger commun de la \u00ab\u00a0destruction mutuelle assur\u00e9e\u00a0\u00bb pour affaiblir d&rsquo;une fa\u00e7on marquante ce caract\u00e8re beaucoup plus antisovi\u00e9tique\/anticommuniste qu&rsquo;antinucl\u00e9aire. On observe tout de m\u00eame que cette r\u00e9ussite de cet \u00e9pisode d&rsquo;une manipulation parfaite au service de la \u00ab\u00a0politique de la peur\u00a0\u00bb d\u00e9boucha sur une situation catastrophique du point de vue de la manipulation (on ne dit pas n\u00e9cessairement \u00ab\u00a0du point de vue des manipulateurs\u00a0\u00bb) : l&rsquo;aventure vietnamienne parall\u00e8lement \u00e0 la mise en cause (<a href=\"http:\/\/www.dedefensa.org\/article\/un-general-president-nous-parle-du-cmi\">Eisenhower, 1961<\/a>) du complexe militaro-industriel, ou <em>National Security State<\/em>, qui font na&icirc;tre un antagonisme promis \u00e0 durer sous diff\u00e9rentes formes et entretenant une tension interne, avec d\u00e9j\u00e0, en 1974-1975, une mise en cause destructrice de la CIA par la commission Church. D&rsquo;autre part, il y eut cette p\u00e9riode de troubles int\u00e9rieurs (r\u00e9volte des Noirs, des \u00e9tudiants, mise en cause de la guerre au Vietnam) qui dura au moins jusqu&rsquo;en 1972 et imprima une marque durable. Le Mod\u00e8le ne marchait plus.<\/p>\n<\/p>\n<p><p>&bull; Comme on l&rsquo;a vu en d\u00e9tails pour les d\u00e9buts de la Guerre Froide, il y a une organisation humaine de la perception de la menace, voire de sa cr\u00e9ation pure et simple, donc indirectement une action de suscitation de la peur, pour des motifs ponctuels pr\u00e9cis, qui sont souvent \u00e0 court terme et n&rsquo;implique nullement une grande strat\u00e9gie m\u00eame s&rsquo;ils installent une situation nouvelle qui, elle, engendrera la n\u00e9cessit\u00e9 d&rsquo;un \u00ab\u00a0grande strat\u00e9gie\u00a0\u00bb. Dans ce cas fondamental des ann\u00e9es 1947-48 que l&rsquo;historiographie-Syst\u00e8me classique attribue \u00e0 une volont\u00e9 h\u00e9g\u00e9monique de l&rsquo;URSS, il y a une fondamentale manipulation de la communication par quelques hommes (le secr\u00e9taire \u00e0 la d\u00e9fense Forrestal notamment et en premier), notamment autour du \u00ab\u00a0coup de Prague\u00a0\u00bb de f\u00e9vrier 1948 qui avait d&rsquo;abord \u00e0 peine inqui\u00e9t\u00e9 le d\u00e9partement d&rsquo;&Eacute;tat, pour forcer \u00e0 une r\u00e9action imm\u00e9diate du gouvernement et du Congr\u00e8s \u00e0 Washington, pour passer des commandes imm\u00e9diates de r\u00e9armement qui sauv\u00e8rent l&rsquo;industrie a\u00e9ronautique US au bord de la d\u00e9sint\u00e9gration par faillites en cascade et, \u00e9ventuellement, \u00e9vit\u00e8rent une rechute dans une Grande D\u00e9pression 2.0. (Voir cette interpr\u00e9tation absolument fondamentale et absolument contre l&rsquo;historiographie-Syst\u00e8me pour comprendre toute notre histoire de 1945 \u00e0 nos jours, en grands d\u00e9tails dans nos <em><a href=\"http:\/\/www.dedefensa.org\/article\/notes-tres-longues-sur-le-trou-noir-du-xxeme-siecle\">Notes d&rsquo;Analyse du 2 septembre 2015<\/a>.<\/em>) A partir d&rsquo;un tel acte fondateur pour la p\u00e9riode, les \u00ab\u00a0peurs\u00a0\u00bb diverses n\u00e9es d&rsquo;une \u00ab\u00a0grande Peur\u00a0\u00bb centrale et sacralis\u00e9e s&rsquo;encha&icirc;nent automatiquement, en tr\u00e8s bon ordre dans le cadre imp\u00e9ratif de \u00ab\u00a0la Grande Peur\u00a0\u00bb et sans n\u00e9cessit\u00e9 de manipulations excessives mais par simple encha&icirc;nement d&rsquo;orientation dans le m\u00eame sens, quasi-naturellement selon un ordre logique, de la perception. L&rsquo;implosion puis la d\u00e9sint\u00e9gration brutales de l&rsquo;URSS interrompirent cet encha&icirc;nement des \u00ab\u00a0peurs\u00a0\u00bb de la Guerre Froide en pulv\u00e9risant le formidable incitatif qu&rsquo;\u00e9tait le bin\u00f4me danger sovi\u00e9tique\/risque de guerre nucl\u00e9aire. A la p\u00e9riode de \u00ab\u00a0la grande Peur\u00a0\u00bb  suscitant des \u00ab\u00a0peurs\u00a0\u00bb contr\u00f4l\u00e9es et ordonn\u00e9es succ\u00e9da aux USA un \u00e9pisode maniaco-d\u00e9pressif, dans l&rsquo;ordre inverse : \u00e9pisode d\u00e9pressif puis \u00e9pisode maniaque. (Voir cette interpr\u00e9tation \u00e9galement tr\u00e8s d\u00e9taill\u00e9e et importante, contre l&rsquo;historiographie-Syst\u00e8me, dans l&rsquo;article du 2 septembre 2005, &laquo; <em><a href=\"http:\/\/www.dedefensa.org\/article\/datlanta-1996-a-new-orleans-2005\">D&rsquo;Atlanta-1996 \u00e0 New Orleans-2005 ?<\/a><\/em> &raquo;.)<\/p>\n<\/p>\n<p><p>Ces remarques telles qu&rsquo;on les a faites induisent \u00e9videmment un rangement chronologique selon des p\u00e9riodes historiques appr\u00e9ci\u00e9es et caract\u00e9ris\u00e9es par une \u00e9volution psychologique affectant essentiellement les USA. Cette pr\u00e9\u00e9minence des USA est, dans ce cas, largement justifi\u00e9e par la domination de communication (d&rsquo;influence, de fascination, etc.) de cette puissance, principal moteur du Syst\u00e8me et productrice fondamentale du syst\u00e8me de la communication pendant la p\u00e9riode. Le temps (la p\u00e9riode) entre 1989-1991 et 9\/11 doit \u00eatre vu comme un interm\u00e8de pour entrer dans une nouvelle p\u00e9riode historico-psychologie, sur laquelle portent incontestablement les r\u00e9flexions du Dr. Altheide. C&rsquo;est de cette fa\u00e7on qu&rsquo;\u00e9voluera notre interpr\u00e9tation.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Les peurs en d\u00e9sordre succ\u00e8dent \u00e0 l&rsquo;ordre de la Grande Peur<\/h2>\n<\/p>\n<p><p>A \u00e9couter en d\u00e9sordre (on verra l&rsquo;ironie plus loin) le Dr. Altheide, c&rsquo;est-\u00e0-dire par bribes plut\u00f4t qu&rsquo;<em>in extenso<\/em>, on se construit tout de m\u00eame une image s\u00e9rieuse des questions qu&rsquo;il \u00e9voque, et ce que nous-m\u00eames avons \u00e9t\u00e9 amen\u00e9s \u00e0 \u00e9voquer : la \u00ab\u00a0politique de la peur\u00a0\u00bb, ou la peur comme manipulatrice des opinions, des analyses courantes, des appr\u00e9ciations, etc. Il en est beaucoup question aujourd&rsquo;hui, avec les \u00ab\u00a0vagues\u00a0\u00bb d&rsquo;attentats, avec ces politiques proclamatrices, ces \u00ab\u00a0mesures d&rsquo;urgence\u00a0\u00bb, ces incroyables mises en sc\u00e8ne. (La comm\u00e9moration de l&rsquo;attaque du 7 janvier 2015 coupe le souffle par sa pompe, son emphase bombastique, sa sacralisation \u00e9minemment la\u00efcarde-r\u00e9publicaine, bref d&rsquo;une fa\u00e7on o&ugrave; les qualificatifs nous manquent par rapport \u00e0 l&rsquo;importance factuelle, op\u00e9rationnelle, strat\u00e9gique qu&rsquo;eut l&rsquo;\u00e9v\u00e8nement&#8230; A presser ainsi, avec cette comm\u00e9moration <strong>extraordinaire-surr\u00e9aliste<\/strong>, le symbolisme pour faire jaillir dans le domaine \u00e9v\u00e8nementiel un g\u00e9ant quasiment m\u00e9tahistorique d&rsquo;un tel avorton historique, c&rsquo;est le d\u00e9valoriser [le symbolisme] jusqu&rsquo;\u00e0 l&rsquo;autodestruction de la pseudo-m\u00e9thode.)<\/p>\n<\/p>\n<p><p>On observera qu&rsquo;il en avait \u00e9t\u00e9 beaucoup question aux USA, de cette \u00ab\u00a0politique de la peur\u00a0\u00bb,  apr\u00e8s le 11 septembre ; c&rsquo;est pourquoi 11\/13, dont on peut attendre une comm\u00e9moration \u00e9galement <strong>extraordinaire-surr\u00e9aliste<\/strong>, fait si bien l&rsquo;affaire, comme reflet mim\u00e9tique de 9\/11, \u00ab\u00a0\u00e0-la-fran\u00e7aise\u00a0\u00bb quand la France est totalement am\u00e9ricanis\u00e9e-Syst\u00e8me et tente d&rsquo;imiter son grand mod\u00e8le sans s&rsquo;apercevoir, bien entendu, que le mod\u00e8le a du plomb dans l&rsquo;aile. Aux USA, en effet, \u00e0 partir du <em>Patriot Act<\/em> de 2002, des mesures furent prises en tr\u00e8s grand nombre, des structures nouvelles d&rsquo;encadrement s\u00e9curitaire furent \u00e9tablies prolongeant et renfor\u00e7ant les anciennes qui ont toujours exist\u00e9 dans ce pays obs\u00e9d\u00e9 par la surveillance et le maintien encadr\u00e9 du conformisme de comportement. Malgr\u00e9 cet effort gigantesque et la prolif\u00e9ration monstrueuse d&rsquo;une bureaucratie \u00ab\u00a0s\u00e9curitaire\u00a0\u00bb avec tous les moyens technologiques qu&rsquo;on imagine, le moins qu&rsquo;on puisse dire est que le r\u00e9sultat n&rsquo;est gu\u00e8re convaincant : le d\u00e9bat n&rsquo;est pas clos aux USA sur la situation du pays avec cet effort de s\u00e9curisation-contr\u00f4le depuis 9\/11, quelles que soient les valeurs et fausset\u00e9s diverses des arguments \u00e9chang\u00e9s ; plus que jamais, la contestation des divers groupes sociaux, soci\u00e9taux et culturels se d\u00e9veloppe et m\u00eame s&rsquo;exacerbe depuis l&rsquo;\u00e9lection d&rsquo;Obama, donnant l&rsquo;image d&rsquo;une tr\u00e8s grand d\u00e9sordre de communication dans un pays de plus en plus radicalement divis\u00e9.<\/p>\n<\/p>\n<p><p>L&rsquo;impression g\u00e9n\u00e9rale des USA post-9\/11 est le contraire d&rsquo;une d\u00e9mocratie totalitaire o&ugrave; r\u00e8gne la peur (la forme la plus avanc\u00e9e du totalitarisme comme le communisme devait \u00eatre la forme la plus achev\u00e9e du socialisme) ; c&rsquo;est-\u00e0-dire l&rsquo;impression d&rsquo;une d\u00e9mocratie d\u00e9vor\u00e9e par un d\u00e9sordre colossal et ce qui va avec, &ndash; inefficacit\u00e9, gaspillage, irresponsabilit\u00e9, fragmentation (d\u00e9structuration-dissolution) ; une d\u00e9mocratie-d\u00e9sordre o&ugrave; plus personne ne sait o&ugrave; est la r\u00e9alit\u00e9, o&ugrave; des lois absurdes et des r\u00e8glements grotesques sont \u00e9dict\u00e9s, engendrant des terreurs psychologiques dans certains domaines et des contestations-affrontements croissants de communication dans d&rsquo;autres, o&ugrave; la corruption r\u00e8gne d&rsquo;une fa\u00e7on si ouverte qu&rsquo;elle en devient caricaturale et l&rsquo;objet d&rsquo;une d\u00e9rision f\u00e9roce autant que d&rsquo;une fureur sans fin, o&ugrave; les in\u00e9galit\u00e9s sont telles que m\u00eame ceux qui en profitent se demandent par quels moyens r\u00e9guler et rendre honorable ce qui les avantage, o&ugrave; la notion d&rsquo;<em>American Dream<\/em> est devenue l&rsquo;objet de tous les sarcasmes.<\/p>\n<\/p>\n<blockquote>\n<p><p>Il s&rsquo;agit d&rsquo;une puissance consid\u00e9rable, les USA, o&ugrave; les peurs de plus en plus nombreuses se r\u00e9pandent comme autant de ferments de d\u00e9sordre et de d\u00e9s\u00e9quilibres depuis 9\/11, o&ugrave; les courants d&rsquo;opinion mesur\u00e9s par les enqu\u00eates statistiques n&rsquo;ont jamais \u00e9t\u00e9 aussi m\u00e9prisants pour les structures d&rsquo;un pouvoir auparavant sacralis\u00e9 et transform\u00e9 aux yeux du citoyen en des fratries mafieuses de gredins \u00e0 visage d\u00e9couvert ; il s&rsquo;agit d&rsquo;une puissance consid\u00e9rable notamment par le pouvoir en oripeaux l&rsquo;habillage d&rsquo;une l\u00e9gitimit\u00e9 cr\u00e9dible qu&rsquo;elle avait su \u00e9tablir \u00e0 sa t\u00eate, o&ugrave; d\u00e9sormais un vulgaire Trump (prenez le qualificatif dans ses deux sens) peut faire trembler l&rsquo;<em>establishment<\/em> au nom d&rsquo;arguments absolument disparates (certains si justes, d&rsquo;autres le contraire), sans aucune coh\u00e9rence entre eux, personnage absolument rigolard traitant avec emphase et une assurance stup\u00e9fiante, quasiment en les ridiculisant involontairement par l&rsquo;outrance de ses propositions qui d\u00e9noncent l&rsquo;impuissance du pouvoir et de l&rsquo;<em>establishment <\/em>ainsi compl\u00e8tement d\u00e9l\u00e9gitim\u00e9s, des questions <strong>qui sont agit\u00e9es depuis quinze ans comme autant d&rsquo;incitatifs \u00e0 toutes les peurs possibles et qu&rsquo;aucune r\u00e9ponse ne vient rendre op\u00e9rationnelles<\/strong>. Nous sommes bien oblig\u00e9s d&rsquo;observer que la machine, dans les ann\u00e9es 1945-1965 que nous avons prises comme r\u00e9f\u00e9rences, \u00e9taient autrement mieux huil\u00e9e par \u00ab\u00a0la Peur\u00a0\u00bb, et un Trump n&rsquo;aurait pas tenu deux mois, &ndash; d&rsquo;ailleurs, il ne lui serait pas venu \u00e0 l&rsquo;id\u00e9e de se pr\u00e9senter \u00e0 la pr\u00e9sidence. En ce temps-l\u00e0, \u00ab\u00a0la Peur\u00a0\u00bb \u00e9tait une chose s\u00e9rieuse ; on adulait le FBI et les fichiers de surveillance de J. Edgar Hoover, \u00ab\u00a0salopard officiel\u00a0\u00bb v\u00e9n\u00e9r\u00e9 par tous comme citoyen admirable ; on s&rsquo;entra&icirc;nait avec z\u00e8le dans toutes les \u00e9coles de la grande R\u00e9publique, d\u00e8s la maternelle, \u00e0 se \u00ab\u00a0mettre \u00e0 couvert\u00a0\u00bb (\u00ab\u00a0<em>Take Cover<\/em>\u00ab\u00a0, titre d&rsquo;un film d'\u00a0\u00bbinformation\u00a0\u00bb de l&rsquo;\u00e9poque) pour le  cas d&rsquo;explosions nucl\u00e9aires, suite \u00e0 une attaque par surprise, en tra&icirc;tre comme toujours, lanc\u00e9e par \u00ab\u00a0les Rouges\u00a0\u00bb, ces salopards de <em>Commies<\/em>&#8230;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>En quelque sorte, dirions-nous en ayant \u00e0 l&rsquo;esprit ces diverses r\u00e9f\u00e9rences, \u00ab\u00a0la mayonnaise ne prend plus\u00a0\u00bb. Quelle \u00e9tait donc la vertu de la \u00ab\u00a0politique de la Peur\u00a0\u00bb ? (Prenons cet \u00e9nonc\u00e9 et majusculons le mot qui nous importe.) M\u00eame si \u00ab\u00a0la Grande Peur\u00a0\u00bb \u00e9tait l&rsquo;effet d&rsquo;une panique, d&rsquo;une lubie, d&rsquo;une obsession, d&rsquo;une parano\u00efa, et bien s&ucirc;r m\u00eame si elle \u00e9tait l&rsquo;effet d&rsquo;une manipulation-complotiste, &ndash; elle \u00e9tait tout cela \u00e0 la fois, apr\u00e8s tout, &ndash; l&rsquo;ordre et la coh\u00e9sion \u00e9taient complets et ne cessaient d&rsquo;\u00eatre renforc\u00e9s tant que cette \u00ab\u00a0Peur\u00a0\u00bb r\u00e9gnait. D\u00e8s lors que \u00ab\u00a0la Peur\u00a0\u00bb \u00e9tait constitu\u00e9e, officiellement approuv\u00e9e et convenablement pr\u00e9sent\u00e9e, elle \u00e9tait nimb\u00e9e de l\u00e9gitimit\u00e9 et investissait majestueusement la psychologie de l&rsquo;am\u00e9ricanisme, accueillie par le public d&rsquo;une fa\u00e7on ordonn\u00e9e et pleine de coh\u00e9sion, sinon avec reconnaissance. En quelque sorte, tout le monde parlait la m\u00eame langue, les esprits \u00e9taient accord\u00e9s, et les citoyens s&rsquo;ils \u00e9taient sous l&#8217;empire de la servitude de \u00ab\u00a0la Grande Peur\u00a0\u00bb, y pratiquaient avec z\u00e8le une servitude volontaire qui les rassemblait. Ainsi la Guerre Froide avait-elle cr\u00e9\u00e9 un \u00ab\u00a0Mod\u00e8le\u00a0\u00bb presque parfait, sinon id\u00e9al (ne jouons pas trop sur l&rsquo;orwellisation des mots) de \u00ab\u00a0gouvernement par la Peur\u00a0\u00bb, d\u00e9mentant absolument, renversant compl\u00e8tement la logique de Roosevelt d\u00e9clarant fameusement lors de son discours d&rsquo;investiture de mars 1933, que &laquo; <em>la seule chose dont nous devons avoir peur, c&rsquo;est de la peur-elle m\u00eame <\/em>&raquo;. \u00ab\u00a0La Peur\u00a0\u00bb, et le gouvernement qui va avec, et le \u00ab\u00a0contr\u00f4le social\u00a0\u00bb qui suit presque avec la complicit\u00e9 enchant\u00e9e des \u00ab\u00a0contr\u00f4l\u00e9s\u00a0\u00bb eux-m\u00eames, avaient \u00e9t\u00e9 institu\u00e9s gr\u00e2ce \u00e0 deux verrous magnifiques, &ndash; la puissance de subversion proclam\u00e9e-et-mal\u00e9fique de l&rsquo;URSS, la puissance de destruction absolue-et-mal\u00e9fique de l&rsquo;arme nucl\u00e9aire&#8230; Comme on l&rsquo;a vu, le \u00ab\u00a0Mod\u00e8le\u00a0\u00bb craqua \u00e0 partir de 1964-1965 er ne retrouva jamais sa perfection des ann\u00e9es r\u00e9f\u00e9renc\u00e9es.<\/p>\n<\/p>\n<p><p>C&rsquo;est ce \u00ab\u00a0Mod\u00e8le\u00a0\u00bb que les \u00ab\u00a0faucons\u00a0\u00bb rebaptis\u00e9s avec l&rsquo;\u00e9tiquette g\u00e9n\u00e9rique beaucoup plus tendance et postmoderne de <em>neocons<\/em> voulaient r\u00e9tablir au terme des ann\u00e9es 1990 v\u00e9cues \u00e0 partir du milieu de la d\u00e9cennie comme des ann\u00e9es inf\u00e2mes et trompeuses \u00e0 cause du sentiment de l&rsquo;ivresse jubilatoire du dominateur de toutes choses et du monde, semblable \u00e0 l&rsquo;\u00e9pisode maniaque d&rsquo;un maniaco-d\u00e9pressif, qui r\u00e9gna \u00e0 partir de 1996, lorsque les critiques-fascin\u00e9s de la superpuissance inventaient le terme d'\u00a0\u00bbhyperpuissance\u00a0\u00bb. Les \u00ab\u00a0faucons\u00a0\u00bb \u00e9taient pourtant plus que jamais furieux \u00e0 l&rsquo;image d&rsquo;un Rumsfeld recevant une d\u00e9l\u00e9gation de parlementaires r\u00e9publicains au matin du 11 septembre, \u00e0 08H00 pour un \u00ab\u00a0petit d\u00e9jeuner de travail\u00a0\u00bb et leur affirmant que les USA avaient besoin d&rsquo;un nouveau Pearl Harbor pour les sortir de leur trompeuse euphorie. C&rsquo;\u00e9tait une heure avant l&rsquo;attaque qu&rsquo;on sait, et les parlementaires s&rsquo;exclam\u00e8rent ensuite \u00e0 propos de l&rsquo;extraordinaire don de divination du secr\u00e9taire \u00e0 la d\u00e9fense. Aussit\u00f4t, l&rsquo;on se mit \u00e0 la t\u00e2che de r\u00e9tablir un \u00ab\u00a0gouvernement de la Peur\u00a0\u00bb, selon le fameux \u00ab\u00a0Mod\u00e8le\u00a0\u00bb certifi\u00e9-Guerre Froide&#8230; Mais il leur manquait bien des choses, les ingr\u00e9dients de base, les psychologies n\u00e9cessaires, chez eux-m\u00eames autant que chez les citoyens de l&rsquo;\u00e9metteur aux r\u00e9cepteurs, la mesure de la d\u00e9marche qu&rsquo;interdisait d\u00e9sormais un syst\u00e8me de la communication qui semblait devenu fou et qui n&rsquo;a cess\u00e9 depuis de sembler de plus en plus fou, c&rsquo;st-\u00e0-dire de semer la folie comme un d\u00e9sordre insens\u00e9. Ainsi n&rsquo;avons-nous pas du tout eu une resuc\u00e9e du fameux Mod\u00e8le de \u00ab\u00a0gouvernement de la Peur\u00a0\u00bb, mais le contraire exactement.<\/p>\n<\/p>\n<blockquote>\n<p><p>&#8230; Non certes, car nous avons un anti-gouvernement, un non-pouvoir, avec une politique de toutes les peurs possibles, dans tous les sens, de toutes les fa\u00e7ons, engendrant d\u00e9sordre et contradictions. Nous avons troqu\u00e9 \u00ab\u00a0la Peur\u00a0\u00bb contre \u00ab\u00a0les peurs\u00a0\u00bb innombrables et chaotiques, comme une ivresse incontr\u00f4lable. Prenez les trois-quatre derni\u00e8res ann\u00e9es, en ayant \u00e0 l&rsquo;esprit que ces \u00ab\u00a0peurs\u00a0\u00bb affectent autant les moutons du Syst\u00e8me que nombre d&rsquo;antiSyst\u00e8me qui ne cessent de reconstruire m\u00e9caniquement l&rsquo;image d&rsquo;une puissance extraordinaire (le Syst\u00e8me, <em>dito<\/em> les USA pour le principal) de plus en plus irr\u00e9sistible \u00e0 mesure qu&rsquo;elle empilent les erreurs, les d\u00e9faites, qu&rsquo;elle se d\u00e9structure et se dissout elle-m\u00eame&#8230; Les trois-quatre derni\u00e8res ann\u00e9es, donc, de qui et de quoi faut-il avoir eu peur ? De Kadhafi ? De BHL ? D&rsquo;Assad ? De Poutine ? De la Chine ? De Wall Street et de Goldman-Sachs ? De ben Laden et de <em>Daesh<\/em> ? De la Commission \u00e0 Bruxelles ? De l&rsquo;Arabie et de la Turquie ? Du \u00ab\u00a0roi du chocolat\u00a0\u00bb Porochenko et de <em>Pravy Sektor<\/em> ? Des USA du TTIP si l&rsquo;on est Europ\u00e9ens ? Des Allemands si l&rsquo;on est Fran\u00e7ais ? Du FN si l&rsquo;on est \u00e0 court d&rsquo;id\u00e9e ? Des \u00ab\u00a0<em><a href=\"http:\/\/www.dedefensa.org\/article\/les-gays-et-le-pouvoir-politique\">gays<\/a><\/em>\u00a0\u00bb si l&rsquo;on est f\u00e9ministe et antinazi ? Des robots de Google si l&rsquo;on doute d&rsquo;\u00eatre encore humains ? Du climat qui n&rsquo;en finit pas de nous tomber sur la t\u00eate ? Pour reprendre une formule de la p\u00e9riode cit\u00e9e en r\u00e9f\u00e9rence, il s&rsquo;agit d&rsquo;une sorte de McCarthysme mou et surtout erratique qui part dans tous les sens, sans McCarthy comme animateur, r\u00e9f\u00e9rence et comme cible \u00e0 la fois, sans les <em>Commies<\/em> \u00e0 l&rsquo;int\u00e9rieur et \u00e0 l&rsquo;ext\u00e9rieur sur lesquels s&rsquo;appuyer pour lancer des accusations&#8230;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le r\u00e9sultat est une immense confusion, un d\u00e9sordre sans fin, un d\u00e9sordre tourbillonnant au gr\u00e9 des crises, c&rsquo;est-\u00e0-dire le contraire de ce que doit produire la \u00ab\u00a0politique de la Peur\u00a0\u00bb. Ce d\u00e9sordre est confirm\u00e9, amplifi\u00e9 lorsque, finalement, l&rsquo;on comprend que la \u00ab\u00a0peur\u00a0\u00bb finale qui conduit \u00e0 la fois cette politique et ceux qui lui sont soumis, est cette \u00ab\u00a0peur\u00a0\u00bb paradoxale dont le Dr. Altheide parle implicitement dans sa derni\u00e8re phrase : &laquo; <em>Avoir une conversation dans un monde si compl\u00e8tement install\u00e9 dans la peur est devenue tr\u00e8s difficile <\/em>&raquo;&#8230; Cette \u00ab\u00a0peur\u00a0\u00bb qui \u00ab\u00a0emp\u00eache les conversations\u00a0\u00bb et qui se r\u00e9v\u00e8le comme productrice de l&rsquo;isolement par la peur-en-tant-que-telle des \u00eatres dans les soci\u00e9t\u00e9s soumises au Syst\u00e8me, produit donc l&rsquo;effet exactement inverse \u00e0 celui de la politique de la Peur, par une atomisation de la peur dans une soci\u00e9t\u00e9 dont on devine qu&rsquo;elle n&rsquo;est plus qu&rsquo;une soumission irresponsable au Syst\u00e8me et en \u00e9tat latent de d\u00e9sordre-d\u00e9testation du Syst\u00e8me qui fait craindre la r\u00e9volte anarchique, au lieu d&rsquo;une mobilisation derri\u00e8re le pouvoir (que nous n&rsquo;appelions pas encore \u00ab\u00a0Syst\u00e8me\u00a0\u00bb) devant un danger commun provoquant une peur commune.<\/p>\n<\/p>\n<p><p>Notre prescient coll\u00e8gue PhG nous a averti de cela, <a href=\"http:\/\/www.dedefensa.org\/article\/et-avance-masquee-la-verite\">dans son intervention d&rsquo;hier<\/a>, d&rsquo;une fa\u00e7on qui tombait bien et nous finirons apr\u00e8s tout en le pompant un peu, &ndash; il ne nous en voudra pas, il n&rsquo;a rien d&rsquo;un McCarthy&#8230; &laquo; &#8230;<em>L\u00e0-dessus, la derni\u00e8re phrase du Dr. Altheide devient lumineuse pour mon compte, car il nous d\u00e9voile d&rsquo;un seul coup l&rsquo;un des Myst\u00e8res les mieux choy\u00e9s du Syst\u00e8me, qui est <strong>la peur int\u00e9rieure \u00e0 lui-m\u00eame<\/strong><\/em>&#8230; [&#8230; O]<em>&ugrave; chacun vit dans la peur de dire ou de faire quelque chose qui ne soit pas conforme \u00e0 la ligne-Syst\u00e8me, o&ugrave; chacun r\u00e9fr\u00e8ne son premier \u00e9lan, dissimule sa r\u00e9flexion sur cet \u00e9lan, \u00e9carte les conclusions qu&rsquo;il en tire et cherche d\u00e9sesp\u00e9r\u00e9ment quelle est la posture ou le bon mot (la \u00ab\u00a0vanne\u00a0\u00bb qui ne \u00ab\u00a0d\u00e9rape\u00a0\u00bb pas) que recommande le conformisme-Syst\u00e8me pour ce cas pr\u00e9cis\u00e9ment<\/em>&#8230; &raquo; Leur \u00ab\u00a0politique de la Peur\u00a0\u00bb se terminant en r\u00e9union de salonards sur le plateau grin\u00e7ant-persifleur de <em>On n&rsquo;est pas couch\u00e9. <\/em>C&rsquo;est une v\u00e9rit\u00e9-de-situation qui nous fait penser \u00e0 une sorte d&rsquo;anti-p\u00e9plum postmoderne dont Kubrick aurait fait un film qui serait le <em>Folamour<\/em> postmoderne, avec le titre \u00ab\u00a0Grandeur et D\u00e9rision\u00a0\u00bb plut\u00f4t que \u00ab\u00a0Grandeur et D\u00e9cadence\u00a0\u00bb tant le Syst\u00e8me et sa caricature de la M\u00e9thode des temps <em>non suspecto<\/em> ne sont absolument pas capables de cette chute honorable qu&rsquo;est la d\u00e9cadence.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0La somme de toutes les peurs\u00a0\u00bb 07 janvier 2016 &ndash; La peur est-elle une politique, nous voulons dire une \u00ab\u00a0politique-en-soi\u00a0\u00bb ? C&rsquo;est-\u00e0-dire la suscitation d&rsquo;une \u00e9motion (la peur) pour installer une politique sp\u00e9cifique, con\u00e7ue pr\u00e9cis\u00e9ment pour un terme long ? C&rsquo;est une th\u00e8se largement r\u00e9pandue depuis l&rsquo;attaque du 11 septembre 2001 (9\/11) au point que&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[354,370,17261,4270,3015,6384,2631,2604,3356,3106,2891,2645,10274,2622,3616,4638,3084,17262,17264,5030,17263,10008,569,4746,3014],"class_list":["post-76343","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-354","tag-370","tag-altheide","tag-autodestruction","tag-communication","tag-controle","tag-de","tag-des","tag-desordre","tag-froide","tag-grande","tag-guerre","tag-janus","tag-la","tag-manipulation","tag-mccarthysme","tag-mobilisation","tag-multiplication","tag-nuclearire","tag-peur","tag-peurs","tag-richard","tag-rumsfeld","tag-social","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76343"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76343\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}