{"id":76369,"date":"2016-01-20T10:39:43","date_gmt":"2016-01-20T10:39:43","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/01\/20\/lue-la-pologne-et-le-neo-marxisme\/"},"modified":"2016-01-20T10:39:43","modified_gmt":"2016-01-20T10:39:43","slug":"lue-la-pologne-et-le-neo-marxisme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/01\/20\/lue-la-pologne-et-le-neo-marxisme\/","title":{"rendered":"L&rsquo;UE, la Pologne et le n\u00e9o-marxisme"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d;font-size:2em;\">L&rsquo;UE, la Pologne et le n\u00e9o-marxisme<\/h2>\n<\/p>\n<p><p><a href=\"https:\/\/en.wikipedia.org\/wiki\/John_Laughland\">John Laughland<\/a>, \u00e0 qui nous avons <a href=\"http:\/\/www.dedefensa.org\/article\/la-nuit-de-cologne-ou-le-crash-des-civilisations\">fait appel tr\u00e8s r\u00e9cemment<\/a>, pour son commentaire sur les \u00e9v\u00e8nements du Jour de l&rsquo;An \u00e0 Cologne et ailleurs, est un intellectuel qui a affirm\u00e9 depuis longtemps ses opinions radicalement eurosceptiques en m\u00eame temps que sa propre position de conservateur britannique au sens ouvert (nous voulons dire \u00ab\u00a0encore plus conservateur, sinon traditionnaliste, que britannique\u00a0\u00bb, donc largement ouvert sur l&rsquo;aspect international des probl\u00e8mes qu&rsquo;il traite et nullement cantonn\u00e9 sur un isolationnisme britannique bien connu). En 1997, il publia un essai qui fit grand scandale dans la bienpensance g\u00e9n\u00e9rale et la vertu europ\u00e9enne, o&ugrave; il jugeait que certaines racines de ce qui est aujourd&rsquo;hui l&rsquo;UE se confondaient avec celles du fascisme, du nazisme et du communisme (<em>The Tainted Source: The Undemocratic Origins of the European Idea<\/em>). Il faut avoir cela \u00e0 l&rsquo;esprit, comme un pr\u00e9liminaire de la r\u00e9flexion, avant de lire son article sur l&rsquo;actuelle \u00ab\u00a0question polonaise\u00a0\u00bb, ou \u00ab\u00a0crise polonaise\u00a0\u00bb au sein de l&rsquo;UE, qui touche en fait nombre de pays de l&rsquo;ancienne Europe de l&rsquo;Est\/l&rsquo;ancienne Europe communiste.<\/p>\n<\/p>\n<p><p>Laughland d\u00e9taille les attendus de cette crise et met bien entendu en \u00e9vidence la compl\u00e8te ill\u00e9gitimit\u00e9 de l&rsquo;UE, \u00e0 la fois dans son intervention dans les affaire polonaises et les r\u00e8glements de surveillance intrusive qui la \u00ab\u00a0justifierait\u00a0\u00bb, \u00e0 la fois dans ses pr\u00e9tentions g\u00e9n\u00e9rales de \u00ab\u00a0gouvernance\u00a0\u00bb qu&rsquo;il relie aux tendances et aux racines de l&rsquo;UE qu&rsquo;il a identifi\u00e9es et toujours d\u00e9nonc\u00e9es. Sur les circonstances de la crise, et notamment les d\u00e9cisions du nouveau gouvernement polonais, Laughland dit son avis plut\u00f4t favorable en les reliant \u00e0 d&rsquo;autres \u00e9volutions dans le m\u00eame sens dans d&rsquo;autres pays de la m\u00eame zone, notamment la Hongrie de Viktor Orban, et certains aspects r\u00e9v\u00e9lateurs en Tch\u00e9quie et en Slovaquie. (Ces quatre pays cit\u00e9s forment <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Groupe_de_Visegr%C3%A1d\">le Groupe de Visegrad<\/a>, rassemblement politique informel affichant la proximit\u00e9 g\u00e9n\u00e9rale de ces quatre pays de l&rsquo;axe central de l&rsquo;ex-Europe communiste, &ndash; laquelle proximit\u00e9 est ainsi largement d\u00e9montr\u00e9e.)<\/p>\n<\/p>\n<p><p>Pour Laughland, il ne s&rsquo;agit de rien moins que d&rsquo;une r\u00e9volte des pays, notamment centre-europ\u00e9ens, qui ont v\u00e9cu sous le joug marxiste de l&rsquo;URSS, contre un organisme (l&rsquo;UE) qui s&rsquo;av\u00e8re absolument ill\u00e9gitime, qui est par cons\u00e9quent dictatorial dans l&rsquo;exerce de son pouvoir, qui est de tendance n\u00e9o-marxiste pour l&rsquo;influence qui y pr\u00e9vaut. (&laquo; <em>La construction europ\u00e9enne depuis la chute du rideau de fer est bas\u00e9e sur une vision d\u00e9terministe et n\u00e9o-marxiste de l&rsquo;histoire, selon laquelle les nations ont in\u00e9vitablement tendance \u00e0 se fondre les unes dans les autres et \u00e0 dispara&icirc;tre<\/em>. &raquo;) Ce verdict de n\u00e9o-marxisme \u00e0 propos  de l&rsquo;UE n&rsquo;est pas une exception exotique de fait de Laughland. Ce jugement sur le n\u00e9o-marxisme de l&rsquo;UE est partag\u00e9 notamment dans la d\u00e9marche critique des libertariens aux USA, qui sont aujourd&rsquo;hui tr\u00e8s affirm\u00e9s dans la dissidence antiSyst\u00e8me, avec les plus virulents consid\u00e9rant que le \u00ab\u00a0centre washingtonien\u00a0\u00bb et les grands centres de pouvoir US s&rsquo;inscrivent \u00e9galement eux-m\u00eames, sinon dans un cadre marxiste, au moins dans un cadre \u00ab\u00a0socialiste\u00a0\u00bb. (Par exemple, l&rsquo;intervention massive de Washington pour sauver les banques de Wall Street de la crise de 2008 qu&rsquo;elles avaient elles-m\u00eames provoqu\u00e9e repr\u00e9sente un n\u00e9o-capitalisme extr\u00eame qui ne peut \u00eatre qualifi\u00e9 que de \u00ab\u00a0socialiste\u00a0\u00bb \u00e0 cause de l&rsquo;intervention statiste massive dupliquant la politique \u00e9conomique des pays communistes du XX\u00e8me si\u00e8cle.) <\/p>\n<\/p>\n<blockquote>\n<p><p>L&rsquo;argument du n\u00e9o-marxisme peut \u00eatre discut\u00e9, mais un tel d\u00e9bat n&rsquo;aboutira sans doute \u00e0 rien de d\u00e9cisif ; l&rsquo;argument est \u00e0 la fois fond\u00e9 et satisfaisant dans les limites qu&rsquo;il se donne lui-m\u00eame et qui sont relativement contraignantes, \u00e0 la fois partiel et insatisfaisant dans l&rsquo;environnement g\u00e9n\u00e9ral o&ugrave; il s&rsquo;inscrit qui est celui de la Grande Crise d&rsquo;effondrement du Syst\u00e8me. <strong>De ce point de vue, il ne fait qu&rsquo;ajouter au d\u00e9sordre g\u00e9n\u00e9ral<\/strong>, d&rsquo;une fa\u00e7on d&rsquo;ailleurs assez logique puisque toute tentative de classement selon les r\u00e9f\u00e9rences anciennes met en \u00e9vidence l&rsquo;ambigu\u00eft\u00e9 totale des \u00ab\u00a0\u00e9tiquettes\u00a0\u00bb id\u00e9ologiques avec les contradictions en cascade qui en d\u00e9coulent.<\/p>\n<\/p>\n<p><p>On sait l&rsquo;incontestabilit\u00e9 des origines trotskistes, et donc marxistes dans son aspect le plus internationaliste, des <em>neocons<\/em> US, qui sont pourtant l&rsquo;aiguillon activiste le plus actif, depuis l&rsquo;origine, de la phase de surpuissance actuelle du Syst\u00e8me dans son aspect le plus d\u00e9structurant et le plus dissolvant, repr\u00e9sentant sans aucun doute une expression plus brutale de la pouss\u00e9e fondamentale de l&rsquo;hypercapitalisme et du <em>Corporate-Power<\/em>. On dirait alors : mais l&rsquo;hypercapitalisme et le <em>Corporate-Power<\/em> (et le syst\u00e8me par cons\u00e9quent ?) sont effectivement des forces qui puisent largement dans l&rsquo;id\u00e9ologie trotskiste\/marxiste ; et l&rsquo;on poursuivrait aussit\u00f4t : que faire alors, dans ce cas, de l&rsquo;opposition radicale et sans la moindre concession \u00e0 l&rsquo;hypercapitalisme\/<em>Corporate-Power<\/em>\/Syst\u00e8me  du mouvement actuel des marxistes (n\u00e9o- ou pas) ou proches du marxisme <a href=\"http:\/\/www.dedefensa.org\/article\/wallerstein-yeats-et-lapressysteme\">type-Wallerstein<\/a>, ou des trotskistes classiques de la IV\u00e8me Internationale (voir <em>WSWS.org<\/em>), s&rsquo;inscrivant dans l&rsquo;aspect anti-expansionniste et anti-belliciste du mouvement ? On trouve chez les uns et les autres des arguments dans tous les sens, qui t\u00e9moignent effectivement des ambigu\u00eft\u00e9s signal\u00e9es plus haut, mais qui ont surtout pour effet, pour cons\u00e9quence, etc., <strong>d&rsquo;accentuer le d\u00e9sordre g\u00e9n\u00e9ral des situations et des esprits au point que l&rsquo;on pourrait en revenir \u00e0 l&rsquo;id\u00e9e que l&rsquo;id\u00e9ologie dominatrice, celle du Syst\u00e8me, est le d\u00e9sordre en soi, jusqu&rsquo;\u00e0 l&rsquo;entropisation<\/strong>. (Et \u00e0 ce point justement, l&rsquo;on est convi\u00e9, si l&rsquo;on a l&rsquo;esprit peu embarrass\u00e9 des cha&icirc;nes et contraintes du Syst\u00e8me, \u00e0 examiner la question g\u00e9n\u00e9rale ainsi \u00e9largie, du point de vue m\u00e9tahistorique, et l&rsquo;on sait <a href=\"http:\/\/www.dedefensa.org\/article\/notes-en-plus-sur-le-systeme\">dans quel sens<\/a> pour notre compte.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Si l&rsquo;on en revient au cas polonais tel que nous l&rsquo;expose Laughland, on retrouve d&rsquo;autres sortes de contradictions, qu&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article\/la-pologne-explosive-au-coeur-de-leurope-et-du-systeme\">on a d\u00e9j\u00e0 signal\u00e9es<\/a> succinctement ou selon une autre approche. Le PiS depuis qu&rsquo;il compte puis arrivant au pouvoir, et les jumeaux Kaczynski r\u00e9duits au seul Jaroslaw depuis 2010, repr\u00e9sentent \u00e9videmment une tendance ultra-nationaliste ou plut\u00f4t ultra-patriotique, traditionniste, catholique, etc., qu&rsquo;il est \u00e9videmment compl\u00e8tement logique de placer dans le camp eurosceptique tr\u00e8s-proche de la Hongrie d&rsquo;Orban (les contacts entre les deux pays se multiplient et sont consid\u00e9rables depuis d\u00e9cembre), et cela effectivement contre l'\u00a0\u00bbUE n\u00e9o-marxiste\u00a0\u00bb de John Laughland. Pourtant, le m\u00eame PiS s&rsquo;est trouv\u00e9 compl\u00e8tement au c\u00f4t\u00e9 de l&rsquo;UE, notamment en 2008 lors de la guerre entre la G\u00e9orgie et la Russie, et surtout lors de la crise ukrainienne dans sa phase paroxystique, entre f\u00e9vrier 2014 et le d\u00e9but de l&rsquo;automne 2015, &ndash; et, dans ce dernier cas, contre la Hongrie d&rsquo;Orban.<\/p>\n<\/p>\n<p><p>Le d\u00e9bat s&rsquo;\u00e9largit de lui-m\u00eame, bien entendu, puisqu&rsquo;on en vient aux relations avec la Russie. Le PiS est naturellement et visc\u00e9ralement antirusse ; pourtant de quelle nation est-il le plus proche, lorsqu&rsquo;il \u00e9nonce son credo (patriotisme, traditionalisme, respect de la religion d&rsquo;origine), sinon de la Russie de Poutine ? Il n&rsquo;est pas n\u00e9cessaire d&rsquo;argumenter longuement \u00e0 ce propos, et <strong>plut\u00f4t qu&rsquo;affirmer une orientation id\u00e9ologique quelconque, l&rsquo;on fait \u00e0 nouveau le constat du d\u00e9sordre<\/strong>. Pour notre compte, on ne peut alors se sortir de ce cercle vicieux de la confusion des jugements et du d\u00e9sordre des situations <strong>qu&rsquo;en se cantonnant au plus simple, qui est aussi le plus fondamental : la bataille de l&rsquo;antiSyst\u00e8me contre le Syst\u00e8me<\/strong>, o&ugrave; la riposte structurante contre la d\u00e9structuration-dissolution, etc. C&rsquo;est en ces termes qu&rsquo;il faut juger des diverses situations, et alors les changements, les voltefaces, les orientations brutalement modifi\u00e9es ne constituent plus ni un signe de d\u00e9sordre ni une force de confusion des esprits et des jugements.<\/p>\n<\/p>\n<p><p>Il est effectivement acquis que la bataille antiSyst\u00e8me contre Syst\u00e8me, c&rsquo;est-\u00e0-dire la course surpuissance-autodestruction du Syst\u00e8me, se fait dans une situation de d\u00e9sordre g\u00e9n\u00e9ral mais il faut accepter ce d\u00e9sordre comme \u00e9tant le fondement m\u00eame de la bataille, sa logique, on dira paradoxalement (mais logiquement selon la domination du courant de l&rsquo;inversion) \u00ab\u00a0son rangement et son ordre\u00a0\u00bb ; et alors, selon cette consid\u00e9ration, le d\u00e9sordre g\u00e9n\u00e9ral de la situation n&rsquo;entra&icirc;ne nullement la confusion dans les esprits mais au contraire il<strong> devrait les nourrit de sa logique paradoxale et alimenter leur jugement bien ordonn\u00e9<\/strong>. Simplement, il faut l&rsquo;avoir souple, le jugement, pour proc\u00e9der selon les r\u00e9f\u00e9rences choisies (antiSyst\u00e8me et Syst\u00e8me) et rudement d\u00e9noncer dans un cas le Pis polonais, puis l&rsquo;applaudir avec chaleur dans l&rsquo;autre. Les antiSyst\u00e8me, car bien entendu nous parlons dans ce sens puisque nous en sommes, doivent accepter les m\u00eames contradictions, notamment du point de vue des \u00e9tiquettes-id\u00e9ologiques, que les <a href=\"http:\/\/www.dedefensa.org\/article\/jecris-ton-ombre-zombie\">zombies-Syst\u00e8me<\/a> assument aveugl\u00e9ment et bien entendu sans s&rsquo;interroger et sans le moindre jugement. L&rsquo;antiSyst\u00e8me assume tout cela, en toute lucidit\u00e9 et en toute satisfaction de sa logique, \u00e0 la diff\u00e9rence compl\u00e8te du zombie bien s&ucirc;r.<\/p>\n<\/p>\n<p><p>Voici donc le texte de John Laughland, <a href=\"https:\/\/francais.rt.com\/opinions\/13880-commission-europeenne-enquete-pologne\">du 14 janvier sur RT<\/a>. Nous avons pris sur nous de faire une correction de ce qui est manifestement un contresens de traduction. Le texte original disait, apr\u00e8s l&rsquo;expos\u00e9 par le ministre polonais des affaires \u00e9trang\u00e8res de ce qui est la vision de l&rsquo;UE que repousse la Pologne : &laquo; <em>A cette vision, digne d&rsquo;un <a href=\"http:\/\/www.lefigaro.fr\/international\/2013\/09\/20\/01003-20130920ARTFIG00537-vladimir-poutine-croise-des-valeurs-chretiennes.php\">Vladimir Poutine<\/a>, le ministre polonais opposait \u00ab\u00a0ce que veut la majorit\u00e9 des Polonais : les traditions, la conscience de son histoire, l&rsquo;amour de la patrie, la foi en Dieu, en une vie de famille normale entre un homme et une femme\u00a0\u00bb&#8230;<\/em> &raquo;. La \u00ab\u00a0vision\u00a0\u00bb de Poutine n&rsquo;est \u00e9videmment pas proche de celle de l&rsquo;UE mais bien de celle du nouveau gouvernement polonais, d&rsquo;o&ugrave; notre correction dans ce sens : &laquo; [A cette vision, le ministre opposait celle-ci, digne d&rsquo;un <a href=\"http:\/\/www.lefigaro.fr\/international\/2013\/09\/20\/01003-20130920ARTFIG00537-vladimir-poutine-croise-des-valeurs-chretiennes.php\">Vladimir Poutine<\/a> :] <em>\u00ab\u00a0Ce que veut la majorit\u00e9 des Polonais : les traditions, la conscience de son histoire, l&rsquo;amour de la patrie, la foi en Dieu, en une vie de famille normale entre un homme et une femme\u00a0\u00bb<\/em>. &raquo; Nous avons \u00e9galement modifi\u00e9 le titre pour des raisons techniques (titre original : &laquo; <em>La Commission europ\u00e9enne voit la paille dans l&rsquo;&oelig;il polonais mais pas la poutre dans le sien<\/em> &raquo;.)<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\">La paille de la Pologne et la poutre de l&rsquo;UE<\/h2>\n<\/p>\n<p><p>D\u00e9cid\u00e9ment, la Commission europ\u00e9enne ne craint pas l&rsquo;autod\u00e9rision.  Avec son <a href=\"http:\/\/europa.eu\/rapid\/press-release_SPEECH-16-71_en.htm\">annonce<\/a>, le 13 janvier, qu&rsquo;elle va lancer une enqu\u00eate pr\u00e9liminaire sur le respect de l&rsquo;\u00e9tat de droit en Pologne, elle montre qu&rsquo;elle voit la paille dans l&rsquo;&oelig;il polonais mais non pas la poutre dans le sien.<\/p>\n<\/p>\n<p><p>Les pr\u00e9textes pour cette annonce, qui est sans pr\u00e9c\u00e9dent dans l&rsquo;histoire de l&rsquo;Union europ\u00e9enne, sont les nouvelles lois sur les m\u00e9dias publics et la nomination de nouveaux juges constitutionnels.  Mais, pire encore que les autres institutions europ\u00e9ennes, la Commission europ\u00e9enne est elle-m\u00eame l&rsquo;incarnation du caract\u00e8re profond\u00e9ment anti-d\u00e9mocratique de l&rsquo;Union europ\u00e9enne.  Les fameux commissaires ne sont pas seulement des fonctionnaires non \u00e9lus, la Commission jouit aussi d&rsquo;un monopole absolu sur le processus l\u00e9gislatif europ\u00e9en: toutes les lois europ\u00e9ennes sont initi\u00e9es par elle.  C&rsquo;est un monopole qui n&rsquo;existe dans aucune d\u00e9mocratie car, en excluant toute initiative l\u00e9gislative populaire ou parlementaire, il est contraire au principe m\u00eame de la repr\u00e9sentation politique.  La Commission de Bruxelles a donc moins de l\u00e9gitimit\u00e9 d\u00e9mocratique que ses presqu&rsquo;homonymes, les fameux Comit\u00e9s centraux des partis communistes qui jadis faisait la pluie et le beau temps en Europe de l&rsquo;Est. Quand Bruxelles accuse la Varsovie d&rsquo;aujourd&rsquo;hui d&rsquo;un manque de respect pour la d\u00e9mocratie, c&rsquo;est la pelle qui se moque du fourgon.<\/p>\n<\/p>\n<p><p>En r\u00e9alit\u00e9, la machine bruxelloise s&rsquo;int\u00e9resse peu \u00e0 l&rsquo;&Eacute;tat de droit. Elle s&rsquo;int\u00e9resse \u00e0 son propre pouvoir<\/p>\n<\/p>\n<p><p>En outre, en invoquant le respect de l&rsquo;Etat de droit comme pr\u00e9texte pour son enqu\u00eate, le commissaire Frans Timmermans &#8211; ancien ministre socialiste des affaires \u00e9trang\u00e8res, et ancien collaborateur du renseignement militaire n\u00e9erlandais &#8211; viole pr\u00e9cis\u00e9ment le principe qu&rsquo;il pr\u00e9tend prot\u00e9ger.  La <a href=\"http:\/\/europa.eu\/rapid\/press-release_IP-14-237_fr.htm\">base l\u00e9gale<\/a> de son enqu\u00eate serait le &laquo;cadre en vue de sauvegarder l&rsquo;Etat de droit&raquo; que la Commission a adopt\u00e9 en mars 2014. Or, l&rsquo;adoption de ce &laquo;cadre&raquo; est un cas d&rsquo;\u00e9cole d&rsquo;une violation des principes juridiques fondamentaux, car c&rsquo;est un pouvoir que la Commission s&rsquo;est auto-d\u00e9cern\u00e9, sans qu&rsquo;il ne lui ait \u00e9t\u00e9 attribu\u00e9 par aucune instance l\u00e9galement comp\u00e9tente. Un pouvoir qu&rsquo;un organe s&rsquo;arroge est un pouvoir ill\u00e9gitime. <\/p>\n<\/p>\n<p><p>Cette usurpation par la Commission est d&rsquo;autant plus absurde qu&rsquo;il existe en Europe, depuis des d\u00e9cennies, <a href=\"https:\/\/francais.rt.com\/opinions\/13274-europe-otan-gouffre\">tout un chapelet d&rsquo;autres institutions <\/a>qui ont \u00e9t\u00e9 cr\u00e9\u00e9es pour veiller sur l&rsquo;&Eacute;tat de droit et la d\u00e9mocratie. Au sein de l&rsquo;UE les organes comp\u00e9tents sont la Cour de Justice \u00e0 Luxembourg et l&rsquo;Agence europ\u00e9enne pour les Droits fondamentaux \u00e0 Vienne; au sein de l&rsquo;OSCE il y a le Bureau pour les Institutions d\u00e9mocratiques et les Droits de l&rsquo;homme \u00e0 Varsovie (ODIHR); et au sein du Conseil de l&rsquo;Europe \u00e0 Strasbourg, il y la Commission de Venise et surtout la Cour europ\u00e9enne des droits de l&rsquo;homme.  Aucune de ses institutions ne s&rsquo;est prononc\u00e9e sur le cas polonais.<\/p>\n<\/p>\n<p><p>En r\u00e9alit\u00e9, la machine bruxelloise s&rsquo;int\u00e9resse peu \u00e0 l&rsquo;&Eacute;tat de droit.  Elle s&rsquo;int\u00e9resse \u00e0 son propre pouvoir.  <a href=\"https:\/\/francais.rt.com\/opinions\/9139-legislatives-pologne-germanophobie-facade\">Depuis les \u00e9lections l\u00e9gislatives l&rsquo;an dernier<\/a> qui ont balay\u00e9 la gauche de sa sc\u00e8ne politique, la Pologne incarne une nouvelle droitisation de l&rsquo;Europe centrale et orientale.  Apr\u00e8s le clivage nord-sud qui s&rsquo;est ouvert en 2009 avec la crise de l&rsquo;euro, notamment entre la Gr\u00e8ce et l&rsquo;Allemagne, voici maintenant que l&rsquo;Europe est d\u00e9chir\u00e9e par un nouveau clivage est-ouest &#8211; entre une Europe occidentale impr\u00e9gn\u00e9e de valeurs postmodernes et une Europe centrale et orientale soucieuse de renouer avec ses valeurs traditionnelles.<\/p>\n<\/p>\n<p><p>Comme la crise nord-sud, qui a provoqu\u00e9 la jacquerie \u00e9ph\u00e9m\u00e8re de Syriza en Gr\u00e8ce contre l&rsquo;arrogance des institutions europ\u00e9ennes soutenues par l&rsquo;Allemagne, la crise est-ouest est une r\u00e9bellion de velours contre une Union europ\u00e9enne per\u00e7ue comme trop intrusive et trop \u00e0 gauche.  Le sillon trac\u00e9 depuis quelques ann\u00e9es par Victor Orban en <a href=\"https:\/\/francais.rt.com\/international\/11506-slovaquie-hongrie-plainte-quotas-migrants\">Hongrie<\/a>, qui revendique ouvertement la souverainet\u00e9 et les racines chr\u00e9tiennes de son pays; les dissidences r\u00e9cidivistes de pr\u00e9sidents tch\u00e8ques successifs sur plusieurs dossiers, et notamment sur la politique antirusse pouss\u00e9e par Berlin;  et le refus muscl\u00e9 affich\u00e9 par le gouvernement slovaque comme par d&rsquo;autres \u00e0 la volont\u00e9 allemande d&rsquo;imposer des quotas de r\u00e9fugi\u00e9s \u00e0 toute l&rsquo;Europe, constituent d\u00e9sormais un consensus en Europe \u00e0 l&rsquo;Est de la ligne l&rsquo;Oder\/Neisse.<\/p>\n<\/p>\n<p><p>La construction europ\u00e9enne depuis la chute du rideau de fer est bas\u00e9e sur une vision d\u00e9terministe et n\u00e9o-marxiste de l&rsquo;histoire, selon laquelle les nations ont in\u00e9vitablement tendance \u00e0 se fondre les unes dans les autres et \u00e0 dispara&icirc;tre.<\/p>\n<\/p>\n<p><p>Ce consensus a \u00e9t\u00e9 d\u00e9crit avec grande lucidit\u00e9 par le ministre polonais des affaires \u00e9trang\u00e8res, Witold Waszczykowski, au <a href=\"http:\/\/www.bild.de\/bild-plus\/politik\/ausland\/polen\/hat-die-regierung-einen-vogel-44003034,var=a,view=conversionToLogin.bild.html\">journal allemand<\/a> <em>Bild <\/em>le 4 janvier : &laquo;Nous voulons simplement gu\u00e9rir notre pays de quelques maladies afin qu&rsquo;il puisse se remettre&raquo;, a-t-il dit.  Cette maladie viendrait du gouvernement pr\u00e9c\u00e9dent qui aurait &laquo;suivi un certain concept politique de gauche&raquo;: <\/p>\n<\/p>\n<p><p>&laquo;Comme si le monde ne devait automatiquement aller que dans un seul sens, selon un mod\u00e8le marxiste &ndash; un nouveau m\u00e9lange de cultures et de races, un monde de cyclistes et de v\u00e9g\u00e9tariens, qui ne mise que sur les \u00e9nergies renouvelables et combat toute forme de religion. Tout cela n&rsquo;a rien \u00e0 voir avec les racines polonaises traditionnelles&raquo;.<\/p>\n<\/p>\n<p><p>[A cette vision, le ministre opposait celle-ci, digne d&rsquo;un <a href=\"http:\/\/www.lefigaro.fr\/international\/2013\/09\/20\/01003-20130920ARTFIG00537-vladimir-poutine-croise-des-valeurs-chretiennes.php\">Vladimir Poutine<\/a> :] &laquo;Ce que veut la majorit\u00e9 des Polonais : les traditions, la conscience de son histoire, l&rsquo;amour de la patrie, la foi en Dieu, en une vie de famille normale entre un homme et une femme&raquo;.<\/p>\n<\/p>\n<p><p>Or, cette justification des r\u00e9formes en Pologne n&rsquo;est rien d&rsquo;autre qu&rsquo;une attaque frontale contre l&rsquo;id\u00e9ologie qui anime la construction europ\u00e9enne depuis la chute du rideau de fer.  En effet, celle-ci est pr\u00e9cis\u00e9ment bas\u00e9e sur une vision d\u00e9terministe et n\u00e9o-marxiste de l&rsquo;histoire, selon laquelle les nations ont in\u00e9vitablement tendance \u00e0 se fondre les unes dans les autres et \u00e0 dispara&icirc;tre, tout comme d&rsquo;autres structures sociales traditionnelles comme la famille. <\/p>\n<\/p>\n<p><p>Pour Marx comme pour la Commission de Bruxelles, c&rsquo;est le march\u00e9 qui doit faciliter et acc\u00e9l\u00e9rer ce processus: Marx soutenait le libre-\u00e9change en 1848 pour faire avancer la r\u00e9volution.  En 1989, cette id\u00e9ologie s&rsquo;est \u00e9croul\u00e9e de fa\u00e7on spectaculaire \u00e0 Berlin et en Europe de l&rsquo;Est. En Europe occidentale, en revanche, o&ugrave; le marxisme avait prosp\u00e9r\u00e9 pendant la Guerre froide dans la quasi totalit\u00e9 des universit\u00e9s, notamment \u00e0 partir des ann\u00e9es soixante, l&rsquo;effondrement de formes de pens\u00e9e directement h\u00e9rit\u00e9es du marxisme qui sont mises en &oelig;uvre aujourd&rsquo;hui par ceux qui ont grandi dans cette ambiance-l\u00e0,  se fait encore attendre.<\/p>\n<\/p>\n<p><h4>John Laughland<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;UE, la Pologne et le n\u00e9o-marxisme John Laughland, \u00e0 qui nous avons fait appel tr\u00e8s r\u00e9cemment, pour son commentaire sur les \u00e9v\u00e8nements du Jour de l&rsquo;An \u00e0 Cologne et ailleurs, est un intellectuel qui a affirm\u00e9 depuis longtemps ses opinions radicalement eurosceptiques en m\u00eame temps que sa propre position de conservateur britannique au sens ouvert&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[17304,7256,3961,5163,5444,17303,2722,17125,17305,16970],"class_list":["post-76369","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-honfrie","tag-jaroslaw","tag-john","tag-kaczynski","tag-laughland","tag-neo-marxisme","tag-orban","tag-pis","tag-traditionnaliste","tag-viktor"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76369"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76369\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}