{"id":76370,"date":"2016-01-21T07:50:35","date_gmt":"2016-01-21T07:50:35","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/01\/21\/lineluctabilite-de-passer-a-lest\/"},"modified":"2016-01-21T07:50:35","modified_gmt":"2016-01-21T07:50:35","slug":"lineluctabilite-de-passer-a-lest","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/01\/21\/lineluctabilite-de-passer-a-lest\/","title":{"rendered":"L&rsquo;in\u00e9luctabilit\u00e9 de \u201cpasser \u00e0 l&rsquo;Est\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">L&rsquo;in\u00e9luctabilit\u00e9 de \u00ab\u00a0passer \u00e0 l&rsquo;Est\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>21 janvier 2016 &ndash; Les Polonais ont beaucoup parl\u00e9 ces derniers jours. Apr\u00e8s les attaques lanc\u00e9es contre le nouveau gouvernement polonais par l&rsquo;UE, la Commission, etc., et les d\u00e9cisions de mettre la Pologne \u00ab\u00a0sous surveillance\u00a0\u00bb, le th\u00e8me g\u00e9n\u00e9ral de leurs discours, je dirais du point de vue symbolique, c&rsquo;est ceci : \u00ab\u00a0L&rsquo;UE d&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, la Commission, se conduisent vis-\u00e0-vis de nous exactement comme l&rsquo;URSS se conduisait vis-\u00e0-vis de la Pologne durant les ann\u00e9es o&ugrave; l&rsquo;Europe de l&rsquo;Est v\u00e9cut sous le contr\u00f4le de cette puissance\u00a0\u00bb. <a href=\"http:\/\/www.dedefensa.org\/article\/lue-la-pologne-et-le-neo-marxisme\">Laughland<\/a> va m\u00eame plus loin, et fort justement : &laquo; <em>La Commission de Bruxelles a donc moins de l\u00e9gitimit\u00e9 d\u00e9mocratique que ses presqu&rsquo;homonymes, les fameux Comit\u00e9s centraux des partis communistes qui jadis faisait la pluie et le beau temps en Europe de l&rsquo;Est<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>C&rsquo;\u00e9tait le temps o&ugrave; r\u00e9gnait la \u00ab\u00a0doctrine Brejnev\u00a0\u00bb, dite de \u00ab\u00a0souverainet\u00e9 limit\u00e9e\u00a0\u00bb, qui triomphait d\u00e9j\u00e0 en 1953 (Berlin-Est), en 1956 (Budapest) avant m\u00eame qu&rsquo;elle e&ucirc;t \u00e9t\u00e9 baptis\u00e9e comme on la conna&icirc;t, et enfin en 1968 (Prague) o&ugrave; elle nous fut clairement expos\u00e9e, par la dialectique des dirigeants sovi\u00e9tiques conduits par Brejnev et de leurs acolytes du Pacte de Varsovie (les Tusk d&rsquo;alors), et par les chars entrant en Tch\u00e9coslovaquie le 21 ao&ucirc;t 1968. (\u00ab\u00a0Souverainet\u00e9 limit\u00e9e\u00a0\u00bb, c&rsquo;\u00e9tait un de ces charmants oxymores, plut\u00f4t involontaires que po\u00e9tiques, comme on en voit tant aujourd&rsquo;hui au gr\u00e9 des <em>narrative<\/em> : comment la souverainet\u00e9, qui est un principe et comme tel quelque chose d&rsquo;irr\u00e9fragable dans sa nature et sa composition, pourrait-elle se concevoir comme \u00ab\u00a0limit\u00e9e\u00a0\u00bb ? On est souverain enti\u00e8rement ou on ne l&rsquo;est pas du tout.) Il est maintenant av\u00e9r\u00e9 que le sentiment des dirigeants polonais, qui s&rsquo;est impos\u00e9 dans leurs esprits en quelques semaines, est de plus en plus largement partag\u00e9, au moins par leurs complices du \u00ab\u00a0Groupe de Visegrad\u00a0\u00bb (outre la Pologne, la Hongrie, la Slovaquie et la Tch\u00e9quie) qui formaient du temps de l&rsquo;URSS l&rsquo;axe central et la voie strat\u00e9gique principale d&rsquo;une Europe de l&rsquo;Est contr\u00f4l\u00e9e par l&rsquo;URSS.<\/p>\n<\/p>\n<blockquote>\n<p><p>M\u00e9ditez et mesurez cette appr\u00e9ciation et tirez-en la force et la puissance symbolique. Pendant un demi-si\u00e8cle et peut-\u00eatre plus pour les nostalgiques du progressisme lib\u00e9ral occidentaliste qui ont gard\u00e9 toute leur vertu antisovi\u00e9tique transmut\u00e9e en hyper-vertu antirusse, l&rsquo;on a d\u00e9nonc\u00e9 l&#8217;emprise de cette oppression venue de leur Est sur ces pauvres pays centre-europ\u00e9ens qui d\u00e9pendaient jusqu&rsquo;en 1985-1989 de la cha&icirc;ne des Politburos jusqu&rsquo;\u00e0 celui de Moscou. On a m\u00eame jug\u00e9 \u00e9vident, sinon habile, de retrouver cette tendance imp\u00e9riale et oppressive \u00e0 l&rsquo;occasion de la crise ukrainienne, et les Polonais eux-m\u00eames, y compris les dirigeants du PiS, s&rsquo;y sont laiss\u00e9s prendre. Et que d\u00e9couvrent-ils aujourd&rsquo;hui ? Le vrai Politburo se trouve \u00e0 l&rsquo;Ouest, et plus du tout \u00e0 l&rsquo;Est. La Commission europ\u00e9enne, sous la direction \u00e9clair\u00e9e mais titubante 24 heures sur 24 de Juncker, s&rsquo;impose comme le bras arm\u00e9 de la nouvelle URSS de l&rsquo;Europe de l&rsquo;Est, comme elle s&rsquo;est impos\u00e9e comme une \u00e9manation \u00e0 peine fard\u00e9e de ce que fut l&rsquo;Allemagne du temps du <em>Reich<\/em> pour la Gr\u00e8ce.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Laissez les arguties politiques, les analyses m\u00e9tahistoriques, les consid\u00e9rations structur\u00e9es au reste du site <em>dedefensa.org<\/em>, et concentrez-vous sur la force du symbole pour ces pays qui ont subi ce qu&rsquo;ils ont subi. Imaginez leur stup\u00e9faction, la puissance du choc qu&rsquo;ils sont en train de subir alors qu&rsquo;ils s&rsquo;\u00e9taient tant r\u00e9jouis de leur entr\u00e9e dans l&rsquo;UE, autour de 2004, comme de l&rsquo;ach\u00e8vement de leur grande entreprise de lib\u00e9ration. Je soup\u00e7onne que la surench\u00e8re pro-ukrainienne et antirusse, pendant la crise ukrainienne, de certains de ceux que l&rsquo;on entend aujourd&rsquo;hui sur un registre si diff\u00e9rent constituait une tentative d\u00e9sesp\u00e9r\u00e9e de se dissimuler \u00e0 soi-m\u00eame la v\u00e9rit\u00e9-de-situation qui commen\u00e7ait \u00e0 se manifester quant \u00e0 leur v\u00e9ritable situation au sein de l&rsquo;UE : des vassaux asservis, des colonies \u00e0 la sauce postmoderne et une \u00ab\u00a0souverainet\u00e9 super-limit\u00e9e\u00a0\u00bb selon les canons de Bruxelles.<\/p>\n<\/p>\n<p><p>Ne vous y trompez pas, c&rsquo;est une r\u00e9volution psychologique qui est en cours dans ces pays, un formidable renversement impos\u00e9 \u00e0 la psychologie d\u00e9clench\u00e9 par la force de l&rsquo;aspect symbolique de l&rsquo;\u00e9pisode que nous sommes en train de vivre. L&rsquo;\u00e9v\u00e9nement est \u00e9norme, souterrainement, au-del\u00e0 des \u00e9changes convenus et des man&oelig;uvres doucereuses de couloir dans les arcanes de la bureaucratie. Bien s&ucirc;r, il y a beaucoup d&rsquo;autres crise pour l&rsquo;UE aujourd&rsquo;hui, par bonheur puisque cela signifie que le mod\u00e8le est en train d&rsquo;\u00eatre pulv\u00e9ris\u00e9 par toutes ses contradictions, ses pr\u00e9tentions, ses iniquit\u00e9s et son ill\u00e9gitimit\u00e9. Mais celle-l\u00e0 est vraiment tr\u00e8s importante, notamment par sa dimension symbolique engageant plus d&rsquo;un demi-si\u00e8cle d&rsquo;affirmation lib\u00e9ratrice proclam\u00e9e et brandie par le supr\u00e9macisme occidentaliste-am\u00e9ricaniste, et anglo-saxon particuli\u00e8rement, et europ\u00e9en-institutionnel pour notre affaire.<\/p>\n<\/p>\n<p><p>Mon sentiment est qu&rsquo;un \u00e9v\u00e9nement de rupture d&rsquo;une r\u00e9elle importance et d&rsquo;une force symbolique inou\u00efe est en cours de formation au sein de l&rsquo;Europe telle qu&rsquo;elle a \u00e9t\u00e9 bidouill\u00e9e par le gang bruxellois, les \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/la-necessaire-lutte-a-mort-avec-lorque\">Orques<\/a>\u00a0\u00bb de \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/redaction\/articles\/editer\/11212\">la Secte<\/a>\u00a0\u00bb comme on d\u00e9signait fort peu aimablement sur ce site les dirigeants de l&rsquo;UE lors du paroxysme de la crise grecque, en juillet dernier. La dynamique se d\u00e9roule encore \u00e0 fleurets mouchet\u00e9s, avec une volont\u00e9 de ne rien dramatiser, ni d&rsquo;un c\u00f4t\u00e9 ni de l&rsquo;autre, mais elle d&rsquo;une puissance consid\u00e9rable qui ne tardera pas \u00e0 donner \u00e0 plein. Je crois bien que, dans cette partie, la disproportion des forces structurelles (en faveur de l&rsquo;UE) est largement compens\u00e9e par la faiblesse conjoncturelle extraordinaire d&rsquo;une UE frapp\u00e9e de nombre de crises, de toutes les sortes et de tous les c\u00f4t\u00e9s possibles, que sa nature invertie et d\u00e9structurante a cr\u00e9\u00e9es.<\/p>\n<\/p>\n<p><p>Certes, les Polonais et leurs comp\u00e8res du \u00ab\u00a0Groupe de Visegrad\u00a0\u00bb vont subir des assauts frontaux et r\u00e9p\u00e9t\u00e9s. Pour l&rsquo;UE aux abois confront\u00e9e \u00e0 ces crises totalement insolubles o&ugrave; elle est totalement impuissante (notamment les migrants-r\u00e9fugi\u00e9s et la saga de la mise \u00e0 mort de Schengen), et parce que l&rsquo;UE vit dans un monde d\u00e9lirant o&ugrave; elle croit pouvoir soumettre le monde d\u00e8s lors qu&rsquo;elle peut asseoir sa petite vertu sur les \u00ab\u00a0principes\u00a0\u00bb sacr\u00e9s de notre contre-civilisation, la crise de l&rsquo;Europe de l&rsquo;Est para&icirc;t \u00e0 son esprit court une fa\u00e7on \u00e0 assez bon compte de tenter de r\u00e9tablir ce pouvoir jug\u00e9 extraordinaire, et qui pourtant se d\u00e9lite \u00e0 grande vitesse. Il en r\u00e9sultera une aggravation de la querelle, et cela tr\u00e8s, tr\u00e8s vite, parce que, <em>bis repetitat<\/em>, l&rsquo;UE est aux abois, et la voie tr\u00e8s-grande ouverte \u00e0 la rupture. On en saura un peu plus, assez rapidement \u00e0 mon sens, par exemple lorsque monsieur Poutine d\u00e9barquera \u00e0 Varsovie, invit\u00e9 pour une visite d&rsquo;&Eacute;tat chaleureuse et si prometteuse. C&rsquo;est normal : l&rsquo;Europe de l&rsquo;Est, si  elle veut \u00ab\u00a0choisir la libert\u00e9\u00a0\u00bb comme au temps de la Guerre froide, n&rsquo;a plus qu&rsquo;\u00e0 se tourner vers son Est.<\/p>\n<\/p>\n<p><p>Le fant\u00f4me du pass\u00e9, &ndash; la Guerre froide et la \u00ab\u00a0souverainet\u00e9 limit\u00e9e\u00a0\u00bb, &ndash; a donc resurgi effectivement. Cela ne se passait pas en Ukraine. Cela se passe aujourd&rsquo;hui, sur notre Est doublement appr\u00e9ci\u00e9, et le fant\u00f4me est celui de l&rsquo;inversion achev\u00e9e et de la mise \u00e0 nu de la v\u00e9rit\u00e9-de-situation de notre contre-civilisation. En 1956 ou en 1968, ou \u00ab\u00a0passait \u00e0 l&rsquo;Ouest\u00a0\u00bb, et c&rsquo;\u00e9tait la libert\u00e9 (on le croyait, certes oui, et moi-m\u00eame y ait cru) ; aujourd&rsquo;hui, <strong>\u00ab\u00a0on passe \u00e0 l&rsquo;Est\u00a0\u00bb<\/strong>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;in\u00e9luctabilit\u00e9 de \u00ab\u00a0passer \u00e0 l&rsquo;Est\u00a0\u00bb 21 janvier 2016 &ndash; Les Polonais ont beaucoup parl\u00e9 ces derniers jours. Apr\u00e8s les attaques lanc\u00e9es contre le nouveau gouvernement polonais par l&rsquo;UE, la Commission, etc., et les d\u00e9cisions de mettre la Pologne \u00ab\u00a0sous surveillance\u00a0\u00bb, le th\u00e8me g\u00e9n\u00e9ral de leurs discours, je dirais du point de vue symbolique, c&rsquo;est ceci&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[4461,3228,2631,3067,17306,2645,4614,3574,3555,2827,6232,2746,2828,2609,13674,14524],"class_list":["post-76370","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-brejnev","tag-crise","tag-de","tag-doctrine","tag-froideeurope","tag-guerre","tag-juncker","tag-lest","tag-legitimite","tag-pologne","tag-quatre","tag-souverainete","tag-tusk","tag-ue","tag-ukrainienne","tag-visegrad"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76370"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76370\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}