{"id":76441,"date":"2016-02-27T12:34:50","date_gmt":"2016-02-27T12:34:50","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/02\/27\/flynn-avec-the-donald\/"},"modified":"2016-02-27T12:34:50","modified_gmt":"2016-02-27T12:34:50","slug":"flynn-avec-the-donald","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/02\/27\/flynn-avec-the-donald\/","title":{"rendered":"Flynn avec <em>The Donald<\/em> ?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Flynn avec <em>The Donald <\/em> ?<\/h2>\n<\/p>\n<p><p>Si l&rsquo;on a beaucoup parl\u00e9 de sa personnalit\u00e9 et de ses performances, on a jusqu&rsquo;ici fort peu parl\u00e9 de l'\u00a0\u00bb\u00e9quipe\u00a0\u00bb, notamment de s\u00e9curit\u00e9 nationale, qu&rsquo;a constitu\u00e9, ou qu&rsquo;est en train de constitue qui sait, celui qui appara&icirc;t d\u00e9sormais comme le grand favori \u00e0 la nomination du parti r\u00e9publicain pour les pr\u00e9sidentielles. (Avec un premier soutien officiel de poids, celui de son ancien adversaire, le gouverneur du New Jersey Chris Christie, &ndash; ce qui a provoqu\u00e9 des remous consid\u00e9rables dans l&rsquo;<em><a href=\"http:\/\/www.washingtonexaminer.com\/shock-disgust-in-right-leaning-media-after-christies-endorsement\/article\/2584403\">establishment<\/a><\/em> et la <a href=\"http:\/\/www.washingtonexaminer.com\/ny-daily-news-previews-front-page-christie-man-with-a-klan\/article\/2584411\">presse-Syst\u00e8me<\/a>.) Trump a promis au d\u00e9but f\u00e9vrier qu&rsquo;il d\u00e9voilerait \u00ab\u00a0prochainement\u00a0\u00bb la composition cette \u00e9quipe&#8230; En attendant, un nom circule, comme \u00e9tant celui d&rsquo;un de ses conseillers : <strong>le d\u00e9sormais tr\u00e8s-fameux g\u00e9n\u00e9ral Michael Flynn, ancien directeur de la DIA, dont nous avons <a href=\"http:\/\/www.dedefensa.org\/article\/daesh-desordre-et-le-general-flynn-en-vedette-americaine\">beaucoup<\/a> <a href=\"http:\/\/www.dedefensa.org\/article\/jecris-ton-nom-trahison\">parl\u00e9<\/a><\/strong>. C&rsquo;est Reuters qui donne la nouvelle concernant cette rumeur, dans une d\u00e9p\u00eache <a href=\"http:\/\/www.reuters.com\/article\/us-usa-election-trump-advisor-idUSMTZSAPEC2Q6G3JRH\">dat\u00e9e du 26 f\u00e9vrier<\/a>. (Voir aussi <a href=\"http:\/\/fr.sputniknews.com\/international\/20160227\/1022796365\/conseiller-trump-renouer-russie-flynn.html#ixzz41Ml3V972\">un compte-rendu<\/a> de la nouvelle sur <em>Sputnik<\/em>-fran\u00e7ais.)<\/p>\n<\/p>\n<blockquote>\n<p><p>En tout \u00e9tat de cause, &ndash; c&rsquo;est-\u00e0-dire information confirm\u00e9e ou pas, &ndash; la pr\u00e9sence d&rsquo;un Flynn au c\u00f4t\u00e9 de Trump ne serait ni illogique ni surprenante, puisque la principale surprise qui est de devoir d\u00e9sormais consid\u00e9rer Trump comme un futur pr\u00e9sident potentiel semble d\u00e9sormais avoir donn\u00e9 nombre de ses effets. Flynn vient de la DIA, c&rsquo;est un homme \u00ab\u00a0de la famille\u00a0\u00bb ; et l&rsquo;on a vu combien cette \u00ab\u00a0famille\u00a0\u00bb-l\u00e0 <a href=\"http:\/\/www.dedefensa.org\/article\/la-dia-et-le-premier-cercle-de-bho\">est fondamentalement hostile<\/a> \u00e0 la politique d&rsquo;Obama, notamment au Moyen-Orient et en Syrie, et donc inclin\u00e9e \u00e0 <strong>soutenir autant que faire se peut un candidat qui consid\u00e9rerait la possibilit\u00e9 de la modifier d&rsquo;une fa\u00e7on significative, ce qui pourrait sinon devrait \u00eatre le cas de Trump<\/strong>. Et puisque nous y sommes, il faut aussi rappeler que Flynn \u00e9tait \u00e0 Moscou, le 10 d\u00e9cembre 2015, <a href=\"http:\/\/www.dedefensa.org\/article\/la-cia-et-la-dia-au-10e-anniversaire-de-rt\">l&rsquo;un des orateurs<\/a> du s\u00e9minaire organis\u00e9 pour le 10<sup>\u00e8me<\/sup> anniversaire de Russia Today (RT), et qu&rsquo;il \u00e9tait plac\u00e9, lors du d\u00e9jeuner offert aux personnalit\u00e9s, \u00e0 la table o&ugrave; se trouvait, imm\u00e9diatement \u00e0 sa droite, le pr\u00e9sident Poutine. L\u00e0-dessus, sept jours plus tard lors d&rsquo;une conf\u00e9rence de presse, <strong>Poutine <a href=\"http:\/\/www.dedefensa.org\/article\/la-connivencele-complot-poutine-the-donald\">r\u00e9pondait avec entrain<\/a> \u00e0 une question d&rsquo;un journaliste concernant la candidature de Donald Trump, par des \u00e9loges appuy\u00e9es du candidat, ou dans tous les cas de sa position<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Reuters : &laquo; <em>Donald Trump is receiving foreign policy advice from a former U.S. military intelligence chief who wants the United States to work more closely with Russia to resolve global security issues, according to three sources. The sources, former foreign policy officials in past administrations, said retired Lieutenant General Michael Flynn, who was chief of the Defense Intelligence Agency under President Barack Obama from 2012-2014, has been informally advising Trump. Trump, who is leading the Republican race to be the party&rsquo;s presidential candidate in November&rsquo;s election, said earlier this month that he would soon release a list of his foreign policy advisers, but has yet to do so. The Trump campaign did not respond to a request for comment about Flynn<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Flynn declined to comment when asked by Reuters whether he is advising Trump. Asked to describe his views about ties with Russia, he referred Reuters to his public statements<\/em>. [&#8230;] <em>A close associate of Flynn said that Trump was not the only presidential hopeful who had consulted the former DIA chief.  \u00ab\u00a0He responds to one and all but is not working for any one,\u00a0\u00bb the associate said.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Mis en ligne le 27 f\u00e9vrier 2016 \u00e012H34<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flynn avec The Donald ? Si l&rsquo;on a beaucoup parl\u00e9 de sa personnalit\u00e9 et de ses performances, on a jusqu&rsquo;ici fort peu parl\u00e9 de l&rsquo;\u00a0\u00bb\u00e9quipe\u00a0\u00bb, notamment de s\u00e9curit\u00e9 nationale, qu&rsquo;a constitu\u00e9, ou qu&rsquo;est en train de constitue qui sait, celui qui appara&icirc;t d\u00e9sormais comme le grand favori \u00e0 la nomination du parti r\u00e9publicain pour les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[3032,2926,916,4105,12756,2639],"class_list":["post-76441","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-dia","tag-flynn","tag-poutine","tag-reuters","tag-rt","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76441"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76441\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}