{"id":76515,"date":"2016-04-10T12:13:27","date_gmt":"2016-04-10T12:13:27","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/04\/10\/nos-atrides-et-leurs-petits-arrangements-familiaux\/"},"modified":"2016-04-10T12:13:27","modified_gmt":"2016-04-10T12:13:27","slug":"nos-atrides-et-leurs-petits-arrangements-familiaux","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/04\/10\/nos-atrides-et-leurs-petits-arrangements-familiaux\/","title":{"rendered":"Nos Atrides et leurs petits arrangements familiaux"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Nos Atrides et leurs petits arrangements familiaux<\/h2>\n<\/p>\n<p><p>Ils disent d&rsquo;Hom\u00e8re qu&rsquo;il a \u00e9t\u00e9 aveugle.<\/p>\n<\/p>\n<p><p>S&ucirc;rement, le po\u00e8te, ce voyant, est plong\u00e9 dans les t\u00e9n\u00e8bres de la c\u00e9cit\u00e9 \u00e0 ce qui est visible pour l&rsquo;&oelig;il.<\/p>\n<\/p>\n<p><p>Plus s&ucirc;rement encore, ce qu&rsquo;il a dit de la trag\u00e9die des Atrides, le meurtre d&rsquo;Agamemnon par sa femme Clytemnestre, puis de celle-ci par Oreste son fils n&rsquo;est qu&rsquo;un travestissement tr\u00e8s romanc\u00e9 d&rsquo;une r\u00e8gle successorale qui avait cours dans les soci\u00e9t\u00e9s antiques parmi les lign\u00e9es royales.<\/p>\n<\/p>\n<p><p>Lorsque les circonstances l&rsquo;exigeaient, et sans doute \u00e0 intervalle r\u00e9gulier, le roi \u00e9tait soumis \u00e0 une \u00e9preuve physique et parfois intellectuelle. La communaut\u00e9 des r\u00e9gis v\u00e9rifiait si la puissance royale \u00e9tait bien incarn\u00e9e et dans le cas contraire \u00e9lisait \u00e0 la fonction royale un autre de ses membres, fort et intelligent. Au terme d&rsquo;un combat singulier, le vaincu p\u00e9rissait. Le vainqueur devait alors \u00e9pouser une femme d\u00e9tentrice d&rsquo;une puissance mystique d&rsquo;origine divine. Il s&rsquo;unit alors plut\u00f4t qu&rsquo;\u00e0 la fille du roi, \u00e0 la fille de la femme du roi qui est dot\u00e9e de cette myst\u00e9rieuse puissance. La succession se fait de beau-p\u00e8re \u00e0 gendre qui devient le meurtrier du roi d\u00e9chu, \u00ab\u00a0l&rsquo;autorit\u00e9 spirituelle\u00a0\u00bb est transmise sur le mode matrilin\u00e9aire.<\/p>\n<\/p>\n<p><p>Des facteurs de stabilit\u00e9 politique mais plus encore d&rsquo;ambition et d&rsquo;\u00e9go\u00efsme sont venus perturber cette tradition d&rsquo;importation r\u00e9guli\u00e8re de nouveaux pr\u00e9tendants \u00e9trangers au noyau familial royal. Deux branches d&rsquo;une m\u00eame famille passent une entente pour se maintenir sur le tr\u00f4ne en alternance. La trag\u00e9die des Atrides transmise par Hom\u00e8re et retranscrite par Eschyle n&rsquo;est rien d&rsquo;autre qu&rsquo;une histoire de d\u00e9tournement d&rsquo;une r\u00e8gle, dilat\u00e9e \u00e0 la dimension d&rsquo;un mythe, c&rsquo;est en quelque sorte  de l&rsquo;historiographie hagiographique.<\/p>\n<\/p>\n<p><p>Atr\u00e9e et Thyeste sont fr\u00e8res.<\/p>\n<\/p>\n<p><p>Egisthe fils de Thyeste est apte \u00e0 remplacer Agamemnon.<\/p>\n<\/p>\n<p><p>Oreste fils d&rsquo;Agamemnon \u00e0 son tour peut remplacer Thyeste.<\/p>\n<\/p>\n<p><p>Les fins funestes des rois parvenus au terme de leur carri\u00e8re restent en coh\u00e9rence avec les r\u00e8gles successorales. Mais elles sont d\u00e9j\u00e0 fauss\u00e9es par le trafic symbolique op\u00e9r\u00e9 par une famille qui s&rsquo;arroge la perp\u00e9tuation d&rsquo;une d\u00e9l\u00e9gation transform\u00e9e en une domination qui perd la traces de ses origines dans la nuit hom\u00e9rique.<\/p>\n<\/p>\n<p><p>La tradition de la d\u00e9tention du pouvoir politique par un petit nombre de familles se retrouve plus tard  \u00e0 l&rsquo;\u00e9poque des monarchies europ\u00e9ennes. Les diff\u00e9rentes dynasties europ\u00e9ennes au travers de leurs alliances matrimoniales crois\u00e9es et enchev\u00eatr\u00e9es n&rsquo;en constituaient plus qu&rsquo;une seule. L&rsquo;institution britannique a \u00e9t\u00e9 mise en p\u00e9ril par l&rsquo;exub\u00e9rante frivolit\u00e9 d&rsquo;un Charles Ier, insensible aux remontrances de son Parlement r\u00e9volt\u00e9 par des taxes abusives et des guerres dispendieuses conseill\u00e9es par son amant le duc de Buckingham. L&rsquo;\u00e9mergence d&rsquo;une classe industrieuse capitaliste fit le reste.<\/p>\n<\/p>\n<p><p>Une monarchie constitutionnelle fut adopt\u00e9e en 1716 et d\u00e9j\u00e0 s&rsquo;installait le syst\u00e8me du bipartisme. M\u00eame consid\u00e9r\u00e9e de droit divin, la monarchie se devait de fonctionner avec un assentiment en principe populaire, celui du ou des Parlements. L&rsquo;abolition de la monarchie en 1789 en France est aussi le terme d&rsquo;un long processus. La mise \u00e0 mort d&rsquo;un roi d\u00e9fectueux et inapte eut lieu \u00e0 nouveau en revivifiant un principe archa\u00efque. Car guerroyer pour occuper une aristocratie d&rsquo;origine et de l\u00e9gitimit\u00e9 chevaleresques dont l&rsquo;arme \u00e9tait le m\u00e9tier et la justification a trop lourdement endett\u00e9 le pays. Ceux qui d\u00e9tenaient le pouvoir \u00e9conomique en eurent assez que 20 millions entretinssent deux mille oisifs. Comme par un ph\u00e9nom\u00e8ne naturel de scissiparit\u00e9, naquirent alors les Montagnards et les Girondins, pr\u00e9figuration de la Droite et de la Gauche.<\/p>\n<\/p>\n<p><p>Les D\u00e9mocratures occidentales et leurs copies fonctionnent ainsi.<\/p>\n<\/p>\n<p><p>Les \u00e9lections sont des \u00e9preuves de force et de rouerie avec des mises \u00e0 mort symboliques, quelquefois sanglantes et d\u00e9loyales, au d\u00e9cours d&rsquo;assassinats, quand le chef a d\u00e9m\u00e9rit\u00e9 aux yeux de ses affid\u00e9s. Le pouvoir reste aux mains du m\u00eame groupe avec des alternances de deux branches dont l&rsquo;individuation devient de plus en plus difficile \u00e0 d\u00e9m\u00ealer tant les relations id\u00e9ologiques incestueuses qu&rsquo;elles cultivent les a rendues indiscernables.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Atr\u00e9e et Thyeste et leurs p\u00e2les rejetons Sark\u00f6zy et Hollande<\/h2>\n<\/p>\n<p><p>Les m\u00eames r\u00e8gnent mais sous r\u00e9gime d&rsquo;alternance sans alternative pour \u00e9viter les effets de r\u00e9sistance. L&rsquo;actuel monarque de la province europ\u00e9enne France, affair\u00e9 par ses scooters autant que l&rsquo;\u00e9tait Louis XVI par ses serrures, a jug\u00e9 <a href=\"http:\/\/www.lefigaro.fr\/vox\/politique\/2016\/03\/29\/31001-20160329ARTFIG00134-temps-de-parole-signature-la-presidentielle-verrouillee.php\">inutile de faire concourir<\/a> les pr\u00e9tendants qui n&rsquo;\u00e9taient admis que pour le nuage de poussi\u00e8re \u00e9mis quand on la leur faisait mordre. Le Parlement n&rsquo;est plus consult\u00e9, ses membres sont absents et donc consentants.<\/p>\n<\/p>\n<p><p>Le Peuple ?<\/p>\n<\/p>\n<p><p>Ce truc informe tant qu&rsquo;il n&rsquo;est pas structur\u00e9 pour se constituer en force politique, on lui sert des l\u00e9gendes. De celles qui forgent la conscience commune, l&rsquo;adh\u00e9sion \u00e0 la repr\u00e9sentation du monde et la pleine acceptation du r\u00f4le distribu\u00e9 \u00e0 chacun.<\/p>\n<\/p>\n<p><p>Il n&rsquo;a qu&rsquo;\u00e0 bien se tenir.<\/p>\n<\/p>\n<p><p>Le pays n&rsquo;est-il donc pas en guerre ?<\/p>\n<\/p>\n<p><p>Le Peuple ne s&rsquo;en est pas aper\u00e7u, mais il en pleut comme \u00e0 Gravelotte. Pas moins de onze attentats auraient \u00e9t\u00e9 <a href=\"http:\/\/www.lefigaro.fr\/actualite-france\/2016\/03\/25\/01016-20160325ARTFIG00001-un-projet-d-attentat-avance-dejoue-en-france.php)\">d\u00e9jou\u00e9s en 2015<\/a>. Avec une telle p\u00e9riodicit\u00e9, il deviendra judicieux de s&rsquo;enqu\u00e9rir des lieux \u00e0 \u00e9viter comme se consulte presque n\u00e9gligemment le bulletin m\u00e9t\u00e9orologique avant de d\u00e9cider de la mise vestimentaire du jour. La r\u00e9p\u00e9tition induit la mithridatisation des esprits face au spectacle des corps d\u00e9chiquet\u00e9s. Les bombes n&rsquo;explosent plus dans des contr\u00e9es \u00e9loign\u00e9es o&ugrave; la &lsquo;chose terroriste&rsquo; est admissible mais dans l&rsquo;ici m\u00eame occidental.<\/p>\n<\/p>\n<p><p>L&rsquo;ici m\u00eame est \u00e0 peine sorti de sa longue cong\u00e9lation de la Guerre Froide d&rsquo;o&ugrave; \u00e9tait guett\u00e9e de ce c\u00f4t\u00e9 du rideau les chars de l&rsquo;Arm\u00e9e Rouge. Ils ne venaient jamais. Ils ne pouvaient venir car cette menace est une des escroqueries et machinations politiques les plus abouties de l&rsquo;histoire. D\u00e8s 1943, et plus encore en 1944, les USA et Churchill savaient que l&rsquo;URSS avait \u00e9t\u00e9 rendue exsangue par le combat qu&rsquo;elle avait men\u00e9e contre les centaines de divisions nazies, quand il y en avait quelques dizaines seulement sur le front de l&rsquo;Ouest. Jusqu&rsquo;\u00e0 la dissolution de l&rsquo;Union, en raison de l&rsquo;\u00e9quilibre des armes nucl\u00e9aires dissuasives, de part et d&rsquo;autre, aucune tentative de franchissement des lignes de d\u00e9marcation entre les deux zones d&rsquo;influence n&rsquo;a \u00e9t\u00e9 envisag\u00e9e.<\/p>\n<\/p>\n<p><p>Maintenant, le feu est port\u00e9 au sein des d\u00e9mocraties de repr\u00e9sentation jusque l\u00e0 \u00e0 peu pr\u00e8s \u00e9pargn\u00e9es des flammes qu&rsquo;elles dispensent partout o&ugrave; leurs int\u00e9r\u00eats les plus triviaux et les plus n\u00e9cessaires les ont dirig\u00e9es. Pourtant, il ne s&rsquo;agit que des effets en retour \u00e0 peine lointains du grand pi\u00e8ge dress\u00e9 en Afghanistan d\u00e8s 1979 et qui devait revenir au Pakistan comme province du Nord en troph\u00e9e de sa participation. La partition jou\u00e9e par le pays des Purs sous la houlette des princes S\u00e9oud soucieux de complaire \u00e0 un clerg\u00e9 wahabbite dont une partie appr\u00e9cie peu la pr\u00e9sence occidentale en Arabie et l&rsquo;adoption de son mode de vie et de consommation. L&rsquo;expression de la contestation du pouvoir corrompu des S\u00e9oud culmina lors de l&rsquo;occupation de la grande mosqu\u00e9e de la Mecque durant deux semaines en novembre et d\u00e9cembre 1979 par un groupe issu de la mouvance salafiste r\u00e9prim\u00e9e dans les ann\u00e9es 1930 al Jamaa Salafia al Mouhtasiba men\u00e9 par Juhaima ai Outaybi. 1979, c&rsquo;est aussi l&rsquo;ann\u00e9e de la R\u00e9volution iranienne qui a install\u00e9 un r\u00e9gime th\u00e9ocratique musulman. Son mode d&rsquo;installation r\u00e9sultant d&rsquo;un formidable \u00e9lan populaire est dou\u00e9 d&rsquo;un potentiel s\u00e9ducteur pour les peuples musulmans, et combattre les communistes en Afghanistan aurait r\u00e9duit alors son attractivit\u00e9. Les S\u00e9oud redor\u00e8rent n\u00e9anmoins en Afghanistan aux yeux des plus myopes des musulmans leur blason de h\u00e9rauts de l&rsquo;Islam contre les impies marxistes et se d\u00e9barrass\u00e8rent de fanatiques et de jeunes lumpen pr\u00eats \u00e0 s&rsquo;engager militairement.<\/p>\n<\/p>\n<p><p>Mais les &laquo; Afghans &raquo; venus d&rsquo;Alg\u00e9rie et de plusieurs pays europ\u00e9ens n&rsquo;y ont pas tous perdu la vie. Une fois les derni\u00e8res troupes sovi\u00e9tiques parties et la d\u00e9sagr\u00e9gation du Parti populaire d\u00e9mocratique afghan accomplie, ils ont reflu\u00e9 pour certains dans leurs pays d&rsquo;origine. Les maquis islamistes takfiri dans les montagnes alg\u00e9riennes des ann\u00e9es 90 en ont \u00e9t\u00e9 les escarboucles sanglantes. Ils allaient viser un \u00e0 un tous les Etats plus ou moins non align\u00e9s. Et le Pakistan encore \u00e0 ce jour tra&icirc;ne cet h\u00e9ritage <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Attentats_li%C3%A9s_%C3%A0_l%27insurrection_islamiste_au_Pakistan\">comme encore hier<\/a> sous forme de meurtres de masse. De plus, le transit du commerce des d\u00e9riv\u00e9s opiac\u00e9s afghans repris \u00e0 grande \u00e9chelle par les Talibans sur son territoire appartient \u00e0 la s\u00e9rie des contrecoups qu&rsquo;il subit. Mais l&rsquo;Iran puis la Russie constituent la premi\u00e8re destination de cette drogue. Les guerres de l&rsquo;opium de l&rsquo;\u00e9poque coloniale anglaise en Chine reviennent quasi-automatiquement en m\u00e9moire.<\/p>\n<\/p>\n<p><p>Si l&rsquo;on s&rsquo;en tient aux r\u00e9sultats de son activit\u00e9, al Qa\u00efda est encore un objet de la CIA.<\/p>\n<\/p>\n<p><p>A aucun moment, elle n&rsquo;a port\u00e9 atteinte aux int\u00e9r\u00eats de l&#8217;empire anglo-saxon pas plus qu&rsquo;\u00e0 ceux de l&rsquo;entit\u00e9 sioniste. C&rsquo;est apr\u00e8s le d\u00e9part du gros des troupes \u00e9tasuniennes d&rsquo;Irak en 2011 qu&rsquo;elle refait parler d&rsquo;elle en terme d&rsquo;organisation qui ambitionne d&rsquo;\u00e9riger un proto-\u00e9tat th\u00e9ocratique. Les proclamations et les attentat-suicides \u00e9manant de cette n\u00e9buleuse \u00e9taient <a href=\"file:\/\/localhost\/)%20%20http\/::www.iris-france.org:wp-content:uploads:2014:11:2007_alqaida.pdf\">dirig\u00e9s contre les chiites<\/a>, processions, lieux de p\u00e8lerinage, mosqu\u00e9es et march\u00e9s des quartiers essentiellement chiites.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Notre ici, lit de l\u00e9gendes en toc<\/h2>\n<\/p>\n<p><p>O&ugrave; donc se terrent les terroristes dormants ou \u00e9veill\u00e9s ?<\/p>\n<\/p>\n<p><p>Une veille syst\u00e9matique de plusieurs dizaines de lieux de culte musulman a \u00e9t\u00e9 mise en place depuis la refonte des services de Renseignements institu\u00e9e sous l&rsquo;impulsion du gouvernement Sarkozy en 2008. Tous les vendredi soir, une cellule sp\u00e9cialis\u00e9e du DCRI dispose des pr\u00eaches \u00e9nonc\u00e9s dans des mosqu\u00e9es et en analyse les th\u00e9matiques. Ils sont analys\u00e9s pour y rechercher des propos &lsquo;de nature \u00e0 troubler l&rsquo;ordre public&rsquo; en particulier l&rsquo;\u00e9vocation de la colonisation de la Palestine. Entre 2005 et 2010, dix-huit pr\u00e9dicateurs &laquo; pr\u00eacheurs de haine &raquo; <a href=\"http:\/\/www.leparisien.fr\/faits-divers\/43-mosquees-sous-surveillance-20-09-2010-1075261.php#xtref=https%3A%2F%2Fwww.google.fr%2F\">ont \u00e9t\u00e9 expuls\u00e9s<\/a>. Certains d\u00e9noncent une insuffisance des moyens attribu\u00e9s \u00e0 la surveillance de l&rsquo; &laquo; Islam de France &raquo; quand les Imams eux-m\u00eames sont mis \u00e0 contribution et <a href=\"http:\/\/www.la-croix.com\/Religion\/Actualite\/En-France-on-est-bien-loin-de-surveiller-toutes-les-mosquees-2013-06-03-968185\">renseignent la police<\/a> en lui signalant les fid\u00e8les qu&rsquo;ils soup\u00e7onnent de radicalisation.<\/p>\n<\/p>\n<p><p>Les dispositifs de surveillance, selon l&rsquo;expression foucaldienne, existent et sont fonctionnels. Au d\u00e9but du si\u00e8cle dernier, les cafetiers maures se voyaient octroyer leur licence en \u00e9change d&rsquo;un certain encadrement de la population immigr\u00e9e. Il semble loisible d&rsquo;imaginer que le permis d&rsquo;imamat se n\u00e9gocie selon les m\u00eames modalit\u00e9s. Observons \u00e0 cette occasion que la vraie r\u00e8gle islamique est que la conduite de la pri\u00e8re du vendredi est traditionnellement attribu\u00e9e de fa\u00e7on consensuelle par la communaut\u00e9 des fid\u00e8les au plus m\u00e9ritant et\/ou savant parmi eux. Elle n&rsquo;\u00e9tait pas consid\u00e9r\u00e9e comme un m\u00e9tier, n&rsquo;\u00e9tait pas r\u00e9tribu\u00e9e et ne s&rsquo;exer\u00e7ait pas toute une vie, jusqu&rsquo;\u00e0 l&rsquo;ing\u00e9rence r\u00e9cente du pouvoir politique dans la plupart des pays musulmans.<\/p>\n<\/p>\n<p><p>L&rsquo;efficacit\u00e9 du renseignement par un tel quadrillage n&rsquo;est pas  \u00e0 mettre en doute.<\/p>\n<\/p>\n<p><p>Les volontaires pour le &laquo; Jihad &raquo; en Syrie (il est \u00e0 noter que le surgeon d&rsquo;Al Qa\u00efda tant qu&rsquo;il fut cantonn\u00e9 \u00e0 l&rsquo;Irak n&rsquo;a pas suscit\u00e9 de vocations en externe) se seraient fait recruter selon deux voies, dans les mosqu\u00e9es ou par des fili\u00e8res sur Internet. Des milliers de Fran\u00e7ais ont \u00e9t\u00e9 s\u00e9duits par la propagande wahhabite, attir\u00e9s par une aventure plus exaltante que les jeux vid\u00e9o o&ugrave; les guerres et l&rsquo;h\u00e9moglobine ne sont que virtuelles ou par des salaires all\u00e9chants ou enfin les deux. Mais Fabius y \u00e9tait aussi all\u00e9 de sa &laquo; fatwa &raquo; en d\u00e9clarant que &laquo; Bachar ne m\u00e9ritait pas de vivre sur terre &raquo;. Quoi de plus rassurant que d&rsquo;avoir l&rsquo;appui et des ma&icirc;tres de La Mecque et du serviteur de Sion ?<\/p>\n<\/p>\n<p><p>Les dispositifs veilleurs ont collig\u00e9 des noms et des trajectoires.<\/p>\n<\/p>\n<p><p>Pourtant, le portrait des jeunes gens tel qu&rsquo;il est donn\u00e9 par la presse qui construit les nouvelles l\u00e9gendes populaires \u00e0 usage &laquo; p\u00e9dagogique &raquo; puis les donne \u00e0 absorber sous forme d&rsquo;opinion n&rsquo;est pas congruent avec le profil de musulmans radicalis\u00e9s. Des d\u00e9linquants, f\u00eatards volontiers flambeurs avec souvent des addictions \u00e0 des substances psychotropes. Les s\u00e9jours par la prison ne sont pas syst\u00e9matiques, aussi, leur endoctrinement et leur recrutement ne se serait pas effectu\u00e9s en milieu p\u00e9nitencier de fa\u00e7on \u00e9lective.<\/p>\n<\/p>\n<p><p>Un mouvement sectaire et messianique qui rappelle plus le n\u00e9o-\u00e9vang\u00e9lisme puritain d&rsquo;outre-Atlantique a persuad\u00e9s ces jeunes lumpenis\u00e9s par la d\u00e9sindustralisation de quitter l&rsquo;enfer terrestre dans lequel ils se meuvent sans perspective pour atteindre un paradis mat\u00e9riel au-del\u00e0, au point d&rsquo;obtenir d&rsquo;eux le sacrifice supr\u00eame. Le suicide pour la Cause les an\u00e9antira mais exaltera une image d&rsquo;eux-m\u00eames bien ternie pas le deal du cannabis et le prox\u00e9n\u00e9tisme.  Le souvenir toujours pr\u00e9gnant des traditions sociales du lieu d&rsquo;\u00e9migration familiale est raviv\u00e9 par le pr\u00eache des agents recruteurs et permet le court-circuit de la &lsquo;conversion&rsquo;, de la table rase de l&rsquo;effacement des p\u00e9ch\u00e9s.<\/p>\n<\/p>\n<p><p>La globalisation des techniques polici\u00e8res et les relations de d\u00e9pendance en mati\u00e8re de s\u00e9curit\u00e9 et de renseignement des provinces europ\u00e9ennes vis-\u00e0-vis des USA conduiraient \u00e0 extrapoler que le modus operandi du FBI est \u00e9tendu au vieux continent. On se souvient des escadrons de la mort d&rsquo;Am\u00e9rique latine, de &laquo; l&rsquo;\u00e9cole des Am\u00e9riques &raquo; de Panama, du terrorisme Gladio en Europe et des m\u00e9thodes du FBI pour liquider aux &laquo; States &raquo; les mouvements d&rsquo;\u00e9mancipation noirs, am\u00e9rindiens et estudiantins au moment de la guerre du Viet-nam. On pourrait affecter chacun des appel\u00e9s europ\u00e9ens au &laquo; Djihadisme &raquo; d&rsquo;un coefficient Merah. Cet indice r\u00e9sulterait d&rsquo;une combinaison pond\u00e9r\u00e9e faite de leur niveau de d\u00e9linquance et criminalit\u00e9, elle-m\u00eame proportionnelle \u00e0 leur susceptibilit\u00e9 \u00e0 la pression polici\u00e8re pour devenir indicateur. La dur\u00e9e et  l&rsquo;\u00e2ge d&rsquo;initiation \u00e0 la consommation de drogues psychotropes rend compte de l&rsquo;appauvrissement neuronal et de l&rsquo;aptitude \u00e0 l&rsquo;endoctrinement peur servir de deuxi\u00e8me param\u00e8tre. Le troisi\u00e8me facteur pourrait \u00eatre figur\u00e9 par le m\u00e9lange entre le niveau de scolarit\u00e9 acquis et le niveau de &lsquo;comp\u00e9tence&rsquo; religieuse familial l\u00e9gu\u00e9 au candidat, la faiblesse de la formation intellectuelle est proportionnelle au carr\u00e9 du risque d&#8217;embrigadement. Sans en \u00eatre l&rsquo;ultime facteur, la combinatoire doit tenir compte de la pr\u00e9sence de l&rsquo;aspirant sur les registres de police, en particulier, la tol\u00e9rance de la force publique vis-\u00e0-vis de leurs voyages r\u00e9pertori\u00e9s au Pakistan, Y\u00e9men et autres foyers connus d&rsquo;entra&icirc;nement. Et pour Merah en Isra\u00ebl m\u00eame.<\/p>\n<\/p>\n<p><p>Car il est des laisser-faire tr\u00e8s \u00e9loquents<\/p>\n<\/p>\n<p><p>Les Prendre au mot, oui, la France est en guerre. Elle participe de fa\u00e7on explicite au d\u00e9mant\u00e8lement de l&rsquo;entit\u00e9 nationale syrienne qu&rsquo;elle avait contribu\u00e9e \u00e0 former lors des accords de dessins frontaliers de Sykes-Picot en 1916 de l&rsquo;Orient arabe, une fois d\u00e9pec\u00e9 le Grand Malade ottoman. Jupp\u00e9 puis \u00e0 sa suite Fabius, ministres de la Guerre d\u00e9guis\u00e9s en sinistres des Affaires \u00e9trang\u00e8res, l&rsquo;ont assum\u00e9 urbi et orbi. Armes et formation militaire furent fournies aux opposants et mercenaires venus d&rsquo;une centaine de pays sans aucun rapport avec la Syrie, m\u00eame avant les manifestations populaires infiltr\u00e9es d&rsquo;\u00e9l\u00e9ments arm\u00e9s qui ont tir\u00e9 \u00e0 la fois sur les civils et les forces de police et de l&rsquo;arm\u00e9e.<\/p>\n<\/p>\n<p><p>Les budgets nationaux de la guerre directe s&rsquo;\u00e9tant r\u00e9tr\u00e9cis sous les effets conjugu\u00e9s et synergiques de la &laquo; crise &raquo; \u00e9conomique et des programmes d&rsquo;aust\u00e9rit\u00e9 publique europ\u00e9ens, c&rsquo;est la manipulation des mal nomm\u00e9es ONG et autres entit\u00e9s qa\u00efdesques qui servirent d&rsquo;outils moins on\u00e9reux. L&rsquo;opinion publique occidentale allait \u00eatre ralli\u00e9e \u00e0 peu de frais sous la banni\u00e8re droidelhomiste. Les dictatures non agr\u00e9\u00e9es par les d\u00e9mocratures occidentales sont \u00e0 abattre, contrairement \u00e0 certaines africaines assist\u00e9es sans fausse honte par les arm\u00e9es fran\u00e7aises au Tchad comme <a href=\"http:\/\/survie.org\/publications\/article\/dossier-d-analyse-elections-en-5100\">\u00e0 Djibouti, au Gabon ou au Congo<\/a>. Les fili\u00e8res de recrutement de l&rsquo;Internationale Djihadiste ont fait leurs emplettes dans les banlieues des grandes villes europ\u00e9ennes essentiellement francophones, Paris et Bruxelles. Au vu et au su des instances ex\u00e9cutives.<\/p>\n<\/p>\n<p><p>C&rsquo;est dans ce vivier qu&rsquo;ont \u00e9t\u00e9 pr\u00e9lev\u00e9s les tueurs du 13 novembre et du 22 mars. Pour punir les d\u00e9mocratures qui ont abandonn\u00e9 les opposants ? Il semble que les USA reprennent de plus belle la formation de <a href=\"https:\/\/francais.rt.com\/international\/18438-pentagone-formation-rebelles-syriens\">&lsquo;rebelles&rsquo;<\/a> pendant que des ONG poursuivent la <a href=\"http:\/\/specialdefense.over-blog.com\/tag\/syrie\/\">livraison d&rsquo;armes en Syrie<\/a>. Pour renforcer la surveillance des populations indig\u00e8nes europ\u00e9ennes et perp\u00e9tuer un \u00e9tat de tension et l&rsquo;\u00e9tat d&rsquo;urgence associ\u00e9 ?<\/p>\n<\/p>\n<p><p>Les \u00e9tudiants qui manifestent contre la nouvelle architecture du Droit du Travail durement r\u00e9prim\u00e9s ne d\u00e9sarment pas. L&rsquo;interdiction des rassemblements publics qui est la marque de l&rsquo;\u00e9tat d&rsquo;urgence est largement bafou\u00e9e, des places sont prises d&rsquo;assaut par une jeunesse qui enfin regimbe contre une absence d&rsquo;avenir d\u00e9cent promis et constitutionnalis\u00e9 par les commissaires europ\u00e9ens et leurs d\u00e9l\u00e9gu\u00e9s au gouvernement fran\u00e7ais. La France est en guerre pour morceler les pays qui r\u00e9sistent pourtant faiblement aux lois de l&rsquo;Empire. Elle rev\u00eat ses allures martiales pour prendre des d\u00e9crets Macron et El Khomri contre les int\u00e9r\u00eats de sa population pr\u00e9caris\u00e9e.<\/p>\n<\/p>\n<p><p>Dans les deux cas, il n&rsquo;est pas s&ucirc;r qu&rsquo;elle gagne.<\/p>\n<\/p>\n<p><p>Hom\u00e8re, s&rsquo;il fut, a peut-\u00eatre \u00e9t\u00e9 aveugle pour constituer un r\u00e9cit fait de trous qui ont \u00e9tabli un socle de croyances congruent avec les pouvoirs royaux qui se mirent \u00e0 d\u00e9fendre des cit\u00e9s, des r\u00e9serves de grain pour les besoins de la division du travail. Dans notre ici, pas de souffle \u00e9pique qui anime les discours chaotiques et h\u00e9sitants d&rsquo;un binoclard \u00e0 scooter ou d&rsquo;un homme \u00e0 talonnettes &lsquo;casse toi p\u00f4v con&rsquo;. Et trop de trous \u00e9vidents dans le r\u00e9cit qui est produit livr\u00e9 \u00e0 des esprits immunis\u00e9s par la trag\u00e9die de Bologne d&rsquo;ao&ucirc;t 1980.<\/p>\n<\/p>\n<p><p>De plus, il est parfaitement su que l&rsquo;Iliade avec ses Atrides et son Iphig\u00e9nie et son Antigone n&rsquo;est qu&rsquo;une mascarade, par del\u00e0 le rapt d&rsquo;une H\u00e9l\u00e8ne consentante, pour se saisir du grain de l&rsquo;autre c\u00f4t\u00e9 de la mer.<\/p>\n<\/p>\n<p><h4>Badia Benjelloun<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos Atrides et leurs petits arrangements familiaux Ils disent d&rsquo;Hom\u00e8re qu&rsquo;il a \u00e9t\u00e9 aveugle. S&ucirc;rement, le po\u00e8te, ce voyant, est plong\u00e9 dans les t\u00e9n\u00e8bres de la c\u00e9cit\u00e9 \u00e0 ce qui est visible pour l&rsquo;&oelig;il. Plus s&ucirc;rement encore, ce qu&rsquo;il a dit de la trag\u00e9die des Atrides, le meurtre d&rsquo;Agamemnon par sa femme Clytemnestre, puis de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[17434,3936,3953,2687,16380,4242,1267],"class_list":["post-76515","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-agamemnon","tag-al","tag-benjelloun","tag-france","tag-hombre","tag-qaida","tag-terrorisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76515"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76515\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}