{"id":76535,"date":"2016-04-22T14:30:38","date_gmt":"2016-04-22T14:30:38","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2016\/04\/22\/erdogan-chantage-caricature-zizek-migrants\/"},"modified":"2016-04-22T14:30:38","modified_gmt":"2016-04-22T14:30:38","slug":"erdogan-chantage-caricature-zizek-migrants","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2016\/04\/22\/erdogan-chantage-caricature-zizek-migrants\/","title":{"rendered":"Erdogan &amp; chantage-caricature, Zizek &amp; migrants"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Erdogan &#038; chantage-caricature, Zizek &#038; migrants<\/h2>\n<\/p>\n<p><p>Puisque nous sommes dans la <a href=\"http:\/\/www.dedefensa.org\/article\/le-bouffon-tragique-ou-la-tragedie-bouffe\">trag\u00e9die-bouffe<\/a>, restons-y avec Erdogan, la caricature et le chantage. (Il faut noter qu&rsquo;Erdogan est l&rsquo;un des fondateurs-inspirateurs de l&rsquo;expression, puisque c&rsquo;est \u00e0 son propos que nous employ\u00e2mes pour la premi\u00e8re fois l&rsquo;expression \u00ab\u00a0trag\u00e9die-bouffe\u00a0\u00bb [ou trag\u00e9die-<em>bouffes<\/em>, selon l&rsquo;humeur], en <a href=\"http:\/\/www.dedefensa.org\/article\/la-turquie-selon-erdogan-ou-la-tragedie-bouffe\">octobre 2012<\/a>.) Depuis quelques semaines, Erdogan se d\u00e9cha&icirc;ne pour une\/des affaire(s) de caricaturiste dont il est la cible. C&rsquo;est en Allemagne cette fois, pas au Danemark, et il n&rsquo;est pas question du Proph\u00e8te mais peut-\u00eatre bien de <a href=\"http:\/\/www.dedefensa.org\/article\/erdogan-janus-sera-t-il-lantechrist-2016\">l&rsquo;Ant\u00e9christ<\/a>. (Et alors, nous inventerions aussit\u00f4t une nouvelle cat\u00e9gorie qui marierait parfaitement le courant eschatologique et le courant de bouffonnerie qui caract\u00e9risent le temps, qui serait celle de l'\u00a0\u00bbAnt\u00e9christ-<em>bouffes<\/em>\u00ab\u00a0.)<\/p>\n<\/p>\n<p><p>Erdogan veut qu&rsquo;on interdise des caricatures de lui et contre lui, en Allemagne comme on en a faites quelques-unes, qu&rsquo;on poursuive les dessinateurs ou les comiques coupables de ce quasi-d\u00e9icide dans l&rsquo;esprit de la chose, et que l&rsquo;un de ces comiques-sur-sc\u00e8ne, particuli\u00e8rement, m\u00e9rite amplement la prison. Il y a une loi pour cette sorte d&rsquo;\u00e9cart en Allemagne et Merkel a aussit\u00f4t \u00e9pous\u00e9 la cause d&rsquo;Erdogan, jugeant que le coupable (l&rsquo;acteur-sur-sc\u00e8ne Jan B\u00f6hmermann) m\u00e9ritait bien le maximum (5 ans de prison), et elle-m\u00eame le titre de chanceli\u00e8re-<em>bouffes<\/em>. La loi, qui punit l&rsquo;insulte publique contre des chefs d&rsquo;&Eacute;tat ou de gouvernement (un an si l&rsquo;insulte est involontaire, 5 ans si elle est volontaire), n&rsquo;a jamais \u00e9t\u00e9 appliqu\u00e9e, et la demande de son application avait \u00e9t\u00e9 rejet\u00e9e pour GW Bush et Beno&icirc;t XVI. Par contre, pour Erdogan, Merkel est, apr\u00e8s les h\u00e9sitations d&rsquo;usage et la consultation de ses conseillers en communication, sans r\u00e9serve favorable \u00e0 la chose. Cela provoque <a href=\"http:\/\/sputniknews.com\/europe\/20160422\/1038416454\/merkel-erdogan-comedian-satan-insult.html#ixzz46XN2ksSx\">une temp\u00eate<\/a> dans son pays et au sein de son gouvernement, et la met une fois de plus en position d\u00e9licate<\/p>\n<\/p>\n<p><p>Pour le cas qui nous occupe, la pauvrette (Merkel) est en effet tenue singuli\u00e8rement par l&rsquo;accord catastrophique entre l&rsquo;UE et la Turquie, qu&rsquo;elle a impos\u00e9e \u00e0 ses partenaires europ\u00e9ens, et elle ne craint qu&rsquo;une chose, qu&rsquo;Erdogan ouvre \u00e0 nouveau le \u00ab\u00a0robinet des migrants\u00a0\u00bb. (Ce qui supposerait qu&rsquo;il l&rsquo;avait ferm\u00e9, enfin bref&#8230;) La \u00ab\u00a0grande politique\u00a0\u00bb de Merkel, qui passait par la mise au pas de quelques vassaux (Gr\u00e8ce &#038; le reste) et l&rsquo;affirmation de son autorit\u00e9 dictatoriale sur l&rsquo;Europe, est r\u00e9duite depuis bient\u00f4t une ann\u00e9e \u00e0 la gestion au jour le jour de la crise migratoire. <strong>On avait dit, avec l&rsquo;affaire grecque, que Merkel n&rsquo;\u00e9tait rien de moins qu&rsquo;une nouvelle Bismarck ; mais alors, avec la crise migratoire, on se permettra de se montrer irrespectueux en esp\u00e9rant vaguement ne pas tomber sous le coup de leur loi et l&rsquo;on parlera respectueusement d&rsquo;une Bismarck-<em>bouffes<\/em><\/strong>.<\/p>\n<\/p>\n<p><p>La m\u00eame atmosph\u00e8re baigne une autre intervention toute fra&icirc;che d&rsquo;Erdogan, d\u00e9cid\u00e9ment infatigable dans ses fureurs ant\u00e9christiques, en Hollande cette fois, o&ugrave; l&rsquo;Ant\u00e9christ-<em>bouffes<\/em> demanderait aux associations turques du pays de rassembler des preuves de caricatures, d&rsquo;insultes, etc., sur lui et contre lui. Ces r\u00e9v\u00e9lations du journal <em>Volkrant<\/em> faites avant-hier ont provoqu\u00e9, l\u00e0 aussi, en Hollande, <a href=\"https:\/\/fr.sputniknews.com\/international\/201604211024435864-erdogan-poursuit-pays-bas\/\">une temp\u00eate du m\u00eame type<\/a> qu&rsquo;en Allemagne. Nommera-t-on cela temp\u00eate-<em>bouffes<\/em> ? Il faut dire que les m\u00e9thodes d&rsquo;Erdogan, sorte d&rsquo;Ubu-dictateur maniant le chantage \u00e0 ciel ouvert, y invitent ; au reste, le chantage est une pratique courante dans ces pays du Moyen-Orient qui sont les grands alli\u00e9s du bloc-BAO, comme <a href=\"http:\/\/www.dedefensa.org\/article\/apres-28-pages-voici-document-17\">l&rsquo;Arabie l&rsquo;a montr\u00e9<\/a> au pr\u00e9sident Obama qui a acquiesc\u00e9, esquissant un agenouillement. Il n&#8217;emp\u00eache, les nouvelles selon lesquelles Erdogan demanderait \u00e0 la justice d&rsquo;investiguer sur plus d&rsquo;un million de cas o&ugrave; l&rsquo;on pourrait trouver l&rsquo;argument d&rsquo;une insulte contre l&rsquo;Ant\u00e9christ-soi-m\u00eame nous paraissent consid\u00e9rablement outr\u00e9es, m\u00eame si elles ont \u00e9t\u00e9 dites. <strong>Mais nous ne cessons d&rsquo;\u00eatre stup\u00e9faits et pris de court par les avatars de cette prodigieuse \u00e9poque<\/strong>.<\/p>\n<\/p>\n<p><p>D&rsquo;autre part, mais sans quitter aucunement le sujet, il est vrai que dans \u00ab\u00a0trag\u00e9die-bouffe\u00a0\u00bb, il y a aussi le mot \u00ab\u00a0trag\u00e9die\u00a0\u00bb, et les affaires m\u00ealant Erdogan au destin europ\u00e9en, qui portent sur la crise migratoire, ont \u00e9galement un aspect tragique. C&rsquo;est de cette fa\u00e7on que le philosophe <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Slavoj_%C5%BDi%C5%BEek\">Slavoj Zizek<\/a>, de tendance alternative, n\u00e9o-marxiste, post-structuraliste, post-et anti-lacanien, et par cons\u00e9quent per\u00e7u comme une des grandes voix de la gauche antiSyst\u00e8me, envisage la question de la crise migratoire. Il a donn\u00e9 une interview \u00e0 RT, sur ce sujet pr\u00e9cis\u00e9ment, o&ugrave; il d\u00e9veloppe certaines id\u00e9es qui ne sont pas n\u00e9cessairement en phase avec l&rsquo;opinion de la gauche postmoderniste sur les migrants, tout en se r\u00e9f\u00e9rant \u00e0 des valeurs assez conformistes du champ politique (les \u00ab\u00a0valeurs\u00a0\u00bb postmodernes,  l&rsquo;Europe &laquo; <em>mais pas la \u00ab\u00a0d\u00e9mocratie anonyme\u00a0\u00bb de l&rsquo;Europe de Bruxelles<\/em> &raquo;, etc.). Le philosophe parle donc essentiellement, dans cette interview, de probl\u00e8mes culturels et sociaux mais surtout essentiellement politiques et concrets, et nullement de concepts philosophiques.<\/p>\n<\/p>\n<p><p>Son intervention d\u00e9veloppe essentiellement deux th\u00e8mes : l&rsquo;attitude de l&rsquo;Europe face \u00e0 cette crise, et surtout les concepts, \u00ab\u00a0valeurs\u00a0\u00bb et complexes sinon obsessions, qui pr\u00e9sident indirectement \u00e0 cette attitude d&rsquo;une part ; la responsabilit\u00e9, qui est rarement cit\u00e9e, de certains pays du Moyen-Orient dans cette crise, et pr\u00e9cis\u00e9ment ceux qu&rsquo;il (Zizek) pr\u00e9sente comme formant un \u00ab\u00a0nouvel axe du mal\u00a0\u00bb (\u00ab\u00a0<em>a new evil axis<\/em>\u00ab\u00a0, avec l&rsquo;expression curieusement emprunt\u00e9e \u00e0 GW Bush et sa bande de l&rsquo;ann\u00e9e 2002). D&rsquo;une fa\u00e7on assez caract\u00e9ristique, qui tranche avec les opinions conventionnelles des \u00e9lites-Syst\u00e8me qui ne peuvent parler du \u00ab\u00a0mal\u00a0\u00bb sans aussit\u00f4t vomir le nom d&rsquo;Assad-de-Syrie et Poutine-de-Russie en premiers ex-aequo, parfois compl\u00e9t\u00e9s par l&rsquo;Iran,<strong> Zizek nomme ce trio : Arabie-Isra\u00ebl-Turquie<\/strong>. Il s&rsquo;attarde notamment sur le cas de la Turquie, dont on a vu plus haut les liens indiscutables avec la crise migratoire et l&rsquo;Europe dans cette occurrence.<\/p>\n<\/p>\n<p><p>Sur la pseudo-politique europ\u00e9enne, Zizek a une position int\u00e9ressante en qualifiant l&rsquo;attitude g\u00e9n\u00e9rale des \u00e9lites-Syst\u00e8me europ\u00e9ennes vis-\u00e0-vis des migrants, <strong>de \u00ab\u00a0n\u00e9ocoloniale\u00a0\u00bb et finalement, et paradoxalement, de \u00ab\u00a0raciste\u00a0\u00bb. Zizek d\u00e9nonce donc indirectement le climat de \u00ab\u00a0repentance\u00a0\u00bb qui submerge la bienpensance-Syst\u00e8me europ\u00e9enne<\/strong>, lorsqu&rsquo;il d\u00e9veloppe ce th\u00e8me, dans un sens qui est effectivement loin d&rsquo;\u00eatre sans int\u00e9r\u00eat. (Il est vrai qu&rsquo;\u00e0 force de regarder les autres, notamment ceux qui viennent des pays du Sud, avec commis\u00e9ration, comme des victimes innocentes, inconscientes, h\u00e9riti\u00e8res des soi-disant souffrances de leurs ain\u00e9s et donc incapables de se d\u00e9gager d&rsquo;un destin d\u00e9crit et \u00e9crit par d&rsquo;autres qu&rsquo;eux, on n&rsquo;est plus tr\u00e8s loin de les consid\u00e9rer comme des irresponsables, de peu de valeur intellectuelle, pas loin d&rsquo;\u00eatre des sous-hommes en un sens&#8230;) &laquo; <em>Je pense que la r\u00e9duction de l&rsquo;autre \u00e0 l&rsquo;\u00e9tat de victime aveugle et impotente, qui n&rsquo;a aucune responsabilit\u00e9 dans ce qui lui arrive, est une autre version de ce que l&rsquo;on nommait, \u00e0 l&rsquo;\u00e9poque du colonialisme, \u00ab\u00a0le fardeau de l&rsquo;homme blanc\u00a0\u00bb. Ceux qui pr\u00e9tendent \u00eatre les plus ouverts aux migrants et aux r\u00e9fugi\u00e9s les traitent en r\u00e9alit\u00e9 d&rsquo;une fa\u00e7on ouvertement raciste et paternaliste. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>(\u00ab\u00a0Le fardeau de l&rsquo;homme blanc\u00a0\u00bb, ou \u00ab\u00a0<em>The white man&rsquo;s burden<\/em>\u00ab\u00a0, est une expression typique de la fin du XIX\u00e8me si\u00e8cle, qui fut notamment employ\u00e9e par Rudyard Kipling, et qui impliquait le \u00ab\u00a0fardeau\u00a0\u00bb de devoir \u00e9duquer, cultiver, civiliser des peuples manifestement et largement en-dessous de l&rsquo;homme de \u00ab\u00a0la civilisation de l&rsquo;homme blanc\u00a0\u00bb. La m\u00eame pens\u00e9e habitait un nombre important de gauches, &ndash; dont Kipling n&rsquo;\u00e9tait \u00e9videmment pas, &ndash; notamment la gauche fran\u00e7aise [L\u00e9on Blum \u00e9tait coutumier de cette sorte de discours], celle-l\u00e0 qui avait soutenu la conqu\u00eate de l&rsquo;Alg\u00e9rie par colonisation et au nom  de \u00ab\u00a0nos valeurs\u00a0\u00bb \u00e0 une droite r\u00e9ticente ou indiff\u00e9rente, \u00e0 un Napol\u00e9on III partisan d&rsquo;un \u00ab\u00a0royaume arabe\u00a0\u00bb et \u00e0 un corps militaire partisan de l&rsquo;autonomie culturelle sinon politique des indig\u00e8nes, dont Lyautey sera plus tard le plus prestigieux repr\u00e9sentant. [A cet \u00e9gard, la lecture des papiers de Isma&yuml;l Urbain, petit-fils d&rsquo;esclave en Guyane, converti \u00e0 l&rsquo;islam, interpr\u00e8te en Alg\u00e9rie du g\u00e9n\u00e9ral Bugeaud et du duc d&rsquo;Aumale, saint-simonien devenu directeur des affaires alg\u00e9riennes au minist\u00e8re de la guerre \u00e0 Paris, &ndash; <em>Isma&yuml;l Urbain, Royaume arabe ou Alg\u00e9rie franco-musulmane ? 1848-1870<\/em>, &ndash; cette lecture est prodigieusement int\u00e9ressante.])<\/p>\n<\/p>\n<p><p>Zizek est partisan d&rsquo;une <strong>\u00ab\u00a0militarisation\u00a0\u00bb de la crise migratoire, une notion qui reste difficile \u00e0 cerner, &ndash; sans parler de l&rsquo;appliquer, si l&rsquo;on consid\u00e8re les ressources tragiquement basses des Europ\u00e9ens<\/strong>. Il s&rsquo;agit, selon lui, de r\u00e9guler et \u00e9ventuellement de contenir le flux migratoire, de le contr\u00f4ler, de l&rsquo;organiser avec des moyens militaires, \u00e0 partir des pays impliqu\u00e9s, notamment la Syrie et la Libye. Et tout cela doit \u00eatre d\u00e9velopp\u00e9 en prenant en consid\u00e9ration la fondamentale question culturelle, c&rsquo;est-\u00e0-dire en refusant que les migrants am\u00e8nent avec eux leur propre culture d&rsquo;un point de vue collectif. &laquo; <em>Les r\u00e9fugi\u00e9s doivent \u00eatre aid\u00e9s, mais pas d&rsquo;une fa\u00e7on chaotique. Si les choses continuent comme elles vont, dans cinq ans l&rsquo;Europe ne sera plus l&rsquo;Europe, non pas dans le sens d&rsquo;une islamisation mais dans le sens de la pr\u00e9dominance d&rsquo;une population anti-immigrant.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Enfin, ses attaques contre les pays du Moyen-Orient, notamment le \u00ab\u00a0nouvel axe du mal\u00a0\u00bb, surtout avec la folie-Erdogan, sont extr\u00eamement violentes : &laquo; <strong><em>Que dire de ces tr\u00e8s riches pays, beaucoup plus riches que l&rsquo;Europe, qui sont plus proches de la crise, comme l&rsquo;Arabie, le Qatar, les &Eacute;mirats ? Ce sont des pays sunnites. Nombre des r\u00e9fugi\u00e9s sont des musulmans sunnites<\/em><\/strong>&#8230; [&#8230;] <em>La Turquie poursuit impitoyablement son programme. L&rsquo;accord <\/em>[de l&rsquo;UE]<em> avec la Turquie est totalement immoral. <\/em>[L&rsquo;UE]<em> fait des compromis avec un pays qui est en partie responsable de la crise<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>Cet ensemble de nouvelles et de consid\u00e9rations, o&ugrave; l&rsquo;\u00e9vidence semble parfois ressembler \u00e0 des r\u00e9v\u00e9lations extraordinaires et compl\u00e8tement inattendues tandis que l&rsquo;absurdit\u00e9 et la sottise constituent la feuille de route standard, nous rappellent simplement, directement et indirectement, l&rsquo;\u00e9tat path\u00e9tique o&ugrave; se trouve aujourd&rsquo;hui l&rsquo;Europe. Zizek n&rsquo;a pas \u00e0 aller chercher loin, et il ne nous \u00e9tonne pas vraiment lorsqu&rsquo;il dit que &laquo; [l]<em>e probl\u00e8me de l&rsquo;Europe n&rsquo;est pas un d\u00e9ficit de d\u00e9mocratie, mais l&rsquo;absence d&rsquo;une force politique qui sache ce qu&rsquo;elle veut<\/em> &raquo; ; il aurait tout aussi bien dire le contraire (\u00ab\u00a0le probl\u00e8me de l&rsquo;Europe n&rsquo;est pas l&rsquo;absence d&rsquo;une force politique qui sache qu&rsquo;elle veut mais un d\u00e9ficit de d\u00e9mocratie\u00a0\u00bb) parce que tous ces sympt\u00f4mes existent finalement, et parce qu&rsquo;ils renvoient \u00e0 une m\u00eame maladie centrale qui est celle du non-\u00eatre, de la dissolution de l&rsquo;identit\u00e9 \u00e0 tous les \u00e9chelons et d&rsquo;un m\u00eame mouvement. L'\u00a0\u00bbEurope unie\u00a0\u00bb ne pouvait \u00eatre diff\u00e9rente de &laquo; <em>la \u00ab\u00a0d\u00e9mocratie anonyme\u00a0\u00bb de l&rsquo;Europe de Bruxelles<\/em> &raquo; ; cela peut-\u00eatre compris dans cette mesure o&ugrave;, en rassemblant ses composants (les pays de l&rsquo;UE), elle les a ch\u00e2tr\u00e9s de leur identit\u00e9 et impos\u00e9 \u00e0 leurs directions un transfert de responsabilit\u00e9 qui s&rsquo;est av\u00e9r\u00e9e \u00eatre un transfert d&rsquo;&laquo; <em>absence d&rsquo;une force politique qui <\/em>[sait]<em> ce qu&rsquo;elle veut<\/em> &raquo; vers une entit\u00e9 qui s&rsquo;est aussit\u00f4t impr\u00e9gn\u00e9e de ce caract\u00e8re, ou de cette absence de caract\u00e8re.<\/p>\n<\/p>\n<blockquote>\n<p><p>L&rsquo;Europe face \u00e0 la crise migratoire est donc bien une Europe n\u00e9o-coloniale, sinon raciste, par simple r\u00e9f\u00e9rence \u00e0 ce qu&rsquo;elle [l&rsquo;Europe] se fait croire \u00e0 elle-m\u00eame qu&rsquo;elle croit. Le \u00ab\u00a0<em>The white man&rsquo;s burden<\/em>\u00ab\u00a0, aujourd&rsquo;hui, par la faute de la forme du d\u00e9veloppement (technologisme et communication) auquel s&rsquo;est soumise avec empressement notre contre-civilisation, <strong>est devenu de se faire croire \u00e0 soi-m\u00eame qu&rsquo;on est encore assez fort pour porter un tel fardeau, et assez digne pour proclamer la l\u00e9gitimit\u00e9 de la responsabilit\u00e9 d&rsquo;un tel fardeau<\/strong>. La fa\u00e7on dont nous traitons les r\u00e9fugi\u00e9s, en leur disant effectivement \u00ab\u00a0venez, venez chez nous, vous pourrez profiter des fruits de notre bonheur, de nos valeurs et de notre civilisation\u00a0\u00bb,<strong> outre d&rsquo;\u00eatre supr\u00e9maciste bien plus encore plus que raciste, est une fa\u00e7on de perp\u00e9tuer l&rsquo;illusion que l&rsquo;Europe existe encore en tant que valeur r\u00e9f\u00e9rentielle irr\u00e9fragable<\/strong>&#8230; (Ce que Zizek lui-m\u00eame semble croire, apr\u00e8s tout, lorsqu&rsquo;il dit que &laquo; <em>le fait que des millions<\/em> [d&rsquo;\u00eatres] <em>veulent aller en Europe prouve que les gens \u00ab\u00a0croient\u00a0\u00bb encore \u00e0 l&rsquo;Europe <\/em>&raquo;. Nous savons pourtant qu&rsquo;ils veulent aller en Europe parce qu&rsquo;on leur a mis dans la t\u00eate et sur leurs <em>I-pad<\/em>, et sur les DVD qu&rsquo;ils regardent, tout cela apr\u00e8s les avoir bombard\u00e9s [nous-m\u00eames aux commandes], qu&rsquo;il faut vouloir aller en Europe ; et nous savons \u00e9galement que nombre d&rsquo;entre eux finissent, apr\u00e8s un s\u00e9jour plus ou moins prolong\u00e9, \u00e0 trouver qu&rsquo;il leur serait plus profitable de rejoindre les hordes de <em>Daesh<\/em>.)<\/p>\n<\/p>\n<p><p>La vague migratoire vers l&rsquo;Europe, dans les conditions o&ugrave; elle se fait, anim\u00e9e par des Ant\u00e9christ-<em>bouffes <\/em>\u00e0&ndash;la-Erdogan que nous entourons de toute notre civilit\u00e9, <strong>n&rsquo;est pas tant une menace mortelle contre l&rsquo;Europe que le signe que l&rsquo;Europe est aussi agonisante que les pays qu&rsquo;elle bombarde ou fait bombarder<\/strong>. Bien entendu, il faut tenter de r\u00e9guler et de contr\u00f4ler cela, bien entendu il faut une &laquo; <em>force politique qui sache ce qu&rsquo;elle veut<\/em> &raquo; ; mais il s&rsquo;agit d&rsquo;am\u00e9nagements tactiques de survie, et ils ne changeraient pas, si jamais ils \u00e9taient par extraordinaire accomplis, le fait essentiel <strong>que tout cela se passe dans un paysage priv\u00e9 de toute conception strat\u00e9gique du monde, et ainsi plong\u00e9 dans le chaos<\/strong>. Consid\u00e9rant tous les \u00e9l\u00e9ments dont nous disposons, il n&rsquo;est pas assur\u00e9 que ce soit une mauvaise chose ; comme il n&rsquo;est pas assur\u00e9 non plus que ce soit une mauvaise chose qu&rsquo;un philosophe comme Zizek, qui fait aussi partie, peut-\u00eatre contre sa volont\u00e9, des ornements du Syst\u00e8me pour se faire croire \u00e0 sa propre diversit\u00e9, dise de ces choses qui vont troubler les vacances studieuses d&rsquo;un BHL o&ugrave; les d\u00e9bats enlev\u00e9s d'\u00a0\u00bb<em>On n&rsquo;est pas couch\u00e9<\/em>\u00ab\u00a0. Pour le reste, le chaos s&rsquo;occupe de nos affaires&#8230; Et cela n&rsquo;est certainement pas \u00e9crit sur un ton sarcastique, d\u00e9risoire ou d\u00e9sesp\u00e9r\u00e9.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le titre complet de l&rsquo;interview de RT du <a href=\"https:\/\/www.rt.com\/news\/340562-eu-refugee-policy-chaos-militarization\/\">22 avril 2016<\/a> est &laquo;&rsquo;<em>EU must militarize chaotic immigration, identify states behind Middle East crisis&rsquo; &ndash; Zizek to RT<\/em> &raquo;.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>______________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">&laquo; <em>EU must militarize chaotic immigration&#8230; <\/em>&raquo;<\/h2>\n<\/p>\n<p><p>Europe&rsquo;s refugee policy is disastrous and chaotic, prominent philosopher Slavoj Zizek told RT, adding that the EU must control migrant flows and get to the root of the Middle East crisis by recognizing its key \u00ab\u00a0components\u00a0\u00bb: Turkey, Saudi Arabia, and Israel.<\/p>\n<\/p>\n<p><p>Zizek, who is known for frankly expressing his views on acute social subjects, is an author, a professor at the European Graduate School, a senior researcher at the University of Ljubljana&rsquo;s Institute of Sociology, and the International Director of the Birkbeck Institute for the Humanities at the University of London&rsquo;s Birkbeck College.<\/p>\n<\/p>\n<p><p>In an exclusive interview with RT, Zizek argued that one of the biggest problems with Europe&rsquo;s immigration policy is that it is pursued from a neo-colonial perspective that focuses on so-called \u00ab\u00a0white man&rsquo;s burden\u00a0\u00bb and \u00ab\u00a0guilt.\u00a0\u00bb However, he added that it would be wrong to blame Europe for all of the problems in the Middle East and to assume that refugees are blind victims who bear no responsibility in the crisis.  \u00ab\u00a0I think this reduction of the other to an impotent, blind victim, who doesn&rsquo;t have any responsibility, is another version of what in colonialist times was called white man&rsquo;s burden,\u00a0\u00bb Zizek explained. \u00ab\u00a0Those who pretend to be the most open to migrants or refugees really treat them in an openly racist, patronizing way.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>According to Zizek, Europe should \u00ab\u00a0fundamentally\u00a0\u00bb change its outlook and avoid the \u00ab\u00a0trap of self-pitying.\u00a0\u00bb \u00ab\u00a0Isn&rsquo;t the very fact that millions want to go to Europe prove that people still see something in Europe,\u00a0\u00bb he noted, stressing that he supports the idea of a united Europe, but not the \u00ab\u00a0anonymous Brussels European democracy.\u00a0\u00bb \u00ab\u00a0The problem with Europe is not democratic deficit, but a deficit of a political force that knows what it wants.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Europeans need to \u00ab\u00a0raise questions\u00a0\u00bb and realize that Muslims are dealing with many internal problems, including radicalization by groups like Islamic State (IS, formerly ISIS\/ISIL), as well as the sectarian Sunni-Shia divide.<\/p>\n<\/p>\n<p><p>Moreover, Zizek argued that external forces in the ongoing Middle Eastern conflicts must be taken into account. He pointed to what he branded as \u00ab\u00a0a new axis of evil\u00a0\u00bb in the region, claiming that its main \u00ab\u00a0components\u00a0\u00bb are Turkey, Israel, and Saudi Arabia.  \u00ab\u00a0We now know that Israel and Saudi Arabia openly collaborate on security issues, secret policy, military and so on. This new front is against mostly their Shia opponents. This is a crucial fact and is the source of the problems.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Zizek blamed Europe for readily opening its borders to refugees at a time when rich Gulf Arab states are accepting \u00ab\u00a0practically none.\u00a0\u00bb \u00ab\u00a0What about the very rich Arab countries, very much richer than Europe, which are closer to the crisis area, such as Saudi Arabia, Qatar, United Arab Emirates? These are Sunni countries. Most of the refugees are Sunni Muslims.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Meanwhile, Turkey, which has been receiving refugees, is at the same time \u00ab\u00a0ruthlessly\u00a0\u00bb following its own agenda in the crisis, he said. Zizek believes that the recent controversial deal struck between the EU and Turkey, which will see Turkey take back all of the migrants who arrive in Greece in return for $6.8 billion worth of aid over the next three years, is a \u00ab\u00a0most shameful agreement\u00a0\u00bb for Europe.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Turkey is ruthlessly pursuing its agenda. The agreement is totally unethical. [The EU] is making a compromise with a state which is in part responsible for the crisis.\u00a0\u00bb Zizek said that while Turkey is allegedly \u00ab\u00a0pretending to fight terror\u00a0\u00bb in the region, in reality it is only cracking down on Kurds, who are \u00ab\u00a0one of the few in northern Syria who are really fighting against Islamic State.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Erdogan began to attack the Kurds out of fear that the last election wouldn&rsquo;t go so well, Zizek argued: \u00ab\u00a0He cooked up this new crisis with Kurds and the operation was very vicious. He hoped he would succeed in preventing the Kurdish party from entering the Parliament.\u00a0\u00bb The philosopher painted a bleak future for Turkish democracy. \u00ab\u00a0Kurds are victims of a more fundamental problem that concerns Turkish society. What kind of Turkey will emerge now? Two years ago there were big demonstrations in Istanbul. [The authorities] are projecting an external enemy their own inner antagonism.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Lambasting the EU&rsquo;s current efforts to tackle the migrant crisis, Zizek offered his own concept for dealing with the problem, which he called \u00ab\u00a0militarization\u00a0\u00bb &ndash; not that of the European space, but of the war-stricken emigration hotspots. He explained that, in his view, European states must establish a military basis to \u00ab\u00a0organize airlifts and regulate immigration\u00a0\u00bb in Syria and Libya. He called the current state of affairs \u00ab\u00a0a political fiasco of Europe&hellip; a scandal,\u00a0\u00bb adding that immigrants \u00ab\u00a0just flow in a disorganized way.\u00a0\u00bb \u00ab\u00a0Refugees should be helped, but not in this chaotic way. If things continue as is, in five years, Europe will no longer be Europe, not in a sense of Islamization, but in a sense of the predominance of anti-immigrant populace.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>For now, EU policies are creating rifts between European neighbors. \u00ab\u00a0These western European countries are playing dirty games. Germany&rsquo;s Chancellor, Angela Merkel, did a big invitation, but then when there were too many refugees, [she] didn&rsquo;t want to dirty [her] hands by saying &lsquo;stop.&rsquo; Instead, small Balkan countries were left to do the dirty job and discreetly stop the flow of refugees,\u00a0\u00bb the philosopher claimed.<\/p>\n<\/p>\n<p><p>The idea that different cultures can peacefully coexist together is a \u00ab\u00a0dream,\u00a0\u00bb Zizek argued. \u00ab\u00a0When different cultures live in the same state, but have different ways of life, they also treat each there in different ways.\u00a0\u00bb As examples, he pointed to situations in which Muslims extremists have attacked gays in the Netherlands, Denmark, and Germany. In addition, he said that in Germany over 2,000 Muslim girls escape from their families per year and then demand protection from the state, which puts additional burden on the government&rsquo;s budget.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Europe needs to be open to refugees, but we have to be clear they are in our culture. Certain ethical limits (for example women&rsquo;s freedom of choice) are non-negotiable. We should be more assertive toward our values,\u00a0\u00bb Zizek argued. \u00ab\u00a0Europe means something noble &ndash; human rights, welfare state, social programs for the poor. All of this is embodied in enlightenment of the European legacy.\u00a0\u00bb<\/p>\n<\/p>\n<p><h4>RT (Slavoj Zizek)<\/h4>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"> <\/h2><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erdogan &#038; chantage-caricature, Zizek &#038; migrants Puisque nous sommes dans la trag\u00e9die-bouffe, restons-y avec Erdogan, la caricature et le chantage. (Il faut noter qu&rsquo;Erdogan est l&rsquo;un des fondateurs-inspirateurs de l&rsquo;expression, puisque c&rsquo;est \u00e0 son propos que nous employ\u00e2mes pour la premi\u00e8re fois l&rsquo;expression \u00ab\u00a0trag\u00e9die-bouffe\u00a0\u00bb [ou trag\u00e9die-bouffes, selon l&rsquo;humeur], en octobre 2012.) Depuis quelques semaines, Erdogan&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[9408,5091,6976,3228,3737,6902,4633,12744,17307,5379,3296,6906,9623,12756,17457,3425,3867,11651],"class_list":["post-76535","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-antechrist","tag-caricature","tag-chantage","tag-crise","tag-erdogan","tag-libye","tag-merkel","tag-migrants","tag-migratoire","tag-militarisation","tag-neo-colonialisme","tag-refugies","tag-repentance","tag-rt","tag-slavoj","tag-supremacisme","tag-syrie","tag-zizek"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=76535"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/76535\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=76535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=76535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=76535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}